{"id":129367,"date":"2011-09-30T09:54:01","date_gmt":"2011-09-30T08:54:01","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/?p=129367"},"modified":"2011-10-27T17:14:06","modified_gmt":"2011-10-27T16:14:06","slug":"francisco-ibanez-premiado-en-bilbao","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/2011\/09\/30\/129367","title":{"rendered":"Francisco Iba\u00f1ez premiado en Bilbao"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_129368\" aria-describedby=\"caption-attachment-129368\" style=\"width: 221px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/files\/2011\/09\/20110804-093845-peq.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-129368\" title=\"20110804-093845-peq\" src=\"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/files\/2011\/09\/20110804-093845-peq-221x300.jpg\" alt=\"\" width=\"221\" height=\"300\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/files\/2011\/09\/20110804-093845-peq-221x300.jpg 221w, https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/files\/2011\/09\/20110804-093845-peq-755x1024.jpg 755w, https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/files\/2011\/09\/20110804-093845-peq.jpg 1308w\" sizes=\"(max-width: 221px) 100vw, 221px\" \/><\/a><figcaption id=\"caption-attachment-129368\" class=\"wp-caption-text\">Portada de &quot;Mortadelo Gigante&quot;<\/figcaption><\/figure>\n<p>Ma\u00f1ana, 1 de octubre de 2011, en la sala de la BBK de Bilbao Francisco Iba\u00f1ez recibir\u00e1 el Premio de La Risa de Bilbao, dentro de la Segunda Semana Internacional de Literatura y Arte con Humor. Paralelamente desde el 28 de septiembre y hasta el 2 de octubre se est\u00e1 desarrollando la exposici\u00f3n, <em>El Gran Iba\u00f1ez<\/em>, en la que podemos ver originales de gran parte de los personajes creados por este historietista, tiene lugar en El Arenal de Bilbao. La obra pertenece a los fondos de Ediciones B.<\/p>\n<p>Francisco Iba\u00f1ez, padre de personajes como \u201cMortadelo y Filem\u00f3n\u201d; \u201cPepe Gotera y Otilio, chapuzas a domicilio\u201d; \u201cEl Botones Sacarino\u201d; \u201c13, Rue del Percebe\u201d; \u201cLa Familia Trapisonda, una tropita que es la bomba\u201d; \u201cCabeza de ajo, el pen\u00faltimo navajo\u201d; \u201cEl doctor Esparadrapo y su ayudante Gazapo\u201d o \u201cRompetechos\u201d entre otros, ya que estamos hablando ante uno de los autores m\u00e1s conocidos y prol\u00edficos de la historieta espa\u00f1ola.<\/p>\n<p>Sus personajes aparecieron en gran cantidad de revistas, entre las que cabe rese\u00f1ar <em>Can Can<\/em>, <em>Super Sacarino<\/em>, <em>Mortadelo<\/em>, <em>DDT, Tio Vivo<\/em>, <em>Pulgarcito<\/em>, <em>Super Mortadelo<\/em>,<em> Ven y Ven<\/em>, etc\u2026<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>Rompetechos es un se\u00f1or m\u00e1s bien bajito y siempre de traje oscuro, con tres pelos que cubren su calva, peque\u00f1o bigote y su caracter\u00edstica m\u00e1s distintiva, con escasa visi\u00f3n incluso con sus gafas de culo de vaso.<\/p>\n<p>Pepe Gotera y Otilio es una pareja de arreglatodo, o m\u00e1s podr\u00edamos decir de rompetodo, ya que en cada encargo la chapuza, est\u00e1 asegurada. Gotera es el jefe, mientras que Otilio es el ejecutor, sin iniciativa alguna, a las ordenes de su jefe.<\/p>\n<p>13, Rue del Percebe es una serie de vi\u00f1etas no secuenciadas, colocadas en sobre una vi\u00f1eta que asemeja un bloque de<\/p>\n<figure id=\"attachment_129369\" aria-describedby=\"caption-attachment-129369\" style=\"width: 205px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/files\/2011\/09\/20110804-093732-peq.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-129369\" title=\"20110804-093732-peq\" src=\"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/files\/2011\/09\/20110804-093732-peq-205x300.jpg\" alt=\"\" width=\"205\" height=\"300\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/files\/2011\/09\/20110804-093732-peq-205x300.jpg 205w, https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/files\/2011\/09\/20110804-093732-peq-701x1024.jpg 701w, https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/files\/2011\/09\/20110804-093732-peq.jpg 1214w\" sizes=\"(max-width: 205px) 100vw, 205px\" \/><\/a><figcaption id=\"caption-attachment-129369\" class=\"wp-caption-text\">Una de las piezas que puede verse en la exposici\u00f3n<\/figcaption><\/figure>\n<p>viviendas, en cada una de las cuales moran unos personajes determinados, cuyas vivencias nos va relatando el autor en cada historieta:<\/p>\n<p>El Botones Sacarino es el botones de un peri\u00f3dico llamado el aullido vespertino que posteriormente pasar\u00eda a serlo de DDT. Sacarino intenta escabullirse de sus labores. De sus l\u00edos suelen salir perjudicados el Jefe o el Presidente.<\/p>\n<p>Finalmente comentar que el autor firmar\u00e1 libros el pr\u00f3ximo 2 de octubre, en la ma\u00f1ana en El Arenal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ma\u00f1ana, 1 de octubre de 2011, en la sala de la BBK de Bilbao Francisco Iba\u00f1ez recibir\u00e1 el Premio de La Risa de Bilbao, dentro de la Segunda Semana Internacional de Literatura y Arte con Humor. Paralelamente desde el 28 de septiembre y hasta el 2 de octubre se est\u00e1 desarrollando la exposici\u00f3n, El Gran Iba\u00f1ez, en la que podemos ver originales de gran parte de los personajes creados por este historietista, tiene lugar en El Arenal de Bilbao. La obra pertenece a los fondos de Ediciones B. Francisco Iba\u00f1ez, padre de personajes como \u201cMortadelo y Filem\u00f3n\u201d; \u201cPepe Gotera\u2026<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1,131],"tags":[11263,11260,11262,11246,11264],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/wp-json\/wp\/v2\/posts\/129367"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/wp-json\/wp\/v2\/comments?post=129367"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/wp-json\/wp\/v2\/posts\/129367\/revisions"}],"predecessor-version":[{"id":129421,"href":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/wp-json\/wp\/v2\/posts\/129367\/revisions\/129421"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/wp-json\/wp\/v2\/media?parent=129367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/wp-json\/wp\/v2\/categories?post=129367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/HumoryCiencia\/wp-json\/wp\/v2\/tags?post=129367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}