{"id":132141,"date":"2011-04-06T09:11:00","date_gmt":"2011-04-06T08:11:00","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/astrofisica\/?p=132141"},"modified":"2011-04-06T09:12:40","modified_gmt":"2011-04-06T08:12:40","slug":"postales-desde-los-confines-del-universo","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141","title":{"rendered":"Postales desde los confines del Universo"},"content":{"rendered":"<p>Cun motivo del A\u00f1o Internacional de la Astronom\u00eda, celebrado en 2009, se realizar\u00f3n numerosas iniciativas divulgativas, que han dejado un <a href=\"http:\/\/astronomia2009.es\/Sobre_el_AIA-IYA2009\/Recursos_y_descargas.html\">importante legado<\/a> (videos y otro material educativo, exposiciones, y una importante infraestructura enfocada a la difusi\u00f3n de la cultura cient\u00edfica).<\/p>\n<p>Entre otras muchas, el <a href=\"http:\/\/www.eso.org\/public\/\">Observatorio Austral Europeo<\/a> (ESO, por su siglas en ingl\u00e9s), en colaboraci\u00f3n con la <a href=\"http:\/\/www.iau.org\/\">Uni\u00f3n Astron\u00f3mica Internacional<\/a>, public\u00f3 un libro que conten\u00eda las historia personales (sus anhelos y motivaciones para haber seguido una carrera como cient\u00edficos) y una breve descripci\u00f3n de las \u00e1reas de investigaci\u00f3n de un par de docenas de investigadores, entre los cuales me encontraba yo. Este libro, con algunas im\u00e1genes espectaculares,\u00a0 se puede <a href=\"http:\/\/www.eso.org\/public\/products\/books\/postcardsfromuniverse\/\">descargar libremente<\/a>.<\/p>\n<p>Adem\u00e1s, dentro de la misma inicitiva, ESO permite el env\u00edo de postales \u00abdesde los confines del Universo\u00bb, mensajes con algunas\u00a0 de las fotograf\u00edas m\u00e1s espectaculares tomadas con telescopios o naves espaciales: desde el\u00a0 \u00abVery Large Telescope\u00bb hasta sondas orbitando Marte, pasando por el telescopio espacial Hubble.<\/p>\n<p>Con unos pocos<a href=\"http:\/\/www.postcardsfromuniverse.org\/?show=cards\"> clicks en el ordenador<\/a>, cualquiera puede enviar una de felicitaci\u00f3n o un simple recordatorio, y conpartir la belleza del Universo.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2011\/04\/Postcards_Portada_red.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-132142\" title=\"Postcards from the Edge of the Universe\" src=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2011\/04\/Postcards_Portada_red-300x181.jpg\" alt=\"\" width=\"300\" height=\"181\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2011\/04\/Postcards_Portada_red-300x181.jpg 300w, https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2011\/04\/Postcards_Portada_red.jpg 556w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cun motivo del A\u00f1o Internacional de la Astronom\u00eda, celebrado en 2009, se realizar\u00f3n numerosas iniciativas divulgativas, que han dejado un importante legado (videos y otro material educativo, exposiciones, y una importante infraestructura enfocada a la difusi\u00f3n de la cultura cient\u00edfica). Entre otras muchas, el Observatorio Austral Europeo (ESO, por su siglas en ingl\u00e9s), en colaboraci\u00f3n con la Uni\u00f3n Astron\u00f3mica Internacional, public\u00f3 un libro que conten\u00eda las historia personales (sus anhelos y motivaciones para haber seguido una carrera como cient\u00edficos) y una breve descripci\u00f3n de las \u00e1reas de investigaci\u00f3n de un par de docenas de investigadores, entre los cuales me encontraba\u2026<\/p>\n","protected":false},"author":140,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[64,555],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cun motivo del A\u00f1o Internacional de la Astronom\u00eda, celebrado en 2009, se realizar\u00f3n numerosas iniciativas divulgativas, que han dejado un importante legado (videos y otro material educativo, exposiciones, y una importante infraestructura enfocada a la difusi\u00f3n de la cultura cient\u00edfica). Entre otras muchas, el Observatorio Austral Europeo (ESO, por su siglas en ingl\u00e9s), en colaboraci\u00f3n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"David Barrado\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Postales desde los confines del Universo - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"Cun motivo del A\u00f1o Internacional de la Astronom\u00eda, celebrado en 2009, se realizar\u00f3n numerosas iniciativas divulgativas, que han dejado un importante legado (videos y otro material educativo, exposiciones, y una importante infraestructura enfocada a la difusi\u00f3n de la cultura cient\u00edfica). Entre otras muchas, el Observatorio Austral Europeo (ESO, por su siglas en ingl\u00e9s), en colaboraci\u00f3n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-04-06T08:11:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-04-06T08:12:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Postales desde los confines del Universo - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cun motivo del A\u00f1o Internacional de la Astronom\u00eda, celebrado en 2009, se realizar\u00f3n numerosas iniciativas divulgativas, que han dejado un importante legado (videos y otro material educativo, exposiciones, y una importante infraestructura enfocada a la difusi\u00f3n de la cultura cient\u00edfica). Entre otras muchas, el Observatorio Austral Europeo (ESO, por su siglas en ingl\u00e9s), en colaboraci\u00f3n\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141#blogposting\",\"name\":\"Postales desde los confines del Universo - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"Postales desde los confines del Universo\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2011\\\/04\\\/Postcards_Portada_red-300x181.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141\\\/#articleImage\"},\"datePublished\":\"2011-04-06T09:11:00+01:00\",\"dateModified\":\"2011-04-06T09:12:40+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141#webpage\"},\"articleSection\":\"Divulgaci\\u00f3n, Mujeres y Ciencia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"position\":2,\"name\":\"Divulgaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141#listItem\",\"name\":\"Postales desde los confines del Universo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141#listItem\",\"position\":3,\"name\":\"Postales desde los confines del Universo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn\",\"name\":\"David Barrado\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"David Barrado\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141\",\"name\":\"Postales desde los confines del Universo - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Cun motivo del A\\u00f1o Internacional de la Astronom\\u00eda, celebrado en 2009, se realizar\\u00f3n numerosas iniciativas divulgativas, que han dejado un importante legado (videos y otro material educativo, exposiciones, y una importante infraestructura enfocada a la difusi\\u00f3n de la cultura cient\\u00edfica). Entre otras muchas, el Observatorio Austral Europeo (ESO, por su siglas en ingl\\u00e9s), en colaboraci\\u00f3n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2011\\\/04\\\/06\\\/132141#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\"},\"datePublished\":\"2011-04-06T09:11:00+01:00\",\"dateModified\":\"2011-04-06T09:12:40+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Postales desde los confines del Universo - Cuaderno de bit\u00e1cora estelar","description":"Cun motivo del A\u00f1o Internacional de la Astronom\u00eda, celebrado en 2009, se realizar\u00f3n numerosas iniciativas divulgativas, que han dejado un importante legado (videos y otro material educativo, exposiciones, y una importante infraestructura enfocada a la difusi\u00f3n de la cultura cient\u00edfica). Entre otras muchas, el Observatorio Austral Europeo (ESO, por su siglas en ingl\u00e9s), en colaboraci\u00f3n","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141#blogposting","name":"Postales desde los confines del Universo - Cuaderno de bit\u00e1cora estelar","headline":"Postales desde los confines del Universo","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2011\/04\/Postcards_Portada_red-300x181.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141\/#articleImage"},"datePublished":"2011-04-06T09:11:00+01:00","dateModified":"2011-04-06T09:12:40+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141#webpage"},"articleSection":"Divulgaci\u00f3n, Mujeres y Ciencia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","position":2,"name":"Divulgaci\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141#listItem","name":"Postales desde los confines del Universo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141#listItem","position":3,"name":"Postales desde los confines del Universo","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn","name":"David Barrado","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"David Barrado"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141","name":"Postales desde los confines del Universo - Cuaderno de bit\u00e1cora estelar","description":"Cun motivo del A\u00f1o Internacional de la Astronom\u00eda, celebrado en 2009, se realizar\u00f3n numerosas iniciativas divulgativas, que han dejado un importante legado (videos y otro material educativo, exposiciones, y una importante infraestructura enfocada a la difusi\u00f3n de la cultura cient\u00edfica). Entre otras muchas, el Observatorio Austral Europeo (ESO, por su siglas en ingl\u00e9s), en colaboraci\u00f3n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author"},"datePublished":"2011-04-06T09:11:00+01:00","dateModified":"2011-04-06T09:12:40+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"Postales desde los confines del Universo - Cuaderno de bit\u00e1cora estelar","og:description":"Cun motivo del A\u00f1o Internacional de la Astronom\u00eda, celebrado en 2009, se realizar\u00f3n numerosas iniciativas divulgativas, que han dejado un importante legado (videos y otro material educativo, exposiciones, y una importante infraestructura enfocada a la difusi\u00f3n de la cultura cient\u00edfica). Entre otras muchas, el Observatorio Austral Europeo (ESO, por su siglas en ingl\u00e9s), en colaboraci\u00f3n","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2011-04-06T08:11:00+00:00","article:modified_time":"2011-04-06T08:12:40+00:00","twitter:card":"summary","twitter:title":"Postales desde los confines del Universo - Cuaderno de bit\u00e1cora estelar","twitter:description":"Cun motivo del A\u00f1o Internacional de la Astronom\u00eda, celebrado en 2009, se realizar\u00f3n numerosas iniciativas divulgativas, que han dejado un importante legado (videos y otro material educativo, exposiciones, y una importante infraestructura enfocada a la difusi\u00f3n de la cultura cient\u00edfica). Entre otras muchas, el Observatorio Austral Europeo (ESO, por su siglas en ingl\u00e9s), en colaboraci\u00f3n","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"132141","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 09:44:10","updated":"2023-06-19 08:56:26","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion\" title=\"Divulgaci\u00f3n\">Divulgaci\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPostales desde los confines del Universo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Divulgaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion"},{"label":"Postales desde los confines del Universo","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2011\/04\/06\/132141"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/132141"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=132141"}],"version-history":[{"count":4,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/132141\/revisions"}],"predecessor-version":[{"id":132145,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/132141\/revisions\/132145"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=132141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=132141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=132141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}