{"id":133784,"date":"2015-07-25T11:07:29","date_gmt":"2015-07-25T10:07:29","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/astrofisica\/?p=133784"},"modified":"2016-03-11T16:04:01","modified_gmt":"2016-03-11T15:04:01","slug":"kepler-452b-un-exoplaneta-analogo-terrestre","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784","title":{"rendered":"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre?"},"content":{"rendered":"<p>Entre la avalancha de descubrimientos astron\u00f3micos de las \u00faltimas semanas, destacan, entre otros, las im\u00e1genes de la sonda Rosetta al orbitar alrededor del cometa 67P\/Churyumov-Gerasimenko, \u00a0los datos que provienen de los planetas enanos Ceres y Plut\u00f3n, tomados con las naves\u00a0 Dawn y New Horizon. Fuera del Sistema Solar, <a href=\"http:\/\/www.jpl.nasa.gov\/news\/news.php?feature=4665\" target=\"_blank\">NASA ha anunciado el descubrimiento del \u201cprimo\u201d de la Tierra<\/a>, denominado Kepler-452.<\/p>\n<p><!--more--><\/p>\n<figure id=\"attachment_133788\" aria-describedby=\"caption-attachment-133788\" style=\"width: 437px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2015\/07\/Kepler_HZ_SType_Planets.jpg\"><img decoding=\"async\" class=\" wp-image-133788 \" title=\"Kepler_HZ_SType_Planets\" src=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2015\/07\/Kepler_HZ_SType_Planets.jpg\" alt=\"\" width=\"437\" height=\"315\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2015\/07\/Kepler_HZ_SType_Planets.jpg 624w, https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2015\/07\/Kepler_HZ_SType_Planets-300x216.jpg 300w\" sizes=\"(max-width: 437px) 100vw, 437px\" \/><\/a><figcaption id=\"caption-attachment-133788\" class=\"wp-caption-text\">Diagrama con varios exoplanetas que se encuentran orbitando alrededor de sus respectivas estrellas en la zona de habitabilidad o confort, en donde el agua, de haberla, podr\u00eda estar en estado l\u00edquido. Hasta el momento se han encontrado varias super-tierras orbitando alrededor de estrellas m\u00e1s fr\u00edas que el Sol. La estrella Kepler-452 es una an\u00e1logo solar, con una temperatura superficial pr\u00e1cticamente id\u00e9ntica, aunque su edad podr\u00eda ser significativamente m\u00e1s alta. En lo que respecta al planeta, su tama\u00f1o es un 60% m\u00e1s grande que la Tierra y no tenemos informaci\u00f3n sobre su masa, densidad media o posible composici\u00f3n<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>El nuevo planeta (y ya son m\u00e1s de 1000 confirmados) tiene varias caracter\u00edsticas que los asimilan a nuestra Tierra:<\/p>\n<ul>\n<li>Orbita alrededor de una <a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/09\/15\/100911\" target=\"_blank\">estrella muy similar al Sol<\/a>, un \u201cgemelo\u201d con una temperatura superficial muy parecida, aunque significativamente m\u00e1s viejo.<\/li>\n<li>Su periodo orbital similar, de 384.8 d\u00edas, es un poco m\u00e1s que un a\u00f1o terrestre, lo que refuerza la identificaci\u00f3n<\/li>\n<li>El planeta est\u00e1 dentro de la <a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2009\/11\/11\/128475\" target=\"_blank\">zona de habitabilidad<\/a>, una regi\u00f3n alrededor de la estrella central en la que podr\u00eda haber agua l\u00edquida<\/li>\n<li>Su tama\u00f1o se ha determinado mediante la t\u00e9cnica de los tr\u00e1nsitos planetarios, una disminuci\u00f3n peri\u00f3dica de la luz que nos llega de la estrella central, provocada por el paso del planea por delante de la misma, al igual que ocurre con Mercurio y Venus, o la Luna durante un eclipse. El resultado es del mismo orden de magnitud que la Tierra, aunque un 60% m\u00e1s grande.<\/li>\n<\/ul>\n<p>As\u00ed, nos encontramos ante un sistema planetario verdaderamente interesante. Sin embargo, \u00bfes realmente el exoplaneta ideal, el grial que estamos buscando, la r\u00e9plica de la Tierra allende los mares siderales?<\/p>\n<p>En realidad, aunque ignor\u00e1semos la gran distancia que nos separa de su estrella, lo que imposibilita cualquier visita de una sonda espacial (no, no veremos im\u00e1genes espectaculares como las que estamos disfrutando en el <a href=\"http:\/\/www.esa.int\/spaceinimages\/Missions\/Rosetta\" target=\"_blank\">comenta 67P<\/a>, <a href=\"http:\/\/dawn.jpl.nasa.gov\/multimedia\/\/images\/ceres.html\" target=\"_blank\">Ceres<\/a> o <a href=\"https:\/\/www.nasa.gov\/mission_pages\/newhorizons\/images\/index.html\" target=\"_blank\">Plut\u00f3n<\/a>), existen otros factores a tener en cuenta.<\/p>\n<p>En primer lugar, todav\u00eda no se ha determinado la masa de Kepler-452b. Ello es, en principio, posible. Para esta medida se usa el m\u00e9todo de la velocidad radial, el mismo que caus\u00f3 el descubrimiento de 51 Pegasi en 1995. Mediante un espectr\u00f3grafo, un instrumento que permite analizar en detalle la luz que nos llega de la estrella, descomponiendola en sus \u201ccolores\u201d o longitudes de onda, se pueden buscar desplazamientos peri\u00f3dicos que est\u00e9n acompasados con las variaciones encontradas en la curva de luz, cuando el planeta oculta parcialmente la estrella. Es lo que se denomina el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Efecto_Doppler\" target=\"_blank\">efecto Doppler<\/a>, que todos hemos experimentado en otro \u00e1mbito: cuando un coche o tren pasa cerca de nosotros y o\u00edmos una cambio en la frecuencia del sonido que emite. Dado que la luz tambi\u00e9n se comporta como una onda, al igual que los ruidos, tambi\u00e9n se observa un cambio en la frecuencia (o longitud de onda, o \u201ccolor\u201d) al variar la velocidad relativa entre el objeto que emite y el que detecta. Igual que lo que ocurre al coche al ir acerc\u00e1ndose y pasar junto a nosotros, para terminar alej\u00e1ndose.<\/p>\n<p>El hecho importante es que debido al escaso brillo de la estrella y a la reducida se\u00f1al que el planeta imprime sobre su espectro, el efecto Doppler no se ha medido todav\u00eda y desconocemos la masa del planeta. As\u00ed, aunque sabemos su tama\u00f1o aproximado, desconocemos su densidad media y por tanto si es esencialmente rocoso, como la Tierra, o su composici\u00f3n qu\u00edmica es muy distinta, pudiendo contener gran cantidad de substancias l\u00edquidas (no solo agua) o gaseosas.<\/p>\n<p>Por otra parte, aunque a edad estelar es un par\u00e1metro cuya determinaci\u00f3n es, en general, imprecisa, los 6000 millones de a\u00f1os hacen que, en principio, su estrella central se encuentre m\u00e1s evolucionada que el Sol y por tanto algo m\u00e1s cerca del final de su vida. De todas maneras, ello solo ocurrir\u00e1 dentro de otros\u2026 4000 millones de a\u00f1os, lo cual no es preocupante. Y, repetimos, la incertidumbre en la determinaci\u00f3n de la edad es significativa y de hecho es incluso posible que fuera algo m\u00e1s joven que el Sol o incluso que alanzara los 8000 millones de a\u00f1os.<\/p>\n<p>Sea como sea, lo m\u00e1s relevante es que\u00a0 su estrella central, no el planeta en s\u00ed, lo que es an\u00e1logo. Podr\u00edamos decir que Kepler-452 (la estrella) es <strong>un \u201cmellizo\u201d del Sol<\/strong> que naci\u00f3 algo antes, mientras que Kepler-452b (el planeta) es, en verdad, <strong>solo un \u201cprimo\u201d<\/strong>, incluso en segundo o tercer grado.<\/p>\n<p>De hecho, seg\u00fan la <a href=\"http:\/\/phl.upr.edu\/projects\/habitable-exoplanets-catalog\" target=\"_blank\">clasificaci\u00f3n de planetas terrestres en la zona de habitabilidad de la Universidad de Puerto Rico<\/a>, existen varios exoplanetas que tienen condiciones m\u00e1s pr\u00f3ximas a nuestra querida Tierra. Seg\u00fan esta lista, Kepler-452b solo se encontrar\u00eda en la sexta posici\u00f3n del ranking, dominado por Kepler-438b, que orbita alrededor de una estrella con la mitad de masa que el Sol y significativamente m\u00e1s fr\u00eda, pero de radio mucho m\u00e1s acorde con el terrestre: solo un 12% m\u00e1s grande. Dada la radiaci\u00f3n incidente que proviene de su astro central, las condiciones de habitabilidad ser\u00edan m\u00e1s id\u00f3neas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>David Barrado Navascu\u00e9s<\/strong><\/p>\n<p style=\"text-align: justify;\">CAB, INTA-CSIC<br \/>\nCentro Europeo de Astronom\u00eda Espacial (ESAC, Madrid)<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><strong>@David_Barrado<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>En cualquier caso merece ser recordado, una vez m\u00e1s, que es mejor cuidar el planeta que s\u00ed sabemos que es habitable, la Tierra.<br \/>\nENLACES:<\/p>\n<ul>\n<li><a href=\"http:\/\/www.jpl.nasa.gov\/news\/news.php?feature=4665\" target=\"blank\"> NASA&#8217;s Kepler Mission Discovers Bigger, Older Cousin to Earth<\/a><\/li>\n<li><a href=\"http:\/\/phl.upr.edu\/projects\/habitable-exoplanets-catalog\" target=\"blank\"> Habitable planet catalog. Universidad de Puerto Rico <\/a><\/li>\n<li><a href=\"http:\/\/www.elmundo.es\/ciencia\/2015\/07\/23\/55b12a6522601d10068b459c.html\" target=\"blank\"> El Mundo: La NASA descubre el planeta m\u00e1s parecido a la Tierra hallado fuera del Sistema Solar<\/a><\/li>\n<li><a href=\"http:\/\/www.abc.es\/ciencia\/20150725\/abci-kepler-exoplanetas-201507242157.html\" target=\"blank\"> ABC: Los \u00abprimos lejanos\u00bb de la Tierra<\/a><\/li>\n<li>Eppu si muove (enlace a\u00f1adido 20150727): <a href=\"https:\/\/perosimuove.wordpress.com\/2015\/07\/24\/kepler-452b-cuando-la-realidad-alcanza-a-la-ficcion\/\" target=\"blank\">Kepler-452b: cuando la realidad alcanza a la ficci\u00f3n.<\/a> Gracias a Jorge Lillo-Box por notificarme dos erratas.<\/li>\n<li>20150727: Art\u00edculo original en ingl\u00e9s: <a href=\"http:\/\/arxiv.org\/abs\/1507.06723\" target=\"blank\">Discovery and Validation of Kepler-452b: A 1.6-Re Super Earth Exoplanet in the Habitable Zone of a G2 Star<\/a><\/li>\n<li>Otro examen cr\u00edtico en ingl\u00e9s (enlace a\u00f1adido 20150727): <a href=\"https:\/\/plus.google.com\/+ElizabethTasker\/posts\/9C3cWzAnyvF\" target=\"blank\">Earth 2.0? Stop right there!<\/a><\/li>\n<\/ul>\n<hr size=\"1\" \/>\n<p><a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/\" target=\"blank\"><br \/>\n<strong> P\u00e1gina principal del \u201cCuaderno de Bit\u00e1cora Estelar\u201d <\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre la avalancha de descubrimientos astron\u00f3micos de las \u00faltimas semanas, destacan, entre otros, las im\u00e1genes de la sonda Rosetta al orbitar alrededor del cometa 67P\/Churyumov-Gerasimenko, \u00a0los datos que provienen de los planetas enanos Ceres y Plut\u00f3n, tomados con las naves\u00a0 Dawn y New Horizon. Fuera del Sistema Solar, NASA ha anunciado el descubrimiento del \u201cprimo\u201d de la Tierra, denominado Kepler-452.<\/p>\n","protected":false},"author":140,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[566,565,559],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Entre la avalancha de descubrimientos astron\u00f3micos de las \u00faltimas semanas, destacan, entre otros, las im\u00e1genes de la sonda Rosetta al orbitar alrededor del cometa 67P\/Churyumov-Gerasimenko, los datos que provienen de los planetas enanos Ceres y Plut\u00f3n, tomados con las naves Dawn y New Horizon. Fuera del Sistema Solar, NASA ha anunciado el descubrimiento del \u201cprimo\u201d\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"David Barrado\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre? - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"Entre la avalancha de descubrimientos astron\u00f3micos de las \u00faltimas semanas, destacan, entre otros, las im\u00e1genes de la sonda Rosetta al orbitar alrededor del cometa 67P\/Churyumov-Gerasimenko, los datos que provienen de los planetas enanos Ceres y Plut\u00f3n, tomados con las naves Dawn y New Horizon. Fuera del Sistema Solar, NASA ha anunciado el descubrimiento del \u201cprimo\u201d\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-07-25T10:07:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-03-11T15:04:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre? - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Entre la avalancha de descubrimientos astron\u00f3micos de las \u00faltimas semanas, destacan, entre otros, las im\u00e1genes de la sonda Rosetta al orbitar alrededor del cometa 67P\/Churyumov-Gerasimenko, los datos que provienen de los planetas enanos Ceres y Plut\u00f3n, tomados con las naves Dawn y New Horizon. Fuera del Sistema Solar, NASA ha anunciado el descubrimiento del \u201cprimo\u201d\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784#blogposting\",\"name\":\"Kepler-452b: \\u00bfUn exoplaneta an\\u00e1logo terrestre? - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"Kepler-452b: \\u00bfUn exoplaneta an\\u00e1logo terrestre?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2015\\\/07\\\/Kepler_HZ_SType_Planets.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784\\\/#articleImage\",\"width\":624,\"height\":450,\"caption\":\"Diagrama con varios exoplanetas que se encuentran orbitando alrededor de sus respectivas estrellas en la zona de habitabilidad o confort, en donde el agua, de haberla, podr\\u00eda estar en estado l\\u00edquido. Hasta el momento se han encontrado varias super-tierras orbitando alrededor de estrellas m\\u00e1s fr\\u00edas que el Sol. La estrella Kepler-452 es una an\\u00e1logo solar, con una temperatura superficial pr\\u00e1cticamente id\\u00e9ntica, aunque su edad podr\\u00eda ser significativamente m\\u00e1s alta. En lo que respecta al planeta, su tama\\u00f1o es un 60% m\\u00e1s grande que la Tierra y no tenemos informaci\\u00f3n sobre su masa, densidad media o posible composici\\u00f3n\"},\"datePublished\":\"2015-07-25T11:07:29+01:00\",\"dateModified\":\"2016-03-11T16:04:01+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784#webpage\"},\"articleSection\":\"Astrobiolog\\u00eda, Marte, el mellizo de la Tierra, Sistemas planetarios\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/sistemas-planetarios#listItem\",\"name\":\"Sistemas planetarios\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/sistemas-planetarios#listItem\",\"position\":2,\"name\":\"Sistemas planetarios\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/sistemas-planetarios\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784#listItem\",\"name\":\"Kepler-452b: \\u00bfUn exoplaneta an\\u00e1logo terrestre?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784#listItem\",\"position\":3,\"name\":\"Kepler-452b: \\u00bfUn exoplaneta an\\u00e1logo terrestre?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/sistemas-planetarios#listItem\",\"name\":\"Sistemas planetarios\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn\",\"name\":\"David Barrado\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"David Barrado\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784\",\"name\":\"Kepler-452b: \\u00bfUn exoplaneta an\\u00e1logo terrestre? - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Entre la avalancha de descubrimientos astron\\u00f3micos de las \\u00faltimas semanas, destacan, entre otros, las im\\u00e1genes de la sonda Rosetta al orbitar alrededor del cometa 67P\\\/Churyumov-Gerasimenko, los datos que provienen de los planetas enanos Ceres y Plut\\u00f3n, tomados con las naves Dawn y New Horizon. Fuera del Sistema Solar, NASA ha anunciado el descubrimiento del \\u201cprimo\\u201d\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/07\\\/25\\\/133784#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\"},\"datePublished\":\"2015-07-25T11:07:29+01:00\",\"dateModified\":\"2016-03-11T16:04:01+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre? - Cuaderno de bit\u00e1cora estelar","description":"Entre la avalancha de descubrimientos astron\u00f3micos de las \u00faltimas semanas, destacan, entre otros, las im\u00e1genes de la sonda Rosetta al orbitar alrededor del cometa 67P\/Churyumov-Gerasimenko, los datos que provienen de los planetas enanos Ceres y Plut\u00f3n, tomados con las naves Dawn y New Horizon. Fuera del Sistema Solar, NASA ha anunciado el descubrimiento del \u201cprimo\u201d","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784#blogposting","name":"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre? - Cuaderno de bit\u00e1cora estelar","headline":"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2015\/07\/Kepler_HZ_SType_Planets.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784\/#articleImage","width":624,"height":450,"caption":"Diagrama con varios exoplanetas que se encuentran orbitando alrededor de sus respectivas estrellas en la zona de habitabilidad o confort, en donde el agua, de haberla, podr\u00eda estar en estado l\u00edquido. Hasta el momento se han encontrado varias super-tierras orbitando alrededor de estrellas m\u00e1s fr\u00edas que el Sol. La estrella Kepler-452 es una an\u00e1logo solar, con una temperatura superficial pr\u00e1cticamente id\u00e9ntica, aunque su edad podr\u00eda ser significativamente m\u00e1s alta. En lo que respecta al planeta, su tama\u00f1o es un 60% m\u00e1s grande que la Tierra y no tenemos informaci\u00f3n sobre su masa, densidad media o posible composici\u00f3n"},"datePublished":"2015-07-25T11:07:29+01:00","dateModified":"2016-03-11T16:04:01+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784#webpage"},"articleSection":"Astrobiolog\u00eda, Marte, el mellizo de la Tierra, Sistemas planetarios"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/sistemas-planetarios#listItem","name":"Sistemas planetarios"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/sistemas-planetarios#listItem","position":2,"name":"Sistemas planetarios","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/sistemas-planetarios","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784#listItem","name":"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784#listItem","position":3,"name":"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/sistemas-planetarios#listItem","name":"Sistemas planetarios"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn","name":"David Barrado","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"David Barrado"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784","name":"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre? - Cuaderno de bit\u00e1cora estelar","description":"Entre la avalancha de descubrimientos astron\u00f3micos de las \u00faltimas semanas, destacan, entre otros, las im\u00e1genes de la sonda Rosetta al orbitar alrededor del cometa 67P\/Churyumov-Gerasimenko, los datos que provienen de los planetas enanos Ceres y Plut\u00f3n, tomados con las naves Dawn y New Horizon. Fuera del Sistema Solar, NASA ha anunciado el descubrimiento del \u201cprimo\u201d","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author"},"datePublished":"2015-07-25T11:07:29+01:00","dateModified":"2016-03-11T16:04:01+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre? - Cuaderno de bit\u00e1cora estelar","og:description":"Entre la avalancha de descubrimientos astron\u00f3micos de las \u00faltimas semanas, destacan, entre otros, las im\u00e1genes de la sonda Rosetta al orbitar alrededor del cometa 67P\/Churyumov-Gerasimenko, los datos que provienen de los planetas enanos Ceres y Plut\u00f3n, tomados con las naves Dawn y New Horizon. Fuera del Sistema Solar, NASA ha anunciado el descubrimiento del \u201cprimo\u201d","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2015-07-25T10:07:29+00:00","article:modified_time":"2016-03-11T15:04:01+00:00","twitter:card":"summary","twitter:title":"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre? - Cuaderno de bit\u00e1cora estelar","twitter:description":"Entre la avalancha de descubrimientos astron\u00f3micos de las \u00faltimas semanas, destacan, entre otros, las im\u00e1genes de la sonda Rosetta al orbitar alrededor del cometa 67P\/Churyumov-Gerasimenko, los datos que provienen de los planetas enanos Ceres y Plut\u00f3n, tomados con las naves Dawn y New Horizon. Fuera del Sistema Solar, NASA ha anunciado el descubrimiento del \u201cprimo\u201d","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"133784","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 09:56:05","updated":"2026-08-05 23:44:29","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/sistemas-planetarios\" title=\"Sistemas planetarios\">Sistemas planetarios<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Sistemas planetarios","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/sistemas-planetarios"},{"label":"Kepler-452b: \u00bfUn exoplaneta an\u00e1logo terrestre?","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/133784"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=133784"}],"version-history":[{"count":18,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/133784\/revisions"}],"predecessor-version":[{"id":134027,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/133784\/revisions\/134027"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=133784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=133784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=133784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}