{"id":133963,"date":"2015-12-17T12:08:37","date_gmt":"2015-12-17T11:08:37","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/astrofisica\/?p=133963"},"modified":"2015-12-17T12:39:17","modified_gmt":"2015-12-17T11:39:17","slug":"el-buscador-de-planetas-carmenes-supera-con-exito-su-fase-de-pruebas","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963","title":{"rendered":"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas"},"content":{"rendered":"<p>CARMENES, un innovador instrumento dise\u00f1ado para buscar planetas similares a la Tierra, ha superado con \u00e9xito su fase de pruebas en el telescopio. Despu\u00e9s de cinco a\u00f1os de preparaci\u00f3n, este instrumento altamente complejo fue empleado por primera vez en noviembre en el telescopio de 3,5 metros del <a href=\"http:\/\/www.caha.es\" target=\"_blank\">Observatorio de Calar Alto<\/a> en Almer\u00eda, operado conjuntamente por la Sociedad Max-Planck (MPG) y el Consejo Superior de Investigaciones Cient\u00edficas (CSIC). CARMENES, dise\u00f1ado y construido por un consorcio internacional de once instituciones alemanas y espa\u00f1olas, consta de dos espectr\u00f3grafos optimizados para la detecci\u00f3n de planetas en torno a estrellas cercanas. Por lo tanto, CARMENES constituir\u00e1 un hito para una de las ramas m\u00e1s interesantes de la exploraci\u00f3n del espacio: la b\u00fasqueda de una segunda Tierra. Numerosos cient\u00edficos y ingenieros\u00a0 de Espa\u00f1a y Alemania han participado en el dise\u00f1o y la construcci\u00f3n de este nuevo \u00abcazador de planetas\u00bb.<\/p>\n<p><!--more--><\/p>\n<p>Por medio de la b\u00fasqueda de planetas fuera de nuestro Sistema Solar -los llamados exoplanetas-, los investigadores quieren entender c\u00f3mo y d\u00f3nde se forman estos cuerpos, y si ofrecen condiciones que podr\u00edan sustentar la vida. Por ahora, han sido descubierto m\u00e1s de dos mil exoplanetas.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abSin embargo, la mayor\u00eda son hostiles para la vida\u00bb, explica Andreas Quirrenbach, investigador que encabeza el proyecto. \u00abPor eso buscaremos planetas en torno a enanas rojas (o enanas M), estrellas m\u00e1s peque\u00f1as que ofrecen las condiciones para la existencia de agua l\u00edquida en \u00f3rbitas cercanas y en las que s\u00ed podemos detectar las oscilaciones producidas por planetas similares al nuestro\u00bb. Adem\u00e1s, la longevidad de este tipo de estrellas y de sus posibles sistemas planetarios constituye una condici\u00f3n necesaria para el desarrollo biol\u00f3gico a largo plazo.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abSin embargo, las enanas rojas son mucho m\u00e1s fr\u00edas y rojizas que el Sol, de modo que ten\u00edamos que observar tanto en el visible como en el infrarrojo, lo que constituye una de las fortalezas de CARMENES: ning\u00fan otro instrumento del mundo puede hacer esto\u00bb, apunta Pedro Amado, investigador que colidera el proyecto y cuyo grupo ha desarrollado el espectr\u00f3grafo infrarrojo.<\/p>\n<p>&nbsp;<\/p>\n<p>Dadas las caracter\u00edsticas e importancia cient\u00edfica del proyecto, el Observatorio de Calar Alto ha garantizado un m\u00ednimo de seiscientas noches de observaci\u00f3n en el mayor de sus telescopios para CARMENES. \u00abProyectos con tan alta dedicaci\u00f3n son poco habituales en la astronom\u00eda moderna -se\u00f1ala Jes\u00fas Aceituno, vicedirector del Observatorio-. Con CARMENES en funcionamiento, Calar Alto se convertir\u00e1 en una referencia internacional en la b\u00fasqueda de planetas de tipo terrestre y se situar\u00e1 en la vanguardia de la instrumentaci\u00f3n astron\u00f3mica\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>La detecci\u00f3n de exoplanetas mediante imagen directa constituye un gran reto debido al resplandor de sus estrellas madre, miles de millones de veces m\u00e1s brillantes que los planetas y muy pr\u00f3ximas a ellos. De modo que los cient\u00edficos aprovechan la fuerza gravitatoria ejercida por los planetas en sus estrellas anfitrionas. \u00abEstrella y planeta giran como si se tratara de dos patinadores cogidos de la mano\u00bb, comenta Ignasi Ribas, encargado de la planificaci\u00f3n del programa de observaci\u00f3n de CARMENES. \u00abPero si uno de los patinadores es muy peque\u00f1o y ligero, el otro solo se tiene que mover un poco\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>En el caso de las estrellas y los planetas, la disparidad de sus masas es tan grande que la estrella se mueve a una velocidad de unos pocos metros por segundo, mientras que los planetas giran a su alrededor a velocidades de kil\u00f3metros por segundo. Pero es el lento movimiento de la estrella lo que revela la presencia del planeta, al generar reveladores bamboleos de l\u00edneas en el espectro estelar llamados desplazamientos Doppler. Estas oscilaciones son causadas por cambios peri\u00f3dicos muy peque\u00f1os del color espectral observado en la estrella debido a su movimiento con respecto al observador. Debido a su tecnolog\u00eda de vanguardia estos peque\u00f1os cambios son, de hecho, detectables con CARMENES.<\/p>\n<p>&nbsp;<\/p>\n<p>Walter Seifert, responsable de la construcci\u00f3n del espectr\u00f3grafo visible, se\u00f1ala: \u00abTen\u00edamos que hacer el instrumento lo suficientemente estable como para poder medir estos peque\u00f1os movimientos de las estrellas acerc\u00e1ndose y alej\u00e1ndose de nosotros durante su danza orbital\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abLa combinaci\u00f3n de los datos de dos espectr\u00f3grafos nos proporcionar\u00e1 mucha m\u00e1s informaci\u00f3n que cualquier instrumento anterior y nos permiten distinguir si estamos viendo el movimiento orbital de un planeta o manchas en la superficie de la estrella\u00bb, comenta Ansgar Reiners, que ha realizado los c\u00e1lculos detallados de lo CARMENES podr\u00e1 medir. \u00abPor lo tanto, esperamos descubrir docenas de planetas potencialmente habitables en los pr\u00f3ximos a\u00f1os\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>Para hacer esto posible, el rendimiento de CARMENES se ha caracterizado y optimizado durante las \u00faltimas semanas. El equipo espera para recoger los primeros datos cient\u00edficos en el primer d\u00eda de 2016.<\/p>\n<p>&nbsp;<\/p>\n<p>Las once instituciones que forman el consorcio CARMENES son:<\/p>\n<p>Max-Planck-Institut f\u00fcr Astronomie, Heidelberg (Alemania)<\/p>\n<p>Instituto de Astrof\u00edsica de Andaluc\u00eda, Granada (Espa\u00f1a)<\/p>\n<p>Landessternwarte K\u00f6nigstuhl,\u00a0 Zentrum f\u00fcr Astronomie der Universit\u00e4t Heidelberg (Alemania)<\/p>\n<p>Institut de Ci\u00e8ncies de l&#8217;Espai, Barcelona (Espa\u00f1a)<\/p>\n<p>Insitut f\u00fcr Astrophysik, Georg-August-Universit\u00e4t G\u00f6ttingen (Alemania)<\/p>\n<p>Universidad Complutense de Madrid, Departamento de Astrof\u00edsica (Espa\u00f1a)<\/p>\n<p>Th\u00fcringer Landessternwarte Tautenburg (Alemania)<\/p>\n<p>Instituto de Astrof\u00edsica de Canarias, Tenerife (Espa\u00f1a)<\/p>\n<p>Hamburger Sternwarte, Universit\u00e4t Hamburg (Alemania)<\/p>\n<p>Centro de Astrobiolog\u00eda, Madrid (Espa\u00f1a)<\/p>\n<p>Centro Astron\u00f3mico Hispano-Alem\u00e1n, Calar Alto (Alemania \/ Espa\u00f1a)<\/p>\n<p>&nbsp;<\/p>\n<p>CARMENES ha sido financiado por la Sociedad Max Planck (MPG), el Consejo Superior de Investigaciones Cient\u00edficas (CSIC) y los miembros del consorcio CARMENES, con contribuciones del Ministerio de Econom\u00eda y Hacienda espa\u00f1ol (MINECO), el estado de Baden-W\u00fcrttemberg, la Fundaci\u00f3n Alemana para la Ciencia (DFG), la Fundaci\u00f3n Klaus Tschira (KTS), la Junta de Andaluc\u00eda y la Uni\u00f3n Europea a trav\u00e9s de los fondos FEDER\/ERF.<\/p>\n<p>&nbsp;<\/p>\n<p>M\u00e1s informaci\u00f3n en \u00a0de CARMENES en <a href=\"http:\/\/carmenes.caha.es\" target=\"_blank\">este enlace<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>PD:<\/p>\n<h3><a href=\"http:\/\/naukas.com\/2015\/12\/17\/carmenes-calar-alto-a-la-caza-de-exotierras\/\" target=\"_blank\">CARMENES: Calar Alto preparado para cazar Exotierras<\/a><\/h3>\n<p>Cr\u00f3nica de <a href=\"https:\/\/twitter.com\/i\/redirect?url=https%3A%2F%2Ftwitter.com%2FEl_Lobo_Rayado%3Fcn%3DcmVwbHk%253D%26refsrc%3Demail&amp;t=1&amp;cn=cmVwbHk%3D&amp;sig=ee4c2e53f214da870a577c2d937748e6fe663a31&amp;iid=0853e24a02f94e65bff5e3cec86b8c49&amp;uid=1303916324&amp;nid=27+231\">@El_Lobo_Rayado<\/a> desde Australia.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CARMENES, un innovador instrumento dise\u00f1ado para buscar planetas similares a la Tierra, ha superado con \u00e9xito su fase de pruebas en el telescopio. Despu\u00e9s de cinco a\u00f1os de preparaci\u00f3n, este instrumento altamente complejo fue empleado por primera vez en noviembre en el telescopio de 3,5 metros del Observatorio de Calar Alto en Almer\u00eda, operado conjuntamente por la Sociedad Max-Planck (MPG) y el Consejo Superior de Investigaciones Cient\u00edficas (CSIC). CARMENES, dise\u00f1ado y construido por un consorcio internacional de once instituciones alemanas y espa\u00f1olas, consta de dos espectr\u00f3grafos optimizados para la detecci\u00f3n de planetas en torno a estrellas cercanas. Por lo tanto,\u2026<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1,557],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"CARMENES, un innovador instrumento dise\u00f1ado para buscar planetas similares a la Tierra, ha superado con \u00e9xito su fase de pruebas en el telescopio. Despu\u00e9s de cinco a\u00f1os de preparaci\u00f3n, este instrumento altamente complejo fue empleado por primera vez en noviembre en el telescopio de 3,5 metros del Observatorio de Calar Alto en Almer\u00eda, operado conjuntamente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrador CBE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"CARMENES, un innovador instrumento dise\u00f1ado para buscar planetas similares a la Tierra, ha superado con \u00e9xito su fase de pruebas en el telescopio. Despu\u00e9s de cinco a\u00f1os de preparaci\u00f3n, este instrumento altamente complejo fue empleado por primera vez en noviembre en el telescopio de 3,5 metros del Observatorio de Calar Alto en Almer\u00eda, operado conjuntamente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-12-17T11:08:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-12-17T11:39:17+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"CARMENES, un innovador instrumento dise\u00f1ado para buscar planetas similares a la Tierra, ha superado con \u00e9xito su fase de pruebas en el telescopio. Despu\u00e9s de cinco a\u00f1os de preparaci\u00f3n, este instrumento altamente complejo fue empleado por primera vez en noviembre en el telescopio de 3,5 metros del Observatorio de Calar Alto en Almer\u00eda, operado conjuntamente\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963#blogposting\",\"name\":\"El buscador de planetas CARMENES supera con \\u00e9xito su fase de pruebas - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"El buscador de planetas CARMENES supera con \\u00e9xito su fase de pruebas\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2015-12-17T12:08:37+01:00\",\"dateModified\":\"2015-12-17T12:39:17+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963#webpage\"},\"articleSection\":\"General, Instrumentaci\\u00f3n espacial y astron\\u00f3mica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963#listItem\",\"name\":\"El buscador de planetas CARMENES supera con \\u00e9xito su fase de pruebas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963#listItem\",\"position\":3,\"name\":\"El buscador de planetas CARMENES supera con \\u00e9xito su fase de pruebas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis\",\"name\":\"Administrador CBE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Administrador CBE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963\",\"name\":\"El buscador de planetas CARMENES supera con \\u00e9xito su fase de pruebas - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"CARMENES, un innovador instrumento dise\\u00f1ado para buscar planetas similares a la Tierra, ha superado con \\u00e9xito su fase de pruebas en el telescopio. Despu\\u00e9s de cinco a\\u00f1os de preparaci\\u00f3n, este instrumento altamente complejo fue empleado por primera vez en noviembre en el telescopio de 3,5 metros del Observatorio de Calar Alto en Almer\\u00eda, operado conjuntamente\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2015\\\/12\\\/17\\\/133963#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"datePublished\":\"2015-12-17T12:08:37+01:00\",\"dateModified\":\"2015-12-17T12:39:17+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas - Cuaderno de bit\u00e1cora estelar","description":"CARMENES, un innovador instrumento dise\u00f1ado para buscar planetas similares a la Tierra, ha superado con \u00e9xito su fase de pruebas en el telescopio. Despu\u00e9s de cinco a\u00f1os de preparaci\u00f3n, este instrumento altamente complejo fue empleado por primera vez en noviembre en el telescopio de 3,5 metros del Observatorio de Calar Alto en Almer\u00eda, operado conjuntamente","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963#blogposting","name":"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas - Cuaderno de bit\u00e1cora estelar","headline":"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#articleImage","width":217,"height":72},"datePublished":"2015-12-17T12:08:37+01:00","dateModified":"2015-12-17T12:39:17+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963#webpage"},"articleSection":"General, Instrumentaci\u00f3n espacial y astron\u00f3mica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963#listItem","name":"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963#listItem","position":3,"name":"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis","name":"Administrador CBE","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Administrador CBE"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963","name":"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas - Cuaderno de bit\u00e1cora estelar","description":"CARMENES, un innovador instrumento dise\u00f1ado para buscar planetas similares a la Tierra, ha superado con \u00e9xito su fase de pruebas en el telescopio. Despu\u00e9s de cinco a\u00f1os de preparaci\u00f3n, este instrumento altamente complejo fue empleado por primera vez en noviembre en el telescopio de 3,5 metros del Observatorio de Calar Alto en Almer\u00eda, operado conjuntamente","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"datePublished":"2015-12-17T12:08:37+01:00","dateModified":"2015-12-17T12:39:17+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas - Cuaderno de bit\u00e1cora estelar","og:description":"CARMENES, un innovador instrumento dise\u00f1ado para buscar planetas similares a la Tierra, ha superado con \u00e9xito su fase de pruebas en el telescopio. Despu\u00e9s de cinco a\u00f1os de preparaci\u00f3n, este instrumento altamente complejo fue empleado por primera vez en noviembre en el telescopio de 3,5 metros del Observatorio de Calar Alto en Almer\u00eda, operado conjuntamente","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2015-12-17T11:08:37+00:00","article:modified_time":"2015-12-17T11:39:17+00:00","twitter:card":"summary","twitter:title":"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas - Cuaderno de bit\u00e1cora estelar","twitter:description":"CARMENES, un innovador instrumento dise\u00f1ado para buscar planetas similares a la Tierra, ha superado con \u00e9xito su fase de pruebas en el telescopio. Despu\u00e9s de cinco a\u00f1os de preparaci\u00f3n, este instrumento altamente complejo fue empleado por primera vez en noviembre en el telescopio de 3,5 metros del Observatorio de Calar Alto en Almer\u00eda, operado conjuntamente","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"133963","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 09:57:33","updated":"2026-08-05 23:44:29","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/general"},{"label":"El buscador de planetas CARMENES supera con \u00e9xito su fase de pruebas","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/12\/17\/133963"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/133963"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=133963"}],"version-history":[{"count":9,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/133963\/revisions"}],"predecessor-version":[{"id":133968,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/133963\/revisions\/133968"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=133963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=133963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=133963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}