{"id":134040,"date":"2016-04-17T11:39:39","date_gmt":"2016-04-17T10:39:39","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/astrofisica\/?p=134040"},"modified":"2016-04-17T11:46:31","modified_gmt":"2016-04-17T10:46:31","slug":"el-futuro-llama-a-la-puerta-hacia-la-colonizacion-estelar","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040","title":{"rendered":"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb"},"content":{"rendered":"<p>Un grupo de destacados fil\u00e1ntropos, cient\u00edficos y tecn\u00f3logos han lanzado una iniciativa para \u201cconquistar\u201d las estrellas. Se trata de un cambio en la estrategia de exploraci\u00f3n espacial: desde las mastod\u00f3nticas naves espaciales de NASA a la microtecnolog\u00eda y la econom\u00eda de escala.<\/p>\n<p><!--more--><\/p>\n<p>Los multimillonarios Yuri Milner\u00a0 (Digital Sky Technologies) y Mark Zuckerberg (Facebook), junto a investigadores de la talla de Stephen Hawking, a trav\u00e9s de la <em><a href=\"http:\/\/breakthroughinitiatives.org\/#http:\/\/breakthroughinitiatives.org\/\">Breakthrough Unitiatives<\/a>,<\/em> han puesto sobre la mesa 100 millones de d\u00f3lares para desarrollar un pionero proyecto cuyo objetivo es enviar naves interestelares del tama\u00f1o de tarjetas de cr\u00e9dito. La iniciativa, denominada <em><a href=\"http:\/\/breakthroughinitiatives.org\/Initiative\/3#http:\/\/breakthroughinitiatives.org\/Initiative\/3\">Starshot<\/a> <\/em>(disparo estelar en ing\u00e9s), forma parte de un conjunto de planes destinados a responder a una de las preguntas esenciales: \u00bfestamos solos en el universo?\u00a0 <em>Starshot<\/em> presenta numerosos desaf\u00edos, pero tambi\u00e9n abre una sinn\u00famero de oportunidades en campos muy diversos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 significa?<\/strong><\/p>\n<p>Nuestro planeta y por tanto nuestra civilizaci\u00f3n est\u00e1n amenazados por nosotros mismos y por el ambiente hostil en el que nos movemos: meteoritos o supernovas podr\u00edan eliminarnos sin dejar huella. De hecho, diversos eventos astrof\u00edsicos han provocado extinciones masivas en el pasado, como fue el caso de la desaparici\u00f3n de los dinosaurios del Cret\u00e1cico-Terciario hace 65 millones de a\u00f1os. \u00a0Siguiendo la estela del a\u00f1orado divulgador Carl Sagan, Hawkins ha propuesto la b\u00fasqueda de nuevos hogares m\u00e1s all\u00e1 del Sistema Solar.<\/p>\n<p><em>Breakthrough<\/em> ha lanzado un iniciativa para el desarrollo de tecnolog\u00edas que permitir\u00e1n el env\u00edo de micronaves de unos pocos gramos a las estrellas m\u00e1s cercanas, entre las que destaca Alfa Centauri, la m\u00e1s pr\u00f3xima similar a nuestro Sol. El objetivo inicial es verificar si existen all\u00ed <a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784#https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2015\/07\/25\/133784\">planetas tipo Tierra<\/a>; el final es la colonizaci\u00f3n. Disponen de 100 millones de d\u00f3lares para acometer los primeros pasos. La factura global superar\u00eda ampliamente los 10,000 millones y requerir\u00eda la cooperaci\u00f3n internacional. En el grupo impulsor, dirigido por el exdirector del Ames Research Center de NASA <strong>Pete Worden,<\/strong><strong> <\/strong>incluye un elenco de figuras muy relevantes de la investigaci\u00f3n y de la cultura.<\/p>\n<p>El desarrollo del programa durar\u00e1 dos o tres d\u00e9cadas. El viaje ser\u00e1 de unos 20 a\u00f1os, con las micronaves desplaz\u00e1ndose al 20% de la velocidad de la luz. Se requerir\u00e1 el desarrollo de numerosas tecnolog\u00edas: propulsores de rayos l\u00e1seres localizados en la Tierra con una potencia equivalente a 100 centrales nucleares, velas fot\u00f3nicas en las naves, escudos contra los rayos c\u00f3smicos y las part\u00edculas de polvo interestelares, sistemas de navegaci\u00f3n, <a href=\"http:\/\/www.bez.es\/378474810\/Los-dias-contados-de-la-Ley-de-Moore.html#http:\/\/www.bez.es\/378474810\/Los-dias-contados-de-la-Ley-de-Moore.html\">microelectr\u00f3nica<\/a> y c\u00e1maras min\u00fasculas, o sistemas de comunicaci\u00f3n para devolver la informaci\u00f3n a la Tierra, entre otras.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfPor qu\u00e9 es importante?<\/strong><\/p>\n<p>El proyecto <em>Starshot<\/em>\u00a0 intenta responder a algunas de las preguntas m\u00e1s importantes que la humanidad siempre se ha formulado: \u00bfestamos solos en el cosmos? Adem\u00e1s, intenta buscar nuevos h\u00e1bitats para poder expandirnos, continuando la emigraci\u00f3n que se inici\u00f3 hace decenas de miles de a\u00f1os desde la sabana africana. <a href=\"http:\/\/www.bez.es\/519080290\/Supertierras-alla-vamos.html#http:\/\/www.bez.es\/519080290\/Supertierras-alla-vamos.html\">El destino, ahora, son las estrellas<\/a>. El objetivo es asegurarnos nuestra supervivencia como especie.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 implicaciones tiene para nosotros?<\/strong><\/p>\n<p>Las numerosas nuevas tecnolog\u00edas que son necesarias tendr\u00e1n un efecto incalculable en la vida diaria, aun cuando el proyecto no se llegue a efectuar ning\u00fan lanzamiento. Desde producci\u00f3n y almacenamiento de energ\u00eda, pasando por la miniaturizaci\u00f3n de la electr\u00f3nica, hasta nuevos sistemas de comunicaci\u00f3n.<\/p>\n<p>El proyecto, adem\u00e1s, pone de manifiesto varios hechos relevantes: la disposici\u00f3n de fundaciones y fil\u00e1ntropos a aceptar retos que implican planificaciones a muy largo plazo y la existencia de visionarios que est\u00e1n dispuestos a financiarlos. Esto contrasta con la sociedad espa\u00f1ola, la falta de proyectos filantr\u00f3picos de sus millonarios y la actitud de los distintos gobiernos, incapaces de pensar a medio plazo y de proporcionar financiaci\u00f3n a proyectos arriesgados.<\/p>\n<p>Pero lo m\u00e1s importante probablemente sea la reflexi\u00f3n sobre la necesidad de pensar en el futuro y la supervivencia. Sin embargo, la propuesta de Stephen Hawking posiblemente no est\u00e9 enfocada de la manera m\u00e1s adecuada. En efecto el universo es un ambiente poco amable, pero el principal peligro para la humanidad est\u00e1 en nosotros (\u201c<em>Homo homini lupus est<\/em>\u201d, \u201cel hombre es el lobo del hombre\u201d). La respuesta debe estar aqu\u00ed y ahora, con una\u00a0 mejor gesti\u00f3n de nuestros recursos.<\/p>\n<p>Y no, no es ciencia-ficci\u00f3n: el futuro ya est\u00e1 aqu\u00ed.<\/p>\n<p>&nbsp;<\/p>\n<p>David Barrado Navascu\u00e9s<strong> <\/strong><\/p>\n<p><strong>@David_Barrado<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>PD:<\/p>\n<p><a href=\"http:\/\/www.breakthroughinitiatives.org\/\" target=\"_blank\">Breakthrough Initiatives<\/a><\/p>\n<p><a href=\"http:\/\/www.elmundo.es\/ciencia\/2016\/04\/17\/570f7035268e3eb23a8b4681.html\">El Mundo, Teresa Guerrero, con entrevista.<strong> &#8216;Starshot&#8217;: el sue\u00f1o interestelar de Hawking, un plan dif\u00edcilmente viable<\/strong><\/a><br \/>\n<a href=\"http:\/\/www.elmundo.es\/ciencia\/2016\/04\/17\/5710c9f6268e3e5b488b45dd.html\">El Mundo, Rafael Bachiller. <\/a> <strong><a href=\"http:\/\/www.elmundo.es\/ciencia\/2016\/04\/17\/5710c9f6268e3e5b488b45dd.html\">Proyecto &#8216;Starshot&#8217; de Hawking: Por el sendero dif\u00edcil hacia las estrellas<\/a><\/strong><\/p>\n<p>Art\u00edculo publicado en BEZ: <strong><a href=\"http:\/\/www.bez.es\/204646387\/Stephen-Hawking-se-lanza-colonizar-el-espacio-con-micronaves.html\" target=\"_blank\">Hawking se lanza a la conquista del espacio con micronaves<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de destacados fil\u00e1ntropos, cient\u00edficos y tecn\u00f3logos han lanzado una iniciativa para \u201cconquistar\u201d las estrellas. Se trata de un cambio en la estrategia de exploraci\u00f3n espacial: desde las mastod\u00f3nticas naves espaciales de NASA a la microtecnolog\u00eda y la econom\u00eda de escala.<\/p>\n","protected":false},"author":140,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[566,556,557],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Un grupo de destacados fil\u00e1ntropos, cient\u00edficos y tecn\u00f3logos han lanzado una iniciativa para \u201cconquistar\u201d las estrellas. Se trata de un cambio en la estrategia de exploraci\u00f3n espacial: desde las mastod\u00f3nticas naves espaciales de NASA a la microtecnolog\u00eda y la econom\u00eda de escala. Los multimillonarios Yuri Milner (Digital Sky Technologies) y Mark Zuckerberg (Facebook), junto a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"David Barrado\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"Un grupo de destacados fil\u00e1ntropos, cient\u00edficos y tecn\u00f3logos han lanzado una iniciativa para \u201cconquistar\u201d las estrellas. Se trata de un cambio en la estrategia de exploraci\u00f3n espacial: desde las mastod\u00f3nticas naves espaciales de NASA a la microtecnolog\u00eda y la econom\u00eda de escala. Los multimillonarios Yuri Milner (Digital Sky Technologies) y Mark Zuckerberg (Facebook), junto a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-04-17T10:39:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-04-17T10:46:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Un grupo de destacados fil\u00e1ntropos, cient\u00edficos y tecn\u00f3logos han lanzado una iniciativa para \u201cconquistar\u201d las estrellas. Se trata de un cambio en la estrategia de exploraci\u00f3n espacial: desde las mastod\u00f3nticas naves espaciales de NASA a la microtecnolog\u00eda y la econom\u00eda de escala. Los multimillonarios Yuri Milner (Digital Sky Technologies) y Mark Zuckerberg (Facebook), junto a\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040#blogposting\",\"name\":\"El futuro llama a la puerta: hacia la \\u00abcolonizaci\\u00f3n estelar\\u00bb - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"El futuro llama a la puerta: hacia la \\u00abcolonizaci\\u00f3n estelar\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2016-04-17T11:39:39+01:00\",\"dateModified\":\"2016-04-17T11:46:31+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040#webpage\"},\"articleSection\":\"Astrobiolog\\u00eda, Estrellas y la Galaxia, Instrumentaci\\u00f3n espacial y astron\\u00f3mica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/estrellas-y-la-galaxia#listItem\",\"name\":\"Estrellas y la Galaxia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/estrellas-y-la-galaxia#listItem\",\"position\":2,\"name\":\"Estrellas y la Galaxia\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/estrellas-y-la-galaxia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040#listItem\",\"name\":\"El futuro llama a la puerta: hacia la \\u00abcolonizaci\\u00f3n estelar\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040#listItem\",\"position\":3,\"name\":\"El futuro llama a la puerta: hacia la \\u00abcolonizaci\\u00f3n estelar\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/estrellas-y-la-galaxia#listItem\",\"name\":\"Estrellas y la Galaxia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn\",\"name\":\"David Barrado\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"David Barrado\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040\",\"name\":\"El futuro llama a la puerta: hacia la \\u00abcolonizaci\\u00f3n estelar\\u00bb - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Un grupo de destacados fil\\u00e1ntropos, cient\\u00edficos y tecn\\u00f3logos han lanzado una iniciativa para \\u201cconquistar\\u201d las estrellas. Se trata de un cambio en la estrategia de exploraci\\u00f3n espacial: desde las mastod\\u00f3nticas naves espaciales de NASA a la microtecnolog\\u00eda y la econom\\u00eda de escala. Los multimillonarios Yuri Milner (Digital Sky Technologies) y Mark Zuckerberg (Facebook), junto a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2016\\\/04\\\/17\\\/134040#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/davidbyn#author\"},\"datePublished\":\"2016-04-17T11:39:39+01:00\",\"dateModified\":\"2016-04-17T11:46:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb - Cuaderno de bit\u00e1cora estelar","description":"Un grupo de destacados fil\u00e1ntropos, cient\u00edficos y tecn\u00f3logos han lanzado una iniciativa para \u201cconquistar\u201d las estrellas. Se trata de un cambio en la estrategia de exploraci\u00f3n espacial: desde las mastod\u00f3nticas naves espaciales de NASA a la microtecnolog\u00eda y la econom\u00eda de escala. Los multimillonarios Yuri Milner (Digital Sky Technologies) y Mark Zuckerberg (Facebook), junto a","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040#blogposting","name":"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb - Cuaderno de bit\u00e1cora estelar","headline":"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#articleImage","width":217,"height":72},"datePublished":"2016-04-17T11:39:39+01:00","dateModified":"2016-04-17T11:46:31+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040#webpage"},"articleSection":"Astrobiolog\u00eda, Estrellas y la Galaxia, Instrumentaci\u00f3n espacial y astron\u00f3mica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/estrellas-y-la-galaxia#listItem","name":"Estrellas y la Galaxia"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/estrellas-y-la-galaxia#listItem","position":2,"name":"Estrellas y la Galaxia","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/estrellas-y-la-galaxia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040#listItem","name":"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040#listItem","position":3,"name":"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/estrellas-y-la-galaxia#listItem","name":"Estrellas y la Galaxia"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn","name":"David Barrado","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"David Barrado"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040","name":"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb - Cuaderno de bit\u00e1cora estelar","description":"Un grupo de destacados fil\u00e1ntropos, cient\u00edficos y tecn\u00f3logos han lanzado una iniciativa para \u201cconquistar\u201d las estrellas. Se trata de un cambio en la estrategia de exploraci\u00f3n espacial: desde las mastod\u00f3nticas naves espaciales de NASA a la microtecnolog\u00eda y la econom\u00eda de escala. Los multimillonarios Yuri Milner (Digital Sky Technologies) y Mark Zuckerberg (Facebook), junto a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/davidbyn#author"},"datePublished":"2016-04-17T11:39:39+01:00","dateModified":"2016-04-17T11:46:31+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb - Cuaderno de bit\u00e1cora estelar","og:description":"Un grupo de destacados fil\u00e1ntropos, cient\u00edficos y tecn\u00f3logos han lanzado una iniciativa para \u201cconquistar\u201d las estrellas. Se trata de un cambio en la estrategia de exploraci\u00f3n espacial: desde las mastod\u00f3nticas naves espaciales de NASA a la microtecnolog\u00eda y la econom\u00eda de escala. Los multimillonarios Yuri Milner (Digital Sky Technologies) y Mark Zuckerberg (Facebook), junto a","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2016-04-17T10:39:39+00:00","article:modified_time":"2016-04-17T10:46:31+00:00","twitter:card":"summary","twitter:title":"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb - Cuaderno de bit\u00e1cora estelar","twitter:description":"Un grupo de destacados fil\u00e1ntropos, cient\u00edficos y tecn\u00f3logos han lanzado una iniciativa para \u201cconquistar\u201d las estrellas. Se trata de un cambio en la estrategia de exploraci\u00f3n espacial: desde las mastod\u00f3nticas naves espaciales de NASA a la microtecnolog\u00eda y la econom\u00eda de escala. Los multimillonarios Yuri Milner (Digital Sky Technologies) y Mark Zuckerberg (Facebook), junto a","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"134040","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 09:58:30","updated":"2026-08-05 23:44:28","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/estrellas-y-la-galaxia\" title=\"Estrellas y la Galaxia\">Estrellas y la Galaxia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Estrellas y la Galaxia","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/estrellas-y-la-galaxia"},{"label":"El futuro llama a la puerta: hacia la \u00abcolonizaci\u00f3n estelar\u00bb","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2016\/04\/17\/134040"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/134040"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=134040"}],"version-history":[{"count":11,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/134040\/revisions"}],"predecessor-version":[{"id":134046,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/134040\/revisions\/134046"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=134040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=134040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=134040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}