{"id":39618,"date":"2006-09-04T00:41:00","date_gmt":"2006-09-04T00:41:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/astrofisica\/archive\/2006\/09\/04\/39618.aspx"},"modified":"2016-10-22T09:00:38","modified_gmt":"2016-10-22T08:00:38","slug":"mas-alla-de-la-tierra-auroras-en-el-sistema-solar","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618","title":{"rendered":"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar"},"content":{"rendered":"<div align=\"justify\">\n<p>David Barrado, Benjam\u00edn MontesinosLas auroras polares no solo se encuentran en la Tierra. Veamos unos pocos ejemplos en varios planetas del Sistema Solar.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div align=\"justify\"><img decoding=\"async\" src=\"http:\/\/www.laeff.cab.inta-csic.es\/users\/barrado\/weblog\/Aurora_Jupiter_HST.jpg\" alt=\"\" width=\"450\" \/><br \/>\n<span style=\"font-style: italic;\">Auroras en J\u00fapiter, observadas por el Hubble Space Telescope. Est\u00e1n relacionadas con la presencia del sat\u00e9lite Io, muy activo volc\u00e1nicamente.<\/span><br style=\"font-style: italic;\" \/> <br style=\"font-style: italic;\" \/><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.laeff.cab.inta-csic.es\/users\/barrado\/weblog\/Aurora_Jupiter_HST_UV.gif\" alt=\"\" width=\"450\" \/><br \/>\n<span style=\"font-style: italic;\">Un detalle de uno de los polos de J\u00fapiter, observado en el ultravioleta (cr\u00e9dito NASA\/ESA)<\/span><\/div>\n<p>El fen\u00f3meno de las auroras se puede encontrar tambi\u00e9n en los planetas gaseosos gigantes del Sistema Solar. Aunque los mecanismos de formaci\u00f3n son distintos, el fundamento f\u00edsico es muy similar. Se necesita un campo magn\u00e9tico, que en el caso de Saturno y J\u00fapiter es muy intenso, part\u00edculas cargadas, que las proporciona el viento solar y una atm\u00f3sfera contra la cual esas part\u00edculas cargadas de alta energ\u00eda puedan colisionar. En las figuras adjuntas se muestran im\u00e1genes espectaculares de estos dos planetas gaseosos, obtenidas con el Telescopio Espacial Hubble donde se ven con mucha claridad auroras espectaculares. En el caso de J\u00fapiter las auroras se producen por la interacci\u00f3n de los campos magn\u00e9ticos del planeta y de Io, uno de los sat\u00e9lites que descubri\u00f3 Galileo en el siglo XVII, en unas de las primeras observaciones astron\u00f3micas realizadas con un telescopio. Las intensidad de las corrientes electricas que se generan en esas estructuras es de miles de amperios.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.laeff.cab.inta-csic.es\/users\/barrado\/weblog\/AuroraSaturn_hst.jpg\" alt=\"\" width=\"450\" \/><br \/>\n<span style=\"font-style: italic;\">Fotocomposici\u00f3n que muestra la evoluci\u00f3n de una aurora en Saturno. Las im\u00e1genes fueron captadas por la sonda Cassini\/Huygens\u00a0 (cr\u00e9dito NASA\/ESA\/Agencia espacial italiana)<\/span><span style=\"font-style: italic;\">.<\/span><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.laeff.cab.inta-csic.es\/users\/barrado\/weblog\/Aurora_Saturn_HST.jpg\" alt=\"\" width=\"450\" \/><br \/>\n<span style=\"font-style: italic;\">Foto del HST donde se observan las auroras de Saturno en ambos polos.<\/span><\/p>\n<p>La sonda Mars Express ha observado tambi\u00e9n auroras en el planeta Marte. En este caso el fen\u00f3meno tampoco est\u00e1 producido por un intenso campo magn\u00e9tico an\u00e1logo al terrestre (Marte carece de \u00e9l), si no por campos magn\u00e9ticos locales asociados a la corteza marciana.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.laeff.cab.inta-csic.es\/users\/barrado\/weblog\/Aurora_Mars.jpg\" alt=\"\" width=\"450\" \/><br \/>\n<span style=\"font-style: italic;\">Mapa de la superficie de Marte reconstruido a partir de datos tomados con el instrumento SPICAM, uno de los que dispone la Mars Express (cr\u00e9dito ESA\/NASA\/MGS)<\/span><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.laeff.cab.inta-csic.es\/users\/barrado\/weblog\/Aurora_Jupiter_Chandra.jpg\" alt=\"\" width=\"450\" \/><br \/>\n<span style=\"font-style: italic;\">Las auroras de J\u00fapiter detectadas en rayos X por el observatorio Chandra (cr\u00e9dito NASA). La figura de la derecha muestra un diagrama con la magnestosfera del planeta.<\/span><br style=\"font-style: italic;\" \/> <br style=\"font-style: italic;\" \/><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.laeff.cab.inta-csic.es\/users\/barrado\/weblog\/Aurora_Chandra.jpg\" alt=\"\" width=\"450\" \/><br \/>\n<span style=\"font-style: italic;\">En nuestro planeta, las auroras tambien se pueden observar en rayos X, como se ve en las figuras adjuntas (cr\u00e9dito NASA\/Chandra).<\/span><br \/>\n\u00bfExistir\u00e1 este tipo de fenomenolog\u00eda en los exoplanetas?\u00bfC\u00f3mo ser\u00e1 una aurora en alguno de los ex\u00f3ticos planetas descubiertos fuera de nuestro sistema planetario?<\/p>\n<p>ENLACES:<br \/>\n<a href=\"http:\/\/www.esa.int\/SPECIALS\/Cassini-Huygens\/index.html\" target=\"blank\"> La sonda Cassini\/Huygens, ESA<\/a><br \/>\n<a href=\"http:\/\/www.esa.int\/SPECIALS\/Mars_Express\/index.html\" target=\"blank\"> La sonda Mars Express, ESA<\/a><br \/>\n<a href=\"http:\/\/www.esa.int\/SPECIALS\/Mars_Express\/SEMLQ71DU8E_0.html\" target=\"blank\"> Auroras en Marte, ESA<\/a><\/p>\n<p><a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/03\/16\/16041.aspx\" target=\"blank\">Auroras australes, auroras boreales<\/a><br \/>\n<a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/08\/31\/39212.aspx\" target=\"blank\">Auroras polares: \u00bfqu\u00e9 son?<\/a><br \/>\n<a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/09\/01\/39306.aspx\" target=\"blank\">\u00bfQu\u00e9 formas y colores tienen las auroras?<\/a><br \/>\n<a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/09\/01\/39329.aspx\" target=\"blank\">\u00bfCu\u00e1ndo y d\u00f3nde ocurren las auroras?<\/a><br \/>\n<a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/09\/04\/39618.aspx\" target=\"blank\">M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>David Barrado, Benjam\u00edn MontesinosLas auroras polares no solo se encuentran en la Tierra. Veamos unos pocos ejemplos en varios planetas del Sistema Solar.<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[64,558,557,564,565,554],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"David Barrado, Benjam\u00edn MontesinosLas auroras polares no solo se encuentran en la Tierra. Veamos unos pocos ejemplos en varios planetas del Sistema Solar. Auroras en J\u00fapiter, observadas por el Hubble Space Telescope. Est\u00e1n relacionadas con la presencia del sat\u00e9lite Io, muy activo volc\u00e1nicamente. Un detalle de uno de los polos de J\u00fapiter, observado en el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrador CBE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"David Barrado, Benjam\u00edn MontesinosLas auroras polares no solo se encuentran en la Tierra. Veamos unos pocos ejemplos en varios planetas del Sistema Solar. Auroras en J\u00fapiter, observadas por el Hubble Space Telescope. Est\u00e1n relacionadas con la presencia del sat\u00e9lite Io, muy activo volc\u00e1nicamente. Un detalle de uno de los polos de J\u00fapiter, observado en el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-09-04T00:41:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-10-22T08:00:38+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"David Barrado, Benjam\u00edn MontesinosLas auroras polares no solo se encuentran en la Tierra. Veamos unos pocos ejemplos en varios planetas del Sistema Solar. Auroras en J\u00fapiter, observadas por el Hubble Space Telescope. Est\u00e1n relacionadas con la presencia del sat\u00e9lite Io, muy activo volc\u00e1nicamente. Un detalle de uno de los polos de J\u00fapiter, observado en el\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618#blogposting\",\"name\":\"M\\u00e1s all\\u00e1 de la Tierra: Auroras en el Sistema Solar - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"M\\u00e1s all\\u00e1 de la Tierra: Auroras en el Sistema Solar\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.laeff.cab.inta-csic.es\\\/users\\\/barrado\\\/weblog\\\/Aurora_Jupiter_HST.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618\\\/#articleImage\"},\"datePublished\":\"2006-09-04T00:41:00+01:00\",\"dateModified\":\"2016-10-22T09:00:38+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":7,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618#webpage\"},\"articleSection\":\"Divulgaci\\u00f3n, El Sol y la Tierra, Instrumentaci\\u00f3n espacial y astron\\u00f3mica, La Tierra desde el espacio, Marte, el mellizo de la Tierra, Sistema Solar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"position\":2,\"name\":\"Divulgaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618#listItem\",\"name\":\"M\\u00e1s all\\u00e1 de la Tierra: Auroras en el Sistema Solar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618#listItem\",\"position\":3,\"name\":\"M\\u00e1s all\\u00e1 de la Tierra: Auroras en el Sistema Solar\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis\",\"name\":\"Administrador CBE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Administrador CBE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618\",\"name\":\"M\\u00e1s all\\u00e1 de la Tierra: Auroras en el Sistema Solar - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"David Barrado, Benjam\\u00edn MontesinosLas auroras polares no solo se encuentran en la Tierra. Veamos unos pocos ejemplos en varios planetas del Sistema Solar. Auroras en J\\u00fapiter, observadas por el Hubble Space Telescope. Est\\u00e1n relacionadas con la presencia del sat\\u00e9lite Io, muy activo volc\\u00e1nicamente. Un detalle de uno de los polos de J\\u00fapiter, observado en el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/04\\\/39618#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"datePublished\":\"2006-09-04T00:41:00+01:00\",\"dateModified\":\"2016-10-22T09:00:38+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar - Cuaderno de bit\u00e1cora estelar","description":"David Barrado, Benjam\u00edn MontesinosLas auroras polares no solo se encuentran en la Tierra. Veamos unos pocos ejemplos en varios planetas del Sistema Solar. Auroras en J\u00fapiter, observadas por el Hubble Space Telescope. Est\u00e1n relacionadas con la presencia del sat\u00e9lite Io, muy activo volc\u00e1nicamente. Un detalle de uno de los polos de J\u00fapiter, observado en el","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618#blogposting","name":"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar - Cuaderno de bit\u00e1cora estelar","headline":"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.laeff.cab.inta-csic.es\/users\/barrado\/weblog\/Aurora_Jupiter_HST.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618\/#articleImage"},"datePublished":"2006-09-04T00:41:00+01:00","dateModified":"2016-10-22T09:00:38+01:00","inLanguage":"es-ES","commentCount":7,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618#webpage"},"articleSection":"Divulgaci\u00f3n, El Sol y la Tierra, Instrumentaci\u00f3n espacial y astron\u00f3mica, La Tierra desde el espacio, Marte, el mellizo de la Tierra, Sistema Solar"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","position":2,"name":"Divulgaci\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618#listItem","name":"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618#listItem","position":3,"name":"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis","name":"Administrador CBE","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Administrador CBE"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618","name":"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar - Cuaderno de bit\u00e1cora estelar","description":"David Barrado, Benjam\u00edn MontesinosLas auroras polares no solo se encuentran en la Tierra. Veamos unos pocos ejemplos en varios planetas del Sistema Solar. Auroras en J\u00fapiter, observadas por el Hubble Space Telescope. Est\u00e1n relacionadas con la presencia del sat\u00e9lite Io, muy activo volc\u00e1nicamente. Un detalle de uno de los polos de J\u00fapiter, observado en el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"datePublished":"2006-09-04T00:41:00+01:00","dateModified":"2016-10-22T09:00:38+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar - Cuaderno de bit\u00e1cora estelar","og:description":"David Barrado, Benjam\u00edn MontesinosLas auroras polares no solo se encuentran en la Tierra. Veamos unos pocos ejemplos en varios planetas del Sistema Solar. Auroras en J\u00fapiter, observadas por el Hubble Space Telescope. Est\u00e1n relacionadas con la presencia del sat\u00e9lite Io, muy activo volc\u00e1nicamente. Un detalle de uno de los polos de J\u00fapiter, observado en el","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2006-09-04T00:41:00+00:00","article:modified_time":"2016-10-22T08:00:38+00:00","twitter:card":"summary","twitter:title":"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar - Cuaderno de bit\u00e1cora estelar","twitter:description":"David Barrado, Benjam\u00edn MontesinosLas auroras polares no solo se encuentran en la Tierra. Veamos unos pocos ejemplos en varios planetas del Sistema Solar. Auroras en J\u00fapiter, observadas por el Hubble Space Telescope. Est\u00e1n relacionadas con la presencia del sat\u00e9lite Io, muy activo volc\u00e1nicamente. Un detalle de uno de los polos de J\u00fapiter, observado en el","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"39618","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-01-28 23:21:09","updated":"2023-06-19 08:38:42","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion\" title=\"Divulgaci\u00f3n\">Divulgaci\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tM\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Divulgaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion"},{"label":"M\u00e1s all\u00e1 de la Tierra: Auroras en el Sistema Solar","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/04\/39618"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/39618"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=39618"}],"version-history":[{"count":2,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/39618\/revisions"}],"predecessor-version":[{"id":134212,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/39618\/revisions\/134212"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=39618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=39618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=39618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}