{"id":43769,"date":"2006-09-28T00:25:00","date_gmt":"2006-09-28T00:25:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/astrofisica\/archive\/2006\/09\/28\/43769.aspx"},"modified":"2006-09-28T00:25:00","modified_gmt":"2006-09-28T00:25:00","slug":"marte-oportunidad-en-el-crater-victoria","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769","title":{"rendered":"Marte: Oportunidad en el crater Victoria"},"content":{"rendered":"<p align=\"justify\">David Barrado y Navascu\u00e9s<\/p>\n<p align=\"justify\">Despu\u00e9s de 21 exitosos meses deambulando por la superficie marciana, el rover Opportunity (oportunidad) ha llegado al crater Victoria. Todo un sue\u00f1o para los ge\u00f3logos, al decir de los responsables de la misi\u00f3n<\/p>\n<p><!--more--><\/p>\n<p align=\"justify\">Opportunity y Spirit fueron dise\u00f1adas para funcionar sobre las dificiles condiciones de Marte por un peri\u00f3do de&nbsp;tres meses. Un extraordinario y cuidadoso dise\u00f1o ha permitido que sigan en activo, produciendo gran cantidad de datos cient\u00edficos e im\u00e1genes impresionates casi dos a\u00f1os m\u00e1s tarde,&nbsp; pr\u00e1cticamente el equivalente a un a\u00f1o marciano.<\/p>\n<p align=\"justify\">M\u00e1s informaci\u00f3n en la <a href=\"http:\/\/www.nasa.gov\/rovers\" target=\"blank\">p\u00e1gina de la NASA<\/a><\/p>\n<p align=\"justify\">PD: El cr\u00e1ter Victoria recibi\u00f3 este nombre en honor de la nao que, comandada por Juan Sebatian Elcano, circunnaveg\u00f3 por primera vez el planeta en 1519-1522<\/p>\n","protected":false},"excerpt":{"rendered":"<p>David Barrado y Navascu\u00e9s Despu\u00e9s de 21 exitosos meses deambulando por la superficie marciana, el rover Opportunity (oportunidad) ha llegado al crater Victoria. Todo un sue\u00f1o para los ge\u00f3logos, al decir de los responsables de la misi\u00f3n<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[64,557,565,553,554],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"David Barrado y Navascu\u00e9s Despu\u00e9s de 21 exitosos meses deambulando por la superficie marciana, el rover Opportunity (oportunidad) ha llegado al crater Victoria. Todo un sue\u00f1o para los ge\u00f3logos, al decir de los responsables de la misi\u00f3nOpportunity y Spirit fueron dise\u00f1adas para funcionar sobre las dificiles condiciones de Marte por un peri\u00f3do de tres meses. Un\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrador CBE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Marte: Oportunidad en el crater Victoria - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"David Barrado y Navascu\u00e9s Despu\u00e9s de 21 exitosos meses deambulando por la superficie marciana, el rover Opportunity (oportunidad) ha llegado al crater Victoria. Todo un sue\u00f1o para los ge\u00f3logos, al decir de los responsables de la misi\u00f3nOpportunity y Spirit fueron dise\u00f1adas para funcionar sobre las dificiles condiciones de Marte por un peri\u00f3do de tres meses. Un\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-09-28T00:25:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2006-09-28T00:25:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Marte: Oportunidad en el crater Victoria - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"David Barrado y Navascu\u00e9s Despu\u00e9s de 21 exitosos meses deambulando por la superficie marciana, el rover Opportunity (oportunidad) ha llegado al crater Victoria. Todo un sue\u00f1o para los ge\u00f3logos, al decir de los responsables de la misi\u00f3nOpportunity y Spirit fueron dise\u00f1adas para funcionar sobre las dificiles condiciones de Marte por un peri\u00f3do de tres meses. Un\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769#blogposting\",\"name\":\"Marte: Oportunidad en el crater Victoria - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"Marte: Oportunidad en el crater Victoria\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-09-28T00:25:00+01:00\",\"dateModified\":\"2006-09-28T00:25:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769#webpage\"},\"articleSection\":\"Divulgaci\\u00f3n, Instrumentaci\\u00f3n espacial y astron\\u00f3mica, Marte, el mellizo de la Tierra, Noticias de Astrof\\u00edsica, Sistema Solar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"position\":2,\"name\":\"Divulgaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769#listItem\",\"name\":\"Marte: Oportunidad en el crater Victoria\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769#listItem\",\"position\":3,\"name\":\"Marte: Oportunidad en el crater Victoria\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis\",\"name\":\"Administrador CBE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Administrador CBE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769\",\"name\":\"Marte: Oportunidad en el crater Victoria - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"David Barrado y Navascu\\u00e9s Despu\\u00e9s de 21 exitosos meses deambulando por la superficie marciana, el rover Opportunity (oportunidad) ha llegado al crater Victoria. Todo un sue\\u00f1o para los ge\\u00f3logos, al decir de los responsables de la misi\\u00f3nOpportunity y Spirit fueron dise\\u00f1adas para funcionar sobre las dificiles condiciones de Marte por un peri\\u00f3do de tres meses. Un\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/09\\\/28\\\/43769#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"datePublished\":\"2006-09-28T00:25:00+01:00\",\"dateModified\":\"2006-09-28T00:25:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Marte: Oportunidad en el crater Victoria - Cuaderno de bit\u00e1cora estelar","description":"David Barrado y Navascu\u00e9s Despu\u00e9s de 21 exitosos meses deambulando por la superficie marciana, el rover Opportunity (oportunidad) ha llegado al crater Victoria. Todo un sue\u00f1o para los ge\u00f3logos, al decir de los responsables de la misi\u00f3nOpportunity y Spirit fueron dise\u00f1adas para funcionar sobre las dificiles condiciones de Marte por un peri\u00f3do de tres meses. Un","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769#blogposting","name":"Marte: Oportunidad en el crater Victoria - Cuaderno de bit\u00e1cora estelar","headline":"Marte: Oportunidad en el crater Victoria","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#articleImage","width":217,"height":72},"datePublished":"2006-09-28T00:25:00+01:00","dateModified":"2006-09-28T00:25:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769#webpage"},"articleSection":"Divulgaci\u00f3n, Instrumentaci\u00f3n espacial y astron\u00f3mica, Marte, el mellizo de la Tierra, Noticias de Astrof\u00edsica, Sistema Solar"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","position":2,"name":"Divulgaci\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769#listItem","name":"Marte: Oportunidad en el crater Victoria"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769#listItem","position":3,"name":"Marte: Oportunidad en el crater Victoria","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis","name":"Administrador CBE","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Administrador CBE"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769","name":"Marte: Oportunidad en el crater Victoria - Cuaderno de bit\u00e1cora estelar","description":"David Barrado y Navascu\u00e9s Despu\u00e9s de 21 exitosos meses deambulando por la superficie marciana, el rover Opportunity (oportunidad) ha llegado al crater Victoria. Todo un sue\u00f1o para los ge\u00f3logos, al decir de los responsables de la misi\u00f3nOpportunity y Spirit fueron dise\u00f1adas para funcionar sobre las dificiles condiciones de Marte por un peri\u00f3do de tres meses. Un","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"datePublished":"2006-09-28T00:25:00+01:00","dateModified":"2006-09-28T00:25:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"Marte: Oportunidad en el crater Victoria - Cuaderno de bit\u00e1cora estelar","og:description":"David Barrado y Navascu\u00e9s Despu\u00e9s de 21 exitosos meses deambulando por la superficie marciana, el rover Opportunity (oportunidad) ha llegado al crater Victoria. Todo un sue\u00f1o para los ge\u00f3logos, al decir de los responsables de la misi\u00f3nOpportunity y Spirit fueron dise\u00f1adas para funcionar sobre las dificiles condiciones de Marte por un peri\u00f3do de tres meses. Un","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2006-09-28T00:25:00+00:00","article:modified_time":"2006-09-28T00:25:00+00:00","twitter:card":"summary","twitter:title":"Marte: Oportunidad en el crater Victoria - Cuaderno de bit\u00e1cora estelar","twitter:description":"David Barrado y Navascu\u00e9s Despu\u00e9s de 21 exitosos meses deambulando por la superficie marciana, el rover Opportunity (oportunidad) ha llegado al crater Victoria. Todo un sue\u00f1o para los ge\u00f3logos, al decir de los responsables de la misi\u00f3nOpportunity y Spirit fueron dise\u00f1adas para funcionar sobre las dificiles condiciones de Marte por un peri\u00f3do de tres meses. Un","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"43769","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-01-28 23:22:14","updated":"2023-06-19 08:38:42","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion\" title=\"Divulgaci\u00f3n\">Divulgaci\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMarte: Oportunidad en el crater Victoria\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Divulgaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion"},{"label":"Marte: Oportunidad en el crater Victoria","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/09\/28\/43769"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/43769"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=43769"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/43769\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=43769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=43769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=43769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}