{"id":45177,"date":"2006-10-07T02:26:00","date_gmt":"2006-10-07T02:26:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/astrofisica\/archive\/2006\/10\/07\/45177.aspx"},"modified":"2006-10-07T02:26:00","modified_gmt":"2006-10-07T02:26:00","slug":"la-astronomia-la-contaminacion-luminica-y-la-degradacion-del-planeta","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177","title":{"rendered":"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\" align=\"justify\">David Barrado y Navascu\u00e9s<\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\" align=\"justify\"><?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p>&nbsp;<\/o:p><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\" align=\"justify\">Existen unas 6,000 estrellas visibles a simple vista. O exist\u00edan\u2026 la contaminaci\u00f3n lum\u00ednica debida a las luces de ciudades ha reducido ese n\u00famero a unas pocas docenas. Por no hablar de otras fuentes contaminantes, mucho m\u00e1s perniciosas para la salud. Y para la Tierra.<\/p>\n<p><!--more--><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\" align=\"justify\">Como astr\u00f3nomo<span style=\"\">&nbsp; <\/span>profesional, es un tema verdaderamente preocupando. Desde muchos observatorios es posible apreciar la contaminaci\u00f3n causada por ciudades que se encuentran a decenas de kil\u00f3metros. Esta luz proporciona un fondo que reduce la calidad de las observaciones, pero tambi\u00e9n a\u00f1ade se\u00f1ales ficticias a los espectros, <span style=\"\">&nbsp;<\/span>l\u00edneas de emisi\u00f3n que eliminan la informaci\u00f3n original que nos llega de la estrella o galaxia. En diferentes observatorios, existen iniciativas para evitar o atenuar este problema (<a href=\"http:\/\/www.iac.es\/proyect\/otpc\/pollu.htm\" target=\"blank\">IAC, oficina t\u00e9cnica para la protecci\u00f3n de la calidad del cielo<\/a>).<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\" align=\"justify\"><o:p>&nbsp;<\/o:p><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\" align=\"justify\">Como amante de la belleza que nos regala el Universo, lamento que haya que irse a un sitio remoto para poder disfrutar de ese espect\u00e1culo (<A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/04\/24\/19813.aspx\" target=\"blank\">observatorio de La Silla<\/a>). En esta <a href=\"http:\/\/sci2.esa.int\/interactive\/media\/applets\/1_2_4.htm\" target=\"blank\">animaci\u00f3n<\/a> de la Agencia Espacial Europea se aprecia f\u00e1cilmente este efecto, en este caso sobbre la observaci\u00f3n del planeta J\u00fapiter. La mayor\u00eda de los habitantes del planeta ya no saben c\u00f3mo es el verdadero cielo nocturno.<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\" align=\"justify\"><o:p>&nbsp;<\/o:p><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\" align=\"justify\">Sin embargo, ese no es el verdadero problema. Como ser humano, me preocupa el futuro del planeta, que tambi\u00e9n es el m\u00edo.<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\" align=\"justify\"><o:p>&nbsp;<\/o:p><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\" align=\"justify\">La mayor parte de esa contaminaci\u00f3n lum\u00ednica se emite de manera totalmente in\u00fatil. Son luces de iluminaci\u00f3n de calle que se lanza directamente hacia arriba, que no cumple su funci\u00f3n y representa un gasto sin sentido. Son dispositivos el\u00e9ctricos encendidos cuando no hay un ser humano en las proximidades. Como ejemplo, suelo llegar el primero a mi centro de investigaci\u00f3n. Por doquier, las luces est\u00e1n encendidas. Han estado as\u00ed toda la noche. Cuando vamos a comer, se dejan luces encendidas tambi\u00e9n. Me dicen que es m\u00e1s eficiente dejarlas as\u00ed que apagar y conectar 40 minutos m\u00e1s tarde. Quisiera ver ese estudio. Pero tambi\u00e9n son pantallas de ordenadores conectadas, televisores funcionando cuando no hay nadie en la sala, aires acondicionados a 18 grados en verano, calefacci\u00f3n al m\u00e1ximo, utilizando como regulador una ventana abierta\u2026 son m\u00faltiples los ejemplos. Son acciones individuales que llevar\u00edan a ahorrar gran cantidad de energ\u00eda. Ayer comentaba Benjam\u00edn sobre el retroceso de los glaciares, la emisi\u00f3n de CO2 y la conveniencia de compartir transporte para ir al trabajo (algo muy com\u00fan en EEUU, al menos en California).<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\" align=\"justify\">&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/earth_lights.lr.jpg\" width=\"450\"><br \/><em>Fotocomposici\u00f3n de la Tierra, vista de noche (cr\u00e9dito NASA, Earth Observatory).<\/em><\/p>\n<p><em> <\/em><\/p>\n<p align=\"justify\"><em><br \/>&nbsp;<\/em>En definitiva, con independencia de la responsabilidad de gobiernos y grandes corporaciones, son las peque\u00f1as acciones individuales las que son de m\u00e1s f\u00e1cil implementaci\u00f3n, las que dependen directamente de nosotros como individuos. Practiqu\u00e9moslas. El planeta, y nuestra propia calidad de vida, nos lo agradecer\u00e1.<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\" align=\"justify\"><o:p>&nbsp;ENLACES:<\/o:p><\/p>\n<p><A href=\"http:\/\/weblogs.madrimasd.org\/medioambiente\" target=\"blank\">MadrI+D, Bit\u00e1cora de Medio Ambriente y Ciencia<\/a><br \/><A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/04\/25\/20001.aspx\" target=\"blank\">Las estrellas desde el Hemisferio Sur<\/a><br \/><a href=\"http:\/\/earthobservatory.nasa.gov\/Newsroom\/NewImages\/images.php3?img_id=4333\" target=\"blank\">Earth&#8217;s City Lights<\/a><br \/><a href=\"http:\/\/earthobservatory.nasa.gov\/Study\/Lights\/\" target=\"blank\">Big, bright city lights<\/a><br \/><a href=\"http:\/\/www.gpc-cl.org\/\" target=\"blank\">Grupo para la protecci\u00f3n del Cielo<\/a><br \/><a href=\"http:\/\/visibleearth.nasa.gov\/view_set.php?categoryID=573\" target=\"blank\">NASA, fotos del impacto ambiental del ser humano sobre el planeta<\/a><\/p>\n<p>PD: Gracias al GPC por el enlace.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>David Barrado y Navascu\u00e9s &nbsp; Existen unas 6,000 estrellas visibles a simple vista. O exist\u00edan\u2026 la contaminaci\u00f3n lum\u00ednica debida a las luces de ciudades ha reducido ese n\u00famero a unas pocas docenas. Por no hablar de otras fuentes contaminantes, mucho m\u00e1s perniciosas para la salud. Y para la Tierra.<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[64,558,564,552,252,60],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"David Barrado y Navascu\u00e9s Existen unas 6,000 estrellas visibles a simple vista. O exist\u00edan\u2026 la contaminaci\u00f3n lum\u00ednica debida a las luces de ciudades ha reducido ese n\u00famero a unas pocas docenas. Por no hablar de otras fuentes contaminantes, mucho m\u00e1s perniciosas para la salud. Y para la Tierra.Como astr\u00f3nomo profesional, es un tema verdaderamente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrador CBE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"David Barrado y Navascu\u00e9s Existen unas 6,000 estrellas visibles a simple vista. O exist\u00edan\u2026 la contaminaci\u00f3n lum\u00ednica debida a las luces de ciudades ha reducido ese n\u00famero a unas pocas docenas. Por no hablar de otras fuentes contaminantes, mucho m\u00e1s perniciosas para la salud. Y para la Tierra.Como astr\u00f3nomo profesional, es un tema verdaderamente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-10-07T02:26:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2006-10-07T02:26:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"David Barrado y Navascu\u00e9s Existen unas 6,000 estrellas visibles a simple vista. O exist\u00edan\u2026 la contaminaci\u00f3n lum\u00ednica debida a las luces de ciudades ha reducido ese n\u00famero a unas pocas docenas. Por no hablar de otras fuentes contaminantes, mucho m\u00e1s perniciosas para la salud. Y para la Tierra.Como astr\u00f3nomo profesional, es un tema verdaderamente\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177#blogposting\",\"name\":\"La Astronom\\u00eda, la contaminaci\\u00f3n lum\\u00ednica y la degradaci\\u00f3n del planeta - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"La Astronom\\u00eda, la contaminaci\\u00f3n lum\\u00ednica y la degradaci\\u00f3n del planeta\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/laeff.inta.es\\\/users\\\/barrado\\\/weblog\\\/earth_lights.lr.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177\\\/#articleImage\"},\"datePublished\":\"2006-10-07T02:26:00+01:00\",\"dateModified\":\"2006-10-07T02:26:00+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":17,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177#webpage\"},\"articleSection\":\"Divulgaci\\u00f3n, El Sol y la Tierra, La Tierra desde el espacio, Observando....., Opiniones, Pol\\u00edtica Cient\\u00edfica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/politica-cientifica#listItem\",\"name\":\"Pol\\u00edtica Cient\\u00edfica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/politica-cientifica#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica Cient\\u00edfica\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/politica-cientifica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177#listItem\",\"name\":\"La Astronom\\u00eda, la contaminaci\\u00f3n lum\\u00ednica y la degradaci\\u00f3n del planeta\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177#listItem\",\"position\":3,\"name\":\"La Astronom\\u00eda, la contaminaci\\u00f3n lum\\u00ednica y la degradaci\\u00f3n del planeta\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/politica-cientifica#listItem\",\"name\":\"Pol\\u00edtica Cient\\u00edfica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis\",\"name\":\"Administrador CBE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Administrador CBE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177\",\"name\":\"La Astronom\\u00eda, la contaminaci\\u00f3n lum\\u00ednica y la degradaci\\u00f3n del planeta - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"David Barrado y Navascu\\u00e9s Existen unas 6,000 estrellas visibles a simple vista. O exist\\u00edan\\u2026 la contaminaci\\u00f3n lum\\u00ednica debida a las luces de ciudades ha reducido ese n\\u00famero a unas pocas docenas. Por no hablar de otras fuentes contaminantes, mucho m\\u00e1s perniciosas para la salud. Y para la Tierra.Como astr\\u00f3nomo profesional, es un tema verdaderamente\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/10\\\/07\\\/45177#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"datePublished\":\"2006-10-07T02:26:00+01:00\",\"dateModified\":\"2006-10-07T02:26:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta - Cuaderno de bit\u00e1cora estelar","description":"David Barrado y Navascu\u00e9s Existen unas 6,000 estrellas visibles a simple vista. O exist\u00edan\u2026 la contaminaci\u00f3n lum\u00ednica debida a las luces de ciudades ha reducido ese n\u00famero a unas pocas docenas. Por no hablar de otras fuentes contaminantes, mucho m\u00e1s perniciosas para la salud. Y para la Tierra.Como astr\u00f3nomo profesional, es un tema verdaderamente","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177#blogposting","name":"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta - Cuaderno de bit\u00e1cora estelar","headline":"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/earth_lights.lr.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177\/#articleImage"},"datePublished":"2006-10-07T02:26:00+01:00","dateModified":"2006-10-07T02:26:00+01:00","inLanguage":"es-ES","commentCount":17,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177#webpage"},"articleSection":"Divulgaci\u00f3n, El Sol y la Tierra, La Tierra desde el espacio, Observando....., Opiniones, Pol\u00edtica Cient\u00edfica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/politica-cientifica#listItem","name":"Pol\u00edtica Cient\u00edfica"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/politica-cientifica#listItem","position":2,"name":"Pol\u00edtica Cient\u00edfica","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/politica-cientifica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177#listItem","name":"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177#listItem","position":3,"name":"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/politica-cientifica#listItem","name":"Pol\u00edtica Cient\u00edfica"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis","name":"Administrador CBE","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Administrador CBE"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177","name":"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta - Cuaderno de bit\u00e1cora estelar","description":"David Barrado y Navascu\u00e9s Existen unas 6,000 estrellas visibles a simple vista. O exist\u00edan\u2026 la contaminaci\u00f3n lum\u00ednica debida a las luces de ciudades ha reducido ese n\u00famero a unas pocas docenas. Por no hablar de otras fuentes contaminantes, mucho m\u00e1s perniciosas para la salud. Y para la Tierra.Como astr\u00f3nomo profesional, es un tema verdaderamente","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"datePublished":"2006-10-07T02:26:00+01:00","dateModified":"2006-10-07T02:26:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta - Cuaderno de bit\u00e1cora estelar","og:description":"David Barrado y Navascu\u00e9s Existen unas 6,000 estrellas visibles a simple vista. O exist\u00edan\u2026 la contaminaci\u00f3n lum\u00ednica debida a las luces de ciudades ha reducido ese n\u00famero a unas pocas docenas. Por no hablar de otras fuentes contaminantes, mucho m\u00e1s perniciosas para la salud. Y para la Tierra.Como astr\u00f3nomo profesional, es un tema verdaderamente","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2006-10-07T02:26:00+00:00","article:modified_time":"2006-10-07T02:26:00+00:00","twitter:card":"summary","twitter:title":"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta - Cuaderno de bit\u00e1cora estelar","twitter:description":"David Barrado y Navascu\u00e9s Existen unas 6,000 estrellas visibles a simple vista. O exist\u00edan\u2026 la contaminaci\u00f3n lum\u00ednica debida a las luces de ciudades ha reducido ese n\u00famero a unas pocas docenas. Por no hablar de otras fuentes contaminantes, mucho m\u00e1s perniciosas para la salud. Y para la Tierra.Como astr\u00f3nomo profesional, es un tema verdaderamente","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"45177","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-01-28 23:23:57","updated":"2023-06-19 08:41:14","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/politica-cientifica\" title=\"Pol\u00edtica Cient\u00edfica\">Pol\u00edtica Cient\u00edfica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Pol\u00edtica Cient\u00edfica","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/politica-cientifica"},{"label":"La Astronom\u00eda, la contaminaci\u00f3n lum\u00ednica y la degradaci\u00f3n del planeta","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/10\/07\/45177"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/45177"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=45177"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/45177\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=45177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=45177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=45177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}