{"id":52059,"date":"2006-11-22T22:12:00","date_gmt":"2006-11-22T22:12:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/astrofisica\/archive\/2006\/11\/22\/52059.aspx"},"modified":"2006-11-22T22:12:00","modified_gmt":"2006-11-22T22:12:00","slug":"desvelando-misterios-con-un-cielo-despejado","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059","title":{"rendered":"Desvelando misterios con  un cielo despejado"},"content":{"rendered":"<p align=\"justify\">David Barrado y Amelia Bayo<\/p>\n<p>Despu\u00e9s de dos noches de espera, observamos\u2026 El cielo esta despejado, sin Luna. Las estrellas verdaderamente nos sonr\u00eden, en ambos sentidos. <\/p>\n<p><!--more--><\/p>\n<div align=\"justify\">Las estrellas brillan sobre un fondo obscuro. Por una vez, parece que la fortuna est\u00e1 de nuestra parte. Y el telescopio de 3.5 metros de Calar Alto se convierte en una m\u00e1quina de generar datos, d\u00e1ndonos espectro tras espectro. El an\u00e1lisis provisional de los mismos, seg\u00fan los obtenemos nos indica que nuestras selecciones, nuestras hip\u00f3tesis, eran correctas. <\/p>\n<p>Estamos observando varias regiones de formaci\u00f3n estelar pertenecientes a la asociaci\u00f3n de Lambda Orionis, la Cabeza de Ori\u00f3n, que se encuentra dominada por la estrella gigante lambda Ori, de tipo espectral O8 III (en realidad un sistema triple), cuya masa se puede estimar en unas 30 veces la del Sol. Esta regi\u00f3n incluye el c\u00famulo abierto asociado a la estrella central, que tiene unos 5 millones de a\u00f1os, y varias nubes de polvo y gas, tales como Barnard 30, Barnard 35, LDN1588 y LND 1603, bastante m\u00e1s j\u00f3venes. Adjunto varias im\u00e1genes tomadas por el sat\u00e9lite infrarrojo IRAS, que permiten apreciar la gran complejidad del conjunto. <\/p>\n<p><img decoding=\"async\" src=\"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/LOSFR_IRAS012mu_10x10deg.gif\" width=\"450\"><br \/><em>Imagen de la Cabeza de Ori\u00f3n tomada en 12 micras con el sat\u00e9lite IRAS, que muestra fundamentalmente el polvo de la regi\u00f3n. El campo corresponde a 100 grados cuadrados <\/em><br \/><em><\/em><br \/>Durante varios a\u00f1os (desde 1999) llevo estudiando esta regi\u00f3n, mediante la adquisici\u00f3n de fotometr\u00eda \u00f3ptica e infrarroja, y tambi\u00e9n de espectroscopia en ambas regiones del espectro. El objetivo, el revelar la poblaci\u00f3n estelar y subestelar, y poder estudiar sus propiedades. Un proceso largo, que ha sido facilitado enormemente por los datos de los sat\u00e9lites XMM (rayos X) y Spitzer (infrarrojo medio y lejano) que hemos ido recibiendo durante los \u00faltimos meses. <\/p>\n<p><img decoding=\"async\" src=\"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/LOSFR_IRAS100mu_10x10deg.gif\" width=\"450\"><\/div>\n<div align=\"justify\"><em>Imagen de la Cabeza de Ori\u00f3n tomada en 100 micras con el sat\u00e9lite IRAS, que muestra fundamentalmente el polvo de la regi\u00f3n (m\u00e1s fr\u00edo que el de la imagen anterior. El campo corresponde a 100 grados cuadrados <\/em><br \/><em><\/em><br \/>El an\u00e1lisis de todos estos datos nos ha proporcionado una muestra numerosa de posibles miembros de cada una de estas asociaciones. Solo quedaba el \u00faltimo paso: la verificaci\u00f3n espectrosc\u00f3pica. Y eso es justamente lo que hemos venido a hacer a Calar Alto. <\/p>\n<p>Esta noche estamos obteniendo un n\u00famero apreciable de espectros, y la gran mayor\u00eda nos muestra intensas l\u00edneas de emisi\u00f3n correspondientes al hidr\u00f3geno en la longitud de onda 6563 angstrom, denominada Halfa. Est\u00e1 l\u00ednea espectral tiene varios posibles or\u00edgenes. Entre ellos est\u00e1 la actividad estelar, como es el caso del Sol, o por acrecimiento de materia desde un disco circunestelar hacia la estrella central, como es en el caso de nuestra muestra. Adem\u00e1s, los tipos espectrales que derivamos nos dan una idea de la masa de la estrella o enana marr\u00f3n. As\u00ed que estamos confirmando la pertenencia de nuestros objetos a la asociaci\u00f3n, nuestra selecci\u00f3n fotom\u00e9trica fue certera. <\/p>\n<p>Las estrellas y las enanas marrones pasan pro varias fases caracter\u00edsticas durante sus primeras etapas de vida. Primero una nube de polvo y gas colapse y se fragmenta, comprimi\u00e9ndose cada uno de estos hasta formar un objeto de Clase 0, que emite fuertemente en el infrarrojo m\u00e1s lejano pero cuyo n\u00facleo esta obscurecido en el \u00f3ptico por una envoltura. Posteriormente se forma un disco de acrecimiento en torno a la protoestrella (Clase I y II, dependiendo de la relaci\u00f3n de flujos en diferentes longitudes de onda. Esto es, de la contribuci\u00f3n del disco). El disco ir\u00e1 perdiendo masa por distintos procesos, entre los cuales se encuentra la formaci\u00f3n de un sistema planetario. El diagrama adjunto ilustra el proceso. Nosotros estamos interesados en los objetos de Clase II, y de esos esta noche hemos verificado la existencia de unos cuantos. <\/p>\n<p><img decoding=\"async\" src=\"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/SF_Hogerheijde1998.jpg\" width=\"450\"><br \/><em>Secuencia que muestra la evoluci\u00f3n de una estrella desde el colapso de la nube primordial hasta la formaci\u00f3n de un sistema planetario. <\/em><br \/><em><\/em><br \/><em><\/em>Adem\u00e1s, como premio a nuestra constancia, hemos recibido una agradable sorpresa. Uno de nuestros candidatos tiene un espectro peculiar, sin caracter\u00edsticas excepto por la presencia de la l\u00ednea de Halfa y de otras en emisi\u00f3n, denominadas prohibidas, y que aparecen cuando existen ejecciones o chorros de materia desde la estrella. Estas caracter\u00edsticas son t\u00edpicas de objetos de Clase I, y en nuestro caso todos los datos indica que la masa es muy, muy reducida, pudiendo ser incluso una enana marr\u00f3n. Esperemos que el an\u00e1lisis detallado de los datos, de vuelta a nuestro centro, nos permita confirmar esta posibilidad. <\/p>\n<p>En cualquier caso, tanto Amelia como yo estamos muy contentos de los resultados de esta campa\u00f1a, a pesar de las <A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/11\/21\/51742.aspx\" target=\"blank\">visicitudes<\/a> que hemos tenido que pasar. <\/p>\n<p>&#8211; <A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/11\/21\/51742.aspx\" target=\"blank\">Varado en una playa interestelar: el poder de la inform\u00e1tica<\/a><br \/>&#8211; <A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/\" target=\"blank\">P\u00e1gina principal del \u201cCuaderno de Bit\u00e1cora Estelar\u201d<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>David Barrado y Amelia Bayo Despu\u00e9s de dos noches de espera, observamos\u2026 El cielo esta despejado, sin Luna. Las estrellas verdaderamente nos sonr\u00eden, en ambos sentidos.<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[64,556,552],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"David Barrado y Amelia BayoDespu\u00e9s de dos noches de espera, observamos\u2026 El cielo esta despejado, sin Luna. Las estrellas verdaderamente nos sonr\u00eden, en ambos sentidos. Las estrellas brillan sobre un fondo obscuro. Por una vez, parece que la fortuna est\u00e1 de nuestra parte. Y el telescopio de 3.5 metros de Calar Alto se convierte en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrador CBE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Desvelando misterios con un cielo despejado - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"David Barrado y Amelia BayoDespu\u00e9s de dos noches de espera, observamos\u2026 El cielo esta despejado, sin Luna. Las estrellas verdaderamente nos sonr\u00eden, en ambos sentidos. Las estrellas brillan sobre un fondo obscuro. Por una vez, parece que la fortuna est\u00e1 de nuestra parte. Y el telescopio de 3.5 metros de Calar Alto se convierte en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-11-22T22:12:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2006-11-22T22:12:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Desvelando misterios con un cielo despejado - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"David Barrado y Amelia BayoDespu\u00e9s de dos noches de espera, observamos\u2026 El cielo esta despejado, sin Luna. Las estrellas verdaderamente nos sonr\u00eden, en ambos sentidos. Las estrellas brillan sobre un fondo obscuro. Por una vez, parece que la fortuna est\u00e1 de nuestra parte. Y el telescopio de 3.5 metros de Calar Alto se convierte en\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059#blogposting\",\"name\":\"Desvelando misterios con un cielo despejado - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"Desvelando misterios con  un cielo despejado\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/laeff.inta.es\\\/users\\\/barrado\\\/weblog\\\/LOSFR_IRAS012mu_10x10deg.gif\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059\\\/#articleImage\"},\"datePublished\":\"2006-11-22T22:12:00+01:00\",\"dateModified\":\"2006-11-22T22:12:00+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059#webpage\"},\"articleSection\":\"Divulgaci\\u00f3n, Estrellas y la Galaxia, Observando.....\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"position\":2,\"name\":\"Divulgaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059#listItem\",\"name\":\"Desvelando misterios con  un cielo despejado\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059#listItem\",\"position\":3,\"name\":\"Desvelando misterios con  un cielo despejado\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis\",\"name\":\"Administrador CBE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Administrador CBE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059\",\"name\":\"Desvelando misterios con un cielo despejado - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"David Barrado y Amelia BayoDespu\\u00e9s de dos noches de espera, observamos\\u2026 El cielo esta despejado, sin Luna. Las estrellas verdaderamente nos sonr\\u00eden, en ambos sentidos. Las estrellas brillan sobre un fondo obscuro. Por una vez, parece que la fortuna est\\u00e1 de nuestra parte. Y el telescopio de 3.5 metros de Calar Alto se convierte en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2006\\\/11\\\/22\\\/52059#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"datePublished\":\"2006-11-22T22:12:00+01:00\",\"dateModified\":\"2006-11-22T22:12:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Desvelando misterios con un cielo despejado - Cuaderno de bit\u00e1cora estelar","description":"David Barrado y Amelia BayoDespu\u00e9s de dos noches de espera, observamos\u2026 El cielo esta despejado, sin Luna. Las estrellas verdaderamente nos sonr\u00eden, en ambos sentidos. Las estrellas brillan sobre un fondo obscuro. Por una vez, parece que la fortuna est\u00e1 de nuestra parte. Y el telescopio de 3.5 metros de Calar Alto se convierte en","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059#blogposting","name":"Desvelando misterios con un cielo despejado - Cuaderno de bit\u00e1cora estelar","headline":"Desvelando misterios con  un cielo despejado","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/LOSFR_IRAS012mu_10x10deg.gif","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059\/#articleImage"},"datePublished":"2006-11-22T22:12:00+01:00","dateModified":"2006-11-22T22:12:00+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059#webpage"},"articleSection":"Divulgaci\u00f3n, Estrellas y la Galaxia, Observando....."},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","position":2,"name":"Divulgaci\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059#listItem","name":"Desvelando misterios con  un cielo despejado"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059#listItem","position":3,"name":"Desvelando misterios con  un cielo despejado","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis","name":"Administrador CBE","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Administrador CBE"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059","name":"Desvelando misterios con un cielo despejado - Cuaderno de bit\u00e1cora estelar","description":"David Barrado y Amelia BayoDespu\u00e9s de dos noches de espera, observamos\u2026 El cielo esta despejado, sin Luna. Las estrellas verdaderamente nos sonr\u00eden, en ambos sentidos. Las estrellas brillan sobre un fondo obscuro. Por una vez, parece que la fortuna est\u00e1 de nuestra parte. Y el telescopio de 3.5 metros de Calar Alto se convierte en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"datePublished":"2006-11-22T22:12:00+01:00","dateModified":"2006-11-22T22:12:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"Desvelando misterios con un cielo despejado - Cuaderno de bit\u00e1cora estelar","og:description":"David Barrado y Amelia BayoDespu\u00e9s de dos noches de espera, observamos\u2026 El cielo esta despejado, sin Luna. Las estrellas verdaderamente nos sonr\u00eden, en ambos sentidos. Las estrellas brillan sobre un fondo obscuro. Por una vez, parece que la fortuna est\u00e1 de nuestra parte. Y el telescopio de 3.5 metros de Calar Alto se convierte en","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2006-11-22T22:12:00+00:00","article:modified_time":"2006-11-22T22:12:00+00:00","twitter:card":"summary","twitter:title":"Desvelando misterios con un cielo despejado - Cuaderno de bit\u00e1cora estelar","twitter:description":"David Barrado y Amelia BayoDespu\u00e9s de dos noches de espera, observamos\u2026 El cielo esta despejado, sin Luna. Las estrellas verdaderamente nos sonr\u00eden, en ambos sentidos. Las estrellas brillan sobre un fondo obscuro. Por una vez, parece que la fortuna est\u00e1 de nuestra parte. Y el telescopio de 3.5 metros de Calar Alto se convierte en","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"52059","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-01-28 23:29:06","updated":"2023-06-19 08:42:14","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion\" title=\"Divulgaci\u00f3n\">Divulgaci\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDesvelando misterios con  un cielo despejado\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Divulgaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion"},{"label":"Desvelando misterios con  un cielo despejado","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2006\/11\/22\/52059"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/52059"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=52059"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/52059\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=52059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=52059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=52059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}