{"id":59807,"date":"2007-02-22T15:21:00","date_gmt":"2007-02-22T15:21:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/astrofisica\/archive\/2007\/02\/22\/59807.aspx"},"modified":"2014-04-25T08:52:55","modified_gmt":"2014-04-25T07:52:55","slug":"piedras-rosetta-sondas-espaciales-cometas-y-marte","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807","title":{"rendered":"Piedras Rosetta, sondas espaciales, cometas y Marte"},"content":{"rendered":"<p align=\"justify\">David Barrado y Navascu\u00e9s<\/p>\n<p>El pr\u00f3ximo d\u00eda 24, la sonda Rosetta de la Agencia Espacial Europea realizar\u00e1 una aproximaci\u00f3n a Marte, camino de su encuentro con el cometa 67P\/Churyumov-Gerasimenko<\/p>\n<p><!--more--><\/p>\n<p align=\"justify\">La <a href=\"http:\/\/es.wikipedia.org\/wiki\/Piedra_de_Rosetta\" target=\"blank\">piedra Rosetta<\/a> fue encontrada por soldados franceses durante las campa\u00f1as napole\u00f3nicas en Egipto en 1799. Fueron desastrosas desde el punto de vista militar, aunque ayudaron a catapultar a Bonaparte al consulado y, finalmente, a detentar el cetro imperial. Sin embargo, fueron un \u00e9xito cient\u00edfico, ayudaron al desarrollo de la <a href=\"http:\/\/www.egiptologia.com\/\" target=\"blank\">egiptolog\u00eda<\/a> y desataron una moda en Europa por la antiqu\u00edsima civilizaci\u00f3n del Nilo. Tal vez uno de los m\u00e1s conocidos sea el descifrado de la escritura jerogl\u00edfica, por Thomas Young Jean Fran\u00e7ois Champollion, mediante el uso de esta estela escrita en tres escrituras distintas y dos lenguas.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/laeff.cab.inta-csic.es\/users\/barrado\/weblog\/Rosetta_Stone_British.lr.jpg\" alt=\"\" \/><br \/>\n<em>La piedra Rosetta, actualmente depositada en el British Museum.<br \/>\n<\/em><\/p>\n<p align=\"justify\">Como su famoso hom\u00f3nimo y predecesor, la <a href=\"http:\/\/www.esa.int\/SPECIALS\/Rosetta\/index.html\" target=\"blank\">sonda Rosetta<\/a> de la ESA pretende descifrar un gran misterio: el del origen del Sistema Solar. Cuando llegue en el a\u00f1o 2014, despu\u00e9s de 10 a\u00f1os de viaje, orbitar\u00e1 durante dos a\u00f1os alrededor del cometa 67P\/Churyumov-Gerasimenko. Adem\u00e1s, una peque\u00f1a nave se posar\u00e1 sobre su superficie.<\/p>\n<p>Para alcanzar este objetivo, y con el objetivo principal de reducir el combustible, la sonda est\u00e1 realizando una compleja maniobra que le conducir\u00e1 en tres ocasiones a las proximidades de nuestro planeta, as\u00ed como a Marte. Justamente este hecho se producir\u00e1 el domingo 25 de febrero. La distancia m\u00ednima ser\u00e1 de solo 250\u00a0<a href=\"http:\/\/www.esa.int\/SPECIALS\/Rosetta\/SEM5WDBE8YE_0.html\" target=\"blank\">kil\u00f3metros sobre la superficie marciana<\/a>. Esta es una cr\u00edtica maniobra, que permitir\u00e1 a la nave incrementar su velocidad de manera considerable, en una honda planetaria. Le deseamos todo el \u00e9xito a los controladores de la ESA en los diversos centros de al organizaci\u00f3n.<\/p>\n<p><strong>ENLACES: <\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/www.esa.int\/SPECIALS\/Rosetta\/index.html\" target=\"blank\">ESA. La sonda Rosetta<\/a><\/li>\n<li><a href=\"http:\/\/www.esa.int\/SPECIALS\/Rosetta\/SEM5WDBE8YE_0.html\" target=\"blank\">ESA. Aproximaci\u00f3n a Marte<\/a><\/li>\n<li><a href=\"http:\/\/es.wikipedia.org\/wiki\/Piedra_de_Rosetta\" target=\"blank\">Wikipedia. Piedra Rosetta<\/a><\/li>\n<li><a href=\"http:\/\/www.egiptologia.com\/\" target=\"blank\">Amigos de la egiptolog\u00eda<\/a><\/li>\n<li><a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2007\/01\/23\/57908.aspx\" target=\"blank\">CBE. Fotos del Cometa McNaught, \u201cEl Grande\u201d <\/a><\/li>\n<li><a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/12\/09\/54536.aspx\" target=\"blank\">CBE. Marte: \u00bfplaneta agua? <\/a><\/li>\n<\/ul>\n<hr size=\"1\" \/>\n<p><a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/\" target=\"blank\"><strong>P\u00e1gina principal del \u201cCuaderno de Bit\u00e1cora Estelar\u201d <\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>David Barrado y Navascu\u00e9s El pr\u00f3ximo d\u00eda 24, la sonda Rosetta de la Agencia Espacial Europea realizar\u00e1 una aproximaci\u00f3n a Marte, camino de su encuentro con el cometa 67P\/Churyumov-Gerasimenko<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[64,557,565,563,553,554],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"David Barrado y Navascu\u00e9s El pr\u00f3ximo d\u00eda 24, la sonda Rosetta de la Agencia Espacial Europea realizar\u00e1 una aproximaci\u00f3n a Marte, camino de su encuentro con el cometa 67P\/Churyumov-Gerasimenko La piedra Rosetta fue encontrada por soldados franceses durante las campa\u00f1as napole\u00f3nicas en Egipto en 1799. Fueron desastrosas desde el punto de vista militar, aunque ayudaron\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrador CBE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Piedras Rosetta, sondas espaciales, cometas y Marte - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"David Barrado y Navascu\u00e9s El pr\u00f3ximo d\u00eda 24, la sonda Rosetta de la Agencia Espacial Europea realizar\u00e1 una aproximaci\u00f3n a Marte, camino de su encuentro con el cometa 67P\/Churyumov-Gerasimenko La piedra Rosetta fue encontrada por soldados franceses durante las campa\u00f1as napole\u00f3nicas en Egipto en 1799. Fueron desastrosas desde el punto de vista militar, aunque ayudaron\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2007-02-22T15:21:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-04-25T07:52:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Piedras Rosetta, sondas espaciales, cometas y Marte - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"David Barrado y Navascu\u00e9s El pr\u00f3ximo d\u00eda 24, la sonda Rosetta de la Agencia Espacial Europea realizar\u00e1 una aproximaci\u00f3n a Marte, camino de su encuentro con el cometa 67P\/Churyumov-Gerasimenko La piedra Rosetta fue encontrada por soldados franceses durante las campa\u00f1as napole\u00f3nicas en Egipto en 1799. Fueron desastrosas desde el punto de vista militar, aunque ayudaron\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807#blogposting\",\"name\":\"Piedras Rosetta, sondas espaciales, cometas y Marte - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"Piedras Rosetta, sondas espaciales, cometas y Marte\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/laeff.cab.inta-csic.es\\\/users\\\/barrado\\\/weblog\\\/Rosetta_Stone_British.lr.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807\\\/#articleImage\"},\"datePublished\":\"2007-02-22T15:21:00+01:00\",\"dateModified\":\"2014-04-25T08:52:55+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":5,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807#webpage\"},\"articleSection\":\"Divulgaci\\u00f3n, Instrumentaci\\u00f3n espacial y astron\\u00f3mica, Marte, el mellizo de la Tierra, Mitolog\\u00eda e Historia, Noticias de Astrof\\u00edsica, Sistema Solar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"position\":2,\"name\":\"Divulgaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807#listItem\",\"name\":\"Piedras Rosetta, sondas espaciales, cometas y Marte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807#listItem\",\"position\":3,\"name\":\"Piedras Rosetta, sondas espaciales, cometas y Marte\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis\",\"name\":\"Administrador CBE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Administrador CBE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807\",\"name\":\"Piedras Rosetta, sondas espaciales, cometas y Marte - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"David Barrado y Navascu\\u00e9s El pr\\u00f3ximo d\\u00eda 24, la sonda Rosetta de la Agencia Espacial Europea realizar\\u00e1 una aproximaci\\u00f3n a Marte, camino de su encuentro con el cometa 67P\\\/Churyumov-Gerasimenko La piedra Rosetta fue encontrada por soldados franceses durante las campa\\u00f1as napole\\u00f3nicas en Egipto en 1799. Fueron desastrosas desde el punto de vista militar, aunque ayudaron\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/02\\\/22\\\/59807#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"datePublished\":\"2007-02-22T15:21:00+01:00\",\"dateModified\":\"2014-04-25T08:52:55+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Piedras Rosetta, sondas espaciales, cometas y Marte - Cuaderno de bit\u00e1cora estelar","description":"David Barrado y Navascu\u00e9s El pr\u00f3ximo d\u00eda 24, la sonda Rosetta de la Agencia Espacial Europea realizar\u00e1 una aproximaci\u00f3n a Marte, camino de su encuentro con el cometa 67P\/Churyumov-Gerasimenko La piedra Rosetta fue encontrada por soldados franceses durante las campa\u00f1as napole\u00f3nicas en Egipto en 1799. Fueron desastrosas desde el punto de vista militar, aunque ayudaron","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807#blogposting","name":"Piedras Rosetta, sondas espaciales, cometas y Marte - Cuaderno de bit\u00e1cora estelar","headline":"Piedras Rosetta, sondas espaciales, cometas y Marte","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/laeff.cab.inta-csic.es\/users\/barrado\/weblog\/Rosetta_Stone_British.lr.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807\/#articleImage"},"datePublished":"2007-02-22T15:21:00+01:00","dateModified":"2014-04-25T08:52:55+01:00","inLanguage":"es-ES","commentCount":5,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807#webpage"},"articleSection":"Divulgaci\u00f3n, Instrumentaci\u00f3n espacial y astron\u00f3mica, Marte, el mellizo de la Tierra, Mitolog\u00eda e Historia, Noticias de Astrof\u00edsica, Sistema Solar"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","position":2,"name":"Divulgaci\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807#listItem","name":"Piedras Rosetta, sondas espaciales, cometas y Marte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807#listItem","position":3,"name":"Piedras Rosetta, sondas espaciales, cometas y Marte","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis","name":"Administrador CBE","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Administrador CBE"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807","name":"Piedras Rosetta, sondas espaciales, cometas y Marte - Cuaderno de bit\u00e1cora estelar","description":"David Barrado y Navascu\u00e9s El pr\u00f3ximo d\u00eda 24, la sonda Rosetta de la Agencia Espacial Europea realizar\u00e1 una aproximaci\u00f3n a Marte, camino de su encuentro con el cometa 67P\/Churyumov-Gerasimenko La piedra Rosetta fue encontrada por soldados franceses durante las campa\u00f1as napole\u00f3nicas en Egipto en 1799. Fueron desastrosas desde el punto de vista militar, aunque ayudaron","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"datePublished":"2007-02-22T15:21:00+01:00","dateModified":"2014-04-25T08:52:55+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"Piedras Rosetta, sondas espaciales, cometas y Marte - Cuaderno de bit\u00e1cora estelar","og:description":"David Barrado y Navascu\u00e9s El pr\u00f3ximo d\u00eda 24, la sonda Rosetta de la Agencia Espacial Europea realizar\u00e1 una aproximaci\u00f3n a Marte, camino de su encuentro con el cometa 67P\/Churyumov-Gerasimenko La piedra Rosetta fue encontrada por soldados franceses durante las campa\u00f1as napole\u00f3nicas en Egipto en 1799. Fueron desastrosas desde el punto de vista militar, aunque ayudaron","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2007-02-22T15:21:00+00:00","article:modified_time":"2014-04-25T07:52:55+00:00","twitter:card":"summary","twitter:title":"Piedras Rosetta, sondas espaciales, cometas y Marte - Cuaderno de bit\u00e1cora estelar","twitter:description":"David Barrado y Navascu\u00e9s El pr\u00f3ximo d\u00eda 24, la sonda Rosetta de la Agencia Espacial Europea realizar\u00e1 una aproximaci\u00f3n a Marte, camino de su encuentro con el cometa 67P\/Churyumov-Gerasimenko La piedra Rosetta fue encontrada por soldados franceses durante las campa\u00f1as napole\u00f3nicas en Egipto en 1799. Fueron desastrosas desde el punto de vista militar, aunque ayudaron","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"59807","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-01-28 23:36:38","updated":"2023-06-19 08:46:10","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion\" title=\"Divulgaci\u00f3n\">Divulgaci\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPiedras Rosetta, sondas espaciales, cometas y Marte\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Divulgaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion"},{"label":"Piedras Rosetta, sondas espaciales, cometas y Marte","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/02\/22\/59807"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/59807"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=59807"}],"version-history":[{"count":1,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/59807\/revisions"}],"predecessor-version":[{"id":133067,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/59807\/revisions\/133067"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=59807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=59807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=59807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}