{"id":65467,"date":"2007-05-13T05:12:00","date_gmt":"2007-05-13T05:12:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/astrofisica\/archive\/2007\/05\/13\/65467.aspx"},"modified":"2007-05-13T05:12:00","modified_gmt":"2007-05-13T05:12:00","slug":"la-mision-%e2%80%9cnew-horizons%e2%80%9d-y-los-volcanes-de-io","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467","title":{"rendered":"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io"},"content":{"rendered":"<div align=\"justify\">David Barrado y Navascu\u00e9s <\/p>\n<p>   En otra <A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2007\/04\/05\/62945.aspx\" target=\"blank\">ocasi\u00f3n ya hemos hablado <\/a> sobre la misi\u00f3n de NASA a Plut\u00f3n denominanda <a href=\"http:\/\/pluto.jhuapl.edu\/gallery\/missionPhotos\/pages\/050107\/050107_08.html\" target=\"blank\"> \u201cNew Horizons\u201d <\/a>. Durante su paso por el sistema de J\u00fapiter, que tiene como objeto proporcionar suficiente energ\u00eda como para dar el salto hacia aquel planeta enano, la nave est\u00e1 proporcionando unas impresionantes im\u00e1genes. <\/div>\n<p><!--more--><\/p>\n<div align=\"justify\">\u201cNew Horizons\u201d todav\u00eda est\u00e1 retransmitiendo los datos tomados durante su acercamiento a J\u00fapiter y a sus sat\u00e9lites. Algunas de las <a href=\"http:\/\/pluto.jhuapl.edu\/gallery\/missionPhotos.html\" target=\"blank\">im\u00e1genes<\/a> son, verdaderamente espectaculares. Como las que ha tomado de la luna joviana \u00cdo, que muestra su alt\u00edsima actividad volc\u00e1nica. <\/div>\n<p>  <img decoding=\"async\" src=\"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/Jupiter_Io_vulcano_NewHorizons.lr.jpg\" width=\"450\"><br \/><i>Imagen de \u00cdo tomada por la nave \u201cNew Horizons\u201d, donde se ven claramente regiones con lava a alta temperatura y otros efectos de sus actividad volc\u00e1nica (cr\u00e9dito NASA)  <\/i><\/p>\n<p><b> ENLACES:<\/b>  <\/p>\n<ul>\n<li> <a href=\"http:\/\/pluto.jhuapl.edu\/gallery\/missionPhotos\/pages\/050107\/050107_08.html\" target=\"blank\">  NASA. New Horizons<\/a> <\/li>\n<li> <a href=\"http:\/\/ciencia.nasa.gov\/headlines\/y2007\/01may_fantasticflyby.htm?list941828\" target=\"blank\">  NASA. El vuelo de New Horizons por el sistema joviano (en castellano) <\/a> <\/li>\n<li> <a href=\"http:\/\/pluto.jhuapl.edu\/gallery\/missionPhotos.html\" target=\"blank\">  NASA. New Horizons. Galer\u00eda de im\u00e1genes<\/a> <\/li>\n<li> <a href=\"http:\/\/pluto.jhuapl.edu\/news_center\/news\/050107_pressGraphics.htm\" target=\"blank\">  NASA. New Horizons, material adicional<\/a> <\/li>\n<li> <A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2007\/04\/05\/62945.aspx\" target=\"blank\">  CBE. Noches de doble luna: un nuevo horizonte para las lunas jovianas \u00cdo y Europa<\/a>        <\/li>\n<\/ul>\n<hr size=\"1\"> <A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/\" target=\"blank\">  <strong> P\u00e1gina principal del \u201cCuaderno de Bit\u00e1cora Estelar\u201d <\/strong><\/a>        <\/p>\n","protected":false},"excerpt":{"rendered":"<p>David Barrado y Navascu\u00e9s En otra ocasi\u00f3n ya hemos hablado sobre la misi\u00f3n de NASA a Plut\u00f3n denominanda \u201cNew Horizons\u201d . Durante su paso por el sistema de J\u00fapiter, que tiene como objeto proporcionar suficiente energ\u00eda como para dar el salto hacia aquel planeta enano, la nave est\u00e1 proporcionando unas impresionantes im\u00e1genes.<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[64,557,554],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"David Barrado y Navascu\u00e9s En otra ocasi\u00f3n ya hemos hablado sobre la misi\u00f3n de NASA a Plut\u00f3n denominanda \u201cNew Horizons\u201d . Durante su paso por el sistema de J\u00fapiter, que tiene como objeto proporcionar suficiente energ\u00eda como para dar el salto hacia aquel planeta enano, la nave est\u00e1 proporcionando unas impresionantes im\u00e1genes. \u201cNew Horizons\u201d todav\u00eda\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrador CBE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"David Barrado y Navascu\u00e9s En otra ocasi\u00f3n ya hemos hablado sobre la misi\u00f3n de NASA a Plut\u00f3n denominanda \u201cNew Horizons\u201d . Durante su paso por el sistema de J\u00fapiter, que tiene como objeto proporcionar suficiente energ\u00eda como para dar el salto hacia aquel planeta enano, la nave est\u00e1 proporcionando unas impresionantes im\u00e1genes. \u201cNew Horizons\u201d todav\u00eda\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2007-05-13T05:12:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2007-05-13T05:12:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"David Barrado y Navascu\u00e9s En otra ocasi\u00f3n ya hemos hablado sobre la misi\u00f3n de NASA a Plut\u00f3n denominanda \u201cNew Horizons\u201d . Durante su paso por el sistema de J\u00fapiter, que tiene como objeto proporcionar suficiente energ\u00eda como para dar el salto hacia aquel planeta enano, la nave est\u00e1 proporcionando unas impresionantes im\u00e1genes. \u201cNew Horizons\u201d todav\u00eda\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467#blogposting\",\"name\":\"La Misi\\u00f3n \\u201cNew Horizons\\u201d y los volcanes de Io - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"La Misi\\u00f3n \\u201cNew Horizons\\u201d y los volcanes de Io\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/laeff.inta.es\\\/users\\\/barrado\\\/weblog\\\/Jupiter_Io_vulcano_NewHorizons.lr.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467\\\/#articleImage\"},\"datePublished\":\"2007-05-13T05:12:00+01:00\",\"dateModified\":\"2007-05-13T05:12:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467#webpage\"},\"articleSection\":\"Divulgaci\\u00f3n, Instrumentaci\\u00f3n espacial y astron\\u00f3mica, Sistema Solar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"position\":2,\"name\":\"Divulgaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467#listItem\",\"name\":\"La Misi\\u00f3n \\u201cNew Horizons\\u201d y los volcanes de Io\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467#listItem\",\"position\":3,\"name\":\"La Misi\\u00f3n \\u201cNew Horizons\\u201d y los volcanes de Io\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis\",\"name\":\"Administrador CBE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Administrador CBE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467\",\"name\":\"La Misi\\u00f3n \\u201cNew Horizons\\u201d y los volcanes de Io - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"David Barrado y Navascu\\u00e9s En otra ocasi\\u00f3n ya hemos hablado sobre la misi\\u00f3n de NASA a Plut\\u00f3n denominanda \\u201cNew Horizons\\u201d . Durante su paso por el sistema de J\\u00fapiter, que tiene como objeto proporcionar suficiente energ\\u00eda como para dar el salto hacia aquel planeta enano, la nave est\\u00e1 proporcionando unas impresionantes im\\u00e1genes. \\u201cNew Horizons\\u201d todav\\u00eda\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/05\\\/13\\\/65467#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"datePublished\":\"2007-05-13T05:12:00+01:00\",\"dateModified\":\"2007-05-13T05:12:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io - Cuaderno de bit\u00e1cora estelar","description":"David Barrado y Navascu\u00e9s En otra ocasi\u00f3n ya hemos hablado sobre la misi\u00f3n de NASA a Plut\u00f3n denominanda \u201cNew Horizons\u201d . Durante su paso por el sistema de J\u00fapiter, que tiene como objeto proporcionar suficiente energ\u00eda como para dar el salto hacia aquel planeta enano, la nave est\u00e1 proporcionando unas impresionantes im\u00e1genes. \u201cNew Horizons\u201d todav\u00eda","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467#blogposting","name":"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io - Cuaderno de bit\u00e1cora estelar","headline":"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/Jupiter_Io_vulcano_NewHorizons.lr.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467\/#articleImage"},"datePublished":"2007-05-13T05:12:00+01:00","dateModified":"2007-05-13T05:12:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467#webpage"},"articleSection":"Divulgaci\u00f3n, Instrumentaci\u00f3n espacial y astron\u00f3mica, Sistema Solar"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","position":2,"name":"Divulgaci\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467#listItem","name":"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467#listItem","position":3,"name":"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis","name":"Administrador CBE","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Administrador CBE"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467","name":"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io - Cuaderno de bit\u00e1cora estelar","description":"David Barrado y Navascu\u00e9s En otra ocasi\u00f3n ya hemos hablado sobre la misi\u00f3n de NASA a Plut\u00f3n denominanda \u201cNew Horizons\u201d . Durante su paso por el sistema de J\u00fapiter, que tiene como objeto proporcionar suficiente energ\u00eda como para dar el salto hacia aquel planeta enano, la nave est\u00e1 proporcionando unas impresionantes im\u00e1genes. \u201cNew Horizons\u201d todav\u00eda","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"datePublished":"2007-05-13T05:12:00+01:00","dateModified":"2007-05-13T05:12:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io - Cuaderno de bit\u00e1cora estelar","og:description":"David Barrado y Navascu\u00e9s En otra ocasi\u00f3n ya hemos hablado sobre la misi\u00f3n de NASA a Plut\u00f3n denominanda \u201cNew Horizons\u201d . Durante su paso por el sistema de J\u00fapiter, que tiene como objeto proporcionar suficiente energ\u00eda como para dar el salto hacia aquel planeta enano, la nave est\u00e1 proporcionando unas impresionantes im\u00e1genes. \u201cNew Horizons\u201d todav\u00eda","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2007-05-13T05:12:00+00:00","article:modified_time":"2007-05-13T05:12:00+00:00","twitter:card":"summary","twitter:title":"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io - Cuaderno de bit\u00e1cora estelar","twitter:description":"David Barrado y Navascu\u00e9s En otra ocasi\u00f3n ya hemos hablado sobre la misi\u00f3n de NASA a Plut\u00f3n denominanda \u201cNew Horizons\u201d . Durante su paso por el sistema de J\u00fapiter, que tiene como objeto proporcionar suficiente energ\u00eda como para dar el salto hacia aquel planeta enano, la nave est\u00e1 proporcionando unas impresionantes im\u00e1genes. \u201cNew Horizons\u201d todav\u00eda","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"65467","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-01-28 23:40:23","updated":"2023-06-19 08:46:10","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion\" title=\"Divulgaci\u00f3n\">Divulgaci\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Divulgaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion"},{"label":"La Misi\u00f3n \u201cNew Horizons\u201d y los volcanes de Io","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/05\/13\/65467"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/65467"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=65467"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/65467\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=65467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=65467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=65467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}