{"id":68948,"date":"2007-06-29T01:40:00","date_gmt":"2007-06-29T01:40:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/astrofisica\/archive\/2007\/06\/29\/68948.aspx"},"modified":"2017-02-26T20:10:14","modified_gmt":"2017-02-26T19:10:14","slug":"%c2%bfse-puede-detectar-agua-en-los-exoplanetas","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948","title":{"rendered":"\u00bfSe puede detectar agua en los exoplanetas?"},"content":{"rendered":"<p class=\"MsoNormal\" align=\"justify\">David ByN<\/p>\n<p class=\"MsoNormal\" align=\"justify\">Una de las principales discusiones que se est\u00e1 manteniendo en la conferencia sobre <a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2007\/05\/15\/65600.aspx\">sistemas planetarios extremos <\/a>es si se puede detectar agua en los exoplanetas.<\/p>\n<p><!--more--><\/p>\n<p class=\"MsoNormal\" align=\"justify\">La t\u00e9cnica es verdaderamente sofisticada. Se trata de obtener espectros en el rango infrarrojo en sistemas que presentan eclipses. Esto es, el exoplaneta cruza en alg\u00fan momento por delante de la estrella central (eclipse principal) y por detr\u00e1s de la misma (eclipse secundario).<\/p>\n<p class=\"MsoNormal\" align=\"justify\">Durante el eclipse principal, la luz que nos llega del sistema decrece de manera apreciable (pocos tantos por cien), debido a que parte de la superficie de la estrella, responsable de la mayor parte de la emisi\u00f3n, es ocultada por el disco del planeta. De hecho, el proceso es an\u00e1logo a los <a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/11\/10\/50422.aspx\">tr\u00e1nsitos de Venus y Mercurio sobre el disco solar<\/a>, de los que hemos tenido unos cuantos ejemplos durante los recientes a\u00f1os.<\/p>\n<p class=\"MsoNormal\" align=\"justify\">El efecto del eclipse secundario es mucho m\u00e1s sutil. La contribuci\u00f3n del planeta a la luminosidad total aparece preferentemente en longitudes de onda m\u00e1s largas (en colores m\u00e1s rojos), esencialmente en lo que denominamos infrarrojo medio. As\u00ed que la estrella bloquea esta min\u00fascula aportaci\u00f3n por parte del planeta.<\/p>\n<p class=\"MsoNormal\" align=\"justify\">El truco consiste en obtener m\u00faltiples espectros cuando no hay eclipse y cuando el planeta pasa por detr\u00e1s del disco estelar, y substraer ambos grupos, lo cual nos deja con la contribuci\u00f3n planetaria, el espectro diferencial.<\/p>\n<p class=\"MsoNormal\" align=\"justify\">Hasta aqu\u00ed es relativamente sencillo. Solo se necesita el <a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2007\/05\/18\/65817.aspx\">telescopio espacial Spitzer<\/a> y muchas horas de observaci\u00f3n. La interpretaci\u00f3n de lo que se observa es mucho m\u00e1s compleja, porque la se\u00f1al del planeta es tan reducida que es muy dif\u00edcil extraer la ciencia que est\u00e1 detr\u00e1s. Es necesario comparar este espectro diferencial observado con complicados modelos atmosf\u00e9ricos para exoplanetas, y la interpretaci\u00f3n no est\u00e1 libre de ambig\u00fcedades. Mantener cierto<a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/07\/21\/35329.aspx\"> escepticismo<\/a>, de todas maneras, es bastante sano.<\/p>\n<p class=\"MsoNormal\" align=\"justify\">Hay varias caracter\u00edsticas espectrales que se insin\u00faan en el espectro diferencial. Una de ellas podr\u00eda corresponder a agua (en realidad a vapor de agua, dado que estos planetas est\u00e1n muy cerca de sus estrellas centrales y sus temperaturas son extraordinariamente altas). Y no, <a href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2007\/05\/23\/66191.aspx\">no hay agua l\u00edquida y presumiblemente no hay vida<\/a>. Pero diferentes grupos de especialistas no se ponen de acuerdo si realmente es agua o no.<\/p>\n<p class=\"MsoNormal\" align=\"justify\">La soluci\u00f3n, como siempre en casos como \u00e9ste, son nuevas observaciones. Spitzer se prepara para nuevas campa\u00f1as de observaci\u00f3n y es posible que dentro de unos meses tengamos una respuesta definitiva.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/laeff.cab.inta-csic.es\/users\/barrado\/weblog\/HD189733_Water_Spitzer.lr.jpg\" alt=\"\" width=\"450\" \/><br \/>\n<em>El espectro del exoplaneta HD189733. En realidad se tienen medidas tomadas en tres bandas (3.6, 5.8 y 8.0 micras). La comparaci\u00f3n con un espectro te\u00f3rico (l\u00ednea azul) sugiere la presencia de una banda de absorpci\u00f3n debida a vapor de agua. Fuente\u00a0<span class=\"credit\"> ESA, NASA\/ JPL-Caltech\/G. Tinetti (Institute d&#8217;Astrophysique de Paris, University College London)<\/span><\/em><em>.<\/em><\/p>\n<p class=\"MsoNormal\" align=\"justify\">PD (2007 \/ VII \/ 12):<br \/>\nNota de prensa \u00ab<a href=\"http:\/\/www.spitzer.caltech.edu\/Media\/releases\/ssc2007-12\/release.shtml\">NASA&#8217;S SPITZER FINDS WATER VAPOR ON HOT, ALIEN PLANET<\/a>\u00bb<br \/>\nEl Pa\u00eds: <a href=\"http:\/\/www.elpais.com\/articulo\/sociedad\/cientificos\/encuentran\/agua\/planeta\/extrasolar\/elpepusoc\/20070711elpepusoc_9\/Tes\">Los cient\u00edficos\u00a0 encuentran agua en un planeta extrasolar<\/a><br \/>\nNature:\u00a0 \u00ab<a href=\"http:\/\/www.nature.com\/nature\/journal\/v448\/n7150\/abs\/nature06002.html\">Water vapour in the atmosphere of a transiting extrasolar planet\u00bb<\/a><br \/>\nEl Mundo: <a href=\"http:\/\/www.elmundo.es\/elmundo\/2007\/07\/11\/ciencia\/1184169281.html?a=7d12d62a7c129d242aa980c046c297e9&amp;t=1184231666\">Descubren un planeta con agua fuera del Sistema Solar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>David ByN Una de las principales discusiones que se est\u00e1 manteniendo en la conferencia sobre sistemas planetarios extremos es si se puede detectar agua en los exoplanetas.<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[566,64,557,553,559],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"David ByN Una de las principales discusiones que se est\u00e1 manteniendo en la conferencia sobre sistemas planetarios extremos es si se puede detectar agua en los exoplanetas. La t\u00e9cnica es verdaderamente sofisticada. Se trata de obtener espectros en el rango infrarrojo en sistemas que presentan eclipses. Esto es, el exoplaneta cruza en alg\u00fan momento por\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrador CBE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfSe puede detectar agua en los exoplanetas? - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"David ByN Una de las principales discusiones que se est\u00e1 manteniendo en la conferencia sobre sistemas planetarios extremos es si se puede detectar agua en los exoplanetas. La t\u00e9cnica es verdaderamente sofisticada. Se trata de obtener espectros en el rango infrarrojo en sistemas que presentan eclipses. Esto es, el exoplaneta cruza en alg\u00fan momento por\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2007-06-29T01:40:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-02-26T19:10:14+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfSe puede detectar agua en los exoplanetas? - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"David ByN Una de las principales discusiones que se est\u00e1 manteniendo en la conferencia sobre sistemas planetarios extremos es si se puede detectar agua en los exoplanetas. La t\u00e9cnica es verdaderamente sofisticada. Se trata de obtener espectros en el rango infrarrojo en sistemas que presentan eclipses. Esto es, el exoplaneta cruza en alg\u00fan momento por\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948#blogposting\",\"name\":\"\\u00bfSe puede detectar agua en los exoplanetas? - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"\\u00bfSe puede detectar agua en los exoplanetas?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/laeff.cab.inta-csic.es\\\/users\\\/barrado\\\/weblog\\\/HD189733_Water_Spitzer.lr.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948\\\/#articleImage\"},\"datePublished\":\"2007-06-29T01:40:00+01:00\",\"dateModified\":\"2017-02-26T20:10:14+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948#webpage\"},\"articleSection\":\"Astrobiolog\\u00eda, Divulgaci\\u00f3n, Instrumentaci\\u00f3n espacial y astron\\u00f3mica, Noticias de Astrof\\u00edsica, Sistemas planetarios\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"position\":2,\"name\":\"Divulgaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948#listItem\",\"name\":\"\\u00bfSe puede detectar agua en los exoplanetas?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948#listItem\",\"position\":3,\"name\":\"\\u00bfSe puede detectar agua en los exoplanetas?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis\",\"name\":\"Administrador CBE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Administrador CBE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948\",\"name\":\"\\u00bfSe puede detectar agua en los exoplanetas? - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"David ByN Una de las principales discusiones que se est\\u00e1 manteniendo en la conferencia sobre sistemas planetarios extremos es si se puede detectar agua en los exoplanetas. La t\\u00e9cnica es verdaderamente sofisticada. Se trata de obtener espectros en el rango infrarrojo en sistemas que presentan eclipses. Esto es, el exoplaneta cruza en alg\\u00fan momento por\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2007\\\/06\\\/29\\\/68948#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"datePublished\":\"2007-06-29T01:40:00+01:00\",\"dateModified\":\"2017-02-26T20:10:14+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfSe puede detectar agua en los exoplanetas? - Cuaderno de bit\u00e1cora estelar","description":"David ByN Una de las principales discusiones que se est\u00e1 manteniendo en la conferencia sobre sistemas planetarios extremos es si se puede detectar agua en los exoplanetas. La t\u00e9cnica es verdaderamente sofisticada. Se trata de obtener espectros en el rango infrarrojo en sistemas que presentan eclipses. Esto es, el exoplaneta cruza en alg\u00fan momento por","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948#blogposting","name":"\u00bfSe puede detectar agua en los exoplanetas? - Cuaderno de bit\u00e1cora estelar","headline":"\u00bfSe puede detectar agua en los exoplanetas?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/laeff.cab.inta-csic.es\/users\/barrado\/weblog\/HD189733_Water_Spitzer.lr.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948\/#articleImage"},"datePublished":"2007-06-29T01:40:00+01:00","dateModified":"2017-02-26T20:10:14+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948#webpage"},"articleSection":"Astrobiolog\u00eda, Divulgaci\u00f3n, Instrumentaci\u00f3n espacial y astron\u00f3mica, Noticias de Astrof\u00edsica, Sistemas planetarios"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","position":2,"name":"Divulgaci\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948#listItem","name":"\u00bfSe puede detectar agua en los exoplanetas?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948#listItem","position":3,"name":"\u00bfSe puede detectar agua en los exoplanetas?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis","name":"Administrador CBE","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Administrador CBE"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948","name":"\u00bfSe puede detectar agua en los exoplanetas? - Cuaderno de bit\u00e1cora estelar","description":"David ByN Una de las principales discusiones que se est\u00e1 manteniendo en la conferencia sobre sistemas planetarios extremos es si se puede detectar agua en los exoplanetas. La t\u00e9cnica es verdaderamente sofisticada. Se trata de obtener espectros en el rango infrarrojo en sistemas que presentan eclipses. Esto es, el exoplaneta cruza en alg\u00fan momento por","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"datePublished":"2007-06-29T01:40:00+01:00","dateModified":"2017-02-26T20:10:14+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"\u00bfSe puede detectar agua en los exoplanetas? - Cuaderno de bit\u00e1cora estelar","og:description":"David ByN Una de las principales discusiones que se est\u00e1 manteniendo en la conferencia sobre sistemas planetarios extremos es si se puede detectar agua en los exoplanetas. La t\u00e9cnica es verdaderamente sofisticada. Se trata de obtener espectros en el rango infrarrojo en sistemas que presentan eclipses. Esto es, el exoplaneta cruza en alg\u00fan momento por","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2007-06-29T01:40:00+00:00","article:modified_time":"2017-02-26T19:10:14+00:00","twitter:card":"summary","twitter:title":"\u00bfSe puede detectar agua en los exoplanetas? - Cuaderno de bit\u00e1cora estelar","twitter:description":"David ByN Una de las principales discusiones que se est\u00e1 manteniendo en la conferencia sobre sistemas planetarios extremos es si se puede detectar agua en los exoplanetas. La t\u00e9cnica es verdaderamente sofisticada. Se trata de obtener espectros en el rango infrarrojo en sistemas que presentan eclipses. Esto es, el exoplaneta cruza en alg\u00fan momento por","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"68948","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-01-28 23:47:24","updated":"2023-06-19 08:47:06","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion\" title=\"Divulgaci\u00f3n\">Divulgaci\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfSe puede detectar agua en los exoplanetas?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Divulgaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion"},{"label":"\u00bfSe puede detectar agua en los exoplanetas?","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2007\/06\/29\/68948"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/68948"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=68948"}],"version-history":[{"count":1,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/68948\/revisions"}],"predecessor-version":[{"id":134319,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/68948\/revisions\/134319"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=68948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=68948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=68948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}