{"id":83029,"date":"2008-01-23T04:56:00","date_gmt":"2008-01-23T04:56:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/astrofisica\/archive\/2008\/01\/23\/83029.aspx"},"modified":"2008-01-23T04:56:00","modified_gmt":"2008-01-23T04:56:00","slug":"la-emocion-de-llegar-a-lugares-insospechados","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029","title":{"rendered":"La emoci\u00f3n de llegar a lugares insospechados&#8230;"},"content":{"rendered":"<p>Benjam\u00edn Montesinos<\/p>\n<div align=\"justify\">Esta ma\u00f1ana un compa\u00f1ero del trabajo me ha alertado acerca de un error que comet\u00ed en la contribuci\u00f3n que escrib\u00ed ayer. Dec\u00eda que las estrellas muy masivas viven &#8216;decenas de miles de a\u00f1os&#8217; cuando obviamente quer\u00eda decir &#8216;decenas de millones&#8217;. He entrado en la p\u00e1gina de la Bit\u00e1cora, he corregido el error y me he quedado mirando al peque\u00f1o icono que David coloc\u00f3 en la p\u00e1gina para ver cuantas visitas recibimos. Si baj\u00e1is un poco en la p\u00e1gina web lo encontrar\u00e9is, identificado con <a href=\"http:\/\/clustrmaps.com\/counter\/maps.php?url=http:\/\/weblogs.madrimasd.org\/astrofisica\/\">&#8216;Visitor locations&#8217;<\/a>. Haciendo un click en el icono se puede acceder a la informaci\u00f3n y a mapas m\u00e1s detallados.<\/div>\n<p><!--more--><\/p>\n<div align=\"justify\">Los c\u00edrculos rojos est\u00e1n superpuestos m\u00e1s o menos en los lugares desde donde las personas que nos siguen se conectan, los m\u00e1s grandes indican 1000 o m\u00e1s visitas, y a la hora que escribo esta entrada la informacion que proporciona esta herramienta dice que hemos recibido casi 294.000 visitas desde el 20 de junio de 2007 hasta el 1 de enero de 2008.<\/div>\n<p><img decoding=\"async\" src=\"http:\/\/www.laeff.inta.es\/users\/bmm\/weblog\/visitas.jpg\" width=\"450\"><\/p>\n<div align=\"justify\">Mirando el mapa me ha emocionado, y lo digo en serio, ver el alcance de internet y la potencialidad de este medio para llegar a todo el mundo. Obviamente, por el hecho de ser una bit\u00e1cora en espa\u00f1ol hay muchas entradas -aparte de las que se producen en Espa\u00f1a- desde Centro y Sudam\u00e9rica y tambi\u00e9n de M\u00e9xico y Estados Unidos. Lo que me ha llamado la atenci\u00f3n es que nos leen en Islandia, India, China (\u00a1hay una gran concentraci\u00f3n en Pek\u00edn!), Jap\u00f3n, Corea, en las islas Aleutianas&nbsp; (ese punto rojo a la izquierda, al suroeste de Alaska), en Costa de Marfil, Togo, Yemen, Iraq, Tailandia, Indonesia y alguien en las estepas de Siberia. <\/p>\n<p>Confieso que he tenido que echar mano de un <a href=\"http:\/\/maps.google.es\" target=\"blank\">mapa mundi<\/a> para identificar algunos de los lugares&#8230;<\/p>\n<p>Si hemos podido crear inquietud cient\u00edfica en nuestros lectores e impulsarlos a buscar por ellos mismos informaci\u00f3n que complete lo que les contamos, o si simplemente si los hemos deleitado con bonitas im\u00e1genes o con experiencias personales, nos sentimos gratificados.<\/p>\n<p>&nbsp;A veces, cuando damos una charla divulgativa sobre Astronom\u00eda para el p\u00fablico en general, los asistentes salen de ella con m\u00e1s dudas de las que entraron, y yo siempre les digo que eso es sano, porque quiz\u00e1s en esa charla era la primera vez que o\u00edan hablar de un concepto o de una idea. Ese es el punto de partida para que, si se ha encendido una chispa de curiosidad, la persona en cuesti\u00f3n empiece una b\u00fasqueda por s\u00ed misma. <\/p>\n<p>Gracias por leernos, y aprovecho para dar p\u00fablicamente las gracias a David por ser quien realmente ha &#8216;tirado del carro&#8217; de esta Bit\u00e1cora en los \u00faltimos meses. <\/div>\n<hr align=\"justify\" size=\"1\">\n<div align=\"justify\"> <A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/\" target=\"blank\">  <strong> P\u00e1gina principal del \u00abCuaderno de Bit\u00e1cora Estelar\u00bb<\/strong><\/a>    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Benjam\u00edn Montesinos Esta ma\u00f1ana un compa\u00f1ero del trabajo me ha alertado acerca de un error que comet\u00ed en la contribuci\u00f3n que escrib\u00ed ayer. Dec\u00eda que las estrellas muy masivas viven &#8216;decenas de miles de a\u00f1os&#8217; cuando obviamente quer\u00eda decir &#8216;decenas de millones&#8217;. He entrado en la p\u00e1gina de la Bit\u00e1cora, he corregido el error y me he quedado mirando al peque\u00f1o icono que David coloc\u00f3 en la p\u00e1gina para ver cuantas visitas recibimos. Si baj\u00e1is un poco en la p\u00e1gina web lo encontrar\u00e9is, identificado con &#8216;Visitor locations&#8217;. Haciendo un click en el icono se puede acceder a la informaci\u00f3n y\u2026<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[64],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Benjam\u00edn MontesinosEsta ma\u00f1ana un compa\u00f1ero del trabajo me ha alertado acerca de un error que comet\u00ed en la contribuci\u00f3n que escrib\u00ed ayer. Dec\u00eda que las estrellas muy masivas viven &#039;decenas de miles de a\u00f1os&#039; cuando obviamente quer\u00eda decir &#039;decenas de millones&#039;. He entrado en la p\u00e1gina de la Bit\u00e1cora, he corregido el error y me\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrador CBE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La emoci\u00f3n de llegar a lugares insospechados\u2026 - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"Benjam\u00edn MontesinosEsta ma\u00f1ana un compa\u00f1ero del trabajo me ha alertado acerca de un error que comet\u00ed en la contribuci\u00f3n que escrib\u00ed ayer. Dec\u00eda que las estrellas muy masivas viven &#039;decenas de miles de a\u00f1os&#039; cuando obviamente quer\u00eda decir &#039;decenas de millones&#039;. He entrado en la p\u00e1gina de la Bit\u00e1cora, he corregido el error y me\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-01-23T04:56:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2008-01-23T04:56:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La emoci\u00f3n de llegar a lugares insospechados\u2026 - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Benjam\u00edn MontesinosEsta ma\u00f1ana un compa\u00f1ero del trabajo me ha alertado acerca de un error que comet\u00ed en la contribuci\u00f3n que escrib\u00ed ayer. Dec\u00eda que las estrellas muy masivas viven &#039;decenas de miles de a\u00f1os&#039; cuando obviamente quer\u00eda decir &#039;decenas de millones&#039;. He entrado en la p\u00e1gina de la Bit\u00e1cora, he corregido el error y me\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029#blogposting\",\"name\":\"La emoci\\u00f3n de llegar a lugares insospechados\\u2026 - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"La emoci\\u00f3n de llegar a lugares insospechados&#8230;\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.laeff.inta.es\\\/users\\\/bmm\\\/weblog\\\/visitas.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029\\\/#articleImage\"},\"datePublished\":\"2008-01-23T04:56:00+01:00\",\"dateModified\":\"2008-01-23T04:56:00+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":4,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029#webpage\"},\"articleSection\":\"Divulgaci\\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"position\":2,\"name\":\"Divulgaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029#listItem\",\"name\":\"La emoci\\u00f3n de llegar a lugares insospechados&#8230;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029#listItem\",\"position\":3,\"name\":\"La emoci\\u00f3n de llegar a lugares insospechados&#8230;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis\",\"name\":\"Administrador CBE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Administrador CBE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029\",\"name\":\"La emoci\\u00f3n de llegar a lugares insospechados\\u2026 - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Benjam\\u00edn MontesinosEsta ma\\u00f1ana un compa\\u00f1ero del trabajo me ha alertado acerca de un error que comet\\u00ed en la contribuci\\u00f3n que escrib\\u00ed ayer. Dec\\u00eda que las estrellas muy masivas viven 'decenas de miles de a\\u00f1os' cuando obviamente quer\\u00eda decir 'decenas de millones'. He entrado en la p\\u00e1gina de la Bit\\u00e1cora, he corregido el error y me\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/01\\\/23\\\/83029#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"datePublished\":\"2008-01-23T04:56:00+01:00\",\"dateModified\":\"2008-01-23T04:56:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La emoci\u00f3n de llegar a lugares insospechados\u2026 - Cuaderno de bit\u00e1cora estelar","description":"Benjam\u00edn MontesinosEsta ma\u00f1ana un compa\u00f1ero del trabajo me ha alertado acerca de un error que comet\u00ed en la contribuci\u00f3n que escrib\u00ed ayer. Dec\u00eda que las estrellas muy masivas viven 'decenas de miles de a\u00f1os' cuando obviamente quer\u00eda decir 'decenas de millones'. He entrado en la p\u00e1gina de la Bit\u00e1cora, he corregido el error y me","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029#blogposting","name":"La emoci\u00f3n de llegar a lugares insospechados\u2026 - Cuaderno de bit\u00e1cora estelar","headline":"La emoci\u00f3n de llegar a lugares insospechados&#8230;","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.laeff.inta.es\/users\/bmm\/weblog\/visitas.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029\/#articleImage"},"datePublished":"2008-01-23T04:56:00+01:00","dateModified":"2008-01-23T04:56:00+01:00","inLanguage":"es-ES","commentCount":4,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029#webpage"},"articleSection":"Divulgaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","position":2,"name":"Divulgaci\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029#listItem","name":"La emoci\u00f3n de llegar a lugares insospechados&#8230;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029#listItem","position":3,"name":"La emoci\u00f3n de llegar a lugares insospechados&#8230;","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis","name":"Administrador CBE","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Administrador CBE"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029","name":"La emoci\u00f3n de llegar a lugares insospechados\u2026 - Cuaderno de bit\u00e1cora estelar","description":"Benjam\u00edn MontesinosEsta ma\u00f1ana un compa\u00f1ero del trabajo me ha alertado acerca de un error que comet\u00ed en la contribuci\u00f3n que escrib\u00ed ayer. Dec\u00eda que las estrellas muy masivas viven 'decenas de miles de a\u00f1os' cuando obviamente quer\u00eda decir 'decenas de millones'. He entrado en la p\u00e1gina de la Bit\u00e1cora, he corregido el error y me","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"datePublished":"2008-01-23T04:56:00+01:00","dateModified":"2008-01-23T04:56:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"La emoci\u00f3n de llegar a lugares insospechados\u2026 - Cuaderno de bit\u00e1cora estelar","og:description":"Benjam\u00edn MontesinosEsta ma\u00f1ana un compa\u00f1ero del trabajo me ha alertado acerca de un error que comet\u00ed en la contribuci\u00f3n que escrib\u00ed ayer. Dec\u00eda que las estrellas muy masivas viven 'decenas de miles de a\u00f1os' cuando obviamente quer\u00eda decir 'decenas de millones'. He entrado en la p\u00e1gina de la Bit\u00e1cora, he corregido el error y me","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2008-01-23T04:56:00+00:00","article:modified_time":"2008-01-23T04:56:00+00:00","twitter:card":"summary","twitter:title":"La emoci\u00f3n de llegar a lugares insospechados\u2026 - Cuaderno de bit\u00e1cora estelar","twitter:description":"Benjam\u00edn MontesinosEsta ma\u00f1ana un compa\u00f1ero del trabajo me ha alertado acerca de un error que comet\u00ed en la contribuci\u00f3n que escrib\u00ed ayer. Dec\u00eda que las estrellas muy masivas viven 'decenas de miles de a\u00f1os' cuando obviamente quer\u00eda decir 'decenas de millones'. He entrado en la p\u00e1gina de la Bit\u00e1cora, he corregido el error y me","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"83029","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-01-28 23:56:47","updated":"2023-06-19 08:49:34","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion\" title=\"Divulgaci\u00f3n\">Divulgaci\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa emoci\u00f3n de llegar a lugares insospechados\u2026\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Divulgaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion"},{"label":"La emoci\u00f3n de llegar a lugares insospechados&#8230;","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/01\/23\/83029"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/83029"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=83029"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/83029\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=83029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=83029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=83029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}