{"id":84036,"date":"2008-02-07T14:12:00","date_gmt":"2008-02-07T14:12:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/astrofisica\/archive\/2008\/02\/07\/84036.aspx"},"modified":"2008-02-07T14:12:00","modified_gmt":"2008-02-07T14:12:00","slug":"xmm-newton-ojos-de-oro-para-ver-el-universo-invisible","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036","title":{"rendered":"XMM-Newton: ojos de oro para ver el Universo invisible"},"content":{"rendered":"<div align=\"justify\">Mar\u00eda Santos Lleo<br \/> European Science Astronomy Centre<br \/> European Space Agency <\/p>\n<p>   Cerca de la urbanizaci\u00f3n Villafranca del Castillo, a unos 30 km de Madrid y en el t\u00e9rmino de Villanueva de la Ca\u00f1ada, se encuentra el observatorio o Centro de Operaciones Cient\u00edficas de XMM-Newton, la Misi\u00f3n Multi-espejo de rayos X de la Agencia Europea del Espacio (ESA, por sus siglas en ingl\u00e9s). El observatorio est\u00e1 ubicado en el Centro Europeo de Astronom\u00eda Espacial (ESAC) que ha sido inaugurado hoy d\u00eda 7 de febrero por los Pr\u00edncipes de Asturias.  <\/div>\n<p> <!--more--><\/p>\n<div align=\"justify\">El observatorio de XMM-Newton es un poco especial, \u00a1tendr\u00eda poco sentido poner observatorio moderno tan cerca de una ciudad grande como Madrid! De hecho, los telescopios de XMM-Newton est\u00e1n muy lejos, a decenas de miles de km, en \u00f3rbita en torno a la Tierra. La luz que captan es tambi\u00e9n especial: los rayos X, como los que se utilizan para hacer radiograf\u00edas, pero generados en distintos lugares del Universo, desde las estrellas o las nubes de gas m\u00e1s cercanas, hasta las galaxias m\u00e1s lejanas. Quiz\u00e1 m\u00e1s que decir que es una luz especial, s\u00f3lo se deber\u00eda decir que, como las ondas radio, infrarrojas o los rayos gamma, es diferente de la luz que vemos y, por eso, las condiciones requeridas para producirla y luego captarla con instrumentos como c\u00e1maras fotogr\u00e1ficas son especiales, o simplemente diferentes. <\/p>\n<p>     <img decoding=\"async\" src=\"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/MdSXMM-artist.jpg\" width=\"450\"><br \/><i><b>Figura 1:<\/b> Dise\u00f1o art\u00edstico del sat\u00e9lite en \u00f3rbita XMM-Newton sobre la Tierra.  <\/i><\/p>\n<p>     Los rayos X son muy energ\u00e9ticos. Podemos entender mejor lo que esto  significa con un ejemplo: cuando un hierro se calienta a unos 1000 grados, se dice que est\u00e1 al rojo vivo: emite luz visible de color rojo. Pues bien, para que el hierro emita luz en el rango de los rayos X, deber\u00edamos calentarlo mil veces m\u00e1s: \u00a1hasta varios millones de grados! Otra forma de entender la energ\u00eda que transportan los rayos X es pensando en c\u00f3mo la luz interacciona con la materia, con los \u00e1tomos. Cuando un fot\u00f3n luminoso choca contra un \u00e1tomo, puede cederle su energ\u00eda a un electr\u00f3n y arrancarlo del \u00e1tomo, lo que se conoce como foto-ionizaci\u00f3n (o ionizaci\u00f3n por medio de la luz). Obviamente, es mucho m\u00e1s dif\u00edcil arrancar los electrones internos, m\u00e1s cercanos al n\u00facleo at\u00f3mico, que los externos. Tomando de nuevo el hierro como muestra, vemos que hace falta mil veces m\u00e1s energ\u00eda para arrancarle el electr\u00f3n m\u00e1s interno que para el m\u00e1s externo: hace falta llegar al rango de los rayos X.  <\/p>\n<p>  <img decoding=\"async\" src=\"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/MdSlight_path_xmm_pn.gif\" width=\"450\"><br \/><i><b>Figura 2: <\/b>Ilustraci\u00f3n del camino seguido por los fotones de rayos X: entrando en los espejos de XMM-Newton, por la izquierda, siendo reflejados dos veces en la superficie interna de los espejos con una ligera curvatura, primero paraboloide y luego hiperboloide, y focalizados a 7 metros y medio de distancia, a la derecha, arriba.  <br \/><\/i><\/p>\n<p>      Debido a su energ\u00eda, los rayos X son tambi\u00e9n dif\u00edciles de capturar: son ondas peque\u00f1as que se \u00abcuelan\u00bb por los huecos at\u00f3micos. Por eso atraviesan, por ejemplo, los tejidos de nuestro cuerpo y s\u00f3lo son detenidos por los huesos. Ese es el motivo de que podamos ver los huesos en las radiograf\u00edas: al bombardear nuestro cuerpo con rayos X y poner una placa fotogr\u00e1fica detr\u00e1s, la luz que \u00abtoca hueso\u00bb  no llega a la placa, mientras que el resto s\u00ed que llega e impresiona la placa. Lo que en medicina es una ventaja, en astronom\u00eda es, sin embargo, un inconveniente. Para recoger muchos fotones X no podemos utilizar espejos convencionales como se utilizan en astronom\u00eda \u00f3ptica, \u00a1los rayos X los atraviesan! \u00bfQu\u00e9 puede entonces hacerse para enfocar fotones de rayos X? Lo que se ha hecho en XMM-Newton es utilizar una t\u00e9cnica conocida como incidencia rasante, es decir, forzar a los rayos X a que reboten, como rebotan los cantos en la superficie de un lago, en la cara interna de espejos cil\u00edndricos que tienen una peque\u00f1a curvatura. Estos espejos son como barriles ba\u00f1ados en oro en su interior: los rayos X que entran en el barril con incidencia rasante, chocan con sus paredes y son desviados hacia un punto del plano focal, a 7,5m de distancia (Figura 2). De esta forma se consigue hacer una imagen de los rayos X provenientes de lugar al que apuntan los espejos. XMM-Newton tiene tres telescopios de rayos X, cada uno est\u00e1 formado por 58 de estos barriles, con radios decrecientes y anidados uno dentro de otro, como mu\u00f1ecas rusas (Figura 3). As\u00ed es capaz de recoger y enfocar la radiaci\u00f3n X del Universo. Adem\u00e1s, el tener tantos espejos le convierte en la misi\u00f3n de rayos X m\u00e1s sensible jam\u00e1s enviada al espacio para observar el Universo.  <\/p>\n<p>               <img decoding=\"async\" src=\"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/MdSxmm_mirror_med.gif\" width=\"450\"><br \/><i><b> Figura 3:<\/b> Fotograf\u00eda de los m\u00f3dulos de espejos de XMM-Newton tomada durante su integraci\u00f3n en el sat\u00e9lite. Solo uno de los tres m\u00f3dulos, el de la izquierda, estaba abierto en el momento que se tom\u00f3 la foto, dejando ver las barras radiales de sujeci\u00f3n. Los otros dos estaban ya tapados, para proteger los espejos de posibles da\u00f1os durante el lanzamiento. Las tapas protectoras se abrieron una vez que el sat\u00e9lite fue colocado en su \u00f3rbita en torno a la Tierra.<br \/><\/i><br \/>&nbsp;<\/p>\n<p>   Todo lo dicho hasta ahora lo podemos sintetizar en que XMM-Newton es un sat\u00e9lite de la ESA, construido y lanzado con el objetivo de captar los rayos X del Universo. La primera propiedad espec\u00edfica de XMM-Newton respecto a sus antecesores en esto de los rayos X es su sensibilidad sin precedentes, ya mencionada. Adem\u00e1s, XMM-Newton se define tambi\u00e9n por su capacidad espectrosc\u00f3pica. Es capaz de medir la energ\u00eda de cada uno de los fotones de rayos X detectado y, por tanto, de separar la luz X en sus distintos colores, como un prisma separa la luz visible en los colores del arco-iris. Los tres telescopios de rayos X que tiene a bordo est\u00e1n provistos con una c\u00e1mara cada uno, para hacer im\u00e1genes y espectroscopia simult\u00e1nea. Dos de los telescopios tienen adem\u00e1s un espectr\u00f3grafo, que proporciona mayor resoluci\u00f3n, es decir, que es capaz de diferenciar mejor los distintos colores (o longitudes de onda) de los rayos X que le llegan. Por \u00faltimo, tiene a bordo tambi\u00e9n un telescopio \u00f3ptico, capaz de proporcionar informaci\u00f3n sobre la luz \u00f3ptica y ultravioleta de las fuentes c\u00f3smicas. La Figura 4 muestra los telescopios y la plataforma de los instrumentos. Todos los instrumentos mencionados trabajan simult\u00e1neamente.  <\/p>\n<p>    <img decoding=\"async\" src=\"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/MdSxmm_spacec_med.gif\" width=\"450\"><br \/><i><b>Figura 4:<\/b> Esquema de la carga cient\u00edfica de XMM-Newton: los tres telescopios de rayos X se muestran abajo a la izquierda, en verde, con las tapas abiertas. Dos de los telescopios tienen en su parte de atr\u00e1s (la opuesta a las tapas) las redes dispersoras de los espectr\u00f3grafos. El telescopio \u00f3ptico, m\u00e1s peque\u00f1o, se muestra en azul. En el lado opuesto del sat\u00e9lite est\u00e1 la plataforma de los instrumentos: las tres c\u00e1maras y los dos espectr\u00f3grafos. Entre ambos extremos se sit\u00faa el tubo de 7m pr\u00e1cticamente vac\u00edo, necesario para conectar ambas partes situando los instrumentos en el plano focal.   <\/p>\n<p><\/i> <br \/>   XMM-Newton fue lanzado el 10 de diciembre de 1999. Ya ha cumplido su octavo cumplea\u00f1os y no ha defraudado en absoluto. La pregunta ahora es obvia, quiz\u00e1 es la primera pregunta que uno se plantea cuando empieza a leer esto: pero, \u00bfpor qu\u00e9 queremos mirar el Universo en rayos X y por qu\u00e9 con XMM-Newton? A esta pregunta le siguen inmediatamente otras: \u00bfQu\u00e9 es lo estamos aprendiendo con XMM-Newton? \u00bfPor qu\u00e9 decimos que no nos ha defraudado? En un siguiente apunte a este cuaderno de bit\u00e1cora contestar\u00e9 a estas preguntas y explicar\u00e9 la contribuci\u00f3n de este sat\u00e9lite a la astrof\u00edsica. Contribuci\u00f3n que se lleva a cabo en una gran parte desde el centro inaugurado hoy: ESAC, definido como el \u00abcoraz\u00f3n cient\u00edfico de la ESA\u00bb en la nota de prensa difundida con motivo de la inauguraci\u00f3n. ESAC es la ventana al espacio de Europa y dentro de ESAC, XMM-Newton ocupa un lugar importante, pero claramente al mismo nivel que el de todos los dem\u00e1s programas  cient\u00edficos, tanto de exploraci\u00f3n del Sistema Solar, astrof\u00edsicas como de observaci\u00f3n de la Tierra que se llevan en el centro.     <\/p>\n<p><b> ENLACES: <\/b> <\/p>\n<ul>\n<li> <a href=\"http:\/\/www.esa.int\/esaCP\/SEMPFOPR4CF_Spain_0.html\" target=\"blank\"> ESAC: inauguraci\u00f3n<\/a>   <\/li>\n<li> <a href=\"http:\/\/www.esa.int\/esaMI\/ESAC\/index.html\" target=\"blank\"> M\u00e1s sobre ESAC y otros programas cient\u00edficos y de observaci\u00f3n de la Tierra<\/a>   <\/li>\n<li> <a href=\"http:\/\/xmm.esac.esa.int\/\" target=\"blank\">XMM-Newton, Centro de operaciones cient\u00edficas<\/a>     <\/li>\n<li> <a href=\"http:\/\/xmm.esac.esa.int\/external\/xmm_science\/gallery\/public\/index.php\" target=\"blank\">  XMM-Newton, galer\u00eda de im\u00e1genes y c\u00f3mo dar un paseo por el cielo visto por XMM-Newton con Google Sky<\/a>       <\/li>\n<li> <a href=\"http:\/\/xmm.esac.esa.int\/external\/xmm_user_support\/documentation\/technical\/index.shtml\" target=\"blank\"> Descripci\u00f3n de XMM-Newton<\/a>    <\/li>\n<li> <a href=\"http:\/\/www.esa.int\/science\/xmmnewton\" target=\"blank\"> XMM-Newton en las p\u00e1ginas de \u00abESA-science\u00bb <\/a>     <\/li>\n<li> <a href=\"http:\/\/xmm.sonoma.edu\/\" target=\"blank\"> XMM-Newton en el programa de \u00abEducation and Public Outreach\u00bb, de la NASA<\/a> <\/li>\n<li><A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/10\/02\/44302.aspx\">CBE: Im\u00e1genes en rayos X del sat\u00e9lite XMM-Newton<\/a><\/li>\n<li><A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/archive\/2006\/06\/02\/27545.aspx\">CBE. Observando el Cosmos desde el Espacio<\/a><\/li>\n<\/ul><\/div>\n<hr align=\"justify\" size=\"1\">\n<div align=\"justify\"> <A href=\"http:\/\/weblogs.madrimasd.org\/astrofisica\/\" target=\"blank\">  <strong> P\u00e1gina principal del \u00abCuaderno de Bit\u00e1cora Estelar\u00bb <\/strong><\/a>         <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda Santos Lleo European Science Astronomy Centre European Space Agency Cerca de la urbanizaci\u00f3n Villafranca del Castillo, a unos 30 km de Madrid y en el t\u00e9rmino de Villanueva de la Ca\u00f1ada, se encuentra el observatorio o Centro de Operaciones Cient\u00edficas de XMM-Newton, la Misi\u00f3n Multi-espejo de rayos X de la Agencia Europea del Espacio (ESA, por sus siglas en ingl\u00e9s). El observatorio est\u00e1 ubicado en el Centro Europeo de Astronom\u00eda Espacial (ESAC) que ha sido inaugurado hoy d\u00eda 7 de febrero por los Pr\u00edncipes de Asturias.<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[64,556,560,557,553],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mar\u00eda Santos Lleo European Science Astronomy Centre European Space Agency Cerca de la urbanizaci\u00f3n Villafranca del Castillo, a unos 30 km de Madrid y en el t\u00e9rmino de Villanueva de la Ca\u00f1ada, se encuentra el observatorio o Centro de Operaciones Cient\u00edficas de XMM-Newton, la Misi\u00f3n Multi-espejo de rayos X de la Agencia Europea del Espacio\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Administrador CBE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"XMM-Newton: ojos de oro para ver el Universo invisible - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta property=\"og:description\" content=\"Mar\u00eda Santos Lleo European Science Astronomy Centre European Space Agency Cerca de la urbanizaci\u00f3n Villafranca del Castillo, a unos 30 km de Madrid y en el t\u00e9rmino de Villanueva de la Ca\u00f1ada, se encuentra el observatorio o Centro de Operaciones Cient\u00edficas de XMM-Newton, la Misi\u00f3n Multi-espejo de rayos X de la Agencia Europea del Espacio\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-02-07T14:12:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2008-02-07T14:12:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"XMM-Newton: ojos de oro para ver el Universo invisible - Cuaderno de bit\u00e1cora estelar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Mar\u00eda Santos Lleo European Science Astronomy Centre European Space Agency Cerca de la urbanizaci\u00f3n Villafranca del Castillo, a unos 30 km de Madrid y en el t\u00e9rmino de Villanueva de la Ca\u00f1ada, se encuentra el observatorio o Centro de Operaciones Cient\u00edficas de XMM-Newton, la Misi\u00f3n Multi-espejo de rayos X de la Agencia Europea del Espacio\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036#blogposting\",\"name\":\"XMM-Newton: ojos de oro para ver el Universo invisible - Cuaderno de bit\\u00e1cora estelar\",\"headline\":\"XMM-Newton: ojos de oro para ver el Universo invisible\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/laeff.inta.es\\\/users\\\/barrado\\\/weblog\\\/MdSXMM-artist.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036\\\/#articleImage\"},\"datePublished\":\"2008-02-07T14:12:00+01:00\",\"dateModified\":\"2008-02-07T14:12:00+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":5,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036#webpage\"},\"articleSection\":\"Divulgaci\\u00f3n, Estrellas y la Galaxia, Galaxias y Cosmolog\\u00eda, Instrumentaci\\u00f3n espacial y astron\\u00f3mica, Noticias de Astrof\\u00edsica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"position\":2,\"name\":\"Divulgaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036#listItem\",\"name\":\"XMM-Newton: ojos de oro para ver el Universo invisible\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036#listItem\",\"position\":3,\"name\":\"XMM-Newton: ojos de oro para ver el Universo invisible\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/category\\\/divulgacion#listItem\",\"name\":\"Divulgaci\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis\",\"name\":\"Administrador CBE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Administrador CBE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036\",\"name\":\"XMM-Newton: ojos de oro para ver el Universo invisible - Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Mar\\u00eda Santos Lleo European Science Astronomy Centre European Space Agency Cerca de la urbanizaci\\u00f3n Villafranca del Castillo, a unos 30 km de Madrid y en el t\\u00e9rmino de Villanueva de la Ca\\u00f1ada, se encuentra el observatorio o Centro de Operaciones Cient\\u00edficas de XMM-Newton, la Misi\\u00f3n Multi-espejo de rayos X de la Agencia Europea del Espacio\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/2008\\\/02\\\/07\\\/84036#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/author\\\/astrofis#author\"},\"datePublished\":\"2008-02-07T14:12:00+01:00\",\"dateModified\":\"2008-02-07T14:12:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/\",\"name\":\"Cuaderno de bit\\u00e1cora estelar\",\"description\":\"Astrof\\u00edsica, astronom\\u00eda, cosmolog\\u00eda, ciencias del espacio\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/astrofisica\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"XMM-Newton: ojos de oro para ver el Universo invisible - Cuaderno de bit\u00e1cora estelar","description":"Mar\u00eda Santos Lleo European Science Astronomy Centre European Space Agency Cerca de la urbanizaci\u00f3n Villafranca del Castillo, a unos 30 km de Madrid y en el t\u00e9rmino de Villanueva de la Ca\u00f1ada, se encuentra el observatorio o Centro de Operaciones Cient\u00edficas de XMM-Newton, la Misi\u00f3n Multi-espejo de rayos X de la Agencia Europea del Espacio","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036#blogposting","name":"XMM-Newton: ojos de oro para ver el Universo invisible - Cuaderno de bit\u00e1cora estelar","headline":"XMM-Newton: ojos de oro para ver el Universo invisible","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/laeff.inta.es\/users\/barrado\/weblog\/MdSXMM-artist.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036\/#articleImage"},"datePublished":"2008-02-07T14:12:00+01:00","dateModified":"2008-02-07T14:12:00+01:00","inLanguage":"es-ES","commentCount":5,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036#webpage"},"articleSection":"Divulgaci\u00f3n, Estrellas y la Galaxia, Galaxias y Cosmolog\u00eda, Instrumentaci\u00f3n espacial y astron\u00f3mica, Noticias de Astrof\u00edsica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","position":2,"name":"Divulgaci\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036#listItem","name":"XMM-Newton: ojos de oro para ver el Universo invisible"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036#listItem","position":3,"name":"XMM-Newton: ojos de oro para ver el Universo invisible","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion#listItem","name":"Divulgaci\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis","name":"Administrador CBE","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8481fdac84e3a1651510eeaa8fadfc6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Administrador CBE"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036","name":"XMM-Newton: ojos de oro para ver el Universo invisible - Cuaderno de bit\u00e1cora estelar","description":"Mar\u00eda Santos Lleo European Science Astronomy Centre European Space Agency Cerca de la urbanizaci\u00f3n Villafranca del Castillo, a unos 30 km de Madrid y en el t\u00e9rmino de Villanueva de la Ca\u00f1ada, se encuentra el observatorio o Centro de Operaciones Cient\u00edficas de XMM-Newton, la Misi\u00f3n Multi-espejo de rayos X de la Agencia Europea del Espacio","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/author\/astrofis#author"},"datePublished":"2008-02-07T14:12:00+01:00","dateModified":"2008-02-07T14:12:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/","name":"Cuaderno de bit\u00e1cora estelar","description":"Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cuaderno de bit\u00e1cora estelar - Astrof\u00edsica, astronom\u00eda, cosmolog\u00eda, ciencias del espacio","og:type":"article","og:title":"XMM-Newton: ojos de oro para ver el Universo invisible - Cuaderno de bit\u00e1cora estelar","og:description":"Mar\u00eda Santos Lleo European Science Astronomy Centre European Space Agency Cerca de la urbanizaci\u00f3n Villafranca del Castillo, a unos 30 km de Madrid y en el t\u00e9rmino de Villanueva de la Ca\u00f1ada, se encuentra el observatorio o Centro de Operaciones Cient\u00edficas de XMM-Newton, la Misi\u00f3n Multi-espejo de rayos X de la Agencia Europea del Espacio","og:url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036","og:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png","article:published_time":"2008-02-07T14:12:00+00:00","article:modified_time":"2008-02-07T14:12:00+00:00","twitter:card":"summary","twitter:title":"XMM-Newton: ojos de oro para ver el Universo invisible - Cuaderno de bit\u00e1cora estelar","twitter:description":"Mar\u00eda Santos Lleo European Science Astronomy Centre European Space Agency Cerca de la urbanizaci\u00f3n Villafranca del Castillo, a unos 30 km de Madrid y en el t\u00e9rmino de Villanueva de la Ca\u00f1ada, se encuentra el observatorio o Centro de Operaciones Cient\u00edficas de XMM-Newton, la Misi\u00f3n Multi-espejo de rayos X de la Agencia Europea del Espacio","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"84036","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-01-28 23:57:18","updated":"2023-06-19 08:49:34","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion\" title=\"Divulgaci\u00f3n\">Divulgaci\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tXMM-Newton: ojos de oro para ver el Universo invisible\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica"},{"label":"Divulgaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/category\/divulgacion"},{"label":"XMM-Newton: ojos de oro para ver el Universo invisible","link":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/2008\/02\/07\/84036"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/84036"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/comments?post=84036"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/posts\/84036\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/media?parent=84036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/categories?post=84036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/astrofisica\/wp-json\/wp\/v2\/tags?post=84036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}