{"id":132054,"date":"2011-10-08T04:29:15","date_gmt":"2011-10-08T03:29:15","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/?p=132054"},"modified":"2012-01-07T05:29:54","modified_gmt":"2012-01-07T04:29:54","slug":"de-vacunas-contra-el-vih-y-mecanismos-de-reparacion-del-adn","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054","title":{"rendered":"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN"},"content":{"rendered":"<p>Dos centros de investigaci\u00f3n hermanos del <a href=\"http:\/\/www.csic.es\/web\/guest\/home\">CSIC<\/a> se pueden encontrar en el Campus de la Universidad Aut\u00f3noma de Madrid: el <a href=\"http:\/\/www.cbm.uam.es\/mkfactory.esdomain\/webs\/CBMSO\/plt_Home.aspx\">Centro de Biolog\u00eda Molecular Severo Ochoa<\/a> \u2013mixto CSIC-UAM- y el <a href=\"http:\/\/www.cnb.uam.es\/\">Centro Nacional de Biotecnolog\u00eda<\/a>. Ambos Centros comparten diversas \u00e1reas de inter\u00e9s en biolog\u00eda molecular, celular o biotecnolog\u00eda. Ambos Centros son excelentes aunque, al parecer, no han convencido a los evaluadores internacionales en la \u00faltima fase para la \u201c<a href=\"http:\/\/www.micinn.es\/portal\/site\/MICINN\/menuitem.7eeac5cd345b4f34f09dfd1001432ea0\/?vgnextoid=cba733a6368c2310VgnVCM1000001d04140aRCRD\">excelencia Severo Ochoa<\/a>\u201d. Sea como fuere, no se puede negar el alto nivel cient\u00edfico que muchos de sus laboratorios poseen. Aqu\u00ed, ahora, y por colaboraci\u00f3n con su Unidad de Divulgaci\u00f3n, se describen dos noticias publicadas y difundidas desde el CNB y el CSIC&#8230;<!--more--><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.micinn.es\/stfls\/MICINN\/Investigacion\/IMAGENES\/Severo_Ochoa.jpg\" alt=\"\" width=\"369\" height=\"212\" \/><\/p>\n<p>\u00a0<\/p>\n<p><strong>Vacuna contra el Sida<\/strong><\/p>\n<p>Pocos grupos han sido tan constantes y perseverantes como el de <a href=\"http:\/\/www.cnb.uam.es\/~bmyc\/esteban.html\">Mariano Esteban<\/a> y su investigaci\u00f3n con el <a href=\"http:\/\/es.wikipedia.org\/wiki\/Vaccinia_virus\">virus vaccinia<\/a> \u2013con el que nos vacunaron contra la viruela- y su uso como herramienta en biomedicina. Y por aquello del \u201cque la sigue la consigue\u201d, acaban de dar a conocer unos resultados prometedores para millones de personas en todo el mundo&#8230;<\/p>\n<p><a href=\"http:\/\/es.wikipedia.org\/wiki\/Virus_de_la_inmunodeficiencia_humana\">El VIH<\/a>, virus causante del S\u00edndrome de Inmunodeficiencia Adquirida, ataca directamente a las c\u00e9lulas del <a href=\"http:\/\/es.wikipedia.org\/wiki\/Sistema_inmunitario\">sistema inmunol\u00f3gico<\/a> responsables de protegernos contra las infecciones virales. Por ello, y su gran variabilidad, ha sido muy complicado elaborar candidatas \u00f3ptimas a vacuna. Sin embargo, <a href=\"http:\/\/www.csic.es\/web\/guest\/noticias?p_p_id=contentviewerservice_WAR_alfresco_packportlet&amp;p_p_lifecycle=1&amp;p_p_state=maximized&amp;p_p_mode=view&amp;p_p_col_id=column-1&amp;p_p_col_pos=1&amp;p_p_col_count=2&amp;_contentviewerservice_WAR_alfresco_packportlet_struts_action=%2Fcontentviewer%2Fview&amp;_contentviewerservice_WAR_alfresco_packportlet_nodeRef=workspace%3A%2F%2FSpacesStore%2F93ae1e34-47c6-4e29-abcc-e32031a59518&amp;_contentviewerservice_WAR_alfresco_packportlet_gsa_index=false&amp;_contentviewerservice_WAR_alfresco_packportlet_title=Notas+de+prensa&amp;contentType=news\">los \u00faltimos resultados<\/a> de un grupo de investigadores multidisciplinar coordinado por Mariano Esteban -del Centro Nacional de Biotecnolog\u00eda (CSIC)- ofrecen una efectividad cercana al 90% con su vacuna denominada, MVA-B.<\/p>\n<p>Desarrollada a partir de 1999, MVA-B recibe el nombre por Vaccinia Modificado de Ankara al que se le ha insertado cuatro genes del virus del Sida (Gag, Pol, Nef y Env) subtipo B, el m\u00e1s prevalente en Europa.<\/p>\n<p>El producto se prob\u00f3 en 24 voluntarios \u2013m\u00e1s 6 que recibieron placebo- en el <a href=\"http:\/\/www.hospitalclinic.org\/\">Hospital Cl\u00ednic de Barcelona<\/a> y <a href=\"http:\/\/www.madrid.org\/cs\/Satellite?pagename=HospitalGregorioMaranon\/Page\/HGMA_home\">Gregorio Mara\u00f1\u00f3n de Madrid<\/a> demostr\u00e1ndose, mediante an\u00e1lisis de sangre perif\u00e9rica durante 48 semanas la producci\u00f3n efectiva y protectora de anticuerpos. La vacuna ya ha sido patentada por el CSIC y los resultados publicados en las revistas <em><a href=\"http:\/\/www.ncbi.nlm.nih.gov\/pubmed?term=Safety%20and%20immunogenicity%20of%20a%20modified%20pox%20vector-based%20HIV%2FAIDS%20vaccine%20candidate%20\">Vaccine<\/a> <\/em>y <em><a href=\"http:\/\/www.ncbi.nlm.nih.gov\/pubmed?term=%20The%20HIV%2FADS%20Vaccine%20Candidate%20MVA-B%20Administered%20as%20a%20Single%20\">Journal of Virology<\/a><\/em>.<\/p>\n<p>Ahora, una vez aceptado el protocolo, se iniciar\u00e1, a trav\u00e9s de la Red de Investigaci\u00f3n del Sida los preceptivos ensayos cl\u00ednicos \u2013I, II y, si todo va bien, III- en un futuro podr\u00eda acabar en el mercado, constituyendo, quiz\u00e1, la mejor oportunidad de poner freno a una de las peores pandemias del siglo XX, y lo que llevamos del XXI.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/3.bp.blogspot.com\/-lFbVbSPSCrA\/Tc16uViGIFI\/AAAAAAAAPRs\/_jB5xdVgqyc\/s400\/vacuna-vih.jpg\" alt=\"\" width=\"300\" height=\"189\" \/><\/p>\n<p><strong>Respuesta al da\u00f1o del ADN<\/strong><\/p>\n<p>En los mam\u00edferos, cuando el espermatozoide se une al \u00f3vulo, los dos n\u00facleos se fusionan en uno solo. Sin embargo, en muchos hongos tras el proceso de apareamiento los dos n\u00facleos que se han apareado no se fusionan y conviven como entidades separadas en el mismo citoplasma, un estado que los bi\u00f3logos llaman <a href=\"http:\/\/www.curtisbiologia.com\/glossary\/term\/307\">dicarionte<\/a>. <em><a href=\"http:\/\/es.wikipedia.org\/wiki\/Ustilago_maydis\">Ustilago maydis<\/a> <\/em>es uno de estos hongos con forma dicarionte que adem\u00e1s es un par\u00e1sito que afecta a las plantas de ma\u00edz.<\/p>\n<p>Las c\u00e9lulas dicariontes est\u00e1n obligadas a establecer un ciclo celular diferente al ciclo celular tradicional para conseguir que, tras la divisi\u00f3n, las c\u00e9lulas hijas hereden cada una un par de n\u00facleos diferentes. Aunque pudiera esperarse que el control de este ciclo celular diferente corriera a cargo de prote\u00ednas <em>diferentes<\/em>, el grupo dirigido por Jos\u00e9 P\u00e9rez-Mart\u00edn,<strong> <\/strong>\u00a0del <a title=\"Mecanismos moleculares de la virulencia f\u00fangica\" href=\"http:\/\/www.cnb.csic.es\/content\/research\/microbial\/cellcyclefungi\/index.php?l=1\" target=\"_blank\">Centro Nacional de Biotecnolog\u00eda<\/a> del CSIC, acaba de descubrir que no es as\u00ed, que se regula por \u00abun sistema de control celular conservado en todos los eucariotas\u00bb. De hecho, son prote\u00ednas conocidas desde hace bastante tiempo por los onc\u00f3logos (la cascada <a title=\"Checkpoint de da\u00f1os en el ADN\" href=\"http:\/\/es.wikipedia.org\/wiki\/Punto_de_control#Checkpoint_de_da.C3.B1os_en_el_ADN\" target=\"_blank\">Atr1-Chk1<\/a>) ya que detectan cualquier da\u00f1o en el ADN y evitan que la c\u00e9lula da\u00f1ada se divida. Para ello, alargan la duraci\u00f3n de la fase previa a la mitosis, la cual no se inicia hasta que el da\u00f1o se ha solucionado. Estos resultados se han publicado en <em><a href=\"http:\/\/www.plantcell.org\/content\/23\/4\/1654\">Plant Cell<\/a>.<\/em><\/p>\n<p>Y eso es precisamente lo que hacen estas prote\u00ednas en las c\u00e9lulas de <em>maydis<\/em>. Lo interesante es que durante el ciclo celular dicarionte esta cascada de se\u00f1alizaci\u00f3n alarga el tiempo previo a la mitosis <a title=\"The DNA Damage Response Signaling Cascade Regulates Proliferation of the Phytopathogenic Fungus Ustilago maydis in Planta\" href=\"http:\/\/www.plantcell.org\/content\/23\/4\/1654.abstract\" target=\"_blank\">permitiendo que los n\u00facleos se distribuyan equitativamente<\/a> entre las c\u00e9lulas hijas, sin que exista da\u00f1o alguno en el ADN. Este descubrimiento sugiere que est\u00e1 cascada muy conservada evolutivamente podr\u00eda jugar papeles m\u00e1s all\u00e1 control del ciclo celular en respuesta a da\u00f1o en el ADN.<\/p>\n<p>Aparte del inter\u00e9s puramente b\u00e1sico, P\u00e9rez-Mart\u00edn nos comenta que la mayor parte de las setas comestibles est\u00e1n formadas por c\u00e9lulas dicariontes y que controlando estas prote\u00ednas podr\u00eda ser posible acelerar a voluntad su capacidad de crecimiento.<\/p>\n<p><a href=\"http:\/\/www.cbm.uam.es\/ccientifica\/Enlaces.html\">CBMSO<\/a> + <a href=\"http:\/\/www.cnb.uam.es\/content\/info\/outreach\/index.php?l=1\">CNB<\/a><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"http:\/\/www.cbm.uam.es\/ccientifica\/Enlaces.html\">DIVULGACI\u00d3N CIENT\u00cdFICA\u00a0 DE\u00a010 de\u00a0OCTUBRE\u00a0DE\u00a02011<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><embed type=\"application\/x-shockwave-flash\" width=\"450\" height=\"360\" src=\"http:\/\/mediateca.madrimasd.org\/videoma\/includes\/flvplayer\/flvplayer_mi+d.swf\" allowfullscreen=\"true\" allowscriptaccess=\"always\" flashvars=\"&amp;file=172_17_99_151_videos_1951&amp;image=http:\/\/mediateca.madrimasd.org\/videoma\/web_publico\/preview_player.php?videoid=1951\"><\/embed><\/p>\n<p style=\"text-align: center;\">\u00a0\u00a0<a href=\"http:\/\/www.madrimasd.org\/informacionidi\/madrimasd-tv\/default.asp\">MADRI+D TV<\/a> (Divulgaci\u00f3n cient\u00edfica con cara, e im\u00e1genes, en 3 minutos)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/podcast\/radio-5\/entre-probetas\/\">ENTRE PROBETAS<\/a> (P\u00edldoras cient\u00edficas en 2 minutos). Radio 5<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/podcast\/radio-5\/a-hombros-de-gigantes\/\">A HOMBROS DE GIGANTES<\/a> Radio 5<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.ivoox.com\/perfil-astrolabio_aj_69799_1.html\">RADIO UTOP\u00cdA<\/a><\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.facebook.com\/home.php?#!\/pages\/Departamento-de-Cultura-Cientifica-Centro-de-Biologia-Molecular\/148445718520196\">FACEBOOK<\/a>\u00a0(Jos\u00e9 Antonio L\u00f3pez-Guerrero)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/?ref=logo#!\/pages\/Departamento-de-Cultura-Cient%C3%ADfica-Centro-de-Biolog%C3%ADa-Molecular\/148445718520196\">FACEBOOK<\/a> (Departamento de Cultura Cient\u00edfica -Centro de Biolog\u00eda Molecular)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/twitter.com\/#!\/JALGUERRERO\">TWITTER<\/a> (JALGUERRERO)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/twitter.com\/#!\/DCCientificaCBM\">TWITTER<\/a> (DCCientificaCBM)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.linkedin.com\/home?trk=hb_tab_home_top\">LINKED-IN <\/a>(Jal Guerrero)<\/p>\n<p style=\"text-align: center;\">\u00a0<\/p>\n<p style=\"text-align: center;\">.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos centros de investigaci\u00f3n hermanos del CSIC se pueden encontrar en el Campus de la Universidad Aut\u00f3noma de Madrid: el Centro de Biolog\u00eda Molecular Severo Ochoa \u2013mixto CSIC-UAM- y el Centro Nacional de Biotecnolog\u00eda. Ambos Centros comparten diversas \u00e1reas de inter\u00e9s en biolog\u00eda molecular, celular o biotecnolog\u00eda. Ambos Centros son excelentes aunque, al parecer, no han convencido a los evaluadores internacionales en la \u00faltima fase para la \u201cexcelencia Severo Ochoa\u201d. Sea como fuere, no se puede negar el alto nivel cient\u00edfico que muchos de sus laboratorios poseen. Aqu\u00ed, ahora, y por colaboraci\u00f3n con su Unidad de Divulgaci\u00f3n, se describen dos noticias publicadas y difundidas desde el CNB y el CSIC&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[539,538,536],"tags":[8850,8851,781,8849,8848],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Dos centros de investigaci\u00f3n hermanos del CSIC se pueden encontrar en el Campus de la Universidad Aut\u00f3noma de Madrid: el Centro de Biolog\u00eda Molecular Severo Ochoa \u2013mixto CSIC-UAM- y el Centro Nacional de Biotecnolog\u00eda. Ambos Centros comparten diversas \u00e1reas de inter\u00e9s en biolog\u00eda molecular, celular o biotecnolog\u00eda. Ambos Centros son excelentes aunque, al parecer, no han convencido a los evaluadores internacionales en la \u00faltima fase para la \u201cexcelencia Severo Ochoa\u201d. Sea como fuere, no se puede negar el alto nivel cient\u00edfico que muchos de sus laboratorios poseen. Aqu\u00ed, ahora, y por colaboraci\u00f3n con su Unidad de Divulgaci\u00f3n, se describen dos noticias publicadas y difundidas desde el CNB y el CSIC...\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"JAL\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bio (Ciencia+Tecnolog\u00eda) - Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN - Bio (Ciencia+Tecnolog\u00eda)\" \/>\n\t\t<meta property=\"og:description\" content=\"Dos centros de investigaci\u00f3n hermanos del CSIC se pueden encontrar en el Campus de la Universidad Aut\u00f3noma de Madrid: el Centro de Biolog\u00eda Molecular Severo Ochoa \u2013mixto CSIC-UAM- y el Centro Nacional de Biotecnolog\u00eda. Ambos Centros comparten diversas \u00e1reas de inter\u00e9s en biolog\u00eda molecular, celular o biotecnolog\u00eda. Ambos Centros son excelentes aunque, al parecer, no han convencido a los evaluadores internacionales en la \u00faltima fase para la \u201cexcelencia Severo Ochoa\u201d. Sea como fuere, no se puede negar el alto nivel cient\u00edfico que muchos de sus laboratorios poseen. Aqu\u00ed, ahora, y por colaboraci\u00f3n con su Unidad de Divulgaci\u00f3n, se describen dos noticias publicadas y difundidas desde el CNB y el CSIC...\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-10-08T03:29:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-01-07T04:29:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN - Bio (Ciencia+Tecnolog\u00eda)\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Dos centros de investigaci\u00f3n hermanos del CSIC se pueden encontrar en el Campus de la Universidad Aut\u00f3noma de Madrid: el Centro de Biolog\u00eda Molecular Severo Ochoa \u2013mixto CSIC-UAM- y el Centro Nacional de Biotecnolog\u00eda. Ambos Centros comparten diversas \u00e1reas de inter\u00e9s en biolog\u00eda molecular, celular o biotecnolog\u00eda. Ambos Centros son excelentes aunque, al parecer, no han convencido a los evaluadores internacionales en la \u00faltima fase para la \u201cexcelencia Severo Ochoa\u201d. Sea como fuere, no se puede negar el alto nivel cient\u00edfico que muchos de sus laboratorios poseen. Aqu\u00ed, ahora, y por colaboraci\u00f3n con su Unidad de Divulgaci\u00f3n, se describen dos noticias publicadas y difundidas desde el CNB y el CSIC...\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054#blogposting\",\"name\":\"De vacunas contra el VIH y mecanismos de reparaci\\u00f3n del ADN - Bio (Ciencia+Tecnolog\\u00eda)\",\"headline\":\"De vacunas contra el VIH y mecanismos de reparaci\\u00f3n del ADN\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.micinn.es\\\/stfls\\\/MICINN\\\/Investigacion\\\/IMAGENES\\\/Severo_Ochoa.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054\\\/#articleImage\"},\"datePublished\":\"2011-10-08T04:29:15+01:00\",\"dateModified\":\"2012-01-07T05:29:54+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054#webpage\"},\"articleSection\":\"GEN\\u00c9TICA Y SU MANIPULACI\\u00d3N, POL\\u00cdTICA Y CIENCIA, VIRUS EN GENERAL, Dicarionte, Reparaci\\u00f3n del ADN, Sida, Vacuna, VIH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/virus-en-general#listItem\",\"name\":\"VIRUS EN GENERAL\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/virus-en-general#listItem\",\"position\":2,\"name\":\"VIRUS EN GENERAL\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/virus-en-general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054#listItem\",\"name\":\"De vacunas contra el VIH y mecanismos de reparaci\\u00f3n del ADN\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054#listItem\",\"position\":3,\"name\":\"De vacunas contra el VIH y mecanismos de reparaci\\u00f3n del ADN\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/virus-en-general#listItem\",\"name\":\"VIRUS EN GENERAL\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\",\"name\":\"Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Biolog\\u00eda molecular y celular. Bioqu\\u00edmica. Biomedicina\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia\",\"name\":\"JAL\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c372814f0d0c3b98b41d9cafe3f11955?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"JAL\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054\",\"name\":\"De vacunas contra el VIH y mecanismos de reparaci\\u00f3n del ADN - Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Dos centros de investigaci\\u00f3n hermanos del CSIC se pueden encontrar en el Campus de la Universidad Aut\\u00f3noma de Madrid: el Centro de Biolog\\u00eda Molecular Severo Ochoa \\u2013mixto CSIC-UAM- y el Centro Nacional de Biotecnolog\\u00eda. Ambos Centros comparten diversas \\u00e1reas de inter\\u00e9s en biolog\\u00eda molecular, celular o biotecnolog\\u00eda. Ambos Centros son excelentes aunque, al parecer, no han convencido a los evaluadores internacionales en la \\u00faltima fase para la \\u201cexcelencia Severo Ochoa\\u201d. Sea como fuere, no se puede negar el alto nivel cient\\u00edfico que muchos de sus laboratorios poseen. Aqu\\u00ed, ahora, y por colaboraci\\u00f3n con su Unidad de Divulgaci\\u00f3n, se describen dos noticias publicadas y difundidas desde el CNB y el CSIC...\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2011\\\/10\\\/08\\\/132054#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"datePublished\":\"2011-10-08T04:29:15+01:00\",\"dateModified\":\"2012-01-07T05:29:54+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/\",\"name\":\"Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Biolog\\u00eda molecular y celular. Bioqu\\u00edmica. Biomedicina\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN - Bio (Ciencia+Tecnolog\u00eda)","description":"Dos centros de investigaci\u00f3n hermanos del CSIC se pueden encontrar en el Campus de la Universidad Aut\u00f3noma de Madrid: el Centro de Biolog\u00eda Molecular Severo Ochoa \u2013mixto CSIC-UAM- y el Centro Nacional de Biotecnolog\u00eda. Ambos Centros comparten diversas \u00e1reas de inter\u00e9s en biolog\u00eda molecular, celular o biotecnolog\u00eda. Ambos Centros son excelentes aunque, al parecer, no han convencido a los evaluadores internacionales en la \u00faltima fase para la \u201cexcelencia Severo Ochoa\u201d. Sea como fuere, no se puede negar el alto nivel cient\u00edfico que muchos de sus laboratorios poseen. Aqu\u00ed, ahora, y por colaboraci\u00f3n con su Unidad de Divulgaci\u00f3n, se describen dos noticias publicadas y difundidas desde el CNB y el CSIC...","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054#blogposting","name":"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN - Bio (Ciencia+Tecnolog\u00eda)","headline":"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.micinn.es\/stfls\/MICINN\/Investigacion\/IMAGENES\/Severo_Ochoa.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054\/#articleImage"},"datePublished":"2011-10-08T04:29:15+01:00","dateModified":"2012-01-07T05:29:54+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054#webpage"},"articleSection":"GEN\u00c9TICA Y SU MANIPULACI\u00d3N, POL\u00cdTICA Y CIENCIA, VIRUS EN GENERAL, Dicarionte, Reparaci\u00f3n del ADN, Sida, Vacuna, VIH"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/virus-en-general#listItem","name":"VIRUS EN GENERAL"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/virus-en-general#listItem","position":2,"name":"VIRUS EN GENERAL","item":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/virus-en-general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054#listItem","name":"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054#listItem","position":3,"name":"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/virus-en-general#listItem","name":"VIRUS EN GENERAL"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization","name":"Bio (Ciencia+Tecnolog\u00eda)","description":"Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia","name":"JAL","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c372814f0d0c3b98b41d9cafe3f11955?s=96&d=mm&r=g","width":96,"height":96,"caption":"JAL"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054","name":"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN - Bio (Ciencia+Tecnolog\u00eda)","description":"Dos centros de investigaci\u00f3n hermanos del CSIC se pueden encontrar en el Campus de la Universidad Aut\u00f3noma de Madrid: el Centro de Biolog\u00eda Molecular Severo Ochoa \u2013mixto CSIC-UAM- y el Centro Nacional de Biotecnolog\u00eda. Ambos Centros comparten diversas \u00e1reas de inter\u00e9s en biolog\u00eda molecular, celular o biotecnolog\u00eda. Ambos Centros son excelentes aunque, al parecer, no han convencido a los evaluadores internacionales en la \u00faltima fase para la \u201cexcelencia Severo Ochoa\u201d. Sea como fuere, no se puede negar el alto nivel cient\u00edfico que muchos de sus laboratorios poseen. Aqu\u00ed, ahora, y por colaboraci\u00f3n con su Unidad de Divulgaci\u00f3n, se describen dos noticias publicadas y difundidas desde el CNB y el CSIC...","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"datePublished":"2011-10-08T04:29:15+01:00","dateModified":"2012-01-07T05:29:54+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/","name":"Bio (Ciencia+Tecnolog\u00eda)","description":"Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Bio (Ciencia+Tecnolog\u00eda) - Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","og:type":"article","og:title":"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN - Bio (Ciencia+Tecnolog\u00eda)","og:description":"Dos centros de investigaci\u00f3n hermanos del CSIC se pueden encontrar en el Campus de la Universidad Aut\u00f3noma de Madrid: el Centro de Biolog\u00eda Molecular Severo Ochoa \u2013mixto CSIC-UAM- y el Centro Nacional de Biotecnolog\u00eda. Ambos Centros comparten diversas \u00e1reas de inter\u00e9s en biolog\u00eda molecular, celular o biotecnolog\u00eda. Ambos Centros son excelentes aunque, al parecer, no han convencido a los evaluadores internacionales en la \u00faltima fase para la \u201cexcelencia Severo Ochoa\u201d. Sea como fuere, no se puede negar el alto nivel cient\u00edfico que muchos de sus laboratorios poseen. Aqu\u00ed, ahora, y por colaboraci\u00f3n con su Unidad de Divulgaci\u00f3n, se describen dos noticias publicadas y difundidas desde el CNB y el CSIC...","og:url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054","og:image":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","article:published_time":"2011-10-08T03:29:15+00:00","article:modified_time":"2012-01-07T04:29:54+00:00","twitter:card":"summary","twitter:title":"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN - Bio (Ciencia+Tecnolog\u00eda)","twitter:description":"Dos centros de investigaci\u00f3n hermanos del CSIC se pueden encontrar en el Campus de la Universidad Aut\u00f3noma de Madrid: el Centro de Biolog\u00eda Molecular Severo Ochoa \u2013mixto CSIC-UAM- y el Centro Nacional de Biotecnolog\u00eda. Ambos Centros comparten diversas \u00e1reas de inter\u00e9s en biolog\u00eda molecular, celular o biotecnolog\u00eda. Ambos Centros son excelentes aunque, al parecer, no han convencido a los evaluadores internacionales en la \u00faltima fase para la \u201cexcelencia Severo Ochoa\u201d. Sea como fuere, no se puede negar el alto nivel cient\u00edfico que muchos de sus laboratorios poseen. Aqu\u00ed, ahora, y por colaboraci\u00f3n con su Unidad de Divulgaci\u00f3n, se describen dos noticias publicadas y difundidas desde el CNB y el CSIC...","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"132054","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-05 23:26:26","updated":"2026-05-26 16:51:48","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/virus-en-general\" title=\"VIRUS EN GENERAL\">VIRUS EN GENERAL<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDe vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia"},{"label":"VIRUS EN GENERAL","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/virus-en-general"},{"label":"De vacunas contra el VIH y mecanismos de reparaci\u00f3n del ADN","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2011\/10\/08\/132054"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/132054"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/comments?post=132054"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/132054\/revisions"}],"predecessor-version":[{"id":132141,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/132054\/revisions\/132141"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/media?parent=132054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/categories?post=132054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/tags?post=132054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}