{"id":132678,"date":"2013-04-06T02:20:04","date_gmt":"2013-04-06T01:20:04","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/?p=132678"},"modified":"2013-04-14T23:34:39","modified_gmt":"2013-04-14T22:34:39","slug":"fluorescencia-en-la-mejora-de-la-experimentacion-animal","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678","title":{"rendered":"Fluorescencia en la mejora de la experimentaci\u00f3n animal"},"content":{"rendered":"<p>Cuatro grupos de investigaci\u00f3n de la <a href=\"http:\/\/www.ricet.es\/es\/\">Red de Enfermedades Tropicales<\/a> (RICET) han desarrollado una t\u00e9cnica basada en unas <a href=\"http:\/\/www.noticiasmedicas.es\/medicina\/noticias\/19145\/1\/Las-proteinas-fluorescentes-son-un-sistema-de-alerta-mas-precoz-que-la-propia-sintomatologia-y-reducen-un-90-la-cantidad-de-animales-sacrificados-para-experimentacion-\/Page1.html\">prote\u00ednas fluorescentes rojas<\/a> a partir de la luci\u00e9rnaga y un p\u00f3lipo marino.<\/p>\n<p>Estas prote\u00ednas fluorescentes permitir\u00e1n evaluar la patogenicidad <em>in vivo<\/em> a tiempo real, realizar estudios de cribado de f\u00e1rmacos de alto rendimiento y constituyen un sistema de alerta en ciertas enfermedades mucho m\u00e1s precoz que los propios s\u00edntomas. Las prote\u00ednas fluorescentes rojas, que han sido probadas con la vacuna para la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Leishmaniasis\">leishmaniasis<\/a> patentada por la propia RICET, permitir\u00e1n adem\u00e1s reducir un 90% la cantidad de animales que exige sacrificar la actual metodolog\u00eda utilizada en experimentaci\u00f3n, con la importancia \u00e9tica que ello conlleva.<\/p>\n<figure id=\"attachment_132679\" aria-describedby=\"caption-attachment-132679\" style=\"width: 518px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.elcorreo.com\/innova\/investigacion\/20130321\/proteinas-fluorescentes-201303211221-rc.html\"><img decoding=\"async\" class=\" wp-image-132679 \" title=\"Prote\u00edna fluorescente roja a trav\u00e9s de la piel...\" src=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2013\/04\/RICET.jpg\" alt=\"Prote\u00edna fluorescente roja a trav\u00e9s de la piel...\" width=\"518\" height=\"185\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2013\/04\/RICET.jpg 647w, https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2013\/04\/RICET-300x107.jpg 300w\" sizes=\"(max-width: 518px) 100vw, 518px\" \/><\/a><figcaption id=\"caption-attachment-132679\" class=\"wp-caption-text\">Prote\u00edna fluorescente roja a trav\u00e9s de la piel&#8230;<\/figcaption><\/figure>\n<p>Para que un estudio cient\u00edfico sea considerado significativo, normalmente se sacrifican unos 4 animales a la semana durante 8 semanas como media, es decir, 32 animales. A esto habr\u00eda que a\u00f1adir otros 32 animales que forman el grupo control. Si como suele ocurrir, al estudiar f\u00e1rmacos se prueban varias dosis, con cada una de ellas deben sacrificarse esta misma cantidad de animales. En una investigaci\u00f3n habitual se requieren unos 200 de ellos. Con la t\u00e9cnica de las prote\u00ednas fluorescentes un rat\u00f3n sirve para el seguimiento de las 8 semanas que dura el experimento, mientras que en los ensayos cl\u00e1sicos habituales se necesitan 8 ratones, para sacrificar uno cada semana, es decir, se reducir\u00eda un 90% la cantidad de animales sacrificados.<!--more--><\/p>\n<p>Una cepa de Leishmania ha sido modificada gen\u00e9ticamente para que contenga <a href=\"http:\/\/en.wikipedia.org\/wiki\/MCherry\">la prote\u00edna mCherry<\/a>, una de las prote\u00ednas fluorescentes m\u00e1s poderosas y que emite una luz con suficiente energ\u00eda como para atravesar tejidos, lo que hace que sea f\u00e1cilmente detectable. Esto ha permitido a los investigadores de la RICET seguir la evoluci\u00f3n de una infecci\u00f3n por leishmania con un detector de luz, sin necesidad de estar continuamente sacrificando grupos de animales como se hace habitualmente en experimentaci\u00f3n. Algo de lo que, personalmente,me alegro mucho.<\/p>\n<p><a href=\"http:\/\/www.uam.es\/personal_pdi\/ciencias\/jolope\/\">JAL (CBMSO)<\/a><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"http:\/\/www.cbm.uam.es\/ccientifica\/Enlaces.html\">DIVULGACI\u00d3N CIENT\u00cdFICA DEL 08 DE ABRIL DE 2013<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><object width=\"450\" height=\"360\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"src\" value=\"http:\/\/mediateca.madrimasd.org\/videoma\/includes\/flvplayer\/flvplayer_mi+d.swf\" \/><param name=\"allowfullscreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"flashvars\" value=\"&amp;file=172_17_99_151_videos_2324&amp;image=http:\/\/mediateca.madrimasd.org\/videoma\/web_publico\/preview_player.php?videoid=2324\" \/><embed width=\"450\" height=\"360\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/mediateca.madrimasd.org\/videoma\/includes\/flvplayer\/flvplayer_mi+d.swf\" allowfullscreen=\"true\" allowscriptaccess=\"always\" flashvars=\"&amp;file=172_17_99_151_videos_2324&amp;image=http:\/\/mediateca.madrimasd.org\/videoma\/web_publico\/preview_player.php?videoid=2324\" \/><\/object><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/madrimasd-tv\/default.asp\">MADRI+D TV<\/a>\u00a0(Divulgaci\u00f3n cient\u00edfica con cara, e im\u00e1genes, en 3 minutos)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/podcast\/radio-5\/entre-probetas\/\">ENTRE PROBETAS<\/a>\u00a0(P\u00edldoras cient\u00edficas en 2 minutos). Radio 5<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/alacarta\/audios\/puntos-de-vista\/\">PUNTOS DE VISTA<\/a>\u00a0Radio Exterior de Espa\u00f1a (cada 15 d\u00edas. Martes)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/podcast\/radio-5\/a-hombros-de-gigantes\/\">A HOMBROS DE GIGANTES<\/a>\u00a0Radio 5<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.ivoox.com\/perfil-astrolabio_aj_69799_1.html\">RADIO UTOP\u00cdA<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.radiosintesis.com\/entrevista.php?id=69\">RADIOS\u00cdNTESIS<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/home.php?#!\/pages\/Departamento-de-Cultura-Cientifica-Centro-de-Biologia-Molecular\/148445718520196\">FACEBOOK<\/a>\u00a0(Jos\u00e9 Antonio L\u00f3pez-Guerrero)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/?ref=logo#!\/pages\/Departamento-de-Cultura-Cient%C3%ADfica-Centro-de-Biolog%C3%ADa-Molecular\/148445718520196\">FACEBOOK<\/a>\u00a0(Departamento de Cultura Cient\u00edfica -Centro de Biolog\u00eda Molecular)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/twitter.com\/#!\/JALGUERRERO\">TWITTER<\/a>\u00a0(JALGUERRERO)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/twitter.com\/#!\/DCCientificaCBM\">TWITTER<\/a>\u00a0(DCCientificaCBM)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.linkedin.com\/home?trk=hb_tab_home_top\">LINKED-IN\u00a0<\/a>(Jal Guerrero)<\/p>\n<p style=\"text-align: center;\">.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuatro grupos de investigaci\u00f3n de la Red de Enfermedades Tropicales (RICET) han desarrollado unas prote\u00ednas fluorescentes rojas a partir de la luci\u00e9rnaga y un p\u00f3lipo marino que permitir\u00e1n evaluar la patogenicidad in vivo a tiempo real, realizar estudios de cribado de f\u00e1rmacos de alto rendimiento y constituyen un sistema de alerta en ciertas enfermedades mucho m\u00e1s precoz que los propios s\u00edntomas. <\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[539,540],"tags":[15921,15788,15923,15922],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cuatro grupos de investigaci\u00f3n de la Red de Enfermedades Tropicales (RICET) han desarrollado unas prote\u00ednas fluorescentes rojas a partir de la luci\u00e9rnaga y un p\u00f3lipo marino que permitir\u00e1n evaluar la patogenicidad in vivo a tiempo real, realizar estudios de cribado de f\u00e1rmacos de alto rendimiento y constituyen un sistema de alerta en ciertas enfermedades mucho m\u00e1s precoz que los propios s\u00edntomas.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"JAL\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bio (Ciencia+Tecnolog\u00eda) - Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fluorescencia en la mejora de la experimentaci\u00f3n animal - Bio (Ciencia+Tecnolog\u00eda)\" \/>\n\t\t<meta property=\"og:description\" content=\"Cuatro grupos de investigaci\u00f3n de la Red de Enfermedades Tropicales (RICET) han desarrollado unas prote\u00ednas fluorescentes rojas a partir de la luci\u00e9rnaga y un p\u00f3lipo marino que permitir\u00e1n evaluar la patogenicidad in vivo a tiempo real, realizar estudios de cribado de f\u00e1rmacos de alto rendimiento y constituyen un sistema de alerta en ciertas enfermedades mucho m\u00e1s precoz que los propios s\u00edntomas.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-04-06T01:20:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-04-14T22:34:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fluorescencia en la mejora de la experimentaci\u00f3n animal - Bio (Ciencia+Tecnolog\u00eda)\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cuatro grupos de investigaci\u00f3n de la Red de Enfermedades Tropicales (RICET) han desarrollado unas prote\u00ednas fluorescentes rojas a partir de la luci\u00e9rnaga y un p\u00f3lipo marino que permitir\u00e1n evaluar la patogenicidad in vivo a tiempo real, realizar estudios de cribado de f\u00e1rmacos de alto rendimiento y constituyen un sistema de alerta en ciertas enfermedades mucho m\u00e1s precoz que los propios s\u00edntomas.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678#blogposting\",\"name\":\"Fluorescencia en la mejora de la experimentaci\\u00f3n animal - Bio (Ciencia+Tecnolog\\u00eda)\",\"headline\":\"Fluorescencia en la mejora de la experimentaci\\u00f3n animal\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/files\\\/2013\\\/04\\\/RICET.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678\\\/#articleImage\",\"width\":647,\"height\":231,\"caption\":\"Prote\\u00edna fluorescente roja a trav\\u00e9s de la piel...\"},\"datePublished\":\"2013-04-06T02:20:04+01:00\",\"dateModified\":\"2013-04-14T23:34:39+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678#webpage\"},\"articleSection\":\"GEN\\u00c9TICA Y SU MANIPULACI\\u00d3N, POPURR\\u00cd, Fluorescencia, Leishmania, mCherry, RICET\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/genetica-y-su-manipulacion#listItem\",\"name\":\"GEN\\u00c9TICA Y SU MANIPULACI\\u00d3N\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/genetica-y-su-manipulacion#listItem\",\"position\":2,\"name\":\"GEN\\u00c9TICA Y SU MANIPULACI\\u00d3N\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/genetica-y-su-manipulacion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678#listItem\",\"name\":\"Fluorescencia en la mejora de la experimentaci\\u00f3n animal\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678#listItem\",\"position\":3,\"name\":\"Fluorescencia en la mejora de la experimentaci\\u00f3n animal\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/genetica-y-su-manipulacion#listItem\",\"name\":\"GEN\\u00c9TICA Y SU MANIPULACI\\u00d3N\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\",\"name\":\"Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Biolog\\u00eda molecular y celular. Bioqu\\u00edmica. Biomedicina\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia\",\"name\":\"JAL\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c372814f0d0c3b98b41d9cafe3f11955?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"JAL\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678\",\"name\":\"Fluorescencia en la mejora de la experimentaci\\u00f3n animal - Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Cuatro grupos de investigaci\\u00f3n de la Red de Enfermedades Tropicales (RICET) han desarrollado unas prote\\u00ednas fluorescentes rojas a partir de la luci\\u00e9rnaga y un p\\u00f3lipo marino que permitir\\u00e1n evaluar la patogenicidad in vivo a tiempo real, realizar estudios de cribado de f\\u00e1rmacos de alto rendimiento y constituyen un sistema de alerta en ciertas enfermedades mucho m\\u00e1s precoz que los propios s\\u00edntomas.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/04\\\/06\\\/132678#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"datePublished\":\"2013-04-06T02:20:04+01:00\",\"dateModified\":\"2013-04-14T23:34:39+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/\",\"name\":\"Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Biolog\\u00eda molecular y celular. Bioqu\\u00edmica. Biomedicina\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Fluorescencia en la mejora de la experimentaci\u00f3n animal - Bio (Ciencia+Tecnolog\u00eda)","description":"Cuatro grupos de investigaci\u00f3n de la Red de Enfermedades Tropicales (RICET) han desarrollado unas prote\u00ednas fluorescentes rojas a partir de la luci\u00e9rnaga y un p\u00f3lipo marino que permitir\u00e1n evaluar la patogenicidad in vivo a tiempo real, realizar estudios de cribado de f\u00e1rmacos de alto rendimiento y constituyen un sistema de alerta en ciertas enfermedades mucho m\u00e1s precoz que los propios s\u00edntomas.","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678#blogposting","name":"Fluorescencia en la mejora de la experimentaci\u00f3n animal - Bio (Ciencia+Tecnolog\u00eda)","headline":"Fluorescencia en la mejora de la experimentaci\u00f3n animal","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2013\/04\/RICET.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678\/#articleImage","width":647,"height":231,"caption":"Prote\u00edna fluorescente roja a trav\u00e9s de la piel..."},"datePublished":"2013-04-06T02:20:04+01:00","dateModified":"2013-04-14T23:34:39+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678#webpage"},"articleSection":"GEN\u00c9TICA Y SU MANIPULACI\u00d3N, POPURR\u00cd, Fluorescencia, Leishmania, mCherry, RICET"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/genetica-y-su-manipulacion#listItem","name":"GEN\u00c9TICA Y SU MANIPULACI\u00d3N"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/genetica-y-su-manipulacion#listItem","position":2,"name":"GEN\u00c9TICA Y SU MANIPULACI\u00d3N","item":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/genetica-y-su-manipulacion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678#listItem","name":"Fluorescencia en la mejora de la experimentaci\u00f3n animal"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678#listItem","position":3,"name":"Fluorescencia en la mejora de la experimentaci\u00f3n animal","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/genetica-y-su-manipulacion#listItem","name":"GEN\u00c9TICA Y SU MANIPULACI\u00d3N"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization","name":"Bio (Ciencia+Tecnolog\u00eda)","description":"Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia","name":"JAL","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c372814f0d0c3b98b41d9cafe3f11955?s=96&d=mm&r=g","width":96,"height":96,"caption":"JAL"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678","name":"Fluorescencia en la mejora de la experimentaci\u00f3n animal - Bio (Ciencia+Tecnolog\u00eda)","description":"Cuatro grupos de investigaci\u00f3n de la Red de Enfermedades Tropicales (RICET) han desarrollado unas prote\u00ednas fluorescentes rojas a partir de la luci\u00e9rnaga y un p\u00f3lipo marino que permitir\u00e1n evaluar la patogenicidad in vivo a tiempo real, realizar estudios de cribado de f\u00e1rmacos de alto rendimiento y constituyen un sistema de alerta en ciertas enfermedades mucho m\u00e1s precoz que los propios s\u00edntomas.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"datePublished":"2013-04-06T02:20:04+01:00","dateModified":"2013-04-14T23:34:39+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/","name":"Bio (Ciencia+Tecnolog\u00eda)","description":"Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Bio (Ciencia+Tecnolog\u00eda) - Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","og:type":"article","og:title":"Fluorescencia en la mejora de la experimentaci\u00f3n animal - Bio (Ciencia+Tecnolog\u00eda)","og:description":"Cuatro grupos de investigaci\u00f3n de la Red de Enfermedades Tropicales (RICET) han desarrollado unas prote\u00ednas fluorescentes rojas a partir de la luci\u00e9rnaga y un p\u00f3lipo marino que permitir\u00e1n evaluar la patogenicidad in vivo a tiempo real, realizar estudios de cribado de f\u00e1rmacos de alto rendimiento y constituyen un sistema de alerta en ciertas enfermedades mucho m\u00e1s precoz que los propios s\u00edntomas.","og:url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678","og:image":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","article:published_time":"2013-04-06T01:20:04+00:00","article:modified_time":"2013-04-14T22:34:39+00:00","twitter:card":"summary","twitter:title":"Fluorescencia en la mejora de la experimentaci\u00f3n animal - Bio (Ciencia+Tecnolog\u00eda)","twitter:description":"Cuatro grupos de investigaci\u00f3n de la Red de Enfermedades Tropicales (RICET) han desarrollado unas prote\u00ednas fluorescentes rojas a partir de la luci\u00e9rnaga y un p\u00f3lipo marino que permitir\u00e1n evaluar la patogenicidad in vivo a tiempo real, realizar estudios de cribado de f\u00e1rmacos de alto rendimiento y constituyen un sistema de alerta en ciertas enfermedades mucho m\u00e1s precoz que los propios s\u00edntomas.","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"132678","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-04 05:56:25","updated":"2026-05-26 17:09:42","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/genetica-y-su-manipulacion\" title=\"GEN\u00c9TICA Y SU MANIPULACI\u00d3N\">GEN\u00c9TICA Y SU MANIPULACI\u00d3N<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFluorescencia en la mejora de la experimentaci\u00f3n animal\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia"},{"label":"GEN\u00c9TICA Y SU MANIPULACI\u00d3N","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/genetica-y-su-manipulacion"},{"label":"Fluorescencia en la mejora de la experimentaci\u00f3n animal","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/04\/06\/132678"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/132678"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/comments?post=132678"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/132678\/revisions"}],"predecessor-version":[{"id":132686,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/132678\/revisions\/132686"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/media?parent=132678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/categories?post=132678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/tags?post=132678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}