{"id":132832,"date":"2013-11-09T02:46:43","date_gmt":"2013-11-09T01:46:43","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/?p=132832"},"modified":"2013-11-18T15:06:32","modified_gmt":"2013-11-18T14:06:32","slug":"semana-de-la-ciencia-2013-desde-el-dcc-del-cbmso","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832","title":{"rendered":"Semana de la Ciencia 2013: desde el DCC del CBMSO"},"content":{"rendered":"<p>Para que los progresos de la ciencia y la tecnolog\u00eda respondan a las necesidades de los ciudadanos y cuenten con su adhesi\u00f3n, es necesario que dispongan de una informaci\u00f3n comprensible y de calidad, as\u00ed como de un acceso libre a esta cultura cient\u00edfica. <a href=\"http:\/\/www.rtve.es\/noticias\/20131108\/semana-ciencia-2013-acerca-investigacion-ciudadania-noviembre\/786841.shtml\">La Semana de la Ciencia<\/a> es uno de los acontecimientos m\u00e1s importantes de ciencia en Europa. Esta XIII edici\u00f3n acoge a m\u00e1s de 600 organismos implicados con el objetivo com\u00fan de acercar la ciencia y la tecnolog\u00eda a los ciudadanos.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.ngmadridstore.com\/ES\/exhibits\/20131112.html\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/encrypted-tbn2.gstatic.com\/images?q=tbn:ANd9GcTjhVAPeyk61pmtgWEGlLctm--R2Hcxkt95vC-fxRzjmM3DzgRB\" alt=\"\" width=\"189\" height=\"267\" \/><\/a><\/p>\n<p><!--more-->Dicha Semana, que siempre consta de 14 d\u00edas, tendr\u00e1 lugar ya desde el 4 al 17 de noviembre bajo el lema \u201cInvestigaci\u00f3n, participaci\u00f3n y progreso\u201d. <a href=\"http:\/\/www.madrimasd.org\/semanaciencia\/2013\/\">Solo en la Comunidad de Madrid<\/a>, a trav\u00e9s de la <a href=\"http:\/\/www.madrimasd.org\/\">Fundaci\u00f3n madri+d<\/a> \u2013Direcci\u00f3n General de Universidades e Investigaci\u00f3n- y con el objetivo de acercar la ciencia y la tecnolog\u00eda a los ciudadanos se llevar\u00e1n a cabo m\u00e1s de 900 actividades gratuitas con la participaci\u00f3n de alrededor de 3.000 cient\u00edficos de todas las disciplinas.<\/p>\n<p>Las actividades gratuitas que ofrece la <a href=\"http:\/\/www.madrimasd.org\/semanaciencia\/2013\/\">XIII Semana de la Ciencia<\/a> ponen al alcance de todos la ciencia y la tecnolog\u00eda, desde el mundo de las nuevas tecnolog\u00edas en materiales hasta las \u00faltimas investigaciones en rob\u00f3tica; desde las m\u00e1s recientes investigaciones en nuevas pol\u00edticas energ\u00e9ticas hasta los \u00faltimos avances en la astronom\u00eda, el transporte, las comunicaciones, las leyes del suelo o la arqueolog\u00eda. Todo un mundo de conocimiento de la mano de los mejores expertos.<\/p>\n<p>En cuanto a las instituciones implicadas se encuentran centros de investigaci\u00f3n, universidades, asociaciones cient\u00edficas, administraciones p\u00fablicas, fundaciones, museos, hospitales, empresas, asociaciones ciudadanas y ONG que ofrecer\u00e1n para todos los p\u00fablicos jornadas de puertas abiertas, visitas guiadas, mesas redondas, conferencias cursos, talleres, exposiciones y sesiones de planetario, entre otras actividades.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/cienciaconchocolate.blogspot.com.es\/2013\/10\/actividades-de-la-semana-de-la-ciencia.html\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/3.bp.blogspot.com\/-UzsCWGnRTlM\/UnJZXivHW9I\/AAAAAAAABpA\/j6nzNGk7FFY\/s1600\/Semana+de+la+Ciencia+2013.jpg\" alt=\"\" width=\"461\" height=\"614\" \/><\/a><\/p>\n<p>Finalmente, mencionar las dos actividades que ofrece el CBMSO: \u201c<a href=\"http:\/\/www.ngmadridstore.com\/ES\/exhibits\/20131112.html\">La ciencia en el cine. El cine en la ciencia<\/a>\u201d y \u201c<a href=\"http:\/\/www.cbm.uam.es\/ccientifica\/SEMANAdelaCIENCIA2013\/index.htm\">De moscas, peces y otros seres: buscando el origen de enfermedades cong\u00e9nitas en el hombre<\/a>\u201d. \u00a1No te las pierdas!<\/p>\n<p><a href=\"http:\/\/www.uam.es\/personal_pdi\/ciencias\/jolope\/\">JAL (DCC-CBMSO)<\/a><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"http:\/\/www.cbm.uam.es\/ccientifica\/Enlaces.html\">DIVULGACI\u00d3N CIENT\u00cdFICA DEL 09 DE NOVIEMBRE DE 2013<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><object width=\"450\" height=\"360\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"src\" value=\"http:\/\/mediateca.madrimasd.org\/videoma\/includes\/flvplayer\/flvplayer_mi+d.swf\" \/><param name=\"allowfullscreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"flashvars\" value=\"&amp;file=172_17_99_151_videos_2419&amp;image=http:\/\/mediateca.madrimasd.org\/videoma\/web_publico\/preview_player.php?videoid=2419\" \/><embed width=\"450\" height=\"360\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/mediateca.madrimasd.org\/videoma\/includes\/flvplayer\/flvplayer_mi+d.swf\" allowfullscreen=\"true\" allowscriptaccess=\"always\" flashvars=\"&amp;file=172_17_99_151_videos_2419&amp;image=http:\/\/mediateca.madrimasd.org\/videoma\/web_publico\/preview_player.php?videoid=2419\" \/><\/object><\/p>\n<p style=\"text-align: center;\">Esta semana mi+d<sup>tv<\/sup> tratar\u00e1 sobre la<strong> XIII Semana de la Ciencia de Madrid<\/strong>; nuevos estudios sobre<strong> las causas de la enfermedad de Crohn<\/strong> y el uso de <strong>paneles solares en la climatizaci\u00f3n<\/strong>.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/madrimasd-tv\/default.asp\">MADRI+D TV<\/a>\u00a0(Divulgaci\u00f3n cient\u00edfica con cara, e im\u00e1genes, en 3 minutos)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/podcast\/radio-5\/entre-probetas\/\">ENTRE PROBETAS<\/a>\u00a0(P\u00edldoras cient\u00edficas en 2 minutos). Radio 5<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/alacarta\/audios\/eureka\/\">EUREKA<\/a>\u00a0Radio Exterior de Espa\u00f1a<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/podcast\/radio-5\/a-hombros-de-gigantes\/\">A HOMBROS DE GIGANTES<\/a>\u00a0RNE<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.ivoox.com\/perfil-astrolabio_aj_69799_1.html\">RADIO UTOP\u00cdA<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/alacarta\/videos\/uned\/\">UNEDtv<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/home.php?#!\/pages\/Departamento-de-Cultura-Cientifica-Centro-de-Biologia-Molecular\/148445718520196\">FACEBOOK<\/a>\u00a0(Jos\u00e9 Antonio L\u00f3pez-Guerrero)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/?ref=logo#!\/pages\/Departamento-de-Cultura-Cient%C3%ADfica-Centro-de-Biolog%C3%ADa-Molecular\/148445718520196\">FACEBOOK<\/a>\u00a0(Departamento de Cultura Cient\u00edfica -Centro de Biolog\u00eda Molecular)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/twitter.com\/#!\/JALGUERRERO\">TWITTER<\/a>\u00a0(JALGUERRERO)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/twitter.com\/#!\/DCCientificaCBM\">TWITTER<\/a>\u00a0(DCCientificaCBM)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.linkedin.com\/home?trk=hb_tab_home_top\">LINKED-IN\u00a0<\/a>(Jal Guerrero)<\/p>\n","protected":false},"excerpt":{"rendered":"<p> La Semana de la Ciencia es uno de los acontecimientos m\u00e1s importantes de ciencia en Europa. Esta XIII edici\u00f3n acoge a m\u00e1s de 600 organismos implicados con el objetivo com\u00fan de acercar la ciencia y la tecnolog\u00eda a los ciudadanos.<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[2482],"tags":[25254],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Semana de la Ciencia es uno de los acontecimientos m\u00e1s importantes de ciencia en Europa. Esta XIII edici\u00f3n acoge a m\u00e1s de 600 organismos implicados con el objetivo com\u00fan de acercar la ciencia y la tecnolog\u00eda a los ciudadanos.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"JAL\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bio (Ciencia+Tecnolog\u00eda) - Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Semana de la Ciencia 2013: desde el DCC del CBMSO - Bio (Ciencia+Tecnolog\u00eda)\" \/>\n\t\t<meta property=\"og:description\" content=\"La Semana de la Ciencia es uno de los acontecimientos m\u00e1s importantes de ciencia en Europa. Esta XIII edici\u00f3n acoge a m\u00e1s de 600 organismos implicados con el objetivo com\u00fan de acercar la ciencia y la tecnolog\u00eda a los ciudadanos.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-11-09T01:46:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-11-18T14:06:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Semana de la Ciencia 2013: desde el DCC del CBMSO - Bio (Ciencia+Tecnolog\u00eda)\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Semana de la Ciencia es uno de los acontecimientos m\u00e1s importantes de ciencia en Europa. Esta XIII edici\u00f3n acoge a m\u00e1s de 600 organismos implicados con el objetivo com\u00fan de acercar la ciencia y la tecnolog\u00eda a los ciudadanos.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832#blogposting\",\"name\":\"Semana de la Ciencia 2013: desde el DCC del CBMSO - Bio (Ciencia+Tecnolog\\u00eda)\",\"headline\":\"Semana de la Ciencia 2013: desde el DCC del CBMSO\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/encrypted-tbn2.gstatic.com\\\/images?q=tbn:ANd9GcTjhVAPeyk61pmtgWEGlLctm--R2Hcxkt95vC-fxRzjmM3DzgRB\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832\\\/#articleImage\"},\"datePublished\":\"2013-11-09T02:46:43+01:00\",\"dateModified\":\"2013-11-18T15:06:32+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832#webpage\"},\"articleSection\":\"DIVULGACI\\u00d3N Y MEDIOS, Semana de la Ciencia 2013\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/divulgacion-y-medios#listItem\",\"name\":\"DIVULGACI\\u00d3N Y MEDIOS\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/divulgacion-y-medios#listItem\",\"position\":2,\"name\":\"DIVULGACI\\u00d3N Y MEDIOS\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/divulgacion-y-medios\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832#listItem\",\"name\":\"Semana de la Ciencia 2013: desde el DCC del CBMSO\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832#listItem\",\"position\":3,\"name\":\"Semana de la Ciencia 2013: desde el DCC del CBMSO\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/divulgacion-y-medios#listItem\",\"name\":\"DIVULGACI\\u00d3N Y MEDIOS\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\",\"name\":\"Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Biolog\\u00eda molecular y celular. Bioqu\\u00edmica. Biomedicina\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia\",\"name\":\"JAL\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c372814f0d0c3b98b41d9cafe3f11955?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"JAL\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832\",\"name\":\"Semana de la Ciencia 2013: desde el DCC del CBMSO - Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"La Semana de la Ciencia es uno de los acontecimientos m\\u00e1s importantes de ciencia en Europa. Esta XIII edici\\u00f3n acoge a m\\u00e1s de 600 organismos implicados con el objetivo com\\u00fan de acercar la ciencia y la tecnolog\\u00eda a los ciudadanos.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2013\\\/11\\\/09\\\/132832#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"datePublished\":\"2013-11-09T02:46:43+01:00\",\"dateModified\":\"2013-11-18T15:06:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/\",\"name\":\"Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Biolog\\u00eda molecular y celular. Bioqu\\u00edmica. Biomedicina\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Semana de la Ciencia 2013: desde el DCC del CBMSO - Bio (Ciencia+Tecnolog\u00eda)","description":"La Semana de la Ciencia es uno de los acontecimientos m\u00e1s importantes de ciencia en Europa. Esta XIII edici\u00f3n acoge a m\u00e1s de 600 organismos implicados con el objetivo com\u00fan de acercar la ciencia y la tecnolog\u00eda a los ciudadanos.","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832#blogposting","name":"Semana de la Ciencia 2013: desde el DCC del CBMSO - Bio (Ciencia+Tecnolog\u00eda)","headline":"Semana de la Ciencia 2013: desde el DCC del CBMSO","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/encrypted-tbn2.gstatic.com\/images?q=tbn:ANd9GcTjhVAPeyk61pmtgWEGlLctm--R2Hcxkt95vC-fxRzjmM3DzgRB","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832\/#articleImage"},"datePublished":"2013-11-09T02:46:43+01:00","dateModified":"2013-11-18T15:06:32+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832#webpage"},"articleSection":"DIVULGACI\u00d3N Y MEDIOS, Semana de la Ciencia 2013"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/divulgacion-y-medios#listItem","name":"DIVULGACI\u00d3N Y MEDIOS"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/divulgacion-y-medios#listItem","position":2,"name":"DIVULGACI\u00d3N Y MEDIOS","item":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/divulgacion-y-medios","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832#listItem","name":"Semana de la Ciencia 2013: desde el DCC del CBMSO"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832#listItem","position":3,"name":"Semana de la Ciencia 2013: desde el DCC del CBMSO","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/divulgacion-y-medios#listItem","name":"DIVULGACI\u00d3N Y MEDIOS"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization","name":"Bio (Ciencia+Tecnolog\u00eda)","description":"Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia","name":"JAL","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c372814f0d0c3b98b41d9cafe3f11955?s=96&d=mm&r=g","width":96,"height":96,"caption":"JAL"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832","name":"Semana de la Ciencia 2013: desde el DCC del CBMSO - Bio (Ciencia+Tecnolog\u00eda)","description":"La Semana de la Ciencia es uno de los acontecimientos m\u00e1s importantes de ciencia en Europa. Esta XIII edici\u00f3n acoge a m\u00e1s de 600 organismos implicados con el objetivo com\u00fan de acercar la ciencia y la tecnolog\u00eda a los ciudadanos.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"datePublished":"2013-11-09T02:46:43+01:00","dateModified":"2013-11-18T15:06:32+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/","name":"Bio (Ciencia+Tecnolog\u00eda)","description":"Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Bio (Ciencia+Tecnolog\u00eda) - Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","og:type":"article","og:title":"Semana de la Ciencia 2013: desde el DCC del CBMSO - Bio (Ciencia+Tecnolog\u00eda)","og:description":"La Semana de la Ciencia es uno de los acontecimientos m\u00e1s importantes de ciencia en Europa. Esta XIII edici\u00f3n acoge a m\u00e1s de 600 organismos implicados con el objetivo com\u00fan de acercar la ciencia y la tecnolog\u00eda a los ciudadanos.","og:url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832","og:image":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","article:published_time":"2013-11-09T01:46:43+00:00","article:modified_time":"2013-11-18T14:06:32+00:00","twitter:card":"summary","twitter:title":"Semana de la Ciencia 2013: desde el DCC del CBMSO - Bio (Ciencia+Tecnolog\u00eda)","twitter:description":"La Semana de la Ciencia es uno de los acontecimientos m\u00e1s importantes de ciencia en Europa. Esta XIII edici\u00f3n acoge a m\u00e1s de 600 organismos implicados con el objetivo com\u00fan de acercar la ciencia y la tecnolog\u00eda a los ciudadanos.","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"132832","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-08 08:38:23","updated":"2026-05-26 17:13:43","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/divulgacion-y-medios\" title=\"DIVULGACI\u00d3N Y MEDIOS\">DIVULGACI\u00d3N Y MEDIOS<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSemana de la Ciencia 2013: desde el DCC del CBMSO\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia"},{"label":"DIVULGACI\u00d3N Y MEDIOS","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/divulgacion-y-medios"},{"label":"Semana de la Ciencia 2013: desde el DCC del CBMSO","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2013\/11\/09\/132832"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/132832"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/comments?post=132832"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/132832\/revisions"}],"predecessor-version":[{"id":132839,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/132832\/revisions\/132839"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/media?parent=132832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/categories?post=132832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/tags?post=132832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}