{"id":133127,"date":"2015-01-18T17:44:18","date_gmt":"2015-01-18T16:44:18","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/?p=133127"},"modified":"2015-02-01T20:36:40","modified_gmt":"2015-02-01T19:36:40","slug":"arte-con-vacuna-la-vacuna-en-el-arte","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127","title":{"rendered":"Arte con vacuna. La vacuna en el arte"},"content":{"rendered":"<p>A pesar de ciertos grupos y sectores de la Sociedad, quiero pensar que mal informados, hay que decirlo alto y claro: nada ha salvado m\u00e1s vidas en la historia de la humanidad ni ha supuesto un punto de inflexi\u00f3n en la longevidad tan claro como <a href=\"http:\/\/www.vacunas.org\/\">la vacunaci\u00f3n<\/a>. Desde 1796, con el <a href=\"http:\/\/es.wikipedia.org\/wiki\/Edward_Jenner\">desarrollo de la vacunaci\u00f3n moderna<\/a>, que ha hecho desaparecer, entre otras cosas, <a href=\"http:\/\/es.wikipedia.org\/wiki\/Viruela\">la viruela<\/a> de la faz de la Tierra, la inmunizaci\u00f3n preventiva ha permitido superar los horrores que pod\u00edan suponer la infecci\u00f3n con virus como el de la <a href=\"http:\/\/www2.cbm.uam.es\/jalopez\/CLASES2002\/CLASES0203\/Tema24.htm\">poliomielitis, sarampi\u00f3n o, incluso, el papiloma humano<\/a>. Pero hoy no toca hablar de aquellos que niegan esta realidad y se ponen en peligro a s\u00ed mismos y a sus hijos\u2026 Hoy quer\u00eda hablar de\u2026 arte.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/artofsavingalife.com\/artists\/alexia-sinclair\/\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/artofsavingalife.com\/wp-content\/uploads\/2014\/12\/Alexia_hero_2-1024x768.jpg\" alt=\"\" width=\"491\" height=\"369\" \/><\/a><\/p>\n<p><!--more-->Con el patrocinio de la <a href=\"http:\/\/www.gatesfoundation.org\/es\">Fundaci\u00f3n Gates<\/a>, m\u00e1s de 30 artistas han expresado con su buen oficio las virtudes de la vacunaci\u00f3n creando el proyecto denominado \u201c<a href=\"http:\/\/www.vacunas.org\/es\/info-profesionales\/noticias\/119494-el-arte-de-salvar-una-vida\">El arte de salvar una vida<\/a>\u201d, proyecto multidisciplinar para sensibilizar al ciudadano y ciudadana sobre las ventajas de la vacunaci\u00f3n y la necesidad de utilizar esta valiosa herramienta para la erradicaci\u00f3n de enfermedades infecciosas. Por supuesto, el proyecto tambi\u00e9n busca la obtenci\u00f3n de fondos para investigaci\u00f3n\u2026<\/p>\n<p><a href=\"http:\/\/elpais.com\/elpais\/2015\/01\/13\/album\/1421165904_955165.html#1421165904_955165_1421233810\">Fotograf\u00edas, cuadros y otras obras<\/a> de arte reflejan escenas hist\u00f3ricas de algunos de los principales hitos cient\u00edficos sobre la vacuna como, por ejemplo, el momento en el que el doctor Edward Jenner vacun\u00f3 a un ni\u00f1o de ocho a\u00f1os con la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Vacuna\">viruela vacuna<\/a>, all\u00e1 por 1796. La Fundaci\u00f3n Bill y Malinda Gates ha enfrentado simb\u00f3licamente a grandes artistas internacionales con determinadas enfermedades infecciosas que todav\u00eda hoy producen estragos en ciertas zonas desfavorecidas del planeta. <a href=\"http:\/\/elpais.com\/elpais\/2015\/01\/13\/planeta_futuro\/1421163721_380017.html\">Simplemente, como bot\u00f3n de muestra<\/a>, podemos citar a la fot\u00f3grafa <a href=\"http:\/\/es.wikipedia.org\/wiki\/Annie_Leibovitz\">Annie Leibovitz<\/a>, la escritora nigeriana <a href=\"http:\/\/es.wikipedia.org\/wiki\/Chimamanda_Ngozi_Adichie\">Chimamanda Ngozi Adichie<\/a> o, incluso, el grupo musical <a href=\"http:\/\/playingforchange.com\/\">Playing for Change<\/a>\u2026<\/p>\n<p>El resultado es una vichyssoise multidisciplinar con tropezones musicales, fotogr\u00e1ficos, cinematogr\u00e1ficos o escult\u00f3ricos que pretenden, desde las redes y los medios, provocar la reflexi\u00f3n y concienciaci\u00f3n de todos sobre la importancia de la vacunaci\u00f3n. La etiqueta de la campa\u00f1a en las redes sociales ser\u00e1 #VaccinesWork y las obras estar\u00e1n disponibles en la <a href=\"http:\/\/artofsavingalife.com\/\">web artofsavingalife.com<\/a>. Desde ya deseo el mayor de los \u00e9xitos a esta interesante iniciativa\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>Por cierto, seg\u00fan se publica en un intenso y extenso art\u00edculo en <a href=\"http:\/\/elpais.com\/elpais\/2015\/01\/13\/planeta_futuro\/1421163721_380017.html\">El Pa\u00eds<\/a>, aqu\u00ed van unos datos sobre inmunizaci\u00f3n:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Se estima que la inmunizaci\u00f3n evita entre 2 y 3 millones de muertes cada a\u00f1o.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 M\u00e1s de un mill\u00f3n de lactantes y ni\u00f1os de corta edad mueren cada a\u00f1o a causa de la enfermedad neumoc\u00f3cica o de la diarrea por rotavirus.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La mortalidad mundial por sarampi\u00f3n se ha reducido en un 74%.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Las defunciones por t\u00e9tanos neonatal han disminuido seg\u00fan las estimaciones hasta 59.000, desde las 790.000 muertes registradas en 1988.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La inmunizaci\u00f3n est\u00e1 llegando a m\u00e1s ni\u00f1os que nunca. En 2010, se estima que 109 millones de ni\u00f1os menores de un a\u00f1o recibieron tres dosis de la vacuna contra difteria-t\u00e9tanos-tos ferina (DTP3).<\/p>\n<p>Fuente: Organizaci\u00f3n Mundial de la Salud<\/p>\n<p><a href=\"http:\/\/www.uam.es\/personal_pdi\/ciencias\/jolope\/\">JAL (DCC-CBMSO)<\/a><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"http:\/\/www.cbm.uam.es\/ccientifica\/Enlaces.html\">DIVULGACI\u00d3N CIENT\u00cdFICA DEL 18 DE ENERO DE 2015<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/madrimasd-tv\/default.asp\"><strong>Mi+dTV y UNEDtv<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><object width=\"450\" height=\"360\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"src\" value=\"http:\/\/mediateca.madrimasd.org\/videoma\/includes\/flvplayer\/flvplayer_mi+d.swf\" \/><param name=\"allowfullscreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"flashvars\" value=\"&amp;file=172_17_99_151_videos_2503&amp;image=http:\/\/mediateca.madrimasd.org\/videoma\/web_publico\/preview_player.php?videoid=2503\" \/><embed width=\"450\" height=\"360\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/mediateca.madrimasd.org\/videoma\/includes\/flvplayer\/flvplayer_mi+d.swf\" allowfullscreen=\"true\" allowscriptaccess=\"always\" flashvars=\"&amp;file=172_17_99_151_videos_2503&amp;image=http:\/\/mediateca.madrimasd.org\/videoma\/web_publico\/preview_player.php?videoid=2503\" \/><\/object><\/p>\n<div style=\"text-align: center;\">\n<p>\u00a0Esta semana mi+dtv tratar\u00e1 sobre <strong>el efecto del cambio clim\u00e1tico en la vida<\/strong>; la caracterizaci\u00f3n de un <strong>virus gigante<\/strong> y antiguo y el efecto beneficioso de algunas <strong>bacterias en la elaboraci\u00f3n del vino<\/strong>.<\/p>\n<\/div>\n<div style=\"text-align: center;\">\n<div style=\"width: 100%; padding-top: 74px; position: relative; border-bottom: 1px solid #aaa; display: inline-block; background: rgba(255,255,255,0.9);\"><iframe loading=\"lazy\" style=\"width: 100%; height: 37px; position: absolute; left: 0; top: 0; overflow: hidden;\" name=\"Virus para comenzar la temporada\" src=\"http:\/\/www.rtve.es\/drmn\/embed\/audio\/2740666\" frameborder=\"0\" scrolling=\"no\" width=\"320\" height=\"240\"><\/iframe><\/p>\n<div style=\"position: absolute; bottom: 0; left: 0; font-family: arial,helvetica,sans-serif; font-size: 12px; line-height: 1.833; display: inline-block; padding: 5px 0 5px 10px;\"><span style=\"float: left; margin-right: 10px;\"><img decoding=\"async\" style=\"height: 20px; width: auto; background: transparent; padding: 0; margin: 0;\" src=\"http:\/\/img.irtve.es\/css\/rtve.commons\/rtve.header.footer\/i\/logoRTVEes.png\" alt=\"\" \/><\/span> <a style=\"color: #333; font-weight: bold;\" title=\"Virus para comenzar la temporada\" href=\"http:\/\/www.rtve.es\/alacarta\/audios\/entre-probetas\/entre-probetas-virus-para-comenzar-temporada-03-04-14\/2740666\/\"><strong>Virus para comenzar la temporada<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/madrimasd-tv\/default.asp\">MADRI+D TV<\/a>\u00a0(Divulgaci\u00f3n cient\u00edfica con cara, e im\u00e1genes, en 3 minutos)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/podcast\/radio-5\/entre-probetas\/\">ENTRE PROBETAS<\/a>\u00a0(P\u00edldoras cient\u00edficas en 2 minutos). Radio 5<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/alacarta\/audios\/eureka\/\">EUREKA<\/a>\u00a0Radio Exterior de Espa\u00f1a<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/podcast\/radio-5\/a-hombros-de-gigantes\/\">A HOMBROS DE GIGANTES<\/a>\u00a0RNE<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.ivoox.com\/perfil-astrolabio_aj_69799_1.html\">RADIO UTOP\u00cdA<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/alacarta\/videos\/uned\/\">UNEDtv<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/home.php?#!\/pages\/Departamento-de-Cultura-Cientifica-Centro-de-Biologia-Molecular\/148445718520196\">FACEBOOK<\/a>\u00a0(Jos\u00e9 Antonio L\u00f3pez-Guerrero)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/?ref=logo#!\/pages\/Departamento-de-Cultura-Cient%C3%ADfica-Centro-de-Biolog%C3%ADa-Molecular\/148445718520196\">FACEBOOK<\/a>\u00a0(Departamento de Cultura Cient\u00edfica -Centro de Biolog\u00eda Molecular)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/twitter.com\/#!\/JALGUERRERO\">TWITTER<\/a>\u00a0(JALGUERRERO)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/twitter.com\/#!\/DCCientificaCBM\">TWITTER<\/a>\u00a0(DCCientificaCBM)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.linkedin.com\/home?trk=hb_tab_home_top\">LINKED-IN\u00a0<\/a>(Jal Guerrero)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de ciertos grupos y sectores de la Sociedad, quiero pensar que mal informados, hay que decirlo alto y claro: nada ha salvado m\u00e1s vidas en la historia de la humanidad ni ha supuesto un punto de inflexi\u00f3n en la longevidad tan claro como la vacunaci\u00f3n&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[2482,77,540,536],"tags":[25400,808],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"A pesar de ciertos grupos y sectores de la Sociedad, quiero pensar que mal informados, hay que decirlo alto y claro: nada ha salvado m\u00e1s vidas en la historia de la humanidad ni ha supuesto un punto de inflexi\u00f3n en la longevidad tan claro como la vacunaci\u00f3n...\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"JAL\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bio (Ciencia+Tecnolog\u00eda) - Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Arte con vacuna. La vacuna en el arte - Bio (Ciencia+Tecnolog\u00eda)\" \/>\n\t\t<meta property=\"og:description\" content=\"A pesar de ciertos grupos y sectores de la Sociedad, quiero pensar que mal informados, hay que decirlo alto y claro: nada ha salvado m\u00e1s vidas en la historia de la humanidad ni ha supuesto un punto de inflexi\u00f3n en la longevidad tan claro como la vacunaci\u00f3n...\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-01-18T16:44:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-02-01T19:36:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Arte con vacuna. La vacuna en el arte - Bio (Ciencia+Tecnolog\u00eda)\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A pesar de ciertos grupos y sectores de la Sociedad, quiero pensar que mal informados, hay que decirlo alto y claro: nada ha salvado m\u00e1s vidas en la historia de la humanidad ni ha supuesto un punto de inflexi\u00f3n en la longevidad tan claro como la vacunaci\u00f3n...\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127#blogposting\",\"name\":\"Arte con vacuna. La vacuna en el arte - Bio (Ciencia+Tecnolog\\u00eda)\",\"headline\":\"Arte con vacuna. La vacuna en el arte\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/artofsavingalife.com\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/Alexia_hero_2-1024x768.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127\\\/#articleImage\"},\"datePublished\":\"2015-01-18T17:44:18+01:00\",\"dateModified\":\"2015-02-01T20:36:40+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127#webpage\"},\"articleSection\":\"DIVULGACI\\u00d3N Y MEDIOS, EN RECUERDO..., POPURR\\u00cd, VIRUS EN GENERAL, Art of saving a life, vacunas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/general#listItem\",\"name\":\"EN RECUERDO...\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"EN RECUERDO...\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127#listItem\",\"name\":\"Arte con vacuna. La vacuna en el arte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127#listItem\",\"position\":3,\"name\":\"Arte con vacuna. La vacuna en el arte\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/general#listItem\",\"name\":\"EN RECUERDO...\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\",\"name\":\"Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Biolog\\u00eda molecular y celular. Bioqu\\u00edmica. Biomedicina\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia\",\"name\":\"JAL\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c372814f0d0c3b98b41d9cafe3f11955?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"JAL\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127\",\"name\":\"Arte con vacuna. La vacuna en el arte - Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"A pesar de ciertos grupos y sectores de la Sociedad, quiero pensar que mal informados, hay que decirlo alto y claro: nada ha salvado m\\u00e1s vidas en la historia de la humanidad ni ha supuesto un punto de inflexi\\u00f3n en la longevidad tan claro como la vacunaci\\u00f3n...\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2015\\\/01\\\/18\\\/133127#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"datePublished\":\"2015-01-18T17:44:18+01:00\",\"dateModified\":\"2015-02-01T20:36:40+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/\",\"name\":\"Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Biolog\\u00eda molecular y celular. Bioqu\\u00edmica. Biomedicina\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Arte con vacuna. La vacuna en el arte - Bio (Ciencia+Tecnolog\u00eda)","description":"A pesar de ciertos grupos y sectores de la Sociedad, quiero pensar que mal informados, hay que decirlo alto y claro: nada ha salvado m\u00e1s vidas en la historia de la humanidad ni ha supuesto un punto de inflexi\u00f3n en la longevidad tan claro como la vacunaci\u00f3n...","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127#blogposting","name":"Arte con vacuna. La vacuna en el arte - Bio (Ciencia+Tecnolog\u00eda)","headline":"Arte con vacuna. La vacuna en el arte","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/artofsavingalife.com\/wp-content\/uploads\/2014\/12\/Alexia_hero_2-1024x768.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127\/#articleImage"},"datePublished":"2015-01-18T17:44:18+01:00","dateModified":"2015-02-01T20:36:40+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127#webpage"},"articleSection":"DIVULGACI\u00d3N Y MEDIOS, EN RECUERDO..., POPURR\u00cd, VIRUS EN GENERAL, Art of saving a life, vacunas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general#listItem","name":"EN RECUERDO..."}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general#listItem","position":2,"name":"EN RECUERDO...","item":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127#listItem","name":"Arte con vacuna. La vacuna en el arte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127#listItem","position":3,"name":"Arte con vacuna. La vacuna en el arte","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general#listItem","name":"EN RECUERDO..."}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization","name":"Bio (Ciencia+Tecnolog\u00eda)","description":"Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia","name":"JAL","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c372814f0d0c3b98b41d9cafe3f11955?s=96&d=mm&r=g","width":96,"height":96,"caption":"JAL"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127","name":"Arte con vacuna. La vacuna en el arte - Bio (Ciencia+Tecnolog\u00eda)","description":"A pesar de ciertos grupos y sectores de la Sociedad, quiero pensar que mal informados, hay que decirlo alto y claro: nada ha salvado m\u00e1s vidas en la historia de la humanidad ni ha supuesto un punto de inflexi\u00f3n en la longevidad tan claro como la vacunaci\u00f3n...","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"datePublished":"2015-01-18T17:44:18+01:00","dateModified":"2015-02-01T20:36:40+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/","name":"Bio (Ciencia+Tecnolog\u00eda)","description":"Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Bio (Ciencia+Tecnolog\u00eda) - Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","og:type":"article","og:title":"Arte con vacuna. La vacuna en el arte - Bio (Ciencia+Tecnolog\u00eda)","og:description":"A pesar de ciertos grupos y sectores de la Sociedad, quiero pensar que mal informados, hay que decirlo alto y claro: nada ha salvado m\u00e1s vidas en la historia de la humanidad ni ha supuesto un punto de inflexi\u00f3n en la longevidad tan claro como la vacunaci\u00f3n...","og:url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127","og:image":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","article:published_time":"2015-01-18T16:44:18+00:00","article:modified_time":"2015-02-01T19:36:40+00:00","twitter:card":"summary","twitter:title":"Arte con vacuna. La vacuna en el arte - Bio (Ciencia+Tecnolog\u00eda)","twitter:description":"A pesar de ciertos grupos y sectores de la Sociedad, quiero pensar que mal informados, hay que decirlo alto y claro: nada ha salvado m\u00e1s vidas en la historia de la humanidad ni ha supuesto un punto de inflexi\u00f3n en la longevidad tan claro como la vacunaci\u00f3n...","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"133127","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-06 19:05:23","updated":"2026-05-26 17:24:23","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general\" title=\"EN RECUERDO...\">EN RECUERDO...<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArte con vacuna. La vacuna en el arte\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia"},{"label":"EN RECUERDO...","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general"},{"label":"Arte con vacuna. La vacuna en el arte","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2015\/01\/18\/133127"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/133127"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/comments?post=133127"}],"version-history":[{"count":4,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/133127\/revisions"}],"predecessor-version":[{"id":133142,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/133127\/revisions\/133142"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/media?parent=133127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/categories?post=133127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/tags?post=133127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}