{"id":133781,"date":"2017-07-23T18:32:58","date_gmt":"2017-07-23T17:32:58","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/?p=133781"},"modified":"2017-07-28T12:34:28","modified_gmt":"2017-07-28T11:34:28","slug":"el-exito-es-sobrevivir-a-toda-costa-mitocondrias","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781","title":{"rendered":"El \u00e9xito es sobrevivir a toda costa: Mitocondrias"},"content":{"rendered":"<p>Hace poco que se ha celebrado el <a href=\"https:\/\/www.ivoox.com\/a-hombros-gigantes-50-anos-de-audios-mp3_rf_19589751_1.html\">50 aniversario del art\u00edculo sobre el origen de las c\u00e9lulas eucariotas<\/a>, de <a href=\"https:\/\/www.britannica.com\/biography\/Lynn-Margulis\">Lynn Margulis<\/a> donde se comenta, entre otras muchas cosas, que las famosas <a href=\"https:\/\/es.wikipedia.org\/wiki\/Mitocondria\">mitocondrias<\/a> de nuestras c\u00e9lulas pudieron ser, miles de millones de a\u00f1os ha, bacterias independientes. Sea como fuere, estos org\u00e1nulos, las mitocondrias se han vuelto indispensables para la supervivencia de cualquier hijo de vecino\u2026<\/p>\n<figure style=\"width: 315px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.isepp.org\/Pages\/San%20Jose%2004-05\/MargulisSaganSJ.html\"><img decoding=\"async\" class=\" \" src=\"http:\/\/www.isepp.org\/Media\/Speaker%20Images\/04-05%20SJ%20Images\/MargulisCheadR.jpg\" alt=\"\" width=\"315\" height=\"334\" \/><\/a><figcaption class=\"wp-caption-text\">Lynn Margulis<\/figcaption><\/figure>\n<p><!--more-->Las mitocondrias son los org\u00e1nulos subcelulares que transforman m\u00e1s eficientemente la energ\u00eda contenida en los alimentos en energ\u00eda celular o <a href=\"https:\/\/es.wikipedia.org\/wiki\/Adenos%C3%ADn_trifosfato\">ATP<\/a>. Estos org\u00e1nulos son, adem\u00e1s, esenciales para muchos otros aspectos del metabolismo -hemo, urea, calcio, por ejemplo-, la detoxificaci\u00f3n celular -producci\u00f3n y eliminaci\u00f3n de especies reactivas de ox\u00edgeno- e, incluso, para el destino de las c\u00e9lulas, ya que juegan un papel esencial en su supervivencia o muerte. Por todo ello, su actividad y funci\u00f3n se optimiza y adapta a las demandas de los tipos celulares y tejidos que constituyen los organismos.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/elrincondelacienciaytecnologia.blogspot.com.es\/2011\/09\/mitocondrias.html\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/1.bp.blogspot.com\/-4h11QhcHTus\/ToAGL0MF6dI\/AAAAAAAAAZo\/xIP94MpoCvk\/s1600\/Las+mitocondrias.jpg\" alt=\"\" width=\"361\" height=\"281\" \/><\/a><\/p>\n<p>En condiciones de equilibrio, las mitocondrias se visualizan a trav\u00e9s del microscopio como una red o malla que interconecta los org\u00e1nulos. Esta red, sin embargo, es muy din\u00e1mica, siendo el resultado de continuos fen\u00f3menos de fusi\u00f3n y divisi\u00f3n. Aunque no siempre es la norma, la morfolog\u00eda de red y el remodelamiento interno de las mitocondrias son fundamentales para una mejor y mayor funcionalidad mitocondrial y celular.<\/p>\n<p>Un grupo de investigadores del CBMSO (CSIC-UAM), liderados por <a href=\"http:\/\/web4.cbm.uam.es\/joomla-rl\/index.php\/en\/scientific-departments\/cell-biology-and-immunology?id=1382\">Jos\u00e9 Mar\u00eda Izquierdo Ju\u00e1rez<\/a>, acaban de publicar un art\u00edculo cient\u00edfico en la revista <em><a href=\"http:\/\/mcb.asm.org\/content\/early\/2017\/06\/13\/MCB.00174-17?related-urls=yes&amp;legid=mcb;MCB.00174-17v1&amp;cited-by=yes&amp;legid=mcb;MCB.00174-17v1\">Molecular and Cellular Biology<\/a><\/em> de la Sociedad Americana de Microbiolog\u00eda, en el que se identifican y describen nuevos mecanismos moleculares a trav\u00e9s de los que se regulan las din\u00e1micas mitocondriales en c\u00e9lulas humanas. En concreto, han demostrado c\u00f3mo unas prote\u00ednas implicadas en respuestas de estr\u00e9s celular (<a href=\"http:\/\/mcb.asm.org\/content\/early\/2017\/06\/13\/MCB.00174-17?related-urls=yes&amp;legid=mcb;MCB.00174-17v1&amp;cited-by=yes&amp;legid=mcb;MCB.00174-17v1\">TIA1, TIAR y HuR<\/a>), son capaces de regular o modular, de forma opuesta, la din\u00e1mica y la funci\u00f3n mitocondrial. As\u00ed, de forma muy esquematizada, TIA1 y TIAR favorece la p\u00e9rdida de la funci\u00f3n mitocondrial, mientras que HuR favorecer\u00eda una mayor y m\u00e1s eficiente funci\u00f3n mitocondrial.<\/p>\n<p>Puede que te resulte algo densa esta informaci\u00f3n, pero la relevancia de las observaciones radica en que la desregulaci\u00f3n de la din\u00e1mica y la funci\u00f3n mitocondrial se asocia a situaciones fisiopatol\u00f3gicas vitales, que est\u00e1n en la base molecular de patolog\u00edas humanas tan graves como el c\u00e1ncer, la diabetes o las enfermedades cardiovasculares y neurodegenerativas. Por consiguiente, y seg\u00fan comenta <a href=\"http:\/\/mcb.asm.org\/content\/early\/2017\/06\/13\/MCB.00174-17?related-urls=yes&amp;legid=mcb;MCB.00174-17v1&amp;cited-by=yes&amp;legid=mcb;MCB.00174-17v1\">Isabel Mart\u00ednez Carrascoso<\/a>, primera autora de este trabajo, estas observaciones identifican \u201cunos actores a trav\u00e9s de los que se podr\u00eda incidir en alguna de estas situaciones para corregir o evitar el desarrollo de fenotipos celulares delet\u00e9reos\u201d.<\/p>\n<p>Por \u00faltimo, este estudio pone de manifiesto, una vez m\u00e1s, que la mitocondria en situaciones de estr\u00e9s desempe\u00f1a un papel fundamental en la biolog\u00eda y el destino celular, a trav\u00e9s de su dise\u00f1o y funci\u00f3n, permitiendo la adaptaci\u00f3n celular con una \u00fanica misi\u00f3n: sobrevivir. Por lo tanto, \u201cen Biolog\u00eda, quiz\u00e1 como en la vida, el \u00e9xito es siempre sobrevivir\u201d. Quien dice esto, es Jos\u00e9 Mar\u00eda Izquierdo Ju\u00e1rez, el jefe.<\/p>\n<p><a href=\"http:\/\/www.uam.es\/personal_pdi\/ciencias\/jolope\/\">JAL (DCC-CBMSO)<\/a><\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/web4.cbm.uam.es\/joomla-rl\/index.php\/es\/servicios\/cultura-cientifica?id=1175\">DIVULGACI\u00d3N CIENT\u00cdFICA DEL 23 DE JULIO DE 2017<\/a><\/p>\n<p style=\"text-align: center;\"><object width=\"450\" height=\"360\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"src\" value=\"http:\/\/mediateca.madrimasd.org\/videoma\/includes\/flvplayer\/flvplayer_mi+d.swf\" \/><param name=\"allowfullscreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"flashvars\" value=\"&amp;file=172_17_99_151_videos_2626&amp;image=http:\/\/mediateca.madrimasd.org\/videoma\/web_publico\/preview_player.php?videoid=2626\" \/><embed width=\"450\" height=\"360\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/mediateca.madrimasd.org\/videoma\/includes\/flvplayer\/flvplayer_mi+d.swf\" allowfullscreen=\"true\" allowscriptaccess=\"always\" flashvars=\"&amp;file=172_17_99_151_videos_2626&amp;image=http:\/\/mediateca.madrimasd.org\/videoma\/web_publico\/preview_player.php?videoid=2626\" \/><\/object><\/p>\n<p style=\"text-align: center;\">\u00a0Esta semana Mi+dTV comienza con presentaci\u00f3n de la\u00a0Conferencia Anual 2018 de la Asociaci\u00f3n Europea para el Compromiso Social de la Ciencia\u00a0(EUSEA, por sus siglas en ingl\u00e9s) organizada en colaboraci\u00f3n con la Fundaci\u00f3n para el Conocimiento madri+d. Mi+dTV\u00a0contin\u00faa con\u00a0el resultado de la \u00faltima encuesta sobre la percepci\u00f3n social de la ciencia\u00a0de Fundaci\u00f3n Espa\u00f1ola Para la Ciencia y la Tecnolog\u00eda (FECYT). Para finalizar, Mi+dTV\u00a0expone los posibles\u00a0nuevos biomarcadores tempranos contra el Alzheimer.<\/p>\n<div style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/alacarta\/audios\/entre-probetas\/entre-probetas-celulas-madre-como-madre-todas-celulas-19-07-17\/4122079\/\"><img decoding=\"async\" src=\"http:\/\/img.rtve.es\/imagenes\/entre-probetas\/1411395241783.jpg\" alt=\"\" width=\"269\" height=\"151\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Mi\u00e9rcoles 00:05 h en Radio 5<\/div>\n<p style=\"text-align: center;\"><strong>Las c\u00e9lulas pluripotentes o, como son conocidas en Espa\u00f1a, c\u00e9lulas madre<\/strong>, comparten varias caracter\u00edsticas b\u00e1sicas: producir copias de s\u00ed mismas, diferenciarse a diversos linajes celulares y tisulares y poder colonizar diferentes tejidos. Por desgracia, tambi\u00e9n estar\u00edan detr\u00e1s del origen de muchos tumores y met\u00e1stasis. Para hablar de c\u00e9lulas madre, su potencial terap\u00e9utico, su potencial destructor y las \u00faltimas novedades tenemos hoy Entre probetas al doctor<strong> Llu\u00eds Orozco Delclos, Director cient\u00edfico del Instituto de Terapia Regenerativa Tisular del Centro M\u00e9dic Teknon de Barcelona<\/strong>.<\/p>\n<div style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/alacarta\/audios\/el-laboratorio-de-jal\/\"><img decoding=\"async\" title=\"El LAB de JAL\" src=\"http:\/\/comfuturo.es\/wp-content\/uploads\/2015\/02\/EL-LABORATORIO-DE-JAL_320x240.jpg\" alt=\"El LAB de JAL\" width=\"143\" height=\"107\" \/><\/a><\/div>\n<div style=\"text-align: center;\">L,X y V a las 10:05h en Radio 5<\/div>\n<p style=\"text-align: center;\">\u00a0\u2026<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/madrimasd-tv\/default.asp\">MADRI+D TV<\/a>\u00a0(Divulgaci\u00f3n cient\u00edfica con cara, e im\u00e1genes, en 3 minutos)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/podcast\/radio-5\/entre-probetas\/\">ENTRE PROBETAS<\/a>\u00a0(25 minutos de intensa y entretenida ciencia). Radio 5<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/alacarta\/audios\/el-laboratorio-de-jal\/\" target=\"_blank\">EL LABORATORIO DE JAL<\/a>\u00a0(P\u00edldoras cient\u00edficas en 3 minutos). Radio 5<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/alacarta\/audios\/marca-espana\/\" target=\"_blank\">MARCA ESPA\u00d1A (A CIENCIA CIERTA)<\/a>\u00a0Radio Exterior de Espa\u00f1a<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/podcast\/radio-5\/a-hombros-de-gigantes\/\">A HOMBROS DE GIGANTES<\/a>\u00a0RNE<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.rtve.es\/alacarta\/videos\/uned\/\">UNEDtv<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/home.php?#!\/pages\/Departamento-de-Cultura-Cientifica-Centro-de-Biologia-Molecular\/148445718520196\">FACEBOOK<\/a>\u00a0(Jos\u00e9 Antonio L\u00f3pez-Guerrero)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/?ref=logo#!\/pages\/Departamento-de-Cultura-Cient%C3%ADfica-Centro-de-Biolog%C3%ADa-Molecular\/148445718520196\">FACEBOOK<\/a>\u00a0(Departamento de Cultura Cient\u00edfica -Centro de Biolog\u00eda Molecular)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/twitter.com\/#!\/JALGUERRERO\">TWITTER<\/a>\u00a0(JALGUERRERO)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/twitter.com\/#!\/DCCientificaCBM\">TWITTER<\/a>\u00a0(DCCientificaCBM)<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.linkedin.com\/home?trk=hb_tab_home_top\">LINKED-IN\u00a0<\/a>(Jal Guerrero)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las mitocondrias son los org\u00e1nulos subcelulares que transforman m\u00e1s eficientemente la energ\u00eda contenida en los alimentos en energ\u00eda celular o ATP. Estos org\u00e1nulos son, adem\u00e1s, esenciales para muchos otros aspectos del metabolismo&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[77,539,540],"tags":[36317,8869,892,36315,36316],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las mitocondrias son los org\u00e1nulos subcelulares que transforman m\u00e1s eficientemente la energ\u00eda contenida en los alimentos en energ\u00eda celular o ATP. Estos org\u00e1nulos son, adem\u00e1s, esenciales para muchos otros aspectos del metabolismo...\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"JAL\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bio (Ciencia+Tecnolog\u00eda) - Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El \u00e9xito es sobrevivir a toda costa: Mitocondrias - Bio (Ciencia+Tecnolog\u00eda)\" \/>\n\t\t<meta property=\"og:description\" content=\"Las mitocondrias son los org\u00e1nulos subcelulares que transforman m\u00e1s eficientemente la energ\u00eda contenida en los alimentos en energ\u00eda celular o ATP. Estos org\u00e1nulos son, adem\u00e1s, esenciales para muchos otros aspectos del metabolismo...\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-07-23T17:32:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-07-28T11:34:28+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El \u00e9xito es sobrevivir a toda costa: Mitocondrias - Bio (Ciencia+Tecnolog\u00eda)\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las mitocondrias son los org\u00e1nulos subcelulares que transforman m\u00e1s eficientemente la energ\u00eda contenida en los alimentos en energ\u00eda celular o ATP. Estos org\u00e1nulos son, adem\u00e1s, esenciales para muchos otros aspectos del metabolismo...\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781#blogposting\",\"name\":\"El \\u00e9xito es sobrevivir a toda costa: Mitocondrias - Bio (Ciencia+Tecnolog\\u00eda)\",\"headline\":\"El \\u00e9xito es sobrevivir a toda costa: Mitocondrias\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.isepp.org\\\/Media\\\/Speaker%20Images\\\/04-05%20SJ%20Images\\\/MargulisCheadR.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781\\\/#articleImage\"},\"datePublished\":\"2017-07-23T18:32:58+01:00\",\"dateModified\":\"2017-07-28T12:34:28+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781#webpage\"},\"articleSection\":\"EN RECUERDO..., GEN\\u00c9TICA Y SU MANIPULACI\\u00d3N, POPURR\\u00cd, HUR, Lynn Margulis, Mitocondria, TIA1, TIAR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/general#listItem\",\"name\":\"EN RECUERDO...\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"EN RECUERDO...\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781#listItem\",\"name\":\"El \\u00e9xito es sobrevivir a toda costa: Mitocondrias\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781#listItem\",\"position\":3,\"name\":\"El \\u00e9xito es sobrevivir a toda costa: Mitocondrias\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/category\\\/general#listItem\",\"name\":\"EN RECUERDO...\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\",\"name\":\"Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Biolog\\u00eda molecular y celular. Bioqu\\u00edmica. Biomedicina\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia\",\"name\":\"JAL\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c372814f0d0c3b98b41d9cafe3f11955?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"JAL\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781\",\"name\":\"El \\u00e9xito es sobrevivir a toda costa: Mitocondrias - Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Las mitocondrias son los org\\u00e1nulos subcelulares que transforman m\\u00e1s eficientemente la energ\\u00eda contenida en los alimentos en energ\\u00eda celular o ATP. Estos org\\u00e1nulos son, adem\\u00e1s, esenciales para muchos otros aspectos del metabolismo...\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/2017\\\/07\\\/23\\\/133781#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/author\\\/biociencia#author\"},\"datePublished\":\"2017-07-23T18:32:58+01:00\",\"dateModified\":\"2017-07-28T12:34:28+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/\",\"name\":\"Bio (Ciencia+Tecnolog\\u00eda)\",\"description\":\"Biolog\\u00eda molecular y celular. Bioqu\\u00edmica. Biomedicina\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/biocienciatecnologia\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El \u00e9xito es sobrevivir a toda costa: Mitocondrias - Bio (Ciencia+Tecnolog\u00eda)","description":"Las mitocondrias son los org\u00e1nulos subcelulares que transforman m\u00e1s eficientemente la energ\u00eda contenida en los alimentos en energ\u00eda celular o ATP. Estos org\u00e1nulos son, adem\u00e1s, esenciales para muchos otros aspectos del metabolismo...","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781#blogposting","name":"El \u00e9xito es sobrevivir a toda costa: Mitocondrias - Bio (Ciencia+Tecnolog\u00eda)","headline":"El \u00e9xito es sobrevivir a toda costa: Mitocondrias","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.isepp.org\/Media\/Speaker%20Images\/04-05%20SJ%20Images\/MargulisCheadR.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781\/#articleImage"},"datePublished":"2017-07-23T18:32:58+01:00","dateModified":"2017-07-28T12:34:28+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781#webpage"},"articleSection":"EN RECUERDO..., GEN\u00c9TICA Y SU MANIPULACI\u00d3N, POPURR\u00cd, HUR, Lynn Margulis, Mitocondria, TIA1, TIAR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general#listItem","name":"EN RECUERDO..."}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general#listItem","position":2,"name":"EN RECUERDO...","item":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781#listItem","name":"El \u00e9xito es sobrevivir a toda costa: Mitocondrias"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781#listItem","position":3,"name":"El \u00e9xito es sobrevivir a toda costa: Mitocondrias","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general#listItem","name":"EN RECUERDO..."}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization","name":"Bio (Ciencia+Tecnolog\u00eda)","description":"Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia","name":"JAL","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c372814f0d0c3b98b41d9cafe3f11955?s=96&d=mm&r=g","width":96,"height":96,"caption":"JAL"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781","name":"El \u00e9xito es sobrevivir a toda costa: Mitocondrias - Bio (Ciencia+Tecnolog\u00eda)","description":"Las mitocondrias son los org\u00e1nulos subcelulares que transforman m\u00e1s eficientemente la energ\u00eda contenida en los alimentos en energ\u00eda celular o ATP. Estos org\u00e1nulos son, adem\u00e1s, esenciales para muchos otros aspectos del metabolismo...","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/author\/biociencia#author"},"datePublished":"2017-07-23T18:32:58+01:00","dateModified":"2017-07-28T12:34:28+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/","name":"Bio (Ciencia+Tecnolog\u00eda)","description":"Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Bio (Ciencia+Tecnolog\u00eda) - Biolog\u00eda molecular y celular. Bioqu\u00edmica. Biomedicina","og:type":"article","og:title":"El \u00e9xito es sobrevivir a toda costa: Mitocondrias - Bio (Ciencia+Tecnolog\u00eda)","og:description":"Las mitocondrias son los org\u00e1nulos subcelulares que transforman m\u00e1s eficientemente la energ\u00eda contenida en los alimentos en energ\u00eda celular o ATP. Estos org\u00e1nulos son, adem\u00e1s, esenciales para muchos otros aspectos del metabolismo...","og:url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781","og:image":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png","article:published_time":"2017-07-23T17:32:58+00:00","article:modified_time":"2017-07-28T11:34:28+00:00","twitter:card":"summary","twitter:title":"El \u00e9xito es sobrevivir a toda costa: Mitocondrias - Bio (Ciencia+Tecnolog\u00eda)","twitter:description":"Las mitocondrias son los org\u00e1nulos subcelulares que transforman m\u00e1s eficientemente la energ\u00eda contenida en los alimentos en energ\u00eda celular o ATP. Estos org\u00e1nulos son, adem\u00e1s, esenciales para muchos otros aspectos del metabolismo...","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"133781","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-04 03:30:37","updated":"2026-05-26 17:42:05","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general\" title=\"EN RECUERDO...\">EN RECUERDO...<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl \u00e9xito es sobrevivir a toda costa: Mitocondrias\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia"},{"label":"EN RECUERDO...","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/category\/general"},{"label":"El \u00e9xito es sobrevivir a toda costa: Mitocondrias","link":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/2017\/07\/23\/133781"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/133781"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/comments?post=133781"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/133781\/revisions"}],"predecessor-version":[{"id":133791,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/posts\/133781\/revisions\/133791"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/media?parent=133781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/categories?post=133781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/biocienciatecnologia\/wp-json\/wp\/v2\/tags?post=133781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}