{"id":131532,"date":"2010-05-31T11:20:13","date_gmt":"2010-05-31T10:20:13","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=131532"},"modified":"2010-06-08T07:51:50","modified_gmt":"2010-06-08T06:51:50","slug":"israel-gaza-otra-vez","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532","title":{"rendered":"Israel, Gaza. Otra vez."},"content":{"rendered":"<p>\u00abEl <a href=\"http:\/\/www.elpais.com\/articulo\/internacional\/Israel\/intercepta\/flotilla\/ayuda\/Gaza\/mata\/activistas\/propalestinos\/elpepuint\/20100531elpepuint_3\/Tes\" target=\"_blank\">Ej\u00e9rcito israel\u00ed ha interceptado esta madrugada<\/a> la flotilla de seis barcos, con m\u00e1s de <a href=\"http:\/\/www.elmundo.es\/elmundo\/2010\/06\/01\/internacional\/1275350130.html\" target=\"_blank\">750 personas a bordo<\/a>, que <a href=\"http:\/\/www.elpais.com\/articulo\/internacional\/flotilla\/ayuda\/humanitaria\/navega\/Gaza\/elpepiint\/20100527elpepiint_9\/Tes\" target=\"blank\"> transportaba ayuda humanitaria para Gaza<\/a>. En el ataque han <a href=\"http:\/\/www.elpais.com\/articulo\/internacional\/Quienes\/estan\/detras\/flotilla\/libertad\/elpepuint\/20100531elpepuint_18\/Tes\" target=\"_blank\">muerto al menos 10 activistas<\/a> y otros 30 han resultado heridos, aunque algunos medios elevan la cifra a 16 y hablan de m\u00e1s de 60 heridos.\u00bb<\/p>\n<p>\u00abLos nueve <a href=\"http:\/\/www.publico.es\/internacional\/316759\/israel\/ataca\/flota\/libertad\/causa\/muertos\/heridos\" target=\"_blank\">activistas turcos que murieron en el asalto<\/a> israel\u00ed a la <a href=\"http:\/\/www.publico.es\/318051\" target=\"_blank\">\u00abFlotilla de la libertad\u00bb el pasado lunes <strong>recibieron 30 disparos<\/strong>,<\/a> seg\u00fan informa el diario brit\u00e1nico <em><a href=\"http:\/\/www.guardian.co.uk\/world\/2010\/jun\/04\/gaza-flotilla-activists-autopsy-results\" target=\"_blank\">The Guardian<\/a><\/em> en su p\u00e1gina web.\u00bb<\/p>\n<p>\u00abEl ej\u00e9rcito de Israel ha puesto fin al trayecto del <a href=\"http:\/\/www.elpais.com\/articulo\/internacional\/marina\/israeli\/aborda\/incidentes\/Rachel\/Corrie\/elpepuint\/20100604elpepuint_14\/Tes\" target=\"_blank\">barco irland\u00e9s <em>Rachel Corrie<\/em>, que llevaba ayuda humanitaria a la Franja de Gaza<\/a>. A media ma\u00f1ana, las fuerzas militares han abordado el barco sin que se produjeran v\u00edctimas, seg\u00fan ha informado la marina israel\u00ed. El abordaje se ha producido despu\u00e9s de que la tripulaci\u00f3n ignorara cuatro llamamientos del ej\u00e9rcito israel\u00ed para que pusiera rumbo al puerto israel\u00ed de Ashdod en vez de a Gaza.\u00bb<\/p>\n<p>Helen Thomas, la decana de los corresponsales de la Casa Blanca acaba de anunciar que se retira como corresponsal de prensa en la Casa Blanca que ha ocupado durante m\u00e1s de medio siglo. Entre las frases que pronunci\u00f3: \u00abRecuerde, esta gente [los palestinos] est\u00e1n siendo ocupados en su propia tierra. No es la tierra ni de los alemanes ni de los polacos\u00bb. <a href=\"http:\/\/www.elpais.com\/articulo\/internacional\/larguen\/Palestina\/elpepuint\/20100607elpepuint_14\/Tes\" target=\"_blank\">Lean m\u00e1s aqu\u00ed.<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2009\/01\/06\/110701\" target=\"_blank\">Despu\u00e9s<\/a>, cuando deje de ser <a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2009\/01\/01\/110471\" target=\"_blank\">noticia<\/a> nos olvidaremos&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abEl Ej\u00e9rcito israel\u00ed ha interceptado esta madrugada la flotilla de seis barcos, con m\u00e1s de 750 personas a bordo, que transportaba ayuda humanitaria para Gaza. En el ataque han muerto al menos 10 activistas y otros 30 han resultado heridos, aunque algunos medios elevan la cifra a 16 y hablan de m\u00e1s de 60 heridos.\u00bb \u00abLos nueve activistas turcos que murieron en el asalto israel\u00ed a la \u00abFlotilla de la libertad\u00bb el pasado lunes recibieron 30 disparos, seg\u00fan informa el diario brit\u00e1nico The Guardian en su p\u00e1gina web.\u00bb \u00abEl ej\u00e9rcito de Israel ha puesto fin al trayecto del barco irland\u00e9s\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"&quot;El Ej\u00e9rcito israel\u00ed ha interceptado esta madrugada la flotilla de seis barcos, con m\u00e1s de 750 personas a bordo, que transportaba ayuda humanitaria para Gaza. En el ataque han muerto al menos 10 activistas y otros 30 han resultado heridos, aunque algunos medios elevan la cifra a 16 y hablan de m\u00e1s de 60 heridos.&quot;\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Israel, Gaza. Otra vez. - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"&quot;El Ej\u00e9rcito israel\u00ed ha interceptado esta madrugada la flotilla de seis barcos, con m\u00e1s de 750 personas a bordo, que transportaba ayuda humanitaria para Gaza. En el ataque han muerto al menos 10 activistas y otros 30 han resultado heridos, aunque algunos medios elevan la cifra a 16 y hablan de m\u00e1s de 60 heridos.&quot;\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-05-31T10:20:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-06-08T06:51:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Israel, Gaza. Otra vez. - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"&quot;El Ej\u00e9rcito israel\u00ed ha interceptado esta madrugada la flotilla de seis barcos, con m\u00e1s de 750 personas a bordo, que transportaba ayuda humanitaria para Gaza. En el ataque han muerto al menos 10 activistas y otros 30 han resultado heridos, aunque algunos medios elevan la cifra a 16 y hablan de m\u00e1s de 60 heridos.&quot;\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/05\\\/31\\\/131532#blogposting\",\"name\":\"Israel, Gaza. Otra vez. - Ciencia Marina y otros asuntos\",\"headline\":\"Israel, Gaza. Otra vez.\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/05\\\/31\\\/131532\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2010-05-31T11:20:13+01:00\",\"dateModified\":\"2010-06-08T07:51:50+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/05\\\/31\\\/131532#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/05\\\/31\\\/131532#webpage\"},\"articleSection\":\"General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/05\\\/31\\\/131532#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/05\\\/31\\\/131532#listItem\",\"name\":\"Israel, Gaza. Otra vez.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/05\\\/31\\\/131532#listItem\",\"position\":3,\"name\":\"Israel, Gaza. Otra vez.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/05\\\/31\\\/131532#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/05\\\/31\\\/131532\",\"name\":\"Israel, Gaza. Otra vez. - Ciencia Marina y otros asuntos\",\"description\":\"\\\"El Ej\\u00e9rcito israel\\u00ed ha interceptado esta madrugada la flotilla de seis barcos, con m\\u00e1s de 750 personas a bordo, que transportaba ayuda humanitaria para Gaza. En el ataque han muerto al menos 10 activistas y otros 30 han resultado heridos, aunque algunos medios elevan la cifra a 16 y hablan de m\\u00e1s de 60 heridos.\\\"\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/05\\\/31\\\/131532#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2010-05-31T11:20:13+01:00\",\"dateModified\":\"2010-06-08T07:51:50+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Israel, Gaza. Otra vez. - Ciencia Marina y otros asuntos","description":"\"El Ej\u00e9rcito israel\u00ed ha interceptado esta madrugada la flotilla de seis barcos, con m\u00e1s de 750 personas a bordo, que transportaba ayuda humanitaria para Gaza. En el ataque han muerto al menos 10 activistas y otros 30 han resultado heridos, aunque algunos medios elevan la cifra a 16 y hablan de m\u00e1s de 60 heridos.\"","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532#blogposting","name":"Israel, Gaza. Otra vez. - Ciencia Marina y otros asuntos","headline":"Israel, Gaza. Otra vez.","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532\/#articleImage","width":217,"height":72},"datePublished":"2010-05-31T11:20:13+01:00","dateModified":"2010-06-08T07:51:50+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532#webpage"},"articleSection":"General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532#listItem","name":"Israel, Gaza. Otra vez."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532#listItem","position":3,"name":"Israel, Gaza. Otra vez.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532","name":"Israel, Gaza. Otra vez. - Ciencia Marina y otros asuntos","description":"\"El Ej\u00e9rcito israel\u00ed ha interceptado esta madrugada la flotilla de seis barcos, con m\u00e1s de 750 personas a bordo, que transportaba ayuda humanitaria para Gaza. En el ataque han muerto al menos 10 activistas y otros 30 han resultado heridos, aunque algunos medios elevan la cifra a 16 y hablan de m\u00e1s de 60 heridos.\"","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2010-05-31T11:20:13+01:00","dateModified":"2010-06-08T07:51:50+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Israel, Gaza. Otra vez. - Ciencia Marina y otros asuntos","og:description":"&quot;El Ej\u00e9rcito israel\u00ed ha interceptado esta madrugada la flotilla de seis barcos, con m\u00e1s de 750 personas a bordo, que transportaba ayuda humanitaria para Gaza. En el ataque han muerto al menos 10 activistas y otros 30 han resultado heridos, aunque algunos medios elevan la cifra a 16 y hablan de m\u00e1s de 60 heridos.&quot;","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2010-05-31T10:20:13+00:00","article:modified_time":"2010-06-08T06:51:50+00:00","twitter:card":"summary","twitter:title":"Israel, Gaza. Otra vez. - Ciencia Marina y otros asuntos","twitter:description":"&quot;El Ej\u00e9rcito israel\u00ed ha interceptado esta madrugada la flotilla de seis barcos, con m\u00e1s de 750 personas a bordo, que transportaba ayuda humanitaria para Gaza. En el ataque han muerto al menos 10 activistas y otros 30 han resultado heridos, aunque algunos medios elevan la cifra a 16 y hablan de m\u00e1s de 60 heridos.&quot;","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"131532","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 16:36:14","updated":"2026-05-26 18:18:44","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tIsrael, Gaza. Otra vez.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Israel, Gaza. Otra vez.","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/05\/31\/131532"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131532"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=131532"}],"version-history":[{"count":8,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131532\/revisions"}],"predecessor-version":[{"id":131535,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131532\/revisions\/131535"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=131532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=131532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=131532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}