{"id":131627,"date":"2010-07-28T16:45:52","date_gmt":"2010-07-28T15:45:52","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=131627"},"modified":"2010-07-28T16:45:52","modified_gmt":"2010-07-28T15:45:52","slug":"las-popoffkas-popov-y-los-navios-redondos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627","title":{"rendered":"Las popoffkas. Popov y los nav\u00edos redondos&#8230;"},"content":{"rendered":"<p>Me han enviado <a href=\"http:\/\/www.alpoma.net\/tecob\/?p=3204\" target=\"_blank\">una entrada del blog Tecnolog\u00eda obsoleta<\/a> , el <strong>blog personal de Alejandro Polanco Masa<\/strong> (alpoma), sobre las <a href=\"http:\/\/www.bruzelius.info\/Nautica\/Ships\/Naval_Science(1874)_p1.html\" target=\"_blank\">popoffkas<\/a> que me ha resultado tan interesante que no he podido resistir reproducirlo parcialmente. <a href=\"http:\/\/www.alpoma.net\/tecob\/?p=3204\" target=\"_blank\">Recomiendo vivamente la lectura del post completo<\/a> y el seguimiento de <a href=\"http:\/\/www.alpoma.net\/tecob\/?page_id=1025\" target=\"_blank\">ese interesante blog y sus proyectos<\/a><\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/4828043097_a7df3d311f_o.jpg\" alt=\"\" width=\"500\" height=\"351\" \/><\/p>\n<p><!--more-->\u201cLos t\u00e9rminos del tratado firmado en Par\u00eds en 1856, que puso fin a la guerra de Crimea, no dejaban a Rusia mucho margen de maniobra en cuanto a su marina de guerra. Se prohib\u00eda a Rusia la navegaci\u00f3n por este mar empleando grandes buques de guerra, lo que oblig\u00f3 a los rusos a agudizar el ingenio para patrullar su costa. La soluci\u00f3n que se le ocurri\u00f3 a Andrei Alexandrovich Popov, encargado de la tarea de reactivar la flota rusa, fue la de crear un nuevo tipo de nave. Si s\u00f3lo se pod\u00eda patrullar por \u00e1reas costeras y por r\u00edos, lo mejor ser\u00eda construir ca\u00f1oneras capaces de maniobrar en aguas poco profundas. Y, de ah\u00ed, nacieron las conocidas como popoffkas, unos de los barcos m\u00e1s raros jam\u00e1s vistos.\u201d<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/4828021269_b242eff4d6_b.jpg\" alt=\"\" width=\"500\" height=\"699\" \/><\/p>\n<p>\u201cLas popoffkas eran como min\u00fasculos acorazados de forma circular y seis h\u00e9lices propulsoras. Ciertamente, en aguas someras se manejaban relativamente bien, y se cuenta que sobre las popoffkas era casi imposible marearse, pero por desgracia para Popov su dise\u00f1o se mostr\u00f3 demasiado lento y, para colmo, cuando sus torres artilladas disparaban, la nave al completo tend\u00eda a girar sobre s\u00ed misma. Si se ped\u00eda al barco un rendimiento que fuera m\u00e1s all\u00e1 de una simple y pl\u00e1cida navegaci\u00f3n, no pod\u00eda muy bien saberse hacia d\u00f3nde decidir\u00eda girar el conjunto. En total, \u00fanicamente se construyeron dos buques de este tipo, aunque m\u00e1s que barcos habr\u00eda que pensar en ellos m\u00e1s bien como plataformas flotantes artilladas. \u00bb<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/Livadia_section_3d.jpg\" alt=\"\" width=\"500\" height=\"739\" \/><\/p>\n<p>\u201cSeis potentes motores animaban las h\u00e9lices que, al menos en teor\u00edas, deb\u00edan otorgar a estos barcos una velocidad y capacidad de maniobra sobresalientes. La realidad fue mucho m\u00e1s triste, salvo por la ventaja que ofrec\u00edan en aguas fluviales debido a su escaso calado, la velocidad m\u00e1xima de apenas seis millas por hora. \u00bb<\/p>\n<p>\u00abPopov insisti\u00f3 en contruir barcos circulares, y lo consigui\u00f3 con un yate imperial. Se trat\u00f3 del Livadia, segundo yate imperial ruso con ese nombre pues el anterior se hundi\u00f3 en 1878 tras embarrancar. El nuevo Livadia fue construido en Escocia y botado en 1880. Aunque aparentemente era un barco m\u00e1s o menos convencional, bajo la l\u00ednea de flotaci\u00f3n se convert\u00eda en un engendro semicircular con cerca de 80 metros de di\u00e1metro dif\u00edcilmente descriptible. Capaz de desplazar 4.000 toneladas, era lento y dif\u00edcil de gobernar pero, eso s\u00ed, estaba lleno de lujos. Apenas fue utilizado y termin\u00f3 sus d\u00edas como sus parientes ca\u00f1oneras, en la chatarra.\u00bb<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/4827975315_e17a298584_o.jpg\" alt=\"\" width=\"500\" height=\"352\" \/><\/p>\n<p>Esto de las popoffkas cada vez me recuerda a m\u00e1s actuaciones de los humanos&#8230;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/20100725elpepspor_1_Ies_SCO.jpg\" alt=\"\" width=\"500\" height=\"335\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me han enviado una entrada del blog Tecnolog\u00eda obsoleta , el blog personal de Alejandro Polanco Masa (alpoma), sobre las popoffkas que me ha resultado tan interesante que no he podido resistir reproducirlo parcialmente. Recomiendo vivamente la lectura del post completo y el seguimiento de ese interesante blog y sus proyectos<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Me han enviado una entrada del blog Tecnolog\u00eda obsoleta , el blog personal de Alejandro Polanco Masa (alpoma), sobre las popoffkas que me ha resultado tan interesante que no he podido resistir reproducirlo parcialmente. Recomiendo vivamente la lectura del post completo y el seguimiento de ese interesante blog y sus proyectos \u201cLos t\u00e9rminos del tratado\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las popoffkas. Popov y los nav\u00edos redondos\u2026 - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Me han enviado una entrada del blog Tecnolog\u00eda obsoleta , el blog personal de Alejandro Polanco Masa (alpoma), sobre las popoffkas que me ha resultado tan interesante que no he podido resistir reproducirlo parcialmente. Recomiendo vivamente la lectura del post completo y el seguimiento de ese interesante blog y sus proyectos \u201cLos t\u00e9rminos del tratado\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-07-28T15:45:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-07-28T15:45:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las popoffkas. Popov y los nav\u00edos redondos\u2026 - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Me han enviado una entrada del blog Tecnolog\u00eda obsoleta , el blog personal de Alejandro Polanco Masa (alpoma), sobre las popoffkas que me ha resultado tan interesante que no he podido resistir reproducirlo parcialmente. Recomiendo vivamente la lectura del post completo y el seguimiento de ese interesante blog y sus proyectos \u201cLos t\u00e9rminos del tratado\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/07\\\/28\\\/131627#blogposting\",\"name\":\"Las popoffkas. Popov y los nav\\u00edos redondos\\u2026 - Ciencia Marina y otros asuntos\",\"headline\":\"Las popoffkas. Popov y los nav\\u00edos redondos&#8230;\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/img.photobucket.com\\\/albums\\\/v153\\\/rodaballo\\\/Weblog\\\/4828043097_a7df3d311f_o.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/07\\\/28\\\/131627\\\/#articleImage\"},\"datePublished\":\"2010-07-28T16:45:52+01:00\",\"dateModified\":\"2010-07-28T16:45:52+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/07\\\/28\\\/131627#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/07\\\/28\\\/131627#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/07\\\/28\\\/131627#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/07\\\/28\\\/131627#listItem\",\"name\":\"Las popoffkas. Popov y los nav\\u00edos redondos&#8230;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/07\\\/28\\\/131627#listItem\",\"position\":3,\"name\":\"Las popoffkas. Popov y los nav\\u00edos redondos&#8230;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/07\\\/28\\\/131627#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/07\\\/28\\\/131627\",\"name\":\"Las popoffkas. Popov y los nav\\u00edos redondos\\u2026 - Ciencia Marina y otros asuntos\",\"description\":\"Me han enviado una entrada del blog Tecnolog\\u00eda obsoleta , el blog personal de Alejandro Polanco Masa (alpoma), sobre las popoffkas que me ha resultado tan interesante que no he podido resistir reproducirlo parcialmente. Recomiendo vivamente la lectura del post completo y el seguimiento de ese interesante blog y sus proyectos \\u201cLos t\\u00e9rminos del tratado\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/07\\\/28\\\/131627#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2010-07-28T16:45:52+01:00\",\"dateModified\":\"2010-07-28T16:45:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Las popoffkas. Popov y los nav\u00edos redondos\u2026 - Ciencia Marina y otros asuntos","description":"Me han enviado una entrada del blog Tecnolog\u00eda obsoleta , el blog personal de Alejandro Polanco Masa (alpoma), sobre las popoffkas que me ha resultado tan interesante que no he podido resistir reproducirlo parcialmente. Recomiendo vivamente la lectura del post completo y el seguimiento de ese interesante blog y sus proyectos \u201cLos t\u00e9rminos del tratado","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627#blogposting","name":"Las popoffkas. Popov y los nav\u00edos redondos\u2026 - Ciencia Marina y otros asuntos","headline":"Las popoffkas. Popov y los nav\u00edos redondos&#8230;","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/4828043097_a7df3d311f_o.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627\/#articleImage"},"datePublished":"2010-07-28T16:45:52+01:00","dateModified":"2010-07-28T16:45:52+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627#listItem","name":"Las popoffkas. Popov y los nav\u00edos redondos&#8230;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627#listItem","position":3,"name":"Las popoffkas. Popov y los nav\u00edos redondos&#8230;","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627","name":"Las popoffkas. Popov y los nav\u00edos redondos\u2026 - Ciencia Marina y otros asuntos","description":"Me han enviado una entrada del blog Tecnolog\u00eda obsoleta , el blog personal de Alejandro Polanco Masa (alpoma), sobre las popoffkas que me ha resultado tan interesante que no he podido resistir reproducirlo parcialmente. Recomiendo vivamente la lectura del post completo y el seguimiento de ese interesante blog y sus proyectos \u201cLos t\u00e9rminos del tratado","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2010-07-28T16:45:52+01:00","dateModified":"2010-07-28T16:45:52+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Las popoffkas. Popov y los nav\u00edos redondos\u2026 - Ciencia Marina y otros asuntos","og:description":"Me han enviado una entrada del blog Tecnolog\u00eda obsoleta , el blog personal de Alejandro Polanco Masa (alpoma), sobre las popoffkas que me ha resultado tan interesante que no he podido resistir reproducirlo parcialmente. Recomiendo vivamente la lectura del post completo y el seguimiento de ese interesante blog y sus proyectos \u201cLos t\u00e9rminos del tratado","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2010-07-28T15:45:52+00:00","article:modified_time":"2010-07-28T15:45:52+00:00","twitter:card":"summary","twitter:title":"Las popoffkas. Popov y los nav\u00edos redondos\u2026 - Ciencia Marina y otros asuntos","twitter:description":"Me han enviado una entrada del blog Tecnolog\u00eda obsoleta , el blog personal de Alejandro Polanco Masa (alpoma), sobre las popoffkas que me ha resultado tan interesante que no he podido resistir reproducirlo parcialmente. Recomiendo vivamente la lectura del post completo y el seguimiento de ese interesante blog y sus proyectos \u201cLos t\u00e9rminos del tratado","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"131627","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-08 17:34:31","updated":"2026-05-26 18:21:43","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLas popoffkas. Popov y los nav\u00edos redondos\u2026\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Las popoffkas. Popov y los nav\u00edos redondos&#8230;","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/07\/28\/131627"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131627"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=131627"}],"version-history":[{"count":6,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131627\/revisions"}],"predecessor-version":[{"id":131633,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131627\/revisions\/131633"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=131627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=131627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=131627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}