{"id":131681,"date":"2010-09-01T10:41:09","date_gmt":"2010-09-01T09:41:09","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=131681"},"modified":"2010-09-01T10:56:14","modified_gmt":"2010-09-01T09:56:14","slug":"la-amistad-vida-y-destino-vasili-grosman","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681","title":{"rendered":"La amistad: Vida y destino. Vasili Grossman"},"content":{"rendered":"<p><strong>Vasili Semi\u00f3novich Grossman,<\/strong> (Berdichev, 12 de diciembre de 1905 &#8211; Mosc\u00fa; 14 de septiembre de 1964), fue un prominente periodista, escritor y corresponsal de guerra sovi\u00e9tico de origen jud\u00edo. Grossman comenz\u00f3 a escribir historias cortas mientras estudiaba en la Universidad Estatal de Mosc\u00fa y m\u00e1s tarde sigui\u00f3 su actividad literaria al mismo tiempo que trabajaba como ingeniero en la regi\u00f3n ucraniana de Donbas. A mediados de los a\u00f1os 30, Grosman dej\u00f3 su trabajo como ingeniero y se dedic\u00f3 en exclusiva a la escritura. Durante la Gran Purga algunos de sus amigos y parientes cercanos fueron detenidos, incluida su compa\u00f1era. Durante meses solicit\u00f3 a las autoridades su liberaci\u00f3n, cosa que ocurri\u00f3 en 1938. Durante la Gran Guerra Patri\u00f3tica, acompa\u00f1\u00f3 al Ej\u00e9rcito Rojo durante su ofensiva como corresponsal de guerra para el peri\u00f3dico <em>Krasnaya Zvezda<\/em> (<em>Estrella Roja<\/em>) desde junio de 1941 hasta Berlin en 1945.<\/p>\n<p><a href=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/Hermandad_-_friendship.jpg\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/Hermandad_-_friendship.jpg\" alt=\"\" width=\"500\" height=\"362\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p>Grosman describi\u00f3 la limpieza \u00e9tnica en Ucrania y Polonia, y la liberaci\u00f3n de los campos de concentraci\u00f3n de Treblinka y Majdanek. Su art\u00edculo <em>El infierno de Treblinka<\/em> fue usado en los juicios de N\u00faremberg como evidencia de la persecuci\u00f3n que ejerc\u00eda el r\u00e9gimen nazi. Despu\u00e9s de la guerra particip\u00f3 en <em>El Libro Negro<\/em>, un proyecto del Comit\u00e9 Jud\u00edo Anti-Fascista para documentar los cr\u00edmenes del Holocausto, pero dicho proyecto afront\u00f3 dificultades de la censura sovi\u00e9tica. Al final el proyecto de este libro fue suprimido en 1948. Poco despu\u00e9s, cuando el r\u00e9gimen sovi\u00e9tico inici\u00f3 al a\u00f1o siguiente una campa\u00f1a ultranacionalista que privilegiaba el sentimiento nacional ruso, Grossman empez\u00f3 a revalorar indirectamente su origen jud\u00edo, al ser evidente que la <em>exaltaci\u00f3n nacionalista<\/em> auspiciada por Stalin implicaba un ataque a los jud\u00edos acusados ahora de \u00abcosmopolitismo\u00bb y falta de nacionalismo. Escribe \u00ab<em>Por una causa justa<\/em>\u00ab, una novela basada en sus vivencias como corresponsal de guerra, luego Grossman escribe la segunda parte, titulada Vida y destino que es considerada su obra cumbre, y donde muestra realistamente los estragos causados por el totalitarismo nazi y el sovi\u00e9tico durante la II Guerra Mundial. Esta \u00faltima obra fue presentada a publicaci\u00f3n en 1962 durante el \u00abdeshielo\u00bb provocado por la desestalinizaci\u00f3n pero a\u00fan as\u00ed fue prohibida por el r\u00e9gimen de Jruschov. Grossman muri\u00f3 de un c\u00e1ncer al est\u00f3mago en Mosc\u00fa en 1964, ignorando a\u00fan si <em>Vida y destino<\/em> ser\u00eda alguna vez le\u00edda por el p\u00fablico.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/amistad.jpg\" alt=\"\" width=\"500\" height=\"368\" \/><\/p>\n<p>Transcribo a continuaci\u00f3n un p\u00e1rrafo de Vida y destino sobre la amistad. Muy interesante para todos y tambi\u00e9n para los cient\u00edficos, que protagonizan Vida y destino y Todo fluye.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/amistad-sincera.jpg\" alt=\"\" width=\"500\" height=\"333\" \/><\/p>\n<p>\u201c\u00a1La amistad! Existen tantos tipos\u2026.<\/p>\n<p>La amistad en el trabajo. La amistad en la actividad revolucionaria, la amistad en un largo viaje, entre soldados, en una prisi\u00f3n de transito, donde entre el recuerdo y la separaci\u00f3n discurren solo dos o tres d\u00edas, pero el recuerdo de esas horas se conserva durante a\u00f1os .La amistad en la alegr\u00eda, la amistad en el dolor. La amistad en la igualdad y en la desigualdad.<\/p>\n<p>\u00bfEn que consiste la amistad? \u00bfEs una simple comunidad de trabajo y destino? A veces el odio entre miembros de un mismo partido cuyas ideas solo se diferencian en peque\u00f1os matices es mayor que hacia los enemigos del partido. A veces los hombres que van juntos a la batalla se detestan mas entre ellos que al enemigo com\u00fan .Y del mismo modo a veces el odio ente prisioneros supera al odio que estos sienten por sus carceleros.<\/p>\n<p>Lo cierto es que los amigos se encuentran la mayor\u00eda de las veces entre aquellos que comparten el mismo destino, la misma profesi\u00f3n, los mismos objetivos, pero concluir que es esa comunidad lo que determina la amistad seria un tanto prematura.<\/p>\n<p>\u00bfPueden establecer lazos de amistad dos caracteres completamente diferentes? \u00a1Por supuesto!<\/p>\n<p>La amistad a veces es una relaci\u00f3n desinteresada.<\/p>\n<p>La amistad a veces es ego\u00edsta, otra esta marcada por el esp\u00edritu de sacrificio; pero lo extra\u00f1o es que el ego\u00edsmo de la amistad aporta un beneficio desinteresado a aquel del que se es amigo, mientras que el sacrificio de la amistad es esencialmente ego\u00edsta.<\/p>\n<p>La amistad es un espejo en el que el hombre se contempla a si mismo .A veces, mientras conversas con un amigo, te reconoces a ti mismo: es contigo mismo con quien hablas, es contigo con quien te relacionas.<\/p>\n<p>La amistad es igualdad y afinidad. Pero al mismo tiempo es desigualdad y diferencia.<\/p>\n<p>Existe una amistad pr\u00e1ctica, eficaz cuando hay un trabajo colectivo, en la lucha com\u00fan por la vida, por un trozo de pan.<\/p>\n<p>Tambi\u00e9n esta la amistad por un ideal elevado, la amistad filos\u00f3fica entre interlocutores contemplativos, entre personas que trabajan en campos diferentes, cada uno por su cuenta, pero que juzgan la vida con criterios id\u00e9nticos.<\/p>\n<p>Es posible que una amistad elevada aun\u00e9 la amistad activa \u2013 la del esfuerzo y la lucha \u2013 y la amistad de los interlocutores contemplativos<\/p>\n<p>Los amigos siempre se necesitan el uno al otro, pero no siempre piden lo mismo a la amistad .Los amigos no siempre quieren la misma cosa de la amistad .Uno ofrece al otro su experiencia, el otro se enriquece con esa experiencia. Uno ,al ayudar a un joven amigo ,d\u00e9bil e inexperto , toma conciencia de su propia fuerza y madurez, en tanto el otro reconoce en el amigo el propio ideal de fuerza , madurez ,experiencia .As\u00ed , en la amistad uno da , mientras que el otro se alegra por los regalos .<\/p>\n<p>Ocurre que un amigo es una instancia tacita que ayuda al hombre a entrar en relaci\u00f3n consigo mismo, a encontrar la felicidad en si mismo, en sus propios pensamientos que se vuelven inteligibles, tangibles gracias a que encuentran un eco en el alma del amigo.<\/p>\n<p>La amistad de la raz\u00f3n, la amistad contemplativa, a menudo exige de los amigos unidad de pensamiento, pero esta afinidad no es obligatoriamente total .A veces la amistad se expresa en la disputa, en las divergencias.<\/p>\n<p>Cuando los amigos son id\u00e9nticos en todos los aspectos, cuando se reflejan el uno en el otro, la disputa con el amigo ser\u00e1 una disputa con uno mismo.<\/p>\n<p>Amigo es aquel que justifica tus debilidades, tus defectos e incluso tus vicios; es aquel que confirma tu equidad, tu talante, tus meritos.<\/p>\n<p>Amigo es aquel que, amando, desenmascara tus debilidades, tus defectos y tus vicios.<\/p>\n<p>La amistad es, pues, aquello que fundado sobre lo semejante, se manifiesta en las diferencias, las contradicciones, las desemejanzas .En la amistad el hombre aspira a recibir de forma ego\u00edsta aquello que \u00e9l no posee. En la amistad el hombre aspira a dar aquello que posee.<\/p>\n<p>El deseo de amistad es inherente a la naturaleza humana, y aquel que no sabe establecer v\u00ednculos de amistad con las personas, los tendr\u00e1 con animales, perros, caballos, gatos, ratones, ara\u00f1as.<\/p>\n<p>Un ser dotado de una fuerza absoluta no necesita amigos; evidentemente, ese ser solo puede ser Dios.<\/p>\n<p>La verdadera amistad no depende de que un amigo se siente en un trono o que, derrocado de dicho trono, vaya a parar a prisi\u00f3n .La verdadera amistad se corresponde con las cualidades del alma y es indiferente a la gloria, a la fuerza exterior.<\/p>\n<p>M\u00faltiples son las formas de la amistad y m\u00faltiple es su contenido, pero hay un fundamento solid\u00f3 en ella: la fe en el car\u00e1cter inquebrantable del amigo, en su fidelidad. Por ello es particularmente bella la amistad all\u00ed donde el hombre celebra el sabbat. All\u00ed donde el amigo y la amistad son sacrificados en nombre de los m\u00e1s altos intereses, el hombre, declarado enemigo del ideal supremo, pierde a todos sus amigos, pero conserva su fe en su \u00fanico amigo.\u201d<\/p>\n<p>Para saber m\u00e1s de Vasili Grossman <a href=\"http:\/\/es.wikipedia.org\/wiki\/Vasili_Grossman\" target=\"_blank\">recomiendo el art\u00edculo de la Wikipedia <\/a>y leer sus obras. Espectaculares!!!<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/9001d1188937884-amistad-amistad.jpg\" alt=\"\" width=\"500\" height=\"384\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vasili Semi\u00f3novich Grossman, (Berdichev, 12 de diciembre de 1905 &#8211; Mosc\u00fa; 14 de septiembre de 1964), fue un prominente periodista, escritor y corresponsal de guerra sovi\u00e9tico de origen jud\u00edo. Grossman comenz\u00f3 a escribir historias cortas mientras estudiaba en la Universidad Estatal de Mosc\u00fa y m\u00e1s tarde sigui\u00f3 su actividad literaria al mismo tiempo que trabajaba como ingeniero en la regi\u00f3n ucraniana de Donbas. A mediados de los a\u00f1os 30, Grosman dej\u00f3 su trabajo como ingeniero y se dedic\u00f3 en exclusiva a la escritura. Durante la Gran Purga algunos de sus amigos y parientes cercanos fueron detenidos, incluida su compa\u00f1era. Durante\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Vasili Semi\u00f3novich Grossman, (Berdichev, 12 de diciembre de 1905 - Mosc\u00fa; 14 de septiembre de 1964), fue un prominente periodista, escritor y corresponsal de guerra sovi\u00e9tico de origen jud\u00edo. Grossman comenz\u00f3 a escribir historias cortas mientras estudiaba en la Universidad Estatal de Mosc\u00fa y m\u00e1s tarde sigui\u00f3 su actividad literaria al mismo tiempo que trabajaba\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La amistad: Vida y destino. Vasili Grossman - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Vasili Semi\u00f3novich Grossman, (Berdichev, 12 de diciembre de 1905 - Mosc\u00fa; 14 de septiembre de 1964), fue un prominente periodista, escritor y corresponsal de guerra sovi\u00e9tico de origen jud\u00edo. Grossman comenz\u00f3 a escribir historias cortas mientras estudiaba en la Universidad Estatal de Mosc\u00fa y m\u00e1s tarde sigui\u00f3 su actividad literaria al mismo tiempo que trabajaba\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-09-01T09:41:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-09-01T09:56:14+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La amistad: Vida y destino. Vasili Grossman - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Vasili Semi\u00f3novich Grossman, (Berdichev, 12 de diciembre de 1905 - Mosc\u00fa; 14 de septiembre de 1964), fue un prominente periodista, escritor y corresponsal de guerra sovi\u00e9tico de origen jud\u00edo. Grossman comenz\u00f3 a escribir historias cortas mientras estudiaba en la Universidad Estatal de Mosc\u00fa y m\u00e1s tarde sigui\u00f3 su actividad literaria al mismo tiempo que trabajaba\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/09\\\/01\\\/131681#blogposting\",\"name\":\"La amistad: Vida y destino. Vasili Grossman - Ciencia Marina y otros asuntos\",\"headline\":\"La amistad: Vida y destino. Vasili Grossman\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/img.photobucket.com\\\/albums\\\/v153\\\/rodaballo\\\/Weblog\\\/Hermandad_-_friendship.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/09\\\/01\\\/131681\\\/#articleImage\"},\"datePublished\":\"2010-09-01T10:41:09+01:00\",\"dateModified\":\"2010-09-01T10:56:14+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/09\\\/01\\\/131681#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/09\\\/01\\\/131681#webpage\"},\"articleSection\":\"General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/09\\\/01\\\/131681#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/09\\\/01\\\/131681#listItem\",\"name\":\"La amistad: Vida y destino. Vasili Grossman\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/09\\\/01\\\/131681#listItem\",\"position\":3,\"name\":\"La amistad: Vida y destino. Vasili Grossman\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/09\\\/01\\\/131681#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/09\\\/01\\\/131681\",\"name\":\"La amistad: Vida y destino. Vasili Grossman - Ciencia Marina y otros asuntos\",\"description\":\"Vasili Semi\\u00f3novich Grossman, (Berdichev, 12 de diciembre de 1905 - Mosc\\u00fa; 14 de septiembre de 1964), fue un prominente periodista, escritor y corresponsal de guerra sovi\\u00e9tico de origen jud\\u00edo. Grossman comenz\\u00f3 a escribir historias cortas mientras estudiaba en la Universidad Estatal de Mosc\\u00fa y m\\u00e1s tarde sigui\\u00f3 su actividad literaria al mismo tiempo que trabajaba\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2010\\\/09\\\/01\\\/131681#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2010-09-01T10:41:09+01:00\",\"dateModified\":\"2010-09-01T10:56:14+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La amistad: Vida y destino. Vasili Grossman - Ciencia Marina y otros asuntos","description":"Vasili Semi\u00f3novich Grossman, (Berdichev, 12 de diciembre de 1905 - Mosc\u00fa; 14 de septiembre de 1964), fue un prominente periodista, escritor y corresponsal de guerra sovi\u00e9tico de origen jud\u00edo. Grossman comenz\u00f3 a escribir historias cortas mientras estudiaba en la Universidad Estatal de Mosc\u00fa y m\u00e1s tarde sigui\u00f3 su actividad literaria al mismo tiempo que trabajaba","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681#blogposting","name":"La amistad: Vida y destino. Vasili Grossman - Ciencia Marina y otros asuntos","headline":"La amistad: Vida y destino. Vasili Grossman","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/Hermandad_-_friendship.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681\/#articleImage"},"datePublished":"2010-09-01T10:41:09+01:00","dateModified":"2010-09-01T10:56:14+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681#webpage"},"articleSection":"General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681#listItem","name":"La amistad: Vida y destino. Vasili Grossman"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681#listItem","position":3,"name":"La amistad: Vida y destino. Vasili Grossman","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681","name":"La amistad: Vida y destino. Vasili Grossman - Ciencia Marina y otros asuntos","description":"Vasili Semi\u00f3novich Grossman, (Berdichev, 12 de diciembre de 1905 - Mosc\u00fa; 14 de septiembre de 1964), fue un prominente periodista, escritor y corresponsal de guerra sovi\u00e9tico de origen jud\u00edo. Grossman comenz\u00f3 a escribir historias cortas mientras estudiaba en la Universidad Estatal de Mosc\u00fa y m\u00e1s tarde sigui\u00f3 su actividad literaria al mismo tiempo que trabajaba","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2010-09-01T10:41:09+01:00","dateModified":"2010-09-01T10:56:14+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"La amistad: Vida y destino. Vasili Grossman - Ciencia Marina y otros asuntos","og:description":"Vasili Semi\u00f3novich Grossman, (Berdichev, 12 de diciembre de 1905 - Mosc\u00fa; 14 de septiembre de 1964), fue un prominente periodista, escritor y corresponsal de guerra sovi\u00e9tico de origen jud\u00edo. Grossman comenz\u00f3 a escribir historias cortas mientras estudiaba en la Universidad Estatal de Mosc\u00fa y m\u00e1s tarde sigui\u00f3 su actividad literaria al mismo tiempo que trabajaba","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2010-09-01T09:41:09+00:00","article:modified_time":"2010-09-01T09:56:14+00:00","twitter:card":"summary","twitter:title":"La amistad: Vida y destino. Vasili Grossman - Ciencia Marina y otros asuntos","twitter:description":"Vasili Semi\u00f3novich Grossman, (Berdichev, 12 de diciembre de 1905 - Mosc\u00fa; 14 de septiembre de 1964), fue un prominente periodista, escritor y corresponsal de guerra sovi\u00e9tico de origen jud\u00edo. Grossman comenz\u00f3 a escribir historias cortas mientras estudiaba en la Universidad Estatal de Mosc\u00fa y m\u00e1s tarde sigui\u00f3 su actividad literaria al mismo tiempo que trabajaba","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"131681","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-07 00:50:21","updated":"2026-05-26 18:23:30","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa amistad: Vida y destino. Vasili Grossman\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"La amistad: Vida y destino. Vasili Grossman","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2010\/09\/01\/131681"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131681"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=131681"}],"version-history":[{"count":6,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131681\/revisions"}],"predecessor-version":[{"id":131686,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131681\/revisions\/131686"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=131681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=131681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=131681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}