{"id":131806,"date":"2011-01-03T10:51:44","date_gmt":"2011-01-03T09:51:44","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=131806"},"modified":"2011-01-03T10:51:44","modified_gmt":"2011-01-03T09:51:44","slug":"genoma-del-mejillon-mussel-genome-mytilus-galloprovincialis","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806","title":{"rendered":"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis)"},"content":{"rendered":"<p>\u00abCuando se conozca, el genoma del mejill\u00f3n ser\u00e1 la base para desentra\u00f1ar los misterios de una especie tan cercana como <em>alien\u00edgena<\/em>,  resistente hasta el extremo y pr\u00e1cticamente incapaz de desarrollar  c\u00e1nceres. La revelaci\u00f3n de su ADN supondr\u00e1 un paso crucial para el  desarrollo de medicamentos y ayudar\u00e1 a sintetizar, por ejemplo, un  potente adhesivo cicatrizante que en el futuro podr\u00e1 sustituir la sutura  de las operaciones quir\u00fargicas.\u00bb<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/Mejillon-4.jpg\" alt=\"\" width=\"450\" \/><\/p>\n<p><!--more--><\/p>\n<p>\u00abConocemos palmo a palmo la Luna\u00bb, y no reparamos en la gran  inc\u00f3gnita que habita las r\u00edas. \u00abLa gente ve el mejill\u00f3n en la lata y no  se para a pensar que ese ser es totalmente marciano, un superm\u00e1n que  aguanta horas sin respirar, que vive sin inmutarse en condiciones  extremas, de fr\u00edo y calor, de sequedad y humedad. Un bicho que esconde  el secreto de la resistencia al estr\u00e9s, que apenas sufre mortalidad, con  una especie de antibi\u00f3tico natural (los p\u00e9ptidos antimicrobianos) que  lo vuelve inmune a determinadas enfermedades\u00bb. Antonio Figueras,  cient\u00edfico del Instituto de Investigaciones Marinas (CSIC), podr\u00eda  hablar semanas seguidas de la compleja existencia de sus compa\u00f1eros de  trabajo. Los mejillones criados en este centro vigu\u00e9s de referencia son  de casta, tienen padre y madre conocidos y controlados, y en breve van a  protagonizar el m\u00e1s ambicioso proyecto gen\u00f3mico llevado a cabo en  Galicia. Figueras, coordinador del proyecto de secuenciaci\u00f3n del genoma  del mejill\u00f3n, que va a ser desarrollado a lo largo de tres a\u00f1os por  investigadores de su instituto y de la Universidade de Vigo, advierte de  que su equipo no sabe \u00ablo que se va a encontrar\u00bb.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/mussel_beach.jpg\" alt=\"\" width=\"450\" \/><\/p>\n<p>Parten de lo  descubierto durante muchos a\u00f1os de investigaci\u00f3n, de una base de datos  importante y de unas cuantas constataciones pr\u00e1cticas como las dotes  inmunes de este bivalvo o esa capacidad tan grande de adherirse a las  superficies, que le permite viajar a toda velocidad sujeto al casco de  un barco como si tal cosa. \u00abYo tengo 53 a\u00f1os, pero aunque tuviera 23  ser\u00eda incapaz de agotar la riqueza que va a generar el genoma del  mejill\u00f3n. Esto da para que investigue luego mucha gente, mucho tiempo,  en el mundo\u00bb, asegura el cient\u00edfico.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/mussels2size.jpg\" alt=\"\" width=\"450\" \/><\/p>\n<p>De momento, si se habla de moluscos, en el planeta solo se ha descifrado el genoma de la ostra japonesa (<em>Crassostrea gigas<\/em>), todav\u00eda sin publicar. El segundo, por tanto, ser\u00e1 el mejill\u00f3n en su versi\u00f3n gallega (<em>Mytilus galloprovincialis<\/em>,  que se extiende hasta el Pa\u00eds Vasco, Francia y el sur de Inglaterra y  alcanza el Mediterr\u00e1neo), un organismo bastante m\u00e1s complejo  gen\u00e9ticamente. Los investigadores vigueses planean ir volcando desde el  principio sus descubrimientos en una web abierta a toda la comunidad  cient\u00edfica, aunque, reconoce Figueras, \u00abpuede que se haga un gran  barrido previo de cuestiones concretas, de inter\u00e9s estrat\u00e9gico para  Galicia\u00bb.<\/p>\n<p>El genoma del mejill\u00f3n podr\u00e1 valer, entre otras cosas,  para domesticar y mejorar este recurso, de momento una especie salvaje, y  para encontrar respuestas al problema de las toxinas que paralizan  peri\u00f3dicamente el sector. Galicia es, despu\u00e9s e China, la segunda  productora mundial de mejill\u00f3n, con 210.000 toneladas anuales, una  facturaci\u00f3n de 150 millones de euros, 11.500 puestos de trabajo directo y  7.000 indirectos. Esta producci\u00f3n constituye el 80% del total de la  acuicultura marina de Espa\u00f1a.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/00210Bateascopia.jpg\" alt=\"\" width=\"450\" \/><\/p>\n<p>El objetivo del equipo investigador  es \u00aba\u00f1adir valor a esta riqueza\u00bb, prestando atenci\u00f3n, sobre todo, a los  p\u00e9ptidos antimicrobianos que hacen a estos moluscos invulnerables a  ciertas enfermedades, y a su pegamento, secretado por la gl\u00e1ndula del  viso. La Nasa ya ha patentado esta sustancia compuesta por prote\u00ednas  naturales, pero se necesitan toneladas de mejillones para extraer una  cantidad m\u00ednima y todav\u00eda no se ha dado con la composici\u00f3n adecuada para  la aplicaci\u00f3n en cirug\u00eda con humanos. Cuando se conozcan los genes  responsables de este adhesivo, se podr\u00e1n crear las condiciones para  sintetizarlo biol\u00f3gicamente en insectos u organismos celulares.<\/p>\n<div>\n<h3>Apenas dinero p\u00fablico<\/h3>\n<div>\n<div>\n<p>\u00abEsto lo vamos a hacer s\u00ed o s\u00ed. Sacaremos dinero de debajo de las  piedras, porque este genoma, que no es patrimonio nuestro, sino de  todos, no puede quedarse en genomilla\u00bb. La secuenciaci\u00f3n del genoma del  mejill\u00f3n costar\u00e1 240.000 euros. \u00abEs lo m\u00ednimo imprescindible\u00bb, afirma  Antonio Figueras, \u00ablos investigadores no cobramos nada porque de  nuestros sueldos ya se encargan el Estado [en el caso de los del  Instituto de Investigaciones Marinas] y la Universidade de Vigo\u00bb. Sin  embargo, para el proyecto en s\u00ed, los cient\u00edficos no han conseguido nada  m\u00e1s que la tercera parte, una subvenci\u00f3n de 80.000 euros que les valdr\u00e1  para empezar concedida por la Conseller\u00eda de Econom\u00eda. Adem\u00e1s, uno de  los mayores responsables de la investigaci\u00f3n (en concreto, del an\u00e1lisis  bioinform\u00e1tico), Carlos Canchaya, tiene un contrato Parga Pondal, una  beca de la Xunta hoy de futuro incierto.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/KaichangLi.jpg\" alt=\"\" width=\"450\" \/><\/p>\n<p>Los cient\u00edficos no  quieren llegar a depender del capital privado y conf\u00edan en que la  Administraci\u00f3n p\u00fablica caiga en la cuenta de \u00abla importancia que para el  desarrollo de la comunidad tiene esta investigaci\u00f3n\u00bb, pero ya han  recibido ofertas de varias sociedades de capital riesgo, y aseguran que,  de una u otra forma, van a llegar al final del genoma. \u00abTiene que ser  Galicia la primera en conseguirlo\u00bb.<\/p><\/div>\n<\/div>\n<\/div>\n<p><a href=\"http:\/\/www.elpais.com\/articulo\/Galicia\/genoma\/mejillon\/ayudara\/sintetizar\/adhesivo\/cirugias\/elpepiautgal\/20110102elpgal_9\/Tes\" target=\"_blank\">Reportaje\u00a0 de Silvia Rodr\u00edguez Pontevedra, publicado en el Pa\u00eds secci\u00f3n de Galicia el 2.2<\/a>.2011.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/Mejillon-14.jpg\" alt=\"\" width=\"450\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abCuando se conozca, el genoma del mejill\u00f3n ser\u00e1 la base para desentra\u00f1ar los misterios de una especie tan cercana como alien\u00edgena, resistente hasta el extremo y pr\u00e1cticamente incapaz de desarrollar c\u00e1nceres. La revelaci\u00f3n de su ADN supondr\u00e1 un paso crucial para el desarrollo de medicamentos y ayudar\u00e1 a sintetizar, por ejemplo, un potente adhesivo cicatrizante que en el futuro podr\u00e1 sustituir la sutura de las operaciones quir\u00fargicas.\u00bb<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[359,357,1,358],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"&quot;Cuando se conozca, el genoma del mejill\u00f3n ser\u00e1 la base para desentra\u00f1ar los misterios de una especie tan cercana como alien\u00edgena, resistente hasta el extremo y pr\u00e1cticamente incapaz de desarrollar c\u00e1nceres. La revelaci\u00f3n de su ADN supondr\u00e1 un paso crucial para el desarrollo de medicamentos y ayudar\u00e1 a sintetizar, por ejemplo, un potente adhesivo cicatrizante\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis) - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"&quot;Cuando se conozca, el genoma del mejill\u00f3n ser\u00e1 la base para desentra\u00f1ar los misterios de una especie tan cercana como alien\u00edgena, resistente hasta el extremo y pr\u00e1cticamente incapaz de desarrollar c\u00e1nceres. La revelaci\u00f3n de su ADN supondr\u00e1 un paso crucial para el desarrollo de medicamentos y ayudar\u00e1 a sintetizar, por ejemplo, un potente adhesivo cicatrizante\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-01-03T09:51:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-01-03T09:51:44+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis) - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"&quot;Cuando se conozca, el genoma del mejill\u00f3n ser\u00e1 la base para desentra\u00f1ar los misterios de una especie tan cercana como alien\u00edgena, resistente hasta el extremo y pr\u00e1cticamente incapaz de desarrollar c\u00e1nceres. La revelaci\u00f3n de su ADN supondr\u00e1 un paso crucial para el desarrollo de medicamentos y ayudar\u00e1 a sintetizar, por ejemplo, un potente adhesivo cicatrizante\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/01\\\/03\\\/131806#blogposting\",\"name\":\"Genoma del Mejill\\u00f3n (Mussel genome Mytilus galloprovincialis) - Ciencia Marina y otros asuntos\",\"headline\":\"Genoma del Mejill\\u00f3n (Mussel genome Mytilus galloprovincialis)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/img.photobucket.com\\\/albums\\\/v153\\\/rodaballo\\\/Weblog\\\/Mejillon-4.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/01\\\/03\\\/131806\\\/#articleImage\"},\"datePublished\":\"2011-01-03T10:51:44+01:00\",\"dateModified\":\"2011-01-03T10:51:44+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/01\\\/03\\\/131806#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/01\\\/03\\\/131806#webpage\"},\"articleSection\":\"Acuicultura. Cultivos Marinos., Biolog\\u00eda Marina, General, Investigaci\\u00f3n Marina En Espa\\u00f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/01\\\/03\\\/131806#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/01\\\/03\\\/131806#listItem\",\"name\":\"Genoma del Mejill\\u00f3n (Mussel genome Mytilus galloprovincialis)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/01\\\/03\\\/131806#listItem\",\"position\":3,\"name\":\"Genoma del Mejill\\u00f3n (Mussel genome Mytilus galloprovincialis)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/01\\\/03\\\/131806#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/01\\\/03\\\/131806\",\"name\":\"Genoma del Mejill\\u00f3n (Mussel genome Mytilus galloprovincialis) - Ciencia Marina y otros asuntos\",\"description\":\"\\\"Cuando se conozca, el genoma del mejill\\u00f3n ser\\u00e1 la base para desentra\\u00f1ar los misterios de una especie tan cercana como alien\\u00edgena, resistente hasta el extremo y pr\\u00e1cticamente incapaz de desarrollar c\\u00e1nceres. La revelaci\\u00f3n de su ADN supondr\\u00e1 un paso crucial para el desarrollo de medicamentos y ayudar\\u00e1 a sintetizar, por ejemplo, un potente adhesivo cicatrizante\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/01\\\/03\\\/131806#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2011-01-03T10:51:44+01:00\",\"dateModified\":\"2011-01-03T10:51:44+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis) - Ciencia Marina y otros asuntos","description":"\"Cuando se conozca, el genoma del mejill\u00f3n ser\u00e1 la base para desentra\u00f1ar los misterios de una especie tan cercana como alien\u00edgena, resistente hasta el extremo y pr\u00e1cticamente incapaz de desarrollar c\u00e1nceres. La revelaci\u00f3n de su ADN supondr\u00e1 un paso crucial para el desarrollo de medicamentos y ayudar\u00e1 a sintetizar, por ejemplo, un potente adhesivo cicatrizante","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806#blogposting","name":"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis) - Ciencia Marina y otros asuntos","headline":"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/Mejillon-4.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806\/#articleImage"},"datePublished":"2011-01-03T10:51:44+01:00","dateModified":"2011-01-03T10:51:44+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806#webpage"},"articleSection":"Acuicultura. Cultivos Marinos., Biolog\u00eda Marina, General, Investigaci\u00f3n Marina En Espa\u00f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806#listItem","name":"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806#listItem","position":3,"name":"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806","name":"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis) - Ciencia Marina y otros asuntos","description":"\"Cuando se conozca, el genoma del mejill\u00f3n ser\u00e1 la base para desentra\u00f1ar los misterios de una especie tan cercana como alien\u00edgena, resistente hasta el extremo y pr\u00e1cticamente incapaz de desarrollar c\u00e1nceres. La revelaci\u00f3n de su ADN supondr\u00e1 un paso crucial para el desarrollo de medicamentos y ayudar\u00e1 a sintetizar, por ejemplo, un potente adhesivo cicatrizante","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2011-01-03T10:51:44+01:00","dateModified":"2011-01-03T10:51:44+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis) - Ciencia Marina y otros asuntos","og:description":"&quot;Cuando se conozca, el genoma del mejill\u00f3n ser\u00e1 la base para desentra\u00f1ar los misterios de una especie tan cercana como alien\u00edgena, resistente hasta el extremo y pr\u00e1cticamente incapaz de desarrollar c\u00e1nceres. La revelaci\u00f3n de su ADN supondr\u00e1 un paso crucial para el desarrollo de medicamentos y ayudar\u00e1 a sintetizar, por ejemplo, un potente adhesivo cicatrizante","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2011-01-03T09:51:44+00:00","article:modified_time":"2011-01-03T09:51:44+00:00","twitter:card":"summary","twitter:title":"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis) - Ciencia Marina y otros asuntos","twitter:description":"&quot;Cuando se conozca, el genoma del mejill\u00f3n ser\u00e1 la base para desentra\u00f1ar los misterios de una especie tan cercana como alien\u00edgena, resistente hasta el extremo y pr\u00e1cticamente incapaz de desarrollar c\u00e1nceres. La revelaci\u00f3n de su ADN supondr\u00e1 un paso crucial para el desarrollo de medicamentos y ayudar\u00e1 a sintetizar, por ejemplo, un potente adhesivo cicatrizante","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"131806","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-08 09:45:32","updated":"2026-05-26 18:26:33","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGenoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Genoma del Mejill\u00f3n (Mussel genome Mytilus galloprovincialis)","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/01\/03\/131806"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131806"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=131806"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131806\/revisions"}],"predecessor-version":[{"id":131811,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131806\/revisions\/131811"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=131806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=131806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=131806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}