{"id":131849,"date":"2011-02-06T12:23:42","date_gmt":"2011-02-06T11:23:42","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=131849"},"modified":"2011-02-06T12:23:42","modified_gmt":"2011-02-06T11:23:42","slug":"algo-sobre-los-crustaceos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849","title":{"rendered":"Algo sobre los crust\u00e1ceos"},"content":{"rendered":"<p>Los crust\u00e1ceos, como los insectos y los ar\u00e1cnidos son artr\u00f3podos, es decir, animales con patas articuladas. Aunque no est\u00e1n diferenciados en tantas especies como lo est\u00e1n los insectos o los ar\u00e1cnidos, pues s\u00f3lo se conocen alrededor de 26.000 especies, son muy abundantes y casi tan importantes en el mar como los insectos lo son en la tierra.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/crustaceans-picture.jpg\" alt=\"\" width=\"500\" height=\"381\" \/><\/p>\n<p><!--more-->Los crust\u00e1ceos constituyen un grupo muy heterog\u00e9neo, por lo que resulta dif\u00edcil hacer una descripci\u00f3n que sirva como tipo para la gran diversidad de formas. Sin embargo tiene como caracter\u00edsticas comunes poseer patas articuladas, el cuerpo segmentado y recubierto de un tegumento quitinoso, generalmente muy calcificado. Respiran por medio de branquias y tienen dos pares de antenas y un n\u00famero variable de ap\u00e9ndices articulados. En el cuerpo se distinguen como regiones distintas: cabeza, torax y abdomen, si bien las dos primeras se pueden fusionar, resultando as\u00ed el cuerpo dividido en dos: cefalotorax y abdomen. Cada segmento del cuerpo lleva un par de ap\u00e9ndices.<\/p>\n<p>Una de las caracter\u00edsticas mas llamativas de los crust\u00e1ceos es que el crecimiento no es cont\u00ednuo, sino que ocurre bruscamente: a saltos peri\u00f3dicos. El caparaz\u00f3n duro que les protege, les impide el crecimiento continuo, por lo que para crecer tienen que desprenderse de \u00e9l. A este fen\u00f3meno se le denomina muda. Comienza con movimientos bruscos de los ap\u00e9ndices, con lo que consiguen abrir el caparaz\u00f3n en la uni\u00f3n del cefalot\u00f3rax con el abdomen y por esta abertura el animal va saliendo lentamente. Se desprende del caparaz\u00f3n correspondiente a las patas y, por \u00faltimo, del de las piezas bucales. El animal liberado de su caparaz\u00f3n se embebe de agua que almacena en sus tejidos, aumentando as\u00ed de volumen y talla. Despu\u00e9s comienza la fabricaci\u00f3n de un nuevo caparaz\u00f3n. Por aportes de sales minerales, el nuevo caparaz\u00f3n se va endureciendo. Durante este per\u00edodo los crust\u00e1ceos son especialmente vulnerables, por lo que se retiran a lugares escondidos .<\/p>\n<p>[youtube]http:\/\/www.youtube.com\/watch?v=6Imj15o-MlU[\/youtube] [youtube]http:\/\/www.youtube.com\/watch?v=l-Aw3DJ3IXc[\/youtube]<\/p>\n<p>Se subdividen en varios grupos de los cuales solo dos tienen inter\u00e9s comercial los cirr\u00edpedos y los dec\u00e1podos, aunque no se pueda olvidar a los cop\u00e9podos, muy importantes en el plancton; los eufasi\u00e1ceos, en los que se incluye el krill , alimento de las ballenas y posible alternativa de alimento para la humanidad; y los misid\u00e1ceos, nuestro krill local alimento de multitud de especies de peces, crust\u00e1ceos y cefal\u00f3podos.<\/p>\n<p>Los primeros organismos que se alimentan de las peque\u00f1as algas del plancton son los integrantes del zooplancton. Entre \u00e9stos, adem\u00e1s de larvas de otros animales, encontramos una multitud de crust\u00e1ceos planct\u00f3nicos.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/Copepod.jpg\" alt=\"\" width=\"500\" height=\"250\" \/><\/p>\n<p>Los <strong>Ostracodos<\/strong> son peque\u00f1os crust\u00e1ceos con el cuerpo encerrado en un caparaz\u00f3n bivalvo, como <em>Conchoecia curta. <\/em><\/p>\n<p>Los <strong>Clad\u00f3ceros<\/strong> son crust\u00e1ceos de cuerpo aparentemente poco segmentado y con largas antenas que usan como remos para nadar, como <em>Evadne nordmani . <\/em><\/p>\n<p><em> <\/em>Son sobre todo importantes\u00a0\u00a0 los <strong>Cop\u00e9podos<\/strong>, cuyo n\u00famero\u00a0 en el plancton se ha dicho que supera a todos los animales que viven sobre la tierra juntos, incluyendo a los insectos. Los cop\u00e9podos libres carecen de caparaz\u00f3n y tienen el cuerpo segmentado en cabeza, t\u00f3rax y abdomen. La mayor\u00eda tienen un s\u00f3lo ojo de color rojo o negro y cinco pares de patas que utilizan para nadar. Constituyen el alimento favorito de la sardina. Un cop\u00e9podo ilustre es <em>Acartia margalefi<\/em> descrito por primera vez en la r\u00eda de Vigo y nombrado en honor de Ram\u00f3n Margalef , uno de nuestros cient\u00edficos\u00a0 m\u00e1s destacados dedicado al estudio de la ecolog\u00eda marina.<\/p>\n<p>Los cop\u00e9podos calanoides, que son el grupo al que pertenecen las especies de <em>Acartia<\/em> son tambi\u00e9n comunes en las aguas dulces, aunque en este caso son los ciclopoides los m\u00e1s abundantes y diversificados. Entre los harpacticoides abundan las formas bent\u00f3nicas.<\/p>\n<p>Entre los cop\u00e9podos hay tambi\u00e9n formas par\u00e1sitas, m\u00e1s de un millar,\u00a0 entre los que est\u00e1n <em>Mytilicola intestinalis<\/em> par\u00e1sito intestinal del mejill\u00f3n, <em>Bopyrus squillarum<\/em> par\u00e1sito de los camarones y <em>Lernaocera branquialis<\/em> par\u00e1sito de gran variedad de peces.\u00a0 Otros crust\u00e1ceos par\u00e1sitos son los <strong>Is\u00f3podos<\/strong> o piojos de mar. Es el caso de <em>Anilocera physodes<\/em> que se encuentra fijado con frecuencia al cuerpo de los\u00a0 peces l\u00e1bridos.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/evenourcrustaceansareprettier.jpg\" alt=\"\" width=\"500\" height=\"419\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los crust\u00e1ceos, como los insectos y los ar\u00e1cnidos son artr\u00f3podos, es decir, animales con patas articuladas. Aunque no est\u00e1n diferenciados en tantas especies como lo est\u00e1n los insectos o los ar\u00e1cnidos, pues s\u00f3lo se conocen alrededor de 26.000 especies, son muy abundantes y casi tan importantes en el mar como los insectos lo son en la tierra.<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los crust\u00e1ceos, como los insectos y los ar\u00e1cnidos son artr\u00f3podos, es decir, animales con patas articuladas. Aunque no est\u00e1n diferenciados en tantas especies como lo est\u00e1n los insectos o los ar\u00e1cnidos, pues s\u00f3lo se conocen alrededor de 26.000 especies, son muy abundantes y casi tan importantes en el mar como los insectos lo son en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Algo sobre los crust\u00e1ceos - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Los crust\u00e1ceos, como los insectos y los ar\u00e1cnidos son artr\u00f3podos, es decir, animales con patas articuladas. Aunque no est\u00e1n diferenciados en tantas especies como lo est\u00e1n los insectos o los ar\u00e1cnidos, pues s\u00f3lo se conocen alrededor de 26.000 especies, son muy abundantes y casi tan importantes en el mar como los insectos lo son en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-02-06T11:23:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-02-06T11:23:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Algo sobre los crust\u00e1ceos - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los crust\u00e1ceos, como los insectos y los ar\u00e1cnidos son artr\u00f3podos, es decir, animales con patas articuladas. Aunque no est\u00e1n diferenciados en tantas especies como lo est\u00e1n los insectos o los ar\u00e1cnidos, pues s\u00f3lo se conocen alrededor de 26.000 especies, son muy abundantes y casi tan importantes en el mar como los insectos lo son en\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/02\\\/06\\\/131849#blogposting\",\"name\":\"Algo sobre los crust\\u00e1ceos - Ciencia Marina y otros asuntos\",\"headline\":\"Algo sobre los crust\\u00e1ceos\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/img.photobucket.com\\\/albums\\\/v153\\\/rodaballo\\\/Weblog\\\/crustaceans-picture.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/02\\\/06\\\/131849\\\/#articleImage\"},\"datePublished\":\"2011-02-06T12:23:42+01:00\",\"dateModified\":\"2011-02-06T12:23:42+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":4,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/02\\\/06\\\/131849#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/02\\\/06\\\/131849#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/02\\\/06\\\/131849#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/02\\\/06\\\/131849#listItem\",\"name\":\"Algo sobre los crust\\u00e1ceos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/02\\\/06\\\/131849#listItem\",\"position\":3,\"name\":\"Algo sobre los crust\\u00e1ceos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/02\\\/06\\\/131849#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/02\\\/06\\\/131849\",\"name\":\"Algo sobre los crust\\u00e1ceos - Ciencia Marina y otros asuntos\",\"description\":\"Los crust\\u00e1ceos, como los insectos y los ar\\u00e1cnidos son artr\\u00f3podos, es decir, animales con patas articuladas. Aunque no est\\u00e1n diferenciados en tantas especies como lo est\\u00e1n los insectos o los ar\\u00e1cnidos, pues s\\u00f3lo se conocen alrededor de 26.000 especies, son muy abundantes y casi tan importantes en el mar como los insectos lo son en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/02\\\/06\\\/131849#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2011-02-06T12:23:42+01:00\",\"dateModified\":\"2011-02-06T12:23:42+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Algo sobre los crust\u00e1ceos - Ciencia Marina y otros asuntos","description":"Los crust\u00e1ceos, como los insectos y los ar\u00e1cnidos son artr\u00f3podos, es decir, animales con patas articuladas. Aunque no est\u00e1n diferenciados en tantas especies como lo est\u00e1n los insectos o los ar\u00e1cnidos, pues s\u00f3lo se conocen alrededor de 26.000 especies, son muy abundantes y casi tan importantes en el mar como los insectos lo son en","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849#blogposting","name":"Algo sobre los crust\u00e1ceos - Ciencia Marina y otros asuntos","headline":"Algo sobre los crust\u00e1ceos","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/crustaceans-picture.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849\/#articleImage"},"datePublished":"2011-02-06T12:23:42+01:00","dateModified":"2011-02-06T12:23:42+01:00","inLanguage":"es-ES","commentCount":4,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849#listItem","name":"Algo sobre los crust\u00e1ceos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849#listItem","position":3,"name":"Algo sobre los crust\u00e1ceos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849","name":"Algo sobre los crust\u00e1ceos - Ciencia Marina y otros asuntos","description":"Los crust\u00e1ceos, como los insectos y los ar\u00e1cnidos son artr\u00f3podos, es decir, animales con patas articuladas. Aunque no est\u00e1n diferenciados en tantas especies como lo est\u00e1n los insectos o los ar\u00e1cnidos, pues s\u00f3lo se conocen alrededor de 26.000 especies, son muy abundantes y casi tan importantes en el mar como los insectos lo son en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2011-02-06T12:23:42+01:00","dateModified":"2011-02-06T12:23:42+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Algo sobre los crust\u00e1ceos - Ciencia Marina y otros asuntos","og:description":"Los crust\u00e1ceos, como los insectos y los ar\u00e1cnidos son artr\u00f3podos, es decir, animales con patas articuladas. Aunque no est\u00e1n diferenciados en tantas especies como lo est\u00e1n los insectos o los ar\u00e1cnidos, pues s\u00f3lo se conocen alrededor de 26.000 especies, son muy abundantes y casi tan importantes en el mar como los insectos lo son en","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2011-02-06T11:23:42+00:00","article:modified_time":"2011-02-06T11:23:42+00:00","twitter:card":"summary","twitter:title":"Algo sobre los crust\u00e1ceos - Ciencia Marina y otros asuntos","twitter:description":"Los crust\u00e1ceos, como los insectos y los ar\u00e1cnidos son artr\u00f3podos, es decir, animales con patas articuladas. Aunque no est\u00e1n diferenciados en tantas especies como lo est\u00e1n los insectos o los ar\u00e1cnidos, pues s\u00f3lo se conocen alrededor de 26.000 especies, son muy abundantes y casi tan importantes en el mar como los insectos lo son en","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"131849","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 14:02:13","updated":"2026-05-26 18:26:33","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAlgo sobre los crust\u00e1ceos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Algo sobre los crust\u00e1ceos","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/02\/06\/131849"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131849"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=131849"}],"version-history":[{"count":4,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131849\/revisions"}],"predecessor-version":[{"id":131853,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/131849\/revisions\/131853"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=131849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=131849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=131849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}