{"id":132144,"date":"2011-10-30T09:45:01","date_gmt":"2011-10-30T08:45:01","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=132144"},"modified":"2011-10-30T09:45:01","modified_gmt":"2011-10-30T08:45:01","slug":"aficiones-desconocidas-de-los-cientificos-en-amazings-es","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144","title":{"rendered":"Aficiones desconocidas de los cient\u00edficos en amazings.es"},"content":{"rendered":"<p>Les recomiendo la lectura del post <a href=\"http:\/\/amazings.es\/2011\/10\/28\/algunas-aficiones-desconocidas-de-los-cientificos\/\" target=\"_blank\">\u00abAlgunas aficiones desconocidas de los cient\u00edficos\u00bb<\/a> de Alfred en el <a href=\"http:\/\/amazings.es\/\" target=\"_blank\">blog Amazings<\/a>. No tiene desperdicio. Copio a continuaci\u00f3n algo sobre Ram\u00f3n y Cajal.<\/p>\n<p><!--more--><\/p>\n<p>\u00abLas m\u00faltiples fotograf\u00edas de un Ram\u00f3n y Cajal ya adulto, nos lo  muestran como un hombre delgado, algo enclenque y algo encorvado, debido  a la postura que se adquiere tras pasar largo tiempo frente a un  microscopio.<\/p>\n<p>El ganador del Premio Nobel de Medicina en 1906, hab\u00eda pasado parte  de su juventud rodeado de peleas y apuestas con sus camaradas de  juergas. En cierta ocasi\u00f3n, siendo aun un estudiante, perdi\u00f3 al echar un  pulso con un amigo. Esto le doli\u00f3 en el orgullo y decidi\u00f3 acudir a  entrenarse a un gimnasio. Lleg\u00f3 al acuerdo de ense\u00f1ar clases de anatom\u00eda  al propietario a cambio de entrenamiento f\u00edsico.<\/p>\n<p>Sus progresos en el gimnasio, sumados a la fuerte afici\u00f3n que le  cogi\u00f3 al culturismo fue tal, que lleg\u00f3 a describirse a s\u00ed mismo como:  \u00a0\u201cancho de espaldas, con pectorales monstruosos, mi circunferencia  tor\u00e1cica exced\u00eda de los 112 cent\u00edmetros, y al andar mostraba esa  inelegancia y contorneo r\u00edtmico caracter\u00edstico de los forzudos o  H\u00e9rcules de Feria\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les recomiendo la lectura del post \u00abAlgunas aficiones desconocidas de los cient\u00edficos\u00bb de Alfred en el blog Amazings. No tiene desperdicio. Copio a continuaci\u00f3n algo sobre Ram\u00f3n y Cajal.<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Les recomiendo la lectura del post &quot;Algunas aficiones desconocidas de los cient\u00edficos&quot; de Alfred en el blog Amazings. No tiene desperdicio. Copio a continuaci\u00f3n algo sobre Ram\u00f3n y Cajal. &quot;Las m\u00faltiples fotograf\u00edas de un Ram\u00f3n y Cajal ya adulto, nos lo muestran como un hombre delgado, algo enclenque y algo encorvado, debido a la postura\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Aficiones desconocidas de los cient\u00edficos en amazings.es - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Les recomiendo la lectura del post &quot;Algunas aficiones desconocidas de los cient\u00edficos&quot; de Alfred en el blog Amazings. No tiene desperdicio. Copio a continuaci\u00f3n algo sobre Ram\u00f3n y Cajal. &quot;Las m\u00faltiples fotograf\u00edas de un Ram\u00f3n y Cajal ya adulto, nos lo muestran como un hombre delgado, algo enclenque y algo encorvado, debido a la postura\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-10-30T08:45:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-10-30T08:45:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Aficiones desconocidas de los cient\u00edficos en amazings.es - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Les recomiendo la lectura del post &quot;Algunas aficiones desconocidas de los cient\u00edficos&quot; de Alfred en el blog Amazings. No tiene desperdicio. Copio a continuaci\u00f3n algo sobre Ram\u00f3n y Cajal. &quot;Las m\u00faltiples fotograf\u00edas de un Ram\u00f3n y Cajal ya adulto, nos lo muestran como un hombre delgado, algo enclenque y algo encorvado, debido a la postura\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/10\\\/30\\\/132144#blogposting\",\"name\":\"Aficiones desconocidas de los cient\\u00edficos en amazings.es - Ciencia Marina y otros asuntos\",\"headline\":\"Aficiones desconocidas de los cient\\u00edficos en amazings.es\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/10\\\/30\\\/132144\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2011-10-30T09:45:01+01:00\",\"dateModified\":\"2011-10-30T09:45:01+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/10\\\/30\\\/132144#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/10\\\/30\\\/132144#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/10\\\/30\\\/132144#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/10\\\/30\\\/132144#listItem\",\"name\":\"Aficiones desconocidas de los cient\\u00edficos en amazings.es\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/10\\\/30\\\/132144#listItem\",\"position\":3,\"name\":\"Aficiones desconocidas de los cient\\u00edficos en amazings.es\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/10\\\/30\\\/132144#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/10\\\/30\\\/132144\",\"name\":\"Aficiones desconocidas de los cient\\u00edficos en amazings.es - Ciencia Marina y otros asuntos\",\"description\":\"Les recomiendo la lectura del post \\\"Algunas aficiones desconocidas de los cient\\u00edficos\\\" de Alfred en el blog Amazings. No tiene desperdicio. Copio a continuaci\\u00f3n algo sobre Ram\\u00f3n y Cajal. \\\"Las m\\u00faltiples fotograf\\u00edas de un Ram\\u00f3n y Cajal ya adulto, nos lo muestran como un hombre delgado, algo enclenque y algo encorvado, debido a la postura\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2011\\\/10\\\/30\\\/132144#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2011-10-30T09:45:01+01:00\",\"dateModified\":\"2011-10-30T09:45:01+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Aficiones desconocidas de los cient\u00edficos en amazings.es - Ciencia Marina y otros asuntos","description":"Les recomiendo la lectura del post \"Algunas aficiones desconocidas de los cient\u00edficos\" de Alfred en el blog Amazings. No tiene desperdicio. Copio a continuaci\u00f3n algo sobre Ram\u00f3n y Cajal. \"Las m\u00faltiples fotograf\u00edas de un Ram\u00f3n y Cajal ya adulto, nos lo muestran como un hombre delgado, algo enclenque y algo encorvado, debido a la postura","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144#blogposting","name":"Aficiones desconocidas de los cient\u00edficos en amazings.es - Ciencia Marina y otros asuntos","headline":"Aficiones desconocidas de los cient\u00edficos en amazings.es","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144\/#articleImage","width":217,"height":72},"datePublished":"2011-10-30T09:45:01+01:00","dateModified":"2011-10-30T09:45:01+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144#listItem","name":"Aficiones desconocidas de los cient\u00edficos en amazings.es"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144#listItem","position":3,"name":"Aficiones desconocidas de los cient\u00edficos en amazings.es","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144","name":"Aficiones desconocidas de los cient\u00edficos en amazings.es - Ciencia Marina y otros asuntos","description":"Les recomiendo la lectura del post \"Algunas aficiones desconocidas de los cient\u00edficos\" de Alfred en el blog Amazings. No tiene desperdicio. Copio a continuaci\u00f3n algo sobre Ram\u00f3n y Cajal. \"Las m\u00faltiples fotograf\u00edas de un Ram\u00f3n y Cajal ya adulto, nos lo muestran como un hombre delgado, algo enclenque y algo encorvado, debido a la postura","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2011-10-30T09:45:01+01:00","dateModified":"2011-10-30T09:45:01+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Aficiones desconocidas de los cient\u00edficos en amazings.es - Ciencia Marina y otros asuntos","og:description":"Les recomiendo la lectura del post &quot;Algunas aficiones desconocidas de los cient\u00edficos&quot; de Alfred en el blog Amazings. No tiene desperdicio. Copio a continuaci\u00f3n algo sobre Ram\u00f3n y Cajal. &quot;Las m\u00faltiples fotograf\u00edas de un Ram\u00f3n y Cajal ya adulto, nos lo muestran como un hombre delgado, algo enclenque y algo encorvado, debido a la postura","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2011-10-30T08:45:01+00:00","article:modified_time":"2011-10-30T08:45:01+00:00","twitter:card":"summary","twitter:title":"Aficiones desconocidas de los cient\u00edficos en amazings.es - Ciencia Marina y otros asuntos","twitter:description":"Les recomiendo la lectura del post &quot;Algunas aficiones desconocidas de los cient\u00edficos&quot; de Alfred en el blog Amazings. No tiene desperdicio. Copio a continuaci\u00f3n algo sobre Ram\u00f3n y Cajal. &quot;Las m\u00faltiples fotograf\u00edas de un Ram\u00f3n y Cajal ya adulto, nos lo muestran como un hombre delgado, algo enclenque y algo encorvado, debido a la postura","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"132144","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-07 17:57:12","updated":"2026-05-26 18:33:04","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAficiones desconocidas de los cient\u00edficos en amazings.es\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Aficiones desconocidas de los cient\u00edficos en amazings.es","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2011\/10\/30\/132144"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/132144"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=132144"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/132144\/revisions"}],"predecessor-version":[{"id":132147,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/132144\/revisions\/132147"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=132144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=132144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=132144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}