{"id":132720,"date":"2012-06-03T17:14:44","date_gmt":"2012-06-03T16:14:44","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=132720"},"modified":"2012-06-03T17:14:44","modified_gmt":"2012-06-03T16:14:44","slug":"criaturas-de-las-profundidades","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720","title":{"rendered":"Criaturas de las profundidades"},"content":{"rendered":"<p>Es obvio que aunque creemos que ya conocemos nuestro planeta a fondo, queda mucho por descubrir. Una de las zonas menos exploradas son las profundidades submarinas. James Cameron el director de Titanic y de la pel\u00edcula <a href=\"http:\/\/www.imdb.com\/title\/tt0096754\/\" target=\"_blank\">\u201cAbyss\u201d<\/a> va a intentar bajar a la<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2008\/11\/02\/105614\" target=\"_blank\"> Fosa de las Marianas.<\/a> Este punto es el m\u00e1s profundo de la corteza terrestre (11.300 metros bajo el mar) y est\u00e1 situada <a href=\"http:\/\/www.xatakaciencia.com\/tecnologia\/descendemos-a-las-profundidades-marinas\" target=\"_blank\">cerca de Guam, en el Pac\u00edfico noroccidental<\/a>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/sub-main-942-31-640x267.jpg\" alt=\"\" width=\"500\" height=\"209\" \/><\/p>\n<p><!--more-->Este punto\u00a0s\u00f3lo se ha visitado en una \u00fanica ocasi\u00f3n: el 23 de enero de 1960 mediante un batiscafo capitaneado por\u00a0 <a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2008\/11\/02\/105614\" target=\"_blank\">Jacques Piccard, del que hablamos en el blog cuando falleci\u00f3<\/a>. El\u00a0<strong> <\/strong>Trieste  tard\u00f3 m\u00e1s de 5 horas. Jacques  Piccard s\u00f3lo pudo estar 20 minutos\u00a0 abajo,. Cameron usar\u00e1 el\u00a0Deepsea Challenger que tardar\u00e1 2 horas en bajar y le permitir\u00e1 6 horas de exploraci\u00f3n. Una nave de m\u00e1s de 7 metros de longitud, capaz de ascender y descender de forma vertical y acompa\u00f1ado de varias c\u00e1maras de alta definici\u00f3n y un enorme panel\u00a0LED\u00a0para poder vislumbrar algo en esa oscuridad.<\/p>\n<p>[youtube]http:\/\/www.youtube.com\/watch?v=0mBG0LbAoqk[\/youtube]<\/p>\n<p>Un adelanto de los que puede encontrar Cameron nos lo avanza una expedici\u00f3n neozelandesa que ha recogido miles de muestras de especies submarinas y captado im\u00e1genes in\u00e9ditas de extra\u00f1as criaturas adaptadas a las duras condiciones de las profundidades del oc\u00e9ano.<\/p>\n<p>El <a href=\"http:\/\/www.nzherald.co.nz\/environment\/news\/article.cfm?c_id=39&amp;objectid=10798544\" target=\"_blank\">barco &#8216;Tangaroa&#8217;, de NIWA,<\/a> realiz\u00f3 <a href=\"http:\/\/www.elmundo.es\/elmundo\/2012\/06\/02\/natura\/1338634564.html\" target=\"_blank\">un viaje de tres semanas <\/a>para estudiar las comunidades submarinas que habitan las aguas frente a la costa norte de Nueva Zelanda y su posible vulnerabilidad ante la acci\u00f3n del hombre.En un \u00e1rea de 10.000 kil\u00f3metros cuadrados y a una profundidad hasta 1.500 metros, tomaron unas 5.000 muestras que los cient\u00edficos de NIWA cree que son nuevas para la ciencia o para Nueva Zelanda.<\/p>\n<p>[youtube]http:\/\/www.youtube.com\/watch?v=lR2x5YWjpnY[\/youtube]<\/p>\n<p>En esta expedici\u00f3n se explor\u00f3 por primera vez los montes submarinos Tangaroa, situados a unos 200 kil\u00f3metros de la ciudad de Wahakatane (Isla Norte) y que forma parte de la cordillera submarina Kermadec. Durante la expedici\u00f3n se constat\u00f3 que \u00abestos animales est\u00e1n espec\u00edficamente adaptados a aguantar los grandes niveles de sulfuro de hidr\u00f3geno gaseoso y agua caliente que produce el conducto hidrotermal\u00bb.<\/p>\n<p>Las muestras se suman a la informaci\u00f3n sobre las estructuras y comportamientos de las comunidades biol\u00f3gicas en la cadena Kermadec, donde hay unos 50 volcanes submarinos que se extienden a lo largo de unos 1.500 kil\u00f3metros.<\/p>\n<p>[vimeo]http:\/\/vimeo.com\/43080363[\/vimeo]<\/p>\n<p>El video que sigue muestras im\u00e1genes de animales de las profundidades del mar de Jap\u00f3n. Queda mucho por descubir.<\/p>\n<p>[youtube]http:\/\/www.youtube.com\/watch?v=Pa0SY6RYJIo[\/youtube]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es obvio que aunque creemos que ya conocemos nuestro planeta a fondo, queda mucho por descubrir. Una de las zonas menos exploradas son las profundidades submarinas. James Cameron el director de Titanic y de la pel\u00edcula \u201cAbyss\u201d va a intentar bajar a la Fosa de las Marianas. Este punto es el m\u00e1s profundo de la corteza terrestre (11.300 metros bajo el mar) y est\u00e1 situada cerca de Guam, en el Pac\u00edfico noroccidental.<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[357,1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Es obvio que aunque creemos que ya conocemos nuestro planeta a fondo, queda mucho por descubrir. Una de las zonas menos exploradas son las profundidades submarinas. James Cameron el director de Titanic y de la pel\u00edcula \u201cAbyss\u201d va a intentar bajar a la Fosa de las Marianas. Este punto es el m\u00e1s profundo de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Criaturas de las profundidades - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Es obvio que aunque creemos que ya conocemos nuestro planeta a fondo, queda mucho por descubrir. Una de las zonas menos exploradas son las profundidades submarinas. James Cameron el director de Titanic y de la pel\u00edcula \u201cAbyss\u201d va a intentar bajar a la Fosa de las Marianas. Este punto es el m\u00e1s profundo de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-06-03T16:14:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-06-03T16:14:44+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Criaturas de las profundidades - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Es obvio que aunque creemos que ya conocemos nuestro planeta a fondo, queda mucho por descubrir. Una de las zonas menos exploradas son las profundidades submarinas. James Cameron el director de Titanic y de la pel\u00edcula \u201cAbyss\u201d va a intentar bajar a la Fosa de las Marianas. Este punto es el m\u00e1s profundo de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2012\\\/06\\\/03\\\/132720#blogposting\",\"name\":\"Criaturas de las profundidades - Ciencia Marina y otros asuntos\",\"headline\":\"Criaturas de las profundidades\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/img.photobucket.com\\\/albums\\\/v153\\\/rodaballo\\\/sub-main-942-31-640x267.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2012\\\/06\\\/03\\\/132720\\\/#articleImage\"},\"datePublished\":\"2012-06-03T17:14:44+01:00\",\"dateModified\":\"2012-06-03T17:14:44+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2012\\\/06\\\/03\\\/132720#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2012\\\/06\\\/03\\\/132720#webpage\"},\"articleSection\":\"Biolog\\u00eda Marina, General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2012\\\/06\\\/03\\\/132720#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2012\\\/06\\\/03\\\/132720#listItem\",\"name\":\"Criaturas de las profundidades\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2012\\\/06\\\/03\\\/132720#listItem\",\"position\":3,\"name\":\"Criaturas de las profundidades\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2012\\\/06\\\/03\\\/132720#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2012\\\/06\\\/03\\\/132720\",\"name\":\"Criaturas de las profundidades - Ciencia Marina y otros asuntos\",\"description\":\"Es obvio que aunque creemos que ya conocemos nuestro planeta a fondo, queda mucho por descubrir. Una de las zonas menos exploradas son las profundidades submarinas. James Cameron el director de Titanic y de la pel\\u00edcula \\u201cAbyss\\u201d va a intentar bajar a la Fosa de las Marianas. Este punto es el m\\u00e1s profundo de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2012\\\/06\\\/03\\\/132720#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2012-06-03T17:14:44+01:00\",\"dateModified\":\"2012-06-03T17:14:44+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Criaturas de las profundidades - Ciencia Marina y otros asuntos","description":"Es obvio que aunque creemos que ya conocemos nuestro planeta a fondo, queda mucho por descubrir. Una de las zonas menos exploradas son las profundidades submarinas. James Cameron el director de Titanic y de la pel\u00edcula \u201cAbyss\u201d va a intentar bajar a la Fosa de las Marianas. Este punto es el m\u00e1s profundo de la","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720#blogposting","name":"Criaturas de las profundidades - Ciencia Marina y otros asuntos","headline":"Criaturas de las profundidades","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/sub-main-942-31-640x267.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720\/#articleImage"},"datePublished":"2012-06-03T17:14:44+01:00","dateModified":"2012-06-03T17:14:44+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720#webpage"},"articleSection":"Biolog\u00eda Marina, General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720#listItem","name":"Criaturas de las profundidades"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720#listItem","position":3,"name":"Criaturas de las profundidades","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720","name":"Criaturas de las profundidades - Ciencia Marina y otros asuntos","description":"Es obvio que aunque creemos que ya conocemos nuestro planeta a fondo, queda mucho por descubrir. Una de las zonas menos exploradas son las profundidades submarinas. James Cameron el director de Titanic y de la pel\u00edcula \u201cAbyss\u201d va a intentar bajar a la Fosa de las Marianas. Este punto es el m\u00e1s profundo de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2012-06-03T17:14:44+01:00","dateModified":"2012-06-03T17:14:44+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Criaturas de las profundidades - Ciencia Marina y otros asuntos","og:description":"Es obvio que aunque creemos que ya conocemos nuestro planeta a fondo, queda mucho por descubrir. Una de las zonas menos exploradas son las profundidades submarinas. James Cameron el director de Titanic y de la pel\u00edcula \u201cAbyss\u201d va a intentar bajar a la Fosa de las Marianas. Este punto es el m\u00e1s profundo de la","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2012-06-03T16:14:44+00:00","article:modified_time":"2012-06-03T16:14:44+00:00","twitter:card":"summary","twitter:title":"Criaturas de las profundidades - Ciencia Marina y otros asuntos","twitter:description":"Es obvio que aunque creemos que ya conocemos nuestro planeta a fondo, queda mucho por descubrir. Una de las zonas menos exploradas son las profundidades submarinas. James Cameron el director de Titanic y de la pel\u00edcula \u201cAbyss\u201d va a intentar bajar a la Fosa de las Marianas. Este punto es el m\u00e1s profundo de la","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"132720","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-04 00:36:59","updated":"2026-05-26 18:44:43","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCriaturas de las profundidades\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Criaturas de las profundidades","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/03\/132720"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/132720"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=132720"}],"version-history":[{"count":9,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/132720\/revisions"}],"predecessor-version":[{"id":132747,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/132720\/revisions\/132747"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=132720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=132720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=132720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}