{"id":132987,"date":"2013-02-10T13:09:02","date_gmt":"2013-02-10T12:09:02","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=132987"},"modified":"2013-02-10T13:09:02","modified_gmt":"2013-02-10T12:09:02","slug":"el-calamar-portentoso-vuela-y-reacciona-con-la-musica-de-un-ipod","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987","title":{"rendered":"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod"},"content":{"rendered":"<p><span style=\"font-size: 13px; line-height: 19px;\">Los cefal\u00f3podos son realmente interesantes. De hecho hemos <a href=\"http:\/\/buscador.madrimasd.org\/search?sort=date%3AD%3AL%3Ad1&amp;ie=iso-8859-1&amp;oe=iso-8859-1&amp;output=xml_no_dtd&amp;site=blogs&amp;client=blog&amp;proxystylesheet=blog&amp;as_sitesearch=http%3A%2F%2Fwww.madrimasd.org%2Fblogs%2Fciencia_marina&amp;q=calamar&amp;x=0&amp;y=0\" target=\"_blank\">escrito sobre ellos<\/a> en varias <a href=\"http:\/\/buscador.madrimasd.org\/search?sort=date%3AD%3AL%3Ad1&amp;ie=iso-8859-1&amp;oe=iso-8859-1&amp;output=xml_no_dtd&amp;site=blogs&amp;client=blog&amp;proxystylesheet=blog&amp;as_sitesearch=http%3A%2F%2Fwww.madrimasd.org%2Fblogs%2Fciencia_marina&amp;q=pulpo&amp;x=0&amp;y=0\" target=\"_blank\">ocasiones<\/a>. Recientemente, <a href=\"http:\/\/www.elconfidencial.com\/tecnologia\/2013\/02\/10\/dos-novedades-los-calamares-vuelan-y-sabemos-como-lo-hacen-4206\/\" target=\"_blank\">un equipo de investigadores de la\u00a0<\/a><\/span><a href=\"http:\/\/www.elconfidencial.com\/tecnologia\/2013\/02\/10\/dos-novedades-los-calamares-vuelan-y-sabemos-como-lo-hacen-4206\/\" target=\"_blank\">Universidad de Hokkaido<\/a><span style=\"font-size: 13px; line-height: 19px;\">\u00a0(Jap\u00f3n) ha descrito las t\u00e9cnicas de propulsi\u00f3n de los calamares con las que logran salir del agua y deslizarse en el aire hasta 30 metros durante varios segundos.<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/2013020924squi_zpsd41a1def.jpeg\" alt=\"\" width=\"500\" height=\"203\" \/><\/p>\n<p><!--more--><br \/>\n\u00abEn un art\u00edculo titulado: \u00abEl calamar oce\u00e1nico vuela\u00bb, los expertos, describen este hecho como una sofisticada \u00abmaniobra de vuelo\u00bb.\u00a0Los expertos realizaron el estudio tras tomar fotograf\u00edas de hasta un centenar de moluscos desde un barco a unos 600 kil\u00f3metros al este de Tokio en 2011, seg\u00fan publica el diario\u00a0<em><a href=\"http:\/\/www.asahi.com\/tech_science\/update\/0208\/TKY201302080057.html\" target=\"_blank\">Asahi<\/a><\/em>.\u00bb<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/2013020927grafo_zps0c8cab4d.jpeg\" alt=\"\" width=\"500\" height=\"472\" \/><\/p>\n<p>\u00abEl equipo muestra c\u00f3mo despu\u00e9s de propulsarse fuera del mar, el cefal\u00f3podo es capaz de impulsarse a trav\u00e9s de un chorro de agua durante dos o tres segundos por el aire y ganar velocidad mediante la extensi\u00f3n de sus aletas y tent\u00e1culos, que utiliza a modo de alas.\u00a0El art\u00edculo, publicado en la revista cient\u00edfica alemana\u00a0<em>Biolog\u00eda Marina<\/em>\u00a0desvela adem\u00e1s que se trata de un movimiento que le sirve al calamar, de apenas 20 cent\u00edmetros de largo, como una maniobra de escape\u00a0<span style=\"font-size: 13px; line-height: 19px;\">cuando se ve amenazado por depredadores como atunes o delfines.\u00a0<\/span><span style=\"font-size: 13px; line-height: 19px;\">\u00a0\u00ab<\/span><\/p>\n<p>[youtube]http:\/\/www.youtube.com\/watch?v=sn7yx3DFthI[\/youtube]<\/p>\n<p><a href=\"http:\/\/hermes.mbl.edu\/mrc\/hanlon\/people.html\" target=\"_blank\">Paloma T. Gonz\u00e1lez Bellido<\/a>, \u00a0llev\u00f3 a cabo experimentos en el laboratorio de <a href=\"http:\/\/hermes.mbl.edu\/mrc\/hanlon\/\" target=\"_blank\">Roger Hanlon en Woods Hole<\/a>, con los axones de las neuronas de otra especie calamar y quedaron impresionados por la belleza de los r\u00e1pidos cambios del color de la piel. En la piel del calamar hay numerosas c\u00e9lulas de colores que reflejan la luz, los cromat\u00f3foros. Intent\u00f3 estimular el nervio de aleta directamente desde el iPod. Los resultados se pueden ver en el video presentado en <a href=\"http:\/\/www.imaginesciencefilms.org\/2012\/10\/10\/insane-in-the-chromatophores\/\" target=\"_blank\">Imagine Science Films Festival de Nueva York<\/a>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Squid-Prep_zps3c5c9654.png\" alt=\"\" width=\"500\" height=\"409\" \/><\/p>\n<p>El video se realiz\u00f3 con un microscopio con un aumento de 8x enfocado en la parte dorsal de la aleta del calamar. Emplearon un electrodo de succi\u00f3n para estimular el nervio de la aleta.<\/p>\n<p>[youtube]http:\/\/www.youtube.com\/watch?v=G-OVrI9x8Zs[\/youtube]<\/p>\n<p><span style=\"font-size: 13px; line-height: 19px;\">\u00abGreg Gage y Tim Marzullo son cofundadores de\u00a0<\/span><a style=\"font-size: 13px; line-height: 19px;\" href=\"http:\/\/www.backyardbrains.com\/\" target=\"_blank\">Backyard Brains<\/a><span style=\"font-size: 13px; line-height: 19px;\">, una empresa que vende kits de neurociencia para el cient\u00edfico informal, de guerrilla y aficionado. Mientras aprendes neurociencia, puedes conectar tu iPod a una cucaracha para que \u201cbaile\u201d al ritmo de tu m\u00fasica favorita.\u00bb<\/span><\/p>\n<p>[youtube]http:\/\/www.youtube.com\/watch?v=-mKen7tCDCs[\/youtube]<\/p>\n<p>Fuente: Secci\u00f3n de Tecnolog\u00eda de <a href=\"http:\/\/naukas.com\/2013\/01\/12\/video-conecta-un-calamar-a-tu-ipod\/\" target=\"_blank\">El Confidencial<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cefal\u00f3podos son realmente interesantes. De hecho hemos escrito sobre ellos en varias ocasiones. Recientemente, un equipo de investigadores de la\u00a0Universidad de Hokkaido\u00a0(Jap\u00f3n) ha descrito las t\u00e9cnicas de propulsi\u00f3n de los calamares con las que logran salir del agua y deslizarse en el aire hasta 30 metros durante varios segundos.<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[357,1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los cefal\u00f3podos son realmente interesantes. De hecho hemos escrito sobre ellos en varias ocasiones. Recientemente, un equipo de investigadores de la Universidad de Hokkaido (Jap\u00f3n) ha descrito las t\u00e9cnicas de propulsi\u00f3n de los calamares con las que logran salir del agua y deslizarse en el aire hasta 30 metros durante varios segundos. &quot;En un art\u00edculo titulado: &quot;El\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Los cefal\u00f3podos son realmente interesantes. De hecho hemos escrito sobre ellos en varias ocasiones. Recientemente, un equipo de investigadores de la Universidad de Hokkaido (Jap\u00f3n) ha descrito las t\u00e9cnicas de propulsi\u00f3n de los calamares con las que logran salir del agua y deslizarse en el aire hasta 30 metros durante varios segundos. &quot;En un art\u00edculo titulado: &quot;El\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-02-10T12:09:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-02-10T12:09:02+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los cefal\u00f3podos son realmente interesantes. De hecho hemos escrito sobre ellos en varias ocasiones. Recientemente, un equipo de investigadores de la Universidad de Hokkaido (Jap\u00f3n) ha descrito las t\u00e9cnicas de propulsi\u00f3n de los calamares con las que logran salir del agua y deslizarse en el aire hasta 30 metros durante varios segundos. &quot;En un art\u00edculo titulado: &quot;El\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/02\\\/10\\\/132987#blogposting\",\"name\":\"El calamar portentoso: vuela y reacciona con la m\\u00fasica de un iPod - Ciencia Marina y otros asuntos\",\"headline\":\"El calamar portentoso: vuela y reacciona con la m\\u00fasica de un iPod\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/img.photobucket.com\\\/albums\\\/v153\\\/rodaballo\\\/2013020924squi_zpsd41a1def.jpeg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/02\\\/10\\\/132987\\\/#articleImage\"},\"datePublished\":\"2013-02-10T13:09:02+01:00\",\"dateModified\":\"2013-02-10T13:09:02+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/02\\\/10\\\/132987#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/02\\\/10\\\/132987#webpage\"},\"articleSection\":\"Biolog\\u00eda Marina, General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/02\\\/10\\\/132987#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/02\\\/10\\\/132987#listItem\",\"name\":\"El calamar portentoso: vuela y reacciona con la m\\u00fasica de un iPod\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/02\\\/10\\\/132987#listItem\",\"position\":3,\"name\":\"El calamar portentoso: vuela y reacciona con la m\\u00fasica de un iPod\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/02\\\/10\\\/132987#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/02\\\/10\\\/132987\",\"name\":\"El calamar portentoso: vuela y reacciona con la m\\u00fasica de un iPod - Ciencia Marina y otros asuntos\",\"description\":\"Los cefal\\u00f3podos son realmente interesantes. De hecho hemos escrito sobre ellos en varias ocasiones. Recientemente, un equipo de investigadores de la Universidad de Hokkaido (Jap\\u00f3n) ha descrito las t\\u00e9cnicas de propulsi\\u00f3n de los calamares con las que logran salir del agua y deslizarse en el aire hasta 30 metros durante varios segundos. \\\"En un art\\u00edculo titulado: \\\"El\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/02\\\/10\\\/132987#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2013-02-10T13:09:02+01:00\",\"dateModified\":\"2013-02-10T13:09:02+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod - Ciencia Marina y otros asuntos","description":"Los cefal\u00f3podos son realmente interesantes. De hecho hemos escrito sobre ellos en varias ocasiones. Recientemente, un equipo de investigadores de la Universidad de Hokkaido (Jap\u00f3n) ha descrito las t\u00e9cnicas de propulsi\u00f3n de los calamares con las que logran salir del agua y deslizarse en el aire hasta 30 metros durante varios segundos. \"En un art\u00edculo titulado: \"El","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987#blogposting","name":"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod - Ciencia Marina y otros asuntos","headline":"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/2013020924squi_zpsd41a1def.jpeg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987\/#articleImage"},"datePublished":"2013-02-10T13:09:02+01:00","dateModified":"2013-02-10T13:09:02+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987#webpage"},"articleSection":"Biolog\u00eda Marina, General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987#listItem","name":"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987#listItem","position":3,"name":"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987","name":"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod - Ciencia Marina y otros asuntos","description":"Los cefal\u00f3podos son realmente interesantes. De hecho hemos escrito sobre ellos en varias ocasiones. Recientemente, un equipo de investigadores de la Universidad de Hokkaido (Jap\u00f3n) ha descrito las t\u00e9cnicas de propulsi\u00f3n de los calamares con las que logran salir del agua y deslizarse en el aire hasta 30 metros durante varios segundos. \"En un art\u00edculo titulado: \"El","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2013-02-10T13:09:02+01:00","dateModified":"2013-02-10T13:09:02+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod - Ciencia Marina y otros asuntos","og:description":"Los cefal\u00f3podos son realmente interesantes. De hecho hemos escrito sobre ellos en varias ocasiones. Recientemente, un equipo de investigadores de la Universidad de Hokkaido (Jap\u00f3n) ha descrito las t\u00e9cnicas de propulsi\u00f3n de los calamares con las que logran salir del agua y deslizarse en el aire hasta 30 metros durante varios segundos. &quot;En un art\u00edculo titulado: &quot;El","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2013-02-10T12:09:02+00:00","article:modified_time":"2013-02-10T12:09:02+00:00","twitter:card":"summary","twitter:title":"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod - Ciencia Marina y otros asuntos","twitter:description":"Los cefal\u00f3podos son realmente interesantes. De hecho hemos escrito sobre ellos en varias ocasiones. Recientemente, un equipo de investigadores de la Universidad de Hokkaido (Jap\u00f3n) ha descrito las t\u00e9cnicas de propulsi\u00f3n de los calamares con las que logran salir del agua y deslizarse en el aire hasta 30 metros durante varios segundos. &quot;En un art\u00edculo titulado: &quot;El","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"132987","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-04 12:19:13","updated":"2026-05-26 18:53:21","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"El calamar portentoso: vuela y reacciona con la m\u00fasica de un iPod","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/02\/10\/132987"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/132987"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=132987"}],"version-history":[{"count":19,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/132987\/revisions"}],"predecessor-version":[{"id":133006,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/132987\/revisions\/133006"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=132987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=132987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=132987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}