{"id":133068,"date":"2013-05-06T12:39:21","date_gmt":"2013-05-06T11:39:21","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=133068"},"modified":"2013-05-06T17:53:49","modified_gmt":"2013-05-06T16:53:49","slug":"politica-y-ciencia","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068","title":{"rendered":"Pol\u00edtica y Ciencia"},"content":{"rendered":"<p><span style=\"font-size: 13px; line-height: 19px;\">En un art\u00edculo titulado\u00a0<\/span><span style=\"font-size: 13px; line-height: 19px;\">\u00bf<a href=\"http:\/\/blogs.elconfidencial.com\/tecnologia\/eureka\/2013\/05\/06\/deben-los-politicos-decidir-que-ciencia-se-financia-con-fondos-publicos-4827\" target=\"_blank\">Deben los pol\u00edticos decidir qu\u00e9 ciencia se financia con fondos p\u00fablicos<\/a>?, Patricia Fern\u00e1ndez de Lis se hace eco de la pol\u00e9mica suscitada recientemente en Estados Unidos.<\/span><\/p>\n<p>\u00abEl congresista republicano por Texas\u00a0<strong>Lamar Smith<\/strong>\u00a0ha presentado una propuesta de ley en la que sugiere que, antes de conceder una beca o ayuda p\u00fablica, el director de la<a href=\"http:\/\/www.nsf.gov\/\" target=\"_blank\">\u00a0Fundaci\u00f3n Nacional de Ciencias<\/a>\u00a0(NSF, por sus siglas en ingl\u00e9s) debe confirmar por escrito que esa investigaci\u00f3n es \u201cpionera y de la m\u00e1s alta calidad, que responde preguntas o resuelve problemas que son de importancia para la sociedad, y que no duplica cualquier otra investigaci\u00f3n financiada por una agencia federal\u201d. Otro senador republicano,\u00a0<strong>Tom Coburn<\/strong>, exig\u00eda hace unos meses que los cient\u00edficos que utilicen fondos p\u00fablicos demuestren que obtienen resultados econ\u00f3micos o que sus estudios son vitales para la seguridad nacional.\u00bb<\/p>\n<p><!--more--><\/p>\n<p>\u00abLa pol\u00e9mica ha sido de tal calibre que el presidente\u00a0<strong>Barack Obama<\/strong>, en un discurso pronunciado el martes pasado en la propia NSF, realiz\u00f3 una defensa cerrada del \u201criguroso\u201d sistema de revisi\u00f3n por pares para \u201cmantener la ventaja competitiva\u201d de la ciencia estadounidense.\u00bb<\/p>\n<p>Vean dos videos.<\/p>\n<p>[youtube]http:\/\/www.youtube.com\/watch?v=GlOlz2aPiKs[\/youtube]<\/p>\n<p>&nbsp;<\/p>\n<p>[vimeo]http:\/\/vimeo.com\/65081399[\/vimeo]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un art\u00edculo titulado\u00a0\u00bfDeben los pol\u00edticos decidir qu\u00e9 ciencia se financia con fondos p\u00fablicos?, Patricia Fern\u00e1ndez de Lis se hace eco de la pol\u00e9mica suscitada recientemente en Estados Unidos. \u00abEl congresista republicano por Texas\u00a0Lamar Smith\u00a0ha presentado una propuesta de ley en la que sugiere que, antes de conceder una beca o ayuda p\u00fablica, el director de la\u00a0Fundaci\u00f3n Nacional de Ciencias\u00a0(NSF, por sus siglas en ingl\u00e9s) debe confirmar por escrito que esa investigaci\u00f3n es \u201cpionera y de la m\u00e1s alta calidad, que responde preguntas o resuelve problemas que son de importancia para la sociedad, y que no duplica cualquier otra investigaci\u00f3n\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En un art\u00edculo titulado \u00bfDeben los pol\u00edticos decidir qu\u00e9 ciencia se financia con fondos p\u00fablicos?, Patricia Fern\u00e1ndez de Lis se hace eco de la pol\u00e9mica suscitada recientemente en Estados Unidos. &quot;El congresista republicano por Texas Lamar Smith ha presentado una propuesta de ley en la que sugiere que, antes de conceder una beca o ayuda p\u00fablica, el director\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pol\u00edtica y Ciencia - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"En un art\u00edculo titulado \u00bfDeben los pol\u00edticos decidir qu\u00e9 ciencia se financia con fondos p\u00fablicos?, Patricia Fern\u00e1ndez de Lis se hace eco de la pol\u00e9mica suscitada recientemente en Estados Unidos. &quot;El congresista republicano por Texas Lamar Smith ha presentado una propuesta de ley en la que sugiere que, antes de conceder una beca o ayuda p\u00fablica, el director\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-05-06T11:39:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-05-06T16:53:49+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pol\u00edtica y Ciencia - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En un art\u00edculo titulado \u00bfDeben los pol\u00edticos decidir qu\u00e9 ciencia se financia con fondos p\u00fablicos?, Patricia Fern\u00e1ndez de Lis se hace eco de la pol\u00e9mica suscitada recientemente en Estados Unidos. &quot;El congresista republicano por Texas Lamar Smith ha presentado una propuesta de ley en la que sugiere que, antes de conceder una beca o ayuda p\u00fablica, el director\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/05\\\/06\\\/133068#blogposting\",\"name\":\"Pol\\u00edtica y Ciencia - Ciencia Marina y otros asuntos\",\"headline\":\"Pol\\u00edtica y Ciencia\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/05\\\/06\\\/133068\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2013-05-06T12:39:21+01:00\",\"dateModified\":\"2013-05-06T17:53:49+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/05\\\/06\\\/133068#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/05\\\/06\\\/133068#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/05\\\/06\\\/133068#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/05\\\/06\\\/133068#listItem\",\"name\":\"Pol\\u00edtica y Ciencia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/05\\\/06\\\/133068#listItem\",\"position\":3,\"name\":\"Pol\\u00edtica y Ciencia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/05\\\/06\\\/133068#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/05\\\/06\\\/133068\",\"name\":\"Pol\\u00edtica y Ciencia - Ciencia Marina y otros asuntos\",\"description\":\"En un art\\u00edculo titulado \\u00bfDeben los pol\\u00edticos decidir qu\\u00e9 ciencia se financia con fondos p\\u00fablicos?, Patricia Fern\\u00e1ndez de Lis se hace eco de la pol\\u00e9mica suscitada recientemente en Estados Unidos. \\\"El congresista republicano por Texas Lamar Smith ha presentado una propuesta de ley en la que sugiere que, antes de conceder una beca o ayuda p\\u00fablica, el director\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2013\\\/05\\\/06\\\/133068#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2013-05-06T12:39:21+01:00\",\"dateModified\":\"2013-05-06T17:53:49+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pol\u00edtica y Ciencia - Ciencia Marina y otros asuntos","description":"En un art\u00edculo titulado \u00bfDeben los pol\u00edticos decidir qu\u00e9 ciencia se financia con fondos p\u00fablicos?, Patricia Fern\u00e1ndez de Lis se hace eco de la pol\u00e9mica suscitada recientemente en Estados Unidos. \"El congresista republicano por Texas Lamar Smith ha presentado una propuesta de ley en la que sugiere que, antes de conceder una beca o ayuda p\u00fablica, el director","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068#blogposting","name":"Pol\u00edtica y Ciencia - Ciencia Marina y otros asuntos","headline":"Pol\u00edtica y Ciencia","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068\/#articleImage","width":217,"height":72},"datePublished":"2013-05-06T12:39:21+01:00","dateModified":"2013-05-06T17:53:49+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068#listItem","name":"Pol\u00edtica y Ciencia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068#listItem","position":3,"name":"Pol\u00edtica y Ciencia","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068","name":"Pol\u00edtica y Ciencia - Ciencia Marina y otros asuntos","description":"En un art\u00edculo titulado \u00bfDeben los pol\u00edticos decidir qu\u00e9 ciencia se financia con fondos p\u00fablicos?, Patricia Fern\u00e1ndez de Lis se hace eco de la pol\u00e9mica suscitada recientemente en Estados Unidos. \"El congresista republicano por Texas Lamar Smith ha presentado una propuesta de ley en la que sugiere que, antes de conceder una beca o ayuda p\u00fablica, el director","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2013-05-06T12:39:21+01:00","dateModified":"2013-05-06T17:53:49+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Pol\u00edtica y Ciencia - Ciencia Marina y otros asuntos","og:description":"En un art\u00edculo titulado \u00bfDeben los pol\u00edticos decidir qu\u00e9 ciencia se financia con fondos p\u00fablicos?, Patricia Fern\u00e1ndez de Lis se hace eco de la pol\u00e9mica suscitada recientemente en Estados Unidos. &quot;El congresista republicano por Texas Lamar Smith ha presentado una propuesta de ley en la que sugiere que, antes de conceder una beca o ayuda p\u00fablica, el director","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2013-05-06T11:39:21+00:00","article:modified_time":"2013-05-06T16:53:49+00:00","twitter:card":"summary","twitter:title":"Pol\u00edtica y Ciencia - Ciencia Marina y otros asuntos","twitter:description":"En un art\u00edculo titulado \u00bfDeben los pol\u00edticos decidir qu\u00e9 ciencia se financia con fondos p\u00fablicos?, Patricia Fern\u00e1ndez de Lis se hace eco de la pol\u00e9mica suscitada recientemente en Estados Unidos. &quot;El congresista republicano por Texas Lamar Smith ha presentado una propuesta de ley en la que sugiere que, antes de conceder una beca o ayuda p\u00fablica, el director","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"133068","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-09 12:24:15","updated":"2026-05-26 18:54:37","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPol\u00edtica y Ciencia\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Pol\u00edtica y Ciencia","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2013\/05\/06\/133068"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/133068"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=133068"}],"version-history":[{"count":2,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/133068\/revisions"}],"predecessor-version":[{"id":133072,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/133068\/revisions\/133072"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=133068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=133068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=133068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}