{"id":133529,"date":"2014-06-09T09:42:22","date_gmt":"2014-06-09T08:42:22","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=133529"},"modified":"2014-06-09T09:42:22","modified_gmt":"2014-06-09T08:42:22","slug":"dia-de-los-oceanos-2014","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529","title":{"rendered":"D\u00eda de los oc\u00e9anos 2014"},"content":{"rendered":"<p>Ayer fue el d\u00eda de los oc\u00e9anos.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/image004.jpg\" alt=\"\" width=\"450\" \/><!--more--><\/p>\n<p>Este\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2012\/06\/08\/132750\" target=\"_blank\">D\u00eda<\/a>, fue\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2007\/06\/08\/67289\" target=\"_blank\">creado<\/a>\u00a0en 1992 durante la Cumbre Mundial en R\u00edo de Janeiro En virtud de su\u00a0resoluci\u00f3n 63\/111, de fecha 5 de diciembre de 2008,\u00a0<a href=\"http:\/\/www.un.org\/es\/events\/oceansday\/\" target=\"_blank\">la Asamblea General decidi\u00f3<\/a>\u00a0que a partir de 2009, las Naciones Unidas designen el 8 de junio D\u00eda Mundial de los Oc\u00e9anos.<\/p>\n<p>\u00abCon ocasi\u00f3n del D\u00eda Mundial de los Oc\u00e9anos, <a href=\"http:\/\/oceana.org\/es\/eu\/prensa-e-informes\/comunicados-de-prensa\/oceana-llama-la-atencion-sobre-los-olvidados-del-mar\" target=\"_blank\">Oceana<\/a> llama la atenci\u00f3n sobre\u00a0<a href=\"http:\/\/bit.ly\/1i8iPYz\">los olvidados del mar<\/a>, una lista de especies y h\u00e1bitats marinos elaborada por la organizaci\u00f3n internacional de conservaci\u00f3n marina. Todos ellos merecen protecci\u00f3n o medidas de conservaci\u00f3n urgentes por su importancia para el ecosistema, y representan a muchos otros desatendidos por la normativa.\u00bb<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/sql-img.jpg\" alt=\"\" width=\"450\" \/><\/p>\n<p><span style=\"font-size: 13px;\">\u00abLa lista de los olvidados incluye:<\/span><\/p>\n<p>Especies olvidadas<\/p>\n<p><a style=\"font-size: 13px;\" href=\"http:\/\/es.wikipedia.org\/wiki\/Xiphias_gladius\" target=\"_blank\">Pez espada<\/a><span style=\"font-size: 13px;\">: A pesar de ser una importante especie comercial, sufre sobrepesca y carece de planes de gesti\u00f3n en el Mediterr\u00e1neo, donde se explota sin control. En el pasado, los ejemplares llegaban a superar los 4,5 metros, pero hoy en d\u00eda los que se capturan est\u00e1n entre 1 y 2.<\/span><\/p>\n<p><a href=\"http:\/\/es.wikipedia.org\/wiki\/Cocolit%C3%B3foro\" target=\"_blank\">Cocolit\u00f3foros<\/a>. Estas algas unicelulares capturan CO2, producen una enorme cantidad de ox\u00edgeno y son el alimento de muchos organismos, pero est\u00e1n amenazadas por la acidificaci\u00f3n marina provocada por el cambio clim\u00e1tico y no hay planes para protegerlas.<\/p>\n<p><a href=\"http:\/\/es.wikipedia.org\/wiki\/Rhinobatidae\" target=\"_blank\">Pez guitarra<\/a> y <a href=\"http:\/\/es.wikipedia.org\/wiki\/Pristiformes\" target=\"_blank\">pez sierra<\/a>: Ambos est\u00e1n en la <a href=\"http:\/\/www.iucn.org\/es\/sobre\/union\/secretaria\/oficinas\/sudamerica\/sur_trabajo\/sur_especies\/sur_listaroja\/\" target=\"_blank\">Lista Roja de la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza<\/a> como \u201cEn Peligro Cr\u00edtico\u201d y muchas de sus poblaciones han desaparecido ya antes de ser protegidos.<\/p>\n<p>[youtube]http:\/\/www.youtube.com\/watch?v=N-WTpvFzjbA[\/youtube]<\/p>\n<p>Los <a href=\"http:\/\/es.wikipedia.org\/wiki\/Isididae\" target=\"_blank\">corales bamb\u00fa<\/a> viven en fondos fangosos en los que se permiten pesquer\u00edas destructivas y han desaparecido de muchos lugares. La legislaci\u00f3n europea apenas les protege, pese a ser esenciales para muchas otras especies.<\/p>\n<p>Los cefal\u00f3podos son especies clave para muchos depredadores, como delfines, tiburones, tortugas o pez espada, pero apenas gozan de medidas de gesti\u00f3n en el plano mundial.\u00bb<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/AL-084.jpg\" alt=\"\" width=\"450\" \/><\/p>\n<p>\u00abH\u00e1bitats olvidados<\/p>\n<p><span style=\"font-size: 13px;\">H\u00e1bitats polares: No est\u00e1n contemplados en convenios internacionales, a pesar de encontrarse en grave riesgo por el cambio clim\u00e1tico y de que recientes descubrimientos sugieren que albergan especies \u00fanicas.<\/span><\/p>\n<p>Comunidades de <a href=\"http:\/\/www.marinespecies.org\/aphia.php?p=taxdetails&amp;id=101954\" target=\"_blank\">Haploops<\/a>: Este h\u00e1bitat formado por crust\u00e1ceos es poco conocido, pero reviste gran importancia para la alimentaci\u00f3n de especies comerciales como el bacalao o peces planos. Apenas hay informaci\u00f3n sobre su distribuci\u00f3n ni planes de gesti\u00f3n para su conservaci\u00f3n.<\/p>\n<p>Las piscinas de salmuera de aguas profundas son masas de agua de elevada salinidad que albergan organismos quimiosint\u00e9ticos (bacterias) que no dependen de la luz solar para su supervivencia. Forman asociaciones especiales con otros organismos en condiciones extremas, creando focos de biodiversidad \u00fanicos.<\/p>\n<p>Los ecosistemas f\u00f3siles y subf\u00f3siles \u00a0\u2013como los formados por corales, bivalvos y esponjas\u2013 sirven para ofrecer sustrato y nutrientes a otras especies, e incluso se pueden encontrar algunos vivos.<\/p>\n<p>Las zonas de puesta de peces son h\u00e1bitats esenciales en el ciclo vital de las especies, pero en muchos casos carecen de protecci\u00f3n.\u00bb<\/p>\n<p>Para m\u00e1s informaci\u00f3n les recomienden visiten con frecuencia la p\u00e1gina de <a href=\"http:\/\/oceana.org\/es\/eu\/portada\" target=\"_blank\">Oceana<\/a>.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2013\/06\/tierra-nasa-644x362.jpg\"><img decoding=\"async\" title=\"tierra-nasa--644x362\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2013\/06\/tierra-nasa-644x362.jpg\" alt=\"\" width=\"500\" height=\"281\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer fue el d\u00eda de los oc\u00e9anos.<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[357,363,1,358],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ayer fue el d\u00eda de los oc\u00e9anos. Este D\u00eda, fue creado en 1992 durante la Cumbre Mundial en R\u00edo de Janeiro En virtud de su resoluci\u00f3n 63\/111, de fecha 5 de diciembre de 2008, la Asamblea General decidi\u00f3 que a partir de 2009, las Naciones Unidas designen el 8 de junio D\u00eda Mundial de los Oc\u00e9anos. &quot;Con ocasi\u00f3n del D\u00eda Mundial\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"D\u00eda de los oc\u00e9anos 2014 - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Ayer fue el d\u00eda de los oc\u00e9anos. Este D\u00eda, fue creado en 1992 durante la Cumbre Mundial en R\u00edo de Janeiro En virtud de su resoluci\u00f3n 63\/111, de fecha 5 de diciembre de 2008, la Asamblea General decidi\u00f3 que a partir de 2009, las Naciones Unidas designen el 8 de junio D\u00eda Mundial de los Oc\u00e9anos. &quot;Con ocasi\u00f3n del D\u00eda Mundial\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-09T08:42:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-09T08:42:22+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"D\u00eda de los oc\u00e9anos 2014 - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ayer fue el d\u00eda de los oc\u00e9anos. Este D\u00eda, fue creado en 1992 durante la Cumbre Mundial en R\u00edo de Janeiro En virtud de su resoluci\u00f3n 63\/111, de fecha 5 de diciembre de 2008, la Asamblea General decidi\u00f3 que a partir de 2009, las Naciones Unidas designen el 8 de junio D\u00eda Mundial de los Oc\u00e9anos. &quot;Con ocasi\u00f3n del D\u00eda Mundial\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2014\\\/06\\\/09\\\/133529#blogposting\",\"name\":\"D\\u00eda de los oc\\u00e9anos 2014 - Ciencia Marina y otros asuntos\",\"headline\":\"D\\u00eda de los oc\\u00e9anos 2014\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/img.photobucket.com\\\/albums\\\/v153\\\/rodaballo\\\/Weblog\\\/image004.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2014\\\/06\\\/09\\\/133529\\\/#articleImage\"},\"datePublished\":\"2014-06-09T09:42:22+01:00\",\"dateModified\":\"2014-06-09T09:42:22+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2014\\\/06\\\/09\\\/133529#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2014\\\/06\\\/09\\\/133529#webpage\"},\"articleSection\":\"Biolog\\u00eda Marina, Cambio global, General, Investigaci\\u00f3n Marina En Espa\\u00f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2014\\\/06\\\/09\\\/133529#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2014\\\/06\\\/09\\\/133529#listItem\",\"name\":\"D\\u00eda de los oc\\u00e9anos 2014\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2014\\\/06\\\/09\\\/133529#listItem\",\"position\":3,\"name\":\"D\\u00eda de los oc\\u00e9anos 2014\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2014\\\/06\\\/09\\\/133529#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2014\\\/06\\\/09\\\/133529\",\"name\":\"D\\u00eda de los oc\\u00e9anos 2014 - Ciencia Marina y otros asuntos\",\"description\":\"Ayer fue el d\\u00eda de los oc\\u00e9anos. Este D\\u00eda, fue creado en 1992 durante la Cumbre Mundial en R\\u00edo de Janeiro En virtud de su resoluci\\u00f3n 63\\\/111, de fecha 5 de diciembre de 2008, la Asamblea General decidi\\u00f3 que a partir de 2009, las Naciones Unidas designen el 8 de junio D\\u00eda Mundial de los Oc\\u00e9anos. \\\"Con ocasi\\u00f3n del D\\u00eda Mundial\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2014\\\/06\\\/09\\\/133529#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2014-06-09T09:42:22+01:00\",\"dateModified\":\"2014-06-09T09:42:22+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"D\u00eda de los oc\u00e9anos 2014 - Ciencia Marina y otros asuntos","description":"Ayer fue el d\u00eda de los oc\u00e9anos. Este D\u00eda, fue creado en 1992 durante la Cumbre Mundial en R\u00edo de Janeiro En virtud de su resoluci\u00f3n 63\/111, de fecha 5 de diciembre de 2008, la Asamblea General decidi\u00f3 que a partir de 2009, las Naciones Unidas designen el 8 de junio D\u00eda Mundial de los Oc\u00e9anos. \"Con ocasi\u00f3n del D\u00eda Mundial","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529#blogposting","name":"D\u00eda de los oc\u00e9anos 2014 - Ciencia Marina y otros asuntos","headline":"D\u00eda de los oc\u00e9anos 2014","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"http:\/\/img.photobucket.com\/albums\/v153\/rodaballo\/Weblog\/image004.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529\/#articleImage"},"datePublished":"2014-06-09T09:42:22+01:00","dateModified":"2014-06-09T09:42:22+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529#webpage"},"articleSection":"Biolog\u00eda Marina, Cambio global, General, Investigaci\u00f3n Marina En Espa\u00f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529#listItem","name":"D\u00eda de los oc\u00e9anos 2014"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529#listItem","position":3,"name":"D\u00eda de los oc\u00e9anos 2014","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529","name":"D\u00eda de los oc\u00e9anos 2014 - Ciencia Marina y otros asuntos","description":"Ayer fue el d\u00eda de los oc\u00e9anos. Este D\u00eda, fue creado en 1992 durante la Cumbre Mundial en R\u00edo de Janeiro En virtud de su resoluci\u00f3n 63\/111, de fecha 5 de diciembre de 2008, la Asamblea General decidi\u00f3 que a partir de 2009, las Naciones Unidas designen el 8 de junio D\u00eda Mundial de los Oc\u00e9anos. \"Con ocasi\u00f3n del D\u00eda Mundial","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2014-06-09T09:42:22+01:00","dateModified":"2014-06-09T09:42:22+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"D\u00eda de los oc\u00e9anos 2014 - Ciencia Marina y otros asuntos","og:description":"Ayer fue el d\u00eda de los oc\u00e9anos. Este D\u00eda, fue creado en 1992 durante la Cumbre Mundial en R\u00edo de Janeiro En virtud de su resoluci\u00f3n 63\/111, de fecha 5 de diciembre de 2008, la Asamblea General decidi\u00f3 que a partir de 2009, las Naciones Unidas designen el 8 de junio D\u00eda Mundial de los Oc\u00e9anos. &quot;Con ocasi\u00f3n del D\u00eda Mundial","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2014-06-09T08:42:22+00:00","article:modified_time":"2014-06-09T08:42:22+00:00","twitter:card":"summary","twitter:title":"D\u00eda de los oc\u00e9anos 2014 - Ciencia Marina y otros asuntos","twitter:description":"Ayer fue el d\u00eda de los oc\u00e9anos. Este D\u00eda, fue creado en 1992 durante la Cumbre Mundial en R\u00edo de Janeiro En virtud de su resoluci\u00f3n 63\/111, de fecha 5 de diciembre de 2008, la Asamblea General decidi\u00f3 que a partir de 2009, las Naciones Unidas designen el 8 de junio D\u00eda Mundial de los Oc\u00e9anos. &quot;Con ocasi\u00f3n del D\u00eda Mundial","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"133529","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-11 04:34:55","updated":"2026-05-26 19:05:18","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tD\u00eda de los oc\u00e9anos 2014\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"D\u00eda de los oc\u00e9anos 2014","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2014\/06\/09\/133529"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/133529"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=133529"}],"version-history":[{"count":1,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/133529\/revisions"}],"predecessor-version":[{"id":133531,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/133529\/revisions\/133531"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=133529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=133529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=133529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}