{"id":134681,"date":"2017-02-16T09:42:51","date_gmt":"2017-02-16T08:42:51","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=134681"},"modified":"2017-02-16T09:42:51","modified_gmt":"2017-02-16T08:42:51","slug":"el-narval-la-leyenda-del-unicornio","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681","title":{"rendered":"El narval. La leyenda del unicornio."},"content":{"rendered":"<p>Se cree que\u00a0el\u00a0mito del unicornio \u00a0puede tener su origen en el <a href=\"http:\/\/www.fordivers.com\/es\/fauna\/especie\/narval\/\" target=\"_blank\">colmillo del narval<\/a>. En la Edad Media se emple\u00f3 su colmillo para curar la epilepsia, fortalecer el coraz\u00f3n y mitigar ciertos venenos. Como la mayor\u00eda de los cuernos o vegetales y animales alargados se empleaba y emplea, como no, para solucionar los problemas de impotencia sexual masculina&#8230; Isabel I de Inglaterra ten\u00eda un colmillo de narval como una de sus posesiones mas estimadas. Por todas estas razones y alguna que se me escapa, hemos cazado narvales para comerciar con su colmillo desde hace siglos. \u00bfCu\u00e1l es realmente la funci\u00f3n de este intrigante cuerno?<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/narval2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-134686\" title=\"narval2\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/narval2.jpg\" alt=\"\" width=\"500\" height=\"343\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/narval2.jpg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/narval2-300x205.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p>\u00abEl <a href=\"https:\/\/es.wikipedia.org\/wiki\/Monodon_monoceros\" target=\"_blank\">narval<\/a> (Monodon monoceros) es una especie de cet\u00e1ceo odontoceto de la familia Monodontidae que habita los mares del \u00c1rtico y el norte del Oc\u00e9ano Atl\u00e1ntico. Es el \u00fanico integrante del g\u00e9nero Monodon y una de las dos especies de la familia junto a la beluga (Delphinapterus leucas). Los machos de esta especie se caracterizan por presentar un colmillo muy largo y retorcido de manera helicoidal que puede llegar a medir dos metros y pesar hasta diez kilogramos, (En el Museo Rocsen en Tanti, provincia de C\u00f3rdoba en la Rep\u00fablica Argentina poseen un colmillo de 2,7 metros que seg\u00fan dice el fundador Juan Bouchon es el m\u00e1s grande del mundo). \u00bb<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/cuerno-narval1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-134688\" title=\"cuerno-narval\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/cuerno-narval1.jpg\" alt=\"\" width=\"500\" height=\"333\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/cuerno-narval1.jpg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/cuerno-narval1-300x199.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Se distribuye principalmente en aguas de la regi\u00f3n \u00e1rtica del norte de Canad\u00e1, los mares del lado ruso del oc\u00e9ano \u00c1rtico y al norte del oc\u00e9ano Atl\u00e1ntico. Habita principalmente en torno a los bloques de hielo que se forman durante los inviernos prolongados del \u00c1rtico, migrando a las bah\u00edas y fiordos circumpolares durante el verano. Se cree que la poblaci\u00f3n mundial es de algo m\u00e1s de 75 000 ejemplares. En 2008 fue catalogado en la Lista Roja de la UICN como especie casi amenazada, debido a que se mantiene una caza significativa, controlada, por parte del pueblo inuit en Canad\u00e1 y Groenlandia (Dinamarca), los cuales se benefician con su carne, grasa y el comercio del colmillo.\u00bb<\/p>\n<p>[youtube]https:\/\/www.youtube.com\/watch?v=YO58kt-jETA[\/youtube]<\/p>\n<p>\u00bfY la funci\u00f3n del colmillo o cuerno del unicornio marino?<\/p>\n<p>Se ha dicho de todo, desde que lo usan de brocheta para<strong>\u00a0ensartar peces<\/strong>\u00a0hasta que se trata de\u00a0<strong>un reclamo sexual<\/strong>.<\/p>\n<p>En un <a href=\"http:\/\/omicrono.elespanol.com\/2016\/06\/colmillo-de-los-narvales\/\" target=\"_blank\">trabajo<\/a> se afirma \u00abque este\u00a0colmillo\u00a0es un\u00a0<a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1002\/ar.22886\/abstract\" target=\"_blank\">sensor<\/a>\u00a0utilizado para estudiar par\u00e1metros del agua como\u00a0la salinidad o la temperatura.\u00a0Esta teor\u00eda se sostiene por\u00a0varios motivos. Por un lado, al contrario de lo que ocurre con otras piezas dentales, el colmillo no est\u00e1 recubierto de\u00a0esmalte, por lo que el agua penetra directamente en \u00e9l, avanzando por una especie de\u00a0t\u00fabulos\u00a0hasta su base, donde se excitan las\u00a0terminaciones nerviosas\u00a0de la pulpa dental, que enviar\u00e1n al\u00a0cerebro\u00a0una serie de se\u00f1ales sobre las\u00a0caracter\u00edsticas del agua\u00a0que se ha filtrado hasta ellas. Adem\u00e1s, se ha comprobado que cuando se modifican\u00a0levemente las caracter\u00edsticas del agua en la que se encuentra el animal, su\u00a0ritmo card\u00edaco\u00a0var\u00eda notablemente, posiblemente por la percepci\u00f3n de estos cambios a trav\u00e9s del colmillo.\u00bb<\/p>\n<p>[youtube]https:\/\/www.youtube.com\/watch?v=gqlAM6zmxxw[\/youtube]<\/p>\n<p>Hay otra caracter\u00edstica de esta especie que llama la atenci\u00f3n. Los narvales pasan el invierno medio aislados en la bah\u00eda de Baffin, hasta que el hielo les permite emigrar a nuevas aguas. <a href=\"http:\/\/www.vozpopuli.com\/next\/sonar-narvales-especial_0_968903621.html\" target=\"_blank\">Investigadores alemanes<\/a> colocaron hidr\u00f3fonos en 11 lugares estrat\u00e9gicos de Groenlandia y registraron los sonidos de estos animales a una profundidad de entre 3 y 18 metros. Los datos recogido revelan que las llamadas de ecolocalizaci\u00f3n de los narvales son las m\u00e1s direccionales de la naturaleza y que sus clics se estrechan probablemente para evitar el rebote sobre la superficie helada del mar. \u00bb<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/narval.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-134689\" title=\"narval\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/narval.jpg\" alt=\"\" width=\"500\" height=\"238\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/narval.jpg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/narval-300x142.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Desde luego el narval es una especie poco conocida y que con caracter\u00edsticas sorprendentes. Esperemos que siga existiendo muchos a\u00f1os.<\/p>\n<p>[youtube]https:\/\/www.youtube.com\/watch?v=MSjjHiysBbE[\/youtube]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se cree que\u00a0el\u00a0mito del unicornio \u00a0puede tener su origen en el colmillo del narval. En la Edad Media se emple\u00f3 su colmillo para curar la epilepsia, fortalecer el coraz\u00f3n y mitigar ciertos venenos. Como la mayor\u00eda de los cuernos o vegetales y animales alargados se empleaba y emplea, como no, para solucionar los problemas de impotencia sexual masculina&#8230; Isabel I de Inglaterra ten\u00eda un colmillo de narval como una de sus posesiones mas estimadas. Por todas estas razones y alguna que se me escapa, hemos cazado narvales para comerciar con su colmillo desde hace siglos. \u00bfCu\u00e1l es realmente la funci\u00f3n\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[357,1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Se cree que el mito del unicornio puede tener su origen en el colmillo del narval. En la Edad Media se emple\u00f3 su colmillo para curar la epilepsia, fortalecer el coraz\u00f3n y mitigar ciertos venenos. Como la mayor\u00eda de los cuernos o vegetales y animales alargados se empleaba y emplea, como no, para solucionar los problemas de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El narval. La leyenda del unicornio. - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Se cree que el mito del unicornio puede tener su origen en el colmillo del narval. En la Edad Media se emple\u00f3 su colmillo para curar la epilepsia, fortalecer el coraz\u00f3n y mitigar ciertos venenos. Como la mayor\u00eda de los cuernos o vegetales y animales alargados se empleaba y emplea, como no, para solucionar los problemas de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-02-16T08:42:51+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-02-16T08:42:51+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El narval. La leyenda del unicornio. - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Se cree que el mito del unicornio puede tener su origen en el colmillo del narval. En la Edad Media se emple\u00f3 su colmillo para curar la epilepsia, fortalecer el coraz\u00f3n y mitigar ciertos venenos. Como la mayor\u00eda de los cuernos o vegetales y animales alargados se empleaba y emplea, como no, para solucionar los problemas de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2017\\\/02\\\/16\\\/134681#blogposting\",\"name\":\"El narval. La leyenda del unicornio. - Ciencia Marina y otros asuntos\",\"headline\":\"El narval. La leyenda del unicornio.\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2017\\\/02\\\/narval2.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2017\\\/02\\\/16\\\/134681\\\/#articleImage\",\"width\":500,\"height\":343},\"datePublished\":\"2017-02-16T09:42:51+01:00\",\"dateModified\":\"2017-02-16T09:42:51+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2017\\\/02\\\/16\\\/134681#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2017\\\/02\\\/16\\\/134681#webpage\"},\"articleSection\":\"Biolog\\u00eda Marina, General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2017\\\/02\\\/16\\\/134681#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2017\\\/02\\\/16\\\/134681#listItem\",\"name\":\"El narval. La leyenda del unicornio.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2017\\\/02\\\/16\\\/134681#listItem\",\"position\":3,\"name\":\"El narval. La leyenda del unicornio.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2017\\\/02\\\/16\\\/134681#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2017\\\/02\\\/16\\\/134681\",\"name\":\"El narval. La leyenda del unicornio. - Ciencia Marina y otros asuntos\",\"description\":\"Se cree que el mito del unicornio puede tener su origen en el colmillo del narval. En la Edad Media se emple\\u00f3 su colmillo para curar la epilepsia, fortalecer el coraz\\u00f3n y mitigar ciertos venenos. Como la mayor\\u00eda de los cuernos o vegetales y animales alargados se empleaba y emplea, como no, para solucionar los problemas de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2017\\\/02\\\/16\\\/134681#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2017-02-16T09:42:51+01:00\",\"dateModified\":\"2017-02-16T09:42:51+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El narval. La leyenda del unicornio. - Ciencia Marina y otros asuntos","description":"Se cree que el mito del unicornio puede tener su origen en el colmillo del narval. En la Edad Media se emple\u00f3 su colmillo para curar la epilepsia, fortalecer el coraz\u00f3n y mitigar ciertos venenos. Como la mayor\u00eda de los cuernos o vegetales y animales alargados se empleaba y emplea, como no, para solucionar los problemas de","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681#blogposting","name":"El narval. La leyenda del unicornio. - Ciencia Marina y otros asuntos","headline":"El narval. La leyenda del unicornio.","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2017\/02\/narval2.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681\/#articleImage","width":500,"height":343},"datePublished":"2017-02-16T09:42:51+01:00","dateModified":"2017-02-16T09:42:51+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681#webpage"},"articleSection":"Biolog\u00eda Marina, General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681#listItem","name":"El narval. La leyenda del unicornio."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681#listItem","position":3,"name":"El narval. La leyenda del unicornio.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681","name":"El narval. La leyenda del unicornio. - Ciencia Marina y otros asuntos","description":"Se cree que el mito del unicornio puede tener su origen en el colmillo del narval. En la Edad Media se emple\u00f3 su colmillo para curar la epilepsia, fortalecer el coraz\u00f3n y mitigar ciertos venenos. Como la mayor\u00eda de los cuernos o vegetales y animales alargados se empleaba y emplea, como no, para solucionar los problemas de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2017-02-16T09:42:51+01:00","dateModified":"2017-02-16T09:42:51+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"El narval. La leyenda del unicornio. - Ciencia Marina y otros asuntos","og:description":"Se cree que el mito del unicornio puede tener su origen en el colmillo del narval. En la Edad Media se emple\u00f3 su colmillo para curar la epilepsia, fortalecer el coraz\u00f3n y mitigar ciertos venenos. Como la mayor\u00eda de los cuernos o vegetales y animales alargados se empleaba y emplea, como no, para solucionar los problemas de","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2017-02-16T08:42:51+00:00","article:modified_time":"2017-02-16T08:42:51+00:00","twitter:card":"summary","twitter:title":"El narval. La leyenda del unicornio. - Ciencia Marina y otros asuntos","twitter:description":"Se cree que el mito del unicornio puede tener su origen en el colmillo del narval. En la Edad Media se emple\u00f3 su colmillo para curar la epilepsia, fortalecer el coraz\u00f3n y mitigar ciertos venenos. Como la mayor\u00eda de los cuernos o vegetales y animales alargados se empleaba y emplea, como no, para solucionar los problemas de","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"134681","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 11:08:43","updated":"2026-05-26 19:19:25","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl narval. La leyenda del unicornio.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"El narval. La leyenda del unicornio.","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2017\/02\/16\/134681"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/134681"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=134681"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/134681\/revisions"}],"predecessor-version":[{"id":134690,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/134681\/revisions\/134690"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=134681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=134681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=134681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}