{"id":135478,"date":"2020-03-04T10:51:52","date_gmt":"2020-03-04T09:51:52","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=135478"},"modified":"2020-04-16T16:33:30","modified_gmt":"2020-04-16T15:33:30","slug":"el-nuevo-coronavirus","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478","title":{"rendered":"El nuevo coronavirus"},"content":{"rendered":"<p>Hay dos palabras que nadie quiere pronunciar ni o\u00edr durante un brote de una enfermedad: contagio local o transmisi\u00f3n comunitaria.<\/p>\n<p>Italia lidera el n\u00famero de casos de COVID-19 en Europa. Su n\u00famero pas\u00f3 r\u00e1pidamente de 11 a 2500 y 79 fallecidos, con bastantes grupos de infecciones sin conexi\u00f3n con China. Siguiendo el ejemplo de Hubei en China se aislaron pueblos y ciudades y se suspendieron actividades que reun\u00edan muchas personas. Este contagio comunitario ya aparece en mas de 70 pa\u00edses. En Corea del Sur o Ir\u00e1n la situaci\u00f3n es especialmente grave.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-10.33.58.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135485\" title=\"Captura de pantalla 2020-03-04 a las 10.33.58\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-10.33.58.png\" alt=\"\" width=\"500\" height=\"210\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-10.33.58.png 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-10.33.58-300x126.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p>En Corea del Sur el n\u00famero de casos se increment\u00f3 en cinco d\u00edas, pasando de 104 a m\u00e1s de 1000, en la actualidad hay m\u00e1s de 5000 casos de infecci\u00f3n y 28 fallecidos . En Ir\u00e1n el n\u00famero de fallecidos lleg\u00f3 a 12 algo sorprendente dado que pocos d\u00edas antes solo hab\u00eda un caso declarado. Una semana m\u00e1s tarde los casos declarados son 2336 y oficialmente el n\u00famero oficial de fallecidos es de 77. COVID-19 tiene una tasa de mortalidad entre el 2% y el 3% lo que sugiere que hay bastantes m\u00e1s casos no reportados en Ir\u00e1n. El n\u00famero de pa\u00edses con casos sigue creciendo. La <a href=\"https:\/\/www.who.int\/es\/emergencies\/diseases\/novel-coronavirus-2019\" target=\"_blank\">Organizaci\u00f3n Mundial de la Salud<\/a> no quiere declarar esta enfermedad como pand\u00e9mica y avisa de que los pa\u00edses tienen que prepararse para lo que venga.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.58.491.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135487\" title=\"Captura de pantalla 2020-03-04 a las 9.58.49\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.58.491.png\" alt=\"\" width=\"500\" height=\"437\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.58.491.png 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.58.491-300x262.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><a href=\"http:\/\/rocs.hu-berlin.de\/corona\/\" target=\"_blank\">Imagen de Coronavirus COVID-19 Global Risk Assessment<\/a><\/p>\n<p>El control de pasajeros puede ralentizar la expansi\u00f3n, pero no evitarla. Ya sucedi\u00f3 con el c\u00f3lera en el siglo XIX, o las crisis de Ebola en la \u00faltima d\u00e9cada. Los confinamientos protegieron algunas poblaciones en la gripe de 1918 y 1919 pero tambi\u00e9n hicieron que pa\u00edses como Portugal no recibiera ayuda. Mientras tanto los grandes diseminadores de la enfermedad, las tropas de la I Guerra Mundial, se mov\u00edan libremente y sin control a trav\u00e9s de las fronteras.<\/p>\n<p>Los virus son maestros del enga\u00f1o. La evidencia acumulada es que este nuevo coronavirus tarda unos cinco d\u00edas en producir s\u00edntomas y los pacientes son contagiosos antes de que estos s\u00edntomas aparezcan. En muchos pa\u00edses el virus estaba presente antes de que se lo buscase activamente. Se est\u00e1 demostrando que algunos fallecimientos por neumon\u00eda, anteriores a la alarma sanitaria, podr\u00edan haber estar relacionados con la presencia de\u00a0 este nuevo coronavirus.<\/p>\n<p>\u00bfSi sube la temperatura se ralentizar\u00e1 la infecci\u00f3n? No lo sabemos. Los coronavirus humanos conocidos anteriormente <a href=\"https:\/\/www.journalofhospitalinfection.com\/article\/S0195-6701(20)30046-3\/fulltext\" target=\"_blank\">pod\u00edan permanecer infectivos en superficies inanimadas a temperatura ambiente hasta 9 d\u00edas<\/a>. A 30 grados o m\u00e1s el tiempo en que permanecen infectivos es menor. Los coronavirus de animales pueden permanecer infecciosos m\u00e1s tiempo, algunos hasta 28 d\u00edas.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.58.25.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135488\" title=\"Captura de pantalla 2020-03-04 a las 9.58.25\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.58.25.png\" alt=\"\" width=\"500\" height=\"602\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.58.25.png 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.58.25-249x300.png 249w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/rocs.hu-berlin.de\/corona\/\" target=\"_blank\">Imagen de Coronavirus COVID-19 Global Risk Assessment<\/a><\/p>\n<p>En el caso de COVID-19, <a href=\"https:\/\/www.nejm.org\/doi\/full\/10.1056\/NEJMc2001737\" target=\"_blank\">el virus infecta no solo los pulmones sino tambi\u00e9n la nariz y la garganta<\/a>. Un estudio publicado en <a href=\"https:\/\/science.sciencemag.org\/content\/early\/2020\/02\/19\/science.abb2507\" target=\"_blank\">Science<\/a> describe que este nuevo coronavirus tienen una capacidad 10 a 20 veces m\u00e1s alta que los otros coronavirus conocidos para entrar en las c\u00e9lulas humanas.<\/p>\n<p>Los modelos matem\u00e1ticos para estudiar c\u00f3mo evoluciona una enfermedad se basan fundamentalmente en cuantas personas son susceptibles, cu\u00e1ntas transmiten la enfermedad y cu\u00e1ntas se recuperan o mueren.<\/p>\n<p>Aunque parezca sencillo cualquier error en esas estimaciones puede hacer que el modelo de informaci\u00f3n equivocada. En 2014, <a href=\"https:\/\/www.statnews.com\/2020\/02\/14\/disease-modelers-see-future-of-covid-19\/\" target=\"_blank\">los modelos del CDC predijeron<\/a> que el brote de <a href=\"https:\/\/www.wmpllc.org\/ojs\/index.php\/jem\/article\/view\/2688\" target=\"_blank\">\u00c9bola en \u00c1frica pod\u00eda causar 550,000 a 1.4 millones de casos en Liberia y Sierra Leona<\/a> hacia el final de Enero si nada cambiaba. Sin embargos los esfuerzos en el aislamiento de pacientes, seguimiento de sus contactos y prohibir los entierros con participaci\u00f3n de muchas personas consiguieron que los casos fueran 28,600 (y 11,325 muertes). Situaciones similares se dieron con otras potenciales pandemias como SARS y MERS.<\/p>\n<p>Los modelos matem\u00e1ticos aplicados a c\u00f3mo evolucion\u00f3 la enfermedad despu\u00e9s de la cuarentena establecida en <a href=\"https:\/\/www.nature.com\/articles\/s41421-020-0148-0\" target=\"_blank\">Wuhan y su eficacia arrojan resultados confusos<\/a>. Algunos investigadores sugieren que el brote comenz\u00f3 a principios de Noviembre de 2019. Aparentemente la cuarentena lleg\u00f3 tarde cuando el virus se hab\u00eda extendido a otras ciudades de China el 23 de enero. Probablemente China estaba exportando casos de coronavirus a trav\u00e9s de otros centros de viaje como\u00a0 Shanghai, Beijing, Shenzhen, Guangzhou, y Kunming entre los m\u00e1s importantes.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.59.17.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135489\" title=\"Captura de pantalla 2020-03-04 a las 9.59.17\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.59.17.png\" alt=\"\" width=\"500\" height=\"443\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.59.17.png 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-9.59.17-300x265.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/rocs.hu-berlin.de\/corona\/\" target=\"_blank\">Imagen de Coronavirus COVID-19 Global Risk Assessment<\/a><\/p>\n<p>La enfermedad sigui\u00f3 extendi\u00e9ndose a Jap\u00f3n y Corea del Sur porque aunque se prohibieron los viajes de Wuhan y Hubei los viajeros de otras ciudades de China pod\u00edan seguir viajando.<\/p>\n<p>Los <a href=\"https:\/\/www.scientificamerican.com\/article\/heres-how-computer-models-simulate-the-future-spread-of-new-coronavirus\/\" target=\"_blank\">modelos<\/a> sugieren que la cuarentena de Wuhan retras\u00f3 el avance global de la epidemia como mucho 3 o 5 d\u00edas. No hay evidencia s\u00f3lida de que la prohibici\u00f3n de viajes sea eficaz. Sirven para retrasar pero no para contener las epidemias, unos d\u00edas o unas semanas. Como pudo comprobarse en el crucero Diamond Princess el aislamiento puede favorecer que la enfermedad se extienda en un grupo confinado. Lo que comenz\u00f3 con 10 infecciones el 4 de Febrero pas\u00f3 de las 600 tres semanas despu\u00e9s.<\/p>\n<p>Los m\u00e9todos para detectar la enfermedad en las personas que viajan tampoco son seguros al 100 por 100. La toma de temperatura solo detecta un 70% de las temperaturas elevadas lo que significa que una de cada cuatro personas con temperatura elevada no es detectada.<\/p>\n<p>Los <a href=\"https:\/\/www.medrxiv.org\/content\/10.1101\/2020.01.28.20019224v2\" target=\"_blank\">modelos matem\u00e1ticos<\/a>, que tienen en cuenta factores como la toma de la temperatura o que las personas no suelen ser muy claras sobre con su historia de viajes y contactos, estiman que como mucho en la mejor de las circunstancias estos screenings en los aeropuertos detectan un 50% de casos y en el peor de los escenarios un 20%. Aproximadamente un 40% de los pasajeros portadores del virus que han pasado por los controles entran en el pa\u00eds de destino.<\/p>\n<p>Un ejemplo podr\u00eda ser Singapur. Tiene uno de los mejores sistemas de salud del planeta gracias a la financiaci\u00f3n p\u00fablica, los costes de tratamiento son bajos y existe un buen ratio de m\u00e9dicos por habitante que ayuda en un brote de esta naturaleza.<\/p>\n<p>Usando Singapur como un est\u00e1ndar para la detecci\u00f3n del COVID-19 un modelo matem\u00e1tico predice que Estados Unidos, Jap\u00f3n y pa\u00edses de Europa tal vez solo est\u00e9n detectando un 38 por ciento de los casos relacionados con los viajes. \u00a0En <a href=\"https:\/\/www.thelancet.com\/journals\/lancet\/article\/PIIS0140-6736(20)30411-6\/fulltext#seccestitle140\" target=\"_blank\">los pa\u00edses con sistemas de salud poco desarrollados<\/a> el modelo predice que el 89% de los casos pueden no ser detectados.<\/p>\n<p>El \u00e9xito de Singapur se basa en el gran esfuerzo de las autoridades en el control de fronteras pero a\u00fan as\u00ed a d\u00eda de hoy los investigadores de Singapur declaran que 8 casos de los 84 declarados no est\u00e1n conectados con exposiciones claras al pat\u00f3geno.<\/p>\n<p>\u00bfQu\u00e9 pasar\u00e1? Nadie lo sabe. Confiemos en el sistema de salud, en los profesionales de la medicina y sigamos las recomendaciones que se han repetido una y otra vez. \u00bfCu\u00e1ntas veces se lav\u00f3 hoy las manos despu\u00e9s de tocar lugares u objetos de acceso p\u00fablico?<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/COVID19_como_protegerse.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135482\" title=\"COVID19_como_protegerse\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/COVID19_como_protegerse.jpg\" alt=\"\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/COVID19_como_protegerse.jpg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/COVID19_como_protegerse-150x150.jpg 150w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/COVID19_como_protegerse-300x300.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<h1>Enlaces de Inter\u00e9s<\/h1>\n<p><a href=\"https:\/\/www.mscbs.gob.es\/profesionales\/saludPublica\/ccayes\/alertasActual\/nCov-China\/home.htm\" target=\"_blank\">Enfermedad por nuevo coronavirus, COVID-19<\/a>\u00a0Ministerio Sanidad Gobierno de Espa\u00f1a.<\/p>\n<p><a href=\"https:\/\/www.who.int\/es\/emergencies\/diseases\/novel-coronavirus-2019\" target=\"_blank\">Organizaci\u00f3n Mundial de la Salud. Coronavirus.<\/a><\/p>\n<p><a href=\"https:\/\/www.ecdc.europa.eu\/en\/novel-coronavirus-china\" target=\"_blank\">European Centre for Disease Prevention and Control<\/a><\/p>\n<p><a href=\"https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/index.html\" target=\"_blank\">Coronavirus Disease 2019. CDC. USA.<\/a><\/p>\n<p><a href=\"https:\/\/gisanddata.maps.arcgis.com\/apps\/opsdashboard\/index.html#\/bda7594740fd40299423467b48e9ecf6\/\" target=\"_blank\">Coronavirus COVID-19 Global Cases by Johns Hopkins CSSE<\/a><\/p>\n<p><a href=\"https:\/\/cmmid-lshtm.shinyapps.io\/traveller_screening\/\" target=\"_blank\">Effectiveness of airport screening at detecting travellers infected with novel coronavirus COVID-19 (formerly 2019-nCoV)<\/a><\/p>\n<p><a href=\"https:\/\/www.thelancet.com\/journals\/lancet\/article\/PIIS0140-6736(20)30411-6\/fulltext#seccestitle140\" target=\"_blank\">Preparedness and vulnerability of African countries against importations of COVID-19: a modelling study<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay dos palabras que nadie quiere pronunciar ni o\u00edr durante un brote de una enfermedad: contagio local o transmisi\u00f3n comunitaria. Italia lidera el n\u00famero de casos de COVID-19 en Europa. Su n\u00famero pas\u00f3 r\u00e1pidamente de 11 a 2500 y 79 fallecidos, con bastantes grupos de infecciones sin conexi\u00f3n con China. Siguiendo el ejemplo de Hubei en China se aislaron pueblos y ciudades y se suspendieron actividades que reun\u00edan muchas personas. Este contagio comunitario ya aparece en mas de 70 pa\u00edses. En Corea del Sur o Ir\u00e1n la situaci\u00f3n es especialmente grave.<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hay dos palabras que nadie quiere pronunciar ni o\u00edr durante un brote de una enfermedad: contagio local o transmisi\u00f3n comunitaria. Italia lidera el n\u00famero de casos de COVID-19 en Europa. Su n\u00famero pas\u00f3 r\u00e1pidamente de 11 a 2500 y 79 fallecidos, con bastantes grupos de infecciones sin conexi\u00f3n con China. Siguiendo el ejemplo de Hubei\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El nuevo coronavirus - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Hay dos palabras que nadie quiere pronunciar ni o\u00edr durante un brote de una enfermedad: contagio local o transmisi\u00f3n comunitaria. Italia lidera el n\u00famero de casos de COVID-19 en Europa. Su n\u00famero pas\u00f3 r\u00e1pidamente de 11 a 2500 y 79 fallecidos, con bastantes grupos de infecciones sin conexi\u00f3n con China. Siguiendo el ejemplo de Hubei\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-03-04T09:51:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-04-16T15:33:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El nuevo coronavirus - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hay dos palabras que nadie quiere pronunciar ni o\u00edr durante un brote de una enfermedad: contagio local o transmisi\u00f3n comunitaria. Italia lidera el n\u00famero de casos de COVID-19 en Europa. Su n\u00famero pas\u00f3 r\u00e1pidamente de 11 a 2500 y 79 fallecidos, con bastantes grupos de infecciones sin conexi\u00f3n con China. Siguiendo el ejemplo de Hubei\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/03\\\/04\\\/135478#blogposting\",\"name\":\"El nuevo coronavirus - Ciencia Marina y otros asuntos\",\"headline\":\"El nuevo coronavirus\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/03\\\/Captura-de-pantalla-2020-03-04-a-las-10.33.58.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/03\\\/04\\\/135478\\\/#articleImage\",\"width\":500,\"height\":210},\"datePublished\":\"2020-03-04T10:51:52+01:00\",\"dateModified\":\"2020-04-16T16:33:30+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/03\\\/04\\\/135478#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/03\\\/04\\\/135478#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/03\\\/04\\\/135478#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/03\\\/04\\\/135478#listItem\",\"name\":\"El nuevo coronavirus\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/03\\\/04\\\/135478#listItem\",\"position\":3,\"name\":\"El nuevo coronavirus\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/03\\\/04\\\/135478#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/03\\\/04\\\/135478\",\"name\":\"El nuevo coronavirus - Ciencia Marina y otros asuntos\",\"description\":\"Hay dos palabras que nadie quiere pronunciar ni o\\u00edr durante un brote de una enfermedad: contagio local o transmisi\\u00f3n comunitaria. Italia lidera el n\\u00famero de casos de COVID-19 en Europa. Su n\\u00famero pas\\u00f3 r\\u00e1pidamente de 11 a 2500 y 79 fallecidos, con bastantes grupos de infecciones sin conexi\\u00f3n con China. Siguiendo el ejemplo de Hubei\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/03\\\/04\\\/135478#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-03-04T10:51:52+01:00\",\"dateModified\":\"2020-04-16T16:33:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El nuevo coronavirus - Ciencia Marina y otros asuntos","description":"Hay dos palabras que nadie quiere pronunciar ni o\u00edr durante un brote de una enfermedad: contagio local o transmisi\u00f3n comunitaria. Italia lidera el n\u00famero de casos de COVID-19 en Europa. Su n\u00famero pas\u00f3 r\u00e1pidamente de 11 a 2500 y 79 fallecidos, con bastantes grupos de infecciones sin conexi\u00f3n con China. Siguiendo el ejemplo de Hubei","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478#blogposting","name":"El nuevo coronavirus - Ciencia Marina y otros asuntos","headline":"El nuevo coronavirus","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/03\/Captura-de-pantalla-2020-03-04-a-las-10.33.58.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478\/#articleImage","width":500,"height":210},"datePublished":"2020-03-04T10:51:52+01:00","dateModified":"2020-04-16T16:33:30+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478#listItem","name":"El nuevo coronavirus"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478#listItem","position":3,"name":"El nuevo coronavirus","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478","name":"El nuevo coronavirus - Ciencia Marina y otros asuntos","description":"Hay dos palabras que nadie quiere pronunciar ni o\u00edr durante un brote de una enfermedad: contagio local o transmisi\u00f3n comunitaria. Italia lidera el n\u00famero de casos de COVID-19 en Europa. Su n\u00famero pas\u00f3 r\u00e1pidamente de 11 a 2500 y 79 fallecidos, con bastantes grupos de infecciones sin conexi\u00f3n con China. Siguiendo el ejemplo de Hubei","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-03-04T10:51:52+01:00","dateModified":"2020-04-16T16:33:30+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"El nuevo coronavirus - Ciencia Marina y otros asuntos","og:description":"Hay dos palabras que nadie quiere pronunciar ni o\u00edr durante un brote de una enfermedad: contagio local o transmisi\u00f3n comunitaria. Italia lidera el n\u00famero de casos de COVID-19 en Europa. Su n\u00famero pas\u00f3 r\u00e1pidamente de 11 a 2500 y 79 fallecidos, con bastantes grupos de infecciones sin conexi\u00f3n con China. Siguiendo el ejemplo de Hubei","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-03-04T09:51:52+00:00","article:modified_time":"2020-04-16T15:33:30+00:00","twitter:card":"summary","twitter:title":"El nuevo coronavirus - Ciencia Marina y otros asuntos","twitter:description":"Hay dos palabras que nadie quiere pronunciar ni o\u00edr durante un brote de una enfermedad: contagio local o transmisi\u00f3n comunitaria. Italia lidera el n\u00famero de casos de COVID-19 en Europa. Su n\u00famero pas\u00f3 r\u00e1pidamente de 11 a 2500 y 79 fallecidos, con bastantes grupos de infecciones sin conexi\u00f3n con China. Siguiendo el ejemplo de Hubei","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"135478","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-04 15:27:39","updated":"2026-05-26 19:27:42","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl nuevo coronavirus\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"El nuevo coronavirus","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/04\/135478"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/135478"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=135478"}],"version-history":[{"count":15,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/135478\/revisions"}],"predecessor-version":[{"id":135793,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/135478\/revisions\/135793"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=135478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=135478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=135478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}