{"id":135738,"date":"2020-04-10T22:25:28","date_gmt":"2020-04-10T21:25:28","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=135738"},"modified":"2020-04-16T16:35:50","modified_gmt":"2020-04-16T15:35:50","slug":"coronavirus-covid19-director-general-organizacion-mundial-de-la-salud-10-de-abril-2020","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738","title":{"rendered":"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020."},"content":{"rendered":"<h2>WHO Director-General&#8217;s opening remarks at the media briefing on COVID-19 &#8211; 10 April 2020<\/h2>\n<p>\u00abA nivel mundial, <strong>casi 1,5 millones de casos confirmados de COVID-19 han sido reportados a la OMS y m\u00e1s de 92,000 muertes<\/strong>. La semana pasada, hemos visto una desaceleraci\u00f3n bienvenida en algunos de los pa\u00edses m\u00e1s afectados en Europa, como Espa\u00f1a, Italia, Alemania y Francia. A nivel personal, me complaci\u00f3 ver que mi amigo Boris Johnson ya no est\u00e1 en cuidados intensivos. Le deseo lo mejor, como le deseo lo mejor a todos los que se enfrentan a lo que \u00e9l enfrent\u00f3. Al mismo tiempo, hemos visto una aceleraci\u00f3n alarmante en otros pa\u00edses. Quiero tomarme un momento para resaltar \u00c1frica, donde estamos viendo la propagaci\u00f3n del virus a las zonas rurales. <a href=\"https:\/\/www.who.int\/dg\/speeches\/detail\/who-director-general-s-opening-remarks-at-the-media-briefing-on-covid-19---10-april-2020\" target=\"_blank\">Ahora estamos viendo grupos de casos y propagaci\u00f3n comunitaria en m\u00e1s de 16 pa\u00edses.<\/a>\u00bb<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Hopkins-coronavirus-10-abril.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135740\" title=\"Hopkins coronavirus 10 abril\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Hopkins-coronavirus-10-abril.jpg\" alt=\"\" width=\"500\" height=\"233\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Hopkins-coronavirus-10-abril.jpg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Hopkins-coronavirus-10-abril-300x139.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p>Anticipamos dificultades severas para los sistemas de salud ya sobrecargados, particularmente en las \u00e1reas rurales, que normalmente carecen de los recursos de aquellos en las ciudades.<\/p>\n<p>S\u00e9 que algunos pa\u00edses ya est\u00e1n planeando la transici\u00f3n para salir de las restricciones de quedarse en casa. La OMS quiere que se levanten las restricciones tanto como cualquiera.<\/p>\n<p>Al mismo tiempo, levantar las restricciones demasiado r\u00e1pido podr\u00eda conducir a un resurgimiento mortal. La bajada puede ser tan peligrosa como la subida si no se maneja adecuadamente. La OMS est\u00e1 trabajando con los pa\u00edses afectados en estrategias para aliviar las restricciones de forma gradual y segura.<\/p>\n<p>Los factores importantes a considerar son:<\/p>\n<p><strong>Primero<\/strong>, esa transmisi\u00f3n est\u00e1 controlada;<\/p>\n<p><strong>Segundo<\/strong>, que haya suficientes servicios m\u00e9dicos y de salud p\u00fablica disponibles;<\/p>\n<p><strong>Tercero<\/strong>, se minimizan los riesgos de brotes en entornos especiales como los centros de atenci\u00f3n a largo plazo;<\/p>\n<p><strong>Cuarto<\/strong>, que existen medidas preventivas en los lugares de trabajo, las escuelas y otros lugares donde es esencial que la gente vaya;<\/p>\n<p><strong>Quinto<\/strong>, que los riesgos de importaci\u00f3n se pueden gestionar;<\/p>\n<p>Y <strong>sexto<\/strong>, y no puedo enfatizar demasiado este punto, que <strong>las comunidades son plenamente conscientes y participan en la transici\u00f3n<\/strong>.<\/p>\n<p>Cada persona tiene un papel que desempe\u00f1ar para poner fin a esta pandemia.<\/p>\n<p>Estamos particularmente preocupados por la gran cantidad de infecciones reportadas entre los trabajadores de la salud.<\/p>\n<p>En algunos pa\u00edses hay informes de m\u00e1s del 10 por ciento de los trabajadores de la salud infectados. Esta es una tendencia alarmante.<\/p>\n<p>Cuando los trabajadores de la salud est\u00e1n en riesgo, todos estamos en riesgo.<\/p>\n<p>La evidencia de China, Italia, Singapur, Espa\u00f1a y los Estados Unidos nos est\u00e1 ayudando a comprender por qu\u00e9 sucede esto y qu\u00e9 podemos hacer al respecto.<\/p>\n<p>Muestra que algunos trabajadores de la salud est\u00e1n realmente infectados fuera de los establecimientos de salud, en sus hogares o comunidades.<\/p>\n<p>Veremos qu\u00e9 pasa. <a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/06\/135501\" target=\"_blank\">El pasado 5 de marzo no se le hizo mucho caso.<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Espan\u0303a10abril-covid19.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135741\" title=\"Espan\u0303a10abril covid19\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Espan\u0303a10abril-covid19.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Espan\u0303a10abril-covid19.jpg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Espan\u0303a10abril-covid19-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<h2><a href=\"https:\/\/www.who.int\/dg\/speeches\/detail\/who-director-general-s-opening-remarks-at-the-media-briefing-on-covid-19---10-april-2020\" target=\"_blank\">WHO Director-General&#8217;s opening remarks at the media briefing on COVID-19 &#8211; 10 April 2020. Completo.<\/a><\/h2>\n<h2 id=\"post-135501\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/03\/06\/135501\" target=\"_blank\">Coronavirus: WHO Director-General\u2019s opening remarks at the media briefing on COVID-19 \u2013 5 March 2020<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>WHO Director-General&#8217;s opening remarks at the media briefing on COVID-19 &#8211; 10 April 2020 \u00abA nivel mundial, casi 1,5 millones de casos confirmados de COVID-19 han sido reportados a la OMS y m\u00e1s de 92,000 muertes. La semana pasada, hemos visto una desaceleraci\u00f3n bienvenida en algunos de los pa\u00edses m\u00e1s afectados en Europa, como Espa\u00f1a, Italia, Alemania y Francia. A nivel personal, me complaci\u00f3 ver que mi amigo Boris Johnson ya no est\u00e1 en cuidados intensivos. Le deseo lo mejor, como le deseo lo mejor a todos los que se enfrentan a lo que \u00e9l enfrent\u00f3. Al mismo tiempo, hemos\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"WHO Director-General&#039;s opening remarks at the media briefing on COVID-19 - 10 April 2020 &quot;A nivel mundial, casi 1,5 millones de casos confirmados de COVID-19 han sido reportados a la OMS y m\u00e1s de 92,000 muertes. La semana pasada, hemos visto una desaceleraci\u00f3n bienvenida en algunos de los pa\u00edses m\u00e1s afectados en Europa, como Espa\u00f1a,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020. - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"WHO Director-General&#039;s opening remarks at the media briefing on COVID-19 - 10 April 2020 &quot;A nivel mundial, casi 1,5 millones de casos confirmados de COVID-19 han sido reportados a la OMS y m\u00e1s de 92,000 muertes. La semana pasada, hemos visto una desaceleraci\u00f3n bienvenida en algunos de los pa\u00edses m\u00e1s afectados en Europa, como Espa\u00f1a,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-04-10T21:25:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-04-16T15:35:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020. - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"WHO Director-General&#039;s opening remarks at the media briefing on COVID-19 - 10 April 2020 &quot;A nivel mundial, casi 1,5 millones de casos confirmados de COVID-19 han sido reportados a la OMS y m\u00e1s de 92,000 muertes. La semana pasada, hemos visto una desaceleraci\u00f3n bienvenida en algunos de los pa\u00edses m\u00e1s afectados en Europa, como Espa\u00f1a,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/10\\\/135738#blogposting\",\"name\":\"Coronavirus: CoVid19. Director General Organizaci\\u00f3n Mundial de la Salud. 10 de Abril 2020. - Ciencia Marina y otros asuntos\",\"headline\":\"Coronavirus: CoVid19. Director General Organizaci\\u00f3n Mundial de la Salud. 10 de Abril 2020.\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/04\\\/Hopkins-coronavirus-10-abril.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/10\\\/135738\\\/#articleImage\",\"width\":500,\"height\":233},\"datePublished\":\"2020-04-10T22:25:28+01:00\",\"dateModified\":\"2020-04-16T16:35:50+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/10\\\/135738#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/10\\\/135738#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/10\\\/135738#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/10\\\/135738#listItem\",\"name\":\"Coronavirus: CoVid19. Director General Organizaci\\u00f3n Mundial de la Salud. 10 de Abril 2020.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/10\\\/135738#listItem\",\"position\":3,\"name\":\"Coronavirus: CoVid19. Director General Organizaci\\u00f3n Mundial de la Salud. 10 de Abril 2020.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/10\\\/135738#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/10\\\/135738\",\"name\":\"Coronavirus: CoVid19. Director General Organizaci\\u00f3n Mundial de la Salud. 10 de Abril 2020. - Ciencia Marina y otros asuntos\",\"description\":\"WHO Director-General's opening remarks at the media briefing on COVID-19 - 10 April 2020 \\\"A nivel mundial, casi 1,5 millones de casos confirmados de COVID-19 han sido reportados a la OMS y m\\u00e1s de 92,000 muertes. La semana pasada, hemos visto una desaceleraci\\u00f3n bienvenida en algunos de los pa\\u00edses m\\u00e1s afectados en Europa, como Espa\\u00f1a,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/10\\\/135738#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-04-10T22:25:28+01:00\",\"dateModified\":\"2020-04-16T16:35:50+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020. - Ciencia Marina y otros asuntos","description":"WHO Director-General's opening remarks at the media briefing on COVID-19 - 10 April 2020 \"A nivel mundial, casi 1,5 millones de casos confirmados de COVID-19 han sido reportados a la OMS y m\u00e1s de 92,000 muertes. La semana pasada, hemos visto una desaceleraci\u00f3n bienvenida en algunos de los pa\u00edses m\u00e1s afectados en Europa, como Espa\u00f1a,","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738#blogposting","name":"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020. - Ciencia Marina y otros asuntos","headline":"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020.","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Hopkins-coronavirus-10-abril.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738\/#articleImage","width":500,"height":233},"datePublished":"2020-04-10T22:25:28+01:00","dateModified":"2020-04-16T16:35:50+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738#listItem","name":"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738#listItem","position":3,"name":"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738","name":"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020. - Ciencia Marina y otros asuntos","description":"WHO Director-General's opening remarks at the media briefing on COVID-19 - 10 April 2020 \"A nivel mundial, casi 1,5 millones de casos confirmados de COVID-19 han sido reportados a la OMS y m\u00e1s de 92,000 muertes. La semana pasada, hemos visto una desaceleraci\u00f3n bienvenida en algunos de los pa\u00edses m\u00e1s afectados en Europa, como Espa\u00f1a,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-04-10T22:25:28+01:00","dateModified":"2020-04-16T16:35:50+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020. - Ciencia Marina y otros asuntos","og:description":"WHO Director-General's opening remarks at the media briefing on COVID-19 - 10 April 2020 &quot;A nivel mundial, casi 1,5 millones de casos confirmados de COVID-19 han sido reportados a la OMS y m\u00e1s de 92,000 muertes. La semana pasada, hemos visto una desaceleraci\u00f3n bienvenida en algunos de los pa\u00edses m\u00e1s afectados en Europa, como Espa\u00f1a,","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-04-10T21:25:28+00:00","article:modified_time":"2020-04-16T15:35:50+00:00","twitter:card":"summary","twitter:title":"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020. - Ciencia Marina y otros asuntos","twitter:description":"WHO Director-General's opening remarks at the media briefing on COVID-19 - 10 April 2020 &quot;A nivel mundial, casi 1,5 millones de casos confirmados de COVID-19 han sido reportados a la OMS y m\u00e1s de 92,000 muertes. La semana pasada, hemos visto una desaceleraci\u00f3n bienvenida en algunos de los pa\u00edses m\u00e1s afectados en Europa, como Espa\u00f1a,","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"135738","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-11 04:34:55","updated":"2026-05-26 19:29:08","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCoronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Coronavirus: CoVid19. Director General Organizaci\u00f3n Mundial de la Salud. 10 de Abril 2020.","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/10\/135738"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/135738"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=135738"}],"version-history":[{"count":6,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/135738\/revisions"}],"predecessor-version":[{"id":135811,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/135738\/revisions\/135811"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=135738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=135738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=135738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}