{"id":135745,"date":"2020-04-17T10:00:06","date_gmt":"2020-04-17T09:00:06","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=135745"},"modified":"2020-04-17T10:00:06","modified_gmt":"2020-04-17T09:00:06","slug":"coronavirus-covid19-durante-cuanto-tiempo-permanece-infecciosoinfectivo-este-coronavirus","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745","title":{"rendered":"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus?"},"content":{"rendered":"<p>Una de las preguntas que m\u00e1s nos hacemos con respecto a SARS Cov 2 es, \u00bfcu\u00e1nto tiempo puede infectar este coronavirus? \u00bfpodemos infectarnos tocando superficies p\u00fablicas, en el supermercado, recogiendo paquetes? Las medidas de confinamiento buscan evitar el contacto con personas potencialmente infectadas por Covid-19. Sin embargo siguen apareciendo miles de nuevos infectados cada d\u00eda. Una explicaci\u00f3n es que se realizan m\u00e1s tests. Otra que la infectividad del virus es muy elevada y que permanece activo mucho tiempo. El\u00a0<a href=\"https:\/\/www.cdc.gov\/mmwr\/volumes\/69\/wr\/mm6912e3.htm\" target=\"_blank\">Centro para el Control de Enfermedades de los EE. UU. (CDC) public\u00f3 un informe sobre los brotes de COVID-19 en cruceros<\/a>, que indica que el ARN del SARS-CoV-2 se identific\u00f3 en las superficies de las cabinas hasta 17 d\u00edas despu\u00e9s de su desocupaci\u00f3n. \u00bfSignifica que todav\u00eda uno se pod\u00eda infectar tocando estas superficies?\u00a0 Este informe creo\u00a0<a href=\"https:\/\/www.sciencemediacentre.org\/expert-reaction-to-cdc-report-on-covid-19-outbreaks-on-cruise-ships-which-includes-that-sars-cov-2-rna-was-identified-on-surfaces-in-cabins-up-to-17-days-after-they-were-vacated\/\" target=\"_blank\">cierta controversia.<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/coronavirus-covid19-espana-suma-10-fallecidos-casos-todas-las-ccaa-domingo-8-marzo-4248.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135827\" title=\"coronavirus-covid19-espana-suma-10-fallecidos-casos-todas-las-ccaa-domingo-8-marzo-4248\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/coronavirus-covid19-espana-suma-10-fallecidos-casos-todas-las-ccaa-domingo-8-marzo-4248.jpg\" alt=\"\" width=\"500\" height=\"297\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/coronavirus-covid19-espana-suma-10-fallecidos-casos-todas-las-ccaa-domingo-8-marzo-4248.jpg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/coronavirus-covid19-espana-suma-10-fallecidos-casos-todas-las-ccaa-domingo-8-marzo-4248-300x178.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Foto Redacci\u00f3n M\u00e9dica<br \/>\n<!--more--><strong><\/strong><\/p>\n<p>El informe del CDC pone de manifiesto que hab\u00eda ARN viral en cabinas que a\u00fan no se hab\u00edan limpiado. Eso significa que el virus era detectable, no que fuera viable o que el contacto con esas superficies hubiera podido infectar a alguien. (el ARN, o \u00e1cido ribonucleico, contiene la informaci\u00f3n gen\u00e9tica del virus). Es decir, hay partes del virus que a\u00fan se pueden detectar en las superficies. El virus necesita muchos otros componentes para ser capaz de infectarnos. Los fragmentos de ARN, no son un virus, necesita su genoma completo y las prote\u00ednas que le permiten infectar las c\u00e9lulas. El hecho de que haya una peque\u00f1a cantidad de ARN no significa que se vaya a producir una infecci\u00f3n.<\/p>\n<p><strong>\u00bfCu\u00e1nto tiempo puede sobrevivir el virus en las superficies?<\/strong><\/p>\n<p>El <a href=\"https:\/\/www.nejm.org\/doi\/10.1056\/NEJMc2004973\" target=\"_blank\">New England Journal of Medicine<\/a> public\u00f3 un estudio para determinar cu\u00e1nto tiempo puede permanecer estable el virus en diferentes superficies, compar\u00e1ndolo con su antecesor SARS Cov, en un <strong>entorno controlado de laboratorio<\/strong>. M\u00e1s <a href=\"https:\/\/www.thelancet.com\/journals\/lanmic\/article\/PIIS2666-5247(20)30003-3\/fulltext\" target=\"_blank\">recientemente The Lance<\/a>t, public\u00f3 otro en el que para determinar su viabilidad e infectividad, aplicaron una soluci\u00f3n de virus a distintas superficies. \u00a0Descubrieron que todav\u00eda era detectable en cobre durante hasta cuatro horas, en cart\u00f3n durante hasta 24 horas y en pl\u00e1stico y acero durante hasta 72 horas. No se pudo recuperar ning\u00fan virus infeccioso ni en papel impreso ni en pa\u00f1uelos de papel despu\u00e9s de una incubaci\u00f3n de 3 horas, tampoco se detect\u00f3 virus infectivo de la madera y tela tratadas el d\u00eda 2. Por el contrario, el SARS-CoV-2 fue m\u00e1s estable en superficies lisas. No se pudo detectar ning\u00fan virus infeccioso el d\u00eda 4 en superficies de vidrio y billetes, o el d\u00eda 7 (acero inoxidable y pl\u00e1stico). <a href=\"https:\/\/www.thelancet.com\/journals\/lanmic\/article\/PIIS2666-5247(20)30003-3\/fulltext\" target=\"_blank\">Sorprendentemente, se detect\u00f3 virus infeccioso en la capa externa de una m\u00e1scara quir\u00fargica el d\u00eda 7<\/a>.<\/p>\n<p>No olvidemos que <strong>estos estudios se realizaron en laboratori<\/strong>o.<\/p>\n<p>En <a href=\"https:\/\/jamanetwork.com\/journals\/jama\/fullarticle\/2762692\" target=\"_blank\">otro estudio publicado en JAMA<\/a>, realizado en habitaciones de hospital (no en la calle, un supermercado o el transporte p\u00fablico), ocupadas por pacientes de CoVId19, hubo una extensa contaminaci\u00f3n ambiental por 1 paciente con SARS-CoV-2 con afectaci\u00f3n leve del tracto respiratorio superior. Las muestras de inodoros y lavabos fueron positivas, lo que sugiere que la\u00a0<strong>eliminaci\u00f3n viral en las heces podr\u00eda ser una ruta potencial de transmisi\u00f3n. Las muestras posteriores a la limpieza fueron negativas, lo que sugiere que las medidas de descontaminaci\u00f3n actuales son suficientes.<\/strong><\/p>\n<p>Las muestras de aire fueron negativas a pesar del grado de contaminaci\u00f3n ambiental.\u00a0<strong>Las muestras tomadas de las salidas de ventilaci\u00f3n de aire dieron positivo, lo que sugiere que las peque\u00f1as gotas cargadas de virus pueden ser desplazadas por los flujos de aire y depositadas en equipos como los respiraderos de los sistemas de aire acondicionado<\/strong>. Hay que tener en cuenta que <strong>no se realiz\u00f3 cultivo viral para demostrar la viabilidad del virus, es decir se detect\u00f3 que hab\u00eda material gen\u00e9tico del virus pero no que pudiese infectar. Los autores concluyen que \u201cLa contaminaci\u00f3n ambiental significativa por pacientes con SARS-CoV-2 a trav\u00e9s de gotitas respiratorias y heces sugiere que el\u00a0<\/strong><strong><a href=\"https:\/\/jamanetwork.com\/journals\/jama\/fullarticle\/2762692\" target=\"_blank\">medio ambiente es un medio potencial de transmisi\u00f3n y respalda la necesidad de una estricto seguimiento de la higiene ambiental y de las manos<\/a><\/strong><strong>.\u201d<\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/COVID19.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135829\" title=\"COVID19\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/COVID19.jpeg\" alt=\"\" width=\"500\" height=\"265\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/COVID19.jpeg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/COVID19-300x159.jpeg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><strong>\u00bfPodr\u00eda infectarme si entro en contacto con una part\u00edcula de coronavirus?<\/strong><\/p>\n<p>Para que se desarrolle la enfermedad es necesario exponerse a una cierta cantidad de part\u00edculas virales. Si solo hay una part\u00edcula viral en su dedo, es poco probable que se infecte. Algunos virus son muy infectivos. En el caso de la gripe con solo 10 virus se puede producir la infecci\u00f3n. En el caso de otros virus se necesitan millones de part\u00edculas virales para que se produzca una infecci\u00f3n. Si nos exponemos a menos part\u00edculas virales, menos probable ser\u00e1 que nos infectemos. Por eso es importante la cantidad de virus infectivo presentes en una superficie.<\/p>\n<p>Los cient\u00edficos no saben con certeza cu\u00e1ntas part\u00edculas virales de SARS-CoV-2 son necesarias para desencadenar la infecci\u00f3n. COVID-19 es claramente muy contagioso, pero esto puede deberse a que se necesitan pocas part\u00edculas virales para que se produzca la infecci\u00f3n (la dosis infecciosa es baja) o porque las personas infectadas liberan muchos virus en su entorno.<\/p>\n<p><strong>\u00bfCu\u00e1ntas personas est\u00e1n siendo infectadas a trav\u00e9s del contacto con superficies comparado con las que lo son por part\u00edculas virales en el aire o contacto directo con una persona infectada?<\/strong><\/p>\n<p>No se sabe con certeza, pero se cree que es mucho m\u00e1s probable que las personas se infecten por contacto con una persona infectada que al tocar una superficie contaminada. Dicho esto, es importante ser consciente de lo que estamos tocando, especialmente las superficies que tocan muchas personas, y tener cuidado al limpiar nuestras manos despu\u00e9s de tocar distintos objetos y superficies. Por ejemplo, en el transporte p\u00fablico o supermercados y lugares donde suele haber mucha gente.<\/p>\n<p>El virus es bastante estable en materiales como el pl\u00e1stico y el acero; puede ser infectivo durante unos d\u00edas. Por lo tanto, es muy posible que alguien que est\u00e9 enfermo deposite el virus en la superficie y luego alguien m\u00e1s lo toque y se toque la cara.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/sintomas-del-coronavirus-covid-19-como-prevenir-tratamiento-y-telefonos-de-atencion-sanitaria.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135830\" title=\"sintomas-del-coronavirus-covid-19-como-prevenir-tratamiento-y-telefonos-de-atencion-sanitaria\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/sintomas-del-coronavirus-covid-19-como-prevenir-tratamiento-y-telefonos-de-atencion-sanitaria.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/sintomas-del-coronavirus-covid-19-como-prevenir-tratamiento-y-telefonos-de-atencion-sanitaria.jpg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/sintomas-del-coronavirus-covid-19-como-prevenir-tratamiento-y-telefonos-de-atencion-sanitaria-300x225.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><strong>\u00a0\u00bfExiste el riesgo de ser infectado por alimentos y paquetes que hemos recibido o que cogemos en tiendas y supermercados?<\/strong><\/p>\n<p>Es un riesgo bajo, pero es posible que si alguien est\u00e1 entregando un paquete en su casa o lo toca en la tienda y est\u00e1 enfermo aunque no tenga s\u00edntomas, puede ser una ruta de transmisi\u00f3n. Es muy recomendable que cada vez que algo nuevo entre en su hogar, tenga cuidado de lavarse las manos despu\u00e9s de manipularlo.<\/p>\n<p>La estabilidad del virus es bastante alta en el cart\u00f3n. Una vez que esos paquetes llegan a nuestra casa, es recomendable abrirlos, desechar r\u00e1pidamente el cart\u00f3n, lavarse las manos y no tocarse la cara. Hay que \u00a0minimizar el contacto de la superficie del paquete con su cara.<\/p>\n<p><strong>\u00bfEs posible que el contenido de un paquete haya sido contaminado por la persona que lo empaquet\u00f3?<\/strong><\/p>\n<p>No se puede descartar esa posibilidad de contaminaci\u00f3n, pero es mucho m\u00e1s probable que el cart\u00f3n que lo envuelve entre en contacto con mucha m\u00e1s gente que lo que hay dentro. Y si lleva d\u00edas llegar a su hogar, cualquier virus que haya dentro ya estar\u00e1 desactivado.<\/p>\n<p><strong>\u00bfC\u00f3mo y con qu\u00e9 frecuencia es recomendable limpiar las superficies de nuestra casa o lugar de trabajo?<\/strong><\/p>\n<p>Es bueno limpiar rutinariamente cualquier superficie de alto contacto, como las manillas y pomos de las puertas y los inodoros. Los limpiadores dom\u00e9sticos habituales son eficaces, incluidas las soluciones de lej\u00eda y las soluciones alcoh\u00f3licas de al menos un 70% de alcohol. Si alguien en su hogar ha sido diagnosticado con Covid-19, entonces la limpieza y la desinfecci\u00f3n son mucho m\u00e1s importantes y deben hacerse con m\u00e1s frecuencia.<\/p>\n<p>El\u00a0<a href=\"https:\/\/www.youtube.com\/watch?time_continue=2&amp;v=bu8XStOh_0s&amp;feature=emb_logo\" target=\"_blank\">Ministerio de Sanidad<\/a> y otros organismos como <a href=\"https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/prevent-getting-sick\/cleaning-disinfection.html?CDC_AA_refVal=https%3A%2F%2Fwww.cdc.gov%2Fcoronavirus%2F2019-ncov%2Fprepare%2Fcleaning-disinfection.html\" target=\"_blank\">el CDC<\/a> tiene una lista de productos de limpieza para el hogar que se sabe que matan a Covid-19. Este virus es un <a href=\"https:\/\/www.infectioncontroltoday.com\/covid-19\/select-effective-disinfectants-use-against-coronavirus-causes-covid-19\" target=\"_blank\">virus envuelto<\/a>, por lo que no sobrevive bien en jab\u00f3n y alcohol.<\/p>\n<p><strong>\u00bfQu\u00e9 public\u00f3 en su momento la OMS sobre la estabilidad y resistencia de SARS Cov (antecesor de SARS Cov2)?<\/strong><\/p>\n<p><a href=\"https:\/\/www.who.int\/csr\/sars\/survival_2003_05_04\/en\/\" target=\"_blank\">Primeros datos sobre estabilidad y resistencia del coronavirus del SARS compilados por miembros de la red de laboratorios de la OMS.<\/a><\/p>\n<p>La siguiente tabla proporciona la primera compilaci\u00f3n de datos sobre la resistencia del coronavirus SARS contra factores ambientales y desinfectantes. Esta informaci\u00f3n ha sido proporcionada por miembros de la red de colaboraci\u00f3n multic\u00e9ntrica de la OMS sobre diagn\u00f3stico de SARS. Se est\u00e1 recogiendo informaci\u00f3n m\u00e1s detallada sobre los m\u00e9todos utilizados y el material utilizado, que estar\u00e1 disponible en breve. Las principales conclusiones de estos estudios son:<\/p>\n<p><strong>Supervivencia del virus en heces y orina.<\/strong><\/p>\n<p>El virus es estable en las heces (y la orina) a temperatura ambiente durante al menos 1-2 d\u00edas.<\/p>\n<p>El virus es m\u00e1s estable (hasta 4 d\u00edas) en las heces de pacientes con diarrea (que tiene un pH m\u00e1s alto que las heces normales).<\/p>\n<p><strong>Desinfectantes<\/strong><\/p>\n<p>El virus pierde infectividad despu\u00e9s de la exposici\u00f3n a diferentes desinfectantes y fijadores com\u00fanmente utilizados.<\/p>\n<p><strong>Supervivencia del virus en sobrenadante de cultivo celular<\/strong><\/p>\n<p>Solo\u00a0 se produce una reducci\u00f3n m\u00ednima en el t\u00edtulo viral despu\u00e9s de 21 d\u00edas a 4 \u00b0 C y -80 \u00b0 C.<\/p>\n<p>Reducci\u00f3n de la concentraci\u00f3n de virus en un solo experimento a temperatura ambiente estable durante 2 d\u00edas. Esto indicar\u00eda que el virus es m\u00e1s estable que los coronavirus humanos conocidos en estas condiciones.<\/p>\n<p>La temperatura por encima de los 56 \u00b0 C mata el coronavirus del SARS a una tasa en torno a 10000 unidades por 15 minutos (reducci\u00f3n r\u00e1pida).<\/p>\n<p><strong>Fijadores (para uso exclusivo en laboratorios)<\/strong><\/p>\n<p><strong>La\u00a0<\/strong><strong><a href=\"https:\/\/www.who.int\/csr\/sars\/survival_2003_05_04\/en\/\" target=\"_blank\">fijaci\u00f3n del virus del SARS<\/a><\/strong>\u00a0(muerte) en portaobjetos de vidrio para ensayos de inmunofluorescencia a temperatura ambiente\u00a0<strong>no mata el virus de manera eficiente a menos que la acetona se enfr\u00ede a -20C.<\/strong><\/p>\n<p>En la siguiente tabla se recogen los resultados de estudios llevados a cabo en\u00a0 su momento por instituciones de investigaci\u00f3n. La tabla original est\u00e1 en ingl\u00e9s (tuve que traducirla) y <a href=\"https:\/\/www.who.int\/csr\/sars\/survival_2003_05_04\/en\/\" target=\"_blank\">se puede consultar aqu\u00ed<\/a>. Tuve que traducirla y no se ve muy bien. Tampoco en el original es muy f\u00e1cil de leer.<\/p>\n<p><strong><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Captura-de-pantalla-2020-04-15-a-las-14.44.37.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135770\" title=\"Captura de pantalla 2020-04-15 a las 14.44.37\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Captura-de-pantalla-2020-04-15-a-las-14.44.37.jpg\" alt=\"\" width=\"700\" height=\"315\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Captura-de-pantalla-2020-04-15-a-las-14.44.37.jpg 700w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/Captura-de-pantalla-2020-04-15-a-las-14.44.37-300x135.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/strong> <strong>\u00a0<\/strong><\/p>\n<p><strong><\/strong>Instituciones participantes: CUHK Chinese University Hong Kong GVU: Government Virus Unit, Dept. of Health, Hong Kong, SAR China QMH: Queen Mary Hospital, The University of Hong Kong, Hong Kong, SAR China NIID: National Institute of infectious Diseases, Tokyo, Japan UnivM: University Marburg, Germany<\/p>\n<p><strong>Conclusi\u00f3n: todav\u00eda sabemos muy poco.<\/strong><\/p>\n<p><strong><\/strong> <a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/52990919_7.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-135763\" title=\"52990919_7\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/52990919_7.png\" alt=\"\" width=\"500\" height=\"805\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/52990919_7.png 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/52990919_7-186x300.png 186w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a> Literatura recomendada.<\/p>\n<p><strong><a href=\"https:\/\/www.who.int\/csr\/sars\/survival_2003_05_04\/en\/\" target=\"_blank\">First data on stability and resistance of SARS coronavirus compiled by members of WHO laboratory network ( 4 de mayo de 2003)<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.cdc.gov\/mmwr\/volumes\/69\/wr\/mm6912e3.htm\" target=\"_blank\">Public Health Responses to COVID-19 Outbreaks on Cruise Ships \u2014 Worldwide, February\u2013March 2020<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.sciencemediacentre.org\/expert-reaction-to-cdc-report-on-covid-19-outbreaks-on-cruise-ships-which-includes-that-sars-cov-2-rna-was-identified-on-surfaces-in-cabins-up-to-17-days-after-they-were-vacated\/\" target=\"_blank\">Expert reaction to CDC report on COVID-19 outbreaks on cruise ships, which includes that SARS-CoV-2 RNA was identified on surfaces in cabins up to 17 days after they were vacated<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/jamanetwork.com\/journals\/jama\/fullarticle\/2762692\" target=\"_blank\">Air, Surface Environmental, and Personal Protective Equipment Contamination by Severe Acute Respiratory Syndrome Coronavirus 2 (SARS-CoV-2) From a Symptomatic Patient<\/a>\u00a04 de Marzo 2020.<\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.thelancet.com\/journals\/lanmic\/article\/PIIS2666-5247(20)30003-3\/fulltext\" target=\"_blank\">Stability of SARS-CoV-2 in different environmental conditions<\/a>. 2 de Abril 2020<\/strong><span style=\"font-size: 2em;\">\u00a0<\/span><\/p>\n<p><strong><a href=\"https:\/\/www.nejm.org\/doi\/10.1056\/NEJMc2004973\" target=\"_blank\">Aerosol and Surface Stability of SARS-CoV-2 as Compared with SARS-CoV-1<\/a>. 17 de Marzo 2020<\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.thelancet.com\/pdfs\/journals\/laninf\/PIIS1473-3099(20)30113-4.pdf\" target=\"_blank\">Viral load of SARS-CoV-2 in clinical samples<\/a>\u00a0<\/strong><strong>24 de febrero 2020<\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.medrxiv.org\/content\/10.1101\/2020.03.11.20034546v1\" target=\"_blank\">Environmental contamination of the SARS-CoV-2 in healthcare premises: An urgent call for protection for healthcare workers. 11 de marzo de 2020.<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.ecdc.europa.eu\/sites\/default\/files\/documents\/coronavirus-SARS-CoV-2-guidance-environmental-cleaning-non-healthcare-facilities.pdf\" target=\"_blank\">Interim guidance for environmental cleaning in non-healthcare facilities exposed to SARS-CoV-2. European center for Disease Prevention and Control. 18 Febrero 2020<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/aem.asm.org\/content\/76\/9\/2712\" target=\"_blank\">Effects of Air Temperature and Relative Humidity on Coronavirus Survival on Surfaces<\/a>\u00a026 Febrero 2010<\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.livescience.com\/coronavirus-can-spread-as-an-aerosol.html\" target=\"_blank\">New coronavirus may spread as an airborne aerosol, like SARS<\/a>. 1 de Abril 2020<\/strong> <strong>\u00a0<\/strong><\/p>\n<p><strong><a href=\"https:\/\/gisanddata.maps.arcgis.com\/apps\/opsdashboard\/index.html#\/bda7594740fd40299423467b48e9ecf6\/\" target=\"_blank\">Coronavirus COVID-19 Global Cases by Johns Hopkins CSSE<\/a><\/strong> \u00a0 \u00a0 <strong>\u00a0<\/strong> <strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las preguntas que m\u00e1s nos hacemos con respecto a SARS Cov 2 es, \u00bfcu\u00e1nto tiempo puede infectar este coronavirus? \u00bfpodemos infectarnos tocando superficies p\u00fablicas, en el supermercado, recogiendo paquetes? Las medidas de confinamiento buscan evitar el contacto con personas potencialmente infectadas por Covid-19. Sin embargo siguen apareciendo miles de nuevos infectados cada d\u00eda. Una explicaci\u00f3n es que se realizan m\u00e1s tests. Otra que la infectividad del virus es muy elevada y que permanece activo mucho tiempo. El\u00a0Centro para el Control de Enfermedades de los EE. UU. (CDC) public\u00f3 un informe sobre los brotes de COVID-19 en cruceros, que\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Una de las preguntas que m\u00e1s nos hacemos con respecto a SARS Cov 2 es, \u00bfcu\u00e1nto tiempo puede infectar este coronavirus? \u00bfpodemos infectarnos tocando superficies p\u00fablicas, en el supermercado, recogiendo paquetes? Las medidas de confinamiento buscan evitar el contacto con personas potencialmente infectadas por Covid-19. Sin embargo siguen apareciendo miles de nuevos infectados cada d\u00eda.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Una de las preguntas que m\u00e1s nos hacemos con respecto a SARS Cov 2 es, \u00bfcu\u00e1nto tiempo puede infectar este coronavirus? \u00bfpodemos infectarnos tocando superficies p\u00fablicas, en el supermercado, recogiendo paquetes? Las medidas de confinamiento buscan evitar el contacto con personas potencialmente infectadas por Covid-19. Sin embargo siguen apareciendo miles de nuevos infectados cada d\u00eda.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-04-17T09:00:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-04-17T09:00:06+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Una de las preguntas que m\u00e1s nos hacemos con respecto a SARS Cov 2 es, \u00bfcu\u00e1nto tiempo puede infectar este coronavirus? \u00bfpodemos infectarnos tocando superficies p\u00fablicas, en el supermercado, recogiendo paquetes? Las medidas de confinamiento buscan evitar el contacto con personas potencialmente infectadas por Covid-19. Sin embargo siguen apareciendo miles de nuevos infectados cada d\u00eda.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/17\\\/135745#blogposting\",\"name\":\"Coronavirus. CoVid19. \\u00bfDurante cu\\u00e1nto tiempo permanece infeccioso\\\/infectivo este coronavirus? - Ciencia Marina y otros asuntos\",\"headline\":\"Coronavirus. CoVid19. \\u00bfDurante cu\\u00e1nto tiempo permanece infeccioso\\\/infectivo este coronavirus?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/04\\\/coronavirus-covid19-espana-suma-10-fallecidos-casos-todas-las-ccaa-domingo-8-marzo-4248.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/17\\\/135745\\\/#articleImage\",\"width\":500,\"height\":297},\"datePublished\":\"2020-04-17T10:00:06+01:00\",\"dateModified\":\"2020-04-17T10:00:06+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/17\\\/135745#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/17\\\/135745#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/17\\\/135745#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/17\\\/135745#listItem\",\"name\":\"Coronavirus. CoVid19. \\u00bfDurante cu\\u00e1nto tiempo permanece infeccioso\\\/infectivo este coronavirus?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/17\\\/135745#listItem\",\"position\":3,\"name\":\"Coronavirus. CoVid19. \\u00bfDurante cu\\u00e1nto tiempo permanece infeccioso\\\/infectivo este coronavirus?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/17\\\/135745#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/17\\\/135745\",\"name\":\"Coronavirus. CoVid19. \\u00bfDurante cu\\u00e1nto tiempo permanece infeccioso\\\/infectivo este coronavirus? - Ciencia Marina y otros asuntos\",\"description\":\"Una de las preguntas que m\\u00e1s nos hacemos con respecto a SARS Cov 2 es, \\u00bfcu\\u00e1nto tiempo puede infectar este coronavirus? \\u00bfpodemos infectarnos tocando superficies p\\u00fablicas, en el supermercado, recogiendo paquetes? Las medidas de confinamiento buscan evitar el contacto con personas potencialmente infectadas por Covid-19. Sin embargo siguen apareciendo miles de nuevos infectados cada d\\u00eda.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/04\\\/17\\\/135745#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-04-17T10:00:06+01:00\",\"dateModified\":\"2020-04-17T10:00:06+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus? - Ciencia Marina y otros asuntos","description":"Una de las preguntas que m\u00e1s nos hacemos con respecto a SARS Cov 2 es, \u00bfcu\u00e1nto tiempo puede infectar este coronavirus? \u00bfpodemos infectarnos tocando superficies p\u00fablicas, en el supermercado, recogiendo paquetes? Las medidas de confinamiento buscan evitar el contacto con personas potencialmente infectadas por Covid-19. Sin embargo siguen apareciendo miles de nuevos infectados cada d\u00eda.","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745#blogposting","name":"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus? - Ciencia Marina y otros asuntos","headline":"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/04\/coronavirus-covid19-espana-suma-10-fallecidos-casos-todas-las-ccaa-domingo-8-marzo-4248.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745\/#articleImage","width":500,"height":297},"datePublished":"2020-04-17T10:00:06+01:00","dateModified":"2020-04-17T10:00:06+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745#listItem","name":"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745#listItem","position":3,"name":"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745","name":"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus? - Ciencia Marina y otros asuntos","description":"Una de las preguntas que m\u00e1s nos hacemos con respecto a SARS Cov 2 es, \u00bfcu\u00e1nto tiempo puede infectar este coronavirus? \u00bfpodemos infectarnos tocando superficies p\u00fablicas, en el supermercado, recogiendo paquetes? Las medidas de confinamiento buscan evitar el contacto con personas potencialmente infectadas por Covid-19. Sin embargo siguen apareciendo miles de nuevos infectados cada d\u00eda.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-04-17T10:00:06+01:00","dateModified":"2020-04-17T10:00:06+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus? - Ciencia Marina y otros asuntos","og:description":"Una de las preguntas que m\u00e1s nos hacemos con respecto a SARS Cov 2 es, \u00bfcu\u00e1nto tiempo puede infectar este coronavirus? \u00bfpodemos infectarnos tocando superficies p\u00fablicas, en el supermercado, recogiendo paquetes? Las medidas de confinamiento buscan evitar el contacto con personas potencialmente infectadas por Covid-19. Sin embargo siguen apareciendo miles de nuevos infectados cada d\u00eda.","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-04-17T09:00:06+00:00","article:modified_time":"2020-04-17T09:00:06+00:00","twitter:card":"summary","twitter:title":"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus? - Ciencia Marina y otros asuntos","twitter:description":"Una de las preguntas que m\u00e1s nos hacemos con respecto a SARS Cov 2 es, \u00bfcu\u00e1nto tiempo puede infectar este coronavirus? \u00bfpodemos infectarnos tocando superficies p\u00fablicas, en el supermercado, recogiendo paquetes? Las medidas de confinamiento buscan evitar el contacto con personas potencialmente infectadas por Covid-19. Sin embargo siguen apareciendo miles de nuevos infectados cada d\u00eda.","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"135745","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 19:57:35","updated":"2026-05-26 19:29:08","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCoronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Coronavirus. CoVid19. \u00bfDurante cu\u00e1nto tiempo permanece infeccioso\/infectivo este coronavirus?","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/04\/17\/135745"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/135745"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=135745"}],"version-history":[{"count":46,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/135745\/revisions"}],"predecessor-version":[{"id":135845,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/135745\/revisions\/135845"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=135745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=135745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=135745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}