{"id":136087,"date":"2020-05-06T20:07:09","date_gmt":"2020-05-06T19:07:09","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=136087"},"modified":"2020-05-07T07:31:59","modified_gmt":"2020-05-07T06:31:59","slug":"coronavirus-covid19-para-cuando-la-segunda-ola","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087","title":{"rendered":"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola?"},"content":{"rendered":"<p>A medida que los epidemi\u00f3logos intentan determinar lo que suceder\u00e1 con Covid-19 este verano y despu\u00e9s, se barajan diversos escenarios que se diferencian en la frecuencia y la gravedad con la que el coronavirus, que ya no es nuevo, continuar\u00e1 golpeando a la humanidad. Estos escenarios difieren en algunos detalles, como por ejemplo c\u00f3mo disminuir\u00e1n las infecciones, y si as\u00ed sucede, c\u00f3mo ser\u00e1n las tasas de transmisi\u00f3n durante el verano y cu\u00e1ntas personas ya han sido infectadas (y posiblemente adquirieron inmunidad). Sin embargo, casi un\u00e1nimemente, prev\u00e9n un mundo en el que, incluso cuando el brote actual disminuya al menos de forma temporal, no tendr\u00e1 nada que ver con el que conoc\u00edamos hace solo tres meses. Ser\u00e1 un mundo en el que, incluso en los pa\u00edses occidentales, usar una mascarilla ser\u00e1 tan normal como usar un tel\u00e9fono m\u00f3vil. Un mundo donde incluso en las peque\u00f1as reuniones sociales la tos ocasional de un amigo nos asustar\u00e1, donde los lugares de trabajo nos parecer\u00e1n peligrosos, y donde usar el transporte p\u00fablico, aunque sea respetuoso con el medio ambiente, podr\u00e1 ser peligroso para nuestra salud.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Playa_de_Badalona_32730880745.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136092\" title=\"Playa_de_Badalona_(32730880745)\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Playa_de_Badalona_32730880745.jpg\" alt=\"\" width=\"670\" height=\"449\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Playa_de_Badalona_32730880745.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Playa_de_Badalona_32730880745-300x201.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>Fuente: Wikimedia<\/p>\n<p><!--more--><\/p>\n<p>En un an\u00e1lisis publicado recientemente por el epidemi\u00f3logo Michael Osterholm y sus colegas, se describen tres posibles situaciones como las olas que llegan a una playa bajo distintas condiciones climatol\u00f3gicas.<\/p>\n<p>En el primer caso, contemplaremos en el futuro de manera retrospectiva, como una ola enorme golpe\u00f3 el mundo a principios de 2020 (el brote actual es de millones de casos y se esperan cientos de miles de muertes en todo el mundo para el 1 de agosto), que ser\u00e1 seguida por mini-olas alternando con brotes mucho m\u00e1s peque\u00f1os cada pocos meses, con s\u00f3lo unos pocos casos en los meses intermedios (pero nunca cero).<\/p>\n<p>En el segundo escenario, la enorme ola que acabamos de vivir es seguida este mismo a\u00f1o por otra dos veces m\u00e1s fuerte y m\u00e1s duradera. En este caso, una ca\u00edda significativa en el n\u00famero de casos y muertes nos llevar\u00eda a todos (gestores de la Sanidad P\u00fablica y poblaci\u00f3n en general) a bajar la guardia, relajando las medidas de distanciamiento f\u00edsico m\u00e1s de lo que era seguro y aconsejable, provocando la recuperaci\u00f3n de un brote despu\u00e9s del verano. Adem\u00e1s, Las primeras se\u00f1ales de advertencia de que un nuevo brote estar\u00eda ganando fuerza se ignorar\u00edan. Despu\u00e9s de esta segunda ola brutal, el mar volver\u00eda casi a la calma, con algunas olas ocasionales con casos que apenas representar\u00edan una quinta parte de lo que sucedi\u00f3 en la primavera y el oto\u00f1o de 2020.<\/p>\n<p>En el tercer posible escenario, la ola actual crea una nueva normalidad, con brotes de Covid-19 de tama\u00f1o similar y, en la mayor\u00eda de los casos, extendi\u00e9ndose hasta finales de 2022. En ese momento, en el mejor de los casos se habr\u00eda conseguido una vacuna eficaz; y si no fuese as\u00ed, el mundo sufrir\u00eda Covid-19 hasta que al menos la mitad de la poblaci\u00f3n se hubiese infectado, padeciendo o no la enfermedad.<\/p>\n<p>En lo que coinciden los tres escenarios es en que no hay ninguna posibilidad de que Covid-19 termine cuando el mundo se despida de este terrible a\u00f1o 2020. La raz\u00f3n es la misma por la cual la enfermedad ha sido tan dura: No tenemos inmunidad frente al nuevo coronavirus. Esta pandemia no terminar\u00e1 hasta que haya suficiente inmunidad en la poblaci\u00f3n, que tendr\u00eda que ser superior al 50% (algunos cient\u00edficos hablan de un 70% o m\u00e1s). Dado que el mundo est\u00e1 muy lejos de ese nivel de inmunidad, (se estima que no m\u00e1s del 5% de la poblaci\u00f3n mundial es inmune al nuevo coronavirus), este virus se mantendr\u00e1 infectando y extendi\u00e9ndose entre la poblaci\u00f3n. Y eso significa que nos espera un largo camino por recorrer.<\/p>\n<p>La incertidumbre sobre c\u00f3mo desarrollar\u00e1 a largo plazo, en un tercer escenario o en un primero mucho menos brutal, refleja la gran cantidad de inc\u00f3gnitas que rodean un brote sin paralelo en la historia moderna. Los cl\u00ednicos han aprendido mucho sobre la enfermedad y su tratamiento, mientras que los cient\u00edficos todav\u00eda est\u00e1n trabajando a marchas forzadas para comprender todo lo relacionado con ella, desde la biolog\u00eda b\u00e1sica del virus (\u00bfcu\u00e1nto reducen la transmisi\u00f3n las temperaturas c\u00e1lidas y la humedad elevada?), el dise\u00f1o de estrategias (\u00bfcerrar las escuelas ayuda lo suficiente como para justificar el impacto sobre la educaci\u00f3n de los ni\u00f1os?) y posibles profilaxis qu\u00edmicas (\u00bfpuede reducirse la gravedad?). Las respuestas a estas preguntas afectar\u00e1n a lo que se haga en el futuro.<\/p>\n<p>Quiz\u00e1s lo que menos conocemos afecta a valores humanos y sociales. Para decirlo sin rodeos, \u00bfcu\u00e1ntas muertes, cu\u00e1nta pobreza puede tolerar un pa\u00eds, ciudad o comunidad en particular? Los distintos pa\u00edses tendr\u00e1n que decidir qu\u00e9 significa \u00abdemasiadas muertes, demasiada miseria\u00bb. Suecia, por ejemplo, ha impuesto solo medidas leves de distanciamiento f\u00edsico, tales como la prohibici\u00f3n de grandes reuniones, pero sus escuelas, restaurantes, tiendas y lugares de trabajo han permanecido abiertos. Tiene menos casos por mill\u00f3n de personas que Espa\u00f1a, Italia, Estados Unidos, Francia, el Reino Unido y otros pa\u00edses que adoptaron medidas m\u00e1s estrictas con un coste social y econ\u00f3mico mucho mayor.<\/p>\n<p>Hace tres meses, cuando Wuhan, el origen de la pandemia, China, llevaba en confinamiento solo una semana, en el mundo hab\u00eda ya 10,000 casos. En Espa\u00f1a se hab\u00eda detectado un \u00fanico caso, una persona que ven\u00eda de Alemania y hab\u00eda estado en contacto con una persona que hab\u00eda estado en China. El primer caso documentado de transmisi\u00f3n comunitaria tardar\u00eda todav\u00eda tres semanas. Sin embargo, los expertos estaban de acuerdo en que no era posible contener el brote. El consenso entre los expertos era que, si bien el nuevo coronavirus podr\u00eda establecerse y simplemente causar resfriados (similar a una gripe), como los otros cuatro coronavirus humanos que ya estaban en circulaci\u00f3n, era m\u00e1s probable que regresara a\u00f1o tras a\u00f1o como la gripe estacional, causando enfermedades mucho m\u00e1s graves que el resfriado.<\/p>\n<p>En este momento, con casi 4 millones de casos confirmados en todo el mundo y m\u00e1s de 250.000 fallecidos, estamos, en opini\u00f3n de los epidemi\u00f3logos, ante tres posibles situaciones en el hemisferio norte. En cada una, la peque\u00f1a ola a principios de 2020 representa el brote de Covid-19 en China, que alcanz\u00f3 su punto m\u00e1ximo a fines de enero y febrero, pero desapareci\u00f3 en marzo. La siguiente cresta de la ola, mucho m\u00e1s grande, representa la pandemia fuera de China, especialmente en Europa y los EE. UU. Cada escenario se extiende hasta 2022, cuando hay una posibilidad razonable de que haya llegado una vacuna y se haya producido suficiente para inocular cientos de millones de personas.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136095\" title=\"Escenario 1\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-1.jpg\" alt=\"\" width=\"670\" height=\"362\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-1.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-1-300x162.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>Fuente:\u00a0<em>HYACINTH EMPINADO\/STAT; SOURCE: MICHAEL OSTERHOLM\/UNIVERSITY OF MINNESOTA<\/em><\/p>\n<p><strong>Escenario uno: olas peque\u00f1as hasta donde llega la vista.<\/strong><\/p>\n<p>En esta situaci\u00f3n, el pico actual en los casos de Covid-19 es seguido por secuencias de pico y valle a lo largo de los dos pr\u00f3ximos a\u00f1os. Los picos ser\u00e1n probablemente la mitad del tama\u00f1o del brote de esta primavera, y los n\u00fameros m\u00e1s altos coincidir\u00e1n con la temporada de gripe el pr\u00f3ximo oto\u00f1o y los per\u00edodos m\u00e1s bajos lo har\u00e1n con este verano y el pr\u00f3ximo. Adem\u00e1s, ser\u00e1n probables variaciones regionales debidas a factores que incluyen brotes aleatorios, la mala suerte de tener s\u00faper contagiadores y pocos tests y casi nulo rastreo de contactos para extinguir los nuevos brotes antes de que exploten y afecten a una gran fracci\u00f3n de la poblaci\u00f3n.<\/p>\n<p>La posibilidad de pico y valle refleja un consenso emergente de que este coronavirus tiene cierta estacionalidad, pero no ser\u00e1 eliminado totalmente por el clima c\u00e1lido y h\u00famedo. El consenso entre los cient\u00edficos es que es poco probable que el clima suprima por s\u00ed solo radicalmente Covid-19 durante el verano de 2020, porque todav\u00eda tendremos una poblaci\u00f3n que es casi completamente susceptible al virus. Por eso la reducci\u00f3n estacional no tendr\u00e1 un gran efecto.<\/p>\n<p>Eso se explica en base al modo de transmisi\u00f3n del virus. El calor y la humedad pueden inactivar el virus en las superficies, pero en el verano todav\u00eda habr\u00e1 muchas personas que puedan transmitirlo de persona a persona, estornudando, tosiendo e incluso hablando. \u00bfCu\u00e1nta gente? Los epidemi\u00f3logos consideran una reducci\u00f3n del 20% en la transmisibilidad durante el verano siempre y cuando se comporte como los otros cuatro coronavirus humanos, que causan resfriados comunes. Esto s\u00f3lo ser\u00e1 un freno temporal.<\/p>\n<p>Por esta reducci\u00f3n de m\u00e1s del 20% en los casos, los expertos recomiendan actuar de acuerdo con la \u201cherencia\u201d que nos dej\u00f3 la pandemia: abrir bares y playas todo lo que quieran, pero limitando el aforo, practicando el distanciamiento f\u00edsico y extremando las medidas de higiene. <strong>Sin la necesidad de \u00f3rdenes estrictas, deberemos incorporar el distanciamiento f\u00edsico en nuestro estilo de vida como muestra de responsabilidad ciudadana.<\/strong><\/p>\n<p>Como resultado, los grandes espect\u00e1culos y los conciertos deber\u00e1n desaparecer temporalmente de nuestras vidas. En otros casos habr\u00e1 que incorporar medidas que implican escalonar los turnos de trabajo,\u00a0 levantar mamparas entre cub\u00edculos y enviar a casa a cualquier empleado que tenga incluso un poco de fiebre. La nueva normalidad consolidar\u00e1 el distanciamiento f\u00edsico que ha evitado que las peores predicciones para la primera ola de Covid-19 se hiciesen realidad.<\/p>\n<p>Para muchos, ponerse una mascarilla antes de reunirse con amigos en un parque o ir al gimnasio ser\u00e1 tan natural como llevar el tel\u00e9fono m\u00f3vil. En los restaurantes, es probable que a los clientes se les tome la temperatura antes de sentarse y los camareros usar\u00e1n mascarilla y guantes. Y cuando ocurran brotes locales, esas medidas se volver\u00e1n m\u00e1s estrictas, aunque solo sea a trav\u00e9s de medidas voluntarias. Muchos trabajadores, asustados por una crisis local, teletrabajar\u00e1n si pueden. La gente volver\u00e1 a evitar el transporte p\u00fablico, incluso los taxis. Pospondr\u00e1n las cirug\u00edas programadas y las visitas al m\u00e9dico, especialmente a medida que arraigue la telemedicina.<\/p>\n<p>Probablemente, gracias a esas medidas el brote se disipar\u00e1 nuevamente. Sin embargo, muchas personas tomar\u00e1n eso como una se\u00f1al de que pueden bajar la guardia y la pr\u00f3xima ola golpear\u00e1 &#8230; una y otra vez hasta que muchas personas se hayan infectados, o una vacuna tenga \u00e9xito, para producir inmunidad colectiva. Seg\u00fan Osterholm, autor del estudio: <strong>\u00abSigo dici\u00e9ndole a la gente que el brote no terminar\u00e1 con esta ola\u00bb<\/strong>.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136097\" title=\"Escenario 2\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-2.jpg\" alt=\"\" width=\"670\" height=\"362\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-2.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-2-300x162.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>Fuente:\u00a0<em>HYACINTH EMPINADO\/STAT; SOURCE: MICHAEL OSTERHOLM\/UNIVERSITY OF MINNESOTA<\/em><\/p>\n<p><strong>Escenario dos: vuelta al pasado<\/strong><\/p>\n<p>En marzo de 1918 se detect\u00f3 la primera ola moderada de gripe espa\u00f1ola. El n\u00famero de casos disminuy\u00f3 durante ese verano, pero seis meses despu\u00e9s, en el oto\u00f1o, la epidemia explot\u00f3. Eso fue seguido por picos m\u00e1s peque\u00f1os a principios de 1919. Y luego termin\u00f3 la pandemia. Las pandemias de gripe de 1957 y 1958, y la gripe porcina de 2009, siguieron un patr\u00f3n similar.<\/p>\n<p>En este escenario, en lugar de reaparecer durante todo el a\u00f1o como los picos del primer escenario, Covid-19 regresar\u00eda con m\u00e1s fuerza a fines del verano y oto\u00f1o y luego se disipar\u00eda, manteniendo un n\u00famero peque\u00f1o, pero casi constante de casos. En este caso, seg\u00fan Osterholm, tendr\u00edamos lo que se conoce como un acantilado. Primero, se infectar\u00edan muchas personas en una primera ola moderada (la actual) y a continuaci\u00f3n ocurrir\u00eda una segunda ola gigante (que alcanzar\u00eda su punto m\u00e1ximo en octubre) que conseguir\u00eda que alcanz\u00e1semos el nivel de inmunidad colectiva (70%). En segundo lugar, esta segunda ola, destrozar\u00eda totalmente el sistema de salud.<\/p>\n<p>En Espa\u00f1a podr\u00eda darse este caso. Actualmente el nivel de infectados en la mayor\u00eda de las Comunidades Aut\u00f3nomas, sobre todo de las costeras no supera el cinco por ciento de la poblaci\u00f3n. Imaginemos desplazamientos sin control desde Comunidades con niveles bastante m\u00e1s elevados a Comunidades con bajo nivel de casos por cien mil habitantes.\u00a0En julio de 2019 se hab\u00edan previsto 43 millones de desplazamientos y en agosto, la previsi\u00f3n fue de 47 millones de desplazamientos de largo recorrido.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Contagios-por-100000.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136099\" title=\"Contagios por 100000\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Contagios-por-100000.jpg\" alt=\"\" width=\"670\" height=\"418\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Contagios-por-100000.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Contagios-por-100000-300x187.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>Fuente: Datos Ministerio de Sanidad. 4 de mayo 2020. Diagnosticados por PCR. Gr\u00e1fico Elaboraci\u00f3n propia.<\/p>\n<p>Las posibilidades de contagio se incrementan. Al acabar el verano, comienzan las clases, la actividad laboral est\u00e1 alcanzando cotas de \u201cnormalidad\u201d se relajan las condiciones (no est\u00e1 pasando nada) y de golpe asistimos a un rebrote de dimensiones muy superiores al que ya tuvimos. Este es el escenario de la gripe del 18.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Gripe-18.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136101\" title=\"Gripe 18\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Gripe-18.jpg\" alt=\"\" width=\"670\" height=\"326\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Gripe-18.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Gripe-18-300x145.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>Fuente: CDC. USA.<\/p>\n<p>Los esfuerzos para \u00abaplanar la curva\u00bb en todo el mundo ten\u00edan como objetivo evitar que los sistemas de salud se colapsasen. A partir de marzo, esos esfuerzos tuvieron un \u00e9xito relativo. Pero incluso si los hospitales utilizasen la pausa de verano para acumular equipos de protecci\u00f3n personal, ventiladores y otras necesidades, para prepararse para un regreso intenso de Covid-19 en oto\u00f1o e invierno, probablemente no ser\u00e1 suficiente. Si adem\u00e1s tuvi\u00e9ramos una mala temporada de gripe, ser\u00e1 muy dif\u00edcil que los hospitales puedan hacer frente a ambos ataques.<\/p>\n<p>Un colapso inminente o real del sistema de atenci\u00f3n m\u00e9dica, similar a lo que el norte de Italia experiment\u00f3 en marzo, obligar\u00eda a imponer medidas de confinamiento a\u00fan m\u00e1s estrictas que las de las \u00faltimas seis semanas, lo que, como sucedi\u00f3 en China desde finales de enero a principios de marzo, en su mayor\u00eda apagar\u00eda el Covid-19. Debido a que el nuevo coronavirus continuar\u00eda circulando, como los otros cuatro coronavirus humanos, todav\u00eda habr\u00eda una transmisi\u00f3n de bajo nivel. Pero los casos ser\u00edan tan pocos que dif\u00edcilmente contar\u00edan como \u00abbrotes\u00bb; en cambio, Covid-19 estar\u00eda con nosotros a un nivel bastante bajo, con quiz\u00e1s miles de casos a la vez.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-3.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136103\" title=\"Escenario 3\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-3.jpg\" alt=\"\" width=\"670\" height=\"362\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-3.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Escenario-3-300x162.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p><strong>Escenario tres: el peor d\u00eda de la marmota<\/strong><\/p>\n<p>Si todo se comporta de forma an\u00e1rquica, con brotes en esta ciudad o en esa otra y se intenta sofocarlos ser\u00eda el escenario que podr\u00edamos denominar de \u00abcombusti\u00f3n lenta\u00bb. Las olas siguen llegando porque el tama\u00f1o de los brotes que siguen al actual son m\u00e1s peque\u00f1os que en el segundo escenario de la gran ola. Por lo tanto, la inmunidad de la poblaci\u00f3n tarda m\u00e1s en conseguirse. Se producen brotes locales, peores en algunos lugares que en otros debido a, entre otras cosas, la diferente capacidad para realizar tests \u00a0generalizados y regulares y el seguimiento de contactos.<\/p>\n<p>Ninguna pandemia anterior de gripe sigui\u00f3 este patr\u00f3n. Sin embargo, hay dos razones por las que Covid-19 podr\u00eda hacerlo. Una es biol\u00f3gica: los coronavirus, como muestran los cuatro que ya son end\u00e9micos, son terriblemente expertos en continuar circulando y nunca desaparecen (el coronavirus del SARS a principios de la d\u00e9cada de 2000 fue una excepci\u00f3n). La otra es sociol\u00f3gica: \u00bfcu\u00e1l es la capacidad de la sociedad para resistir otro cierre econ\u00f3mico?, y \u00bfde forma recurrente?. En el futuro, esas pol\u00edticas, al menos en algunas ciudades y autonom\u00edas, pueden ser menos estrictas y, por lo tanto, menos eficaces para controlar los brotes, que las impuestas esta primavera. Es por eso que, en este escenario, los futuros brotes siguen llegando, con duraciones y n\u00famero de casos comparables a la actual.<\/p>\n<p>\u00bfLas olas interminables significan que el distanciamiento f\u00edsico tendr\u00e1 que volver a imponerse una y otra vez, forzando el cierre repetido de negocios que acaban de reabrir y el despido de empleados cuyos trabajos siguen siendo eliminados? Aunque es dif\u00edcil de recordar, las \u00f3rdenes de quedarse en casa, los cierres de negocios y otras medidas de mitigaci\u00f3n ten\u00edan como objetivo aplanar la curva: ralentizar la propagaci\u00f3n de Covid-19 lo suficiente como para mantener el n\u00famero de pacientes que necesitan hospitalizaci\u00f3n, cuidados intensivos, o un ventilador no superior a la capacidad del sistema de salud. Aplanar la curva no significaba que no iba a haber enfermos de distinta gravedad o muertes. Si ese sigue siendo el objetivo para las futuras olas de Covid-19, entonces las medidas de confinamiento podr\u00edan ser no tan severas, como reconoce un n\u00famero creciente de epidemi\u00f3logos. Una vez que hemos comprobado la escasez de suministros sanitarios se deber\u00eda utilizar la pausa de verano para prepararse mejor y hacer ajustes para poder absorber una posible oleada de casos en el pr\u00f3ximo oto\u00f1o.<\/p>\n<p>La sociedad debe preparase para un tira y afloja de tres v\u00edas: mantener bajos los casos y las muertes, preservar los empleos y actividad econ\u00f3mica y preservar el bienestar emocional de las personas. Si el sistema de salud p\u00fablica se debilita, las olas seguir\u00e1n llegando hasta fines de 2022.<\/p>\n<p>\u00bfY qu\u00e9 escenario es m\u00e1s probable? Seg\u00fan el epidemi\u00f3logo Osterholm, tendremos algunos meses dif\u00edciles en el futuro. Deseo que se equivoque.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuentes.<\/p>\n<p>&nbsp;<\/p>\n<p>COVID-19: The CIDRAP Viewpoint April 30th, 2020 Part 1: The Future of the COVID-19 Pandemic: Lessons Learned from Pandemic Influenza Kristine A. Moore, MD, MPH Marc Lipsitch, DPhil John M. Barry, MA Michael T. Osterholm, PhD, MPH<\/p>\n<p><a href=\"https:\/\/www.statnews.com\/2020\/05\/01\/three-potential-futures-for-covid-19\/\">Three potential futures for Covid-19: recurring small outbreaks, a monster wave, or a persistent crisis<\/a> por SHARON BEGLEY en STATNEWS<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que los epidemi\u00f3logos intentan determinar lo que suceder\u00e1 con Covid-19 este verano y despu\u00e9s, se barajan diversos escenarios que se diferencian en la frecuencia y la gravedad con la que el coronavirus, que ya no es nuevo, continuar\u00e1 golpeando a la humanidad. Estos escenarios difieren en algunos detalles, como por ejemplo c\u00f3mo disminuir\u00e1n las infecciones, y si as\u00ed sucede, c\u00f3mo ser\u00e1n las tasas de transmisi\u00f3n durante el verano y cu\u00e1ntas personas ya han sido infectadas (y posiblemente adquirieron inmunidad). Sin embargo, casi un\u00e1nimemente, prev\u00e9n un mundo en el que, incluso cuando el brote actual disminuya al menos de\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"A medida que los epidemi\u00f3logos intentan determinar lo que suceder\u00e1 con Covid-19 este verano y despu\u00e9s, se barajan diversos escenarios que se diferencian en la frecuencia y la gravedad con la que el coronavirus, que ya no es nuevo, continuar\u00e1 golpeando a la humanidad. Estos escenarios difieren en algunos detalles, como por ejemplo c\u00f3mo disminuir\u00e1n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"A medida que los epidemi\u00f3logos intentan determinar lo que suceder\u00e1 con Covid-19 este verano y despu\u00e9s, se barajan diversos escenarios que se diferencian en la frecuencia y la gravedad con la que el coronavirus, que ya no es nuevo, continuar\u00e1 golpeando a la humanidad. Estos escenarios difieren en algunos detalles, como por ejemplo c\u00f3mo disminuir\u00e1n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-05-06T19:07:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-05-07T06:31:59+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A medida que los epidemi\u00f3logos intentan determinar lo que suceder\u00e1 con Covid-19 este verano y despu\u00e9s, se barajan diversos escenarios que se diferencian en la frecuencia y la gravedad con la que el coronavirus, que ya no es nuevo, continuar\u00e1 golpeando a la humanidad. Estos escenarios difieren en algunos detalles, como por ejemplo c\u00f3mo disminuir\u00e1n\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/05\\\/06\\\/136087#blogposting\",\"name\":\"Coronavirus: CoVid19. \\u00bfpara cu\\u00e1ndo la segunda ola? - Ciencia Marina y otros asuntos\",\"headline\":\"Coronavirus: CoVid19. \\u00bfpara cu\\u00e1ndo la segunda ola?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/05\\\/Playa_de_Badalona_32730880745.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/05\\\/06\\\/136087\\\/#articleImage\",\"width\":670,\"height\":449},\"datePublished\":\"2020-05-06T20:07:09+01:00\",\"dateModified\":\"2020-05-07T07:31:59+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/05\\\/06\\\/136087#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/05\\\/06\\\/136087#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/05\\\/06\\\/136087#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/05\\\/06\\\/136087#listItem\",\"name\":\"Coronavirus: CoVid19. \\u00bfpara cu\\u00e1ndo la segunda ola?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/05\\\/06\\\/136087#listItem\",\"position\":3,\"name\":\"Coronavirus: CoVid19. \\u00bfpara cu\\u00e1ndo la segunda ola?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/05\\\/06\\\/136087#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/05\\\/06\\\/136087\",\"name\":\"Coronavirus: CoVid19. \\u00bfpara cu\\u00e1ndo la segunda ola? - Ciencia Marina y otros asuntos\",\"description\":\"A medida que los epidemi\\u00f3logos intentan determinar lo que suceder\\u00e1 con Covid-19 este verano y despu\\u00e9s, se barajan diversos escenarios que se diferencian en la frecuencia y la gravedad con la que el coronavirus, que ya no es nuevo, continuar\\u00e1 golpeando a la humanidad. Estos escenarios difieren en algunos detalles, como por ejemplo c\\u00f3mo disminuir\\u00e1n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/05\\\/06\\\/136087#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-05-06T20:07:09+01:00\",\"dateModified\":\"2020-05-07T07:31:59+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola? - Ciencia Marina y otros asuntos","description":"A medida que los epidemi\u00f3logos intentan determinar lo que suceder\u00e1 con Covid-19 este verano y despu\u00e9s, se barajan diversos escenarios que se diferencian en la frecuencia y la gravedad con la que el coronavirus, que ya no es nuevo, continuar\u00e1 golpeando a la humanidad. Estos escenarios difieren en algunos detalles, como por ejemplo c\u00f3mo disminuir\u00e1n","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087#blogposting","name":"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola? - Ciencia Marina y otros asuntos","headline":"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/05\/Playa_de_Badalona_32730880745.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087\/#articleImage","width":670,"height":449},"datePublished":"2020-05-06T20:07:09+01:00","dateModified":"2020-05-07T07:31:59+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087#listItem","name":"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087#listItem","position":3,"name":"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087","name":"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola? - Ciencia Marina y otros asuntos","description":"A medida que los epidemi\u00f3logos intentan determinar lo que suceder\u00e1 con Covid-19 este verano y despu\u00e9s, se barajan diversos escenarios que se diferencian en la frecuencia y la gravedad con la que el coronavirus, que ya no es nuevo, continuar\u00e1 golpeando a la humanidad. Estos escenarios difieren en algunos detalles, como por ejemplo c\u00f3mo disminuir\u00e1n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-05-06T20:07:09+01:00","dateModified":"2020-05-07T07:31:59+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola? - Ciencia Marina y otros asuntos","og:description":"A medida que los epidemi\u00f3logos intentan determinar lo que suceder\u00e1 con Covid-19 este verano y despu\u00e9s, se barajan diversos escenarios que se diferencian en la frecuencia y la gravedad con la que el coronavirus, que ya no es nuevo, continuar\u00e1 golpeando a la humanidad. Estos escenarios difieren en algunos detalles, como por ejemplo c\u00f3mo disminuir\u00e1n","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-05-06T19:07:09+00:00","article:modified_time":"2020-05-07T06:31:59+00:00","twitter:card":"summary","twitter:title":"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola? - Ciencia Marina y otros asuntos","twitter:description":"A medida que los epidemi\u00f3logos intentan determinar lo que suceder\u00e1 con Covid-19 este verano y despu\u00e9s, se barajan diversos escenarios que se diferencian en la frecuencia y la gravedad con la que el coronavirus, que ya no es nuevo, continuar\u00e1 golpeando a la humanidad. Estos escenarios difieren en algunos detalles, como por ejemplo c\u00f3mo disminuir\u00e1n","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"136087","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-04 05:53:13","updated":"2026-05-26 19:31:04","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCoronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Coronavirus: CoVid19. \u00bfpara cu\u00e1ndo la segunda ola?","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/06\/136087"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136087"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=136087"}],"version-history":[{"count":22,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136087\/revisions"}],"predecessor-version":[{"id":136115,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136087\/revisions\/136115"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=136087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=136087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=136087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}