{"id":136453,"date":"2020-06-04T10:41:07","date_gmt":"2020-06-04T09:41:07","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=136453"},"modified":"2020-06-04T10:41:07","modified_gmt":"2020-06-04T09:41:07","slug":"coronavirus-como-hacer-las-pruebas-y-el-seguimiento-de-contactos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453","title":{"rendered":"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos"},"content":{"rendered":"<h2 id=\"a862\">Parte 3 de Coronavirus: Aprendiendo a Danzar<\/h2>\n<p data-selectable-paragraph=\"\"><em>Traducci\u00f3n del art\u00edculo de\u00a0<\/em><a href=\"https:\/\/medium.com\/@tomaspueyo\" rel=\"noopener\" target=\"_blank\"><em>Tomas Pueyo<\/em><\/a><em>\u00a0por\u00a0<\/em><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/\" rel=\"noopener nofollow\" target=\"_blank\"><em>Antonio Figueras<\/em><\/a><em>.<\/em><\/p>\n<p data-selectable-paragraph=\"\">\n<section>\n<div>\n<div>\n<p id=\"4d23\" data-selectable-paragraph=\"\"><em>Nuestros art\u00edculos anteriores,\u00a0<\/em><a href=\"https:\/\/medium.com\/tomas-pueyo\/coronavirus-por-qu%C3%A9-debemos-actuar-ya-93079c61e200\" rel=\"noopener\" target=\"_blank\">Coronavirus: Por qu\u00e9 Debemos Actuar Ya<\/a><em>,\u00a0<\/em><a href=\"https:\/\/medium.com\/tomas-pueyo\/coronavirus-el-martillo-y-la-danza-32abc4dd4ebb\" rel=\"noopener\" target=\"_blank\">Coronavirus: El Martillo y la Danza<\/a><em>, and\u00a0<\/em><a href=\"https:\/\/medium.com\/@tomaspueyo\/coronavirus-out-of-many-one-36b886af37e9\" rel=\"noopener\" target=\"_blank\"><em>Out of Many, One<\/em><\/a><em>\u00a0han reunido m\u00e1s de 60 millones de visitas y han sido traducidos a m\u00e1s de 40 idiomas. Esta entrega es la parte 3 (<\/em><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/25\/136297\" rel=\"noopener\" target=\"_blank\"><em>parte 1<\/em><\/a><em>\u00a0y\u00a0<\/em><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/01\/136401\" rel=\"noopener\" target=\"_blank\"><em>parte 2<\/em><\/a><em>) de nuestro cuarto art\u00edculo,\u00a0<\/em><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/25\/136297\" rel=\"noopener\" target=\"_blank\"><em>Aprendiendo a Danzar<\/em><\/a><em>, una serie que se centra en los pasos espec\u00edficos necesarios para abrir la econom\u00eda.\u00a0<\/em><\/p>\n<\/div>\n<\/div>\n<\/section>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Bx0Im8jDGZ2e7Cxe-copia1.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136471\" title=\"0_Bx0Im8jDGZ2e7Cxe copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Bx0Im8jDGZ2e7Cxe-copia1.png\" alt=\"\" width=\"670\" height=\"379\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Bx0Im8jDGZ2e7Cxe-copia1.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Bx0Im8jDGZ2e7Cxe-copia1-300x169.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">\n<section>\n<div>\n<div>\n<p id=\"8e2e\" data-selectable-paragraph=\"\">Resumen<br \/>\nPodemos reabrir la econom\u00eda nuevamente s\u00ed llevamos a cabo correctamente algunas acciones, incluidas las pruebas de diagn\u00f3stico y el seguimiento de contactos. Necesitamos evaluar a todas las personas con s\u00edntomas y sus contactos, lo que significa que como m\u00e1ximo el 3% de nuestras pruebas deber\u00edan resultar positivas. Necesitamos identificar tantos infectados como sea posible, y entre el 70% y el 90% de sus contactos, para aislarlos o ponerlos en cuarentena. Si hacemos todo eso realmente r\u00e1pido (dentro de un d\u00eda m\u00e1s o menos), podr\u00eda ser suficiente para controlar la epidemia. Deber\u00edamos contratar a mucha gente para hacer eso, y tambi\u00e9n usar tecnolog\u00eda. La tecnolog\u00eda tiene algunas compensaciones de privacidad, pero son realmente razonables. La mayor\u00eda de las aplicaciones de rastreo de contactos bluetooth creadas hoy son incre\u00edbles piezas de tecnolog\u00eda que ser\u00e1n in\u00fatiles a menos que sufran cambios fundamentales<\/p>\n<\/div>\n<\/div>\n<\/section>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p data-selectable-paragraph=\"\">\n<section>\n<p id=\"6e32\" data-selectable-paragraph=\"\">En la actualidad, muchos pa\u00edses est\u00e1n soportando la acci\u00f3n del Martillo: un gran conjunto de medidas de distanciamiento y confinamiento social que han detenido la econom\u00eda. Millones han perdido sus empleos, sus ingresos, sus ahorros, sus negocios, su libertad. El coste econ\u00f3mico es brutal. Los pa\u00edses est\u00e1n desesperados por saber qu\u00e9 deben hacer para reactivar nuevamente la econom\u00eda.<\/p>\n<p id=\"d998\" data-selectable-paragraph=\"\">Afortunadamente, un conjunto de cuatro medidas puede reducir dr\u00e1sticamente la epidemia. En comparaci\u00f3n con el cierre de la econom\u00eda son bastante menos costosas. Muchos pa\u00edses est\u00e1n soportando actualmente la acci\u00f3n contundente del\u00a0<a href=\"https:\/\/medium.com\/@tomaspueyo\/coronavirus-the-hammer-and-the-dance-be9337092b56\" rel=\"noopener\" target=\"_blank\">Martillo<\/a>\u00a0, estas medidas que exponemos a continuaci\u00f3n, son el bistur\u00ed, que extrae cuidadosamente a los infectados en lugar de golpear a todos a la vez.<\/p>\n<p id=\"1088\" data-selectable-paragraph=\"\">Estas cuatro medidas se necesitan mutuamente. No funcionan independientemente:<\/p>\n<ul>\n<li id=\"e9df\" data-selectable-paragraph=\"\">Con las\u00a0pruebas, descubrimos qui\u00e9n est\u00e1 infectado<\/li>\n<li id=\"907e\" data-selectable-paragraph=\"\">Con\u00a0aislamientos, evitamos que infecten a otros<\/li>\n<li id=\"e14f\" data-selectable-paragraph=\"\">Con el\u00a0seguimiento de contactos, descubrimos las personas con las que han estado en contacto<\/li>\n<li id=\"7558\" data-selectable-paragraph=\"\">Con las\u00a0cuarentenas, evitamos que estos contactos infecten a otros<\/li>\n<\/ul>\n<p id=\"930d\" data-selectable-paragraph=\"\">Las pruebas y el seguimiento de contactos son la inteligencia, mientras que los aislamientos y las cuarentenas son la acci\u00f3n. Hoy profundizaremos en las dos primeras\u2014 pruebas y seguimiento de contactos \u2014 y trataremos los dos siguientes a continuaci\u00f3n.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_3Gdz4tkkliF5GCRP-copia1.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136511\" title=\"0_3Gdz4tkkliF5GCRP copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_3Gdz4tkkliF5GCRP-copia1.png\" alt=\"\" width=\"670\" height=\"389\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_3Gdz4tkkliF5GCRP-copia1.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_3Gdz4tkkliF5GCRP-copia1-300x174.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_3Gdz4tkkliF5GCRP-copia.png\"><br \/>\n<\/a><\/p>\n<h2 id=\"0455\" data-selectable-paragraph=\"\">Pruebas (Tests)<\/h2>\n<p id=\"0f9a\" data-selectable-paragraph=\"\">Las pruebas han estado en el centro de la conversaci\u00f3n durante semanas. En la mayor\u00eda de los pa\u00edses, la gente critica la falta de tests. Pero pocas personas preguntan: \u00bfCu\u00e1ntas pruebas debemos hacer?<\/p>\n<h2 id=\"495b\" data-selectable-paragraph=\"\">\u00bfCu\u00e1ntos tests necesitan realizar los pa\u00edses?<\/h2>\n<p id=\"b781\" data-selectable-paragraph=\"\">Depende de cada pa\u00eds y de lo que est\u00e1 tratando de conseguir. Hay dos tipos de pa\u00edses.<\/p>\n<p id=\"b3e1\" data-selectable-paragraph=\"\">Por un lado, tenemos pa\u00edses como Estados Unidos, Espa\u00f1a, Reino Unido o Francia en los que la epidemia est\u00e1 fuera de control. No estaban preparados para manejar la crisis, por lo que aplicaron el\u00a0<a href=\"https:\/\/medium.com\/tomas-pueyo\/coronavirus-el-martillo-y-la-danza-32abc4dd4ebb\" rel=\"noopener\" target=\"_blank\">Martillo<\/a>, una serie de medidas muy duras para bloquear la econom\u00eda y evitar que las personas se infecten. As\u00ed es como est\u00e1n intentando detener la epidemia. Para ellos, no es necesario diagnosticar a grandes cantidades de personas en este momento, porque est\u00e1n limitando la propagaci\u00f3n con el Martillo. Las \u00fanicas personas que necesitan examinar son aquellas que est\u00e1n enfermas o que pueden caer enfermas (por ejemplo, trabajadores de la salud), para aislarlas y tratarlas. La mayor\u00eda de estos pa\u00edses son los que aqu\u00ed est\u00e1n en rojo o naranja.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_bhaLcEohlSQ2DfO8-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136473\" title=\"0_bhaLcEohlSQ2DfO8 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_bhaLcEohlSQ2DfO8-copia.png\" alt=\"\" width=\"670\" height=\"568\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_bhaLcEohlSQ2DfO8-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_bhaLcEohlSQ2DfO8-copia-300x254.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"e98d\" data-selectable-paragraph=\"\">Pero antes de que los pa\u00edses en naranja o rojo comiencen la Danza, deber\u00e1n estar preparados. Eso significa incrementar enormemente los tests para acercarse al segundo tipo de pa\u00edses, en verde.<\/p>\n<p id=\"823d\" data-selectable-paragraph=\"\">Estos incluyen pa\u00edses como Taiw\u00e1n, Vietnam o Corea del Sur. Tambi\u00e9n usan tests para diagnosticar pacientes, pero tambi\u00e9n tienen otro uso. Rastrean los contactos de los infectados y los someten a tests, incluso si no tienen s\u00edntomas. Tambi\u00e9n eval\u00faan a cualquier otra persona que pueda estar infectada pero que a\u00fan no lo sabe.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_O0WuJQKW6D4O1ciH-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136474\" title=\"0_O0WuJQKW6D4O1ciH copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_O0WuJQKW6D4O1ciH-copia.png\" alt=\"\" width=\"670\" height=\"384\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_O0WuJQKW6D4O1ciH-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_O0WuJQKW6D4O1ciH-copia-300x171.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Para evaluar los grupos adicionales de viajeros o contactos rastreados, es necesario realizar los test a m\u00e1s personas que las que tienen s\u00edntomas. Por eso solo aproximadamente el 1% -3% de sus pruebas detectan a alguien infectado. Todos los pa\u00edses desarrollados que han controlado la epidemia tienen ese nivel de tests positivos.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_O6akz0rCnG4AZxnA-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136475\" title=\"0_O6akz0rCnG4AZxnA copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_O6akz0rCnG4AZxnA-copia.png\" alt=\"\" width=\"670\" height=\"372\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_O6akz0rCnG4AZxnA-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_O6akz0rCnG4AZxnA-copia-300x166.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<div>\n<div>\n<figure><figcaption data-selectable-paragraph=\"\">Los pa\u00edses dentro del c\u00edrculo verde controlaron la epidemia y realizaron muchos test. Los pa\u00edses en el c\u00edrculo ojo fallaron en ambos aspectos. Aqu\u00ed solo hay dos tipos de valores at\u00edpicos. Por un lado, en un c\u00edrculo azul, est\u00e1 Islandia, con muchas pruebas pero tambi\u00e9n muchas infecciones. Es un pa\u00eds muy singular: una isla remota con muchas caracter\u00edsticas espec\u00edficas, incluidas pruebas aleatorias en la poblaci\u00f3n. El otro grupo est\u00e1 en un c\u00edrculo en gris. Estos pa\u00edses no tienen muchas pruebas, pero tambi\u00e9n pocas infecciones per c\u00e1pita. Puede haber muchas razones que lo expliquen, desde tener una gran poblaci\u00f3n hasta beneficiarse de un retraso en la epidemia, aplicar el martillo temprano, estar de camino hacia un brote \u2026<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p data-selectable-paragraph=\"\">Para la mayor\u00eda de los pa\u00edses desarrollados, cuanto menos tests realizaron, mayor es la gravedad de su epidemia. El grupo de pa\u00edses encerrados en rojo ha realizado pocos test y experimentaron brotes devastadores, mientras que los pa\u00edses en la parte inferior izquierda realizaron un n\u00famero excelente de tests y pocos casos. Cuando los pa\u00edses que mejor manejan la crisis est\u00e1n haciendo muchas pruebas, otros pa\u00edses deber\u00edan seguir su ejemplo, que parece estar alrededor de un 3% de positivos con respecto al n\u00famero de tests realizados.<\/p>\n<p id=\"d6bd\" data-selectable-paragraph=\"\">Singapur y Alemania son casos interesantes. Sol\u00edan tener ~ 3% de positivos, pero con el reciente brote, subieron hasta el 8%. Con suerte, esto no se debe a un problema de capacidad de realizar tests y pueden evaluar a todos los que quieran; solo est\u00e1n encontrando muchos m\u00e1s positivos. Pero tambi\u00e9n podr\u00eda mostrar c\u00f3mo un brote puede agotar la capacidad de realizar tests, haciendo que sea m\u00e1s dif\u00edcil identificar todos los casos y aislarlos, y haciendo que sea m\u00e1s dif\u00edcil detenerlo.<\/p>\n<p id=\"5b36\" data-selectable-paragraph=\"\">Los gobiernos quieren saber cu\u00e1ndo han realizado suficientes tests, pero esa pregunta es extremadamente dif\u00edcil de responder porque su n\u00famero de tests y casos cambian constantemente, y de hecho los casos tambi\u00e9n est\u00e1n influenciados por los tests, ya que a m\u00e1s tests encontrar\u00e1n m\u00e1s casos. Entonces, \u00bfc\u00f3mo pueden conocer cu\u00e1ndo est\u00e1n realizando suficientes tests?<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_ft59pDnCyE8oHdQ0-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136476\" title=\"0_ft59pDnCyE8oHdQ0 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_ft59pDnCyE8oHdQ0-copia.png\" alt=\"\" width=\"670\" height=\"434\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_ft59pDnCyE8oHdQ0-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_ft59pDnCyE8oHdQ0-copia-300x194.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<p id=\"3eb4\" data-selectable-paragraph=\"\">En este gr\u00e1fico, los nuevos\u00a0casos\u00a0diarios son la l\u00ednea\u00a0roja\u00a0y las nuevas pruebas diarias son la l\u00ednea\u00a0verde. Hemos utilizados dos escalas (nuevos casos diarios a la izquierda y tests a la derecha) para poder compararlos. Como acabamos de ver m\u00e1s arriba, la experiencia de los pa\u00edses que controlaron la epidemia indica que debemos aspirar a alcanzar un 3% de los positivos de los tests realizados, lo que significa que queremos hacer~ 33 veces m\u00e1s pruebas que casos detectados. Por eso, el eje de tests a la derecha es ~ 33x m\u00e1s grande que el eje de casos a la izquierda. Con eso se puede ver f\u00e1cilmente en qu\u00e9 momento se han hecho suficientes tests.<\/p>\n<p id=\"1989\" data-selectable-paragraph=\"\">En Corea del Sur, cuando el brote realmente creci\u00f3, el n\u00famero de casos era demasiado elevado para el n\u00famero de test, y perdieron la confianza en el n\u00famero oficial de casos (\u00e1rea roja). Sin embargo, en cuesti\u00f3n de semanas, pudieron hacerse suficientes pruebas para volver nuevamente a la zona verde. Ahora, todos los d\u00edas, realizan muchas m\u00e1s pruebas de las que necesitan para superar el umbral del 3%. Est\u00e1 alrededor del 1%.<\/p>\n<p id=\"fdbb\" data-selectable-paragraph=\"\">Comparemos este caso con Italia.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_7duLHU-UdTHP7yt4-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136477\" title=\"0_7duLHU-UdTHP7yt4 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_7duLHU-UdTHP7yt4-copia.png\" alt=\"\" width=\"670\" height=\"429\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_7duLHU-UdTHP7yt4-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_7duLHU-UdTHP7yt4-copia-300x192.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"4f1a\" data-selectable-paragraph=\"\">Como se puede ver, Italia ha aumentando constantemente su n\u00famero de test diarios, pero a\u00fan no son suficientes para saber el alcance de la epidemia. Sin embargo, con este gr\u00e1fico, pueden comenzar a tener una idea de cu\u00e1ndo cruzar\u00e1n ese umbral. Si los casos contin\u00faan disminuyendo mientras las pruebas contin\u00faan aumentando, podr\u00edan cruzarse en unas pocas semanas.<\/p>\n<p id=\"0caf\" data-selectable-paragraph=\"\">Aqu\u00ed hay algunos pa\u00edses m\u00e1s:<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_YxYcF3ZNlW9ipENo-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136478\" title=\"0_YxYcF3ZNlW9ipENo copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_YxYcF3ZNlW9ipENo-copia.png\" alt=\"\" width=\"670\" height=\"383\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_YxYcF3ZNlW9ipENo-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_YxYcF3ZNlW9ipENo-copia-300x171.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<div>\n<div>\n<figure><figcaption data-selectable-paragraph=\"\">Aparecen muy pocos pa\u00edses porque muy pocos pa\u00edses tienen suficientes datos claros sobre la cantidad diaria de personas sometidas a tests diagn\u00f3sticos. Algunos pa\u00edses no tienen n\u00fameros diarios, para otros no est\u00e1 claro cu\u00e1l es la unidad contable de tests. \u00bfSon personas? Kits de tests? \u00bfCu\u00e1ntos kits de tests hay por pa\u00eds? Nuestros n\u00fameros para Taiw\u00e1n son de kits de tests, y no sabemos cu\u00e1ntos kits de test se emplearon por persona. Pero la l\u00ednea roja es lo suficientemente baja en comparaci\u00f3n con la l\u00ednea verde que incluso 2 pruebas por persona a\u00fan mantendr\u00edan la l\u00ednea roja debajo de la l\u00ednea verde. Especialmente si est\u00e1n utilizando estrategias de tests inteligentes que pueden aumentar la eficiencia.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p data-selectable-paragraph=\"\">Estos gr\u00e1ficos muestran claramente lo lejos que la mayor\u00eda de los pa\u00edses est\u00e1n de realizar un n\u00famero suficiente de tests.<\/p>\n<p id=\"1b53\" data-selectable-paragraph=\"\">Con suficientes pruebas, puede comenzar la fase de Danza. Se puede gestionar la epidemia aislando casos y poniendo en cuarentena sus contactos. Al hacer esto, se puede identificar r\u00e1pidamente a aquellos que son contagiosos o propensos a serlo y luego evitar que infecten a otros, y como resultado, se puede proteger a la poblaci\u00f3n sin tener que confinar a todos y limitar su libertad. La gente puede salir y se puede reiniciar la econom\u00eda. Por eso es tan importante hacer m\u00e1s pruebas y aumentar las pruebas hasta que solo el 3% de las personas den positivo.<\/p>\n<p id=\"fa6f\" data-selectable-paragraph=\"\">Si no realizan suficientes tests, no se a\u00edsla a los infectados, no se sabe d\u00f3nde est\u00e1n y los pa\u00edses se ven obligados a aplicar un nuevo confinamiento.<\/p>\n<p id=\"3377\" data-selectable-paragraph=\"\">Mientras el n\u00famero de tests sean limitados, los pa\u00edses tambi\u00e9n deben decidir a qui\u00e9n eval\u00faan primero. \u00bfC\u00f3mo pueden priorizar los pocos tests que tienen?<\/p>\n<h2 id=\"c38d\" data-selectable-paragraph=\"\">Prioridades en los tests<\/h2>\n<p id=\"0e4a\" data-selectable-paragraph=\"\">Como dijimos antes, las primeras personas a las que realizar los tests son aquellas con s\u00edntomas, generalmente en el hospital o en el consultorio del m\u00e9dico, para saber a qui\u00e9n tratar y aislar. Esto es lo que los pa\u00edses hacen durante el Martillo.<\/p>\n<p id=\"28e0\" data-selectable-paragraph=\"\">Para los pa\u00edses que se preparan para bailar (danzar), una vez que hayan realizado tests a los que presentan s\u00edntomas, deben comenzar a evaluar a aquellos que a\u00fan no tienen s\u00edntomas. Eso es lo que permite el rastreo de contactos: descubrir qui\u00e9n podr\u00eda estar enfermo y realizarles pruebas.<\/p>\n<p id=\"306c\" data-selectable-paragraph=\"\">Si has le\u00eddo nuestra publicaci\u00f3n anterior, has visto este gr\u00e1fico:<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kyqGeHhCZdgPP-ln-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136479\" title=\"0_kyqGeHhCZdgPP-ln copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kyqGeHhCZdgPP-ln-copia.png\" alt=\"\" width=\"670\" height=\"393\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kyqGeHhCZdgPP-ln-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kyqGeHhCZdgPP-ln-copia-300x175.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<div>\n<p id=\"6ba9\" data-selectable-paragraph=\"\">Como recordatorio, proviene de un\u00a0<a href=\"https:\/\/science.sciencemag.org\/content\/early\/2020\/04\/09\/science.abb6936\" rel=\"noopener nofollow\" target=\"_blank\">excelente art\u00edculo de la Universidad de Oxford publicado en Science<\/a>. Recoge el fruto de grandes esfuerzos para identificar c\u00f3mo se propaga el coronavirus de persona a persona. El eje horizontal muestra los d\u00edas desde la primera infecci\u00f3n, y el eje vertical muestra cu\u00e1ntas otras personas se infectan de diferentes maneras en un d\u00eda determinado. Por ejemplo, el d\u00eda 5 despu\u00e9s del contagio, los portadores infectan en promedio cerca de 0.4 personas. La mayor parte de eso proviene directamente de personas que ya son sintom\u00e1ticas o que pronto lo ser\u00e1n (por lo que se llaman pre-sintom\u00e1ticas). Una parte es a trav\u00e9s del medio ambiente (probablemente superficies), y otra contribuci\u00f3n menor proviene de personas que tienen el virus pero que nunca desarrollar\u00e1n s\u00edntomas.<\/p>\n<blockquote>\n<p id=\"20af\" data-selectable-paragraph=\"\">Las pruebas y el rastreo de contactos son la inteligencia; aislamiento y cuarentenas son la acci\u00f3n.<\/p>\n<\/blockquote>\n<p data-selectable-paragraph=\"\">Si solo se realizan los tests y se a\u00edsla a las personas con s\u00edntomas, se puede reducir la R (la tasa de transmisi\u00f3n efectiva) como m\u00e1ximo en un 40%. Si la R es 2.5 o 3, como en la epidemia actual, eso conseguir\u00e1 que lleguemos por debajo de 1.<\/p>\n<p id=\"7b3e\" data-selectable-paragraph=\"\">Pero si tambi\u00e9n sigue sus contactos y se les hace la prueba, ahora tambi\u00e9n se puede detectar los presintom\u00e1ticos, reduciendo los contagios hasta en un 85%.<\/p>\n<p id=\"bd07\" data-selectable-paragraph=\"\">En resumen, se necesitan muchos tests tanto para aquellos con s\u00edntomas como para todos sus contactos.<\/p>\n<p id=\"a1c9\" data-selectable-paragraph=\"\">Pero eso solo puede obtener una reducci\u00f3n del 85% en la R si su metodolog\u00eda de realizar tests es perfecta. En la vida real, lleva algo de tiempo. \u00bfCu\u00e1nto importa eso?<\/p>\n<h2 id=\"4d33\" data-selectable-paragraph=\"\">La importancia de la rapidez en las pruebas<\/h2>\n<p id=\"f5a7\" data-selectable-paragraph=\"\">Si la estrategia de tests no es lo suficientemente r\u00e1pida, o si es demasiado dif\u00edcil o costoso hacer los tests, las personas no se har\u00e1n los tests a tiempo o los resultados no ser\u00e1n lo suficientemente r\u00e1pidos. Como resultado, una parte de las infecciones habr\u00e1n sucedido antes de que tengamos tiempo para aislar estos casos.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_d8p5KrN0WB-PyDlv-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136480\" title=\"0_d8p5KrN0WB-PyDlv copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_d8p5KrN0WB-PyDlv-copia.png\" alt=\"\" width=\"670\" height=\"389\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_d8p5KrN0WB-PyDlv-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_d8p5KrN0WB-PyDlv-copia-300x174.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div><\/div>\n<div>El mismo concepto se aplica al seguimiento de contactos. Si se tarda un promedio de tres d\u00edas desde la infecci\u00f3n para detectar los contactos y ponerlos en cuarentena o aislarlos, se perder\u00e1n muchos contagios.<\/div>\n<\/div>\n<div><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_6U2JZdsFWqyvQP9Z-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136481\" title=\"0_6U2JZdsFWqyvQP9Z copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_6U2JZdsFWqyvQP9Z-copia.png\" alt=\"\" width=\"670\" height=\"383\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_6U2JZdsFWqyvQP9Z-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_6U2JZdsFWqyvQP9Z-copia-300x171.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/div>\n<div>\n<p data-selectable-paragraph=\"\">Hay tres factores cr\u00edticos:<\/p>\n<ol>\n<li id=\"b94e\" data-selectable-paragraph=\"\">Cuantos infectados identificamos y aislamos<\/li>\n<li id=\"1dce\" data-selectable-paragraph=\"\">Cuantos contactos identificamos y ponemos en cuarentena<\/li>\n<li id=\"ed9f\" data-selectable-paragraph=\"\">Cuanto tardamos en llevar a cabo ambas acciones<\/li>\n<\/ol>\n<p id=\"1011\" data-selectable-paragraph=\"\">\u00bfC\u00f3mo podemos comparar la importancia de estos tres factores? Imaginemos primero que de forma muy r\u00e1pida realizamos tests y el seguimiento de contactos.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_pnBTnDSAqRrGyIm3-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136482\" title=\"0_pnBTnDSAqRrGyIm3 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_pnBTnDSAqRrGyIm3-copia.png\" alt=\"\" width=\"670\" height=\"425\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_pnBTnDSAqRrGyIm3-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_pnBTnDSAqRrGyIm3-copia-300x190.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<p id=\"78d0\" data-selectable-paragraph=\"\">Este gr\u00e1fico, extra\u00eddo de la\u00a0<a href=\"https:\/\/science.sciencemag.org\/content\/early\/2020\/04\/09\/science.abb6936\" rel=\"noopener nofollow\" target=\"_blank\">publicaci\u00f3n cient\u00edfica de Oxford<\/a>, indica cu\u00e1ntas personas infectadas y sus contactos es necesario identificar, para que se pueda aislarlos o ponerlos en cuarentena y reducir la tasa de transmisi\u00f3n de la epidemia.<\/p>\n<p id=\"e56b\" data-selectable-paragraph=\"\">La epidemia crece en la zona roja \/ naranja y se reduce en la zona verde. El l\u00edmite es la l\u00ednea negra, con las l\u00edneas punteadas como el intervalo de confianza (que representa la incertidumbre). Se supone que cualquier punto en esa l\u00ednea es suficiente para controlar la epidemia. Por ejemplo, si nos fijamos en la posici\u00f3n de la X roja, se podr\u00eda controlar la epidemia si se pudiera aislar instant\u00e1neamente al 60% de los pacientes con s\u00edntomas antes de que infecten a cualquier otra persona, diagnosticar instant\u00e1neamente a m\u00e1s del 50% de sus contactos y aislar \/ ponerlos en cuarentena antes de que infecten a alguien.<\/p>\n<p id=\"a3b2\" data-selectable-paragraph=\"\">Parece realmente dif\u00edcil. La buena noticia es que, si se hace bien, esta medida por s\u00ed sola podr\u00eda detener la epidemia. Pero incluso si no lo haces bien, contribuye a su ralentizaci\u00f3n. Por ejemplo, aislar al 50% de los infectados y al 30% de sus contactos nos acercar\u00e1 al \u00e1rea verde. Eso es bueno. Si se combina esto con otras medidas, como el uso de mascarillas, estaremos m\u00e1s cerca del control de la epidemia, sin la necesidad de usar un martillo.<\/p>\n<p id=\"2fa6\" data-selectable-paragraph=\"\">Otro aspectos que asume este gr\u00e1fico es que no hay demora entre la infecci\u00f3n y las pruebas o el seguimiento e identificaci\u00f3n de contactos. Pero los retrasos son inevitables en el mundo real. \u00bfCu\u00e1nto importan?<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_aPGJNhVzAL9dsmo4-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136483\" title=\"0_aPGJNhVzAL9dsmo4 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_aPGJNhVzAL9dsmo4-copia.png\" alt=\"\" width=\"670\" height=\"319\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_aPGJNhVzAL9dsmo4-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_aPGJNhVzAL9dsmo4-copia-300x142.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"b09e\" data-selectable-paragraph=\"\">El gr\u00e1fico de la derecha es el mismo que se muestra arriba. Los otros tres gr\u00e1ficos muestran lo que sucede si hay un retraso de un d\u00eda, dos d\u00edas o tres d\u00edas al aislar a las personas sintom\u00e1ticas y asintom\u00e1ticas.<\/p>\n<p id=\"a191\" data-selectable-paragraph=\"\">Veamos el gr\u00e1fico completamente a la izquierda. B\u00e1sicamente nos dice: \u201cSi hay un retraso de 3 d\u00edas en aislar y poner en cuarentena a los casos positivos, ser\u00e1 muy dif\u00edcil detener la enfermedad\u201d. Cada peque\u00f1o aspecto contribuye, pero con este tipo de retraso, se ayuda muy poco a parar la propagaci\u00f3n de la enfermedad.<\/p>\n<p id=\"8ddf\" data-selectable-paragraph=\"\">El segundo gr\u00e1fico nos dice: \u201cSi hay un retraso de solo dos d\u00edas en aislar y poner en cuarentena, tiene que poder aislar al menos 70% -90% de los infectados e identificar al menos al 70% -90% de sus contactos para detener la epidemia solo con esta medida \u201c.<\/p>\n<p id=\"47bb\" data-selectable-paragraph=\"\">Dicho de otra manera: puede controlar la epidemia\u00a0<em>sin<\/em>\u00a0parar las econom\u00eda y\u00a0<em>solo con este \u00fanico tipo de medidas<\/em>\u00a0si es r\u00e1pido y efectivo diagnosticando a las personas, aislando a los enfermos, identificando sus contactos y poni\u00e9ndolos en cuarentena. Es necesario hacerlo s\u00faper r\u00e1pido y de forma\u00a0<em>realmente<\/em>\u00a0eficaz, de lo contrario no se podr\u00e1 controlar la epidemia solo con esta medida.<\/p>\n<p id=\"2f16\" data-selectable-paragraph=\"\">Sin ejecutar bien este conjunto de medidas, ser\u00e1 terriblemente dif\u00edcil controlar la epidemia, y los pa\u00edses se ver\u00e1n obligados a encontrar otro conjunto de medidas milagrosas, intentar conseguir la inmunidad de reba\u00f1o (tambi\u00e9n conocida como poblacional o comunitaria) o aplicar de nuevo otro martillo, con todos sus costos econ\u00f3micos o muertes masivas.<\/p>\n<p id=\"a66c\" data-selectable-paragraph=\"\">Por eso es tan importante que los pa\u00edses realicen muchos tests que funcionen lo m\u00e1s r\u00e1pido posible. Se necesitan ambos: la cantidad y la velocidad.<\/p>\n<p id=\"2f6f\" data-selectable-paragraph=\"\">Los tests hechos en el coche y la cabina telef\u00f3nica de Corea del Sur ofrecen un modelo. Cuanto m\u00e1s f\u00e1cil sea para las personas hacerse la prueba, m\u00e1s personas lo har\u00e1n r\u00e1pidamente y mejor controlaremos la epidemia.<\/p>\n<p id=\"9b0d\" data-selectable-paragraph=\"\">Algunos pa\u00edses est\u00e1n considerando realizar tests a todo el mundo multitud de veces. Imagine, por ejemplo, que la mayor\u00eda de la poblaci\u00f3n de los Estados Unidos se somete a tests cada semana, digamos 300 millones de los 330 millones. Eso le dir\u00eda al pa\u00eds qui\u00e9n est\u00e1 cayendo enfermo en cualquier momento y probablemente ayude a controlar su epidemia. Sin embargo, hacer ahora 300 millones de pruebas cada semana es complicado y puede ser un poco caro. En un a\u00f1o, son m\u00e1s de 15 mil millones de pruebas. Si suponemos que el precio baja debido al volumen, digamos 20 $ cada test, eso significa 300 mil millones $, que es bastante dinero, incluso si solo significa el 15% del est\u00edmulo a la econom\u00eda de 2 billones $ lanzado por el Gobierno.<\/p>\n<p id=\"0ffc\" data-selectable-paragraph=\"\">Hoy en d\u00eda, es extremadamente costoso y no es realista. Pero si pudi\u00e9ramos tener formas eficientes de evaluar a m\u00e1s personas, el c\u00e1lculo podr\u00eda cambiar.<\/p>\n<p id=\"3520\" data-selectable-paragraph=\"\">Hay maneras. Por ejemplo,\u00a0<a href=\"https:\/\/www.medrxiv.org\/content\/10.1101\/2020.04.14.20064618v1.full.pdf\" rel=\"noopener nofollow\" target=\"_blank\">este documento<\/a>\u00a0explica c\u00f3mo, si pocas personas est\u00e1n infectadas (es decir, si la prevalencia de la enfermedad es baja), se puede evaluar a un grupo de personas a la vez y reducir ocho veces la cantidad de pruebas necesarias . Reducir el coste de los tests masivos de 300 mil millones $ a menos de 40 mil millones $ ser\u00eda una gran mejora. Muchos pa\u00edses\u00a0<a href=\"https:\/\/www.freethink.com\/articles\/group-coronavirus-testing\" rel=\"noopener nofollow\" target=\"_blank\">ya lo est\u00e1n haciendo<\/a>, como Alemania, Austria, Israel o los Estados Unidos.<\/p>\n<p id=\"7183\" data-selectable-paragraph=\"\">Pero dado el costo y dado que todav\u00eda no estamos listos para evaluar a todos todos los d\u00edas, debemos priorizar a qui\u00e9n evaluar actualmente.<\/p>\n<p id=\"496e\" data-selectable-paragraph=\"\">En resumen:<\/p>\n<ul>\n<li id=\"3c8f\" data-selectable-paragraph=\"\">Se deben realizar muchos tests para identificar lo antes posible a las personas infectadas .<\/li>\n<li id=\"f30e\" data-selectable-paragraph=\"\">Eso significa hacer un n\u00famero de tests suficientes para que solo el 3% de sus personas sean positivas, ya que eso es lo que est\u00e1n viendo los pa\u00edses con \u00e9xito.<\/li>\n<li id=\"7ad6\" data-selectable-paragraph=\"\">Hay que hacer los tests muy r\u00e1pido, para poder aislar a los infectados de inmediato y reducir la cantidad de personas que infectan.<\/li>\n<li id=\"2895\" data-selectable-paragraph=\"\">Esa es la mitad de la batalla. La otra mitad est\u00e1 en realizar tests a todos los contactos para identificar qui\u00e9n m\u00e1s est\u00e1 infectado pero a\u00fan no ha desarrollado s\u00edntomas. El 45% de las infecciones provienen de ellos.<\/li>\n<li id=\"8b10\" data-selectable-paragraph=\"\">Del mismo modo, es necesario realizar esa identificaci\u00f3n de contactos de forma muy r\u00e1pida, para reducir el per\u00edodo de infectividad pre-sintom\u00e1tica.<\/li>\n<li id=\"03e5\" data-selectable-paragraph=\"\">Hay formas de hacer pruebas de manera eficiente, diagnosticando a varias personas con una sola prueba.<\/li>\n<li id=\"05f8\" data-selectable-paragraph=\"\">En un mundo perfecto, podr\u00edamos realizar el test a todos todo el tiempo. Tal vez lleguemos a ese punto, pero mientras tanto, parece costoso y dif\u00edcil.<\/li>\n<li id=\"862f\" data-selectable-paragraph=\"\">Por lo tanto, hay que priorizar a qui\u00e9n se le realice el test. Primero, a las personas con s\u00edntomas. Despu\u00e9s, a todos sus contactos.Eso nos lleva a la localizaci\u00f3n de contactos.<\/li>\n<\/ul>\n<p id=\"654b\" data-selectable-paragraph=\"\"><em>Nota: Cubriremos las pruebas serol\u00f3gicas y otros detalles de las pruebas en otro momento. Esta secci\u00f3n se basa en gran medida en ideas y fuentes de la investigaci\u00f3n de\u00a0<\/em><a href=\"http:\/\/twitter.com\/Genevieve\" rel=\"noopener nofollow\" target=\"_blank\"><em>@Genevieve<\/em><\/a><em>\u00a0Gee sobre Tests. Especialmente, la idea de rastrear la % de positivos es suya.<\/em><\/p>\n<h2 id=\"ef56\" data-selectable-paragraph=\"\">Identificaci\u00f3n de contactos<\/h2>\n<p id=\"7500\" data-selectable-paragraph=\"\">Esta es, con mucho, la secci\u00f3n m\u00e1s jugosa de todo el art\u00edculo. Es a prop\u00f3sito: hay mucho en juego. Como acabamos de ver, no solo las buenas identificaciones y seguimientos de contactos pueden reducir las transmisiones de la enfereemdad; Es vital pasar del Martillo al Baile, para reabrir la econom\u00eda de manera segura. Pero tambi\u00e9n es muy complejo y plantea muchas cuestiones de privacidad.<\/p>\n<p id=\"289d\" data-selectable-paragraph=\"\">Pero antes de sumergirnos en \u00e9l, necesitamos tener una buena idea de lo que significa exactamente rastrear e identificar contactos.<\/p>\n<p id=\"e3b8\" data-selectable-paragraph=\"\">Llamemos a Bob la persona que ha sido infectada. Queremos identificar la mayor cantidad posible de sus contactos, lo m\u00e1s r\u00e1pido posible. Los que importan no son todas las personas con las que estuvo en contacto, sino las que podr\u00edan haber sido infectadas.<\/p>\n<p data-selectable-paragraph=\"\">[youtube]https:\/\/youtu.be\/BE-cA4UK07c[\/youtube]<\/p>\n<p data-selectable-paragraph=\"\">Para hacer eso, se necesita un equipo de rastreadores de contactos.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_8AMJBY616BqCnkYe-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136484\" title=\"0_8AMJBY616BqCnkYe copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_8AMJBY616BqCnkYe-copia.png\" alt=\"\" width=\"670\" height=\"446\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_8AMJBY616BqCnkYe-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_8AMJBY616BqCnkYe-copia-300x199.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<div>\n<div>\n<figure><figcaption data-selectable-paragraph=\"\">El personal sanitario del Departamento de Salud de Anchorage y el Distrito Escolar de Anchorage trabajan en el equipo de monitoreo e investigaciones de contacto COVID-19 el jueves 16 de abril de 2020 en una sala de conferencias en el departamento de salud en el centro de Anchorage. Foto: Loren Holmes \/ ADN, v\u00eda\u00a0<a href=\"https:\/\/www.adn.com\/alaska-news\/2020\/04\/17\/how-epidemiology-detectives-are-tracing-each-alaska-coronavirus-case\/\" rel=\"noopener nofollow\" target=\"_blank\">Anchorage Daily News<\/a><\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p data-selectable-paragraph=\"\">Los rastreadores de contactos tienen varias funciones. Primero, se les da una lista de personas como Bob que han sido infectadas. Entrevistan a Bob para saber d\u00f3nde estuvo en las \u00faltimas semanas y con qui\u00e9n estuvo. Como Bob es humano, con frecuencia puede equivocarse: puede ser olvidadizo, estar enfermo, aterrorizado, triste, ser poco cooperativo o todo lo anterior. Entonces, los rastreadores de contacto tambi\u00e9n podr\u00edan apoyarse en la tecnolog\u00eda para ayudar. Un ejemplo podr\u00eda ser Corea del Sur, donde los rastreadores usan datos m\u00f3viles de GPS, datos de gastos de tarjetas de cr\u00e9dito y secuencias de CCTV. Otro ejemplo podr\u00eda ser el uso de resultados de una aplicaci\u00f3n de seguimiento de contactos (app).<\/p>\n<p id=\"d590\" data-selectable-paragraph=\"\">Con toda esa informaci\u00f3n, elaboraron una lista de los contactos de Bob que podr\u00edan haber sido infectados, ordenados por probabilidad de infecci\u00f3n. Luego, llaman a todos estos contactos. Dependiendo de la probabilidad de infecci\u00f3n y de las reglas del gobierno, podr\u00edan ordenar que se hagan la prueba, se pongan en cuarentena o simplemente verifiquen sus s\u00edntomas. Quieren identificar a tantos contactos como sea posible, lo m\u00e1s r\u00e1pido posible.<\/p>\n<p id=\"e6e7\" data-selectable-paragraph=\"\">\u00bfPero qu\u00e9 es un contacto? \u00bfCu\u00e1ntos contactos necesitamos identificar? \u00bfCon qu\u00e9 rapidez necesitamos identificarlo?<\/p>\n<h2 id=\"faa0\" data-selectable-paragraph=\"\">\u00bfQu\u00e9 identifica a alguien como contacto?<\/h2>\n<p id=\"9ff5\" data-selectable-paragraph=\"\">Dado que se cree que la mayor\u00eda de las personas son infecciosas solo durante aproximadamente dos semanas, solo nos preocupamos por las personas con las que Bob podr\u00eda haber estado en contacto durante las \u00faltimas dos semanas. Antes de eso, era poco probable que Bob se infectara, y si lo fuera, sus contactos ya no ser\u00edan infecciosos.<\/p>\n<p id=\"7f75\" data-selectable-paragraph=\"\">Dentro de estas dos semanas, solo queremos identificar a las personas que probablemente est\u00e9n infectadas. Los\u00a0<a href=\"https:\/\/www.medrxiv.org\/content\/10.1101\/2020.04.11.20056010v1.full.pdf\" rel=\"noopener nofollow\" target=\"_blank\">miembros de la familia<\/a>\u00a0de Bob\u00a0<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC7104686\/\" rel=\"noopener nofollow\" target=\"_blank\">son<\/a>\u00a0<a href=\"https:\/\/academic.oup.com\/cid\/advance-article\/doi\/10.1093\/cid\/ciaa316\/5810900\" rel=\"noopener nofollow\" target=\"_blank\">todos<\/a>\u00a0<a href=\"https:\/\/ccforum.biomedcentral.com\/articles\/10.1186\/s13054-020-2817-7\" rel=\"noopener nofollow\" target=\"_blank\">candidatos muy<\/a>\u00a0<a href=\"https:\/\/www.thelancet.com\/journals\/lancet\/article\/PIIS0140-6736(20)30154-9\/fulltext\" rel=\"noopener nofollow\" target=\"_blank\">probables<\/a>. Por el contrario, no importan tanto las personas con las que se cruz\u00f3 por la calle a 5 m de distancia (~ 15 pies).<\/p>\n<p id=\"ffd1\" data-selectable-paragraph=\"\">Como vimos en\u00a0<a href=\"https:\/\/medium.com\/tomas-pueyo\/coronavirus-los-sencillos-pasos-de-baile-que-todos-pueden-seguir-b389d7cd58c6\" rel=\"noopener\" target=\"_blank\">Los sencillos pases de baile que todos pueden seguir<\/a>, es mucho m\u00e1s probable que ocurran contagios en entornos confinados donde las personas est\u00e1n cerca unas de otras, hablando, tosiendo o cantando durante un largo per\u00edodo de tiempo.<\/p>\n<p id=\"65c3\" data-selectable-paragraph=\"\">Los pa\u00edses est\u00e1n convierten esto en reglas. Por ejemplo, investigan los contactos de Bob si pasan\u00a0<a href=\"https:\/\/www.ecdc.europa.eu\/sites\/default\/files\/documents\/Public-health-management-persons-contact-novel-coronavirus-cases-2020-03-31.pdf\" rel=\"noopener nofollow\" target=\"_blank\">m\u00e1s de 15 minutos juntos en un radio de 2 metros<\/a>. Eso suena razonable. Pero en realidad, los\u00a0<a href=\"https:\/\/www.canada.ca\/en\/public-health\/services\/diseases\/2019-novel-coronavirus-infection\/health-professionals\/interim-guidance-cases-contacts.html\" rel=\"noopener nofollow\" target=\"_blank\">rastreadores<\/a>\u00a0son mucho m\u00e1s sutiles . Una persona que comparti\u00f3 una comida durante una hora sentada cara a cara puede ser identificada como de alto riesgo y pedirle que se ponga en cuarentena, con los controles cada pocas horas, mientras que a una persona que comparti\u00f3 la fila en el supermercado solo se le puede pedir que tenga mucho cuidado y controle sus s\u00edntomas con frecuencia.<\/p>\n<h2 id=\"dc1e\" data-selectable-paragraph=\"\">\u00bfCu\u00e1ntos contactos necesitamos rastrear?<\/h2>\n<p id=\"50fc\" data-selectable-paragraph=\"\">Vimos antes que quer\u00edamos rastrear al menos el 60% de los contactos y ponerlos en cuarentena \/ aislarlos inmediatamente para reducir sustancialmente R (el n\u00famero de reproducci\u00f3n efectivo, cuantas infecciones son causadas por un portador del coronavirus). Pero ese documento asumi\u00f3 un R0 de 2.5 (R0 es el n\u00famero de reproducci\u00f3n en perfectas condiciones: cuando todav\u00eda nadie es inmune y no se han tomado medidas contra \u00e9l). \u00bfQu\u00e9 pasa si es diferente?<\/p>\n<p id=\"b9ec\" data-selectable-paragraph=\"\">Este\u00a0<a href=\"https:\/\/www.thelancet.com\/action\/showPdf?pii=S2214-109X%2820%2930074-7\" rel=\"noopener nofollow\" target=\"_blank\">art\u00edculo<\/a>\u00a0estudia eso precisamente. Analiza diferentes R0 y eval\u00faa qu\u00e9 porcentaje de contactos necesitamos rastrear para que R descienda por debajo de 1. Cada l\u00ednea a continuaci\u00f3n representa un R0 diferente, uno de 1.5 (l\u00ednea roja), otro de 2.5 (l\u00ednea gris) y otro 3.5 (l\u00ednea marr\u00f3n).<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_0nBxd8XI4UUNaZZq-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136485\" title=\"0_0nBxd8XI4UUNaZZq copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_0nBxd8XI4UUNaZZq-copia.png\" alt=\"\" width=\"670\" height=\"364\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_0nBxd8XI4UUNaZZq-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_0nBxd8XI4UUNaZZq-copia-300x162.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"02da\" data-selectable-paragraph=\"\">El eje horizontal indica la cantidad de contactos trazados, y el eje vertical el impacto en la R.<\/p>\n<p id=\"a027\" data-selectable-paragraph=\"\">Tomemos la l\u00ednea marr\u00f3n en la parte superior, con R0 = 3.5. Si no se hace nada, tiene una tasa de transmisi\u00f3n cercana a 3: cada persona infecta a otras 3 (no es 3.5 porque el documento supone un aislamiento de los pacientes infectados). Luego, la R baja a medida que se rastrean y ponen en cuarentena m\u00e1s y m\u00e1s contactos.<\/p>\n<p id=\"e1ef\" data-selectable-paragraph=\"\">Se puede ver que la l\u00ednea marr\u00f3n va por debajo de la l\u00ednea punteada de \u201c1\u201d en alrededor del 90% de los contactos trazados. Eso significa que se debe identificar el 90% de los contactos, y asegurarse, para detener la epidemia, de que no pasen a ser infecciosos. Si se hace bien, esta medida por s\u00ed sola puede detenerlo. Pero afortunadamente, incluso si no se hace a la perfecci\u00f3n, sigue siendo \u00fatil.<\/p>\n<p id=\"595d\" data-selectable-paragraph=\"\">La l\u00ednea marr\u00f3n tiene un \u00e1rea alrededor. Muestra que estos c\u00e1lculos a\u00fan no son perfectos. Nos faltan muchos datos, por lo que debemos hacer algunas conjeturas. Puede ser que el seguimiento del 90% de los contactos solo consiga que la R = 1.5 o 0.5. No estamos seguros Pero definitivamente lo reduce sustancialmente.<\/p>\n<p id=\"19cf\" data-selectable-paragraph=\"\">Si en lugar de R0 = 3.5, observamos R0 = 2.5 (la l\u00ednea gris), nuestra mejor suposici\u00f3n es que identificar el 70% de los casos es suficiente para detener la epidemia.<\/p>\n<p id=\"e658\" data-selectable-paragraph=\"\">Tengamos en cuenta estos n\u00fameros: en funci\u00f3n de todos nuestros datos, queremos identificar y diagnosticar entre el 70% y el 90% de los contactos, lo m\u00e1s r\u00e1pido posible, para tener el mayor impacto posible en la reducci\u00f3n de la epidemia.<\/p>\n<p id=\"e15a\" data-selectable-paragraph=\"\">Seg\u00fan un\u00a0<a href=\"https:\/\/cmmid.github.io\/topics\/covid19\/reports\/bbc_contact_tracing.pdf\" rel=\"noopener nofollow\" target=\"_blank\">art\u00edculo<\/a>, eso se traduce en alrededor de\u00a0<a href=\"https:\/\/twitter.com\/AdamJKucharski\/status\/1254166919248261120\" rel=\"noopener nofollow\" target=\"_blank\">20 a 30 contactos<\/a>\u00a0a identificar por infectado.<\/p>\n<h2 id=\"e30c\" data-selectable-paragraph=\"\">\u00bfCu\u00e1ntos investigadores necesitas?<\/h2>\n<p id=\"1d8f\" data-selectable-paragraph=\"\">As\u00ed es como\u00a0<a href=\"https:\/\/www.centerforhealthsecurity.org\/our-work\/pubs_archive\/pubs-pdfs\/2020\/200410-national-plan-to-contact-tracing.pdf\" rel=\"noopener nofollow\" target=\"_blank\">Johns Hopkins lo est\u00e1 planteando<\/a>:<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Fv4RECzGa0IaQgj1-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136486\" title=\"0_Fv4RECzGa0IaQgj1 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Fv4RECzGa0IaQgj1-copia.png\" alt=\"\" width=\"670\" height=\"366\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Fv4RECzGa0IaQgj1-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Fv4RECzGa0IaQgj1-copia-300x163.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"4882\" data-selectable-paragraph=\"\">Seg\u00fan este plan de Johns Hopkins, EE. UU. Necesitar\u00eda 100.000 rastreadores de contactos. Otros c\u00e1lculos ponen ese n\u00famero en 300,000. Esa es un rango muy amplio. Refleja el amplio rango de este gr\u00e1fico, que muestra una diferencia de 10 veces entre Wuhan y Nueva Zelanda. \u00bfPor qu\u00e9?<\/p>\n<p id=\"ce6a\" data-selectable-paragraph=\"\">Esta brecha en la cantidad de rastreadores de contactos necesarios por persona es dif\u00edcil de comprender. Si un pa\u00eds tiene 1 mill\u00f3n de personas y cero infecciones, y otro pa\u00eds tambi\u00e9n tiene 1 mill\u00f3n de personas pero 10,000 infecciones: \u00bfDeber\u00edan tener el mismo n\u00famero de rastreadores de contacto? No. el tama\u00f1o de la poblaci\u00f3n no es importante.<\/p>\n<p id=\"95cf\" data-selectable-paragraph=\"\">Cuando contratas rastreadores de contactos, est\u00e1s comprando su tiempo. El tiempo necesario depende del n\u00famero de casos y el tiempo que van a emplear por caso.<\/p>\n<p id=\"3f37\" data-selectable-paragraph=\"\">El n\u00famero de casos es diferente por pa\u00eds y depende de c\u00f3mo evolucione la epidemia. El tiempo necesario por caso depende de la capacitaci\u00f3n y la tecnolog\u00eda. Tomemos un par de ejemplos para hacernos una idea de la magnitud de la operaci\u00f3n.<\/p>\n<p id=\"fa32\" data-selectable-paragraph=\"\">En el pico m\u00e1ximo de la epidemia, Hubei ten\u00eda 1.800 equipos de 5 investigadores que realizaban el seguimiento de contactos. Son 9,000 investigadores. El n\u00famero m\u00e1ximo de casos oficiales fue de alrededor de 4.000 casos. Supongamos que los 9,000 investigadores fueron contratados en promedio unos d\u00edas despu\u00e9s de que Hubei fue encerrado, y pudieron superar la acumulaci\u00f3n de casos alrededor de un mes despu\u00e9s, cuando la crisis se calm\u00f3.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_EqxotjgMksY2GW2H-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136487\" title=\"0_EqxotjgMksY2GW2H copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_EqxotjgMksY2GW2H-copia.png\" alt=\"\" width=\"670\" height=\"417\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_EqxotjgMksY2GW2H-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_EqxotjgMksY2GW2H-copia-300x186.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"3d35\" data-selectable-paragraph=\"\">Entre estas dos fechas, 9,000 rastreadores trabajando durante 27 d\u00edas (suponiendo que no haya fines de semana) habr\u00edan podido procesar alrededor de 63,000 casos, lo que significa alrededor de 4 personas por d\u00eda (una persona.d\u00eda es una persona que trabaja por un d\u00eda. Por tanto 4. persona.d\u00eda pueden ser 4 personas trabajando en algo durante un d\u00eda, o una persona trabajando en eso durante 4 d\u00edas, por ejemplo). Si suponemos que fueron contratados unos d\u00edas antes y aclararon los casos m\u00e1s tarde, podr\u00edan llegar a ser 5 o 6 personas.d\u00eda por caso, no mucho m\u00e1s.<\/p>\n<p id=\"c22e\" data-selectable-paragraph=\"\">Compare esto con lo que dice un<a href=\"https:\/\/twitter.com\/propublica\/status\/1253352107056529409?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed&amp;ref_url=https%3A%2F%2Fcdn.embedly.com%2Fwidgets%2Fmedia.html%3Ftype%3Dtext%252Fhtml%26key%3Da19fcc184b9711e1b4764040d3dc5c07%26schema%3Dtwitter%26url%3Dhttps%253A%2F%2Ftwitter.com%2Fpropublica%2Fstatus%2F1253352107056529409%26image%3Dhttps%253A%2F%2Fi.embed.ly%2F1%2Fimage%253Furl%253Dhttps%25253A%25252F%25252Fpbs.twimg.com%25252Fprofile_images%25252F902174720040292354%25252FrLSBbM4r_400x400.jpg%2526key%253Da19fcc184b9711e1b4764040d3dc5c07\" target=\"_blank\"> ex jefe de los Centros de Servicios de Medicare y Medicaid<\/a>:<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-01-a-las-10.09.21-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136488\" title=\"Captura de pantalla 2020-06-01 a las 10.09.21 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-01-a-las-10.09.21-copia.png\" alt=\"\" width=\"506\" height=\"441\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-01-a-las-10.09.21-copia.png 506w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-01-a-las-10.09.21-copia-300x261.png 300w\" sizes=\"(max-width: 506px) 100vw, 506px\" \/><\/a><\/p>\n<div>\n<p id=\"7231\" data-selectable-paragraph=\"\">Seg\u00fan esto, resolver un caso requiere 12 a 15 personas por d\u00eda.<\/p>\n<p id=\"3522\" data-selectable-paragraph=\"\">Supongamos que un pa\u00eds tiene 10,000 nuevos casos por d\u00eda, y est\u00e1 seguro de que este es el caso porque sus pruebas est\u00e1n dando alrededor del 3% de los positivos (como vimos en la secci\u00f3n de tests, este es un buen n\u00famero para tener una buena idea de lo que est\u00e1 sucediendo realmente).<\/p>\n<p id=\"9ee9\" data-selectable-paragraph=\"\">Supongamos que no tienen tecnolog\u00eda de rastreo de contactos, por lo que los investigadores deben llamar a las personas infectadas, entrevistarlas y luego llamar a todos sus contactos y entrevistarlos uno por uno. Cada una de estas conversaciones es muy larga, porque las personas no recuerdan con qui\u00e9n almorzaron hace dos d\u00edas, ni te cuento sobre lo que hizo hace dos semanas. Luego necesitan presentar informes, analizar los datos, hacer referencias cruzadas entre los casos \u2026<\/p>\n<p id=\"c21a\" data-selectable-paragraph=\"\">Si les lleva 15 personas por d\u00eda por caso, necesitaremos 15 * 10,000 = 150,000 personas por d\u00eda de trabajo todos los d\u00edas, por lo que debemos contratar a 150,000 personas. Si necesitas cubrir los fines de semana, d\u00edas festivos, d\u00edas de enfermedad, etc., ese n\u00famero puede alcanzar aproximadamente los 200,000. Suponiendo 20 $ por hora con todos los costes incluidos, eso es 7 mil millones $ por a\u00f1o. Eso es razonablemente caro, pero una peque\u00f1a gota en el mar en comparaci\u00f3n con el coste del cierre de la econom\u00eda actual.<\/p>\n<p id=\"ad6e\" data-selectable-paragraph=\"\">Imagine, en cambio, que tenemos solo 1,000 casos nuevos por d\u00eda en lugar de 10,000. Nuestra necesidad se reduce a 20,000 trabajadores por d\u00eda.<\/p>\n<p data-selectable-paragraph=\"\">Desafortunadamente, ambos escenarios necesitan tres d\u00edas, ya que ambos requieren que cinco personas trabajen en un caso durante tres d\u00edas. Sin embargo, como vimos, el tiempo es cr\u00edtico.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_2nNJrK0EAf3zPKsB-copia.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136489\" title=\"0_2nNJrK0EAf3zPKsB copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_2nNJrK0EAf3zPKsB-copia.jpg\" alt=\"\" width=\"670\" height=\"446\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_2nNJrK0EAf3zPKsB-copia.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_2nNJrK0EAf3zPKsB-copia-300x199.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<div>\n<div>\n<div>\n<figure><figcaption data-selectable-paragraph=\"\">La enfermera del distrito escolar de Anchorage, Bethany Zimpelman, trabaja en el equipo de monitoreo e investigaciones de contacto COVID-19 el jueves 16 de abril de 2020. El equipo est\u00e1 compuesto por enfermeras del municipio y del distrito escolar de Anchorage. (Loren Holmes \/ ADN)\u00a0<a href=\"https:\/\/www.adn.com\/alaska-news\/2020\/04\/17\/how-epidemiology-detectives-are-tracing-each-alaska-coronavirus-case\/\" rel=\"noopener nofollow\" target=\"_blank\">Anchorage Daily News<\/a><\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p id=\"64c7\" data-selectable-paragraph=\"\">Imagin\u00e9mos ahora que todav\u00eda tenemos 1,000 casos nuevos por d\u00eda, pero nuestros rastreadores de contactos son tan productivos como los de Wuhan, donde un equipo de 5 puede resolver un caso completo por d\u00eda. Con 5,000 rastreadores de contacto (~ 7,000 incluyendo d\u00edas festivos, etc.), se puede cubrir todos los casos en un d\u00eda en lugar de en 3.<\/p>\n<p id=\"21ac\" data-selectable-paragraph=\"\">Estos n\u00fameros son solo aproximaciones. El objetivo es resaltar c\u00f3mo pensar en esto, alentar a los pa\u00edses a cuantificar y minimizar ese coste, y planificar con amplitud de miras. Estos n\u00fameros nos ayudan a darnos cuenta de muchas cosas:<\/p>\n<ul>\n<li id=\"11c6\" data-selectable-paragraph=\"\">Es muy dif\u00edcil confiar en el rastreo de contactos mientras se desata una epidemia. Con los ~ 30,000 casos nuevos por d\u00eda que tiene EE. UU. A fines de abril, si necesitan 15 personas por d\u00eda, deben contratar a m\u00e1s de 500,000 personas para hacerlo bien. Es muy dif\u00edcil hacerlo de manera r\u00e1pida y efectiva. Uno de los valores del Martillo es reducir ese n\u00famero, de modo que sea manejable para los rastreadores de contacto.<\/li>\n<li id=\"918e\" data-selectable-paragraph=\"\">Tambi\u00e9n ilustra que, si un pa\u00eds tiene otro brote, como en Singapur o Corea del Sur, los martillos locales podr\u00edan ser necesarios, ya que esos brotes agotan la capacidad de trabajo de los rastreadores de contacto.<\/li>\n<li id=\"a041\" data-selectable-paragraph=\"\">Si un equipo de 5 rastreadores necesita 3 d\u00edas para procesar completamente un caso, eso es extremadamente lento. Muchos de los contagios ya habr\u00e1n sucedido.<\/li>\n<li id=\"ae88\" data-selectable-paragraph=\"\">Tambi\u00e9n es probable que estas personas, manualmente, no puedan identificar todos los contactos que necesitan identficar. El proceso manual del equipo de rastreo de contactos de Anchorage de la imagen podr\u00eda ser un pionero en los EE. UU. Tal vez sea suficiente para Alaska, pero no se adapta a la mayor\u00eda de los estados o pa\u00edses. Tiene que ser mucho m\u00e1s efectivo.<\/li>\n<\/ul>\n<div><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_qj7KWFacNA8aIjK9-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136490\" title=\"0_qj7KWFacNA8aIjK9 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_qj7KWFacNA8aIjK9-copia.png\" alt=\"\" width=\"670\" height=\"379\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_qj7KWFacNA8aIjK9-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_qj7KWFacNA8aIjK9-copia-300x169.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/div>\n<div>\n<p id=\"c3bf\" data-selectable-paragraph=\"\">Imaginemos que Bob (punto rojo, infectado) es bastante sociable y tuvo interacciones significativas con 55 contactos en las \u00faltimas dos semanas. En una conversaci\u00f3n con un rastreador de contactos, podr\u00eda ser f\u00e1cil para \u00e9l contarle sobre sus cuatro miembros de la familia. Despu\u00e9s de revisar su calendario, podr\u00eda contarle acerca de ocho compa\u00f1eros de trabajo con quienes ha tenido reuniones. Recuerda que cen\u00f3 con cuatro amigos m\u00e1s y un viaje que hizo a la tienda de comestibles.<\/p>\n<p id=\"8acc\" data-selectable-paragraph=\"\">Despu\u00e9s de mirar los CCTV, los rastreadores pueden ver los movimientos de Bob en la tienda de comestibles e identificar dos contactos m\u00e1s para rastrear, llegando aun total de 18 contactos. Como los rastreadores no tienen los n\u00fameros de tel\u00e9fono de los contactos de trabajo o la identidad de las personas en la tienda de comestibles, ahora necesitan hablar con el empleador y la tienda para obtener estos contactos. Eso supone que Bob est\u00e1 cooperando.<\/p>\n<p id=\"89a3\" data-selectable-paragraph=\"\">18 casos es menos de la mitad, y desafortunadamente necesitaron 3 d\u00edas para investigarlos. Recuerde, idealmente necesitamos del 70% al 90% en un d\u00eda. Pero con este proceso, confiamos en la cooperaci\u00f3n y la memoria de Bob, as\u00ed como en en vencer todas las dificultades para obtener todos los datos. Eso no es suficiente.<\/p>\n<p id=\"e745\" data-selectable-paragraph=\"\">Un pa\u00eds que lo ha hecho realmente bien es Corea del Sur. \u00bfC\u00f3mo lo hicieron?<\/p>\n<h2 id=\"896a\" data-selectable-paragraph=\"\">Tecnolog\u00eda para rastreadores de contacto: datos personales de los infectados<\/h2>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_JNyDU7V1jXcxSlXG-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136491\" title=\"0_JNyDU7V1jXcxSlXG copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_JNyDU7V1jXcxSlXG-copia.png\" alt=\"\" width=\"670\" height=\"358\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_JNyDU7V1jXcxSlXG-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_JNyDU7V1jXcxSlXG-copia-300x160.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"a474\" data-selectable-paragraph=\"\">Los rastreadores de contactos de Corea del Sur tienen acceso a los datos de gasto de GPS y tarjetas de cr\u00e9dito de las personas infectadas como Bob. Gracias a ellos, es bastante f\u00e1cil averiguar d\u00f3nde ha estado Bob durante las \u00faltimas 2 semanas (cuadrados verdes en la tabla).<\/p>\n<p id=\"ef51\" data-selectable-paragraph=\"\">Habiendo refrescado la memoria de Bob , es mucho m\u00e1s f\u00e1cil identificar a todas las personas con las que podr\u00eda haber entrado en contacto. Y eso se puede complementar ahora con las im\u00e1genes de CCTV y otras cosas, como el acceso a los sistemas de etiquetado de autobuses o gimnasios. Como resultado, en este escenario hipot\u00e9tico, pasamos de 18 a 41 contactos rastreados. No hemos llegado a los 55, pero estamos mucho m\u00e1s cerca de eso. Ya es el 75%, lo que nos pondr\u00eda en el rango de lo que tiene un impacto dram\u00e1tico en la tasa de transmisi\u00f3n.<\/p>\n<p id=\"8978\" data-selectable-paragraph=\"\">Estos n\u00fameros son aproximaciones, pero reflejan la realidad de Corea del Sur. As\u00ed es como lo est\u00e1n haciendo, y han evitado todos los nuevos brotes. Esto indica que hacerlo bien podr\u00eda ser suficiente para controlar la epidemia, sin otras medidas.<\/p>\n<p id=\"258f\" data-selectable-paragraph=\"\">Hay otro gran beneficio para esto que a\u00fan no hemos discutido.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_EadrgFj9zxKiLNwy-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136492\" title=\"0_EadrgFj9zxKiLNwy copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_EadrgFj9zxKiLNwy-copia.png\" alt=\"\" width=\"670\" height=\"362\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_EadrgFj9zxKiLNwy-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_EadrgFj9zxKiLNwy-copia-300x162.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<p id=\"35f6\" data-selectable-paragraph=\"\">En nuestro art\u00edculo\u00a0<a href=\"https:\/\/medium.com\/tomas-pueyo\/coronavirus-aprendiendo-a-danzar-4925ee8d8048\" rel=\"noopener\" target=\"_blank\">Coronavirus: Aprendiendo a Danzar<\/a>, explicamos c\u00f3mo Corea del Sur public\u00f3 donde hab\u00edan estado los pacientes infectados y en qu\u00e9 momento. Las personas pueden comprobar r\u00e1pidamente si en un lugar donde estuvieron hab\u00eda una infecci\u00f3n, saber si podr\u00edan haberse infectado ellos mismos y hacerse la prueba.<\/p>\n<p id=\"e3e2\" data-selectable-paragraph=\"\">Adem\u00e1s, las personas pueden descargar esta informaci\u00f3n en su tel\u00e9fono y usar aplicaciones (apps) que coinciden autom\u00e1ticamente con los datos oficiales sobre lugares infecciosos con sus propios datos de movilidad. De esa manera, si tiene una de estas aplicaciones, puede saber de inmediato si\u00a0<em>estuviste<\/em>\u00a0con alguien infectado.<\/p>\n<p id=\"db1a\" data-selectable-paragraph=\"\">Debido a que existe un beneficio inmediato para usted (\u201c\u00a1Oh, hay una aplicaci\u00f3n en la que puedo ver si he estado infectado en alg\u00fan lugar? \u00a1Quiero saber!\u201d), Es probable que las personas descarguen dicha aplicaci\u00f3n y la usen.<\/p>\n<p id=\"ca1e\" data-selectable-paragraph=\"\">Para que todo lo anterior sea posible, las autoridades deben tener acceso a los gastos de la tarjeta de cr\u00e9dito y los datos de movilidad telef\u00f3nica para las personas infectadas como Bob.<\/p>\n<p id=\"0d1d\" data-selectable-paragraph=\"\">Eso significa que es hora de hablar sobre privacidad.<\/p>\n<h1 id=\"7ada\" data-selectable-paragraph=\"\">La privacidad del rastreo de contactos<\/h1>\n<p id=\"9c9a\" data-selectable-paragraph=\"\"><em>Nota: Hemos hablado con varios expertos en epidemiolog\u00eda y privacidad para crear esta secci\u00f3n, pero nuestras conclusiones no son definitivas. Presentamos los pensamientos a continuaci\u00f3n para promover el debate sobre el seguimiento de contactos y la privacidad, e invitamos a otros expertos a debatir estas ideas con nosotros.<\/em><\/p>\n<p id=\"9e40\" data-selectable-paragraph=\"\">Algunas personas podr\u00edan leer esto y tener una reacci\u00f3n inmediata de que no es aceptable porque viola los derechos de privacidad de las personas, empujando al gobierno hacia una pendiente resbaladiza de recogida de datos y violaciones de privacidad como la que Estados Unidos todav\u00eda sufre a ra\u00edz de la Patriot Act de 2001.<\/p>\n<p id=\"39b1\" data-selectable-paragraph=\"\">Ese es un debate que abordaremos m\u00e1s adelante, pero es completamente irrelevante en este punto: los cr\u00edticos no se dan cuenta de que en muchos pa\u00edses, las leyes realmente no necesitan cambiar para lograr lo que est\u00e1 arriba, debido a algo que se llama una\u00a0<a href=\"https:\/\/es.wikipedia.org\/wiki\/Enfermedades_de_Declaraci%C3%B3n_Obligatoria\" rel=\"noopener nofollow\" target=\"_blank\">enfermedad de declaraci\u00f3n obligatoria<\/a>.<\/p>\n<h2 id=\"6396\" data-selectable-paragraph=\"\">La privacidad de una enfermedad de declaraci\u00f3n obligatoria.<\/h2>\n<p id=\"35e9\" data-selectable-paragraph=\"\">Bob est\u00e1 infectado. Por eso, es un peligro para la salud de la comunidad. Eso significa que tiene diferentes derechos de privacidad, y los ha tenido durante siglos en muchos pa\u00edses, como el\u00a0<a href=\"https:\/\/www.bmj.com\/content\/340\/bmj.c1131\" rel=\"noopener nofollow\" target=\"_blank\">Reino Unido<\/a>\u00a0o\u00a0<a href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?cidTexte=LEGITEXT000006072665&amp;idArticle=LEGIARTI000006911766&amp;dateTexte=&amp;categorieLien=cid\" rel=\"noopener nofollow\" target=\"_blank\">Francia<\/a>. Muchos pa\u00edses m\u00e1s, como\u00a0<a href=\"https:\/\/www.legislation.gov.au\/Details\/C2016C00847\" rel=\"noopener nofollow\" target=\"_blank\">Australia<\/a>, tienen reglas similares. En los Estados Unidos, son de nivel estatal.<\/p>\n<p id=\"86a6\" data-selectable-paragraph=\"\">Esto es algo que tiene sentido. Hemos olvidado lo devastadoras que pueden ser las enfermedades infecciosas.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_F-Hdtrt6k7GF1tjn-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136493\" title=\"0_F-Hdtrt6k7GF1tjn copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_F-Hdtrt6k7GF1tjn-copia.png\" alt=\"\" width=\"670\" height=\"480\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_F-Hdtrt6k7GF1tjn-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_F-Hdtrt6k7GF1tjn-copia-300x214.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<p id=\"1f25\" data-selectable-paragraph=\"\">En este gr\u00e1fico, podemos ver c\u00f3mo las tasas de mortalidad cambiaron masivamente de un a\u00f1o a otro debido a las epidemias en los Estados Unidos. Pero a medida que se implementaron medidas, como agua limpia o cloraci\u00f3n del agua, todos los picos desaparecieron.<\/p>\n<p id=\"33e4\" data-selectable-paragraph=\"\">Esa es la imagen de una epidemia desenfrenada. En ese momento, era de conocimiento com\u00fan que los enfermos no ten\u00edan los mismos derechos que los sanos, porque constitu\u00edan una amenaza existencial para la sociedad. Identificarlos y aislarlos fue crucial, por lo que las autoridades ten\u00edan derecho a hacerlo.<\/p>\n<p id=\"a09c\" data-selectable-paragraph=\"\">Esto sigue siendo cierto hoy para largas listas de enfermedades. Pero el concepto es el mismo: si usted es una amenaza para la sociedad, las autoridades deber\u00edan estar equipadas para eliminar ese riesgo.<\/p>\n<p id=\"7910\" data-selectable-paragraph=\"\">Si el coronavirus se etiquetara como una enfermedad de declaraci\u00f3n obligatoria, los m\u00e9dicos tendr\u00edan que informar de inmediato los positivos a las autoridades. Estos deber\u00edan estar equipados para usar los recursos, datos y herramientas que ya tienen para rastrear los contactos de Bob.<\/p>\n<p id=\"5cfc\" data-selectable-paragraph=\"\">Estos tres pasos (tener una enfermedad en la lista de enfermedades de notificaci\u00f3n obligatoria, un proceso para notificar la enfermedad a las autoridades y los derechos de privacidad renunciados en estos casos) generalmente corresponden a tres leyes diferentes en cada pa\u00eds, por lo que todas tienen diferentes asume qu\u00e9 hacer.<\/p>\n<p id=\"9905\" data-selectable-paragraph=\"\">Pero para los pa\u00edses que env\u00edan el archivo de Bob a las autoridades, esto no es diferente de que la polic\u00eda tenga acceso a los datos del tel\u00e9fono m\u00f3vil o de la tarjeta de cr\u00e9dito de un mal actor, para identificarlo y localizarlo. Ya pueden hacerlo, y deber\u00edan poder hacerlo aqu\u00ed sin otorgar poderes especiales que nos conduzcan por una pendiente resbaladiza.<\/p>\n<p id=\"2306\" data-selectable-paragraph=\"\">Ya sea que haya una soluci\u00f3n tecnol\u00f3gica para tener acceso f\u00e1cil a los datos del GPS y de la tarjeta de cr\u00e9dito o no, no importa: los rastreadores de contactos ya deber\u00edan tener acceso a este tipo de informaci\u00f3n. Hacerlo artificialmente dif\u00edcil para ellos es una tonter\u00eda.<\/p>\n<p id=\"6e10\" data-selectable-paragraph=\"\">Hasta donde podemos ver, este es el nivel de privacidad que tiene Corea del Sur, por lo que podr\u00eda ser suficiente para resolver el problema.\u00a0<a href=\"http:\/\/www.law.go.kr\/LSW\/lsInfoP.do?lsiSeq=188080&amp;chrClsCd=010203&amp;urlMode=engLsInfoR&amp;viewCls=engLsInfoR#0000\" rel=\"noopener nofollow\" target=\"_blank\">Aprobaron una legislaci\u00f3n especial<\/a>\u00a0con este fin despu\u00e9s del brote de MERS en 2015, para que otros pa\u00edses puedan hacer lo mismo.<\/p>\n<p id=\"5a72\" data-selectable-paragraph=\"\">Dig\u00e1moslo de nuevo: esta es una herramienta de valor incalculable para detener adecuadamente los brotes masivos que hemos tenido en todo el mundo, y no requiere un debate sobre la privacidad furibundo. Deber\u00edamos centrar nuestra atenci\u00f3n en hacer esto.<\/p>\n<p id=\"ed00\" data-selectable-paragraph=\"\">Pero podemos hacer m\u00e1s. El verdadero debate sobre la privacidad deber\u00eda ser sobre eso: \u00bflas autoridades tambi\u00e9n deber\u00edan tener acceso a los datos de personas que\u00a0<em>a\u00fan no est\u00e1n infectadas oficialmente<\/em>?<\/p>\n<h2 id=\"c118\" data-selectable-paragraph=\"\">La privacidad de los contactos rastreados<\/h2>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_sFfBEpSIgUjf_9b2-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136494\" title=\"0_sFfBEpSIgUjf_9b2 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_sFfBEpSIgUjf_9b2-copia.png\" alt=\"\" width=\"670\" height=\"358\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_sFfBEpSIgUjf_9b2-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_sFfBEpSIgUjf_9b2-copia-300x160.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"7f6b\" data-selectable-paragraph=\"\">Ahora imagine que, adem\u00e1s de la tarjeta de cr\u00e9dito y los datos de movilidad de Bob, nuestro rastreador de contactos recibi\u00f3 una lista de contactos potenciales de operadores m\u00f3viles.<\/p>\n<p id=\"ad03\" data-selectable-paragraph=\"\">Los operadores m\u00f3viles conocen su posici\u00f3n en cualquier momento. Podr\u00edan grabar esto, junto con otras personas cercanas a usted, y cada vez que dos personas est\u00e9n cerca la una de la otra durante un per\u00edodo de tiempo, como 2 m (6 pies) durante m\u00e1s de 10 minutos, registran un contacto. Los pa\u00edses que solo tienen un operador m\u00f3vil principal pueden hacerlo f\u00e1cilmente, pero los pa\u00edses con m\u00e1s operadores tambi\u00e9n podr\u00edan crear una base de datos de este tipo, de manera que cada empresa no pueda ver los datos de los clientes de otras compa\u00f1\u00edas.<\/p>\n<p id=\"1d14\" data-selectable-paragraph=\"\">El gobierno puede enviar una solicitud para obtener todos los contactos de Bob y d\u00f3nde y cu\u00e1ndo ocurri\u00f3 el contacto, sin conocer m\u00e1s detalles sobre el resto de la poblaci\u00f3n.<\/p>\n<p id=\"8e28\" data-selectable-paragraph=\"\">Habr\u00eda muchos falsos positivos: por ejemplo, el GPS no puede determinar la altura, por lo que en un complejo de apartamentos, parecer\u00eda que todas las personas que viven en los apartamentos que pertenecen a la misma vertical son sus contactos. Pero un rastreador de contactos puede excluir la mayor\u00eda de estos al eliminar todas las coincidencias que ocurren constantemente en casa y no viven con usted.<\/p>\n<p id=\"8cb6\" data-selectable-paragraph=\"\">Los datos proporcionados al gobierno en esta situaci\u00f3n son exactamente los datos que queremos que tenga el gobierno: solo los datos de movilidad personal de los infectados de un lado y las coincidencias con los contactos del otro lado. Nadie tiene muchos datos sobre los movimientos de las personas que no ten\u00edan previamente, excepto lo que es cr\u00edtico tener para esta situaci\u00f3n espec\u00edfica.<\/p>\n<p id=\"06ac\" data-selectable-paragraph=\"\">Los operadores m\u00f3viles tampoco tienen acceso a m\u00e1s datos de los que suelen obtener. Esto preserva la privacidad al tiempo que mejora el seguimiento de contactos.<\/p>\n<p id=\"b5bb\" data-selectable-paragraph=\"\">La desventaja de esto es que el GPS no es lo suficientemente preciso, y es posible que se pierdan algunos contactos y se agreguen otros contactos que no deber\u00edan haber sido. En realidad, el GPS se puede hacer m\u00e1s preciso si el ej\u00e9rcito de EE. UU. decide hacerlo, pero es posible que no quiera, o con herramientas de IA. Pero puede ser que la precisi\u00f3n sea tan mala que esta soluci\u00f3n sea completamente in\u00fatil. Tal vez solo funciona en \u00e1reas de baja densidad. Todav\u00eda no he visto un an\u00e1lisis que estudie esto en profundidad. Los espero con ansia.<\/p>\n<p id=\"f0a9\" data-selectable-paragraph=\"\">Esta limitaci\u00f3n es la raz\u00f3n por la que tantos pa\u00edses se han unido a la moda de las aplicaciones bluetooth.<\/p>\n<h1 id=\"baeb\" data-selectable-paragraph=\"\">Qu\u00e9 se necesitar\u00eda para que las aplicaciones Bluetooth sean \u00fatiles para el rastreo de contactos<\/h1>\n<p id=\"45f2\" data-selectable-paragraph=\"\">Supongamos ahora que nuestros rastreadores de contactos tienen acceso a los datos de Bob y, adem\u00e1s, pueden confiar en los datos de contacto de las aplicaciones bluetooth disponibles en el mercado.<\/p>\n<p id=\"cabd\" data-selectable-paragraph=\"\">Si no est\u00e1 familiarizado con estas aplicaciones bluetooth, la forma en que la mayor\u00eda de ellas se concibe es que las personas las descargan y las configuran para que, cuando est\u00e9n abiertas, registren c\u00f3digos an\u00f3nimos de todas las personas con las que se acercan, como siempre y cuando estas personas tambi\u00e9n tengan habilitada una aplicaci\u00f3n similar. Esto es lo que\u00a0<a href=\"https:\/\/blog.google\/inside-google\/company-announcements\/apple-and-google-partner-covid-19-contact-tracing-technology\" rel=\"noopener nofollow\" target=\"_blank\">Apple y Google acordaron habilitar<\/a>.<\/p>\n<p id=\"9e3f\" data-selectable-paragraph=\"\">Si Bob tiene una de estas aplicaciones, puede notificar que ha sido infectado por el coronavirus y que desea enviar esta informaci\u00f3n a las autoridades.<\/p>\n<p id=\"4d6f\" data-selectable-paragraph=\"\">Entonces, \u00bfcu\u00e1ntas personas desear\u00edan usar una aplicaci\u00f3n de este tipo?<\/p>\n<p id=\"03d5\" data-selectable-paragraph=\"\">Si lee\u00a0<a href=\"https:\/\/medium.com\/tomas-pueyo\/coronavirus-aprendiendo-a-danzar-4925ee8d8048\" rel=\"noopener\" target=\"_blank\">nuestra primera entrega<\/a>, comprobar\u00e1 que la aplicaci\u00f3n bluetooth oficial de Singapur, TraceTogether, tiene solo un 20% de usuarios. Islandia, otro pa\u00eds que deber\u00eda ser capaz de lograr altos niveles de adopci\u00f3n, afirma que solo tiene un\u00a0<a href=\"https:\/\/www.economist.com\/science-and-technology\/2020\/04\/16\/app-based-contact-tracing-may-help-countries-get-out-of-lockdown\" rel=\"noopener nofollow\" target=\"_blank\">40% de usuarios<\/a>. India lanz\u00f3 una aplicaci\u00f3n descargada por\u00a0<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2020-04-16\/india-virus-track-app-gets-50-million-users-amid-privacy-concern\" rel=\"noopener nofollow\" target=\"_blank\">50 millones de personas<\/a>, que parece un \u00e9xito hasta que te das cuenta de que es menos del\u00a0<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2020-04-16\/india-virus-track-app-gets-50-million-users-amid-privacy-concern\" rel=\"noopener nofollow\" target=\"_blank\">4% de la poblaci\u00f3n<\/a>.<\/p>\n<p id=\"5b60\" data-selectable-paragraph=\"\">Seamos tremendamente optimistas y supongamos que la mayor\u00eda de los pa\u00edses pueden hacerlo un 50% mejor que Singapur, lo que es poco probable, ya que es muy rico, todos tienen un tel\u00e9fono inteligente, la educaci\u00f3n es muy alta y la gente conf\u00eda en el gobierno, y se descarga el 30% de la poblaci\u00f3n la aplicaci\u00f3n.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_hHn8xqMrI4dFZRo0-copia1.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136496\" title=\"0_hHn8xqMrI4dFZRo0 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_hHn8xqMrI4dFZRo0-copia1.png\" alt=\"\" width=\"670\" height=\"360\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_hHn8xqMrI4dFZRo0-copia1.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_hHn8xqMrI4dFZRo0-copia1-300x161.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"e15e\" data-selectable-paragraph=\"\">Aqu\u00ed, los puntos que tienen un c\u00edrculo turquesa alrededor son contactos que han descargado una de estas aplicaciones bluetooth. Desafortunadamente, Bob no lo hizo, por lo que todo esto no tiene valor en esta situaci\u00f3n. Este es el caso el 70% del tiempo si la penetraci\u00f3n de estas aplicaciones es del 30%.<\/p>\n<p id=\"3e60\" data-selectable-paragraph=\"\">Ok, ahora supongamos que Bob, de hecho, tiene la aplicaci\u00f3n instalada. No solo eso, sino que Bob es muy diligente y lo tiene todo configurado y el Bluetooth activado todo el tiempo.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Sp33TBAWCG7RzGzw-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136497\" title=\"0_Sp33TBAWCG7RzGzw copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Sp33TBAWCG7RzGzw-copia.png\" alt=\"\" width=\"670\" height=\"379\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Sp33TBAWCG7RzGzw-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Sp33TBAWCG7RzGzw-copia-300x169.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<p id=\"9112\" data-selectable-paragraph=\"\">En este caso, el rastreador de contactos puede agregar 8 de los contactos de Bob, alrededor del 15% de los contactos que necesitamos. \u00bfPor qu\u00e9 tan poco? Porque, para empezar, solo el 30% de los contactos de Bob tienen la aplicaci\u00f3n. Tal vez un poco m\u00e1s: dado que Bob tiene la aplicaci\u00f3n, significa que es consciente de la necesidad de usar la aplicaci\u00f3n, y es m\u00e1s probable que sus amigos sean como \u00e9l. As\u00ed que supongamos que el 40% de sus contactos descargaron la aplicaci\u00f3n. Pero muchos de ellos nunca lo abrieron, ni lo configuraron, o lo hicieron, pero su bluetooth no estaba habilitado cuando se encontraron.<\/p>\n<p id=\"b313\" data-selectable-paragraph=\"\">Entonces, el 70% de las veces no tenemos nada porque Bob no tiene la aplicaci\u00f3n. Incluso si la descarg\u00f3, lo m\u00e1s probable es que no lo haya abierto, ni la haya configurado, ni tenga habilitado el bluetooth. Imaginemos que solo el 50% de los que lo descargan lo usan seg\u00fan lo previsto. Eso significa que el 85% del tiempo, los rastreadores de contacto se topan con personas que tienen una aplicaci\u00f3n que no tiene informaci\u00f3n relevante.<\/p>\n<p id=\"9b3a\" data-selectable-paragraph=\"\">Por lo dem\u00e1s, alrededor del 15% de todos los infectados, solo el 15% de sus contactos tienen la aplicaci\u00f3n funcionando correctamente, y alcanzamos un total de alrededor del 2% de los contactos rastreados.<\/p>\n<p id=\"1941\" data-selectable-paragraph=\"\">Recuerde, esto se compara con el 70% -90% de los contactos que necesitamos rastrear para pasar del Martillo a la Danza.<\/p>\n<p id=\"af21\" data-selectable-paragraph=\"\">\u00a1Pero eso no es todo! La forma en que se configuran las aplicaciones actuales, las personas necesitan controlar de sus s\u00edntomas (lo que una gran parte de la gente no har\u00e1) y luego decidir activamente enviar esos datos al gobierno.<\/p>\n<p id=\"c61e\" data-selectable-paragraph=\"\">Muchos buenos ciudadanos lo har\u00e1n, pero muchos no lo har\u00e1n: si entregan los datos a los investigadores, la consecuencia probable es que todos sus familiares y amigos deber\u00e1n someterse a pruebas y muchos quedar\u00e1n en cuarentena. Si su esposo o su amigo se arriesgan a perder su trabajo porque tienen que quedarse en casa durante dos semanas m\u00e1s, \u00bfentregar\u00eda estos datos?<\/p>\n<p id=\"52ba\" data-selectable-paragraph=\"\">Por lo tanto, puede acabar la tarea con la mitad de la cantidad de contactos rastreados.<\/p>\n<p id=\"49b9\" data-selectable-paragraph=\"\">Nadie sabe cu\u00e1ntas personas realizar\u00edan cada una de estas acciones, pero despu\u00e9s de trabajar durante m\u00e1s de 10 a\u00f1os en la adopci\u00f3n de productos tecnol\u00f3gicos, mi suposici\u00f3n educada en el manejo de grandes n\u00fameros es la siguiente:<\/p>\n<div>\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Cym_y7TDufyF8qoD-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136498\" title=\"0_Cym_y7TDufyF8qoD copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Cym_y7TDufyF8qoD-copia.png\" alt=\"\" width=\"670\" height=\"402\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Cym_y7TDufyF8qoD-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Cym_y7TDufyF8qoD-copia-300x180.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/div>\n<div>\n<div>\n<div>\n<div>\n<figure><figcaption data-selectable-paragraph=\"\"><a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1zx6Yaw2WHAQ2XaS84J-ELadA7g2e1hHp7ayjG4M-ONY\/edit#gid=0\" rel=\"noopener nofollow\" target=\"_blank\">Puedes jugar con este modelo aqu\u00ed<\/a><\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p data-selectable-paragraph=\"\">Tal vez haya sido optimista y tal vez la proporci\u00f3n de contactos entregados a los rastreadores de contactos podr\u00eda ser solo del 0.1%. O tal vez he sido pesimista y es del 5%. O incluso 10%. Pero con el enfoque actual, nunca estar\u00e1 cerca del 70% -90% que queremos. Cada peque\u00f1a cosa cuenta, pero esta es muy peque\u00f1a.<\/p>\n<p id=\"5f3c\" data-selectable-paragraph=\"\">Entonces, \u00bfqu\u00e9 podemos hacer para cambiar esto? Primero, imagine que Apple y Google crearon una actualizaci\u00f3n del sistema operativo, en el que est\u00e1n trabajando, pero en lugar de tener que descargar la aplicaci\u00f3n, tan pronto como actualice el sistema operativo, la aplicaci\u00f3n se ejecuta en segundo plano, optimizada para detectar contactos. En tal situaci\u00f3n, es probable que\u00a0<a href=\"https:\/\/www.statista.com\/statistics\/565270\/apple-devices-ios-version-share-worldwide\/\" rel=\"noopener nofollow\" target=\"_blank\">~ 50% de las personas actualicen su sistema operativo<\/a>. Esa es la tasa normal en de un mes.<\/p>\n<p id=\"bcff\" data-selectable-paragraph=\"\">Supongamos que, con tal aplicaci\u00f3n, Bob todav\u00eda necesita decirle activamente a la aplicaci\u00f3n que est\u00e1 infectado para enviar sus contactos a las autoridades. Supongamos que solo el 50% lo hace.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kHK88QSM0okvMpkW-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136499\" title=\"0_kHK88QSM0okvMpkW copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kHK88QSM0okvMpkW-copia.png\" alt=\"\" width=\"670\" height=\"375\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kHK88QSM0okvMpkW-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kHK88QSM0okvMpkW-copia-300x167.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"427d\" data-selectable-paragraph=\"\">\u00a1Todav\u00eda solo tenemos alrededor del 10% de los contactos! Algo es mejor que nada, pero a\u00fan no es sustancial. \u00bfPodemos hacerlo mejor? S\u00ed.<\/p>\n<p id=\"f38d\" data-selectable-paragraph=\"\">Supongamos ahora que la descarga del sistema operativo es autom\u00e1tica. Los usuarios pueden decidir no participar, pero Apple y Google insisten mucho, todos los d\u00edas, para que actualice el sistema operativo.<\/p>\n<p id=\"f78b\" data-selectable-paragraph=\"\">Supongamos tambi\u00e9n que, dado que Bob tiene una enfermedad de declaraci\u00f3n obligatoria, no puede elegir cargar su lista de contactos cuando da positivo. Se carga por \u00e9l.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mAZ3jNLJYGfGUNdm-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136500\" title=\"0_mAZ3jNLJYGfGUNdm copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mAZ3jNLJYGfGUNdm-copia.png\" alt=\"\" width=\"670\" height=\"360\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mAZ3jNLJYGfGUNdm-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mAZ3jNLJYGfGUNdm-copia-300x161.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Hay mucha investigaci\u00f3n que respalda la gran diferencia entre un opt-in y un opt-out.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_3-P80ScdT4lGVaEJ-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136501\" title=\"0_3-P80ScdT4lGVaEJ copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_3-P80ScdT4lGVaEJ-copia.png\" alt=\"\" width=\"670\" height=\"466\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_3-P80ScdT4lGVaEJ-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_3-P80ScdT4lGVaEJ-copia-300x208.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Para la donaci\u00f3n de \u00f3rganos, la diferencia est\u00e1 entre el ~ 15% y el ~ 99%. Para el seguimiento de contactos, la mayor\u00eda de las personas tampoco optar\u00edan por no participar. Y si lo hacen, hay muchas cosas que podr\u00edamos hacer para obligarlos a que vuelvan a suscribirse, como solicitar una nueva confirmaci\u00f3n cada pocas horas o pedirles que naveguen a la configuraci\u00f3n cada pocas horas para confirmar la exclusi\u00f3n. Es posible que no todos los pa\u00edses logren una penetraci\u00f3n del 99% con una opci\u00f3n de exclusi\u00f3n debido a la pol\u00edtica, pero si queremos que estas aplicaciones sean \u00fatiles, esta es la \u00fanica manera.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_KmPX9laQHWWHEwpZ-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136502\" title=\"0_KmPX9laQHWWHEwpZ copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_KmPX9laQHWWHEwpZ-copia.png\" alt=\"\" width=\"670\" height=\"380\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_KmPX9laQHWWHEwpZ-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_KmPX9laQHWWHEwpZ-copia-300x170.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<p id=\"98b0\" data-selectable-paragraph=\"\">Lo que estoy tratando de hacer es mostrar es que necesitamos una penetraci\u00f3n muy, muy alta de estas aplicaciones para que sean eficaces, y cada decisi\u00f3n que tomen los usuarios disminuir\u00e1 significativamente su eficacia. Pero si lo logramos, el premio es asombroso.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_zn2_kMNgZSbAdhmM-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136503\" title=\"0_zn2_kMNgZSbAdhmM copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_zn2_kMNgZSbAdhmM-copia.png\" alt=\"\" width=\"670\" height=\"389\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_zn2_kMNgZSbAdhmM-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_zn2_kMNgZSbAdhmM-copia-300x174.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<p id=\"e901\" data-selectable-paragraph=\"\">Inmediatamente despu\u00e9s de que se sabe que alguien est\u00e1 enfermo, las autoridades podr\u00edan tener una lista de todos los contactos relevantes (adem\u00e1s de muchos falsos positivos). La entrevista con Bob ser\u00eda muy f\u00e1cil, y se podr\u00eda llamar a todos los contactos de inmediato.<\/p>\n<p id=\"e86f\" data-selectable-paragraph=\"\">Y ni siquiera es tan dif\u00edcil hacer que esto suceda. \u00bfRecuerdas\u00a0<a href=\"https:\/\/blog.google\/inside-google\/company-announcements\/apple-and-google-partner-covid-19-contact-tracing-technology\" rel=\"noopener nofollow\" target=\"_blank\">el anuncio que mencion\u00e9 antes de Apple y Google<\/a>? Lo que dicen estas compa\u00f1\u00edas es que primero est\u00e1n permitiendo que los desarrolladores creen aplicaciones bluetooth que puedan interactuar f\u00e1cilmente entre s\u00ed. Pero luego implementar\u00e1n estas caracter\u00edsticas en sus sistemas operativos principales. Est\u00e1n planeando hacer que los usuarios lo autoricen, pero esto probablemente podr\u00eda ser f\u00e1cil de convertir en una opci\u00f3n de exclusi\u00f3n, o incluso voluntaria de forma forzosa, si la necesidad es lo suficientemente clara y los gobiernos lo exigen.<\/p>\n<p id=\"f698\" data-selectable-paragraph=\"\">Recuerde, el objetivo de todo esto es mantenernos por encima del umbral crucial donde el rastreo de contactos funciona lo suficientemente bien como para permitir que la econom\u00eda se vuelva a abrir, para pasar del Martillo a la Danza. Si las decisiones de exclusi\u00f3n pasaran del 20% al 5%, se podr\u00eda rastrear un n\u00famero suficientemente alto de contactos y enviarlos a las autoridades para que esto tenga el impacto decisivo en la lucha contra la pandemia.<\/p>\n<p id=\"5e35\" data-selectable-paragraph=\"\"><em>Perm\u00edtanme reiterar que todos los n\u00fameros utilizados en esta secci\u00f3n son ilustrativos, no reales. Ilustran el razonamiento de que el factor de \u00e9xito m\u00e1s importante para cualquier tecnolog\u00eda de rastreo de contactos ser\u00e1 la adopci\u00f3n voluntaria.<\/em><\/p>\n<h2 id=\"262e\" data-selectable-paragraph=\"\">C\u00f3digos QR como alternativa a las aplicaciones Bluetooth<\/h2>\n<p data-selectable-paragraph=\"\">Las aplicaciones Bluetooth (o funciones integradas en iOS o Android) no son la \u00fanica forma de conseguir nuestro objetivo. Hay algunas otras alternativas interesantes. Uno de ellos es a trav\u00e9s de c\u00f3digos QR, como lo que est\u00e1 construyendo\u00a0<a href=\"https:\/\/www.zerobase.io\/\" rel=\"noopener nofollow\" target=\"_blank\">Zerobase<\/a>.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_CnWOU68l7BKXILJF-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136504\" title=\"0_CnWOU68l7BKXILJF copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_CnWOU68l7BKXILJF-copia.png\" alt=\"\" width=\"670\" height=\"503\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_CnWOU68l7BKXILJF-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_CnWOU68l7BKXILJF-copia-300x225.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Un pasajero escanea un c\u00f3digo QR para obtener su pase verde en una estaci\u00f3n de metro en Wuhan el 1 de abril de 2020. Ng Han Guan \/ AP Photo, a trav\u00e9s de\u00a0<a href=\"https:\/\/www.businessinsider.com\/coronavirus-china-health-software-color-coded-how-it-works-2020-4?IR=T#heres-what-one-of-these-checkpoints-seen-in-a-subway-station-in-hangzhou-looks-like-people-show-their-codes-on-their-phones-to-a-security-guard-who-either-wave-them-through-or-stop-them-8\" rel=\"noopener nofollow\" target=\"_blank\">Business Insider<\/a><\/p>\n<p id=\"5d25\" data-selectable-paragraph=\"\">Cuando entre en un edificio, es posible que deba escanear un c\u00f3digo QR. Escanearlo te vincula a ese lugar en ese momento, y a todos los dem\u00e1s que tambi\u00e9n marcaron su entrada al mismo tiempo. Estos c\u00f3digos pueden imprimirse y publicarse muy f\u00e1cilmente en cualquier lugar: en la entrada de edificios, habitaciones, estaciones de autobuses, vagones de tren \u2026 El seguimiento se puede hacer de una manera que conserve la privacidad.<\/p>\n<p id=\"32c1\" data-selectable-paragraph=\"\">La diferencia con las aplicaciones bluetooth no es la tecnolog\u00eda. Ambos son geniales. La diferencia es el porcentaje de adopci\u00f3n, el n\u00famero de usuarios: podr\u00edamos hacer que sea obligatorio para las personas escanear c\u00f3digos QR si desean entrar en un edificio. De esta forma, se conserva la opci\u00f3n de optar por no participar (no entrar en el edificio), pero el incentivo para cumplir la norma es fuerte. Algo similar podr\u00eda hacerse con las aplicaciones bluetooth: si fuera obligatorio tener una abierta para entrar en los edificios, la adopci\u00f3n podr\u00eda acabar siendo lo suficientemente alta para ser \u00fatil.<\/p>\n<p id=\"64ee\" data-selectable-paragraph=\"\">Tenga en cuenta que todav\u00eda tenemos el problema del control personal del estado de salud. Queremos conseguir una forma de que los lugares y contactos lleguen autom\u00e1ticamente a las autoridades cuando se determine que Bob est\u00e1 infectado.<\/p>\n<p id=\"13d9\" data-selectable-paragraph=\"\">Esa fue mucha informaci\u00f3n. Resumamos todas nuestras opciones, con sus ventajas y desventajas:<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mFJmPVgWip3g85Rs-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136506\" title=\"0_mFJmPVgWip3g85Rs copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mFJmPVgWip3g85Rs-copia.png\" alt=\"\" width=\"670\" height=\"225\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mFJmPVgWip3g85Rs-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mFJmPVgWip3g85Rs-copia-300x100.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"a500\" data-selectable-paragraph=\"\">Como puede comprobar, creo que las aplicaciones que requieren la opci\u00f3n de Bluetooth no tienen ning\u00fan valor. Los c\u00f3digos QR que no son obligatorios son ligeramente mejores, porque al menos Bob puede escanearlos y registrar d\u00f3nde ha estado. Pero si no es obligatorio, pocas personas y empresas lo usar\u00e1n, por lo que se registrar\u00e1n pocos contactos.<\/p>\n<p id=\"a437\" data-selectable-paragraph=\"\">El seguimiento manual de contactos es el siguiente en utilidad. De todos modos, es necesario tener rastreadores manuales, por lo que deber\u00edamos hacerlo. Pero rastrear\u00e1n solo una parte de los contactos, y llevar\u00e1 tiempo. De todos modos, tambi\u00e9n invadir\u00e1n la privacidad de los infectados y sus contactos.<\/p>\n<p id=\"1f70\" data-selectable-paragraph=\"\">Luego tenemos una serie de soluciones tecnol\u00f3gicas que ayudan sustancialmente a los rastreadores de contacto. Ya sea a trav\u00e9s del acceso autom\u00e1tico al GPS de Bob y a los datos de la tarjeta de cr\u00e9dito, agregando coincidencias de GPS dirigidas por el operador m\u00f3vil o excluyendo aplicaciones de rastreo de contactos , estas proporcionan una cantidad sustancial de informaci\u00f3n realmente r\u00e1pida, a un bajo costo para la privacidad.<\/p>\n<p id=\"a7de\" data-selectable-paragraph=\"\">Las mejores opciones son el c\u00f3digo QR obligatorio o las aplicaciones bluetooth. Proporcionan un volcado inmediato de contactos, mientras que la privacidad se puede mantener razonablemente, ya que lo \u00fanico que reciben las autoridades es la informaci\u00f3n de la persona y la lista de coincidencias, junto con d\u00f3nde y cu\u00e1ndo ocurrieron.<\/p>\n<p id=\"def7\" data-selectable-paragraph=\"\">Para estas soluciones, las autoridades no necesitar\u00edan tener m\u00e1s informaci\u00f3n que esta. No es necesario realizar un seguimiento de cada movimiento durante meses y almacenarlo en una base de datos. Solo las coincidencias de las \u00faltimas dos semanas, una vez que alguien est\u00e1 infectado.<\/p>\n<p id=\"6506\" data-selectable-paragraph=\"\">Algunas personas podr\u00edan desaprobar incluso esta cantidad limitada de reducci\u00f3n de privacidad. As\u00ed que hablemos de eso.<\/p>\n<h1 id=\"cf21\" data-selectable-paragraph=\"\">\u00bfC\u00f3mo debemos pensar sobre el coronavirus y la privacidad?<\/h1>\n<p id=\"37c8\" data-selectable-paragraph=\"\">Tenemos miedo.<\/p>\n<p id=\"7ede\" data-selectable-paragraph=\"\">Poco a poco, todo el mundo que conoc\u00edamos a nuestro alrededor ha desaparecido casi de la noche a la ma\u00f1ana. Los trabajos, las vidas, las libertades, las amistades que todos apreciamos han sido puestas en cuarentena.<\/p>\n<p id=\"82d6\" data-selectable-paragraph=\"\">Entonces, cuando hablamos de algo m\u00e1s que nos quitan, nuestra privacidad, reaccionamos. Nos rebelamos. No queremos perder eso tambi\u00e9n.<\/p>\n<p id=\"770b\" data-selectable-paragraph=\"\">Porque entendemos que los trabajos, las amistades, la libertad volver\u00e1n. Pero tememos que, si renunciamos a nuestra privacidad, no la recuperaremos.<\/p>\n<p id=\"7398\" data-selectable-paragraph=\"\">Tememos 1984.<\/p>\n<p id=\"f070\" data-selectable-paragraph=\"\">Queremos evitar un mundo impulsado por la IA en el que el gobierno conozca todos nuestros movimientos, nos califique de acuerdo con nuestro comportamiento y pronto nos diga qu\u00e9 pensar. No queremos ser China.<\/p>\n<p id=\"c04b\" data-selectable-paragraph=\"\">Eso no es solo una pesadilla te\u00f3rica.\u00a0<a href=\"https:\/\/www.bbc.com\/news\/world-europe-52095500\" rel=\"noopener nofollow\" target=\"_blank\">Hungr\u00eda acaba de caer en una dictadura<\/a>, en el coraz\u00f3n de la Uni\u00f3n Europea y mientras tanto a gente no prestaba atenci\u00f3n. Y Estados Unidos todav\u00eda est\u00e1 bajo la Patriot Act, aprobada hace 19 a\u00f1os a ra\u00edz del 11 de septiembre.<\/p>\n<p id=\"8dd3\" data-selectable-paragraph=\"\">Este miedo es bueno, porque nos alerta. Nos hace prestar atenci\u00f3n. Nos hace apreciar las libertades que tenemos y luchar para defenderlas, porque si las perdemos hoy, tal vez nunca las recuperemos.<\/p>\n<p id=\"5344\" data-selectable-paragraph=\"\">Pero ese miedo no puede ser irracional. No puede ser exhaustivo. No puede convertirse en p\u00e1nico.<\/p>\n<p id=\"d9dc\" data-selectable-paragraph=\"\">Necesitamos analizar el problema con frialdad, diseccionarlo y decidir racionalmente que podemos hacer.<\/p>\n<p id=\"247c\" data-selectable-paragraph=\"\">La primera forma en que lo diseccionamos es d\u00e1ndonos cuenta de que no se trata de los datos de todos, sino de dos peque\u00f1os grupos: los infectados y sus contactos.<\/p>\n<p id=\"5877\" data-selectable-paragraph=\"\">Los infectados ya tienen diferentes derechos de privacidad. Muchos pa\u00edses ya tienen legislaci\u00f3n para tratarlos de manera diferente. Y queremos que lo hagan. \u00bfQueremos que los infectados no puedan colaborar con las autoridades para reducir el impacto de la epidemia? El \u00fanico debate aqu\u00ed es el nivel de privacidad que se les debe permitir mantener.<\/p>\n<p id=\"0973\" data-selectable-paragraph=\"\">Todas las propuestas hechas, sugieren que los \u00fanicos datos que deben conocerse sobre los infectados es d\u00f3nde han estado durante las \u00faltimas dos semanas y con qui\u00e9n. Preguntarles directamente es complicado y de poca utilidad. Obtener esa informaci\u00f3n a trav\u00e9s de GPS, patrones de gasto de tarjeta de cr\u00e9dito o aplicaciones obligatorias de bluetooth es confiable e inmediato, al tiempo que limita la exposici\u00f3n a menos informaci\u00f3n de lo que la polic\u00eda ya puede descubrir sobre cualquiera de nosotros.<\/p>\n<p id=\"f204\" data-selectable-paragraph=\"\">En cuanto a sus contactos, sus derechos de privacidad deber\u00edan ser ligeramente superiores. No necesitamos sus extractos de tarjeta de cr\u00e9dito o sus datos completos de movilidad. Solo queremos saber qui\u00e9nes son y la interacci\u00f3n que han tenido con las personas infectadas: d\u00f3nde, cu\u00e1ndo y por cu\u00e1nto tiempo. Solo queremos esa informaci\u00f3n durante las \u00faltimas dos o tres semanas. Esa informaci\u00f3n se puede recopilar a trav\u00e9s de aplicaciones bluetooth obligatorias, c\u00f3digos QR obligatorios, informes de operadores m\u00f3viles y probablemente otras herramientas. Los gobiernos no necesitan saber m\u00e1s que eso. Solo eso.<\/p>\n<p id=\"13e0\" data-selectable-paragraph=\"\">Eso sugiere una lista de limitaciones a los datos que las autoridades deber\u00edan poder acceder:<\/p>\n<ul>\n<li id=\"edee\" data-selectable-paragraph=\"\">L\u00edmites a los datos recogidos: para las personas infectadas, solo recopilaremos su paradero, a qui\u00e9n conocieron, d\u00f3nde y por cu\u00e1nto tiempo. Para sus contactos, solo que hab\u00eda un contacto, donde y por cuanto tiempo.<\/li>\n<li id=\"b233\" data-selectable-paragraph=\"\">L\u00edmite de tiempo: solo se podr\u00e1 acceder a los datos durante las tres semanas anteriores. Todos los datos anteriores ser\u00e1n eliminados.<\/li>\n<li id=\"747c\" data-selectable-paragraph=\"\">Acceso: solo el Ministerio de Salud o una agencia auton\u00f3mica equivalente debe tener acceso a los datos recopilados bajo el marco legal de empresas privadas o por investigadores en entrevistas. Qui\u00e9n tiene acceso a los datos dentro del Ministerio de Salud (p. Ej., Investigadores) debe estar claramente estipulado, controlado cuidadosamente mediante un seguimiento cada vez que un empleado accede a un dato, y sujeto a una auditor\u00eda s\u00f3lida.<\/li>\n<li id=\"7392\" data-selectable-paragraph=\"\">Seguridad: Toda la informaci\u00f3n de identificaci\u00f3n personal (PII) estar\u00e1 protegida para cumplir con los est\u00e1ndares m\u00e9dicos.<\/li>\n<li id=\"f581\" data-selectable-paragraph=\"\">Criterios de finalizaci\u00f3n claramente definidos:\u00a0necesitamos estos datos solo durante la epidemia. La definici\u00f3n de \u201cEpidemia\u201d debe ser objetiva y estar claramente establecida. Por ejemplo, una vez que m\u00e1s del 70% de la poblaci\u00f3n se vuelve inmune, ya sea por vacunaci\u00f3n o por inmunidad colectiva, el sistema de recopilaci\u00f3n de datos se cerrar\u00e1 autom\u00e1ticamente y los datos recopilados ser\u00e1n destruidos.<\/li>\n<li id=\"f853\" data-selectable-paragraph=\"\">Debido proceso: las personas pueden y deben recurrir a los tribunales si el gobierno ha utilizado los datos de forma no adecuada, o si las conclusiones alcanzadas por los investigadores son injustas o inadecuadas.<\/li>\n<li id=\"5de5\" data-selectable-paragraph=\"\">Transparencia: Toda la informaci\u00f3n recogida debe hacerse expl\u00edcita. Tambi\u00e9n debe hacerse p\u00fablico, extrayendo toda la informaci\u00f3n de identificaci\u00f3n personal (PII): cosas como nombres o direcciones.<\/li>\n<\/ul>\n<p id=\"34d6\" data-selectable-paragraph=\"\">Los profesionales de la privacidad pueden ofrecer m\u00e1s detalles sobre c\u00f3mo proteger los datos del historial de ubicaciones. Por ejemplo, podr\u00edamos tener toda la operaci\u00f3n de rastreo de contactos dirigida por una corporaci\u00f3n o una organizaci\u00f3n sin fines de lucro, o un conjunto de ellas. Simplemente podr\u00edan comunicarse con las autoridades sobre qui\u00e9n deber\u00eda estar aislado y qui\u00e9n deber\u00eda ser puesto en cuarentena. Tal vez las personas no pueden optar por no compartir la informaci\u00f3n, pero pueden elegir a qui\u00e9n se la dan.<\/p>\n<p id=\"e3a6\" data-selectable-paragraph=\"\">La segunda forma en que podemos acercarnos a este problema es a trav\u00e9s de los datos que no queremos que tenga el gobierno. Es probable que la mayor\u00eda de las personas compartan con el gobierno coincidencias con personas infectadas que han tenido en las \u00faltimas dos semanas. Lo que no quieren es que el gobierno conozca todos sus movimientos.<\/p>\n<p id=\"d549\" data-selectable-paragraph=\"\">Pero ya puede.<\/p>\n<p id=\"53eb\" data-selectable-paragraph=\"\">No solo porque ya tiene grandes cantidades de datos, en un pa\u00eds como los EE. UU. Del IRS, el DHS, el FBI y otros organismos. Adem\u00e1s, porque gran parte de esta informaci\u00f3n ya est\u00e1 disponible en empresas privadas.<\/p>\n<p id=\"1a14\" data-selectable-paragraph=\"\">Tal como\u00a0<a href=\"https:\/\/www.nytimes.com\/interactive\/2018\/12\/10\/business\/location-data-privacy-apps.html\" rel=\"noopener nofollow\" target=\"_blank\">inform\u00f3 el New York Times<\/a>, docenas, si no cientos, de compa\u00f1\u00edas recopilan y venden mucha m\u00e1s informaci\u00f3n de la que se requiere aqu\u00ed. Empresas como Google, Apple, Waze, Uber, IBM, Kiip, TheScore, Facebook y docenas m\u00e1s saben d\u00f3nde est\u00e1s y a d\u00f3nde vas todo el tiempo, y muchas venden esa informaci\u00f3n.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_ysAO27VShdnRaLCS-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136507\" title=\"0_ysAO27VShdnRaLCS copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_ysAO27VShdnRaLCS-copia.png\" alt=\"\" width=\"670\" height=\"376\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_ysAO27VShdnRaLCS-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_ysAO27VShdnRaLCS-copia-300x168.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Fuente:\u00a0<a href=\"https:\/\/www.nytimes.com\/interactive\/2018\/12\/10\/business\/location-data-privacy-apps.html\" rel=\"noopener nofollow\" target=\"_blank\">New York Times<\/a><\/p>\n<p data-selectable-paragraph=\"\">\n<section>\n<div>\n<div>\n<p id=\"2a37\" data-selectable-paragraph=\"\">Las empresas ya revelan que comparten 5,000 datos por usuario. Probablemente sea er m\u00e1s de lo que sabes sobre ti. Esa informaci\u00f3n se vende anonimizada a veces, pero se puede\u00a0<a href=\"https:\/\/www.fastcompany.com\/90278465\/sorry-your-data-can-still-be-identified-even-its-anonymized\" rel=\"noopener nofollow\" target=\"_blank\">des-anonimizar<\/a>.<\/p>\n<p id=\"28d6\" data-selectable-paragraph=\"\">Por tanto, estamos debatiendo compartir con compa\u00f1\u00edas, ONG o gobiernos una peque\u00f1a cantidad de informaci\u00f3n que es mucho menos de lo que ya se puede comprar en l\u00ednea, y es mucho m\u00e1s preocupante que compartir si conoci\u00f3 a Bob para almorzar la semana pasada.<\/p>\n<p id=\"7a2e\" data-selectable-paragraph=\"\">La tercera manera en que podemos resolver este problema es buscando opciones. Es posible que algunos de los sistemas descritos aqu\u00ed sigan siendo pol\u00e9micos, pero es posible que deseemos construirlos ahora, sin aprobarlos todav\u00eda. Si esperamos durante meses para resolver el debate, y de repente ocurre un nuevo brote, podr\u00edamos necesitar decidir entre billones de d\u00f3lares en cierres de la econom\u00eda o activar un interruptor y usar esta tecnolog\u00eda. Pero solo podemos hacer eso si la tecnolog\u00eda est\u00e1 disponible. Si queremos usar, por ejemplo, aplicaciones bluetooth obligatorias para todos, necesitamos construir eso ahora para tener la opci\u00f3n en unos pocos meses.<\/p>\n<p id=\"935a\" data-selectable-paragraph=\"\">Finalmente, debemos poner la privacidad en el contexto de los otros derechos que hemos perdido. Hemos perdido nuestra salud. Perdimos nuestra econom\u00eda. Hemos perdido nuestra libertad. Si podemos recuperarlos con un poco de privacidad, \u00bfno lo vamos a considerar? El paquete de\u00a0<a href=\"https:\/\/www.wsj.com\/articles\/whats-in-the-2-trillion-senate-coronavirus-bill-11585185450\" rel=\"noopener nofollow\" target=\"_blank\">2 billones<\/a>\u00a0$ aprobado en los Estados Unidos es equivalente a 10,000 $ por adulto. \u00bfEst\u00e1s realmente seguro de que prefieres pagar 10,000 $ en lugar de darle al gobierno un poco de informaci\u00f3n que ya le das a FourSquare?<\/p>\n<p id=\"4432\" data-selectable-paragraph=\"\">Para resumir, solo queremos compartir un poco de informaci\u00f3n, que puede ser muy limitada, que es mucho menos de lo que ya est\u00e1 disponible p\u00fablicamente, o disponible para el gobierno, sobre muy pocas personas. Todo para que podamos recuperar nuestra salud, nuestra econom\u00eda, nuestra libertad y nuestras vidas.<\/p>\n<p id=\"8618\" data-selectable-paragraph=\"\">Los humanos no est\u00e1n destinados a estar aislados. Estamos destinados a\u00a0<em>bailar<\/em>.<\/p>\n<p id=\"55d0\" data-selectable-paragraph=\"\">Esta secci\u00f3n se basa en gran medida en ideas y fuentes de la investigaci\u00f3n de\u00a0<a href=\"http:\/\/twitter.com\/Genevieve\" rel=\"noopener nofollow\" target=\"_blank\">@Genevieve<\/a>\u00a0Gee sobre el seguimiento de contactos.<\/p>\n<\/div>\n<\/div>\n<\/section>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p data-selectable-paragraph=\"\">\n<section>\n<div>\n<div>\n<p id=\"1824\" data-selectable-paragraph=\"\"><em>Si desea recibir las pr\u00f3ximas entregas del art\u00edculo,\u00a0<\/em><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfMlYTvQiZL1nBJILpFYvawQ85TVersnwXuRq3kqV2oTR5GzA\/viewform\" rel=\"noopener nofollow\" target=\"_blank\"><em>suscr\u00edbase al bolet\u00edn<\/em><\/a><em>.<\/em><\/p>\n<p>Esta es la Parte 3 de nuestro art\u00edculo, Coronavirus: aprender a bailar. En la Parte 4, hablaremos sobre Aislamientos y Cuarentenas. En la Parte 5, hablaremos sobre las prohibiciones de viaje, los l\u00edmites a las reuniones sociales y los cierres econ\u00f3micos. En la Parte 6, lo pondremos todo junto. Le daremos recomendaciones espec\u00edficas sobre cada uno, incluida una advertencia: la mayor\u00eda de los pa\u00edses no se est\u00e1n acercando bien al baile. Si contin\u00faan su camino actual, terminar\u00e1n como Singapur.<\/p>\n<p id=\"f7a9\" data-selectable-paragraph=\"\"><em>Este ha sido un esfuerzo de equipo masivo con la ayuda de docenas de personas que han proporcionado investigaciones, fuentes, argumentos, comentarios sobre la redacci\u00f3n, cuestionaron mis argumentos y suposiciones, y no estuvieron de acuerdo conmigo. Un agradecimiento especial a Carl Juneau, Genevieve Gee, Matt Bell, Jorge Pe\u00f1alva, Christina Mueller, Barthold Albrecht, Elena Baillie, Pierre Djian, Yasemin Denari, Eric Ries, Shishir Mehrotra, Eric Ries, Kunal Rambhia, Jeffrey Ladish, Claire Marshall, Donatus Albrecht , el equipo de prueba y rastreo, y muchos m\u00e1s. Esto hubiera sido imposible sin todos ustedes.<\/em><\/p>\n<p id=\"2ac8\" data-selectable-paragraph=\"\"><em>Si desea conocer lo \u00faltimo sobre Pruebas y seguimiento de contactos en los EE. UU., vaya a\u00a0<\/em><a href=\"https:\/\/testandtrace.com\/\" rel=\"noopener nofollow\" target=\"_blank\"><em>Test and Trace<\/em><\/a><em>.<\/em><\/p>\n<p data-selectable-paragraph=\"\">\n<\/div>\n<\/div>\n<\/section>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p data-selectable-paragraph=\"\">\n","protected":false},"excerpt":{"rendered":"<p>Parte 3 de Coronavirus: Aprendiendo a Danzar Traducci\u00f3n del art\u00edculo de\u00a0Tomas Pueyo\u00a0por\u00a0Antonio Figueras. Nuestros art\u00edculos anteriores,\u00a0Coronavirus: Por qu\u00e9 Debemos Actuar Ya,\u00a0Coronavirus: El Martillo y la Danza, and\u00a0Out of Many, One\u00a0han reunido m\u00e1s de 60 millones de visitas y han sido traducidos a m\u00e1s de 40 idiomas. Esta entrega es la parte 3 (parte 1\u00a0y\u00a0parte 2) de nuestro cuarto art\u00edculo,\u00a0Aprendiendo a Danzar, una serie que se centra en los pasos espec\u00edficos necesarios para abrir la econom\u00eda.\u00a0 &nbsp; &nbsp; &nbsp; &nbsp; Resumen Podemos reabrir la econom\u00eda nuevamente s\u00ed llevamos a cabo correctamente algunas acciones, incluidas las pruebas de diagn\u00f3stico y el seguimiento\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Parte 3 de Coronavirus: Aprendiendo a Danzar Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Nuestros art\u00edculos anteriores, Coronavirus: Por qu\u00e9 Debemos Actuar Ya, Coronavirus: El Martillo y la Danza, and Out of Many, One han reunido m\u00e1s de 60 millones de visitas y han sido traducidos a m\u00e1s de 40 idiomas. Esta entrega es la parte 3 (parte 1 y parte 2)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Parte 3 de Coronavirus: Aprendiendo a Danzar Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Nuestros art\u00edculos anteriores, Coronavirus: Por qu\u00e9 Debemos Actuar Ya, Coronavirus: El Martillo y la Danza, and Out of Many, One han reunido m\u00e1s de 60 millones de visitas y han sido traducidos a m\u00e1s de 40 idiomas. Esta entrega es la parte 3 (parte 1 y parte 2)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-04T09:41:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-04T09:41:07+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Parte 3 de Coronavirus: Aprendiendo a Danzar Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Nuestros art\u00edculos anteriores, Coronavirus: Por qu\u00e9 Debemos Actuar Ya, Coronavirus: El Martillo y la Danza, and Out of Many, One han reunido m\u00e1s de 60 millones de visitas y han sido traducidos a m\u00e1s de 40 idiomas. Esta entrega es la parte 3 (parte 1 y parte 2)\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/04\\\/136453#blogposting\",\"name\":\"Coronavirus: c\\u00f3mo hacer las pruebas y el seguimiento de contactos - Ciencia Marina y otros asuntos\",\"headline\":\"Coronavirus: c\\u00f3mo hacer las pruebas y el seguimiento de contactos\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/06\\\/0_Bx0Im8jDGZ2e7Cxe-copia1.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/04\\\/136453\\\/#articleImage\",\"width\":670,\"height\":379},\"datePublished\":\"2020-06-04T10:41:07+01:00\",\"dateModified\":\"2020-06-04T10:41:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/04\\\/136453#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/04\\\/136453#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/04\\\/136453#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/04\\\/136453#listItem\",\"name\":\"Coronavirus: c\\u00f3mo hacer las pruebas y el seguimiento de contactos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/04\\\/136453#listItem\",\"position\":3,\"name\":\"Coronavirus: c\\u00f3mo hacer las pruebas y el seguimiento de contactos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/04\\\/136453#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/04\\\/136453\",\"name\":\"Coronavirus: c\\u00f3mo hacer las pruebas y el seguimiento de contactos - Ciencia Marina y otros asuntos\",\"description\":\"Parte 3 de Coronavirus: Aprendiendo a Danzar Traducci\\u00f3n del art\\u00edculo de Tomas Pueyo por Antonio Figueras. Nuestros art\\u00edculos anteriores, Coronavirus: Por qu\\u00e9 Debemos Actuar Ya, Coronavirus: El Martillo y la Danza, and Out of Many, One han reunido m\\u00e1s de 60 millones de visitas y han sido traducidos a m\\u00e1s de 40 idiomas. Esta entrega es la parte 3 (parte 1 y parte 2)\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/04\\\/136453#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-06-04T10:41:07+01:00\",\"dateModified\":\"2020-06-04T10:41:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos - Ciencia Marina y otros asuntos","description":"Parte 3 de Coronavirus: Aprendiendo a Danzar Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Nuestros art\u00edculos anteriores, Coronavirus: Por qu\u00e9 Debemos Actuar Ya, Coronavirus: El Martillo y la Danza, and Out of Many, One han reunido m\u00e1s de 60 millones de visitas y han sido traducidos a m\u00e1s de 40 idiomas. Esta entrega es la parte 3 (parte 1 y parte 2)","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453#blogposting","name":"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos - Ciencia Marina y otros asuntos","headline":"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Bx0Im8jDGZ2e7Cxe-copia1.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453\/#articleImage","width":670,"height":379},"datePublished":"2020-06-04T10:41:07+01:00","dateModified":"2020-06-04T10:41:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453#listItem","name":"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453#listItem","position":3,"name":"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453","name":"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos - Ciencia Marina y otros asuntos","description":"Parte 3 de Coronavirus: Aprendiendo a Danzar Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Nuestros art\u00edculos anteriores, Coronavirus: Por qu\u00e9 Debemos Actuar Ya, Coronavirus: El Martillo y la Danza, and Out of Many, One han reunido m\u00e1s de 60 millones de visitas y han sido traducidos a m\u00e1s de 40 idiomas. Esta entrega es la parte 3 (parte 1 y parte 2)","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-06-04T10:41:07+01:00","dateModified":"2020-06-04T10:41:07+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos - Ciencia Marina y otros asuntos","og:description":"Parte 3 de Coronavirus: Aprendiendo a Danzar Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Nuestros art\u00edculos anteriores, Coronavirus: Por qu\u00e9 Debemos Actuar Ya, Coronavirus: El Martillo y la Danza, and Out of Many, One han reunido m\u00e1s de 60 millones de visitas y han sido traducidos a m\u00e1s de 40 idiomas. Esta entrega es la parte 3 (parte 1 y parte 2)","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-06-04T09:41:07+00:00","article:modified_time":"2020-06-04T09:41:07+00:00","twitter:card":"summary","twitter:title":"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos - Ciencia Marina y otros asuntos","twitter:description":"Parte 3 de Coronavirus: Aprendiendo a Danzar Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Nuestros art\u00edculos anteriores, Coronavirus: Por qu\u00e9 Debemos Actuar Ya, Coronavirus: El Martillo y la Danza, and Out of Many, One han reunido m\u00e1s de 60 millones de visitas y han sido traducidos a m\u00e1s de 40 idiomas. Esta entrega es la parte 3 (parte 1 y parte 2)","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"136453","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-05 15:29:18","updated":"2026-05-26 19:32:13","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCoronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Coronavirus: c\u00f3mo hacer las pruebas y el seguimiento de contactos","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136453"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=136453"}],"version-history":[{"count":18,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136453\/revisions"}],"predecessor-version":[{"id":136521,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136453\/revisions\/136521"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=136453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=136453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=136453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}