{"id":136566,"date":"2020-06-10T17:19:28","date_gmt":"2020-06-10T16:19:28","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=136566"},"modified":"2020-06-10T17:19:28","modified_gmt":"2020-06-10T16:19:28","slug":"coronavirus-prevenir-la-siembra-y-la-propagacion","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566","title":{"rendered":"Coronavirus: prevenir la siembra y la propagaci\u00f3n"},"content":{"rendered":"<p id=\"28d7\">\u00bfDeber\u00edamos restringir los viajes? \u00bfNo celebrar festivales de m\u00fasica? \u00bfQu\u00e9 hacer con las escuelas? \u00bfQu\u00e9 negocios deber\u00edamos abrir? \u00bfQu\u00e9 eventos sociales deber\u00edan permitirse?<\/p>\n<p id=\"7371\" data-selectable-paragraph=\"\"><em>Traducci\u00f3n del art\u00edculo de\u00a0<\/em><a href=\"https:\/\/medium.com\/@tomaspueyo\" rel=\"noopener\" target=\"_blank\"><em>Tomas Pueyo<\/em><\/a><em>\u00a0por\u00a0<\/em><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/\" rel=\"noopener nofollow\" target=\"_blank\"><em>Antonio Figueras<\/em><\/a><em>.<\/em><\/p>\n<p id=\"aeff\" data-selectable-paragraph=\"\"><em>Esta es la Parte 5 de Aprender a Danzar (<\/em><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/25\/136297\" rel=\"noopener\" target=\"_blank\"><em>Parte 1<\/em><\/a><em>,\u00a0<\/em><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/01\/136401\" rel=\"noopener\" target=\"_blank\"><em>Parte 2<\/em><\/a><em>,\u00a0<\/em><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453\" rel=\"noopener\" target=\"_blank\"><em>Parte 3<\/em><\/a><em>. Parte 4 in\u00e9dita), una serie en la que profundizamos para comprender lo que los pa\u00edses deben hacer para bailar, para reabrir sus econom\u00edas sin nuevos brotes.<\/em><\/p>\n<p data-selectable-paragraph=\"\"><!--more--><\/p>\n<div>\n<p id=\"49f6\" data-selectable-paragraph=\"\">Los pa\u00edses est\u00e1n retomando su actividad social y econ\u00f3mica. Quieren imitar\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/25\/136297\" rel=\"noopener\" target=\"_blank\">el \u00e9xito de pa\u00edses como Corea del Sur o Taiw\u00e1n<\/a>. Ahora sabemos que pueden hacerlo con buenas\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/04\/136453\" target=\"_blank\">estrategias de tests y rastreo de contactos,<\/a> aislamientos y cuarentenas,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/01\/136401\" rel=\"noopener\" target=\"_blank\">exigiendo el uso de mascarillas aunque sean caseras, con higiene, distanciamiento f\u00edsico y educaci\u00f3n p\u00fablica<\/a>.<\/p>\n<p id=\"b5dc\" data-selectable-paragraph=\"\">Todas estas medidas son mucho menos costosas en comparaci\u00f3n con el cierre de la econom\u00eda, pero \u00bfson suficientes? \u00bfTambi\u00e9n necesitamos mantener cerradas las escuelas? \u00bfLos diversos negocios? \u00bfFestivales de m\u00fasica? \u00bfTurismo? \u00bfExisten otras medidas que son costosas para la econom\u00eda pero necesarias para mantener el virus bajo control?<\/p>\n<p id=\"a7b5\" data-selectable-paragraph=\"\">Primero las malas noticas:<\/p>\n<ul>\n<li id=\"557d\" data-selectable-paragraph=\"\">Es probable que necesitemos frenar en gran medida el turismo nacional e internacional durante meses<\/li>\n<li id=\"5c83\" data-selectable-paragraph=\"\">Los grandes eventos como ferias de negocios o conciertos de m\u00fasica deber\u00e1n evitarse por ahora.<\/li>\n<\/ul>\n<p id=\"5f6b\" data-selectable-paragraph=\"\">Las buenas noticias:<\/p>\n<ul>\n<li id=\"dd03\" data-selectable-paragraph=\"\">Deber\u00edamos poder viajar en una sola direcci\u00f3n o de muy larga distancia.<\/li>\n<li id=\"3fcd\" data-selectable-paragraph=\"\">Hay formas de acelerar la reapertura del turismo<\/li>\n<li id=\"26ac\" data-selectable-paragraph=\"\">Probablemente podamos reabrir escuelas<\/li>\n<li id=\"8b58\" data-selectable-paragraph=\"\">En base a la experiencia com\u00fan, est\u00e1 apareciendo un orden bastante claro que las empresas deber\u00edan seguir para reabrir.<\/li>\n<li id=\"a367\" data-selectable-paragraph=\"\">Las actividades m\u00e1s importantes que deben estar abiertos son los bancos, los supermercados y las tiendas en general, y los menos importantes son los caf\u00e9s y los bares, las pasteler\u00edas y los gimnasios.<\/li>\n<\/ul>\n<p id=\"10c6\" data-selectable-paragraph=\"\">Vamos a intentarlo.<\/p>\n<p id=\"3795\" data-selectable-paragraph=\"\">Imagine que su pa\u00eds ha aplicado el Martillo razonablemente bien y ahora se est\u00e1 preparando para Danzar. Algunas \u00e1reas todav\u00eda est\u00e1n en cuarentena, pero el resto de la econom\u00eda se est\u00e1 abriendo lentamente. Las autoridades son cuidadosas: el uso de m\u00e1scaras se aplica en\u00e9rgicamente, todos los contactos se rastrean, todas las personas enfermas se a\u00edslan en habitaciones de hotel y las cuarentenas se aplican al rastrear los movimientos de los tel\u00e9fonos m\u00f3viles.<\/p>\n<p id=\"deb8\" data-selectable-paragraph=\"\">Tu pa\u00eds ahora tiene dos objetivos:<\/p>\n<ol>\n<li id=\"9a29\" data-selectable-paragraph=\"\">Proteger las \u00e1reas seguras de infecciones provenientes de \u00e1reas de brotes. A eso lo llamamos \u201cevitar la siembra\u201d de nuevos casos.<\/li>\n<li id=\"19c3\" data-selectable-paragraph=\"\">Evitar que estas semillas se conviertan en brotes. Podemos llamar a eso \u201cevitar la propagaci\u00f3n\u201d. Los pa\u00edses deben evitar la siembra del virus y su propagaci\u00f3n.<\/li>\n<\/ol>\n<p id=\"246e\" data-selectable-paragraph=\"\">Para evitar la siembra, son necesarias restricciones de viaje.<br \/>\nPara evitar la propagaci\u00f3n, son necesarias restricciones en las reuniones sociales.<\/p>\n<p id=\"2d17\" data-selectable-paragraph=\"\">Como la mayor\u00eda de los pa\u00edses est\u00e1n abriendo sus pa\u00edses y est\u00e1n comenzando a permitir reuniones sociales, es m\u00e1s urgente hablar sobre la\u00a0propagaci\u00f3n. Primero trataremos eso, y luego exploraremos la siembra a trav\u00e9s de los viajes.<\/p>\n<h1 id=\"16fd\" data-selectable-paragraph=\"\">Los eventos favoritos del coronavirus<\/h1>\n<h2 id=\"2e00\" data-selectable-paragraph=\"\">S\u00faper infectadores (super-spreaders)<\/h2>\n<p id=\"9fbd\" data-selectable-paragraph=\"\">Como\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/25\/136297\" rel=\"noopener\" target=\"_blank\">ya lo he tratado anteriormente<\/a>, probablemente hayas o\u00eddo hablar del super infectador de Corea del Sur:<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_9iEvwDW3fnZiYE7q-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136568\" title=\"0_9iEvwDW3fnZiYE7q copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_9iEvwDW3fnZiYE7q-copia.png\" alt=\"\" width=\"670\" height=\"401\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_9iEvwDW3fnZiYE7q-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_9iEvwDW3fnZiYE7q-copia-300x179.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<div>\n<p id=\"209c\" data-selectable-paragraph=\"\">Fuente:\u00a0<a href=\"https:\/\/graphics.reuters.com\/CHINA-HEALTH-SOUTHKOREA-CLUSTERS\/0100B5G33SB\/index.html\" rel=\"noopener nofollow\" target=\"_blank\">Reuters<\/a><\/p>\n<p data-selectable-paragraph=\"\">Una sola persona, el paciente 31, caus\u00f3 m\u00e1s de 5,000 casos. En ese momento fueron la gran mayor\u00eda de los casos en Corea del Sur. A mediados de mayo, esta cifra todav\u00eda representa m\u00e1s del 40% de los casos en el pa\u00eds, sin contar toda la propagaci\u00f3n que podr\u00eda haber surgido desde entonces. Si esta persona no hubiera causado este brote, tal vez Corea del Sur nunca hubiera tenido uno, como Taiw\u00e1n.<\/p>\n<p id=\"f484\" data-selectable-paragraph=\"\">Es posible que sepa que esto lo caus\u00f3 el paciente 31 porque fue a una megaiglesia dos veces. Lo que quiz\u00e1 no sepa es\u00a0<a href=\"https:\/\/www.nytimes.com\/2020\/02\/21\/world\/asia\/south-korea-coronavirus-shincheonji.html\" rel=\"noopener nofollow\" target=\"_blank\">cu\u00e1l era el aspecto de ese servicio religioso<\/a>.<\/p>\n<\/div>\n<div><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_7Hd26fUeakIK0XhD-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136569\" title=\"0_7Hd26fUeakIK0XhD copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_7Hd26fUeakIK0XhD-copia.png\" alt=\"\" width=\"670\" height=\"335\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_7Hd26fUeakIK0XhD-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_7Hd26fUeakIK0XhD-copia-300x150.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/div>\n<div>Acto religioso en la Iglesia Shincheonji .\u00a0<a href=\"https:\/\/freedomofconscience.eu\/south-korea-coronavirus-and-shincheonji-stopping-the-witch-hunt-urgent-appeal-from-human-rights-groups\/\" rel=\"noopener nofollow\" target=\"_blank\">Fuente.<\/a><\/div>\n<div>\n<p id=\"5d11\" data-selectable-paragraph=\"\">En esta iglesia, miles de personas se sientan juntas durante largos per\u00edodos de tiempo, tienen prohibido usar gafas o mascarillas, cantan y rezan en voz alta. La iglesia no les permite no asistir a la funci\u00f3n religiosa, aunque est\u00e9n enfermos. Por eso, mientras estaba enfermo, el paciente 31 fue dos domingos seguidos a una funci\u00f3n religiosa.<\/p>\n<p id=\"7d21\" data-selectable-paragraph=\"\">En la\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/01\/136401\" rel=\"noopener\" target=\"_blank\">Parte 2 de esta serie de art\u00edculos<\/a>, expliqu\u00e9 c\u00f3mo el virus se propaga, a trav\u00e9s de gotitas y nubes de gotitas, al toser pero tambi\u00e9n cantando o incluso hablando. Tambi\u00e9n discutimos c\u00f3mo el virus prefiere espacios confinados compartidos durante largos per\u00edodos por personas que interact\u00faan estrechamente entre s\u00ed.<\/p>\n<p id=\"dde2\" data-selectable-paragraph=\"\">Este entorno de megaiglesia cumpl\u00eda con todos los requisitos que incrementan la velocidad de transmisi\u00f3n: hablar, cantar y estar en espacios confinados durante largos per\u00edodos de tiempo, especialmente porque a nadie se le permiti\u00f3 usar mascarillas o gafas.<\/p>\n<p id=\"594c\" data-selectable-paragraph=\"\">Como tambi\u00e9n hemos visto en la\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/25\/136297\" rel=\"noopener\" target=\"_blank\">Parte 1<\/a>, algo similar sucedi\u00f3 en los dormitorios de Singapur.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_aVAldqqQH-Sp8Jxb-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136570\" title=\"0_aVAldqqQH-Sp8Jxb copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_aVAldqqQH-Sp8Jxb-copia.png\" alt=\"\" width=\"670\" height=\"422\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_aVAldqqQH-Sp8Jxb-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_aVAldqqQH-Sp8Jxb-copia-300x188.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Como recordatorio, esta es una foto del dormitorio principal, tomada despu\u00e9s del confinamiento en ese pa\u00eds.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_t7e0N9tvVrnmfsmZ-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136571\" title=\"0_t7e0N9tvVrnmfsmZ copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_t7e0N9tvVrnmfsmZ-copia.png\" alt=\"\" width=\"670\" height=\"518\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_t7e0N9tvVrnmfsmZ-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_t7e0N9tvVrnmfsmZ-copia-300x231.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<div>\n<p id=\"3b15\" data-selectable-paragraph=\"\">Lo mismo: estos son lugares en los que conviven muchas personas en lugares cerrados que tienen fuertes interacciones sociales que probablemente incluyen mucha conversaci\u00f3n.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_lYbXBft9DVn9ffl7-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136572\" title=\"0_lYbXBft9DVn9ffl7 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_lYbXBft9DVn9ffl7-copia.png\" alt=\"\" width=\"670\" height=\"447\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_lYbXBft9DVn9ffl7-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_lYbXBft9DVn9ffl7-copia-300x200.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Trabajadores emigrantes en su habitaci\u00f3n del dormitorio WestLite Toh Guan en Singapur. Foto: EPA. Fuente:\u00a0<a href=\"https:\/\/www.scmp.com\/week-asia\/explained\/article\/3080466\/how-did-migrant-worker-dormitories-become-singapores-biggest\" rel=\"noopener nofollow\" target=\"_blank\">South China Morning Post<\/a>. Como se puede ver, la propagaci\u00f3n podr\u00eda no haber sido por su culpa, sino m\u00e1s bien una consecuencia inevitable de sus condiciones de vida.<\/p>\n<div>\n<div>\n<div>\n<p id=\"aa65\" data-selectable-paragraph=\"\">La propagaci\u00f3n explosiva del coronavirus en las reuniones sociales incluye muchos otros ejemplos. Uno es un\u00a0<a href=\"https:\/\/www.healthline.com\/health-news\/hone-social-gathering-can-quickly-spread-covid-19\" rel=\"noopener nofollow\" target=\"_blank\">coro en el estado de Washington<\/a>, donde las personas cantan en voz alta, muy juntas, durante un largo per\u00edodo de tiempo. 45 de 60 personas enfermaron.<\/p>\n<p id=\"c8ec\" data-selectable-paragraph=\"\">M\u00e1s de 4.000 personas se infectaron en toda Europa probablemente a trav\u00e9s de un camarero\u00a0<a href=\"https:\/\/www.dw.com\/de\/corona-versuchte-vertuschung-in-tirol\/a-53100314\" rel=\"noopener nofollow\" target=\"_blank\">en Ischgl<\/a>, donde las reuniones de amigos despu\u00e9s del esqu\u00ed son comunes.<\/p>\n<\/div>\n<\/div>\n<div>La zona alrededor de Gangelt en Alemania sufri\u00f3\u00a0<a href=\"https:\/\/www.theguardian.com\/world\/2020\/apr\/09\/the-cluster-effect-how-social-gatherings-were-rocket-fuel-for-coronavirus\" rel=\"noopener nofollow\" target=\"_blank\">1,500 infecciones despu\u00e9s de un carnaval<\/a>, donde la gente se mezcl\u00f3, habl\u00f3, cant\u00f3 y se bes\u00f3 en la mejilla.<\/div>\n<\/div>\n<div><\/div>\n<div>Esta es una imagen del evento:<\/div>\n<div><\/div>\n<\/div>\n<div><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.17.52-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136573\" title=\"Captura de pantalla 2020-06-10 a las 17.17.52 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.17.52-copia.png\" alt=\"\" width=\"497\" height=\"528\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.17.52-copia.png 497w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.17.52-copia-282x300.png 282w\" sizes=\"(max-width: 497px) 100vw, 497px\" \/><\/a><\/div>\n<div><a href=\"https:\/\/twitter.com\/racerxnyc\/status\/559405070463545344?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed&amp;ref_url=https%3A%2F%2Fcdn.embedly.com%2Fwidgets%2Fmedia.html%3Ftype%3Dtext%252Fhtml%26key%3Da19fcc184b9711e1b4764040d3dc5c07%26schema%3Dtwitter%26url%3Dhttps%253A%2F%2Ftwitter.com%2Fracerxnyc%2Fstatus%2F559405070463545344%26image%3D\" target=\"_blank\">Trofana Alm, fiesta despu\u00e9s de esquiar en Ischgl<\/a><\/div>\n<div><\/div>\n<div>La zona alrededor de Gangelt en Alemania sufri\u00f3\u00a0<a href=\"https:\/\/www.theguardian.com\/world\/2020\/apr\/09\/the-cluster-effect-how-social-gatherings-were-rocket-fuel-for-coronavirus\" rel=\"noopener nofollow\" target=\"_blank\">1,500 infecciones despu\u00e9s de un carnaval<\/a>, donde la gente se mezcl\u00f3, habl\u00f3, cant\u00f3 y se bes\u00f3 en la mejilla.<\/div>\n<div><\/div>\n<div><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_dpHKYizwHef-M24W-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136574\" title=\"0_dpHKYizwHef-M24W copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_dpHKYizwHef-M24W-copia.png\" alt=\"\" width=\"670\" height=\"470\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_dpHKYizwHef-M24W-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_dpHKYizwHef-M24W-copia-300x210.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/div>\n<div>Esta es una imagen del evento:<\/div>\n<div><\/div>\n<div><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Mlfx69OZVQGP2IRW-copia.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136575\" title=\"0_Mlfx69OZVQGP2IRW copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Mlfx69OZVQGP2IRW-copia.jpg\" alt=\"\" width=\"670\" height=\"446\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Mlfx69OZVQGP2IRW-copia.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_Mlfx69OZVQGP2IRW-copia-300x199.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/div>\n<div>Fuente\u00a0<a href=\"https:\/\/rp-online.de\/nrw\/staedte\/kreis-heinsberg\/coronavirus-in-nrw-kappensitzung-in-gangelt-bei-heinsberg-besucher-berichten_aid-49230563\" rel=\"noopener nofollow\" target=\"_blank\">Fotograf\u00eda<\/a>: Heinz Eschweiler<\/div>\n<div>\n<div>\n<p id=\"2089\" data-selectable-paragraph=\"\">El otro brote gran brote en Alemania tambi\u00e9n se debi\u00f3 a una fiesta. El distrito alem\u00e1n de Tirschenreuth, con 600 casos, tiene la mayor\u00eda de los casos per c\u00e1pita en el pa\u00eds despu\u00e9s de las fiesta de la cerveza.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_scj2EzQ_J-zCjNtO-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136576\" title=\"0_scj2EzQ_J-zCjNtO copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_scj2EzQ_J-zCjNtO-copia.png\" alt=\"\" width=\"670\" height=\"379\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_scj2EzQ_J-zCjNtO-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_scj2EzQ_J-zCjNtO-copia-300x169.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<div>\n<p id=\"a48a\" data-selectable-paragraph=\"\">La\u00a0<a href=\"https:\/\/www.theguardian.com\/world\/2020\/apr\/09\/the-cluster-effect-how-social-gatherings-were-rocket-fuel-for-coronavirus\" rel=\"noopener nofollow\" target=\"_blank\">lista<\/a>\u00a0contin\u00faa:<\/p>\n<ul>\n<li id=\"286d\" data-selectable-paragraph=\"\">En la playa de Bondi en Sydney, al menos 30 personas se infectaron despu\u00e9s de asistir a una fiesta con multitud de personas la noche antes de que se prohibieran las reuniones de 500 personas o m\u00e1s.<\/li>\n<li id=\"692f\" data-selectable-paragraph=\"\">En Francia, una celebraci\u00f3n de cuatro d\u00edas en la iglesia cristiana Porte Ouverte reuni\u00f3 a 2.500 fieles, muchos se infectaron e iniciaron brotes en todo el pa\u00eds, incluyendo a 250 personas que trabajan en el hospital de la Universidad de Estrasburgo o 263 casos en C\u00f3rcega.<\/li>\n<li id=\"b927\" data-selectable-paragraph=\"\">Un\u00a0<a href=\"https:\/\/www.independent.co.uk\/sport\/football\/european\/coronavirus-news-latest-atalanta-valencia-champions-league-italy-crisis-bergamo-a9448541.html\" rel=\"noopener nofollow\" target=\"_blank\">partido de f\u00fatbol<\/a>\u00a0en febrero entre el equipo italiano Atalanta, de B\u00e9rgamo, y Valencia, de Espa\u00f1a, sembr\u00f3 lo que m\u00e1s tarde se convirti\u00f3 en el brote de B\u00e9rgamo, uno de los m\u00e1s grandes de Italia.<\/li>\n<li id=\"f089\" data-selectable-paragraph=\"\">Incluso en Se\u00fal, la capital de Corea del Sur, que tiene uno de los mejores tratamientos de coronavirus del mundo,\u00a0<a href=\"https:\/\/www.mrt.com\/news\/article\/Asia-Today-S-Korea-counts-18-more-cases-after-15258306.php#item-85307-tbla-2\" rel=\"noopener nofollow\" target=\"_blank\">2,100 bares y clubes cerraron a mediados de mayo<\/a>\u00a0despu\u00e9s de que una sola persona infectada visit\u00f3 cinco clubes durante un largo fin de semana, infectando\u00a0<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2020-05-11\/gay-club-outbreak-poses-challenge-to-korea-s-open-virus-strategy\" rel=\"noopener nofollow\" target=\"_blank\">al menos\u00a0<\/a><a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2020-05-11\/gay-club-outbreak-poses-challenge-to-korea-s-open-virus-strategy\" rel=\"noopener nofollow\" target=\"_blank\">hasta ahora<\/a>\u00a0<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2020-05-11\/gay-club-outbreak-poses-challenge-to-korea-s-open-virus-strategy\" rel=\"noopener nofollow\" target=\"_blank\">a 100\u00a0<\/a>. Actualmente se est\u00e1 rastreando a m\u00e1s de 1.900 contactos .<\/li>\n<\/ul>\n<p id=\"6d6f\" data-selectable-paragraph=\"\">Esto no se limita a celebraciones masivas.<\/p>\n<p id=\"fc67\" data-selectable-paragraph=\"\">Bodas, funerales y cumplea\u00f1os generaron el 10% de los eventos de difusi\u00f3n temprana en los Estados Unidos. Por ejemplo,\u00a0<a href=\"https:\/\/www.cdc.gov\/mmwr\/volumes\/69\/wr\/mm6915e1.htm\" rel=\"noopener nofollow\" target=\"_blank\">este hombre de Chicago<\/a>\u00a0infect\u00f3 a otras 16 personas en un funeral y 3 de ellas murieron posteriormente. Esto tiene sentido, ya que las personas en este tipo de eventos a menudo pasan horas juntas, toc\u00e1ndose, abraz\u00e1ndose, hablando. En esta fiesta de\u00a0<a href=\"https:\/\/www.nytimes.com\/2020\/03\/23\/us\/coronavirus-westport-connecticut-party-zero.html\" rel=\"noopener nofollow\" target=\"_blank\">50 personas<\/a>, m\u00e1s de la mitad se infectaron, y estas personas luego propagaron el virus a trav\u00e9s de los Estados Unidos y el mundo.<\/p>\n<p id=\"44bd\" data-selectable-paragraph=\"\">Estos eventos superdifusores tambi\u00e9n ocurren en el mundo de los negocios.<\/p>\n<p id=\"219e\" data-selectable-paragraph=\"\">Al menos\u00a0<a href=\"https:\/\/en.wikipedia.org\/wiki\/Impact_of_the_COVID-19_pandemic_on_the_meat_industry_in_the_United_States\" rel=\"noopener nofollow\" target=\"_blank\">115 plantas procesadoras<\/a>\u00a0de carne han tenido brotes en los Estados Unidos, afectando al menos a 5k trabajadores.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mIA5pNesvVmYKufq-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136577\" title=\"0_mIA5pNesvVmYKufq copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mIA5pNesvVmYKufq-copia.png\" alt=\"\" width=\"670\" height=\"446\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mIA5pNesvVmYKufq-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_mIA5pNesvVmYKufq-copia-300x199.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Trabajadores de Planta de procesamiento de carne en Estados Unidos ( USDA ).\u00a0<a href=\"https:\/\/civileats.com\/2020\/04\/17\/poor-conditions-at-meatpacking-plants-have-long-put-workers-at-risk-the-pandemic-makes-it-much-worse\/\" rel=\"noopener nofollow\" target=\"_blank\">Fuente<\/a>.<\/p>\n<div>\n<div>\n<p id=\"d177\" data-selectable-paragraph=\"\">Una conferencia de Biogen en Boston a principios de marzo\u00a0<a href=\"https:\/\/www.nytimes.com\/2020\/04\/12\/us\/coronavirus-biogen-boston-superspreader.html\" rel=\"noopener nofollow\" target=\"_blank\">caus\u00f3 alrededor de 100 infecciones<\/a>\u00a0y propag\u00f3 el virus a seis estados. En una planta de procesamiento de pescado en Ghana,\u00a0<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2020-05-11\/ghana-fish-factory-worker-infects-533-people-as-virus-cases-jump\" rel=\"noopener nofollow\" target=\"_blank\">un trabajador infect\u00f3 a m\u00e1s de 500<\/a>.<\/p>\n<p id=\"e8d9\" data-selectable-paragraph=\"\">Y no se limita al trabajo manual. Un trabajador de un centro de llamadas infect\u00f3 a unos 100 compa\u00f1eros de trabajo (~ 45%) en Corea del Sur.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_GvtfcMEsaq6rnPAA-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136578\" title=\"0_GvtfcMEsaq6rnPAA copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_GvtfcMEsaq6rnPAA-copia.png\" alt=\"\" width=\"670\" height=\"485\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_GvtfcMEsaq6rnPAA-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_GvtfcMEsaq6rnPAA-copia-300x217.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/wwwnc.cdc.gov\/eid\/article\/26\/8\/20-1274_article\" rel=\"noopener nofollow\" target=\"_blank\">Fuente<\/a><\/p>\n<div>\n<p id=\"52c7\" data-selectable-paragraph=\"\"><a href=\"https:\/\/www.nytimes.com\/2020\/05\/04\/health\/coronavirus-office-makeover.html\" rel=\"noopener nofollow\" target=\"_blank\">Adi\u00f3s a las oficinas sin separaciones y aislamiento<\/a>.<\/p>\n<p id=\"b205\" data-selectable-paragraph=\"\">En todo el mundo, vemos el mismo patr\u00f3n una y otra vez. Cercan\u00eda entre personas, interacci\u00f3n social, cantar, hablar, bailar, abrazarse, besarse, todo durante largos per\u00edodos de tiempo en un ambiente confinado \u2026 Un patr\u00f3n consistente con el modelo de que la mayor\u00eda de las infecciones ocurren a trav\u00e9s de gotas o nubes de gotas mientras se tose, se habla o se canta. No hemos o\u00eddo hablar de brotes en salas de cine, por ejemplo, donde las personas est\u00e1n en su mayor\u00eda en silencio y permanecen en un asiento todo el tiempo.<\/p>\n<p id=\"18ec\" data-selectable-paragraph=\"\">En un\u00a0<a href=\"https:\/\/www.medrxiv.org\/content\/10.1101\/2020.04.20.20054726v1\" rel=\"noopener nofollow\" target=\"_blank\">art\u00edculo cient\u00edfico<\/a>\u00a0(preimpreso) dirigido por\u00a0<a href=\"https:\/\/twitter.com\/Carl\" rel=\"noopener nofollow\" target=\"_blank\">@Carl Juneau, PhD<\/a>\u00a0\u2014soy coautor \u2014 revisamos cientos de art\u00edculos. Para la gripe, la evidencia fue mixta, pero parece que el tipo y el momento de los eventos tuvieron gran influencia. Lo que descubrimos fue que es m\u00e1s probable que la gripe se propague\u00a0<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/23856374\" rel=\"noopener nofollow\" target=\"_blank\">durante eventos largos<\/a>, abarrotados y en interiores.\u00a0<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3022852\/\" rel=\"noopener nofollow\" target=\"_blank\">Otro estudio<\/a>\u00a0sugiri\u00f3 que, para la gripe, limitar las reuniones masivas solo era \u00fatil justo antes o al comienzo de un brote (pero tendr\u00eda poco efecto 20 d\u00edas despu\u00e9s del pico de infecci\u00f3n). Aqu\u00ed hay algunas citas relevantes de publicaciones recientes:<\/p>\n<blockquote>\n<p id=\"a0c5\" data-selectable-paragraph=\"\">\u201cLa evidencia disponible sugiere que los eventos de varios d\u00edas en lugares comunes abarrotados est\u00e1n m\u00e1s asociados con un mayor riesgo. Las reuniones masivas no son homog\u00e9neas y el riesgo debe evaluarse caso por caso \u201c.\u00a0<a href=\"https:\/\/www.cebm.net\/covid-19\/what-is-the-evidence-for-mass-gatherings-during-global-pandemics\/\" rel=\"noopener nofollow\" target=\"_blank\">Nunan y Brassey<\/a>\u00a0(marzo de 2020), Universidad de Oxford, no revisado por pares.<\/p>\n<p id=\"193a\" data-selectable-paragraph=\"\">Los resultados demostraron que las cancelaciones de eventos pueden reducir la tasa de infecci\u00f3n de COVID-19 en un 35%.\u00a0<a href=\"https:\/\/www.medrxiv.org\/content\/10.1101\/2020.03.12.20035220v1\" rel=\"noopener nofollow\" target=\"_blank\">Sugishita y col<\/a>. (Marzo de 2020), no revisado por pares.<\/p>\n<\/blockquote>\n<p id=\"eb11\" data-selectable-paragraph=\"\">Ferguson et. al. del Imperial College creen que el impacto de limitar los eventos p\u00fablicos se traduce en una reducci\u00f3n en la tasa de transmisi\u00f3n de alrededor del 12.5%.<\/p>\n<p id=\"a4a1\" data-selectable-paragraph=\"\">Con toda esta evidencia, est\u00e1 cada vez m\u00e1s claro que al coronavirus le encantan las reuniones sociales y los espacios llenos de gente. Para aquellos de nosotros que nos gusta sentirnos parte de un grupo grande y conocer gente nueva, tal vez nos veamos obligados a no verlos durante los pr\u00f3ximos meses. Esto es especialmente cr\u00edtico si en estas reuniones nos encontramos con muchas personas desconocidas.<\/p>\n<h2 id=\"58ea\" data-selectable-paragraph=\"\">La red social<\/h2>\n<p id=\"ca64\" data-selectable-paragraph=\"\"><a href=\"https:\/\/arxiv.org\/pdf\/2003.05924.pdf\" rel=\"noopener nofollow\" target=\"_blank\">Otro art\u00edculo<\/a>\u00a0analiz\u00f3 c\u00f3mo se propagan realmente las enfermedades infecciosas en los grupos sociales. Cuanto m\u00e1s grande es el grupo, m\u00e1s r\u00e1pido se propaga la infecci\u00f3n a todo el grupo.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_-i1SuED3pliJlDK2-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136579\" title=\"0_-i1SuED3pliJlDK2 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_-i1SuED3pliJlDK2-copia.png\" alt=\"\" width=\"670\" height=\"412\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_-i1SuED3pliJlDK2-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_-i1SuED3pliJlDK2-copia-300x184.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"343a\" data-selectable-paragraph=\"\">Sigamos la l\u00ednea verde que dice n = 20, que representa un grupo con 20 personas. Esta l\u00ednea muestra que, a medida que aumenta la tasa de transmisi\u00f3n de un virus, tambi\u00e9n lo hace la proporci\u00f3n de individuos en el grupo que se infectan. Y lo hace m\u00e1s r\u00e1pido que la poblaci\u00f3n normal (la l\u00ednea de puntos inferior). Sin embargo, un grupo de 100 personas la mayor\u00eda de ellas contraer\u00e1 la infecci\u00f3n, incluso con una baja tasa de infecci\u00f3n.<\/p>\n<p id=\"0702\" data-selectable-paragraph=\"\">Comparemos un concierto de m\u00fasica con 10.000 personas con un aula de 20 individuos. En el concierto, hay una mayor probabilidad de que al menos una persona est\u00e9 infectada que en el aula. Adem\u00e1s de eso, cada persona interactuar\u00e1 con muchas m\u00e1s personas, mientras que en una clase tiene un l\u00edmite de 20. Y adem\u00e1s de eso, las personas en el concierto de m\u00fasica no se conocen entre s\u00ed. Provienen de grupos sociales muy diferentes, por lo que el virus se propagar\u00e1 a todos estos grupos, y estas personas llevar\u00e1n el virus a sus grupos y los infectar\u00e1n. Por el contrario, en el aula, ya que siempre ser re\u00fane el mismo grupo, si alguien se infecta, la infecci\u00f3n permanece en gran medida contenida en ese grupo.<\/p>\n<blockquote>\n<p id=\"99fe\" data-selectable-paragraph=\"\">Los grandes eventos no son solo peores que los peque\u00f1os. Son mucho, mucho peores.<\/p>\n<\/blockquote>\n<p id=\"a34c\" data-selectable-paragraph=\"\">En los pr\u00f3ximos meses, m\u00e1s y mejor investigaci\u00f3n podr\u00eda arrojar luz sobre exactamente de qu\u00e9 forma diferentes eventos de reuni\u00f3n social est\u00e1n afectando la propagaci\u00f3n del coronavirus. Mientras tanto, lo que podemos intuir es:<\/p>\n<ul>\n<li id=\"d9ba\" data-selectable-paragraph=\"\">Deben evitarse las reuniones sociales si muchas personas est\u00e1n cerca, cantan, hablan mucho o se mezclan.<\/li>\n<li id=\"9f33\" data-selectable-paragraph=\"\">Las \u00e1reas interiores y confinadas son mucho peores que las actividades al aire libre.<\/li>\n<li id=\"b478\" data-selectable-paragraph=\"\"><a href=\"https:\/\/www.erinbromage.com\/post\/the-risks-know-them-avoid-them\" rel=\"noopener nofollow\" target=\"_blank\">La duraci\u00f3n del evento importa<\/a>. Poco tiempo probablemente implique bajo riesgo. Si hablamos de horas el riesgo se incrementa.<\/li>\n<li id=\"c6b0\" data-selectable-paragraph=\"\">Mezclar diferentes grupos sociales es especialmente arriesgado.<\/li>\n<li id=\"f6be\" data-selectable-paragraph=\"\">Por el contrario, los peque\u00f1os eventos al aire libre donde las personas no hablan o interact\u00faan probablemente sean seguros, especialmente si se combinan con medidas como m\u00e1scaras, distanciamiento f\u00edsico e higiene.<\/li>\n<\/ul>\n<p id=\"36e7\" data-selectable-paragraph=\"\">\u00bfC\u00f3mo podemos usar estas ideas para decidir qu\u00e9 tipos de eventos permitir?<\/p>\n<h1 id=\"a1e9\" data-selectable-paragraph=\"\">Restricciones de las reuniones sociales: evitar la propagaci\u00f3n<\/h1>\n<p id=\"bbfc\" data-selectable-paragraph=\"\">Podemos establecer algunas reglas generales. Por ejemplo:<\/p>\n<ul>\n<li id=\"7c34\" data-selectable-paragraph=\"\">Los cines o los conciertos de m\u00fasica cl\u00e1sica son probablemente mucho m\u00e1s seguros que los conciertos de rock. En las primeras, un n\u00famero limitado de personas se sientan juntas, pero apenas interact\u00faan y no hablan. Tambi\u00e9n, si es necesario, pueden usar mascarillas, y pueden estar sentados a 2 metros de distancia. En un concierto de rock, es dif\u00edcil no cantar, moverse o interactuar con muchas personas a tu alrededor.<\/li>\n<li id=\"41e6\" data-selectable-paragraph=\"\">Las escuelas o reuniones de peque\u00f1as empresas con las mismas personas de forma regular son mucho m\u00e1s seguras que las grandes ferias, los viajes por trabajo o los grandes eventos deportivos. Si alguien se infecta en la red escolar, muchos miembros tambi\u00e9n pueden infectarse, pero al menos eso no se propaga a muchos otros lugares fuera de esa red.<\/li>\n<li id=\"11dd\" data-selectable-paragraph=\"\">Si se acerca una boda, cancele, posponga o celebre una peque\u00f1a ceremonia al aire libre donde las personas usen mascarillas, no se abrazen y eviten hablar lo m\u00e1s posible, especialmente de cerca. Dado que hacer todo eso ser\u00eda muy dif\u00edcil, es mucho m\u00e1s seguro posponerlo. En cualquier caso, si celebra un evento de boda, d\u00edgale a la abuela o a su primo diab\u00e9tico que los quiere mucho pero que realmente no deber\u00edan venir. Es un pobre sustituto, pero dadas las circunstancias, una videoconferencia es su \u00fanica opci\u00f3n segura.<\/li>\n<\/ul>\n<p id=\"e90a\" data-selectable-paragraph=\"\">Todo lo anterior son conclusiones muy preliminares basadas en evidencia actual, pero todav\u00eda escasa. Estas conclusiones cambiar\u00e1n. Pero con lo que sabemos, puedes imaginar lo arriesgado que puede ser un evento concreto. Lo que estamos tratando de hacer es llegar a un punto en el que podamos estimar cu\u00e1ntas infecciones suceder\u00e1n en ese evento.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_RdX7c_nDLjGMIm0r-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136580\" title=\"0_RdX7c_nDLjGMIm0r copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_RdX7c_nDLjGMIm0r-copia.png\" alt=\"\" width=\"670\" height=\"362\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_RdX7c_nDLjGMIm0r-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_RdX7c_nDLjGMIm0r-copia-300x162.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Nota: Todos estos n\u00fameros se estiman en funci\u00f3n de todo lo que he le\u00eddo. Estoy seguro de que est\u00e1n equivocados. Sin embargo, estas son las decisiones que tomamos hoy: conjeturas fundamentadas. Espero que esto estimule una nueva investigaci\u00f3n que cuantifique esto adecuadamente.<\/p>\n<div>\n<p id=\"9ad3\" data-selectable-paragraph=\"\">Esta tabla intenta evaluar cu\u00e1ntas infecciones pueden ser causadas por diferentes eventos. Podemos ver que ir al el cine puede causar solo una infecci\u00f3n, mientras que celebrar una gran feria puede causar 20,000.<\/p>\n<p id=\"9183\" data-selectable-paragraph=\"\">Este es solo un aspecto de la ecuaci\u00f3n: el coste de permitir reuniones sociales. El otro es el beneficio.<\/p>\n<h2 id=\"9890\" data-selectable-paragraph=\"\">El coste-beneficio de las reuniones sociales<\/h2>\n<p id=\"0677\" data-selectable-paragraph=\"\">Una vez que tenemos el coste por evento, las infecciones, se puede calcular el beneficio por evento y, finalmente, comparar manzanas con manzanas.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_FI5-C_hB9sDSYnRM-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136581\" title=\"0_FI5-C_hB9sDSYnRM copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_FI5-C_hB9sDSYnRM-copia.png\" alt=\"\" width=\"670\" height=\"330\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_FI5-C_hB9sDSYnRM-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_FI5-C_hB9sDSYnRM-copia-300x147.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<p id=\"bf8d\" data-selectable-paragraph=\"\">Una vez que tenemos una aproximaci\u00f3n que refleje la realidad, podemos llegar a muchas conclusiones:<\/p>\n<ol>\n<li id=\"feb7\" data-selectable-paragraph=\"\">\u00bfVale la pena permitir los eventos, seg\u00fan lo que sabemos sobre costes y beneficios? Por ejemplo, en este modelo, la \u00f3pera tiene un\u00a0<em>valor<\/em>\u00a0de 33k $ por infecci\u00f3n. Ese es el valor m\u00e1s alto por persona para cualquier evento (de nuevo, seguramente est\u00e9 mal estimado. Esto es ilustrativo). Pero, \u00bfcu\u00e1l es el coste por infecci\u00f3n para la sociedad? Si establecemos en base a nuestro sistema de atenci\u00f3n m\u00e9dica que el coste es de solo 10,000 $por infecci\u00f3n, entonces deber\u00edamos permitir la \u00f3pera, los teatros, los cines y las grandes conferencias y congresos, pero no deber\u00edamos permitir eventos como grandes ferias o conciertos de m\u00fasica, ya que su valor es debajo de 10,000 $ por infecci\u00f3n.<\/li>\n<li id=\"50d8\" data-selectable-paragraph=\"\">\u00bfC\u00f3mo podemos contabilizar el valor de algo que va m\u00e1s all\u00e1 del valor monetario estricto, como el valor psicol\u00f3gico, \u00e9tico o legal?<\/li>\n<li id=\"2a92\" data-selectable-paragraph=\"\">\u00bfC\u00f3mo cambia eso con los cambios en la prevalencia? \u00bfCon qu\u00e9 prevalencia puedo comenzar a permitir eventos? \u00bfC\u00f3mo cambia eso por regi\u00f3n? \u00bfPuedo llevar a cabo eventos en \u00e1reas donde hay muy pocos casos? \u00bfCon qu\u00e9 prevalencia puedo abrir qu\u00e9 tipos de eventos?<\/li>\n<li id=\"4e0c\" data-selectable-paragraph=\"\">\u00bfC\u00f3mo puedo modificar el riesgo de cada tipo de evento? \u00bfPuedo obligar a usar mascarillas? \u00bfPuedo obligar a las personas a interactuar solo con pocas personas?<\/li>\n<li id=\"3043\" data-selectable-paragraph=\"\">\u00bfC\u00f3mo cuantifico estos costes por infecci\u00f3n con los de los turistas que vienen a su pa\u00eds?<\/li>\n<\/ol>\n<p id=\"4929\" data-selectable-paragraph=\"\">Permitir estos eventos podr\u00eda merecer la pena si se toman medidas inteligentes.<\/p>\n<p id=\"77d8\" data-selectable-paragraph=\"\">Por ejemplo, si escanear un c\u00f3digo QR es obligatorio para acceder a un evento, y las personas necesitan tener habilitado el Bluetooth del m\u00f3vil en todo momento para registrar qui\u00e9n est\u00e1 cerca de qui\u00e9n, si luego descubrimos que una persona estaba infectada, podemos rastrear a todas las dem\u00e1s personas en el evento que estaba cerca, ponerse en contacto con ellos, realizarles el test de la PCR y aislarlos o ponerlos en cuarentena. Si hay controles de temperatura en la entrada, se puede reducir la cantidad de infecciones potenciales que entran (pero probablemente menos de la mitad). Si se puede lograr que las personas usen mascarillas, el evento podr\u00eda ser aceptable.<\/p>\n<h2 id=\"abfc\" data-selectable-paragraph=\"\">Lo mejor es enemigo de lo bueno: por qu\u00e9 se necesita un marco impreciso<\/h2>\n<p id=\"1055\" data-selectable-paragraph=\"\">Esto puede sonar extremadamente dif\u00edcil e impreciso, por lo que vale la pena detenerse por un momento, dar un paso atr\u00e1s y reflexionar sobre las razones que nos llevan a plantear esto.<\/p>\n<p id=\"dfe7\" data-selectable-paragraph=\"\">La mayor\u00eda de los gestores p\u00fablicos est\u00e1n comenzando a intuir todo esto. Incluso si no hacen los c\u00e1lculos formalmente, est\u00e1n haciendo este c\u00e1lculo mentalmente. Lo \u00fanico que estamos haciendo es extraerlo de sus cabezas y permitir que las personas lo debatan empleando un lenguaje com\u00fan.<\/p>\n<p id=\"3029\" data-selectable-paragraph=\"\">Cuando un grupo de cient\u00edficos y pol\u00edticos se re\u00fane para decidir qu\u00e9 tama\u00f1o de multitud permitir\u00e1n, \u00bfde qu\u00e9 crees que hablan? De la relaci\u00f3n coste-beneficio, aunque es posible que no se den cuenta.<\/p>\n<blockquote>\n<p id=\"6085\" data-selectable-paragraph=\"\">Si prohibimos eventos por encima de 1,000 personas, estamos prohibiendo muchos eventos deportivos, ferias y m\u00fasica. Eso es muy duro.\u201d<\/p>\n<p id=\"96f8\" data-selectable-paragraph=\"\">\u201cS\u00ed, pero estos son los eventos que causan la mayor\u00eda de las infecciones\u201d.<\/p>\n<p id=\"83aa\" data-selectable-paragraph=\"\">\u201cPero, \u00bfqu\u00e9 pasa con todos los trabajos que se van a perder?\u201d<\/p>\n<p id=\"988b\" data-selectable-paragraph=\"\">\u201c\u00a1Piensa en todas las muertes que vas a prevenir!\u201d<\/p>\n<\/blockquote>\n<p id=\"896d\" data-selectable-paragraph=\"\">El valor de formalizar todo esto en una relaci\u00f3n coste-beneficio no es preciso. Con los datos que tenemos la precisi\u00f3n es imposible. El valor es poner todos nuestros prejuicios y datos, conocimientos, ideas, objetivos, problemas y soluciones en un solo lugar, frente a todos, con un lenguaje com\u00fan, para que todos podamos discutirlo y llegar a la mejor conjetura sobre lo que es m\u00e1s valioso que la sociedad pueda hacer.<\/p>\n<h2 id=\"e75f\" data-selectable-paragraph=\"\">\u00bfQu\u00e9 negocios debemos abrir o cerrar?<\/h2>\n<p id=\"bd7a\" data-selectable-paragraph=\"\">Los investigadores ya est\u00e1n aplicando este enfoque para determinar qu\u00e9 empresas deben abrir primero:<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kkEPNP9fGfpFKSNp-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136582\" title=\"0_kkEPNP9fGfpFKSNp copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kkEPNP9fGfpFKSNp-copia.png\" alt=\"\" width=\"670\" height=\"418\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kkEPNP9fGfpFKSNp-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_kkEPNP9fGfpFKSNp-copia-300x187.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Fuente. Notas: el peligro se calcula teniendo en cuenta la cantidad de visitas, la cantidad de visitantes \u00fanicos y las horas de visitas por persona que superan los dos umbrales de densidad. Por lo tanto, los bancos son bastante seguros porque pocas personas los visitan, aquellos que tienden a ser iguales todo el tiempo y no pasan mucho tiempo en ellos. Por el contrario, a gimnasios y caf\u00e9s van muchas personas diferentes, y pasan all\u00ed mucho tiempo, en el caso de los caf\u00e9s, hablando mucho cara a cara. La importancia proviene de una combinaci\u00f3n de cu\u00e1nto les importa a las personas las diferentes empresas seg\u00fan las encuestas y cu\u00e1nta riqueza generan en funci\u00f3n del empleo y los ingresos. Tenga en cuenta que este modelo no es perfecto porque no tiene en cuenta las conversaciones cara a cara o el canto. Otros modelos deber\u00edan explicar eso, e idealmente para otros aspectos como la evidencia emp\u00edrica.<\/p>\n<p id=\"efb6\" data-selectable-paragraph=\"\">Seg\u00fan este an\u00e1lisis (que tiene en cuenta datos del mundo real, como la movilidad, las preferencias de los consumidores y las estad\u00edsticas gubernamentales), los bancos y las tiendas de comestibles son los m\u00e1s importantes mantener abiertos, mientras que los gimnasios o cafeter\u00edas deben permanecer cerrados y ser los \u00faltimos en reabrir. No es perfecto, pero permite jerarquizar el orden de reapertura:<\/p>\n<ul>\n<li id=\"83ed\" data-selectable-paragraph=\"\">Si estuvieran cerrados, los bancos, las compa\u00f1\u00edas financieras, los supermercados y las tiendas generales deber\u00edan ser los primeros en reabrir<\/li>\n<li id=\"e78c\" data-selectable-paragraph=\"\">Despu\u00e9s de eso, se volver\u00eda a abrir los grandes almacenes, colegios y universidades, tiendas de ropa y calzado, y concesionarios de autom\u00f3viles y talleres mec\u00e1nicos.<\/li>\n<li id=\"e215\" data-selectable-paragraph=\"\">Luego vendr\u00edan tiendas de muebles y art\u00edculos para el hogar, electr\u00f3nica, peluquer\u00edas y salones, ferreter\u00edas, lugares de culto, casinos, tiendas de suministros de oficina y cines.<\/li>\n<li id=\"25d9\" data-selectable-paragraph=\"\">Luego vienen los parques de atracciones, las librer\u00edas, los museos, las tiendas de mascotas y suministros, y las tiendas de licores y tabaco.<\/li>\n<li id=\"04d7\" data-selectable-paragraph=\"\">Los \u00faltimos en abrir deber\u00edan ser las tiendas de art\u00edculos deportivos, gimnasios, cafeter\u00edas y bares.<\/li>\n<\/ul>\n<p id=\"7bb3\" data-selectable-paragraph=\"\">Curiosamente, el an\u00e1lisis confirma los tipos de empresas que los pa\u00edses ya\u00a0<a href=\"https:\/\/papers.ssrn.com\/sol3\/papers.cfm?abstract_id=3579678\" rel=\"noopener nofollow\" target=\"_blank\">han priorizado de forma intuitiva<\/a>, incluso con datos imperfectos.<\/p>\n<p id=\"63e4\" data-selectable-paragraph=\"\">Modelos como este a\u00fan no son perfectos. Por ejemplo, no estoy de acuerdo con su conclusi\u00f3n sobre los restaurantes. Es cierto que los restaurantes de comida r\u00e1pida deber\u00edan abrir antes que los restaurantes cl\u00e1sicos, ya que las personas se quedan mucho menos tiempo y hablan menos, pero este documento sugiere que podr\u00edamos reabrir algunos de ellos a plena capacidad desde el principio. Eso se debe a que no tienen en cuenta el gran peligro que se genera en los restaurantes de personas sentadas cara a cara durante largos per\u00edodos de tiempo. Tampoco tienen en cuenta las formas creativas en que las empresas pueden adaptarse para volver a abrir de forma segura. Los gimnasios, por ejemplo, podr\u00edan limitar la asistencia, reorganizar el espacio en el suelo, requerir que las personas mantengan una distancia de 2 metros y \/ o tener a alguien en el personal que mantenga todos los espacios limpios a tiempo completo, como en este gimnasio:<\/p>\n<p data-selectable-paragraph=\"\">[youtube]https:\/\/youtu.be\/gtUYZsBaIkI[\/youtube]<\/p>\n<p id=\"b4d1\" data-selectable-paragraph=\"\">Las empresas tambi\u00e9n podr\u00edan imponer restricciones m\u00e1s estrictas durante el horario comercial con horas exclusivas para clientes de m\u00e1s edad. Este es solo un ejemplo, y al final, la pregunta m\u00e1s l\u00f3gica podr\u00eda no ser \u201c\u00bfQu\u00e9 empresas deber\u00edan abrir?\u201d sino \u201c\u00bfC\u00f3mo pueden reabrir las empresas de manera segura?\u201d<\/p>\n<h2 id=\"f92f\" data-selectable-paragraph=\"\">Familias y Transporte.<\/h2>\n<p id=\"0657\" data-selectable-paragraph=\"\">En China, fuera de Hubei, alrededor del\u00a0<a href=\"https:\/\/www.medrxiv.org\/content\/10.1101\/2020.04.04.20053058v1.full.pdf\" rel=\"noopener nofollow\" target=\"_blank\">80% de las infecciones<\/a>\u00a0involucraban familias y contactos cercanos en el hogar. Este es seguramente un efecto de las cuarentenas en el hogar, ya que las reuniones masivas fueron limitadas. Pero ilustra cu\u00e1nto se propaga el virus en las familias.<\/p>\n<p id=\"1cf3\" data-selectable-paragraph=\"\">Entre estos contactos, el mayor riesgo es la transmisi\u00f3n a los\u00a0<a href=\"https:\/\/academic.oup.com\/cid\/advance-article\/doi\/10.1093\/cid\/ciaa450\/5821281\" rel=\"noopener nofollow\" target=\"_blank\">c\u00f3nyuges<\/a>: el 28% de ellos terminan infectados, en comparaci\u00f3n con el 17% de otros adultos en el hogar y solo el 4% de los ni\u00f1os menores de 18 a\u00f1os.<\/p>\n<p id=\"cb81\" data-selectable-paragraph=\"\">Sin embargo, probablemente podamos sacar conclusiones que sean aplicables en otros lugares:<\/p>\n<ul>\n<li id=\"19aa\" data-selectable-paragraph=\"\">Detener las infecciones en el hogar puede tener un efecto cr\u00edtico en la epidemia.<\/li>\n<li id=\"7812\" data-selectable-paragraph=\"\">No es muy probable que contraiga el virus de personas aleatorias en la calle.<\/li>\n<li id=\"b467\" data-selectable-paragraph=\"\">Sin embargo, es muy probable que lo contagie su c\u00f3nyuge, sus hijos, sus padres o los amigos que visita.<\/li>\n<\/ul>\n<p id=\"d14e\" data-selectable-paragraph=\"\">El\u00a0<a href=\"https:\/\/www.thelancet.com\/journals\/laninf\/article\/PIIS1473-3099(20)30287-5\/fulltext\" rel=\"noopener nofollow\" target=\"_blank\">transporte<\/a>\u00a0tambi\u00e9n tiene un impacto, aunque no est\u00e1 claro si se debe a viajar con miembros de la familia o confinado con otras personas.<\/p>\n<p id=\"9e77\" data-selectable-paragraph=\"\">As\u00ed que trate a los miembros de su familia con precauci\u00f3n. Intente evitar interactuar f\u00edsicamente con miembros que est\u00e1n en riesgo. Ll\u00e1melos en vez de visitarlos. Si alguien tiene s\u00edntomas, trate de aislar a esa persona. Es dif\u00edcil hacer esto con un miembro de la familia, pero la alternativa puede ser m\u00e1s enfermedad, una visita al hospital o incluso la muerte. Si hay s\u00edntomas, evite besos, abrazos o incluso hablar cara a cara sin una m\u00e1scara.<\/p>\n<p id=\"9a6c\" data-selectable-paragraph=\"\"><em>Gracias\u00a0<\/em><a href=\"https:\/\/twitter.com\/mugecevik\" rel=\"noopener nofollow\" target=\"_blank\"><em>Dr. Muge Cevik<\/em><\/a><em>\u00a0por su\u00a0<\/em><a href=\"https:\/\/twitter.com\/mugecevik\/status\/1257392347010215947?s=20\" rel=\"noopener nofollow\" target=\"_blank\"><em>resumen de trabajos<\/em><\/a><em>.<\/em><\/p>\n<h2 id=\"af1b\" data-selectable-paragraph=\"\">\u00bfQu\u00e9 hacemos con las escuelas?<\/h2>\n<p id=\"deab\" data-selectable-paragraph=\"\">El papel de los ni\u00f1os en la epidemia de coronavirus no est\u00e1 claro. \u00bfQu\u00e9 posibilidades tienen de contraer y transmitir el coronavirus? \u00bfC\u00f3mo les afecta?<\/p>\n<p id=\"36c2\" data-selectable-paragraph=\"\">Por un lado, parece que se infectan con menos frecuencia y, cuando lo est\u00e1n,\u00a0<a href=\"https:\/\/www.worldometers.info\/coronavirus\/coronavirus-age-sex-demographics\/\" rel=\"noopener nofollow\" target=\"_blank\">no fallecen\u00a0<\/a>o\u00a0<a href=\"https:\/\/www.nature.com\/articles\/d41586-020-01354-0\" rel=\"noopener nofollow\" target=\"_blank\">infectan mucho a otras personas<\/a>. Como resultado,\u00a0<a href=\"https:\/\/www.thelancet.com\/journals\/lanchi\/article\/PIIS2352-4642(20)30095-X\/fulltext\" rel=\"noopener nofollow\" target=\"_blank\">parece que el cierre de escuelas solo tendr\u00eda un peque\u00f1o efecto en limitar la propagaci\u00f3n del virus<\/a>. Por otro lado, no estamos seguros, porque la mayor\u00eda de los pa\u00edses las cerraron, por lo que es dif\u00edcil de establecer comparaciones, pero hay algunas noticias recientes\u00a0<a href=\"https:\/\/www.nbcnewyork.com\/news\/local\/more-local-hospitals-report-children-with-possible-covid-19-health-consequences\/2399514\/?_osource=SocialFlowFB_NYBrand&amp;fbclid=IwAR1dYw5NIHzoVlFystMQ_o9XvSkStCKRDy6g0YyEvmNIxnrkR-O893uNMQM\" rel=\"noopener nofollow\" target=\"_blank\">de ni\u00f1os con s\u00edntomas inusuales<\/a>, y hay informes de\u00a0<a href=\"https:\/\/nationalpost.com\/news\/canada\/twelve-children-infected-with-covid-19-in-quebecs-first-daycare-outbreak\" rel=\"noopener nofollow\" target=\"_blank\">algunos brotes en guarder\u00edas.<\/a><\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_C-ZWuuNCIwKL0juf-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136583\" title=\"0_C-ZWuuNCIwKL0juf copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_C-ZWuuNCIwKL0juf-copia.png\" alt=\"\" width=\"670\" height=\"447\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_C-ZWuuNCIwKL0juf-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_C-ZWuuNCIwKL0juf-copia-300x200.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Un pa\u00eds que solo cerr\u00f3 en unas pocas regiones y solo por unas pocas semanas es\u00a0<a href=\"https:\/\/www.theguardian.com\/world\/2020\/mar\/16\/why-australia-is-not-shutting-schools-to-help-control-the-spread-of-coronavirus\" rel=\"noopener nofollow\" target=\"_blank\">Australia<\/a>, que ahora ha controlado la epidemia.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0__V7G-l4t4ccYloE-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136584\" title=\"0__V7G--l4t4ccYloE copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0__V7G-l4t4ccYloE-copia.png\" alt=\"\" width=\"670\" height=\"517\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0__V7G-l4t4ccYloE-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0__V7G-l4t4ccYloE-copia-300x231.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"0756\" data-selectable-paragraph=\"\"><a href=\"https:\/\/www.theguardian.com\/world\/2020\/mar\/16\/why-australia-is-not-shutting-schools-to-help-control-the-spread-of-coronavirus\" rel=\"noopener nofollow\" target=\"_blank\">Seg\u00fan su primer ministro<\/a>, el comit\u00e9 de expertos recomend\u00f3 mantener abiertas las escuelas porque no afectar\u00eda en gran medida a la propagaci\u00f3n del virus, incluso podr\u00eda ser mejor, ya que los ni\u00f1os no lo estar\u00edan propagando a trav\u00e9s de muchos grupos sociales diferentes (principalmente su aula \/ escuelas), y podr\u00eda ser beneficioso para los padres poder trabajar.<\/p>\n<p id=\"7815\" data-selectable-paragraph=\"\">\u00bfCu\u00e1l es el impacto en la educaci\u00f3n? Sabemos que los estudiantes que perdieron a\u00f1os de clase durante la Segunda Guerra Mundial tuvieron\u00a0<a href=\"https:\/\/uh.edu\/~adkugler\/Ichino%26Winter-Ebmer.pdf\" rel=\"noopener nofollow\" target=\"_blank\">reducciones dr\u00e1sticas en sus salarios<\/a>\u00a0de por vida. Hoy en d\u00eda,\u00a0<a href=\"https:\/\/www.economist.com\/international\/2020\/04\/30\/closing-schools-for-covid-19-does-lifelong-harm-and-widens-inequality\" rel=\"noopener nofollow\" target=\"_blank\">cada a\u00f1o de educaci\u00f3n incrementa en un 10% las expectativas de ganancias anuales<\/a>. El cierre de escuelas tambi\u00e9n tiene un efecto excesivo en la desigualdad, ya que los ni\u00f1os de padres m\u00e1s ricos tienen m\u00e1s apoyo, mientras que los que provienen de familias m\u00e1s pobres, alimentados en la escuela, pueden exponerse a no comer en casa.<\/p>\n<p id=\"6a5c\" data-selectable-paragraph=\"\">Dado todo eso, probablemente sea una buena idea reabrir las escuelas con cautela.\u00a0<a href=\"https:\/\/www.economist.com\/leaders\/2020\/04\/30\/when-easing-lockdowns-governments-should-open-schools-first\" rel=\"noopener nofollow\" target=\"_blank\">The Economist sugiere un orden de apertura razonable<\/a>:<\/p>\n<ol>\n<li id=\"641b\" data-selectable-paragraph=\"\">Comience con ni\u00f1os peque\u00f1os, abriendo guarder\u00edas, pre-inf\u00e1ntiles, guarder\u00edas y escuelas primarias. Estos ni\u00f1os est\u00e1n aprendiendo m\u00e1s, son los menos afectados por el coronavirus, sus padres obtienen el mayor alivio al poder trabajar y su edad es primordial para reducir la desigualdad a trav\u00e9s del aprendizaje y la nutrici\u00f3n (<em>nota: conflicto de intereses. Tengo tres ni\u00f1os peque\u00f1os<\/em>)<\/li>\n<li id=\"f18f\" data-selectable-paragraph=\"\">Contin\u00fae con los ni\u00f1os mayores, especialmente aquellos con ex\u00e1menes importantes: son m\u00e1s capaces de seguir las pautas de distanciamiento f\u00edsico, y su futuro est\u00e1 m\u00e1s en juego.<\/li>\n<li id=\"d432\" data-selectable-paragraph=\"\">Se deben tomar medidas para reducir la propagaci\u00f3n de la enfermedad, como realizar controles de temperatura, test para educadores (e idealmente ni\u00f1os), reducciones en el tama\u00f1o de las clases e, idealmente, la asistencia podr\u00eda dividirse en turnos o d\u00edas.<\/li>\n<\/ol>\n<p id=\"4487\" data-selectable-paragraph=\"\">Los colegios y universidades son diferentes de las escuelas. Re\u00fanen a muchas personas de diferentes redes sociales. Los estudiantes se mezclan en entornos de alta densidad donde se tocan y hablan entre ellos. Esto es cierto para casi todos los aspectos de sus vidas, desde aulas hasta grupos de estudio, dormitorios o fiestas. Los estudiantes tambi\u00e9n son mayores que los ni\u00f1os, por lo que son m\u00e1s susceptibles al virus y son m\u00e1s capaces de estudiar a trav\u00e9s del aprendizaje online.<\/p>\n<p id=\"ad59\" data-selectable-paragraph=\"\">Como resultado, el riesgo es probablemente mayor que para las escuelas, y el beneficio podr\u00eda ser menor. A pesar de eso, las universidades est\u00e1n en apuros. Si no abren en oto\u00f1o,\u00a0<a href=\"https:\/\/www.nytimes.com\/2020\/04\/26\/opinion\/coronavirus-colleges-universities.html\" rel=\"noopener nofollow\" target=\"_blank\">pierden la mitad de sus ingresos anuales<\/a>. Si abren solo en l\u00ednea, est\u00e1n argumentando que el aprendizaje en el campus no es tan \u00fatil como sol\u00edan decir, lo que ser\u00e1 dif\u00edcil de rechazar una vez que puedan aceptar libremente a los estudiantes en el campus.<\/p>\n<p id=\"24b7\" data-selectable-paragraph=\"\">Es probable que esto sea una ventaja para las escuelas online, mientras que la mayor\u00eda con sede en el campus y con dificultades financieras existentes podr\u00edan tener dificultades para permanecer abiertas.<\/p>\n<p id=\"5b53\" data-selectable-paragraph=\"\">Por eso quieren abrir en oto\u00f1o.\u00a0<a href=\"https:\/\/eoss.asu.edu\/health\/announcements\/coronavirus\/faqs\" rel=\"noopener nofollow\" target=\"_blank\">Har\u00e1n lo que sea necesario<\/a>\u00a0para abrir el campus mientras reducen la propagaci\u00f3n de la enfermedad.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_WS6Fh6Y6dAbUUu3D-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136585\" title=\"0_WS6Fh6Y6dAbUUu3D copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_WS6Fh6Y6dAbUUu3D-copia.png\" alt=\"\" width=\"670\" height=\"445\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_WS6Fh6Y6dAbUUu3D-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_WS6Fh6Y6dAbUUu3D-copia-300x199.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<p id=\"804a\" data-selectable-paragraph=\"\">Es posible que puedan hacerlo, ya que los estudiantes son m\u00e1s capaces de seguir las reglas de distanciamiento social, mientras que las universidades est\u00e1n en condiciones de cambiar sus circunstancias de entorno para limitar la propagaci\u00f3n del virus y hacer cumplir a todos el uso de aplicaciones en tel\u00e9fonos inteligentes en el campus, haciendo que el seguimiento de contactos, el aislamiento y las cuarentenas sean mucho m\u00e1s f\u00e1ciles (<em>nota: conflicto de intereses. Trabajo en\u00a0<\/em><a href=\"https:\/\/www.coursehero.com\/\" rel=\"noopener nofollow\" target=\"_blank\"><em>Course Hero<\/em><\/a><em>, una compa\u00f1\u00eda que ayuda a los estudiantes de colegio y universidad a estudiar online<\/em>)<\/p>\n<h2 id=\"c41e\" data-selectable-paragraph=\"\">Resumen de las restricciones de reuniones sociales.<\/h2>\n<p id=\"a97e\" data-selectable-paragraph=\"\">Esto es lo que hemos aprendido:<\/p>\n<ul>\n<li id=\"aca2\" data-selectable-paragraph=\"\">El coronavirus se propaga principalmente en ambientes cerrados y cerrados donde las personas pasan mucho tiempo juntas hablando, cantando, respirando o toc\u00e1ndose.<\/li>\n<li id=\"c05e\" data-selectable-paragraph=\"\">Los grandes eventos que mezclan muchos grupos sociales son m\u00e1s arriesgados. Deber\u00edan ser limitados. Esto es especialmente cierto en cosas como ferias de negocios y festivales de m\u00fasica, mientras que los cines y las \u00f3peras podr\u00edan estar bien si se respeta el distanciamiento f\u00edsico.<\/li>\n<li id=\"5c79\" data-selectable-paragraph=\"\">Deber\u00edamos escalonar la reapertura de las empresas. La prioridad m\u00e1s alta siempre son los supermercados, bancos, servicios financieros y tiendas en general, mientras que la m\u00e1s baja son los gimnasios, cafeter\u00edas, pasteler\u00edas donde se come, bares y clubes.<\/li>\n<li id=\"31e2\" data-selectable-paragraph=\"\">Los lugares de trabajo de alta densidad son una receta para un desastre contagioso. Se deben tomar medidas de distanciamiento f\u00edsico, como barreras f\u00edsicas, controles de temperatura, turnos escalonados, trabajo remoto o al aire libre, si est\u00e1 disponible.<\/li>\n<li id=\"3dc4\" data-selectable-paragraph=\"\">Ten mucho cuidado con la familia. Es m\u00e1s probable que contraiga el virus de su pareja, otros adultos en su hogar o amigos. El mayor riesgo es en casa o durante el tr\u00e1nsito. Evite ver a los abuelos y aislarse lo m\u00e1s que pueda si tiene s\u00edntomas.<\/li>\n<li id=\"6b55\" data-selectable-paragraph=\"\">La reapertura de las escuelas debe ser una prioridad, siempre teniendo cuidado y comenzando con los ni\u00f1os m\u00e1s peque\u00f1os.<\/li>\n<\/ul>\n<blockquote>\n<p id=\"bb0d\" data-selectable-paragraph=\"\">Los pa\u00edses deben evitar la siembra y la propagaci\u00f3n.<\/p>\n<\/blockquote>\n<p id=\"89fe\" data-selectable-paragraph=\"\">Hemos revisado c\u00f3mo detener la propagaci\u00f3n del coronavirus en una comunidad limitando las reuniones sociales. Ahora tambi\u00e9n debemos asegurarnos de no introducir en la comunidad casos del extranjero. Veamos las restricciones de viaje.<\/p>\n<p id=\"9f00\" data-selectable-paragraph=\"\"><em>Esta secci\u00f3n ha sido fuertemente influida por el trabajo realizado por Barthold Albrecht. \u00a1Gracias!<\/em><\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_z1J6I14K7TZfZuEB-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136586\" title=\"0_z1J6I14K7TZfZuEB copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_z1J6I14K7TZfZuEB-copia.png\" alt=\"\" width=\"670\" height=\"337\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_z1J6I14K7TZfZuEB-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_z1J6I14K7TZfZuEB-copia-300x150.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"a845\" data-selectable-paragraph=\"\">El pa\u00eds controlaba las semillas de China muy bien desde el principio. Como puede ver, algunas semillas azules en enero se detuvieron despu\u00e9s de la prohibici\u00f3n de los visitantes chinos. Pero fue demasiado lento para detener a los visitantes de pa\u00edses como Italia, Francia, Espa\u00f1a y Alemania en la primera mitad de marzo, y luego el Reino Unido, los EE. UU. Y otros pa\u00edses m\u00e1s tarde. El resultado es que estos pocos casos azules crearon el brote (en rosa) justo despu\u00e9s de eso.<\/p>\n<p id=\"a205\" data-selectable-paragraph=\"\">Por el contrario, como vimos en la\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/05\/25\/136297\" rel=\"noopener\" target=\"_blank\">Parte 1<\/a>, Taiw\u00e1n estaba muy por encima de las prohibiciones de viaje, actualiz\u00e1ndolas diariamente. El pa\u00eds prohibi\u00f3 a los viajeros de Wuhan el d\u00eda de los bloqueos, y a todos los ciudadanos chinos dos semanas despu\u00e9s, el 6 de febrero. El 14 de marzo, todos los visitantes europeos residentes tuvieron que ponerse en cuarentena durante dos semanas a su llegada. Se ampli\u00f3 a todos los visitantes tres d\u00edas despu\u00e9s, y para el 19 de marzo, todos los extranjeros no residentes simplemente fueron prohibidos. A partir del 18 de abril, los viajes no esenciales estaban prohibidos y todos los viajeros que ingresen deben pasar por cuarentena durante 14 d\u00edas.<\/p>\n<p id=\"ed1c\" data-selectable-paragraph=\"\">Corea del Sur ten\u00eda una prohibici\u00f3n inversa. \u201cGracias\u201d a su epidemia temprana,\u00a0<a href=\"http:\/\/news.chosun.com\/site\/data\/html_dir\/2020\/03\/20\/2020032000121.html\" rel=\"noopener nofollow\" target=\"_blank\">171 pa\u00edses prohibieron los viajes<\/a>\u00a0hacia y desde el pa\u00eds, lo que elimin\u00f3 una gran cantidad de semillas potenciales.<\/p>\n<p id=\"0770\" data-selectable-paragraph=\"\">Otro pa\u00eds que ha manejado la crisis oficialmente realmente bien es Vietnam. Declar\u00f3\u00a0<a href=\"https:\/\/en.vietnamplus.vn\/vietnam-declares-novel-coronavirus-epidemic\/168021.vnp\" rel=\"noopener nofollow\" target=\"_blank\">la situaci\u00f3n como una epidemia<\/a>\u00a0el 1 de febrero, tan pronto como descubrieron la propagaci\u00f3n en la comunidad. Prohibieron todos los vuelos desde China. Luego prohibieron r\u00e1pidamente los vuelos desde la mayor\u00eda de los pa\u00edses. De hecho, fueron tan r\u00e1pidos que cerraron el pa\u00eds a los visitantes de Espa\u00f1a, Francia y el Reino Unido antes de que esos pa\u00edses anunciaran sus bloqueos. A partir del 18 de abril, el pa\u00eds tiene 270 casos, en una poblaci\u00f3n de 95 millones.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_QxOa9ooONmGdUh0r-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136587\" title=\"0_QxOa9ooONmGdUh0r copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_QxOa9ooONmGdUh0r-copia.png\" alt=\"\" width=\"670\" height=\"347\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_QxOa9ooONmGdUh0r-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_QxOa9ooONmGdUh0r-copia-300x155.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\">Este gr\u00e1fico muestra cu\u00e1ndo diferentes pa\u00edses de Asia Oriental tomaron diferentes medidas de restricci\u00f3n de viaje. Cada pa\u00eds tiene una franja, y las l\u00edneas de colores muestran restricciones dirigidas a diferentes \u00e1reas geogr\u00e1ficas: Hubei, China, Corea del Sur, el norte de Italia, Europa y el mundo. Es realmente dif\u00edcil graficar esto, porque hay un n\u00famero infinito de medidas que se pueden tomar, desde controles de temperatura hasta declaraciones de salud, restricciones regionales de viaje, cuarentenas para ciertos visitantes, excepciones para otros \u2026 Pero tratamos de simplificar lo m\u00e1s posible lo que estaba m\u00e1s cerca de una cuarentena obligatoria para todos los visitantes de un \u00e1rea determinada o una prohibici\u00f3n total, a pesar de las exenciones frecuentes, como los diplom\u00e1ticos u otros.<\/p>\n<p data-selectable-paragraph=\"\">En este gr\u00e1fico, podemos ver el momento en el que los distintos pa\u00edses de Asia Oriental tomaron diferentes medidas sobre el control en los viajes. Cada l\u00ednea representa una restricci\u00f3n desde un \u00e1rea diferente, desde Hubei hasta el mundo. Podemos comprobar que Taiw\u00e1n y Vietnam, que tienen menos de 1,000 casos, restringieron los viajes desde la mayor\u00eda de los otros pa\u00edses con m\u00e1s rapidez.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_6FCHIEiys0hI9_1Z-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136588\" title=\"0_6FCHIEiys0hI9_1Z copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_6FCHIEiys0hI9_1Z-copia.png\" alt=\"\" width=\"670\" height=\"422\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_6FCHIEiys0hI9_1Z-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_6FCHIEiys0hI9_1Z-copia-300x188.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p id=\"4920\" data-selectable-paragraph=\"\">Singapur fue razonablemente r\u00e1pido, pero no lo suficientemente r\u00e1pido como para detener las semillas, principalmente de Bangladesh e Indonesia. La suerte tambi\u00e9n tiene un papel: si Singapur no hubiera sido tan cosmopolita, podr\u00eda no haber tenido este brote. Afortunadamente, la incre\u00edble gesti\u00f3n del pa\u00eds ya redujo el brote.<\/p>\n<p id=\"9e34\" data-selectable-paragraph=\"\">Corea del Sur es un caso especial: aunque no siempre fue muy r\u00e1pido restringir los viajes, s\u00ed restringi\u00f3 los viajes desde China r\u00e1pidamente. A fines de febrero, docenas de pa\u00edses ya hab\u00edan prohibido viajar\u00a0<em>desde<\/em>\u00a0Corea del Sur, lo que tambi\u00e9n hac\u00eda mucho m\u00e1s dif\u00edcil para los viajeros ir\u00a0<em>al<\/em>\u00a0pa\u00eds. Esta \u201cprohibici\u00f3n inversa\u201d seguramente ayud\u00f3 al pa\u00eds.<\/p>\n<p id=\"b3d6\" data-selectable-paragraph=\"\">Aunque Tailandia fue m\u00e1s lenta, ten\u00eda algunas medidas, como controles de temperatura y declaraciones de salud. Tambi\u00e9n podr\u00eda haber tenido suerte y as\u00ed evitar m\u00e1s siembra.<\/p>\n<p id=\"5492\" data-selectable-paragraph=\"\">Jap\u00f3n fue en general el m\u00e1s lento de todos, lo que probablemente explica el lento crecimiento en los casos hasta febrero y marzo, con el brote final a fines de marzo. Afortunadamente, el pa\u00eds tambi\u00e9n ha reaccionado bien y parece que ahora est\u00e1 controlando el brote .<\/p>\n<p id=\"aecc\" data-selectable-paragraph=\"\">Con todo esto, podemos ver que los pa\u00edses de Asia oriental que restringieron los viajes m\u00e1s r\u00e1pido tambi\u00e9n fueron en general los que tuvieron menos siembra y, por lo tanto, menos contagios.<\/p>\n<p id=\"5d8f\" data-selectable-paragraph=\"\">El problema, obviamente, es que las prohibiciones de viaje son muy caras. Para algunos pa\u00edses, muy dependientes del turismo, viajar es vital.<\/p>\n<h2 id=\"02e9\" data-selectable-paragraph=\"\">Prohibiciones de viaje comparadas con las cuarentenas<\/h2>\n<p id=\"1a58\" data-selectable-paragraph=\"\">El turismo representa ~\u00a0<a href=\"https:\/\/www.statista.com\/statistics\/1099933\/travel-and-tourism-share-of-gdp\/\" rel=\"noopener nofollow\" target=\"_blank\">10% del PIB mundial<\/a>. Para un pa\u00eds como Espa\u00f1a, es\u00a0<a href=\"https:\/\/www.theolivepress.es\/spain-news\/2019\/03\/09\/one-in-every-seven-euros-into-spains-economy-comes-from-tourism\/\" rel=\"noopener nofollow\" target=\"_blank\">el 15%.<\/a>\u00a0El pa\u00eds recibe\u00a0<a href=\"http:\/\/www.xinhuanet.com\/english\/2019-02\/02\/c_137793067.htm\" rel=\"noopener nofollow\" target=\"_blank\">83 millones de visitantes al a\u00f1o<\/a>. El bloqueo en marzo y abril probablemente le haya costado al pa\u00eds el 2% del PIB solo en 2 meses. Necesita desesperadamente abrir el turismo ahora: el 6% de todo el PIB proviene del turismo entre junio y septiembre. \u00bfPodr\u00e1 Espa\u00f1a abrir a tiempo? \u00bfC\u00f3mo deber\u00eda pensar el pa\u00eds sobre las restricciones de viaje?<\/p>\n<p id=\"b4f6\" data-selectable-paragraph=\"\">Existen muchos tipos diferentes de restricciones de viaje, como controles de temperatura, declaraciones de salud o tests, pero dos tienen un impacto importante en la siembra de infecciones: cuarentenas y prohibiciones directas. Las cuarentenas requieren que los visitantes est\u00e9n recluidos durante dos semanas. Las prohibiciones simplemente les impiden entrar en el pa\u00eds.<\/p>\n<p id=\"87d1\" data-selectable-paragraph=\"\">Si la cuarentena es tan severa como en\u00a0<a href=\"https:\/\/medium.com\/@tomaspueyo\/coronavirus-learning-how-to-dance-b8420170203e\" rel=\"noopener\" target=\"_blank\">Taiw\u00e1n<\/a>, es razonable suponer que muy pocas infecciones provendr\u00edan de los viajeros.<\/p>\n<p id=\"949c\" data-selectable-paragraph=\"\">Desafortunadamente, esto es dif\u00edcil de asumir y poco pr\u00e1ctico para la mayor\u00eda de los turistas. \u00bfQui\u00e9n quiere pasar dos semanas de vacaciones encerradas en una habitaci\u00f3n, solo para pasar dos semanas m\u00e1s en cuarentena cuando vuelvan a casa?<\/p>\n<p id=\"e6f1\" data-selectable-paragraph=\"\">Si pa\u00edses tur\u00edsticos como Espa\u00f1a est\u00e1n entrando en el baile, deben limitar la siembra desde el extranjero. Por ejemplo, tomemos viajeros del Reino Unido. En 2019,\u00a0<a href=\"https:\/\/www.statista.com\/statistics\/447742\/yearly-number-of-tourists-with-residence-in-the-united-kingdom-spain\/\" rel=\"noopener nofollow\" target=\"_blank\">18 millones de brit\u00e1nicos fueron a Espa\u00f1a<\/a>. Supongamos que el\u00a0<a href=\"https:\/\/www.imperial.ac.uk\/media\/imperial-college\/medicine\/sph\/ide\/gida-fellowships\/Imperial-College-COVID19-Europe-estimates-and-NPI-impact-30-03-2020.pdf\" rel=\"noopener nofollow\" target=\"_blank\">1.2% de los brit\u00e1nicos est\u00e1n infectados<\/a>\u00a0y que las personas enfermas tienen un 50% menos de probabilidades de viajar. Eso significa que, durante un a\u00f1o,\u00a0Espa\u00f1a importar\u00eda 108,000 casos de coronavirus del Reino Unido, un promedio de alrededor de 300 por d\u00eda. Y ese es solo un pa\u00eds. Te puedes imaginar qu\u00e9 desastre ser\u00eda abrir el pa\u00eds a los turistas.<\/p>\n<p id=\"e597\" data-selectable-paragraph=\"\">Entonces, \u00bfc\u00f3mo deber\u00eda pensar un pa\u00eds como Espa\u00f1a al respecto?<\/p>\n<p id=\"e2ba\" data-selectable-paragraph=\"\">La clave es pensar en t\u00e9rminos de coste-beneficio. El coste aqu\u00ed es nuevas semillas de infecci\u00f3n en el pa\u00eds. Eso es lo que queremos minimizar. Por lo tanto, intentemos comprender la cantidad de infecciones que los viajeros de un pa\u00eds extranjero importar\u00edan. El beneficio es el dinero que aportan a la econom\u00eda.<\/p>\n<p id=\"6d70\" data-selectable-paragraph=\"\">Probablemente hay dos tipos de viajeros: los que est\u00e1n dispuestos a pasar por una cuarentena y los que no. Los que est\u00e1n dispuestos a pasar por una cuarentena tienen m\u00e1s probabilidades de vivir en el pa\u00eds y participar en gran medida en la econom\u00eda. Gracias a la cuarentena, tambi\u00e9n es mucho menos probable que agreguen casos a su pa\u00eds. Por lo tanto, cuestan menos en t\u00e9rminos de infecciones y valen m\u00e1s en t\u00e9rminos de actividad econ\u00f3mica.<\/p>\n<p id=\"09e4\" data-selectable-paragraph=\"\">Por tanto, como regla general,\u00a0los pa\u00edses que pueden permitirse las semillas extranjeras deben cambiar primero de prohibiciones de viaje a cuarentenas de viaje para todos los visitantes, sin importar el pa\u00eds de donde provengan.\u00a0<a href=\"https:\/\/edition.cnn.com\/travel\/article\/spain-coronavirus-quarantine-travelers-intl-scli\/index.html\" rel=\"noopener nofollow\" target=\"_blank\">Espa\u00f1a finalmente se ha dado cuenta de esto<\/a>.<\/p>\n<p id=\"bd84\" data-selectable-paragraph=\"\">Los pa\u00edses que hacen un buen trabajo al poner en cuarentena a los visitantes a largo plazo se aseguran de tener una residencia. De lo contrario, deben permanecer en un hotel sancionado por el gobierno.\u00a0<a href=\"https:\/\/www.forbes.com\/sites\/tamarathiessen\/2020\/04\/04\/australian-travelers-complain-about-5-star-hotel-quarantine\/#3f9a14446dbe\" rel=\"noopener nofollow\" target=\"_blank\">Algunos pa\u00edses incluso lo pagan<\/a>.<\/p>\n<p id=\"df91\" data-selectable-paragraph=\"\">Tambi\u00e9n se aseguran de que el tr\u00e1nsito desde el aeropuerto, o la frontera, hasta la residencia\u00a0<a href=\"https:\/\/www.facebook.com\/jonathan.chen.1213\/posts\/10158178965295127\" rel=\"noopener nofollow\" target=\"_blank\">ofrece la menor cantidad posible de contagio local<\/a>. En Taiw\u00e1n o China, usted usa su transporte privado o transporte autorizado por el gobierno. Cualquier otro medio de transporte, incluido caminar por la calle, est\u00e1 prohibido.<\/p>\n<p id=\"fe15\" data-selectable-paragraph=\"\">Una vez que esta operaci\u00f3n funciona bien, los pa\u00edses deben monitorear la situaci\u00f3n para asegurarse de que se importen pocas infecciones y que siempre est\u00e9n contenidas. Pueden convertir las prohibiciones de viaje en cuarentenas pa\u00eds por pa\u00eds, seg\u00fan los casos que est\u00e9n importando y su capacidad para contenerlas.<\/p>\n<p id=\"63c1\" data-selectable-paragraph=\"\">Tomemos\u00a0<a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1Epl5KKW_HmwuF718WiFIw41HgqOeNorbBJTpLnsri0c\/edit?usp=sharing\" rel=\"noopener nofollow\" target=\"_blank\">esta situaci\u00f3n imaginaria<\/a>:<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_XCe0yEsPFA_C35do-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136589\" title=\"0_XCe0yEsPFA_C35do copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_XCe0yEsPFA_C35do-copia.png\" alt=\"\" width=\"670\" height=\"150\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_XCe0yEsPFA_C35do-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_XCe0yEsPFA_C35do-copia-300x67.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1Epl5KKW_HmwuF718WiFIw41HgqOeNorbBJTpLnsri0c\/edit\" rel=\"noopener nofollow\" target=\"_blank\">Fuente para el modelo<\/a><\/p>\n<p id=\"f765\" data-selectable-paragraph=\"\">Imagine que un pa\u00eds como Espa\u00f1a tuviera que elegir con qu\u00e9 pa\u00edses abre sus fronteras. El pa\u00eds H suele ser una gran fuente de turistas (\u00a110 millones!), Pero no ha controlado la epidemia y en este momento alrededor del 5% de su poblaci\u00f3n podr\u00eda estar infectada. Si estas personas tienden a sentirse m\u00e1s enfermas y viajan un 30% menos que otras, eso podr\u00eda significar que podr\u00edan entrar en el pa\u00eds cerca de 350,000 infecciones. Esto no puede suceder de ninguna manera.<\/p>\n<p id=\"76c1\" data-selectable-paragraph=\"\">Por el contrario, el pa\u00eds D est\u00e1 danzando con la enfermedad con \u00e9xito y tiene muy pocos viajeros infectados. Tiene m\u00e1s sentido abrirse primero a ese pa\u00eds. Pero, \u00bfqu\u00e9 pa\u00eds debemos abrir primero: D, O o W? Debe tener en cuenta el valor aportado al pa\u00eds por viajero infectado.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_NZY90LPaBry3vJxk-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136590\" title=\"0_NZY90LPaBry3vJxk copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_NZY90LPaBry3vJxk-copia.png\" alt=\"\" width=\"670\" height=\"232\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_NZY90LPaBry3vJxk-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_NZY90LPaBry3vJxk-copia-300x103.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1Epl5KKW_HmwuF718WiFIw41HgqOeNorbBJTpLnsri0c\/edit#gid=0\" rel=\"noopener nofollow\" target=\"_blank\">Fuente<\/a><\/p>\n<p id=\"1904\" data-selectable-paragraph=\"\">Aqu\u00ed, Espa\u00f1a est\u00e1 aplicando una cuarentena a todos los viajeros a largo plazo, que asumiremos que reduce la cantidad de semillas en un 75%. Podemos ver que abrir las fronteras a los del pa\u00eds H trae alrededor de 1.7 millones $ por persona infectada a la econom\u00eda, \u00a1pero abrir Espa\u00f1a a los visitantes del pa\u00eds D trae 700 millones $! Tambi\u00e9n resulta obvio que, si Espa\u00f1a tiene que elegir de d\u00f3nde recibe visitantes a largo plazo, debe priorizar primero el pa\u00eds D, luego O (alrededor de $ 11 millones por persona infectada), y luego W y finalmente H.<\/p>\n<p id=\"63d7\" data-selectable-paragraph=\"\">Espa\u00f1a decidir\u00eda de cu\u00e1ntos de estos pa\u00edses puede recibir semillas en funci\u00f3n del n\u00famero de casos que puede tolerar. Aqu\u00ed, la apertura a los pa\u00edses D, O y W traer\u00eda alrededor de 1.250 casos por a\u00f1o al pa\u00eds, o alrededor de cuatro por d\u00eda.<\/p>\n<p id=\"efd0\" data-selectable-paragraph=\"\">Si eso funciona, la siguiente pregunta para cualquier pa\u00eds es: \u00bfPodemos incluso levantar las cuarentenas para los viajeros de ciertos pa\u00edses? Este es el santo grial del turismo. Sin eso, est\u00e1 en problemas.<\/p>\n<p id=\"706d\" data-selectable-paragraph=\"\">El c\u00e1lculo es realmente el mismo: \u00bfcu\u00e1l es el beneficio por turista que obtienes y cu\u00e1l es el coste por infecci\u00f3n? Reciba viajeros de los pa\u00edses con el mejor beneficio por infecci\u00f3n importada, hasta el n\u00famero m\u00e1ximo que decida que su sistema de atenci\u00f3n m\u00e9dica puede atender, y siempre que los beneficios superen los costes.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_62o4WYgXMRTPpGdH-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136591\" title=\"0_62o4WYgXMRTPpGdH copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_62o4WYgXMRTPpGdH-copia.png\" alt=\"\" width=\"670\" height=\"308\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_62o4WYgXMRTPpGdH-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_62o4WYgXMRTPpGdH-copia-300x137.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1Epl5KKW_HmwuF718WiFIw41HgqOeNorbBJTpLnsri0c\/edit\" rel=\"noopener nofollow\" target=\"_blank\">Fuente<\/a><\/p>\n<p id=\"4202\" data-selectable-paragraph=\"\">Esto puede ilustrar, por ejemplo, que tiene sentido permitir a los turistas del pa\u00eds D y O, incluso sin una cuarentena,\u00a0<em>antes<\/em>\u00a0de permitir a cualquier viajero a largo plazo del pa\u00eds H, simplemente porque el pa\u00eds D y O est\u00e1n haciendo un buen trabajo bailando con la enfermedad: Sus turistas aportan 25 millones $ y 2 millones $ a la econom\u00eda local, en comparaci\u00f3n con solo 1.7 $ de los visitantes a largo plazo del pa\u00eds H.<\/p>\n<p id=\"a080\" data-selectable-paragraph=\"\">Con eso, podemos priorizar de qu\u00e9 pa\u00edses recibir visitantes y qu\u00e9 tipo de visitantes permitir.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_LMRoUiabC9OSDmOn-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136592\" title=\"0_LMRoUiabC9OSDmOn copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_LMRoUiabC9OSDmOn-copia.png\" alt=\"\" width=\"670\" height=\"376\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_LMRoUiabC9OSDmOn-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_LMRoUiabC9OSDmOn-copia-300x168.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1Epl5KKW_HmwuF718WiFIw41HgqOeNorbBJTpLnsri0c\/edit#gid=0\" rel=\"noopener nofollow\" target=\"_blank\">Fuente<\/a><\/p>\n<div>\n<div>\n<p id=\"fa67\" data-selectable-paragraph=\"\">Si Espa\u00f1a puede permitirse traer 10 nuevos casos por d\u00eda al pa\u00eds, puede recibir visitantes a largo plazo de los pa\u00edses D, O y W, y turistas del pa\u00eds D.<\/p>\n<p id=\"c872\" data-selectable-paragraph=\"\">Hay algunos detalles importantes. Por ejemplo, no considere solo el pa\u00eds de origen, sino tambi\u00e9n la ruta de viaje. Debe sentirse seguro acerca de la cantidad de infecciones que puede prevenir mediante cuarentenas. Debe adivinar\/conocer la prevalencia por pa\u00eds y conocer el beneficio por turista o residente.<\/p>\n<p id=\"14f3\" data-selectable-paragraph=\"\">M\u00e1s importante a\u00fan, entienda los n\u00fameros que m\u00e1s importan y c\u00f3mo tratarlos. Para este modelo, los n\u00fameros clave son la prevalencia de personas infectadas en los pa\u00edses de origen y la proporci\u00f3n de infecciones que puede detectar o aislar. Si habilita los controles de temperatura y las pruebas de PCR en los aeropuertos para detectar qui\u00e9n est\u00e1 infectado, por ejemplo, puede abrir el pa\u00eds de forma m\u00e1s r\u00e1pida. Este es el resultado si detecta el 75% de los potencialmente infectados:<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_V7WNRtWIUlbtJOJE-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136593\" title=\"0_V7WNRtWIUlbtJOJE copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_V7WNRtWIUlbtJOJE-copia.png\" alt=\"\" width=\"670\" height=\"375\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_V7WNRtWIUlbtJOJE-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_V7WNRtWIUlbtJOJE-copia-300x167.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1Epl5KKW_HmwuF718WiFIw41HgqOeNorbBJTpLnsri0c\/edit#gid=0\" rel=\"noopener nofollow\" target=\"_blank\">Fuente<\/a><\/p>\n<div>De repente, \u00a1los visitantes a largo plazo y los turistas de la mayor\u00eda de los pa\u00edses son bienvenidos! Esta podr\u00eda ser una de las razones por las cuales Corea del Sur ha podido mantener sus fronteras abiertas durante mucho tiempo. <a href=\"https:\/\/twitter.com\/michaelvkim\/status\/1258987354934538248?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed&amp;ref_url=https%3A%2F%2Fcdn.embedly.com%2Fwidgets%2Fmedia.html%3Ftype%3Dtext%252Fhtml%26key%3Da19fcc184b9711e1b4764040d3dc5c07%26schema%3Dtwitter%26url%3Dhttps%253A%2F%2Ftwitter.com%2Fmichaelvkim%2Fstatus%2F1258987354934538248%26image%3D\" target=\"_blank\">Este es su proceso:<\/a><\/div>\n<\/div>\n<div><\/div>\n<div><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.20.36-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136594\" title=\"Captura de pantalla 2020-06-10 a las 17.20.36 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.20.36-copia.png\" alt=\"\" width=\"495\" height=\"216\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.20.36-copia.png 495w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.20.36-copia-300x130.png 300w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><\/div>\n<div><\/div>\n<div>\n<p id=\"cd64\" data-selectable-paragraph=\"\"><a href=\"https:\/\/www.viennaairport.com\/pcrtest?fbclid=IwAR0PtHVFW1Z-6U60bdXDMv4YJ0jhkxyKhta9lt6oK7kfKEQTofGRxSoKpAE\" rel=\"noopener nofollow\" target=\"_blank\">Austria ya ofrece pruebas de PCR<\/a>\u00a0para viajeros entrantes y salientes.<\/p>\n<p id=\"68f6\" data-selectable-paragraph=\"\">Estos importantes detalles son los que en las pr\u00f3ximas semanas y meses de trabajo deber\u00edan resolver. Estos n\u00fameros est\u00e1n todos inventados. Pero si los \u00f3rdenes de magnitud son ampliamente v\u00e1lidos, este tipo de modelo puede darnos muchas ideas diferentes. Por ejemplo:<\/p>\n<ul>\n<li id=\"00d4\" data-selectable-paragraph=\"\">Los dos factores clave aqu\u00ed son la prevalencia del coronavirus (proporci\u00f3n de la poblaci\u00f3n infectada) del pa\u00eds de origen y el \u00e9xito en la identificaci\u00f3n y el aislamiento de casos. Despu\u00e9s de eso, viene el beneficio por visitante o turista.<\/li>\n<li id=\"d503\" data-selectable-paragraph=\"\">Si hay muchos casos en todo el mundo, incluso poner en cuarentena a todos los viajeros a\u00fan podr\u00eda colapsar el sistema, y tal vez queramos elegir de qu\u00e9 pa\u00edses permitimos visitantes. Si la mayor parte del mundo hace un buen trabajo para controlar el coronavirus, la prevalencia ser\u00e1 tan baja que los pa\u00edses podr\u00e1n abrirse a visitantes a largo plazo de muchos otros pa\u00edses.<\/li>\n<li id=\"b4b8\" data-selectable-paragraph=\"\">Los pa\u00edses que persiguen la inmunidad de reba\u00f1o podr\u00edan tener tantos casos que incluso una cuarentena de sus viajeros a largo plazo no sea lo suficientemente buena como para permitirlos en pa\u00edses extranjeros.<\/li>\n<li id=\"bf2d\" data-selectable-paragraph=\"\">Los visitantes a largo plazo, que probablemente aporten m\u00e1s valor por persona al pa\u00eds que los turistas y est\u00e9n dispuestos a sufrir una cuarentena, casi siempre tienen una prioridad m\u00e1s alta que los turistas. Si esto es cierto, es probable que primero nos abramos a los pa\u00edses a trav\u00e9s de las cuarentenas de viajeros, y una vez que el sistema pueda hacer frente a eso, podemos comenzar a permitir que los pa\u00edses env\u00eden viajeros sin cuarentenas.<\/li>\n<li id=\"f178\" data-selectable-paragraph=\"\">Si un pa\u00eds tiene una credibilidad solida en su protocolo de identificaci\u00f3n de casos de viajeros y ponerlos en cuarentena, y puede presumir de una puntuaci\u00f3n de \u00e9xito de cuarentena del 100%, puede abrirse para recibir visitantes a largo plazo de todo el mundo.<\/li>\n<li id=\"a08f\" data-selectable-paragraph=\"\">La entrada de turistas es de importancia secundaria respecto a la de los residentes. Pero los ciudadanos de pa\u00edses que tienen una prevalencia muy baja podr\u00edan tener m\u00e1s libertad para viajar a donde quieran. Para la industria del turismo, esto podr\u00eda ser dif\u00edcil: a menos que la prevalencia sea realmente baja, los pa\u00edses tiene que trabajar hasta ser muy buenos para detectar los casos de coronavirus desde el principio del desarrollo de la enfermedad, sino es as\u00ed, o la industria del turismo encuentra formas de distanciar f\u00edsicamente a todos los clientes, o podr\u00eda verse afectada durante mucho tiempo hasta que se desarolle una vacuna o un tratamiento efectivo. Esto tardar\u00e1 a\u00f1os.<\/li>\n<\/ul>\n<p id=\"572e\" data-selectable-paragraph=\"\">Todo esto se basa en este modelo b\u00e1sico y te\u00f3rico, por lo que cualquiera de las conclusiones anteriores podr\u00eda estar equivocada. El objetivo no es tanto llegar a estas conclusiones, sino destacar c\u00f3mo esa forma de pensar puede ayudar a tomar decisiones pol\u00edticas.<\/p>\n<p id=\"9842\" data-selectable-paragraph=\"\">As\u00ed es como\u00a0<a href=\"https:\/\/www.scmp.com\/news\/hong-kong\/politics\/article\/3074380\/coronavirus-hong-kong-planning-extend-travel-restrictions\" rel=\"noopener nofollow\" target=\"_blank\">Hong Kong<\/a>\u00a0piensa sobre el <a href=\"https:\/\/www.scmp.com\/news\/hong-kong\/politics\/article\/3074380\/coronavirus-hong-kong-planning-extend-travel-restrictions\" target=\"_blank\">problema<\/a><\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.20.52-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136595\" title=\"Captura de pantalla 2020-06-10 a las 17.20.52 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.20.52-copia.png\" alt=\"\" width=\"615\" height=\"152\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.20.52-copia.png 615w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/Captura-de-pantalla-2020-06-10-a-las-17.20.52-copia-300x74.png 300w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/a><\/p>\n<div>\n<p id=\"dfbf\" data-selectable-paragraph=\"\">De su plan oficial:<\/p>\n<blockquote>\n<p id=\"8d9f\" data-selectable-paragraph=\"\">\u201cEl Gobierno realiz\u00f3 an\u00e1lisis de riesgos detallados antes de la implementaci\u00f3n de medidas sanitarias portuarias en vista del brote de enfermedades en otros pa\u00edses o regiones. Adem\u00e1s de considerar el n\u00famero, la distribuci\u00f3n y la tasa de aumento de personas infectadas, el Gobierno tambi\u00e9n tendr\u00e1 en cuenta las medidas de vigilancia y control implementadas por las autoridades de ese pa\u00eds \/ regi\u00f3n en particular, as\u00ed como la frecuencia de los viajes entre Hong Kong y ese pa\u00eds. pa\u00eds \/ regi\u00f3n particular. El Gobierno revisar\u00e1 y racionalizar\u00e1 adecuadamente las medidas pertinentes teniendo en cuenta el \u00faltimo desarrollo del brote \u201c. \u2014\u00a0<a href=\"https:\/\/www.legco.gov.hk\/yr19-20\/english\/panels\/hs\/papers\/hs20200408cb2-794-1-e.pdf\" rel=\"noopener nofollow\" target=\"_blank\">Panel del Consejo Legislativo sobre Prevenci\u00f3n y Control de Servicios de Salud de la Enfermedad por Coronavirus 2019 en Hong Kong<\/a><\/p>\n<\/blockquote>\n<h2 id=\"4231\" data-selectable-paragraph=\"\">Un cuento de dos mundos<\/h2>\n<p id=\"03ca\" data-selectable-paragraph=\"\">Esto sugiere que los pa\u00edses podr\u00edan dividirse en dos clases: pa\u00edses que bailan con la enfermedad y pa\u00edses infectados.<\/p>\n<p id=\"469e\" data-selectable-paragraph=\"\">Con trabajo duro, los pa\u00edses bailarines habr\u00e1n eliminado la mayor\u00eda de los casos internos de coronavirus. Estar\u00e1n seguros de viajar entre ellos, con pocas limitaciones. Sin embargo, rehuir\u00e1n a los pa\u00edses que buscan inmunidad colectiva, por temor a causar nuevos brotes. Los pa\u00edses infectados, a su vez, podr\u00edan recibir visitantes de todos los pa\u00edses, ya que no tienen nada que perder. Desafortunadamente, en su mayor\u00eda podr\u00edan recibir visitantes de otros pa\u00edses infectados, ya que los de los pa\u00edses que bailan con la enfermedad no querr\u00e1n contraer el virus y es posible que sus pa\u00edses no les permitan regresar sin una cuarentena.<\/p>\n<p id=\"f9d7\" data-selectable-paragraph=\"\">Esta es otra raz\u00f3n para que tengan cuidado los pa\u00edses que buscan conseguir la inmunidad de reba\u00f1o. Puede que les resulte dif\u00edcil permitir que sus ciudadanos viajen al extranjero, y luchan por mantener a flote sus industrias tur\u00edsticas debido a las amplias restricciones de viaje hacia y desde sus or\u00edgenes<\/p>\n<p id=\"270c\" data-selectable-paragraph=\"\">Hasta ahora, solo he hablado de pa\u00edses, pero la misma l\u00f3gica es v\u00e1lida en todas las regiones.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_5O0EI2DQdMrZtmN2-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136596\" title=\"0_5O0EI2DQdMrZtmN2 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_5O0EI2DQdMrZtmN2-copia.png\" alt=\"\" width=\"670\" height=\"444\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_5O0EI2DQdMrZtmN2-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_5O0EI2DQdMrZtmN2-copia-300x198.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<div>\n<div>\n<p id=\"141b\" data-selectable-paragraph=\"\">Dentro de los Estados Unidos, algunos estados danzantes tienen muy pocos casos, como Alaska, Oreg\u00f3n, Montana, Idaho, Haw\u00e1i o Maine. Los estados infectados con brotes graves incluyen Illinois, Iowa, Nueva York, Nueva Jersey o Maryland.<\/p>\n<p id=\"a5a5\" data-selectable-paragraph=\"\">Podr\u00edamos imaginar que los estados danzantes se abran para viajar entre ellos, pero eviten que los visitantes se infecten o fuercen una cuarentena, como ya lo hacen\u00a0<a href=\"https:\/\/www.adn.com\/nation-world\/2020\/05\/07\/more-rogue-tourists-arrested-as-hawaii-tries-to-limit-coronavirus-spread\/\" rel=\"noopener nofollow\" target=\"_blank\">Hawai<\/a>\u00a0y\u00a0<a href=\"https:\/\/gov.alaska.gov\/wp-content\/uploads\/sites\/2\/COVID-19-Health-Mandate-010-Travel-Declaration.pdf\" rel=\"noopener nofollow\" target=\"_blank\">Alaska<\/a>. Estados como California, Nevada o Washington est\u00e1n esforz\u00e1ndose seriamente para llegar a un nivel de prevalencia lo suficientemente bajo como para ser aceptado en el club.<\/p>\n<p id=\"5fd3\" data-selectable-paragraph=\"\">Por el contrario, algunos estados como Iowa, Nebraska o Illinois pueden tener brotes tan intensos que deciden optar por la inmunidad colectiva. A estos podr\u00edan unirse estados del sur como Georgia, Tennessee o Mississippi. Los estados en el medio pueden decidir si quieren pertenecer al club de baile o al club infectado.<\/p>\n<p data-selectable-paragraph=\"\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_REJhVRnzXsp23mH9-copia.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136597\" title=\"0_REJhVRnzXsp23mH9 copia\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_REJhVRnzXsp23mH9-copia.png\" alt=\"\" width=\"670\" height=\"411\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_REJhVRnzXsp23mH9-copia.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_REJhVRnzXsp23mH9-copia-300x184.png 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<div>\n<section>\n<div>\n<div>\n<p id=\"42c3\" data-selectable-paragraph=\"\">Algo similar se est\u00e1 considerando en muchos pa\u00edses.<\/p>\n<p id=\"d86e\" data-selectable-paragraph=\"\">En\u00a0<a href=\"https:\/\/www.pm.gov.au\/sites\/default\/files\/files\/covid-safe-australia-roadmap.pdf\" rel=\"noopener nofollow\" target=\"_blank\">Australia<\/a>, se permiten viajes locales y regionales a medida que las regiones ingresan al Paso 1 (algunos ya lo han hecho). El Paso 2 permitir\u00e1 algunos viajes interestatales, y el Paso 3 incluir\u00e1 viajes internacionales.<\/p>\n<p id=\"b5c6\" data-selectable-paragraph=\"\">En\u00a0<a href=\"https:\/\/www.lamoncloa.gob.es\/consejodeministros\/resumenes\/Documents\/2020\/28042020_Anexo%20II%20FASES.pdf\" rel=\"noopener nofollow\" target=\"_blank\">Espa\u00f1a<\/a>, donde las diferentes regiones tendr\u00e1n diferentes derechos en funci\u00f3n de sus niveles de prevalencia, se permitir\u00e1 viajar hacia y desde las provincias de baile, mientras que las provincias infectadas tendr\u00e1n que trabajar m\u00e1s para detener sus epidemias. El gobierno central no permite que las provincias intenten alcanzar la inmunidad de reba\u00f1o.<\/p>\n<p id=\"d081\" data-selectable-paragraph=\"\"><em>Esta secci\u00f3n se basa en el trabajo de Jorge Pe\u00f1alva.<\/em><\/p>\n<h1 id=\"ddaf\" data-selectable-paragraph=\"\">Conclusi\u00f3n<\/h1>\n<p id=\"ce02\" data-selectable-paragraph=\"\">Los pa\u00edses que desean bailar con \u00e9xito podr\u00edan hacerlo con solo pruebas, rastreo de contactos, aislamientos, cuarentenas, m\u00e1scaras, higiene, distanciamiento f\u00edsico y educaci\u00f3n p\u00fablica. Adem\u00e1s de eso, podr\u00edan necesitar limitar las reuniones sociales hasta que la prevalencia de coronavirus sea baja y encuentren formas de limitar los contagios en estos eventos. Durante el baile, tendr\u00e1n que limitar las infecciones procedentes del extranjero a trav\u00e9s de cuarentenas, medidas de filtrado en las fronteras o prohibiciones directas.<\/p>\n<p id=\"f154\" data-selectable-paragraph=\"\">Los pa\u00edses que hacen todo eso bien podr\u00e1n abrir sus econom\u00edas y viajar entre s\u00ed.<\/p>\n<p id=\"b9a3\" data-selectable-paragraph=\"\">Para los pa\u00edses que no lo hacen y buscan la inmunidad colectiva, su sufrimiento no se limitar\u00e1 a la p\u00e9rdida de viajes desde las \u00e1reas de baile. Vale la pena recordar el coste en muertes, afecciones cr\u00f3nicas, brotes cont\u00ednuos e impacto econ\u00f3mico.<\/p>\n<p id=\"399d\" data-selectable-paragraph=\"\">Si la tasa de transmisi\u00f3n\u00a0<a href=\"https:\/\/github.com\/midas-network\/COVID-19\/tree\/master\/parameter_estimates\/2019_novel_coronavirus\" rel=\"noopener nofollow\" target=\"_blank\">R es 2.7<\/a>, alrededor del 65% de la poblaci\u00f3n podr\u00eda infectarse, o alrededor de 214 millones de estadounidenses. Si la tasa de mortalidad por infecci\u00f3n (IFR) est\u00e1 entre 0.5% y 1.5%, lo que parece estar basado en los estudios de seroprevalencia m\u00e1s confiables, la cifra de muertes en los EE. UU. Podr\u00eda ser de entre 1 y 3 millones de personas.<\/p>\n<p id=\"633d\" data-selectable-paragraph=\"\">Adem\u00e1s de eso, puede haber afecciones cr\u00f3nicas que surgen del efecto del virus en\u00a0<a href=\"https:\/\/www.washingtonpost.com\/health\/2020\/05\/10\/coronavirus-attacks-body-symptoms\/?arc404=true&amp;fbclid=IwAR0w8url4UP1TPOE8HGyovGdHByt-H_b6GUIwQcV2ZyTBly4ypeRHmObjDY\" rel=\"noopener nofollow\" target=\"_blank\">los pulmones, los ri\u00f1ones, la sangre, el cerebro<\/a>\u00a0\u2026 Alcanzar la inmunidad del reba\u00f1o llevar\u00eda meses, durante los cuales la econom\u00eda estar\u00eda deprimida ya que las personas no querr\u00edan salir, contraer una infecci\u00f3n y transmitirla a sus seres queridos. Alrededor del 45% de los estadounidenses tienen afecciones que har\u00edan que el coronavirus sea muy peligroso, como diabetes, obesidad o simplemente ser mayores.<\/p>\n<p id=\"9731\" data-selectable-paragraph=\"\">De todos modos, es probable que todo eso no valga nada, ya que no podr\u00e1n prevenir nuevos brotes: la inmunidad del reba\u00f1o a trav\u00e9s de la enfermedad no significa que la poblaci\u00f3n ahora est\u00e9 libre de ella. Los brotes reaparecen con frecuencia, especialmente si el virus se comporta como otros virus de la gripe y nuestra inmunidad desaparece despu\u00e9s de 1 a 2 a\u00f1os.<\/p>\n<p id=\"5c23\" data-selectable-paragraph=\"\">Por lo tanto, la estrategia de inmunidad del reba\u00f1o ser\u00eda perjudicial para la salud y la econom\u00eda. Lo mejor es evitar sembrar y esparcir.<\/p>\n<\/div>\n<\/div>\n<\/section>\n<hr \/>\n<section>\n<div>\n<div>\n<p id=\"6ef4\" data-selectable-paragraph=\"\"><em>Si desea recibir las pr\u00f3ximas entregas del art\u00edculo,\u00a0<\/em><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfMlYTvQiZL1nBJILpFYvawQ85TVersnwXuRq3kqV2oTR5GzA\/viewform\" rel=\"noopener nofollow\" target=\"_blank\"><em>suscr\u00edbase al bolet\u00edn<\/em><\/a><em>.<\/em><\/p>\n<p id=\"a583\" data-selectable-paragraph=\"\"><em>Esta es la Parte 5 de nuestro art\u00edculo, Coronavirus: aprender a bailar. En la\u00a0<\/em><a href=\"https:\/\/medium.com\/tomas-pueyo\/coronavirus-aprendiendo-a-danzar-4925ee8d8048\" rel=\"noopener\" target=\"_blank\"><em>Parte 1<\/em><\/a><em>, discutimos las mejores pr\u00e1cticas de Taiw\u00e1n, Singapur, China y Corea del Sur. En la\u00a0<\/em><a href=\"https:\/\/medium.com\/tomas-pueyo\/coronavirus-los-sencillos-pasos-de-baile-que-todos-pueden-seguir-b389d7cd58c6\" rel=\"noopener\" target=\"_blank\"><em>Parte 2<\/em><\/a><em>, discutimos mascarillas, higiene, distanciamiento f\u00edsico y educaci\u00f3n p\u00fablica. En la\u00a0<\/em><a href=\"https:\/\/medium.com\/tomas-pueyo\/coronavirus-c%C3%B3mo-hacer-las-pruebas-y-el-seguimiento-de-contactos-93eaa86966c5\" rel=\"noopener\" target=\"_blank\"><em>Parte 3<\/em><\/a><em>, tratamos los tests y el rastreo de contactos. En la Parte 4, hablaremos sobre Aislamientos y Cuarentenas. En la Parte 6, lo pondremos todo junto. Le daremos recomendaciones espec\u00edficas sobre cada aspecto, incluida una advertencia: la mayor\u00eda de los pa\u00edses no se est\u00e1n acercando bien al baile. Si contin\u00faan su camino actual, terminar\u00e1n como Singapur.<\/em><\/p>\n<p id=\"47b3\" data-selectable-paragraph=\"\"><em>Este ha sido un esfuerzo de equipo masivo con la ayuda de docenas de personas que han proporcionado investigaciones, fuentes, argumentos, comentarios sobre la redacci\u00f3n, cuestionaron mis argumentos y suposiciones, y no estuvieron de acuerdo conmigo. Un agradecimiento especial a Barthold Albrecht, Jorge Pe\u00f1alva, Genevieve Gee, Matt Bell, Carl Juneau, Mike Mitzel, Christina Mueller, Elena Baillie, Pierre Djian, Yasemin Denari, Claire Marshall y muchos m\u00e1s. Esto hubiera sido imposible sin todos ustedes.<\/em><\/p>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfDeber\u00edamos restringir los viajes? \u00bfNo celebrar festivales de m\u00fasica? \u00bfQu\u00e9 hacer con las escuelas? \u00bfQu\u00e9 negocios deber\u00edamos abrir? \u00bfQu\u00e9 eventos sociales deber\u00edan permitirse? Traducci\u00f3n del art\u00edculo de\u00a0Tomas Pueyo\u00a0por\u00a0Antonio Figueras. Esta es la Parte 5 de Aprender a Danzar (Parte 1,\u00a0Parte 2,\u00a0Parte 3. Parte 4 in\u00e9dita), una serie en la que profundizamos para comprender lo que los pa\u00edses deben hacer para bailar, para reabrir sus econom\u00edas sin nuevos brotes.<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u00bfDeber\u00edamos restringir los viajes? \u00bfNo celebrar festivales de m\u00fasica? \u00bfQu\u00e9 hacer con las escuelas? \u00bfQu\u00e9 negocios deber\u00edamos abrir? \u00bfQu\u00e9 eventos sociales deber\u00edan permitirse? Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Esta es la Parte 5 de Aprender a Danzar (Parte 1, Parte 2, Parte 3. Parte 4 in\u00e9dita), una serie en la que profundizamos para comprender lo que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coronavirus: prevenir la siembra y la propagaci\u00f3n - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"\u00bfDeber\u00edamos restringir los viajes? \u00bfNo celebrar festivales de m\u00fasica? \u00bfQu\u00e9 hacer con las escuelas? \u00bfQu\u00e9 negocios deber\u00edamos abrir? \u00bfQu\u00e9 eventos sociales deber\u00edan permitirse? Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Esta es la Parte 5 de Aprender a Danzar (Parte 1, Parte 2, Parte 3. Parte 4 in\u00e9dita), una serie en la que profundizamos para comprender lo que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-10T16:19:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-10T16:19:28+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coronavirus: prevenir la siembra y la propagaci\u00f3n - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u00bfDeber\u00edamos restringir los viajes? \u00bfNo celebrar festivales de m\u00fasica? \u00bfQu\u00e9 hacer con las escuelas? \u00bfQu\u00e9 negocios deber\u00edamos abrir? \u00bfQu\u00e9 eventos sociales deber\u00edan permitirse? Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Esta es la Parte 5 de Aprender a Danzar (Parte 1, Parte 2, Parte 3. Parte 4 in\u00e9dita), una serie en la que profundizamos para comprender lo que\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/10\\\/136566#blogposting\",\"name\":\"Coronavirus: prevenir la siembra y la propagaci\\u00f3n - Ciencia Marina y otros asuntos\",\"headline\":\"Coronavirus: prevenir la siembra y la propagaci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/06\\\/0_9iEvwDW3fnZiYE7q-copia.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/10\\\/136566\\\/#articleImage\",\"width\":670,\"height\":401},\"datePublished\":\"2020-06-10T17:19:28+01:00\",\"dateModified\":\"2020-06-10T17:19:28+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/10\\\/136566#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/10\\\/136566#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/10\\\/136566#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/10\\\/136566#listItem\",\"name\":\"Coronavirus: prevenir la siembra y la propagaci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/10\\\/136566#listItem\",\"position\":3,\"name\":\"Coronavirus: prevenir la siembra y la propagaci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/10\\\/136566#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/10\\\/136566\",\"name\":\"Coronavirus: prevenir la siembra y la propagaci\\u00f3n - Ciencia Marina y otros asuntos\",\"description\":\"\\u00bfDeber\\u00edamos restringir los viajes? \\u00bfNo celebrar festivales de m\\u00fasica? \\u00bfQu\\u00e9 hacer con las escuelas? \\u00bfQu\\u00e9 negocios deber\\u00edamos abrir? \\u00bfQu\\u00e9 eventos sociales deber\\u00edan permitirse? Traducci\\u00f3n del art\\u00edculo de Tomas Pueyo por Antonio Figueras. Esta es la Parte 5 de Aprender a Danzar (Parte 1, Parte 2, Parte 3. Parte 4 in\\u00e9dita), una serie en la que profundizamos para comprender lo que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/06\\\/10\\\/136566#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-06-10T17:19:28+01:00\",\"dateModified\":\"2020-06-10T17:19:28+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Coronavirus: prevenir la siembra y la propagaci\u00f3n - Ciencia Marina y otros asuntos","description":"\u00bfDeber\u00edamos restringir los viajes? \u00bfNo celebrar festivales de m\u00fasica? \u00bfQu\u00e9 hacer con las escuelas? \u00bfQu\u00e9 negocios deber\u00edamos abrir? \u00bfQu\u00e9 eventos sociales deber\u00edan permitirse? Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Esta es la Parte 5 de Aprender a Danzar (Parte 1, Parte 2, Parte 3. Parte 4 in\u00e9dita), una serie en la que profundizamos para comprender lo que","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566#blogposting","name":"Coronavirus: prevenir la siembra y la propagaci\u00f3n - Ciencia Marina y otros asuntos","headline":"Coronavirus: prevenir la siembra y la propagaci\u00f3n","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/06\/0_9iEvwDW3fnZiYE7q-copia.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566\/#articleImage","width":670,"height":401},"datePublished":"2020-06-10T17:19:28+01:00","dateModified":"2020-06-10T17:19:28+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566#listItem","name":"Coronavirus: prevenir la siembra y la propagaci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566#listItem","position":3,"name":"Coronavirus: prevenir la siembra y la propagaci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566","name":"Coronavirus: prevenir la siembra y la propagaci\u00f3n - Ciencia Marina y otros asuntos","description":"\u00bfDeber\u00edamos restringir los viajes? \u00bfNo celebrar festivales de m\u00fasica? \u00bfQu\u00e9 hacer con las escuelas? \u00bfQu\u00e9 negocios deber\u00edamos abrir? \u00bfQu\u00e9 eventos sociales deber\u00edan permitirse? Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Esta es la Parte 5 de Aprender a Danzar (Parte 1, Parte 2, Parte 3. Parte 4 in\u00e9dita), una serie en la que profundizamos para comprender lo que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-06-10T17:19:28+01:00","dateModified":"2020-06-10T17:19:28+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Coronavirus: prevenir la siembra y la propagaci\u00f3n - Ciencia Marina y otros asuntos","og:description":"\u00bfDeber\u00edamos restringir los viajes? \u00bfNo celebrar festivales de m\u00fasica? \u00bfQu\u00e9 hacer con las escuelas? \u00bfQu\u00e9 negocios deber\u00edamos abrir? \u00bfQu\u00e9 eventos sociales deber\u00edan permitirse? Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Esta es la Parte 5 de Aprender a Danzar (Parte 1, Parte 2, Parte 3. Parte 4 in\u00e9dita), una serie en la que profundizamos para comprender lo que","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-06-10T16:19:28+00:00","article:modified_time":"2020-06-10T16:19:28+00:00","twitter:card":"summary","twitter:title":"Coronavirus: prevenir la siembra y la propagaci\u00f3n - Ciencia Marina y otros asuntos","twitter:description":"\u00bfDeber\u00edamos restringir los viajes? \u00bfNo celebrar festivales de m\u00fasica? \u00bfQu\u00e9 hacer con las escuelas? \u00bfQu\u00e9 negocios deber\u00edamos abrir? \u00bfQu\u00e9 eventos sociales deber\u00edan permitirse? Traducci\u00f3n del art\u00edculo de Tomas Pueyo por Antonio Figueras. Esta es la Parte 5 de Aprender a Danzar (Parte 1, Parte 2, Parte 3. Parte 4 in\u00e9dita), una serie en la que profundizamos para comprender lo que","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"136566","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 17:13:51","updated":"2026-05-26 19:33:50","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCoronavirus: prevenir la siembra y la propagaci\u00f3n\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Coronavirus: prevenir la siembra y la propagaci\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/06\/10\/136566"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136566"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=136566"}],"version-history":[{"count":6,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136566\/revisions"}],"predecessor-version":[{"id":136602,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136566\/revisions\/136602"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=136566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=136566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=136566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}