{"id":136842,"date":"2020-07-31T09:50:37","date_gmt":"2020-07-31T08:50:37","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=136842"},"modified":"2020-07-31T09:50:37","modified_gmt":"2020-07-31T08:50:37","slug":"coronavirus-vamos-con-mucho-retraso","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842","title":{"rendered":"Coronavirus: Vamos con mucho retraso"},"content":{"rendered":"<p><a href=\"http:\/\/patologia.iim.csic.es\/grupo_patolog\/personal-detalle\/1\/6\/1\/Antonio%20Figueras%20Huerta\" rel=\"noopener noreferrer\" target=\"_blank\" data-rapid-elm=\"context_link\" data-ylk=\"elm:context_link;itc:0\" data-rapid-sec=\"{&quot;entry-text&quot;:&quot;entry-text&quot;}\" data-rapid-itc=\"0\" data-rapid_p=\"2\" data-v9y=\"1\">Antonio Figueras<\/a>, doctor en biolog\u00eda y uno de los investigadores con un curr\u00edculum m\u00e1s extenso del CSIC, repite una y otra vez una premisa: adelantarse a la enfermedad, arrinconarla y que no sea el\u00a0<a href=\"https:\/\/www.huffingtonpost.es\/news\/coronavirus\/\" target=\"&quot;_blank\" data-rapid-elm=\"context_link\" data-ylk=\"elm:context_link;itc:0\" data-rapid-sec=\"{&quot;entry-text&quot;:&quot;entry-text&quot;}\" data-rapid-itc=\"0\" data-rapid_p=\"3\" data-v9y=\"1\">Sars-CoV-2<\/a>\u00a0el que parta con ventaja. Esto es clave para que haya una situaci\u00f3n controlada y no de transmisi\u00f3n comunitaria.<\/p>\n<p><!--more-->A finales de enero, este veterano experto gallego ya torci\u00f3 el gesto ante las continuas declaraciones de que esto era una gripe. \u201cEn febrero pulsaba el ascensor con el codo\u201d, comenta. En aquel entonces y aunque no lo sab\u00eda, la sociedad occidental ya iba muy por detr\u00e1s del pat\u00f3geno, que infectaba sin oposici\u00f3n.<\/p>\n<p>Ahora, con m\u00e1s de tres meses de experiencia contra el virus, la situaci\u00f3n se est\u00e1 volviendo a complicar y los datos crecen a diario. De nuevo, Figueras lo vio venir.\u00a0<a href=\"https:\/\/www.huffingtonpost.es\/entry\/un-experto-de-csic-alerta-de-que-la-poblacion-no-es-consciente-de-lo-que-esta-ocurriendo-con-el-coronavirus_es_5ef9f517c5b6ca970912ca09\" target=\"&quot;_blank\" data-rapid-elm=\"context_link\" data-ylk=\"elm:context_link;itc:0\" data-rapid-sec=\"{&quot;entry-text&quot;:&quot;entry-text&quot;}\" data-rapid-itc=\"0\" data-rapid_p=\"4\" data-v9y=\"1\">\u201cVamos mal no, lo siguiente\u201d, avis\u00f3 el pasado 27 de junio en su cuenta de Twitter.\u00a0<\/a><\/p>\n<div id=\"entry_paragraph_3\" data-label-height=\"50\">\n<div id=\"cser_gpt-INTEXT\" data-google-query-id=\"CKvwnpmH9-oCFRLc3godLfQECg\">\n<div id=\"google_ads_iframe_7811748\/huffingtonpost_web\/virales\/intext_0__container__\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/07\/Captura-de-pantalla-2020-07-31-a-las-10.22.05.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136843\" title=\"Captura de pantalla 2020-07-31 a las 10.22.05\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/07\/Captura-de-pantalla-2020-07-31-a-las-10.22.05.png\" alt=\"\" width=\"670\" height=\"734\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/07\/Captura-de-pantalla-2020-07-31-a-las-10.22.05.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/07\/Captura-de-pantalla-2020-07-31-a-las-10.22.05-273x300.png 273w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<p>No hab\u00eda ning\u00fan indicativo que le llevara al optimismo. Casi tres semanas despu\u00e9s, sigue llev\u00e1ndose las manos a la cabeza con el incremento de contagiados. Adem\u00e1s, lo hace con la experiencia que acumul\u00f3 en una situaci\u00f3n de crisis como miembro del Comit\u00e9 Cient\u00edfico Asesor para la Cat\u00e1strofe del Prestige y con la esperanza de que la pandemia cambie la din\u00e1mica del pa\u00eds.<\/p>\n<p>\u00bfExactamente qu\u00e9 le hizo pensar que iba a haber tantos rebrotes tan pronto?<\/p>\n<p>Una combinaci\u00f3n de todo lo que estaba viendo. Estaba creciendo todo: los brotes, los infectados, la movilidad, la gente que estaba respirando y saliendo tras meses de encierro, la llegada del turismo extranjero\u2026 Estaban subiendo todos los indicativos y echarle la culpa de los rebrotes a gente como por ejemplo los temporeros es realmente cruel. \u00bfQui\u00e9n va a recoger la fruta por 5 euros la hora al sol? Sin ellos muchas empresas hortofrut\u00edcolas podr\u00edan hasta casi desaparecer. Habr\u00eda que arreglar sus condiciones.<\/p>\n<div>\n<p>\u00bfSe necesitan muchos m\u00e1s rastreadores para contener al virus?<\/p>\n<p>En mi opini\u00f3n hacen falta 20.000 en total. Si no tenemos una aplicaci\u00f3n, la tarea de los rastreadores es muy dif\u00edcil. Ha salido que detectan de media tres contactos cuando una persona podr\u00eda tener 15 \u00f3 20 si es extrovertido. Esto indica que estamos fallando y es porque no hay suficiente personal. El rastreo es muy lento y cansado, una persona no se acuerda de buenas a primeras de todos sus contactos y a lo mejor tardas 5 \u00f3 6 d\u00edas hasta llegar al 70 u 80% de los contactos. Tambi\u00e9n hay otro factor: que haya gente que pueda tener miedo a dar sus contactos por si dan positivo y puedan perder su empleo en este momento. Por eso hay que pedir voluntarios, tirar de personal funcionario, etc.<\/p>\n<p>\u00bfPuede jugar una mala pasada la palabra recomendable en\u00a0<a href=\"https:\/\/www.lavanguardia.com\/vida\/20200720\/482441133697\/coches-barcelona-restricciones-confinamiento-coronavirus.html\" rel=\"noopener noreferrer\" target=\"_blank\" data-rapid-elm=\"context_link\" data-ylk=\"elm:context_link;itc:0\" data-rapid-sec=\"{&quot;entry-text&quot;:&quot;entry-text&quot;}\" data-rapid-itc=\"0\" data-rapid_p=\"7\" data-v9y=\"0\">confinamientos como el que propuso el Govern<\/a>?<\/p>\n<p>Creo que lo que hay que hacer es un confinamiento de precisi\u00f3n sabiendo claramente las zonas afectadas y, en cuanto se supere un n\u00famero determinado de casos concretos que depender\u00e1 de la densidad de poblaci\u00f3n, habr\u00eda que hacer cuarentenas aunque sean de un edificio. Hemos dado un martillazo y ahora tenemos que bailar con este virus y si veo que se me desmadra una situaci\u00f3n, me retiro inmediatamente y no le dejo personas para replicarse. Sobre todo, no hay que ir al confinamiento general indiscriminado, deben de ser parciales y para eso se necesita una fuerte identificaci\u00f3n de contactos y rastreabilidad para poder realizarles pruebas.<\/p>\n<\/div>\n<blockquote><p>Hay que hacer un confinamiento de precisi\u00f3n y no a un general indiscriminado<\/p><\/blockquote>\n<div>\n<p>\u00bfEstamos en una situaci\u00f3n similar a la de febrero o principios de marzo en cuanto a la carga viral en Espa\u00f1a?<\/p>\n<p>Podemos estar como en febrero, aproximadamente. Lo que ahora las condiciones ambientales no son las mismas y, aunque la carga viral sea parecida, est\u00e1n jugando en contra del virus, con una temperatura m\u00e1s alta y una humedad m\u00e1s baja.<\/p>\n<p>\u00bfEs acertada la medida de las\u00a0<a href=\"https:\/\/www.huffingtonpost.es\/entry\/mapa-de-las-mascarillas_es_5f0f0e0bc5b648c301f251d5\" target=\"&quot;_blank\" data-rapid-elm=\"context_link\" data-ylk=\"elm:context_link;itc:0\" data-rapid-sec=\"{&quot;entry-text&quot;:&quot;entry-text&quot;}\" data-rapid-itc=\"0\" data-rapid_p=\"8\" data-v9y=\"0\">mascarillas obligatorias seg\u00fan la comunidad<\/a>\u00a0o la impondr\u00eda directamente en la totalidad del territorio?<\/p>\n<p>El uso de la mascarilla no es una imposici\u00f3n del nuevo orden mundial, es una manera de protegerte y de proteger a otros. Si es un virus respiratorio lo que hay que hacer es usar algo que limite o elimine que puedas inhalar o expulsar ese virus, ya sea un pa\u00f1uelo, una mascarilla o lo que sea. Es inc\u00f3moda, pero es transitoria, por llevarla un a\u00f1o no pasa nada.<\/p>\n<p>Ahora se est\u00e1 aumentando la movilidad entre comunidades con distintos niveles de infecci\u00f3n y, para frenar la transmisi\u00f3n, una medida sencilla es que hay que usar la mascarilla. No hay que explicar que si est\u00e1s en lo alto de los Picos de Europa no hay que llevarla, pero s\u00ed si est\u00e1s en calles con gente. Cuando tengamos la vacuna ya veremos, pero ahora hay que usarla, lavarse las manos y evitar entrar en aglomeraciones. Ahora es muy necesaria la mascarilla, igual que lo era en marzo.<\/p>\n<p>\u00bfPor qu\u00e9 tantas idas y venidas en temas como\u00a0<a href=\"https:\/\/www.huffingtonpost.es\/entry\/si-el-coronavirus-se-transmite-por-el-aire-que-cambia-en-nuestras-vidas_es_5f0da45fc5b648c301ef7182\" target=\"&quot;_blank\" data-rapid-elm=\"context_link\" data-ylk=\"elm:context_link;itc:0\" data-rapid-sec=\"{&quot;entry-text&quot;:&quot;entry-text&quot;}\" data-rapid-itc=\"0\" data-rapid_p=\"9\" data-v9y=\"0\">la trasmisi\u00f3n por el aire<\/a>? \u00bfNo ser\u00eda mejor prevenir desde un principio?<\/p>\n<p>Eso se sabe desde el principio. Lo que percibo es que hay un poco de retraso por parte de la OMS de recoger evidencias cient\u00edficas y trasladarlas a recomendaciones a todo el mundo, que es lo que puede hacer. Ning\u00fan pa\u00eds tiene la obligaci\u00f3n de comunicarle a la OMS nada, es todo recomendaci\u00f3n.<\/p>\n<p>El doctor\u00a0<a href=\"https:\/\/www.huffingtonpost.es\/entry\/no-esta-diciendo-toda-la-verdad-el-experto-bonaventura-clotet-acusa-a-madrid-de-mentir-sobre-sus-datos-de-contagios_es_5f152dd5c5b6cec246c490bd\" target=\"&quot;_blank\" data-rapid-elm=\"context_link\" data-ylk=\"elm:context_link;itc:0\" data-rapid-sec=\"{&quot;entry-text&quot;:&quot;entry-text&quot;}\" data-rapid-itc=\"0\" data-rapid_p=\"10\" data-v9y=\"0\">Bonaventura Clotet ha acusado a Madrid de no decir toda la verdad<\/a>\u00a0sobre los contagios, \u00bfusted se los cree?<\/p>\n<p>Veo los datos de Madrid y creo que las autoridades sanitarias de Madrid tienen que explicarlos. No pasa nada y no hay que ir a una confrontaci\u00f3n. Tienen que decir qu\u00e9 est\u00e1 pasando. Yo ya dije hace dos semanas que hab\u00eda cosas que no me encajaban, no es normal lo que est\u00e1 pasando. En Madrid, por ejemplo, no es obligatorio la mascarilla. Entonces \u00bfqu\u00e9 pasa? \u00bfse ha extinguido? Supongo que tendr\u00e1n alguna explicaci\u00f3n y la tendr\u00edan que dar tanto para los ciudadanos de esa comunidad como del resto, ya que viajan a otros territorios\u2026 Las pruebas y el rastreo, repito, tienen que ser ante la m\u00ednima sospecha.<\/p>\n<\/div>\n<div>[youtube]https:\/\/www.youtube.com\/watch?v=ug_W_66yeN4[\/youtube]<\/div>\n<div>\n<p>\u00bfSon los PCR en origen una buena medida para los turistas extranjeros?<\/p>\n<p>S\u00ed, porque si no viene el descontrol. Pero tendr\u00eda que ser una decisi\u00f3n que se tomara a nivel europeo. Es incre\u00edble que en la cola de los aeropuertos haya distancia y en el avi\u00f3n no, que es un milagro donde hay algo m\u00e1gico y no te contagias. No todos los fabricantes tienen los mismos sistemas de filtraci\u00f3n de aire y no todos los modelos del mismo fabricante tiene el mismo sistema de filtraci\u00f3n de aire. Habr\u00eda que ir con mascarilla, lavarse las manos, etc. Riesgo no certifica certeza, riesgo significa la posibilidad de y en un lago solo es m\u00e1s improbable que en un avi\u00f3n.<\/p>\n<p>Rellenar un papel, tomar una temperatura y que un m\u00e9dico te mire es un poco de broma. Mira Australia, Sidney ha decidido que no deja entrar m\u00e1s de 350 personas al d\u00eda y con seguimiento. En Reino Unido apuntan los usuarios que han estado en restaurantes y bares, mientras que en Corea del Sur hacen un seguimiento continuo con llamadas al m\u00f3vil. Lo que como tenemos tanta dependencia del turismo hemos decidido barra libre.<\/p>\n<p>Tras\u00a0<a href=\"https:\/\/www.huffingtonpost.es\/entry\/la-vacuna-de-oxford-contra-el-coronavirus-genera-una-reaccion-inmune-en-su-primera-prueba-con-humanos_es_5f15a705c5b619afc404753f\" target=\"&quot;_blank\" data-rapid-elm=\"context_link\" data-ylk=\"elm:context_link;itc:0\" data-rapid-sec=\"{&quot;entry-text&quot;:&quot;entry-text&quot;}\" data-rapid-itc=\"0\" data-rapid_p=\"11\" data-v9y=\"0\">las \u00faltimas informaciones publicadas por la universidad de Oxford<\/a>\u00a0o Moderna, \u00bfve factible que se pueda empezar a vacunar a finales de este a\u00f1o o principios del que viene?<\/p>\n<p>Desde mi punto de vista, la cosa va para largo. Que tengamos vacunas que protejan parcialmente, s\u00ed. Pero la vacuna de Moderna, por ejemplo, en la nota de Reuters dice que los que se inocularon por segunda vez tuvieron mareos, desmayos, dolores, fatigas, etc. No quiero decir que no haya esperanza, pero lo que hay que hacer es modular para que no haya falsas esperanzas, porque como se empiece a caer todo en octubre o noviembre no me quiero imaginar la que se va a montar. Adem\u00e1s, con toda la cantidad de negacionistas que hay y que no se comprende que la ciencia es lenta\u2026<\/p>\n<p>\u00bfC\u00f3mo ha visto a la sociedad?<\/p>\n<p>Esto ha sido muy grave, la gente no es consciente de que estamos despu\u00e9s de una Guerra Mundial, la devastaci\u00f3n es enorme, va todo muy mal y cualquier economista o m\u00e9dico lo puede decir mejor que yo. No hay culpables. Es como si hubiera ca\u00eddo un asteroide peque\u00f1o, nadie tiene la culpa como tal. A la gente hay que informarla sin aterrorizar. Estamos por encima de miles de casos diarios y en Australia han confinado por 100 casos. Aqu\u00ed y ahora estamos en una situaci\u00f3n de grave emergencia nacional, no hace falta decretar un estado de alarma para verlo.<\/p>\n<p>Creo que la gente no se da cuenta. Despu\u00e9s de la Guerra Civil no se preocupaban si pod\u00edan ir a la playa o no, se preocupaban de lo esencial. Pero revertir una marea de pensamiento colectivo que se ha ido generando durante mucho tiempo es muy dif\u00edcil, para cambiar este pa\u00eds se necesitan 10 \u00f3 15 a\u00f1os. En Finlandia el modelo educativo lo empezaron a cambiar hace m\u00e1s de una d\u00e9cada. Aqu\u00ed vemos el resultado de m\u00e1s de 40 a\u00f1os de dirigir nuestros esfuerzos econ\u00f3micos al turismo y se deber\u00eda plantear urgentemente c\u00f3mo ir cambiando de modelo. Esto es un toque de atenci\u00f3n clar\u00edsimo.<\/p>\n<\/div>\n<blockquote><p>Aqu\u00ed y ahora estamos en una situaci\u00f3n de grave emergencia nacional<\/p><\/blockquote>\n<div>\n<p>\u00bfSu respuesta quiere decir que no hemos salido mejores?<\/p>\n<p>Vamos a salir igual. Las generaciones que m\u00e1s tienen que ganar o perder, que son las de los j\u00f3venes, se tienen que dar cuenta que el futuro de Espa\u00f1a depende de ellos y no de sus padres. Se necesitan personas que les puedan influir para no repetir errores y tambi\u00e9n desde el sistema educativo se tiene que refrendar este cambio. En Finlandia la nota de magisterio es muy alta y los maestros son la parte fundamental para poner los cimientos de un pa\u00eds. Nos tenemos que repensar y eso se hace trazando un plan a 10 \u00f3 15 a\u00f1os. Hay que mantener en el tiempo las cosas poni\u00e9ndose todos de acuerdo. Es como la ciencia, la media de edad de los cient\u00edficos es muy alta, no hay renovaci\u00f3n de plantillas. El coronavirus es una oportunidad para reinventar este pa\u00eds, suena a politiqueo barato, pero hay que creerse que somos capaces de mejorar la ciencia, la tecnolog\u00eda, la sanidad, educaci\u00f3n, etc. Hay que coger el toro por los cuernos y pensar en lo que queremos.<\/p>\n<p>\u00bfQu\u00e9 le ha parecido la labor de Fernando Sim\u00f3n y del Gobierno?<\/p>\n<p>Sin entrar a valorar lo que ya est\u00e1 hecho, creo que tienen que pisar el acelerador y anticiparse a la pandemia. Lo deben de hacer trabajando codo con codo con las comunidades aut\u00f3nomas. Hay que aprender de lo que se hizo e ir por delante. Firmaron el\u00a0<a href=\"https:\/\/www.huffingtonpost.es\/entry\/gobierno-y-ccaa-adoptaran-medidas-coordinadas-de-salud-publica-en-brotes-que-afecten-a-varias-regiones_es_5f0c48c6c5b6480493d2cc05\" target=\"&quot;_blank\" data-rapid-elm=\"context_link\" data-ylk=\"elm:context_link;itc:0\" data-rapid-sec=\"{&quot;entry-text&quot;:&quot;entry-text&quot;}\" data-rapid-itc=\"0\" data-rapid_p=\"12\" data-v9y=\"0\">plan para atajar los rebrotes cuando ya media Espa\u00f1a estaba con ellos<\/a>, hay que cambiar ese ritmo. Tambi\u00e9n se tiene que hacer p\u00fablico el dep\u00f3sito de material sanitario que tienen las comunidades y el Gobierno. Eso es transmitir confianza y tendr\u00eda que ser conocido por todos.<\/p>\n<p>Otro punto importante es la necesidad de crear unidades especializadas en los hospitales para seguir a los enfermos que se han recuperado. No vale que se los repartan entre especialistas seg\u00fan el s\u00edntoma, ya que es una enfermedad nueva y sus manifestaciones se tienen que tratar con especialistas formados para ella. Hay muchas secuelas.<\/p>\n<p>Si estamos yendo por detr\u00e1s de la enfermedad \u00bfquiere decir que no hemos aprendido nada en estos meses?<\/p>\n<p>Esto no tiene ideolog\u00eda y aqu\u00ed no hay ning\u00fan culpable. Ahora se est\u00e1 usando la culpabilidad respecto a la gente joven por irresponsables y es que a lo mejor no les estamos haciendo part\u00edcipes de lo importante que son para que esto se controle. Los hemos tenido metidos en casa con mucha inseguridad respecto a su futuro y ante eso han decidido vivir el momento. No es una cr\u00edtica. Estamos equivoc\u00e1ndonos como colectivo y nos estamos pegando con el remo en vez de ir todos en la misma direcci\u00f3n. Estamos errando todos. Hay que intentar que la gente vuelva a estar unida y no somos capaces de dejar de lado nuestras diferencias en un momento muy excepcional, esto no pasa cada cinco a\u00f1os. Nuestros grandes hitos en cuanto a tragedias colectivas del \u00faltimo siglo pueden ser la gripe del 18, la Guerra Civil, la dictadura posterior y esto. No vale tirar contra unos u otros. Nos tenemos que convencer de que solo podemos salir remando juntos porque si no siempre vamos por detr\u00e1s.<\/p>\n<\/div>\n<blockquote><p>Estar en el puesto de Fernando Sim\u00f3n es extremadamente complicado<\/p><\/blockquote>\n<div>\n<p>\u00bfVe bien que Sim\u00f3n se haya ido a hacer surf?<\/p>\n<p>Hay que ser comprensivos con \u00e9l y con su familia. La presi\u00f3n que est\u00e1n soportando es brutal y cargarles por si se va o se deja de ir no tiene sentido. Hay que darse cuenta de que, independientemente de que la gente piense una cosa u otra, est\u00e1 trabajando para hacerlo lo mejor posible, est\u00e1 haciendo el esfuerzo que requiere la situaci\u00f3n y tiene una presi\u00f3n enorme. Entrar a valorar estas cosas a m\u00ed no me parece oportuno. No es solamente Fernando Sim\u00f3n, es \u00e9l y su familia. Estar en su puesto es extremadamente complicado y genera una tensi\u00f3n muy muy elevada.<\/p>\n<p><a href=\"https:\/\/www.huffingtonpost.es\/entry\/mariano-esteban-coronavirus-csic_es_5f0832adc5b67a80bc05ba3a\" target=\"&quot;_blank\" data-rapid-elm=\"context_link\" data-ylk=\"elm:context_link;itc:0\" data-rapid-sec=\"{&quot;entry-text&quot;:&quot;entry-text&quot;}\" data-rapid-itc=\"0\" data-rapid_p=\"13\" data-v9y=\"1\">Mariano Esteban asegur\u00f3 que era \u201cmuy importante\u201d la presentaci\u00f3n del Plan de choque para la Ciencia y la Innovaci\u00f3n<\/a>\u00a0que present\u00f3 el Gobierno porque los cient\u00edficos hab\u00e9is estado en condiciones paup\u00e9rrimas en los \u00faltimos a\u00f1os, \u00bftambi\u00e9n est\u00e1 contento con la iniciativa?<\/p>\n<p>Hablar de un Plan de Choque sin un plan a medio y largo no me interesa. El corto se desvanece r\u00e1pido, yo quiero los otros. Esto es como un chaparr\u00f3n en el desierto, pero si no se sigue regando desaparecer\u00e1n las plantas que hayan salido. Si no se ve la importancia de la ciencia y la tecnolog\u00eda en un pa\u00eds, ese pa\u00eds est\u00e1 condenado a vivir del servicio. De todos los investigadores que he formado, pocos se han quedado en Espa\u00f1a y muchos se han ido a trabajar para otros pa\u00edses tras gastarnos tiempo y dinero aqu\u00ed. Necesitamos una mezcla de senior con junior, porque los que estamos nos tenemos que ir yendo poco a poco.<\/p>\n<p><a href=\"https:\/\/www.huffingtonpost.es\/entry\/antonio-figueras-csic-coronavirus_es_5f16be0dc5b651977c06468e\" target=\"_blank\">Antonio Figueras, experto del CSIC: \u00abEstamos fallando y es porque no hay suficiente personal\u00bb<\/a><br \/>\n<a href=\"https:\/\/www.huffingtonpost.es\/entry\/antonio-figueras-csic-coronavirus_es_5f16be0dc5b651977c06468e\" target=\"_blank\">\u00abVamos mal no, lo siguiente\u00bb, avis\u00f3 el pasado 27 de junio. The Huffington Post.<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Antonio Figueras, doctor en biolog\u00eda y uno de los investigadores con un curr\u00edculum m\u00e1s extenso del CSIC, repite una y otra vez una premisa: adelantarse a la enfermedad, arrinconarla y que no sea el\u00a0Sars-CoV-2\u00a0el que parta con ventaja. Esto es clave para que haya una situaci\u00f3n controlada y no de transmisi\u00f3n comunitaria.<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Antonio Figueras, doctor en biolog\u00eda y uno de los investigadores con un curr\u00edculum m\u00e1s extenso del CSIC, repite una y otra vez una premisa: adelantarse a la enfermedad, arrinconarla y que no sea el Sars-CoV-2 el que parta con ventaja. Esto es clave para que haya una situaci\u00f3n controlada y no de transmisi\u00f3n comunitaria. A finales de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coronavirus: Vamos con mucho retraso - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Antonio Figueras, doctor en biolog\u00eda y uno de los investigadores con un curr\u00edculum m\u00e1s extenso del CSIC, repite una y otra vez una premisa: adelantarse a la enfermedad, arrinconarla y que no sea el Sars-CoV-2 el que parta con ventaja. Esto es clave para que haya una situaci\u00f3n controlada y no de transmisi\u00f3n comunitaria. A finales de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-07-31T08:50:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-07-31T08:50:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coronavirus: Vamos con mucho retraso - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Antonio Figueras, doctor en biolog\u00eda y uno de los investigadores con un curr\u00edculum m\u00e1s extenso del CSIC, repite una y otra vez una premisa: adelantarse a la enfermedad, arrinconarla y que no sea el Sars-CoV-2 el que parta con ventaja. Esto es clave para que haya una situaci\u00f3n controlada y no de transmisi\u00f3n comunitaria. A finales de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/07\\\/31\\\/136842#blogposting\",\"name\":\"Coronavirus: Vamos con mucho retraso - Ciencia Marina y otros asuntos\",\"headline\":\"Coronavirus: Vamos con mucho retraso\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/07\\\/Captura-de-pantalla-2020-07-31-a-las-10.22.05.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/07\\\/31\\\/136842\\\/#articleImage\",\"width\":670,\"height\":734},\"datePublished\":\"2020-07-31T09:50:37+01:00\",\"dateModified\":\"2020-07-31T09:50:37+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/07\\\/31\\\/136842#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/07\\\/31\\\/136842#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/07\\\/31\\\/136842#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/07\\\/31\\\/136842#listItem\",\"name\":\"Coronavirus: Vamos con mucho retraso\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/07\\\/31\\\/136842#listItem\",\"position\":3,\"name\":\"Coronavirus: Vamos con mucho retraso\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/07\\\/31\\\/136842#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/07\\\/31\\\/136842\",\"name\":\"Coronavirus: Vamos con mucho retraso - Ciencia Marina y otros asuntos\",\"description\":\"Antonio Figueras, doctor en biolog\\u00eda y uno de los investigadores con un curr\\u00edculum m\\u00e1s extenso del CSIC, repite una y otra vez una premisa: adelantarse a la enfermedad, arrinconarla y que no sea el Sars-CoV-2 el que parta con ventaja. Esto es clave para que haya una situaci\\u00f3n controlada y no de transmisi\\u00f3n comunitaria. A finales de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/07\\\/31\\\/136842#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-07-31T09:50:37+01:00\",\"dateModified\":\"2020-07-31T09:50:37+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Coronavirus: Vamos con mucho retraso - Ciencia Marina y otros asuntos","description":"Antonio Figueras, doctor en biolog\u00eda y uno de los investigadores con un curr\u00edculum m\u00e1s extenso del CSIC, repite una y otra vez una premisa: adelantarse a la enfermedad, arrinconarla y que no sea el Sars-CoV-2 el que parta con ventaja. Esto es clave para que haya una situaci\u00f3n controlada y no de transmisi\u00f3n comunitaria. A finales de","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842#blogposting","name":"Coronavirus: Vamos con mucho retraso - Ciencia Marina y otros asuntos","headline":"Coronavirus: Vamos con mucho retraso","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/07\/Captura-de-pantalla-2020-07-31-a-las-10.22.05.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842\/#articleImage","width":670,"height":734},"datePublished":"2020-07-31T09:50:37+01:00","dateModified":"2020-07-31T09:50:37+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842#listItem","name":"Coronavirus: Vamos con mucho retraso"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842#listItem","position":3,"name":"Coronavirus: Vamos con mucho retraso","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842","name":"Coronavirus: Vamos con mucho retraso - Ciencia Marina y otros asuntos","description":"Antonio Figueras, doctor en biolog\u00eda y uno de los investigadores con un curr\u00edculum m\u00e1s extenso del CSIC, repite una y otra vez una premisa: adelantarse a la enfermedad, arrinconarla y que no sea el Sars-CoV-2 el que parta con ventaja. Esto es clave para que haya una situaci\u00f3n controlada y no de transmisi\u00f3n comunitaria. A finales de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-07-31T09:50:37+01:00","dateModified":"2020-07-31T09:50:37+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Coronavirus: Vamos con mucho retraso - Ciencia Marina y otros asuntos","og:description":"Antonio Figueras, doctor en biolog\u00eda y uno de los investigadores con un curr\u00edculum m\u00e1s extenso del CSIC, repite una y otra vez una premisa: adelantarse a la enfermedad, arrinconarla y que no sea el Sars-CoV-2 el que parta con ventaja. Esto es clave para que haya una situaci\u00f3n controlada y no de transmisi\u00f3n comunitaria. A finales de","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-07-31T08:50:37+00:00","article:modified_time":"2020-07-31T08:50:37+00:00","twitter:card":"summary","twitter:title":"Coronavirus: Vamos con mucho retraso - Ciencia Marina y otros asuntos","twitter:description":"Antonio Figueras, doctor en biolog\u00eda y uno de los investigadores con un curr\u00edculum m\u00e1s extenso del CSIC, repite una y otra vez una premisa: adelantarse a la enfermedad, arrinconarla y que no sea el Sars-CoV-2 el que parta con ventaja. Esto es clave para que haya una situaci\u00f3n controlada y no de transmisi\u00f3n comunitaria. A finales de","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"136842","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 20:01:10","updated":"2026-05-26 19:35:35","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCoronavirus: Vamos con mucho retraso\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Coronavirus: Vamos con mucho retraso","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/07\/31\/136842"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136842"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=136842"}],"version-history":[{"count":10,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136842\/revisions"}],"predecessor-version":[{"id":136853,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136842\/revisions\/136853"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=136842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=136842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=136842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}