{"id":136943,"date":"2020-08-28T12:26:35","date_gmt":"2020-08-28T11:26:35","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=136943"},"modified":"2020-08-28T12:26:35","modified_gmt":"2020-08-28T11:26:35","slug":"coronavirus-y-la-vacuna-para-cuando","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943","title":{"rendered":"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo?"},"content":{"rendered":"<p>Hay m\u00e1s de 160 vacunas experimentales de Covid-19 <a href=\"https:\/\/www.who.int\/publications\/m\/item\/draft-landscape-of-covid-19-candidate-vaccines\" target=\"_blank\">en desarrollo en este momento<\/a>, y recientemente algunas de ellas han entrado en las etapas finales de pruebas en humanos. Los hallazgos iniciales son prometedores: en los primeros ensayos, estas vacunas parecen seguras y parecen estimular una respuesta inmunitaria en el cuerpo. Pero, \u00bfc\u00f3mo sabremos que una vacuna realmente est\u00e1 funcionando? \u00bfY cu\u00e1ndo podr\u00eda ser eso?<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/a48df6c804384fe9bce1bb07b1f1019d_18.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136945\" title=\"a48df6c804384fe9bce1bb07b1f1019d_18\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/a48df6c804384fe9bce1bb07b1f1019d_18.jpg\" alt=\"\" width=\"670\" height=\"377\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/a48df6c804384fe9bce1bb07b1f1019d_18.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/a48df6c804384fe9bce1bb07b1f1019d_18-300x168.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p><!--more-->A pesar de las optimistas predicciones de <a href=\"https:\/\/www.nbcnews.com\/politics\/white-house\/trump-says-without-evidence-vaccine-could-be-ready-election-day-n1236029\" target=\"_blank\">muchos pol\u00edticos<\/a>, los expertos afirman que el corto plazo es poco probable.<\/p>\n<p>Moderna y Pfizer <a href=\"https:\/\/www.nytimes.com\/2020\/07\/27\/health\/moderna-vaccine-covid.html\" target=\"_blank\">iniciaron las pruebas de la \u00faltima etapa<\/a> a fines de julio, y ambas compa\u00f1\u00edas esperan inscribir a 30.000 personas. En un <a href=\"https:\/\/www.cnn.com\/2020\/08\/10\/health\/covid-vaccine-election-moderna-clinical-trials\/index.html\" target=\"_blank\">correo electr\u00f3nico del 7 de agosto de Moderna obtenido por la CNN<\/a>, los investigadores afirmaban que hasta aquel momento hab\u00edan inscrito a 4.536 individuos. Mientras tanto, se espera que AstraZeneca comience pronto una gran prueba en los EE. UU. Llevar\u00e1 tiempo evaluar a las personas para saber primero si son aptas para participar. Adem\u00e1s, cada una de las vacunas que est\u00e1n probando estas empresas requiere dos dosis, una inyecci\u00f3n inicial y un \u00abrefuerzo\u00bb que se administra aproximadamente un mes despu\u00e9s.<\/p>\n<p>Despu\u00e9s de eso, los investigadores deber\u00e1n seguir a las personas durante varias semanas para saber si se enferman con Covid-19 mientras llevan a cabo sus vidas diarias. Los investigadores tambi\u00e9n deber\u00e1n tomar muestras de sangre de las personas y analizarlas en busca de anticuerpos contra el SARS-CoV-2, el virus que causa el Covid-19. Espec\u00edficamente, esperan que una vacuna induzca la producci\u00f3n de anticuerpos que puedan neutralizar el virus. Buscar anticuerpos neutralizantes es m\u00e1s dif\u00edcil y requiere m\u00e1s tiempo que otras pruebas de anticuerpos porque los cient\u00edficos necesitan probar los anticuerpos contra el virus real en un laboratorio de bioseguridad.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/vaccination-1400px-600x400-c-default.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136946\" title=\"vaccination-1400px-600x400-c-default\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/vaccination-1400px-600x400-c-default.jpg\" alt=\"\" width=\"670\" height=\"447\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/vaccination-1400px-600x400-c-default.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/vaccination-1400px-600x400-c-default-300x200.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>Fuente: University Texas<\/p>\n<p>El desarrollo de vacunas suele ser un proceso lento, que suele tardar una d\u00e9cada o m\u00e1s. Pero la urgencia de la pandemia de coronavirus y el <a href=\"https:\/\/onezero.medium.com\/an-experimental-coronavirus-vaccine-is-already-being-tested-on-people-9541cec49097\" target=\"_blank\">advenimiento de una nueva generaci\u00f3n de vacunas<\/a> significan que se podr\u00eda producir una vacuna Covid-19 en un tiempo r\u00e9cord. A\u00fan as\u00ed, los estudios de vacunas solo pueden ir muy r\u00e1pido.<\/p>\n<p>Los investigadores primero deben realizar ensayos de fase 1, en los que administran una vacuna en diferentes dosis a una peque\u00f1a cantidad de personas, generalmente solo unas pocas docenas, para probar la seguridad. Quieren determinar la dosis m\u00e1s alta que puedan administrar a las personas con los menores efectos secundarios. El list\u00f3n de seguridad en un estudio de vacunas es mucho m\u00e1s alto que en un ensayo de un f\u00e1rmaco o terapia para una enfermedad espec\u00edfica porque las vacunas se administran a grandes poblaciones de personas sanas.<\/p>\n<p>En un ensayo de fase 3, los investigadores determinan si una vacuna est\u00e1 funcionando comparando la cantidad de infecciones en el grupo no vacunado con las que recibieron la vacuna. La eficacia de la vacuna se mide como la diferencia en la tasa de enfermedad en el grupo tratado com placebo menos la tasa de enfermedad en el grupo vacunado, todo dividido por la tasa en el grupo de placebo.<\/p>\n<p>El riesgo tambi\u00e9n influye en la ecuaci\u00f3n. Con el uso de mascarillas y el distanciamiento f\u00edsico requerido en muchos lugares, \u00bfqu\u00e9 probabilidad hay de que las personas en el ensayo est\u00e9n expuestas al virus? Los investigadores quieren asegurarse de que tanto el grupo placebo como el grupo vacunado tengan el mismo riesgo de exposici\u00f3n.<\/p>\n<p>Consideremos un ensayo de 200 personas: 100 que reciben una vacuna y 100 que reciben un placebo. Si las 100 personas del grupo de placebo enferman y ninguno de los grupos vacunados lo hace, la vacuna tendr\u00eda una tasa de eficacia del 100%. Si hay 100 infecciones en el grupo placebo y 50 en el grupo vacunado, la eficacia ser\u00eda del 50%. Si hay el mismo n\u00famero de infecciones en ambos grupos, la eficacia ser\u00eda del 0%.<\/p>\n<p>En junio, la Administraci\u00f3n de Drogas y Alimentos de EE. UU. <a href=\"https:\/\/www.fda.gov\/news-events\/press-announcements\/coronavirus-covid-19-update-fda-takes-action-help-facilitate-timely-development-safe-effective-covid\" target=\"_blank\">public\u00f3 una gu\u00eda para la aprobaci\u00f3n de una vacuna Covid-1<\/a>9. En un comunicado afirm\u00f3 que para obtener la aprobaci\u00f3n, una vacuna deber\u00e1 prevenir la enfermedad o disminuir su gravedad en al menos el 50% de las personas vacunadas. En comparaci\u00f3n, la vacuna contra la gripe tiene una eficacia de entre un 40% y un 60% y var\u00eda cada a\u00f1o. La vacuna contra la gripe de este a\u00f1o tiene una eficacia de <a href=\"https:\/\/www.cdc.gov\/flu\/vaccines-work\/effectiveness-studies.htm\" target=\"_blank\">aproximadamente un 45%<\/a>, seg\u00fan los Centros para el Control y la Prevenci\u00f3n de Enfermedades.<\/p>\n<p>Esto se debe a que las tasas de eficacia, que se calculan a partir de un ensayo cl\u00ednico realizado en condiciones ideales, difieren de la efectividad real de una vacuna, que es lo bien que funciona en el mundo real.<\/p>\n<p>La eficacia de la vacuna suele ser menor en el mundo real. Una de las principales razones es que los ensayos cl\u00ednicos pueden <a href=\"https:\/\/onezero.medium.com\/the-coronavirus-vaccine-may-not-work-on-the-elderly-3fc176f75751\" target=\"_blank\">excluir a las personas de edad avanzada<\/a>, que no responden tan bien a las vacunas debido al debilitamiento de su sistema inmunol\u00f3gico. Los ensayos de vacunas tambi\u00e9n tienden a inscribir a personas que en general est\u00e1n sanas y los cient\u00edficos saben que las enfermedades cr\u00f3nicas pueden disminuir la efectividad de una vacuna.<\/p>\n<p>Otra raz\u00f3n de esta discrepancia es que la gran mayor\u00eda de los voluntarios del ensayo reciben el r\u00e9gimen completo de dosis que requiere una vacuna. En la vida real, las tasas de vacunaci\u00f3n disminuyen despu\u00e9s de una primera dosis, lo que hace que la vacuna sea menos eficaz.<\/p>\n<p>Los ensayos de fase 3 tambi\u00e9n podr\u00edan revelar si una vacuna Covid-19 solo podr\u00e1 prevenir los s\u00edntomas de la enfermedad Covid-19 o proteger completamente contra la infecci\u00f3n. Seg\u00fan una estimaci\u00f3n del <a href=\"https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/hcp\/planning-scenarios.html\" target=\"_blank\">10 de julio<\/a> de los Centros para el Control y la Prevenci\u00f3n de Enfermedades, alrededor del 40% de las personas que se infectan con el virus son asintom\u00e1ticas.<\/p>\n<p>\u00bfCu\u00e1ndo podremos saber si una vacuna contra el coronavirus est\u00e1 funcionando? Algunos piensan que, como muy pronto, podr\u00edamos saberlo antes de fin de a\u00f1o, pero lo m\u00e1s probable es que sea a principios de 2021.<\/p>\n<p>Despu\u00e9s hay que fabricarla y distribuirla. Paciencia. Metros, mascarillas y manos.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/M7SWPZBWEII6TNOS5WNOTQYR34.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-136947\" title=\"M7SWPZBWEII6TNOS5WNOTQYR34\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/M7SWPZBWEII6TNOS5WNOTQYR34.jpg\" alt=\"\" width=\"670\" height=\"447\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/M7SWPZBWEII6TNOS5WNOTQYR34.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/M7SWPZBWEII6TNOS5WNOTQYR34-300x200.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>Fuente. Boston Globe<\/p>\n<p>Fuentes:<\/p>\n<p><a href=\"https:\/\/coronavirus.medium.com\/how-and-when-well-know-if-a-covid-19-vaccine-is-working-7ec4cb26067f\" target=\"_blank\">How \u2014 and When \u2014 We\u2019ll Know If a Covid-19 Vaccine Is Working<\/a><\/p>\n<p><a href=\"https:\/\/coronavirus.medium.com\/oxfords-coronavirus-vaccine-shows-promise-e19dc040f8d7\" target=\"_blank\">Oxford\u2019s Coronavirus Vaccine Shows Promise<\/a><\/p>\n<p><a href=\"https:\/\/www.nytimes.com\/2020\/08\/11\/health\/russia-covid-19-vaccine-safety.html\" target=\"_blank\">This Is All Beyond Stupid.\u2019 Experts Worry About Russia\u2019s Rushed Vaccine<\/a><\/p>\n<p><a href=\"https:\/\/www.nytimes.com\/2020\/08\/15\/world\/americas\/brazil-coronavirus-vaccine.html\" target=\"_blank\">Coronavirus Crisis Has Made Brazil an Ideal Vaccine Laboratory<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay m\u00e1s de 160 vacunas experimentales de Covid-19 en desarrollo en este momento, y recientemente algunas de ellas han entrado en las etapas finales de pruebas en humanos. Los hallazgos iniciales son prometedores: en los primeros ensayos, estas vacunas parecen seguras y parecen estimular una respuesta inmunitaria en el cuerpo. Pero, \u00bfc\u00f3mo sabremos que una vacuna realmente est\u00e1 funcionando? \u00bfY cu\u00e1ndo podr\u00eda ser eso?<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hay m\u00e1s de 160 vacunas experimentales de Covid-19 en desarrollo en este momento, y recientemente algunas de ellas han entrado en las etapas finales de pruebas en humanos. Los hallazgos iniciales son prometedores: en los primeros ensayos, estas vacunas parecen seguras y parecen estimular una respuesta inmunitaria en el cuerpo. Pero, \u00bfc\u00f3mo sabremos que una\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Hay m\u00e1s de 160 vacunas experimentales de Covid-19 en desarrollo en este momento, y recientemente algunas de ellas han entrado en las etapas finales de pruebas en humanos. Los hallazgos iniciales son prometedores: en los primeros ensayos, estas vacunas parecen seguras y parecen estimular una respuesta inmunitaria en el cuerpo. Pero, \u00bfc\u00f3mo sabremos que una\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-08-28T11:26:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-08-28T11:26:35+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hay m\u00e1s de 160 vacunas experimentales de Covid-19 en desarrollo en este momento, y recientemente algunas de ellas han entrado en las etapas finales de pruebas en humanos. Los hallazgos iniciales son prometedores: en los primeros ensayos, estas vacunas parecen seguras y parecen estimular una respuesta inmunitaria en el cuerpo. Pero, \u00bfc\u00f3mo sabremos que una\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/08\\\/28\\\/136943#blogposting\",\"name\":\"Coronavirus. \\u00bfY la vacuna para cu\\u00e1ndo? - Ciencia Marina y otros asuntos\",\"headline\":\"Coronavirus. \\u00bfY la vacuna para cu\\u00e1ndo?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/08\\\/a48df6c804384fe9bce1bb07b1f1019d_18.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/08\\\/28\\\/136943\\\/#articleImage\",\"width\":670,\"height\":377},\"datePublished\":\"2020-08-28T12:26:35+01:00\",\"dateModified\":\"2020-08-28T12:26:35+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/08\\\/28\\\/136943#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/08\\\/28\\\/136943#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/08\\\/28\\\/136943#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/08\\\/28\\\/136943#listItem\",\"name\":\"Coronavirus. \\u00bfY la vacuna para cu\\u00e1ndo?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/08\\\/28\\\/136943#listItem\",\"position\":3,\"name\":\"Coronavirus. \\u00bfY la vacuna para cu\\u00e1ndo?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/08\\\/28\\\/136943#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/08\\\/28\\\/136943\",\"name\":\"Coronavirus. \\u00bfY la vacuna para cu\\u00e1ndo? - Ciencia Marina y otros asuntos\",\"description\":\"Hay m\\u00e1s de 160 vacunas experimentales de Covid-19 en desarrollo en este momento, y recientemente algunas de ellas han entrado en las etapas finales de pruebas en humanos. Los hallazgos iniciales son prometedores: en los primeros ensayos, estas vacunas parecen seguras y parecen estimular una respuesta inmunitaria en el cuerpo. Pero, \\u00bfc\\u00f3mo sabremos que una\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/08\\\/28\\\/136943#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-08-28T12:26:35+01:00\",\"dateModified\":\"2020-08-28T12:26:35+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo? - Ciencia Marina y otros asuntos","description":"Hay m\u00e1s de 160 vacunas experimentales de Covid-19 en desarrollo en este momento, y recientemente algunas de ellas han entrado en las etapas finales de pruebas en humanos. Los hallazgos iniciales son prometedores: en los primeros ensayos, estas vacunas parecen seguras y parecen estimular una respuesta inmunitaria en el cuerpo. Pero, \u00bfc\u00f3mo sabremos que una","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943#blogposting","name":"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo? - Ciencia Marina y otros asuntos","headline":"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/08\/a48df6c804384fe9bce1bb07b1f1019d_18.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943\/#articleImage","width":670,"height":377},"datePublished":"2020-08-28T12:26:35+01:00","dateModified":"2020-08-28T12:26:35+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943#listItem","name":"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943#listItem","position":3,"name":"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943","name":"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo? - Ciencia Marina y otros asuntos","description":"Hay m\u00e1s de 160 vacunas experimentales de Covid-19 en desarrollo en este momento, y recientemente algunas de ellas han entrado en las etapas finales de pruebas en humanos. Los hallazgos iniciales son prometedores: en los primeros ensayos, estas vacunas parecen seguras y parecen estimular una respuesta inmunitaria en el cuerpo. Pero, \u00bfc\u00f3mo sabremos que una","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-08-28T12:26:35+01:00","dateModified":"2020-08-28T12:26:35+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo? - Ciencia Marina y otros asuntos","og:description":"Hay m\u00e1s de 160 vacunas experimentales de Covid-19 en desarrollo en este momento, y recientemente algunas de ellas han entrado en las etapas finales de pruebas en humanos. Los hallazgos iniciales son prometedores: en los primeros ensayos, estas vacunas parecen seguras y parecen estimular una respuesta inmunitaria en el cuerpo. Pero, \u00bfc\u00f3mo sabremos que una","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-08-28T11:26:35+00:00","article:modified_time":"2020-08-28T11:26:35+00:00","twitter:card":"summary","twitter:title":"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo? - Ciencia Marina y otros asuntos","twitter:description":"Hay m\u00e1s de 160 vacunas experimentales de Covid-19 en desarrollo en este momento, y recientemente algunas de ellas han entrado en las etapas finales de pruebas en humanos. Los hallazgos iniciales son prometedores: en los primeros ensayos, estas vacunas parecen seguras y parecen estimular una respuesta inmunitaria en el cuerpo. Pero, \u00bfc\u00f3mo sabremos que una","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"136943","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 14:50:35","updated":"2026-05-26 19:35:35","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCoronavirus. \u00bfY la vacuna para cu\u00e1ndo?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Coronavirus. \u00bfY la vacuna para cu\u00e1ndo?","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/08\/28\/136943"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136943"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=136943"}],"version-history":[{"count":4,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136943\/revisions"}],"predecessor-version":[{"id":136950,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/136943\/revisions\/136950"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=136943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=136943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=136943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}