{"id":137061,"date":"2020-11-25T17:36:37","date_gmt":"2020-11-25T16:36:37","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=137061"},"modified":"2020-11-25T17:36:37","modified_gmt":"2020-11-25T16:36:37","slug":"las-vacunas-contra-el-coronavirus-y-los-miedos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061","title":{"rendered":"Las vacunas contra el coronavirus y los miedos"},"content":{"rendered":"<p>El <a href=\"https:\/\/www.nytimes.com\/2006\/03\/20\/obituaries\/us\/e-russell-alexander-77-public-health-expert.html\" target=\"_blank\">Dr. E. Russell Alexander<\/a> hablando sobre el programa de vacunaci\u00f3n masivo frente a la posible epidemia de gripe porcina de 1976, declar\u00f3: \u201cMi opini\u00f3n es que se debe ser conservador al introducir material extra\u00f1o en el cuerpo humano. Eso siempre es cierto &#8230; especialmente cuando se habla de 200 millones de personas. La necesidad debe estimarse de forma conservadora. Si no se necesita suministrarlo, no lo haga\u201d.. El Dr. Alexander era miembro de un comit\u00e9 sobre pr\u00e1cticas de inmunizaci\u00f3n que asesoraba a los Centros para el Control y la Prevenci\u00f3n de Enfermedades cuando se inform\u00f3 por primera vez sobre <a href=\"https:\/\/en.wikipedia.org\/wiki\/1976_swine_flu_outbreak\" target=\"_blank\">la gripe porcina en Fort Dix<\/a>, Nueva Jersey, en 1976. En 1976, unos 500 soldados se infectaron con gripe porcina en un periodo de pocas semanas. Sin embargo, al final de ese mes, los investigadores encontraron que <a href=\"https:\/\/www.bbc.com\/future\/article\/20200918-the-fiasco-of-the-us-swine-flu-affair-of-1976\" target=\"_blank\">el virus hab\u00eda, literalmente, \u00abdesaparecido misteriosamente\u00bb<\/a>.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/President_Ford_receives_a_swine_flu_inoculation_-_NARA_-_7064718.jpg\" target=\"_blank\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137081\" title=\"President_Ford_receives_a_swine_flu_inoculation_-_NARA_-_7064718\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/President_Ford_receives_a_swine_flu_inoculation_-_NARA_-_7064718.jpg\" alt=\"\" width=\"600\" height=\"367\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/President_Ford_receives_a_swine_flu_inoculation_-_NARA_-_7064718.jpg 600w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/President_Ford_receives_a_swine_flu_inoculation_-_NARA_-_7064718-300x183.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><a title=\"w:en:David Hume Kennerly\" href=\"https:\/\/en.wikipedia.org\/wiki\/en:David_Hume_Kennerly\">David Hume Kennerly<\/a>\u00a0&#8211;\u00a0<a title=\"en:Gerald R. Ford Presidential Library\" href=\"https:\/\/en.wikipedia.org\/wiki\/Gerald_R._Ford_Presidential_Library\">Gerald R. Ford Presidential Library<\/a>:\u00a0<a href=\"https:\/\/www.fordlibrarymuseum.gov\/avproj\/swineflu.asp\" rel=\"nofollow\">B1874-07A<\/a><\/p>\n<p><!--more--><\/p>\n<p>El Dr. Alexander recomend\u00f3 precauci\u00f3n y abog\u00f3 por el almacenamiento de la vacuna contra la gripe, sin lanzar programas de vacunaci\u00f3n hasta que se pudiera demostrar que la gripe se hab\u00eda extendido m\u00e1s all\u00e1 de Fort Dix. Pero el comit\u00e9 decidi\u00f3 actuar r\u00e1pidamente para cortar el contagio potencial y alrededor de 40 millones de estadounidenses recibieron la vacuna. Un peque\u00f1o porcentaje de los tratados desarrollaron el s\u00edndrome de <a href=\"https:\/\/medlineplus.gov\/spanish\/ency\/article\/000684.htm\" target=\"_blank\">Guillain-Barr\u00e9,<\/a> un trastorno similar a la polio que causa par\u00e1lisis, y algunas muertes de pacientes se relacionaron con las vacunas.<\/p>\n<p>Una vacuna imita la infecci\u00f3n para dar al sistema inmune una visi\u00f3n previa de la enfermedad. La vacunaci\u00f3n se convirti\u00f3 en una herramienta de salud p\u00fablica despu\u00e9s de que Edward Jenner demostr\u00f3 en 1796 que la inoculaci\u00f3n con <a href=\"https:\/\/www.tandfonline.com\/doi\/abs\/10.1080\/08998280.2005.11928028&quot;\" target=\"_blank\">la viruela menos virulenta podr\u00eda prevenir la viruela<\/a>. Despu\u00e9s de la muerte de su hijo por la viruela, Benjamin Franklin <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC2653186\/\" target=\"_blank\">lament\u00f3<\/a> su decisi\u00f3n de no vacunar a su hijo contra ella. Hoy en d\u00eda, las <a href=\"https:\/\/royalsocietypublishing.org\/doi\/10.1098\/rstb.2013.0433\" target=\"_blank\">vacunas<\/a> son ampliamente acreditadas para la <a href=\"https:\/\/www.cdc.gov\/vaccines\/vpd\/vaccines-list.html\" target=\"_blank\">prevenci\u00f3n y erradicaci\u00f3n<\/a> de muchas de las enfermedades mortales que antes tem\u00edan.<\/p>\n<p>Las vacunas <a href=\"http:\/\/www.imgt.org\/IMGTeducation\/Tutorials\/ImmuneSystem\/UK\/the_immune_system.pdf\" target=\"_blank\">preparan el sistema inmune<\/a> para que genere prote\u00ednas que combaten enfermedades llamadas anticuerpos, que buscan y atacan si alguna vez aparece el verdadero virus infeccioso.<\/p>\n<p>Las vacunas tradicionales contra virus son <a href=\"https:\/\/www.cdc.gov\/vaccines\/hcp\/conversations\/downloads\/vacsafe-understand-color-office.pdf\" target=\"_blank\">versiones<\/a> debilitadas del virus completo que no pueden causar la enfermedad; o est\u00e1n hechos de prote\u00ednas virales caracter\u00edsticas llamadas ant\u00edgenos, que luego provocan una respuesta inmune. Un ant\u00edgeno en el nuevo coronavirus SARS-CoV-2 es la <a href=\"https:\/\/gacetamedica.com\/investigacion\/el-covid-19-utiliza-una-llave-virica-para-introducirse-en-las-celulas-humanas\/\" target=\"_blank\">prote\u00edna espiga (S)<\/a>, que forma una estructura similar a una corona, a trav\u00e9s de la cual el virus se adhiere a las c\u00e9lulas pulmonares y respiratorias.<\/p>\n<p>Sin embargo, el desarrollo de vacunas basadas en las prote\u00ednas virales es un proceso lento debido a las dificultades para producir prote\u00ednas puras con est\u00e1ndares m\u00e9dicos en grandes cantidades. Pero ahora los cient\u00edficos han desarrollado un tipo diferente de vacuna: <a href=\"https:\/\/theconversation.com\/coronavirus-a-new-type-of-vaccine-using-rna-could-help-defeat-covid-19-133217\" target=\"_blank\">las vacunas de ARNm<\/a>.<\/p>\n<p>En lugar de inocular a una persona una vacuna hecha con prote\u00ednas del virus, se inyecta <a href=\"https:\/\/es.wikipedia.org\/wiki\/ARN_mensajero\" target=\"_blank\">ARNm<\/a>, que es el c\u00f3digo biol\u00f3gico que las c\u00e9lulas leen y traducen para producir sus propias prote\u00ednas. Por lo tanto, en lugar de las vacunas tradicionales de prote\u00ednas virales, una vacuna de ARNm proporciona una copia sint\u00e9tica del c\u00f3digo para sintentizar prote\u00ednas individuales\u00a0 del virus, que el cuerpo del hu\u00e9sped utiliza para producir la prote\u00edna viral. Al igual que con otras vacunas, la presencia de la prote\u00edna inicia el sistema inmunol\u00f3gico del cuerpo para combatir el virus.<\/p>\n<p>Una gran ventaja de las vacunas de ARNm es que los cient\u00edficos pueden omitir la producci\u00f3n de prote\u00ednas en el laboratorio al inyectar directamente las instrucciones moleculares para hacer que la prote\u00edna ingrese al cuerpo humano.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935546.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137072\" title=\"d41586-020-01221-y_17935546\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935546.png\" alt=\"\" width=\"600\" height=\"1359\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935546.png 600w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935546-132x300.png 132w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935546-452x1024.png 452w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Coronavirus. \u00bfC\u00f3mo se est\u00e1n dise\u00f1ando las vacunas?<\/strong><\/p>\n<p>Los cient\u00edficos est\u00e1n desarrollando <a href=\"https:\/\/www.nytimes.com\/2020\/05\/20\/health\/coronavirus-vaccines.html\" target=\"_blank\">m\u00e1s de 100 vacunas contra el coronavirus<\/a> utilizando una variedad de t\u00e9cnicas, algunas de las cuales est\u00e1n bien establecidas y algunas de las cuales nunca antes han sido aprobadas para uso m\u00e9dico.<\/p>\n<p>La mayor\u00eda de estas vacunas se dirigen a las llamadas <a href=\"https:\/\/www.nytimes.com\/interactive\/2020\/04\/03\/science\/coronavirus-genome-bad-news-wrapped-in-protein.html\" target=\"_blank\">prote\u00ednas de espiga o de punta \u201cSpike\u201d<\/a> que cubren el virus y lo ayudan a <a href=\"https:\/\/www.nytimes.com\/interactive\/2020\/03\/11\/science\/how-coronavirus-hijacks-your-cells.html\" target=\"_blank\">invadir las c\u00e9lulas humanas<\/a>. El sistema inmunitario puede desarrollar anticuerpos que se adhieren a las prote\u00ednas de la espiga y detienen el virus.<\/p>\n<p>Una vacuna con \u00e9xito para el coronavirus SARS-CoV-2 ense\u00f1ar\u00eda al sistema inmunitario de las personas a producir anticuerpos contra el virus sin causar la enfermedad y lanzar\u00eda los mecanismos inmunes que impedir\u00edan su replicaci\u00f3n con lo cual no habr\u00eda liberaci\u00f3n de virus. Es decir una vacuna sin \u00abfugas\u00bb.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935130.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137073\" title=\"d41586-020-01221-y_17935130\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935130.png\" alt=\"\" width=\"600\" height=\"442\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935130.png 600w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935130-300x221.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Vacunas de virus enteros<\/strong><\/p>\n<p>Vacunas que modifican todo el coronavirus para provocar una respuesta inmune.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935124.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137074\" title=\"d41586-020-01221-y_17935124\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935124.png\" alt=\"\" width=\"600\" height=\"677\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935124.png 600w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935124-265x300.png 265w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Vacunas inactivadas y vivas atenuadas<\/strong><\/p>\n<p>Varios equipos est\u00e1n desarrollando vacunas utilizando el virus en s\u00ed mismo, en forma debilitada o inactiva que no puede causar la enfermedad. Muchas vacunas existentes se hacen de esta manera, como las contra el sarampi\u00f3n y la poliomielitis, pero requieren pruebas de seguridad exhaustivas. Hacer estas vacunas significa cultivar virus, en gran cantidad. Las vacunas contra la gripe se cultivan generalmente en huevos de gallina, y otras vacunas se cultivan en fermentadores con c\u00e9lulas en suspensi\u00f3n. Estos procedimientos pueden necesitar meses para producir un lote de vacunas nuevas.<\/p>\n<p>EJEMPLOS: Las vacunas convencionales contra la gripe, la varicela, el sarampi\u00f3n, las <a href=\"https:\/\/www.nytimes.com\/2020\/05\/02\/us\/politics\/vaccines-coronavirus-research.html\">paperas<\/a> y la rub\u00e9ola se incluyen en esta categor\u00eda.<\/p>\n<p>EMPRESAS QUE DESARROLLAN O HAN DESARROLLADO VACUNAS DE SARS-COV-2: <a href=\"https:\/\/www.nytimes.com\/2020\/05\/04\/business\/coronavirus-china-vaccine.html\" target=\"_blank\">Sinovac<\/a> en Beijing usa una versi\u00f3n inactivada de SARS-CoV-2.<\/p>\n<p><strong>Vacunas Gen\u00e9ticas<\/strong><\/p>\n<p>Vacunas que usan parte del c\u00f3digo gen\u00e9tico del coronavirus.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935118.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137075\" title=\"d41586-020-01221-y_17935118\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935118.png\" alt=\"\" width=\"600\" height=\"712\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935118.png 600w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935118-252x300.png 252w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Vacunas de ADN<\/strong><\/p>\n<p>Varias vacunas experimentales de coronavirus no inoculan virus completos. En cambio, proporcionan instrucciones gen\u00e9ticas para construir una prote\u00edna viral. La prote\u00edna puede estimular el sistema inmunitario para que produzca anticuerpos y ayudar a montar otras defensas contra el coronavirus.<\/p>\n<p>Uno de estos enfoques gen\u00e9ticos se conoce como vacuna de ADN. Se inocula ADN dise\u00f1ado en el laboratorio que incorpora alg\u00fan gen del virus que codifica para que se sinteticen prote\u00ednas que ser\u00e1n reconocidas por el sistema inmune.<\/p>\n<p>Las vacunas prototipo de ADN basadas en la prote\u00edna espiga protegieron a\u00a0<a href=\"https:\/\/www.nytimes.com\/2020\/05\/20\/health\/coronavirus-vaccine-harvard.html\" target=\"_blank\">monos del coronavirus.<\/a><\/p>\n<p>EJEMPLOS: Las vacunas de ADN han sido aprobadas para casos veterinarios como el melanoma canino y el virus del Nilo Occidental en caballos. No hay vacunas de ADN aprobadas para su uso en humanos, pero los investigadores est\u00e1n realizando pruebas para ver si pueden ser efectivas para enfermedades como el Zika y la gripe.<\/p>\n<p>EMPRESAS: Inovio y otros.<\/p>\n<p><strong>Vacunas de ARN<\/strong><\/p>\n<p>Algunos investigadores usan ARN mensajero. Las c\u00e9lulas leen el ARNm y producen prote\u00ednas de pico o espiga (spike) que provocan una respuesta inmune.<\/p>\n<p>Las compa\u00f1\u00edas Pfizer y Moderna completaron recientemente sus fases 3 de ensayos cl\u00ednicos y est\u00e1n tramitando su empleo de urgencia ante distintas agencias reguladoras del medicamento del mundo. Sus n\u00edveles de protecci\u00f3n y de seguridad son elevados.<\/p>\n<p>Tanto las vacunas de ARN como las de ADN pueden producirse m\u00e1s r\u00e1pidamente que las que emplean m\u00e9todos tradicionales.<\/p>\n<p>EJEMPLOS: No hay vacunas de ARN aprobadas, pero est\u00e1n en ensayos cl\u00ednicos para MERS y otras enfermedades.<\/p>\n<p>EMPRESAS: <a href=\"https:\/\/www.nih.gov\/news-events\/news-releases\/promising-interim-results-clinical-trial-nih-moderna-covid-19-vaccine\" target=\"_blank\">Moderna<\/a>, <a href=\"https:\/\/www.pfizer.com\/news\/press-release\/press-release-detail\/pfizer-and-biontech-submit-emergency-use-authorization\" target=\"_blank\">Pfizer<\/a> y <a href=\"https:\/\/biontech.de\/\" target=\"_blank\">BioNTech<\/a>, <a href=\"https:\/\/www.curevac.com\/en\/\" target=\"_blank\">CureVac<\/a> y otros.<\/p>\n<p><strong>Vacunas de vectores virales<\/strong><\/p>\n<p>Vacunas que usan un virus para administrar genes de coronavirus en las c\u00e9lulas.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935122.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137076\" title=\"d41586-020-01221-y_17935122\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935122.png\" alt=\"\" width=\"600\" height=\"681\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935122.png 600w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935122-264x300.png 264w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Vacunas que usan adenovirus u otros virus<\/strong><\/p>\n<p>Alrededor de 25 grupos est\u00e1n trabajando en vacunas de vectores virales. Un virus como el sarampi\u00f3n o el adenovirus est\u00e1 gen\u00e9ticamente modificado para que pueda producir prote\u00ednas de coronavirus en el cuerpo. Estos virus est\u00e1n debilitados para que no puedan causar enfermedades. Hay dos tipos: los que a\u00fan pueden replicar dentro de las c\u00e9lulas y los que no pueden porque los genes clave han sido desactivados.<\/p>\n<p>EJEMPLOS: Se utilizan varias vacunas de vectores de virus para vacunar a los animales contra la rabia y el moquillo. Johnson &amp; Johnson <a href=\"https:\/\/www.jnj.com\/tag\/hiv\" target=\"_blank\">ha desarrollado vacunas contra el H.I.V<\/a>. y <a href=\"https:\/\/www.jnj.com\/latest-news\/latest-facts-about-johnson-johnson-ebola-vaccine\" target=\"_blank\">vacunas contra el \u00c9bola<\/a> con un adenovirus. Ambos han demostrado ser seguros en humanos y ahora est\u00e1n en ensayos de eficacia.<\/p>\n<p>EMPRESAS: <a href=\"https:\/\/www.jnj.com\/coronavirus\" target=\"_blank\">Johnson &amp; Johnson<\/a>, <a href=\"https:\/\/www.globaltimes.cn\/content\/1206031.shtml\" target=\"_blank\">CanSino<\/a>, <a href=\"https:\/\/www.astrazeneca.com\/media-centre\/press-releases\/2020\/azd1222hlr.html\" target=\"_blank\">Astra Zeneca<\/a>-Universidad de Oxford, <a href=\"https:\/\/sputnikvaccine.com\/esp\/\" target=\"_blank\">Sputnik<\/a> y otros.<\/p>\n<p><strong>Vacunas a base de prote\u00ednas<\/strong><\/p>\n<p>Vacunas que usan una prote\u00edna de coronavirus o un fragmento de prote\u00edna<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935126.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137077\" title=\"d41586-020-01221-y_17935126\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935126.png\" alt=\"\" width=\"601\" height=\"1059\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935126.png 601w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935126-170x300.png 170w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/d41586-020-01221-y_17935126-581x1024.png 581w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/><\/a><\/p>\n<p><strong>Vacunas de part\u00edculas similares a virus<\/strong><\/p>\n<p>Muchos investigadores quieren inyectar prote\u00ednas de coronavirus directamente en el cuerpo. Tambi\u00e9n se pueden usar fragmentos de prote\u00ednas o capas proteicas que imitan la capa externa del coronavirus. No pueden causar enfermedades porque no son virus reales, pero el sistema inmunitario se activa al reconocerlas como prote\u00ednas del coronavirus.<\/p>\n<p>EJEMPLOS: La vacuna contra el <a href=\"https:\/\/www.nytimes.com\/2019\/06\/27\/health\/hpv-vaccine-warts-cancer.html\">VPH<\/a> entra en esta categor\u00eda.<\/p>\n<p>EMPRESAS: <a href=\"https:\/\/www.gsk.com\/en-gb\/media\/press-releases\/medicago-and-gsk-announce-start-of-phase-23-clinical-trials-of-adjuvanted-covid-19-vaccine-candidate\/\" target=\"_blank\">Medicago<\/a>, <a href=\"https:\/\/www.doherty.edu.au\/news-events\/news\/mrff-backs-melbourne-based-covid-19-vaccine-candidate\" target=\"_blank\">Doherty Institute<\/a> y otros.<\/p>\n<p><strong>Vacunas recombinantes<\/strong><\/p>\n<p>Se inserta el gen de un virus en c\u00e9lulas como las de la levadura, que producir\u00edan prote\u00ednas virales. Se podr\u00edan recoger y utilizarse en una vacuna. Una vacuna de coronavirus de este dise\u00f1o contendr\u00eda prote\u00ednas de espiga enteras o peque\u00f1os trozos de la prote\u00edna.<\/p>\n<p>EJEMPLOS: Esta categor\u00eda incluye algunas vacunas contra el herpes z\u00f3ster y la hepatitis B.<\/p>\n<p>EMPRESAS: <a href=\"https:\/\/ir.novavax.com\/news-releases\/news-release-details\/novavax-covid-19-vaccine-granted-fast-track-designation-us-fda\" target=\"_blank\">Novavax<\/a> y otros.<\/p>\n<p><strong>Ensayos de la industria<\/strong><\/p>\n<p>M\u00e1s del 70% de los grupos que lideran los esfuerzos de investigaci\u00f3n de vacunas son de empresas industriales o privadas. Los ensayos cl\u00ednicos comienzan con peque\u00f1os estudios de seguridad en animales y personas, seguidos de ensayos mucho m\u00e1s grandes para determinar si una vacuna genera una respuesta inmune.<\/p>\n<p><strong>Fuentes<\/strong><\/p>\n<p><a href=\"https:\/\/www.who.int\/publications\/m\/item\/draft-landscape-of-covid-19-candidate-vaccines\" target=\"_blank\">Draft landscape of COVID-19 candidate vaccines. WHO.<\/a><\/p>\n<p><a href=\"https:\/\/www.niaid.nih.gov\/diseases-conditions\/coronaviruses-therapeutics-vaccines\" target=\"_blank\">Developing Therapeutics and Vaccines for Coronaviruses<\/a><\/p>\n<p><a href=\"https:\/\/www.nejm.org\/doi\/full\/10.1056\/NEJMp2005630\" target=\"_blank\">Developing Covid-19 Vaccines at Pandemic Speed<\/a><\/p>\n<p><a href=\"https:\/\/www.nejm.org\/doi\/full\/10.1056\/nejmoa2022483\" target=\"_blank\">An mRNA Vaccine against SARS-CoV-2 \u2014 Preliminary Report<\/a><\/p>\n<p><a href=\"https:\/\/www.nytimes.com\/interactive\/2020\/05\/20\/science\/coronavirus-vaccine-development.html\" target=\"_blank\">Different Approaches to a Coronavirus Vaccine\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Dr. E. Russell Alexander hablando sobre el programa de vacunaci\u00f3n masivo frente a la posible epidemia de gripe porcina de 1976, declar\u00f3: \u201cMi opini\u00f3n es que se debe ser conservador al introducir material extra\u00f1o en el cuerpo humano. Eso siempre es cierto &#8230; especialmente cuando se habla de 200 millones de personas. La necesidad debe estimarse de forma conservadora. Si no se necesita suministrarlo, no lo haga\u201d.. El Dr. Alexander era miembro de un comit\u00e9 sobre pr\u00e1cticas de inmunizaci\u00f3n que asesoraba a los Centros para el Control y la Prevenci\u00f3n de Enfermedades cuando se inform\u00f3 por primera vez sobre\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Dr. E. Russell Alexander hablando sobre el programa de vacunaci\u00f3n masivo frente a la posible epidemia de gripe porcina de 1976, declar\u00f3: \u201cMi opini\u00f3n es que se debe ser conservador al introducir material extra\u00f1o en el cuerpo humano. Eso siempre es cierto ... especialmente cuando se habla de 200 millones de personas. La necesidad\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las vacunas contra el coronavirus y los miedos - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"El Dr. E. Russell Alexander hablando sobre el programa de vacunaci\u00f3n masivo frente a la posible epidemia de gripe porcina de 1976, declar\u00f3: \u201cMi opini\u00f3n es que se debe ser conservador al introducir material extra\u00f1o en el cuerpo humano. Eso siempre es cierto ... especialmente cuando se habla de 200 millones de personas. La necesidad\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-11-25T16:36:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-11-25T16:36:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las vacunas contra el coronavirus y los miedos - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Dr. E. Russell Alexander hablando sobre el programa de vacunaci\u00f3n masivo frente a la posible epidemia de gripe porcina de 1976, declar\u00f3: \u201cMi opini\u00f3n es que se debe ser conservador al introducir material extra\u00f1o en el cuerpo humano. Eso siempre es cierto ... especialmente cuando se habla de 200 millones de personas. La necesidad\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/11\\\/25\\\/137061#blogposting\",\"name\":\"Las vacunas contra el coronavirus y los miedos - Ciencia Marina y otros asuntos\",\"headline\":\"Las vacunas contra el coronavirus y los miedos\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/11\\\/President_Ford_receives_a_swine_flu_inoculation_-_NARA_-_7064718.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/11\\\/25\\\/137061\\\/#articleImage\",\"width\":600,\"height\":367},\"datePublished\":\"2020-11-25T17:36:37+01:00\",\"dateModified\":\"2020-11-25T17:36:37+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/11\\\/25\\\/137061#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/11\\\/25\\\/137061#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/11\\\/25\\\/137061#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/11\\\/25\\\/137061#listItem\",\"name\":\"Las vacunas contra el coronavirus y los miedos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/11\\\/25\\\/137061#listItem\",\"position\":3,\"name\":\"Las vacunas contra el coronavirus y los miedos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/11\\\/25\\\/137061#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/11\\\/25\\\/137061\",\"name\":\"Las vacunas contra el coronavirus y los miedos - Ciencia Marina y otros asuntos\",\"description\":\"El Dr. E. Russell Alexander hablando sobre el programa de vacunaci\\u00f3n masivo frente a la posible epidemia de gripe porcina de 1976, declar\\u00f3: \\u201cMi opini\\u00f3n es que se debe ser conservador al introducir material extra\\u00f1o en el cuerpo humano. Eso siempre es cierto ... especialmente cuando se habla de 200 millones de personas. La necesidad\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/11\\\/25\\\/137061#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-11-25T17:36:37+01:00\",\"dateModified\":\"2020-11-25T17:36:37+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Las vacunas contra el coronavirus y los miedos - Ciencia Marina y otros asuntos","description":"El Dr. E. Russell Alexander hablando sobre el programa de vacunaci\u00f3n masivo frente a la posible epidemia de gripe porcina de 1976, declar\u00f3: \u201cMi opini\u00f3n es que se debe ser conservador al introducir material extra\u00f1o en el cuerpo humano. Eso siempre es cierto ... especialmente cuando se habla de 200 millones de personas. La necesidad","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061#blogposting","name":"Las vacunas contra el coronavirus y los miedos - Ciencia Marina y otros asuntos","headline":"Las vacunas contra el coronavirus y los miedos","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/11\/President_Ford_receives_a_swine_flu_inoculation_-_NARA_-_7064718.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061\/#articleImage","width":600,"height":367},"datePublished":"2020-11-25T17:36:37+01:00","dateModified":"2020-11-25T17:36:37+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061#listItem","name":"Las vacunas contra el coronavirus y los miedos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061#listItem","position":3,"name":"Las vacunas contra el coronavirus y los miedos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061","name":"Las vacunas contra el coronavirus y los miedos - Ciencia Marina y otros asuntos","description":"El Dr. E. Russell Alexander hablando sobre el programa de vacunaci\u00f3n masivo frente a la posible epidemia de gripe porcina de 1976, declar\u00f3: \u201cMi opini\u00f3n es que se debe ser conservador al introducir material extra\u00f1o en el cuerpo humano. Eso siempre es cierto ... especialmente cuando se habla de 200 millones de personas. La necesidad","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-11-25T17:36:37+01:00","dateModified":"2020-11-25T17:36:37+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Las vacunas contra el coronavirus y los miedos - Ciencia Marina y otros asuntos","og:description":"El Dr. E. Russell Alexander hablando sobre el programa de vacunaci\u00f3n masivo frente a la posible epidemia de gripe porcina de 1976, declar\u00f3: \u201cMi opini\u00f3n es que se debe ser conservador al introducir material extra\u00f1o en el cuerpo humano. Eso siempre es cierto ... especialmente cuando se habla de 200 millones de personas. La necesidad","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-11-25T16:36:37+00:00","article:modified_time":"2020-11-25T16:36:37+00:00","twitter:card":"summary","twitter:title":"Las vacunas contra el coronavirus y los miedos - Ciencia Marina y otros asuntos","twitter:description":"El Dr. E. Russell Alexander hablando sobre el programa de vacunaci\u00f3n masivo frente a la posible epidemia de gripe porcina de 1976, declar\u00f3: \u201cMi opini\u00f3n es que se debe ser conservador al introducir material extra\u00f1o en el cuerpo humano. Eso siempre es cierto ... especialmente cuando se habla de 200 millones de personas. La necesidad","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"137061","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 19:29:56","updated":"2026-05-26 19:36:53","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLas vacunas contra el coronavirus y los miedos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Las vacunas contra el coronavirus y los miedos","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/11\/25\/137061"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137061"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=137061"}],"version-history":[{"count":18,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137061\/revisions"}],"predecessor-version":[{"id":137086,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137061\/revisions\/137086"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=137061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=137061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=137061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}