{"id":137088,"date":"2020-12-02T17:41:48","date_gmt":"2020-12-02T16:41:48","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=137088"},"modified":"2020-12-02T17:41:48","modified_gmt":"2020-12-02T16:41:48","slug":"son-las-vacunas-frente-al-coronavirus-eficaces-en-los-mayores-de-edad","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088","title":{"rendered":"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad?"},"content":{"rendered":"<p>No pensemos que una vacuna contra el virus causante de la Covid-19 erradicar\u00e1 el coronavirus de nuestras vidas a corto plazo o que nuestra inmunidad colectiva detendr\u00e1 la propagaci\u00f3n. Por ahora, hay que centrar esos esfuerzos en mantener el distanciamiento f\u00edsico y el uso de medidas de protecci\u00f3n individual, como las mascarillas o la higiene de manos, hasta que la ciencia sugiera lo contrario. A\u00fan se desconoce cu\u00e1nta inmunidad generar\u00e1n las vacunas en la poblaci\u00f3n y cu\u00e1nto tiempo durar\u00e1. Despu\u00e9s de d\u00e9cadas de esfuerzo, todav\u00eda no existe una vacuna contra el VIH. Y aunque se han desarrollado vacunas para muchos otros tipos de virus, desde las paperas hasta la gripe, nadie ha descubierto una para el resfriado com\u00fan, lo que preocupa a los investigadores en parte porque puede ser causado por varios coronavirus y unos 160 rinovirus diferentes.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/Ancianos.EFEEPAWILL-OLIVERArchivo.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137098\" title=\"Ancianos.EFEEPAWILL-OLIVERArchivo\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/Ancianos.EFEEPAWILL-OLIVERArchivo.jpg\" alt=\"\" width=\"670\" height=\"447\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/Ancianos.EFEEPAWILL-OLIVERArchivo.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/Ancianos.EFEEPAWILL-OLIVERArchivo-300x200.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>Fuente:\u00a0EFEEPAWILL-OLIVER<\/p>\n<p><!--more-->Cuando nos recuperamos de una infecci\u00f3n viral, generalmente desarrollamos cierto nivel de inmunidad, que nos protege de la reinfecci\u00f3n. Pero el SARS-CoV-2, el coronavirus que causa el Covid-19, ha causado\u00a0 desde ausencia de s\u00edntomas hasta s\u00edntomas leves y un r\u00e1pido deterioro en casos severos y muerte. Infecta e inflama los pulmones, a veces el intestino, y tal vez incluso el cerebro.<\/p>\n<p>A veces los virus cambian. No tiene que mutar a una cepa completamente nueva para que la inmunidad sea menos eficaz. Las partes del virus frente a las que desarrollamos una respuesta inmune solo necesitan cambiar de forma relativamente menor para evadir la inmunidad. Estos son los cambios antig\u00e9nicos, y explican por qu\u00e9 la vacuna contra la gripe debe ser redise\u00f1ada cada a\u00f1o. Solo el tiempo nos dir\u00e1 la tasa de mutaci\u00f3n para el SARS-CoV-2 y su influencia sobre los ant\u00edgenos y las vacunas que se est\u00e1n dise\u00f1ando y fabricando.<\/p>\n<p>Las vacunas, incluidas las de Moderna y Pfizer, generalmente se dise\u00f1an para la poblaci\u00f3n joven saludable y solo m\u00e1s tarde se centran en los grupos m\u00e1s vulnerables. El ambicioso calendario de lanzamiento de vacunas probablemente representa la l\u00ednea de partida, no la l\u00ednea de meta, cuando se trata de la inmunidad de los mayores.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/file-20200714-18-k3tuue.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137097\" title=\"file-20200714-18-k3tuue\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/file-20200714-18-k3tuue.jpg\" alt=\"\" width=\"670\" height=\"330\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/file-20200714-18-k3tuue.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/file-20200714-18-k3tuue-300x147.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>A medida que envejecemos, nuestros cuerpos pierden la capacidad de responder a nuevas amenazas y reconocer a las que hemos estado expuestos anteriormente, lo que significa que los adultos mayores no desarrollan una defensa vigorosa despu\u00e9s de las vacunas.<\/p>\n<p>Tomemos, por ejemplo, la vacuna contra la gripe: para los que tienen entre cuarenta y cincuenta a\u00f1os, las vacunas contra la gripe tienen <a href=\"https:\/\/www.cdc.gov\/flu\/vaccines-work\/past-seasons-estimates.html\" target=\"_blank\">una efectividad entre 30% y 60%.<\/a> Sin embargo, para las personas mayores de 65 a\u00f1os, la efectividad con frecuencia se <a href=\"https:\/\/www.cdc.gov\/flu\/vaccines-work\/2017-2018.html\" target=\"_blank\">reduce al 10-20%.<\/a>o Un art\u00edculo publicado el mes pasado en el <a href=\"https:\/\/www.nejm.org\/doi\/full\/10.1056\/NEJMp2006761\" target=\"_blank\">New England Journal of Medicine argument\u00f3<\/a> que \u00abla respuesta a la pandemia sigue siendo dificultada por nuestra comprensi\u00f3n limitada de c\u00f3mo generar inmunidad efectiva, particularmente en los ancianos\u00bb.<\/p>\n<p>Los avances en la gen\u00f3mica moderna y la biolog\u00eda molecular nos han permitido crear vacunas m\u00e1s seguras y m\u00e1s espec\u00edficas que las que ten\u00edamos en el pasado, pero tambi\u00e9n han creado un abismo m\u00e1s amplio en la inmunidad lograda por los j\u00f3venes y los viejos. Nuestras primeras vacunas contra la poliomielitis y la tuberculosis se elaboraron con un pat\u00f3geno vivo debilitado. Un pat\u00f3geno completo posee una gran cantidad de objetivos, o ant\u00edgenos, para el sistema inmune, por lo que genera la respuesta m\u00e1s fuerte y duradera.<\/p>\n<p>Las vacunas modernas ya no dependen de virus vivo atenuado. Los investigadores ahora pueden identificar una o m\u00e1s piezas de prote\u00edna viral que creen que ser\u00e1n un buen objetivo para el sistema inmune y luego entregarlas al cuerpo utilizando una variedad de m\u00e9todos inteligentes. La t\u00e9cnica que Moderna y Pfizer y otras compa\u00f1\u00edas est\u00e1n utilizando consiste en inyectar solo el ARN mensajero que codifica la prote\u00edna espiga (spike) espec\u00edfica del coronavirus. No se va a generar el virus ni tampoco se va a insertar en nuestro c\u00f3digo gen\u00e9tico.<\/p>\n<p>Una posible desventaja de los m\u00e9todos m\u00e1s avanzados es que no ofrecen una variedad tan amplia de ant\u00edgenos para activar nuestra respuesta inmune, lo que se convierte en un problema para las personas cuyos sistemas inmunitarios son menos vigorosos. Las eficacia de las nuevas vacunas, nunca ha sido aprobado en humanos, y mucho menos en adultos mayores.<\/p>\n<p>Adaptar una vacuna a los mayores de 65 a\u00f1os depende de averiguar por qu\u00e9 son tan susceptibles a la enfermedad, que, en Espa\u00f1a, ha causado la muerte de m\u00e1s de 20.000 personas de edad avanzada. Justo cuando la piel comienza a arrugarse y ceder con la edad, el cuerpo tambi\u00e9n comienza a perder su capacidad para eliminar las part\u00edculas extra\u00f1as de los pulmones y las v\u00edas respiratorias. Esto supone una carga mayor para el sistema inmunitario, especialmente su capacidad para producir anticuerpos que se adhieren a los virus y los neutralizan antes de que penetren en las c\u00e9lulas y las conviertan en f\u00e1bricas de virus. Los <a href=\"https:\/\/investors.modernatx.com\/news-releases\/news-release-details\/moderna-announces-positive-interim-phase-1-data-its-mrna-vaccine\" target=\"_blank\">resultados parciales que Moderna<\/a> public\u00f3 recientemente resaltaron el hecho de que ocho de los 45 sujetos, todos menores de 55 a\u00f1os, produc\u00edan <a href=\"https:\/\/onezero.medium.com\/the-race-is-on-to-find-the-holy-grail-of-covid-19-antibodies-db8f8961ac20\" target=\"_blank\">anticuerpos neutralizantes<\/a> contra el coronavirus. Sin embargo, las personas mayores generalmente no producen tantos anticuerpos neutralizantes en respuesta a la vacunaci\u00f3n. Una estrategia para compensar esto es proporcionarles m\u00e1s ant\u00edgeno. Una vacuna <a href=\"https:\/\/www.cdc.gov\/flu\/prevent\/qa_fluzone.htm\" target=\"_blank\">para mayores contra la gripe<\/a> para mayores, por ejemplo, contiene cuatro veces la dosis de una vacuna t\u00edpica.<\/p>\n<p>Hay un segundo obst\u00e1culo que una vacuna para los mayores de 65 a\u00f1os tendr\u00e1 que superar. Aunque la capacidad de inducir anticuerpos neutralizantes es una de las principales medidas a tener en cuenta, no hay que\u00a0 olvidar que para eliminar una infecci\u00f3n de los pulmones es necesario activar una segunda rama del sistema inmune que involucre a las c\u00e9lulas T, un tipo especial de gl\u00f3bulos blancos que pueden destruir las c\u00e9lulas infectadas y detener la replicaci\u00f3n del virus.<\/p>\n<p>Los aditivos para vacunas conocidos como adyuvantes pueden ser cruciales. La vacuna Shingrix contra el herpes z\u00f3ster, aprobada en 2017, fue una rara victoria que demostr\u00f3 ser casi 90% efectiva entre las personas de 70 a\u00f1os o m\u00e1s, gracias a un <a href=\"https:\/\/www.medpagetoday.com\/meetingcoverage\/oar\/74765\" target=\"_blank\">nuevo adyuvante aislado del<\/a> \u00e1rbol de corteza de jab\u00f3n de Chile que <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5946839\/\" target=\"_blank\">incrementa la respuesta de las c\u00e9lulas T<\/a>.<\/p>\n<p>Los adyuvantes son la magia negra del desarrollo de vacunas. Sus efectos inmunoestimulantes ayudan a que una vacuna funcione, pero tambi\u00e9n pueden, en casos raros, <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC4615573\/\" target=\"_blank\">causar reacciones peligrosas<\/a>, raz\u00f3n por la cual los fabricantes tienden a ser conservadores con ellos. Seg\u00fan el <a href=\"https:\/\/milkeninstitute.org\/covid-19-tracker\" target=\"_blank\">Instituto Milken<\/a>, se est\u00e1n desarrollando m\u00e1s de 140 posibles vacunas para el coronavirus en todo el mundo, y muchas probablemente recurrir\u00e1n a adyuvantes a <a href=\"https:\/\/www.sciencedirect.com\/topics\/medicine-and-dentistry\/alum\" target=\"_blank\">base de aluminio<\/a>, viejos recursos que han existido desde la d\u00e9cada de 1920. Estos adyuvantes aumentan la cantidad de tiempo que un ant\u00edgeno est\u00e1 presente en el cuerpo, comprando m\u00e1s tiempo para producir una respuesta inmune.<\/p>\n<p>Este grupo est\u00e1 trabajando en asociaci\u00f3n con varias compa\u00f1\u00edas de biotecnolog\u00eda, incluidas Exicure en Skokie, Illinois y Avidea Technologies en Baltimore, para ayudar a desarrollar formulaciones de vacunas que sean seguras y efectivas en todas las categor\u00edas de edad. Tambi\u00e9n est\u00e1 en conversaciones con Moderna, que abandon\u00f3 la dosis m\u00e1s alta que prob\u00f3 en las personas despu\u00e9s de que se produjeran reacciones inmunes sist\u00e9micas, como fiebre. Es posible que la compa\u00f1\u00eda necesite explorar estrategias con \u00a0adyuvantes para producir la respuesta m\u00e1s eficaz en adultos mayores con dosis m\u00e1s bajas. Moderna <a href=\"https:\/\/clinicaltrials.gov\/ct2\/show\/NCT04283461?term=vaccine&amp;cond=Sars-CoV2&amp;cntry=US&amp;draw=2&amp;rank=1\" target=\"_blank\">tiene planes de probar<\/a> su vacuna en personas de hasta 70 a\u00f1os. El director m\u00e9dico de Moderna descart\u00f3 que ser\u00e1 menos eficaz para las personas mayores de 65 a\u00f1os aunque los resultados m\u00e1s recientes <a href=\"https:\/\/www.scientificamerican.com\/article\/coronavirus-vaccines-may-not-work-for-the-elderly-and-this-lab-aims-to-change-that\/\" target=\"_blank\">cuestionan esa c<\/a>erteza.<\/p>\n<p>La rapidez con la que se est\u00e1n desarrollando las vacunas, significa que habr\u00e1 informaci\u00f3n limitada sobre la duraci\u00f3n de la inmunidad de una vacuna y si es segura para las personas mayores a largo plazo. Vacunar a miles millones de habitantes tendr\u00e1 un coste inmenso.<\/p>\n<p>Los primeros resultados de los ensayos en curso muestran que las vacunas desatan respuesta frente al coronavirus en personas mayores de 60 a\u00f1os. La eficacia de la vacuna variar\u00e1 con las diferentes preparaciones de vacuna, y debemos elegir cuidadosamente qu\u00e9 formulaciones funcionar\u00e1n mejor en personas mayores, qu\u00e9 dosis son m\u00e1s eficaz y cu\u00e1ndo administrar las vacunas de refuerzo para lograr los mejores resultados.<\/p>\n<p>El <a href=\"https:\/\/www.bmj.com\/content\/371\/bmj.m4471\" target=\"_blank\">Instituto Nacional de Salud de EE. UU., llev\u00f3 a cabo el an\u00e1lisis de la eficacia de la vacuna de Moderna<\/a> en base a 95 casos de covid-19, de los cuales 90 se observaron en el grupo de placebo y cinco en el grupo de vacuna. El ensayo reclut\u00f3 a m\u00e1s de 30.000 participantes estadounidenses, incluidos 7000 mayores de 65 a\u00f1os y 5000 menores de 65 a\u00f1os con enfermedades cr\u00f3nicas de alto riesgo. M\u00e1s de un tercio (37%) de los participantes del ensayo no son blancos, con 6000 participantes identificados como hispanos y m\u00e1s de 3000 identificados como afroamericanos.<\/p>\n<p>De los 95 casos, 15 correspondieron a adultos mayores de 65 a\u00f1os y 20 se identificaron como pertenecientes a comunidades diversas (12 hispanos, cuatro afroamericanos, tres asi\u00e1ticoamericanos y uno multirracial).<\/p>\n<p>En ausencia de una vacuna altamente eficaz, la calidad de vida de los adultos mayores depender\u00e1 en gran medida del desarrollo con \u00e9xito de medicamentos Covid-19 que atacan directamente al virus. A principios de este mes, la FDA emiti\u00f3 una autorizaci\u00f3n de emergencia para el Remdesivir , que ha demostrado un efecto relativo a la hora de acelerar la recuperaci\u00f3n de los pacientes hospitalizados.<\/p>\n<p>Pero los cient\u00edficos tambi\u00e9n est\u00e1n probando una amplia gama de medicamentos preexistentes y nuevos compuestos. Una segunda l\u00ednea de defensa podr\u00eda provenir de los <a href=\"https:\/\/www.sciencemag.org\/news\/2020\/05\/race-antibodies-stop-new-coronavirus\" target=\"_blank\">anticuerpos monoclonales<\/a> comerciales, aunque es probable que cuesten cientos de d\u00f3lares por dosis y tendr\u00edan que suministrase cada dos meses.<\/p>\n<p>Una defensa similar a una vacuna en el horizonte consiste en eludir el sistema inmune fr\u00e1gil de los adultos mayores al inyectar las instrucciones gen\u00e9ticas para producir anticuerpos directamente en sus m\u00fasculos y estimularlos para que produzcan los anticuerpos. La t\u00e9cnica <a href=\"https:\/\/www.cell.com\/molecular-therapy-family\/molecular-therapy\/fulltext\/S1525-0016(19)30091-7\" target=\"_blank\">se prob\u00f3 con \u00e9xito en s<\/a>imios contra el virus del Zika, y dos compa\u00f1\u00edas con sede en Massachusetts, Generation Bio y SmartPharm Therapeutics, esperan implementarla para el nuevo coronavirus.<\/p>\n<p>Los cient\u00edficos tambi\u00e9n est\u00e1n explorando la posibilidad de que algunas personas puedan beneficiarse <a href=\"https:\/\/www.nature.com\/articles\/s41577-020-0337-y\" target=\"_blank\">de las vacunas vivas<\/a> que todav\u00eda se usan para ciertas enfermedades en otros pa\u00edses, y de la exposici\u00f3n a <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/32316118\/\" target=\"_blank\">enfermedades infecciosas como la malaria<\/a><\/p>\n<p>Si bien las primeras vacunas aprobadas contra el coronavirus pueden no ser totalmente eficaces para los mayores, algunos cient\u00edficos afirman que podr\u00edan ser beneficiosas. A medida que las personas m\u00e1s j\u00f3venes reciben las vacunas, la inmunidad del reba\u00f1o finalmente se afianzar\u00e1, protegiendo a los mayores de 65 a\u00f1os mejor que las vacunas.<\/p>\n<p>Vamos por el buen camino pero queda algo por\u00a0 recorrer.<\/p>\n<p><a href=\"https:\/\/theconversation.com\/coronavirus-vaccine-results-are-pouring-in-and-its-good-news-for-older-people-150424\" target=\"_blank\">Coronavirus vaccine results are pouring in, and it\u2019s good news for older people.<\/a> The Conversation<\/p>\n<p><a href=\"https:\/\/www.nature.com\/articles\/d41586-020-02856-7\" target=\"_blank\">How anti-ageing drugs could boost COVID vaccines in older people.<\/a> Nature.<\/p>\n<p><a href=\"https:\/\/www.bbc.com\/news\/health-54993652\" target=\"_blank\">Covid: Oxford vaccine shows &#8216;encouraging&#8217; immune response in older adults.<\/a> BBC.<\/p>\n<p><a href=\"https:\/\/jamanetwork.com\/journals\/jamainternalmedicine\/fullarticle\/2771091\" target=\"_blank\">The Exclusion of Older Persons From Vaccine and Treatment Trials for Coronavirus Disease 2019\u2014Missing the Target<\/a><\/p>\n<p><a href=\"https:\/\/www.bmj.com\/content\/371\/bmj.m4471\" target=\"_blank\">Covid-19: Moderna vaccine is nearly 95% effective, trial involving high risk and elderly people shows<\/a>\u00a0BMJ<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/file-20201112-19-14zre5e.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137099\" title=\"file-20201112-19-14zre5e\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/file-20201112-19-14zre5e.jpg\" alt=\"\" width=\"670\" height=\"447\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/file-20201112-19-14zre5e.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/file-20201112-19-14zre5e-300x200.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No pensemos que una vacuna contra el virus causante de la Covid-19 erradicar\u00e1 el coronavirus de nuestras vidas a corto plazo o que nuestra inmunidad colectiva detendr\u00e1 la propagaci\u00f3n. Por ahora, hay que centrar esos esfuerzos en mantener el distanciamiento f\u00edsico y el uso de medidas de protecci\u00f3n individual, como las mascarillas o la higiene de manos, hasta que la ciencia sugiera lo contrario. A\u00fan se desconoce cu\u00e1nta inmunidad generar\u00e1n las vacunas en la poblaci\u00f3n y cu\u00e1nto tiempo durar\u00e1. Despu\u00e9s de d\u00e9cadas de esfuerzo, todav\u00eda no existe una vacuna contra el VIH. Y aunque se han desarrollado vacunas para muchos\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"No pensemos que una vacuna contra el virus causante de la Covid-19 erradicar\u00e1 el coronavirus de nuestras vidas a corto plazo o que nuestra inmunidad colectiva detendr\u00e1 la propagaci\u00f3n. Por ahora, hay que centrar esos esfuerzos en mantener el distanciamiento f\u00edsico y el uso de medidas de protecci\u00f3n individual, como las mascarillas o la higiene\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"No pensemos que una vacuna contra el virus causante de la Covid-19 erradicar\u00e1 el coronavirus de nuestras vidas a corto plazo o que nuestra inmunidad colectiva detendr\u00e1 la propagaci\u00f3n. Por ahora, hay que centrar esos esfuerzos en mantener el distanciamiento f\u00edsico y el uso de medidas de protecci\u00f3n individual, como las mascarillas o la higiene\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-12-02T16:41:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-12-02T16:41:48+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"No pensemos que una vacuna contra el virus causante de la Covid-19 erradicar\u00e1 el coronavirus de nuestras vidas a corto plazo o que nuestra inmunidad colectiva detendr\u00e1 la propagaci\u00f3n. Por ahora, hay que centrar esos esfuerzos en mantener el distanciamiento f\u00edsico y el uso de medidas de protecci\u00f3n individual, como las mascarillas o la higiene\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/02\\\/137088#blogposting\",\"name\":\"\\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad? - Ciencia Marina y otros asuntos\",\"headline\":\"\\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/12\\\/Ancianos.EFEEPAWILL-OLIVERArchivo.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/02\\\/137088\\\/#articleImage\",\"width\":670,\"height\":447},\"datePublished\":\"2020-12-02T17:41:48+01:00\",\"dateModified\":\"2020-12-02T17:41:48+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/02\\\/137088#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/02\\\/137088#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/02\\\/137088#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/02\\\/137088#listItem\",\"name\":\"\\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/02\\\/137088#listItem\",\"position\":3,\"name\":\"\\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/02\\\/137088#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/02\\\/137088\",\"name\":\"\\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad? - Ciencia Marina y otros asuntos\",\"description\":\"No pensemos que una vacuna contra el virus causante de la Covid-19 erradicar\\u00e1 el coronavirus de nuestras vidas a corto plazo o que nuestra inmunidad colectiva detendr\\u00e1 la propagaci\\u00f3n. Por ahora, hay que centrar esos esfuerzos en mantener el distanciamiento f\\u00edsico y el uso de medidas de protecci\\u00f3n individual, como las mascarillas o la higiene\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/02\\\/137088#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-12-02T17:41:48+01:00\",\"dateModified\":\"2020-12-02T17:41:48+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad? - Ciencia Marina y otros asuntos","description":"No pensemos que una vacuna contra el virus causante de la Covid-19 erradicar\u00e1 el coronavirus de nuestras vidas a corto plazo o que nuestra inmunidad colectiva detendr\u00e1 la propagaci\u00f3n. Por ahora, hay que centrar esos esfuerzos en mantener el distanciamiento f\u00edsico y el uso de medidas de protecci\u00f3n individual, como las mascarillas o la higiene","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088#blogposting","name":"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad? - Ciencia Marina y otros asuntos","headline":"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/Ancianos.EFEEPAWILL-OLIVERArchivo.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088\/#articleImage","width":670,"height":447},"datePublished":"2020-12-02T17:41:48+01:00","dateModified":"2020-12-02T17:41:48+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088#listItem","name":"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088#listItem","position":3,"name":"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088","name":"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad? - Ciencia Marina y otros asuntos","description":"No pensemos que una vacuna contra el virus causante de la Covid-19 erradicar\u00e1 el coronavirus de nuestras vidas a corto plazo o que nuestra inmunidad colectiva detendr\u00e1 la propagaci\u00f3n. Por ahora, hay que centrar esos esfuerzos en mantener el distanciamiento f\u00edsico y el uso de medidas de protecci\u00f3n individual, como las mascarillas o la higiene","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-12-02T17:41:48+01:00","dateModified":"2020-12-02T17:41:48+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad? - Ciencia Marina y otros asuntos","og:description":"No pensemos que una vacuna contra el virus causante de la Covid-19 erradicar\u00e1 el coronavirus de nuestras vidas a corto plazo o que nuestra inmunidad colectiva detendr\u00e1 la propagaci\u00f3n. Por ahora, hay que centrar esos esfuerzos en mantener el distanciamiento f\u00edsico y el uso de medidas de protecci\u00f3n individual, como las mascarillas o la higiene","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-12-02T16:41:48+00:00","article:modified_time":"2020-12-02T16:41:48+00:00","twitter:card":"summary","twitter:title":"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad? - Ciencia Marina y otros asuntos","twitter:description":"No pensemos que una vacuna contra el virus causante de la Covid-19 erradicar\u00e1 el coronavirus de nuestras vidas a corto plazo o que nuestra inmunidad colectiva detendr\u00e1 la propagaci\u00f3n. Por ahora, hay que centrar esos esfuerzos en mantener el distanciamiento f\u00edsico y el uso de medidas de protecci\u00f3n individual, como las mascarillas o la higiene","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"137088","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-04 13:53:39","updated":"2026-05-26 19:36:53","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"\u00bfSon las vacunas frente al coronavirus eficaces en los mayores de edad?","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/02\/137088"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137088"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=137088"}],"version-history":[{"count":11,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137088\/revisions"}],"predecessor-version":[{"id":137102,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137088\/revisions\/137102"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=137088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=137088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=137088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}