{"id":137122,"date":"2020-12-09T16:31:23","date_gmt":"2020-12-09T15:31:23","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=137122"},"modified":"2020-12-09T16:31:23","modified_gmt":"2020-12-09T15:31:23","slug":"efectos-adversos-de-las-nuevas-vacunas-de-arn-mensajero-frente-a-sars-cov-2-en-reino-unido-covid-19-coronavirus","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122","title":{"rendered":"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus"},"content":{"rendered":"<p>Varios <a href=\"https:\/\/www.phgfoundation.org\/briefing\/rna-vaccines\" target=\"_blank\">expertos<\/a> hab\u00edan avisado sobre las posibles reacciones inmunes adversas que, en una fracci\u00f3n limitada de la poblaci\u00f3n, podr\u00edan provocar las nuevas vacunas basadas en ARN mensajero. <a href=\"https:\/\/www.theguardian.com\/world\/2020\/dec\/09\/pfizer-covid-vaccine-nhs-extreme-allergy-sufferers-regulators-reaction\" target=\"_blank\">Este mi\u00e9rcoles (hoy), la Agencia Reguladora de Medicamentos del Reino Unido, despu\u00e9s de que dos trabajadores del Sistema nacional de Salud (NHS) experimentaron s\u00edntomas de reacci\u00f3n al\u00e9rgica severa<\/a>, asegura que: \u201cLas personas con antecedentes de reacciones al\u00e9rgicas serias no deben recibir la vacuna Covid de Pfizer (y tal vez la de Moderna).<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/kiwi-kC0-620x349@abc.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137137\" title=\"kiwi-kC0--620x349@abc\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/kiwi-kC0-620x349@abc.jpg\" alt=\"\" width=\"500\" height=\"282\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/kiwi-kC0-620x349@abc.jpg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/kiwi-kC0-620x349@abc-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><!--more-->Ambos miembros del personal del NHS llevan autoinyectores de adrenalina, lo que sugiere que han sufrido reacciones en el pasado. Este tipo de dispositivos, cuya marca m\u00e1s conocida es EpiPen, administran un r\u00e1pido impulso de adrenalina para contrarrestar las reacciones al\u00e9rgicas que ocurren cuando algunas personas tienen reacciones al\u00e9rgicas al ingerir comida como el kiwi, algunos frutos secos como los cacahuetes o las nueces, las fresas etc. En <a href=\"https:\/\/www.aepnaa.org\/\" target=\"_blank\">Espa\u00f1a<\/a>,\u00a0<a href=\"https:\/\/www.alimente.elconfidencial.com\/bienestar\/2018-07-23\/alergia-a-alimentos-el-riesgo-aumenta-en-verano_1586738\/\" target=\"_blank\">el 8% de los menores de 14 a\u00f1os y entre el 2 y el 3% de los adultos<\/a> tienen al menos una alergia alimentaria\u00a0<a href=\"https:\/\/www.seaic.org\/pacientes\" target=\"_blank\">presentan alergias alimentarias<\/a>. Habr\u00e1 que esperar para saber que reacciones al\u00e9rgicas aconsejan evitar esta vacuna.<\/p>\n<p>El folleto de informaci\u00f3n para el paciente de la vacuna Pfizer \/ BioNTech dice que no debe administrarse a personas al\u00e9rgicas a ninguna sustancia de la vacuna, lo que plantea dudas sobre la actitud confiada del NHS al seleccionar a los miembros del personal que se vacunar\u00e1n.<\/p>\n<p>Seg\u00fan el folleto: \u00abLos signos de una reacci\u00f3n al\u00e9rgica pueden incluir erupci\u00f3n cut\u00e1nea con picor, dificultad para respirar e hinchaz\u00f3n de la cara o la lengua\u00bb.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/Captura-de-pantalla-2020-12-09-a-las-16.10.03.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137131\" title=\"Captura de pantalla 2020-12-09 a las 16.10.03\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/Captura-de-pantalla-2020-12-09-a-las-16.10.03.png\" alt=\"\" width=\"670\" height=\"1031\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/Captura-de-pantalla-2020-12-09-a-las-16.10.03.png 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/Captura-de-pantalla-2020-12-09-a-las-16.10.03-194x300.png 194w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/Captura-de-pantalla-2020-12-09-a-las-16.10.03-665x1024.png 665w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>Fuente: <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5906799\/\" target=\"_blank\">mRNA vaccines \u2014 a new era in vaccinology<\/a><\/p>\n<p>Las ventajas de las vacunas de ARN sobre las vacunas tradicionales son el <a href=\"https:\/\/www.phgfoundation.org\/briefing\/rna-vaccines\" target=\"_blank\">dise\u00f1o<\/a> y la<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5906799\/\" target=\"_blank\"> velocidad de producci\u00f3n<\/a>, el bajo coste de producci\u00f3n, y la <a href=\"https:\/\/link.springer.com\/protocol\/10.1007%2F978-1-4939-6481-9_1\" target=\"_blank\">inducci\u00f3n de inmunidad celular, as\u00ed como inmunidad humoral<\/a>.\u00a0 La autoinmunidad y la reacci\u00f3n inmune elevada (principalmente inducida por las nanopart\u00edculas lip\u00eddicas tratadas con <a href=\"https:\/\/es.wikipedia.org\/wiki\/Polietilenglicol#:~:text=Poli(oxi%2D1%2C2,%2C%20%C3%B3xido%20de%20polietileno%2C%20Macrogol.&amp;text=Diarrea.,N%C3%A1useas.\" target=\"_blank\">polietilenglicol<\/a>) se han destacado como posibles efectos secundarios.<\/p>\n<p>Las cadenas de ARNm de la vacuna pueden provocar una reacci\u00f3n inmune no deseada; para minimizar esto, las secuencias de la vacuna de ARNm est\u00e1n dise\u00f1adas para imitar las producidas por c\u00e9lulas de mam\u00edferos (es decir, c\u00e9lulas humanas).<\/p>\n<p>El sistema de administraci\u00f3n de f\u00e1rmacos que contiene la mol\u00e9cula de ARNm (que protege las fr\u00e1giles hebras de ARNm para que no se descompongan antes de que entren en la c\u00e9lula humana son <a href=\"https:\/\/en.wikipedia.org\/wiki\/Solid_lipid_nanoparticles\" target=\"_blank\">nanopart\u00edculas lip\u00eddicas<\/a> <a href=\"https:\/\/en.wikipedia.org\/wiki\/PEGylation\" target=\"_blank\">PEGiladas<\/a>\u00a0 (La PEGilaci\u00f3n es el proceso de uni\u00f3n o fusi\u00f3n covalente y no covalente de cadenas de pol\u00edmero de polietilenglicol a mol\u00e9culas y macroestructuras, como un f\u00e1rmaco, una prote\u00edna terap\u00e9utica o una ves\u00edcula, que luego se describe como PEGilada) que pueden ser <a href=\"https:\/\/en.wikipedia.org\/wiki\/Reactogenicity\" target=\"_blank\">reactog\u00e9nicas<\/a> (elevada respuesta inmune), desencadenar sus propias reacciones inmunitarias y <a href=\"https:\/\/www.sciencemag.org\/news\/2017\/12\/can-multibillion-dollar-biotech-prove-its-rna-drugs-are-safe-rare-disease\" target=\"_blank\">causar da\u00f1o al h\u00edgado en dosis m\u00e1s altas<\/a>. De hecho en los ensayos de nuevas vacunas de ARN COVID-19 se notificaron <a href=\"https:\/\/science.sciencemag.org\/content\/370\/6520\/1022\" target=\"_blank\">fuertes efectos reactog\u00e9nicos<\/a>.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/F1.large_.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137127\" title=\"F1.large\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/F1.large_.jpg\" alt=\"\" width=\"670\" height=\"386\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/F1.large_.jpg 670w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/F1.large_-300x172.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a><\/p>\n<p>GRAPHIC: V. ALTOUNIAN\/<a href=\"https:\/\/science.sciencemag.org\/content\/370\/6520\/1022\" target=\"_blank\">SCIENCE<\/a><\/p>\n<p>Las identidades de los trabajadores del NHS y los hospitales donde fueron vacunados no se han revelado. El NHS de Inglaterra, confirm\u00f3 los dos incidentes y dijo que ahora se hab\u00eda aconsejado a todos los centros de vacunaci\u00f3n que no vacunasen a las personas con antecedentes de reacciones al\u00e9rgicas.<\/p>\n<p>El profesor Stephen Powis, director m\u00e9dico nacional del NHS en Inglaterra declar\u00f3 que \u201cComo es com\u00fan con las nuevas vacunas, la MHRA [Agencia Reguladora de Medicamentos y Productos Sanitarios] ha advertido como precauci\u00f3n que las personas con un historial significativo de reacciones al\u00e9rgicas no suministrar esta vacuna, despu\u00e9s de que dos personas con antecedentes de reacciones al\u00e9rgicas importantes respondieran ayer de manera adversa. Ambos se est\u00e1n recuperando bien \u00ab.<\/p>\n<p>A partir de hoy,\u00a0 la MHRA establece que: \u201cCualquier persona con un historial de una reacci\u00f3n al\u00e9rgica significativa a una vacuna, medicamento o alimento (como un historial previo de reacci\u00f3n anafil\u00e1ctica o aquellos a quienes se les haya recomendado que lleven un autoinyector de adrenalina) no deben recibir la vacuna de Pfizer \/ BioNtech. Las instalaciones de reanimaci\u00f3n deben estar disponibles en todo momento para todas las vacunas. La vacunaci\u00f3n solo debe realizarse en instalaciones donde se disponga de medidas de reanimaci\u00f3n \u00ab.<\/p>\n<p>Los trabajadores del NHS desarrollaron s\u00edntomas de \u00abreacci\u00f3n anafil\u00e1ctica\u00bb poco despu\u00e9s de recibir la vacuna, y ambos se recuperaron despu\u00e9s del tratamiento.<\/p>\n<p>Peter Openshaw, profesor de medicina experimental en el Imperial College de Londres, declar\u00f3: \u201cAl igual que con todos los alimentos y medicamentos, existe una posibilidad muy peque\u00f1a de una reacci\u00f3n al\u00e9rgica a cualquier vacuna. Sin embargo, es importante que pongamos este riesgo en perspectiva. La aparici\u00f3n de cualquier reacci\u00f3n al\u00e9rgica fue uno de los factores controlados en el ensayo cl\u00ednico de fase 3 de esta vacuna Pfizer \/ BioNTech Covid-19, cuyos datos detallados se publicaron ayer. Seg\u00fan esos datos un n\u00famero muy peque\u00f1o de reacciones al\u00e9rgicas tanto en los grupos de vacuna como de placebo (0,63% y 0,51%). Ya es casualidad que reci\u00e9n comenzadas las vacunaciones en el Reino Unido se hayan dado dos casos.<\/p>\n<p>Los datos de Pfizer mostraron que alrededor del 0,6% de las personas tuvieron alg\u00fan tipo de reacci\u00f3n al\u00e9rgica en el ensayo con la vacuna, y alrededor del 0,5% con el placebo. Hay bastante incertidumbre en torno a esa estimaci\u00f3n.<\/p>\n<p>\u201cLo \u00fanico que est\u00e1 contraindicado con esta vacuna (lo que significa que no se debe recibirla) es la hipersensibilidad a la vacuna o cualquiera de los excipientes (otras componentes de la vacuna), pero algunas personas no sabr\u00e1n si tienen hipersensibilidad a algunos constituyentes de la vacuna hasta despu\u00e9s de recibirla.<\/p>\n<p>\u00abLo prudente, como ya ha aconsejado la MHRA, ser\u00eda que cualquier persona que haya conocido una reacci\u00f3n al\u00e9rgica grave que necesite llevar un EpiPen, posponga la vacunaci\u00f3n hasta que se aclare el motivo de la reacci\u00f3n al\u00e9rgica\u00bb.<\/p>\n<p>Seg\u00fan Pfizer UK \u201cEn el ensayo cl\u00ednico de fase 3, esta vacuna fue generalmente bien tolerada y el comit\u00e9 independiente de seguimiento de datos no inform\u00f3 de problemas graves de seguridad. El ensayo ha inscrito a m\u00e1s de 44.000 participantes hasta la fecha, m\u00e1s de 42.000 de los cuales han recibido una segunda vacuna.<\/p>\n<p>Para saber m\u00e1s:<\/p>\n<p><a href=\"https:\/\/www.phgfoundation.org\/briefing\/rna-vaccines\" target=\"_blank\">RNA vaccines: an introduction<\/a>\u00a0Cambridge University<\/p>\n<p><a href=\"https:\/\/science.sciencemag.org\/content\/370\/6520\/1022\" target=\"_blank\">Public needs to prep for vaccine side effects<\/a>\u00a0Science.<\/p>\n<p><a href=\"https:\/\/www.sciencemag.org\/news\/2017\/12\/can-multibillion-dollar-biotech-prove-its-rna-drugs-are-safe-rare-disease\" target=\"_blank\">Can a multibillion-dollar biotech prove its RNA drugs are safe for a rare disease?<\/a> Science<\/p>\n<p><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5906799\/\" target=\"_blank\">mRNA vaccines \u2014 a new era in vaccinology<\/a>. Nat Rev Drug Discov. 2018 Apr; 17(4): 261\u2013279.<\/p>\n<p><a href=\"https:\/\/link.springer.com\/protocol\/10.1007%2F978-1-4939-6481-9_1\" target=\"_blank\">Introduction to RNA Vaccines.<\/a> RNA Vaccines.<\/p>\n<p><a href=\"https:\/\/www.theguardian.com\/world\/2020\/dec\/09\/pfizer-covid-vaccine-nhs-extreme-allergy-sufferers-regulators-reaction\" target=\"_blank\">NHS told not to give Covid vaccine to those with history of allergic reactions.<\/a> The Guardian<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Varios expertos hab\u00edan avisado sobre las posibles reacciones inmunes adversas que, en una fracci\u00f3n limitada de la poblaci\u00f3n, podr\u00edan provocar las nuevas vacunas basadas en ARN mensajero. Este mi\u00e9rcoles (hoy), la Agencia Reguladora de Medicamentos del Reino Unido, despu\u00e9s de que dos trabajadores del Sistema nacional de Salud (NHS) experimentaron s\u00edntomas de reacci\u00f3n al\u00e9rgica severa, asegura que: \u201cLas personas con antecedentes de reacciones al\u00e9rgicas serias no deben recibir la vacuna Covid de Pfizer (y tal vez la de Moderna).<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Varios expertos hab\u00edan avisado sobre las posibles reacciones inmunes adversas que, en una fracci\u00f3n limitada de la poblaci\u00f3n, podr\u00edan provocar las nuevas vacunas basadas en ARN mensajero. Este mi\u00e9rcoles (hoy), la Agencia Reguladora de Medicamentos del Reino Unido, despu\u00e9s de que dos trabajadores del Sistema nacional de Salud (NHS) experimentaron s\u00edntomas de reacci\u00f3n al\u00e9rgica severa,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Varios expertos hab\u00edan avisado sobre las posibles reacciones inmunes adversas que, en una fracci\u00f3n limitada de la poblaci\u00f3n, podr\u00edan provocar las nuevas vacunas basadas en ARN mensajero. Este mi\u00e9rcoles (hoy), la Agencia Reguladora de Medicamentos del Reino Unido, despu\u00e9s de que dos trabajadores del Sistema nacional de Salud (NHS) experimentaron s\u00edntomas de reacci\u00f3n al\u00e9rgica severa,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-12-09T15:31:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-12-09T15:31:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Varios expertos hab\u00edan avisado sobre las posibles reacciones inmunes adversas que, en una fracci\u00f3n limitada de la poblaci\u00f3n, podr\u00edan provocar las nuevas vacunas basadas en ARN mensajero. Este mi\u00e9rcoles (hoy), la Agencia Reguladora de Medicamentos del Reino Unido, despu\u00e9s de que dos trabajadores del Sistema nacional de Salud (NHS) experimentaron s\u00edntomas de reacci\u00f3n al\u00e9rgica severa,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/09\\\/137122#blogposting\",\"name\":\"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus - Ciencia Marina y otros asuntos\",\"headline\":\"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2020\\\/12\\\/kiwi-kC0-620x349@abc.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/09\\\/137122\\\/#articleImage\",\"width\":500,\"height\":282},\"datePublished\":\"2020-12-09T16:31:23+01:00\",\"dateModified\":\"2020-12-09T16:31:23+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/09\\\/137122#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/09\\\/137122#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/09\\\/137122#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/09\\\/137122#listItem\",\"name\":\"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/09\\\/137122#listItem\",\"position\":3,\"name\":\"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/09\\\/137122#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/09\\\/137122\",\"name\":\"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus - Ciencia Marina y otros asuntos\",\"description\":\"Varios expertos hab\\u00edan avisado sobre las posibles reacciones inmunes adversas que, en una fracci\\u00f3n limitada de la poblaci\\u00f3n, podr\\u00edan provocar las nuevas vacunas basadas en ARN mensajero. Este mi\\u00e9rcoles (hoy), la Agencia Reguladora de Medicamentos del Reino Unido, despu\\u00e9s de que dos trabajadores del Sistema nacional de Salud (NHS) experimentaron s\\u00edntomas de reacci\\u00f3n al\\u00e9rgica severa,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2020\\\/12\\\/09\\\/137122#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2020-12-09T16:31:23+01:00\",\"dateModified\":\"2020-12-09T16:31:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus - Ciencia Marina y otros asuntos","description":"Varios expertos hab\u00edan avisado sobre las posibles reacciones inmunes adversas que, en una fracci\u00f3n limitada de la poblaci\u00f3n, podr\u00edan provocar las nuevas vacunas basadas en ARN mensajero. Este mi\u00e9rcoles (hoy), la Agencia Reguladora de Medicamentos del Reino Unido, despu\u00e9s de que dos trabajadores del Sistema nacional de Salud (NHS) experimentaron s\u00edntomas de reacci\u00f3n al\u00e9rgica severa,","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122#blogposting","name":"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus - Ciencia Marina y otros asuntos","headline":"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2020\/12\/kiwi-kC0-620x349@abc.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122\/#articleImage","width":500,"height":282},"datePublished":"2020-12-09T16:31:23+01:00","dateModified":"2020-12-09T16:31:23+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122#listItem","name":"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122#listItem","position":3,"name":"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122","name":"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus - Ciencia Marina y otros asuntos","description":"Varios expertos hab\u00edan avisado sobre las posibles reacciones inmunes adversas que, en una fracci\u00f3n limitada de la poblaci\u00f3n, podr\u00edan provocar las nuevas vacunas basadas en ARN mensajero. Este mi\u00e9rcoles (hoy), la Agencia Reguladora de Medicamentos del Reino Unido, despu\u00e9s de que dos trabajadores del Sistema nacional de Salud (NHS) experimentaron s\u00edntomas de reacci\u00f3n al\u00e9rgica severa,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2020-12-09T16:31:23+01:00","dateModified":"2020-12-09T16:31:23+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus - Ciencia Marina y otros asuntos","og:description":"Varios expertos hab\u00edan avisado sobre las posibles reacciones inmunes adversas que, en una fracci\u00f3n limitada de la poblaci\u00f3n, podr\u00edan provocar las nuevas vacunas basadas en ARN mensajero. Este mi\u00e9rcoles (hoy), la Agencia Reguladora de Medicamentos del Reino Unido, despu\u00e9s de que dos trabajadores del Sistema nacional de Salud (NHS) experimentaron s\u00edntomas de reacci\u00f3n al\u00e9rgica severa,","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2020-12-09T15:31:23+00:00","article:modified_time":"2020-12-09T15:31:23+00:00","twitter:card":"summary","twitter:title":"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus - Ciencia Marina y otros asuntos","twitter:description":"Varios expertos hab\u00edan avisado sobre las posibles reacciones inmunes adversas que, en una fracci\u00f3n limitada de la poblaci\u00f3n, podr\u00edan provocar las nuevas vacunas basadas en ARN mensajero. Este mi\u00e9rcoles (hoy), la Agencia Reguladora de Medicamentos del Reino Unido, despu\u00e9s de que dos trabajadores del Sistema nacional de Salud (NHS) experimentaron s\u00edntomas de reacci\u00f3n al\u00e9rgica severa,","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"137122","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 15:14:03","updated":"2026-05-26 19:38:55","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEfectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Efectos adversos de las nuevas vacunas de ARN mensajero frente a SARS Cov 2 en Reino Unido. Covid 19. Coronavirus","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2020\/12\/09\/137122"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137122"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=137122"}],"version-history":[{"count":16,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137122\/revisions"}],"predecessor-version":[{"id":137141,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137122\/revisions\/137141"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=137122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=137122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=137122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}