{"id":137373,"date":"2021-07-21T17:07:04","date_gmt":"2021-07-21T16:07:04","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=137373"},"modified":"2021-07-21T17:07:04","modified_gmt":"2021-07-21T16:07:04","slug":"si-el-sars-cov2-causante-de-covid-19-es-estacional-por-que-se-esta-transmitiendo-tan-eficazmente-en-verano","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373","title":{"rendered":"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano?"},"content":{"rendered":"<p>Al igual que la mayor\u00eda de los dem\u00e1s virus respiratorios el virus se transmite mejor en invierno. Sin embargo las <a href=\"https:\/\/elpais.com\/sociedad\/2021-07-18\/la-quinta-ola-desbarata-las-previsiones-para-el-segundo-verano-de-la-pandemia.html\" target=\"_blank\">tasas de infecci\u00f3n est\u00e1n experimentando un aumento repentino en el verano<\/a>. Tambi\u00e9n ha habido grandes olas epid\u00e9micas de Covid-19 en regiones como Am\u00e9rica del Sur e India fuera del invierno. \u00bfA qu\u00e9 se debe?<\/p>\n<p>Desde el comienzo de la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Pandemia\" target=\"_blank\">pandemia<\/a>, muchos se preguntaron hasta qu\u00e9 punto Covid mostrar\u00eda un comportamiento estacional con un mayor n\u00famero de casos en invierno. La mayor\u00eda de los virus respiratorios en circulaci\u00f3n, incluida la gripe y los cuatro coronavirus end\u00e9micos que contribuyen a los \u00abresfriados comunes\u00bb, muestran patrones <a href=\"https:\/\/espanol.cdc.gov\/flu\/prevent\/index.html\" target=\"_blank\">estacionales<\/a> claros, y la mayor\u00eda de las infecciones ocurren en invierno en ambos hemisferios.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/descarga-41.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137378\" title=\"descarga (4)\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/descarga-41.jpeg\" alt=\"\" width=\"500\" height=\"333\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/descarga-41.jpeg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/descarga-41-300x199.jpeg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><!--more-->Los mecanismos detr\u00e1s de esta <a href=\"Seasonality of Respiratory Viral Infections\" target=\"_blank\">estacionalidad<\/a> son complejos y todav\u00eda no se comprenden completamente. Incluyen el efecto directo de las variables clim\u00e1ticas: los virus de ARN envueltos, como el causante de Covid-19, sobreviven mejor en aire fr\u00edo y seco y con poca exposici\u00f3n a la luz ultravioleta. Tambi\u00e9n influye el comportamiento del hu\u00e9sped, ya que los humanos tienden a pasar m\u00e1s tiempo en contacto cercano en espacios mal ventilados durante el invierno.<\/p>\n<p>Sin embargo, el hecho de que un virus sea estacional no implica que no pueda transmitirse en determinadas \u00e9pocas del a\u00f1o, siempre que las condiciones sean favorables para su propagaci\u00f3n. Para comprender mejor esto, debemos considerar la estacionalidad como solo uno de los cuatro factores principales que impulsan la transmisi\u00f3n. Los otros tres factores son el comportamiento del hospedador, la evoluci\u00f3n viral y las tasas de inmunizaci\u00f3n en la poblaci\u00f3n, proporcionados por la exposici\u00f3n previa al pat\u00f3geno y \/ o la vacunaci\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/Estacionalidad-virus.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137379\" title=\"Estacionalidad virus\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/Estacionalidad-virus.jpg\" alt=\"\" width=\"500\" height=\"433\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/Estacionalidad-virus.jpg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/Estacionalidad-virus-300x259.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.annualreviews.org\/doi\/10.1146\/annurev-virology-012420-022445\" target=\"_blank\">Fuente: Moriyama et al. 2020<\/a><\/p>\n<p>Estos cuatro factores influir\u00e1n en la din\u00e1mica de la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Pandemia\" target=\"_blank\">pandemia<\/a>. Los epidemi\u00f3logos de enfermedades infecciosas utilizan un concepto matem\u00e1tico llamado n\u00famero \u00abR\u00bb para describir el comportamiento de las epidemias. Representa el n\u00famero medio de nuevas infecciones causadas por personas infectadas a lo largo del tiempo. Cuando R es mayor que 1, cada individuo infecta a m\u00e1s de un nuevo hu\u00e9sped en promedio y el n\u00famero de casos aumenta con el tiempo. Cuando R es menor que 1, los n\u00fameros de casos disminuyen.<\/p>\n<p>El distanciamiento social a trav\u00e9s de cambios de comportamiento, ya sean voluntarios o impuestos por las autoridades, disminuir\u00e1 la transmisi\u00f3n viral. Dado que las intervenciones de distanciamiento social m\u00faltiples generalmente se implementan juntas, y junto con otros factores, puede ser dif\u00edcil estimar la efectividad de cada intervenci\u00f3n de salud p\u00fablica de forma aislada. Por ejemplo, la efectividad de los cierres de escuelas todav\u00eda se debate apasionadamente, en parte porque el impacto de esta medida sigue siendo dif\u00edcil de desvincular de otras intervenciones y de la aparici\u00f3n de variantes virales m\u00e1s transmisibles.<\/p>\n<p>Los virus siempre est\u00e1n bajo presi\u00f3n de selecci\u00f3n para que sean m\u00e1s transmisibles. La capacidad de infectar m\u00e1s hospedadores es clave para el \u00e9xito evolutivo de los virus. Se puede lograr una mayor transmisibilidad a trav\u00e9s de varios mecanismos, como una carga viral m\u00e1s alta o eludiendo la inmunidad del hu\u00e9sped, lo que permite que las variantes utilicen una poblaci\u00f3n susceptible m\u00e1s grande. La variante Alpha que surgi\u00f3 a fines de 2020 era intr\u00ednsecamente m\u00e1s transmisible que los linajes anteriores en circulaci\u00f3n. La variante Delta, que es responsable del aumento actual en muchas partes del planeta, es incluso m\u00e1s transmisible que Alpha, pero tambi\u00e9n es menos probable que infecte a personas que est\u00e1n inmunizadas a trav\u00e9s de una infecci\u00f3n o vacunaci\u00f3n previa.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/vi070083.f31.gif\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137381\" title=\"vi070083.f3\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/vi070083.f31.gif\" alt=\"\" width=\"500\" height=\"292\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/vi070083.f31.gif 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/vi070083.f31-300x175.gif 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.annualreviews.org\/doi\/10.1146\/annurev-virology-012420-022445\" target=\"_blank\">Fuente: Moriyama et al. 2020<\/a><\/p>\n<p>La inmunizaci\u00f3n de la poblaci\u00f3n mediante la infecci\u00f3n natural previa y la vacunaci\u00f3n disminuir\u00e1 el n\u00famero R, al reducir la fracci\u00f3n de la poblaci\u00f3n hu\u00e9sped a trav\u00e9s de la cual se puede propagar el virus. A medida que aumenta la proporci\u00f3n de la poblaci\u00f3n que ha sido vacunada y \/ o infectada previamente, la poblaci\u00f3n se acerca al \u201cumbral de inmunidad colectiva\u201d, el punto en el que cada hu\u00e9sped infectado infecta a menos de una persona en promedio. Este valor se encuentra alrededor del 85% para la variante Delta, aunque es poco probable que se logre una inmunidad de grupo estable a largo plazo contra Covid porque la inmunidad disminuir\u00e1 con el tiempo. Adem\u00e1s, aunque las vacunas actuales son notablemente eficaces para reducir la transmisi\u00f3n, la morbilidad y la mortalidad, no bloquean el 100% de las infecciones.<\/p>\n<p>La inmunidad de la poblaci\u00f3n seguir\u00e1 aumentando mediante la vacunaci\u00f3n y la infecci\u00f3n hasta alcanzar un valor de equilibrio. Sars Cov 2 continuar\u00e1 evolucionando, pero eventualmente alcanzar\u00e1 su m\u00e1xima transmisibilidad, que se espera que se mantenga m\u00e1s alta en invierno.<\/p>\n<p>Con la mayor\u00eda de la poblaci\u00f3n vacunada en un futuro pr\u00f3ximo y un probable retorno a las tasas de contacto prepand\u00e9micas, se espera que Covid alcance pronto su equilibrio epid\u00e9mico. Cuando se imponga la estacionalidad la R estar\u00e1 por encima de 1 en invierno y por debajo de 1 en verano. En esta etapa, Covid se unir\u00e1 a los otros 200 virus respiratorios <a href=\"https:\/\/es.wikipedia.org\/wiki\/Endemia\" target=\"_blank\">end\u00e9micos<\/a> <a href=\"https:\/\/espanol.cdc.gov\/flu\/prevent\/index.html\" target=\"_blank\">estacionales<\/a> que circulan a nivel mundial. En resumen, debemos esperar a que pase lo peor de la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Pandemia\" target=\"_blank\">pandemia<\/a> antes de que la estacionalidad se convierta en el factor que dicta la tasa de transmisibilidad del virus.<\/p>\n<p>Probablemente la gran mayor\u00eda de las infecciones en personas previamente inmunizadas sean bastante benignas. No pudimos eliminar Covid y es poco probable que lo hagamos en un futuro previsible. Gracias a las vacunas cada vez m\u00e1s eficaces y epidemiolog\u00eda viral que nos permite actualizar las vacunas cuando sea necesario, los que tienen la suerte de vivir en pa\u00edses ricos se enfrentan a un enemigo muy domesticado, que probablemente ser\u00e1 comparable en su morbilidad y mortalidad asociadas a la gripe, o incluso los cuatro coronavirus del resfriado com\u00fan que ya est\u00e1n en circulaci\u00f3n.<\/p>\n<p>Es posible que transici\u00f3n de Covid a un situaci\u00f3n <a href=\"https:\/\/es.wikipedia.org\/wiki\/Endemia\" target=\"_blank\">end\u00e9mica<\/a> ocurra progresivamente con ondas epid\u00e9micas de amplitud decreciente que se ir\u00e1n asentando en invierno. Este estado end\u00e9mico estacional se alcanzar\u00e1 en momentos diferentes en distintos lugares del mundo. En la mayor parte de Europa y EE. UU., la transici\u00f3n hacia la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Endemia\" target=\"_blank\">situaci\u00f3n de endemia<\/a> ya est\u00e1 muy avanzada, y es poco probable que ocurran en el futuro oleadas epid\u00e9micas vinculadas a una morbilidad y mortalidad masivas, como las que experimentamos antes.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/vi070083.f2.gif\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-137382\" title=\"vi070083.f2\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/vi070083.f2.gif\" alt=\"\" width=\"500\" height=\"215\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/vi070083.f2.gif 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/vi070083.f2-300x129.gif 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.annualreviews.org\/doi\/10.1146\/annurev-virology-012420-022445\" target=\"_blank\">Fuente: Moriyama et al. 2020<\/a><\/p>\n<p>Traducido al castellano de \u201c<a href=\"https:\/\/www.theguardian.com\/commentisfree\/2021\/jul\/16\/covid-19-seasonal-virus-spreading-during-summer-pandemic?CMP=Share_iOSApp_Other\" target=\"_blank\">If Covid-19 is a seasonal virus, why is it spreading during the summer? Francois Balloux<\/a>\u201d<\/p>\n<p><a href=\"https:\/\/www.who.int\/es\/emergencies\/diseases\/novel-coronavirus-2019\/media-resources\/science-in-5\/episode-1\" target=\"_blank\">Inmunidad Colectiva.<\/a> OMS.<\/p>\n<p><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/32196426\/\" target=\"_blank\">Seasonality of Respiratory Viral Infections<\/a>. Miyu Moriyama , Walter J Hugentobler, Akiko Iwasaki. Annu Rev Virol. 2020 Sep 29;7(1):83-101.<\/p>\n<p><a href=\"https:\/\/www.frontiersin.org\/articles\/10.3389\/fpubh.2020.567184\/full\" target=\"_blank\">Seasonality of Respiratory Viral Infections: Will COVID-19 Follow Suit?.<\/a> Amani Audi, Malak AlIbrahim, Malak Kaddoura, Ghina Hijazi, Hadi M. Yassine and Hassan Zaraket.Front. Public Health, 15 September 2020 | https:\/\/doi.org\/10.3389\/fpubh.2020.567184<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al igual que la mayor\u00eda de los dem\u00e1s virus respiratorios el virus se transmite mejor en invierno. Sin embargo las tasas de infecci\u00f3n est\u00e1n experimentando un aumento repentino en el verano. Tambi\u00e9n ha habido grandes olas epid\u00e9micas de Covid-19 en regiones como Am\u00e9rica del Sur e India fuera del invierno. \u00bfA qu\u00e9 se debe? Desde el comienzo de la pandemia, muchos se preguntaron hasta qu\u00e9 punto Covid mostrar\u00eda un comportamiento estacional con un mayor n\u00famero de casos en invierno. La mayor\u00eda de los virus respiratorios en circulaci\u00f3n, incluida la gripe y los cuatro coronavirus end\u00e9micos que contribuyen a los \u00abresfriados\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,1,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Al igual que la mayor\u00eda de los dem\u00e1s virus respiratorios el virus se transmite mejor en invierno. Sin embargo las tasas de infecci\u00f3n est\u00e1n experimentando un aumento repentino en el verano. Tambi\u00e9n ha habido grandes olas epid\u00e9micas de Covid-19 en regiones como Am\u00e9rica del Sur e India fuera del invierno. \u00bfA qu\u00e9 se debe? Desde\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Al igual que la mayor\u00eda de los dem\u00e1s virus respiratorios el virus se transmite mejor en invierno. Sin embargo las tasas de infecci\u00f3n est\u00e1n experimentando un aumento repentino en el verano. Tambi\u00e9n ha habido grandes olas epid\u00e9micas de Covid-19 en regiones como Am\u00e9rica del Sur e India fuera del invierno. \u00bfA qu\u00e9 se debe? Desde\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-07-21T16:07:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-07-21T16:07:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Al igual que la mayor\u00eda de los dem\u00e1s virus respiratorios el virus se transmite mejor en invierno. Sin embargo las tasas de infecci\u00f3n est\u00e1n experimentando un aumento repentino en el verano. Tambi\u00e9n ha habido grandes olas epid\u00e9micas de Covid-19 en regiones como Am\u00e9rica del Sur e India fuera del invierno. \u00bfA qu\u00e9 se debe? Desde\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2021\\\/07\\\/21\\\/137373#blogposting\",\"name\":\"Si el SARS Cov2, causante de COVID 19 es estacional, \\u00bfpor qu\\u00e9 se est\\u00e1 transmitiendo tan eficazmente en verano? - Ciencia Marina y otros asuntos\",\"headline\":\"Si el SARS Cov2, causante de COVID 19 es estacional, \\u00bfpor qu\\u00e9 se est\\u00e1 transmitiendo tan eficazmente en verano?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2021\\\/07\\\/descarga-41.jpeg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2021\\\/07\\\/21\\\/137373\\\/#articleImage\",\"width\":500,\"height\":333},\"datePublished\":\"2021-07-21T17:07:04+01:00\",\"dateModified\":\"2021-07-21T17:07:04+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2021\\\/07\\\/21\\\/137373#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2021\\\/07\\\/21\\\/137373#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, General, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2021\\\/07\\\/21\\\/137373#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2021\\\/07\\\/21\\\/137373#listItem\",\"name\":\"Si el SARS Cov2, causante de COVID 19 es estacional, \\u00bfpor qu\\u00e9 se est\\u00e1 transmitiendo tan eficazmente en verano?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2021\\\/07\\\/21\\\/137373#listItem\",\"position\":3,\"name\":\"Si el SARS Cov2, causante de COVID 19 es estacional, \\u00bfpor qu\\u00e9 se est\\u00e1 transmitiendo tan eficazmente en verano?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2021\\\/07\\\/21\\\/137373#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2021\\\/07\\\/21\\\/137373\",\"name\":\"Si el SARS Cov2, causante de COVID 19 es estacional, \\u00bfpor qu\\u00e9 se est\\u00e1 transmitiendo tan eficazmente en verano? - Ciencia Marina y otros asuntos\",\"description\":\"Al igual que la mayor\\u00eda de los dem\\u00e1s virus respiratorios el virus se transmite mejor en invierno. Sin embargo las tasas de infecci\\u00f3n est\\u00e1n experimentando un aumento repentino en el verano. Tambi\\u00e9n ha habido grandes olas epid\\u00e9micas de Covid-19 en regiones como Am\\u00e9rica del Sur e India fuera del invierno. \\u00bfA qu\\u00e9 se debe? Desde\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2021\\\/07\\\/21\\\/137373#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2021-07-21T17:07:04+01:00\",\"dateModified\":\"2021-07-21T17:07:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano? - Ciencia Marina y otros asuntos","description":"Al igual que la mayor\u00eda de los dem\u00e1s virus respiratorios el virus se transmite mejor en invierno. Sin embargo las tasas de infecci\u00f3n est\u00e1n experimentando un aumento repentino en el verano. Tambi\u00e9n ha habido grandes olas epid\u00e9micas de Covid-19 en regiones como Am\u00e9rica del Sur e India fuera del invierno. \u00bfA qu\u00e9 se debe? Desde","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373#blogposting","name":"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano? - Ciencia Marina y otros asuntos","headline":"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2021\/07\/descarga-41.jpeg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373\/#articleImage","width":500,"height":333},"datePublished":"2021-07-21T17:07:04+01:00","dateModified":"2021-07-21T17:07:04+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373#webpage"},"articleSection":"CoVid19-SARS Cov2, General, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373#listItem","name":"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373#listItem","position":3,"name":"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373","name":"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano? - Ciencia Marina y otros asuntos","description":"Al igual que la mayor\u00eda de los dem\u00e1s virus respiratorios el virus se transmite mejor en invierno. Sin embargo las tasas de infecci\u00f3n est\u00e1n experimentando un aumento repentino en el verano. Tambi\u00e9n ha habido grandes olas epid\u00e9micas de Covid-19 en regiones como Am\u00e9rica del Sur e India fuera del invierno. \u00bfA qu\u00e9 se debe? Desde","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2021-07-21T17:07:04+01:00","dateModified":"2021-07-21T17:07:04+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano? - Ciencia Marina y otros asuntos","og:description":"Al igual que la mayor\u00eda de los dem\u00e1s virus respiratorios el virus se transmite mejor en invierno. Sin embargo las tasas de infecci\u00f3n est\u00e1n experimentando un aumento repentino en el verano. Tambi\u00e9n ha habido grandes olas epid\u00e9micas de Covid-19 en regiones como Am\u00e9rica del Sur e India fuera del invierno. \u00bfA qu\u00e9 se debe? Desde","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2021-07-21T16:07:04+00:00","article:modified_time":"2021-07-21T16:07:04+00:00","twitter:card":"summary","twitter:title":"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano? - Ciencia Marina y otros asuntos","twitter:description":"Al igual que la mayor\u00eda de los dem\u00e1s virus respiratorios el virus se transmite mejor en invierno. Sin embargo las tasas de infecci\u00f3n est\u00e1n experimentando un aumento repentino en el verano. Tambi\u00e9n ha habido grandes olas epid\u00e9micas de Covid-19 en regiones como Am\u00e9rica del Sur e India fuera del invierno. \u00bfA qu\u00e9 se debe? Desde","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"137373","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-04 00:41:56","updated":"2026-05-26 19:41:01","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSi el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"Si el SARS Cov2, causante de COVID 19 es estacional, \u00bfpor qu\u00e9 se est\u00e1 transmitiendo tan eficazmente en verano?","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2021\/07\/21\/137373"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137373"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=137373"}],"version-history":[{"count":11,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137373\/revisions"}],"predecessor-version":[{"id":137389,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/137373\/revisions\/137389"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=137373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=137373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=137373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}