{"id":138049,"date":"2022-02-22T16:58:10","date_gmt":"2022-02-22T15:58:10","guid":{"rendered":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=138049"},"modified":"2022-02-22T16:58:10","modified_gmt":"2022-02-22T15:58:10","slug":"coronavirus-cuando-termina-esto","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049","title":{"rendered":"Coronavirus. \u00bfCu\u00e1ndo termina esto?"},"content":{"rendered":"<p>Mientras el mundo se estaba reconstruyendo despu\u00e9s de la Primera Guerra Mundial, John Maynard Keynes escribi\u00f3 que el futuro es \u201cfluctuante, vago e incierto\u201d. Y lleg\u00f3 la d\u00e9cada de 1930 con un desempleo masivo que acab\u00f3 en un desastre internacional que pod\u00eda y no pod\u00eda preverse.<\/p>\n<p>La pandemia nos enfrenta brutalmente con la incertidumbre que acompa\u00f1a la historia de nuestra especie. Aunque creamos lo contrario, no podemos predecir lo que suceder\u00e1 en el espacio de un segundo, un minuto, una hora o un d\u00eda. De un momento a otro, la pandemia parece girar y se\u00f1alar con el dedo a cualquiera, incluso a los que cre\u00edan que eran inmunes.<\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/f_ci_39_1100x680.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-138050\" src=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/f_ci_39_1100x680.jpeg\" alt=\"\" width=\"500\" height=\"318\" srcset=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/f_ci_39_1100x680.jpeg 500w, https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/f_ci_39_1100x680-300x191.jpeg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><!--more-->La expansi\u00f3n del virus y el programa de vacunaci\u00f3n en diferentes pa\u00edses ha sido cruelmente desigual, pero mientras COVID siga siendo global, tendremos oleadas de gravedad variable en cualquier lugar y en cualquier momento. La pandemia m\u00e1s mortal del siglo XX, la gripe de 1918 al final de la Primera Guerra Mundial, pas\u00f3 ola tras ola y dur\u00f3 casi cuatro a\u00f1os.<\/p>\n<p>El 4 de marzo de 2020 escrib\u00ed esto en mi blog\u201d El control de pasajeros puede ralentizar la expansi\u00f3n, pero no evitarla. Ya sucedi\u00f3 con el c\u00f3lera en el siglo XIX, o las crisis de \u00c9bola en la \u00faltima d\u00e9cada. Los confinamientos protegieron algunas poblaciones en la gripe de 1918 y 1919 pero tambi\u00e9n hicieron que pa\u00edses como Portugal no recibiera ayuda. Mientras tanto los grandes diseminadores de la enfermedad, las tropas de la I Guerra Mundial, se mov\u00edan libremente y sin control a trav\u00e9s de las fronteras.\u201d<\/p>\n<p>\u201cLos virus son maestros del enga\u00f1o. La evidencia acumulada es que este nuevo coronavirus tarda unos cinco d\u00edas en producir s\u00edntomas y los pacientes son contagiosos antes de que estos s\u00edntomas aparezcan. En muchos pa\u00edses el virus estaba presente antes de que se lo buscase activamente. Se est\u00e1 demostrando que algunos fallecimientos por neumon\u00eda, anteriores a la alarma sanitaria, podr\u00edan haber estar relacionados con la presencia de este nuevo coronavirus.\u201d<\/p>\n<p>Casi dos a\u00f1os despu\u00e9s, la gente est\u00e1 desesperada por sentir que hemos pasado el ecuador, que tenemos el final a la vista, solo para enfrentarnos otra vez a un futuro que parece una de nuestras borrascas m\u00e1s negras. Nadie sabe, con cierto grado de confianza, qu\u00e9 suceder\u00e1 a continuaci\u00f3n. Cualquier afirmaci\u00f3n rotunda sobre el futuro es un fraude.<\/p>\n<p><a href=\"http:\/\/sedici.unlp.edu.ar\/bitstream\/handle\/10915\/8458\/Documento_completo.pdf?sequence=1&amp;isAllowed=y\" target=\"_blank\" rel=\"noopener\">Sigmund Freud dijo una vez que nadie cree en su propia muerte<\/a>. En el inconsciente, hay un espacio en blanco donde deber\u00eda estar el conocimiento de esto hecho cierto sobre nuestro futuro. Si la pandemia ha cambiado la vida para siempre, podr\u00eda ser porque esa incapacidad para tolerar la muerte ha sobrepasado los umbrales de lo que no viv\u00edamos desde hace muchos a\u00f1os en el mundo occidental.<\/p>\n<p>Muchos cient\u00edficos piensan que la variante \u00d3micron es el primer paso en un proceso de adaptaci\u00f3n del virus a la poblaci\u00f3n humana en el que la enfermedad cursar\u00eda con s\u00edntomas m\u00e1s leves. De momento no ha transcurrido el tiempo suficiente para comprobar si esta hip\u00f3tesis es s\u00f3lida.<\/p>\n<p>Mientras tanto, necesitamos aumentar la cobertura de vacunaci\u00f3n en todo el mundo, no solo en nuestro entorno privilegiado, realizar cribados masivos r\u00e1pidos, mejorar la ventilaci\u00f3n interior, animar a seguir usando mascarillas (incluso mascarillas de mayor protecci\u00f3n) y ayudar a las personas a saber cu\u00e1ndo est\u00e1n infectadas. Existe informaci\u00f3n preliminar de que recibir un refuerzo aumenta la protecci\u00f3n superior proporcionada solo por las primeras dosis de vacunas.<\/p>\n<p>Adoptar estas medidas mientras se despejan las inc\u00f3gnitas ayudar\u00e1 a lograr un equilibrio entre la reducci\u00f3n del riesgo y al mismo tiempo disfrutar de nuestras vidas. Eso es lo que esperan los cient\u00edficos, como todos los dem\u00e1s. 2022 ser\u00e1 un a\u00f1o mejor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras el mundo se estaba reconstruyendo despu\u00e9s de la Primera Guerra Mundial, John Maynard Keynes escribi\u00f3 que el futuro es \u201cfluctuante, vago e incierto\u201d. Y lleg\u00f3 la d\u00e9cada de 1930 con un desempleo masivo que acab\u00f3 en un desastre internacional que pod\u00eda y no pod\u00eda preverse. La pandemia nos enfrenta brutalmente con la incertidumbre que acompa\u00f1a la historia de nuestra especie. Aunque creamos lo contrario, no podemos predecir lo que suceder\u00e1 en el espacio de un segundo, un minuto, una hora o un d\u00eda. De un momento a otro, la pandemia parece girar y se\u00f1alar con el dedo a cualquiera,\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[4145,356],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mientras el mundo se estaba reconstruyendo despu\u00e9s de la Primera Guerra Mundial, John Maynard Keynes escribi\u00f3 que el futuro es \u201cfluctuante, vago e incierto\u201d. Y lleg\u00f3 la d\u00e9cada de 1930 con un desempleo masivo que acab\u00f3 en un desastre internacional que pod\u00eda y no pod\u00eda preverse. La pandemia nos enfrenta brutalmente con la incertidumbre que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coronavirus. \u00bfCu\u00e1ndo termina esto? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Mientras el mundo se estaba reconstruyendo despu\u00e9s de la Primera Guerra Mundial, John Maynard Keynes escribi\u00f3 que el futuro es \u201cfluctuante, vago e incierto\u201d. Y lleg\u00f3 la d\u00e9cada de 1930 con un desempleo masivo que acab\u00f3 en un desastre internacional que pod\u00eda y no pod\u00eda preverse. La pandemia nos enfrenta brutalmente con la incertidumbre que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-02-22T15:58:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-02-22T15:58:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coronavirus. \u00bfCu\u00e1ndo termina esto? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Mientras el mundo se estaba reconstruyendo despu\u00e9s de la Primera Guerra Mundial, John Maynard Keynes escribi\u00f3 que el futuro es \u201cfluctuante, vago e incierto\u201d. Y lleg\u00f3 la d\u00e9cada de 1930 con un desempleo masivo que acab\u00f3 en un desastre internacional que pod\u00eda y no pod\u00eda preverse. La pandemia nos enfrenta brutalmente con la incertidumbre que\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2022\\\/02\\\/22\\\/138049#blogposting\",\"name\":\"Coronavirus. \\u00bfCu\\u00e1ndo termina esto? - Ciencia Marina y otros asuntos\",\"headline\":\"Coronavirus. \\u00bfCu\\u00e1ndo termina esto?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2022\\\/02\\\/f_ci_39_1100x680.jpeg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2022\\\/02\\\/22\\\/138049\\\/#articleImage\",\"width\":500,\"height\":318},\"datePublished\":\"2022-02-22T16:58:10+01:00\",\"dateModified\":\"2022-02-22T16:58:10+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2022\\\/02\\\/22\\\/138049#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2022\\\/02\\\/22\\\/138049#webpage\"},\"articleSection\":\"CoVid19-SARS Cov2, Solidaridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2022\\\/02\\\/22\\\/138049#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/solidaridad#listItem\",\"name\":\"Solidaridad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/solidaridad#listItem\",\"position\":2,\"name\":\"Solidaridad\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/solidaridad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2022\\\/02\\\/22\\\/138049#listItem\",\"name\":\"Coronavirus. \\u00bfCu\\u00e1ndo termina esto?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2022\\\/02\\\/22\\\/138049#listItem\",\"position\":3,\"name\":\"Coronavirus. \\u00bfCu\\u00e1ndo termina esto?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/solidaridad#listItem\",\"name\":\"Solidaridad\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2022\\\/02\\\/22\\\/138049#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2022\\\/02\\\/22\\\/138049\",\"name\":\"Coronavirus. \\u00bfCu\\u00e1ndo termina esto? - Ciencia Marina y otros asuntos\",\"description\":\"Mientras el mundo se estaba reconstruyendo despu\\u00e9s de la Primera Guerra Mundial, John Maynard Keynes escribi\\u00f3 que el futuro es \\u201cfluctuante, vago e incierto\\u201d. Y lleg\\u00f3 la d\\u00e9cada de 1930 con un desempleo masivo que acab\\u00f3 en un desastre internacional que pod\\u00eda y no pod\\u00eda preverse. La pandemia nos enfrenta brutalmente con la incertidumbre que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2022\\\/02\\\/22\\\/138049#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2022-02-22T16:58:10+01:00\",\"dateModified\":\"2022-02-22T16:58:10+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Coronavirus. \u00bfCu\u00e1ndo termina esto? - Ciencia Marina y otros asuntos","description":"Mientras el mundo se estaba reconstruyendo despu\u00e9s de la Primera Guerra Mundial, John Maynard Keynes escribi\u00f3 que el futuro es \u201cfluctuante, vago e incierto\u201d. Y lleg\u00f3 la d\u00e9cada de 1930 con un desempleo masivo que acab\u00f3 en un desastre internacional que pod\u00eda y no pod\u00eda preverse. La pandemia nos enfrenta brutalmente con la incertidumbre que","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049#blogposting","name":"Coronavirus. \u00bfCu\u00e1ndo termina esto? - Ciencia Marina y otros asuntos","headline":"Coronavirus. \u00bfCu\u00e1ndo termina esto?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/f_ci_39_1100x680.jpeg","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049\/#articleImage","width":500,"height":318},"datePublished":"2022-02-22T16:58:10+01:00","dateModified":"2022-02-22T16:58:10+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049#webpage"},"articleSection":"CoVid19-SARS Cov2, Solidaridad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/solidaridad#listItem","name":"Solidaridad"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/solidaridad#listItem","position":2,"name":"Solidaridad","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/solidaridad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049#listItem","name":"Coronavirus. \u00bfCu\u00e1ndo termina esto?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049#listItem","position":3,"name":"Coronavirus. \u00bfCu\u00e1ndo termina esto?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/solidaridad#listItem","name":"Solidaridad"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049","name":"Coronavirus. \u00bfCu\u00e1ndo termina esto? - Ciencia Marina y otros asuntos","description":"Mientras el mundo se estaba reconstruyendo despu\u00e9s de la Primera Guerra Mundial, John Maynard Keynes escribi\u00f3 que el futuro es \u201cfluctuante, vago e incierto\u201d. Y lleg\u00f3 la d\u00e9cada de 1930 con un desempleo masivo que acab\u00f3 en un desastre internacional que pod\u00eda y no pod\u00eda preverse. La pandemia nos enfrenta brutalmente con la incertidumbre que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2022-02-22T16:58:10+01:00","dateModified":"2022-02-22T16:58:10+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"Coronavirus. \u00bfCu\u00e1ndo termina esto? - Ciencia Marina y otros asuntos","og:description":"Mientras el mundo se estaba reconstruyendo despu\u00e9s de la Primera Guerra Mundial, John Maynard Keynes escribi\u00f3 que el futuro es \u201cfluctuante, vago e incierto\u201d. Y lleg\u00f3 la d\u00e9cada de 1930 con un desempleo masivo que acab\u00f3 en un desastre internacional que pod\u00eda y no pod\u00eda preverse. La pandemia nos enfrenta brutalmente con la incertidumbre que","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2022-02-22T15:58:10+00:00","article:modified_time":"2022-02-22T15:58:10+00:00","twitter:card":"summary","twitter:title":"Coronavirus. \u00bfCu\u00e1ndo termina esto? - Ciencia Marina y otros asuntos","twitter:description":"Mientras el mundo se estaba reconstruyendo despu\u00e9s de la Primera Guerra Mundial, John Maynard Keynes escribi\u00f3 que el futuro es \u201cfluctuante, vago e incierto\u201d. Y lleg\u00f3 la d\u00e9cada de 1930 con un desempleo masivo que acab\u00f3 en un desastre internacional que pod\u00eda y no pod\u00eda preverse. La pandemia nos enfrenta brutalmente con la incertidumbre que","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"138049","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-04 00:24:33","updated":"2026-05-26 19:49:16","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/solidaridad\" title=\"Solidaridad\">Solidaridad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCoronavirus. \u00bfCu\u00e1ndo termina esto?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"Solidaridad","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/solidaridad"},{"label":"Coronavirus. \u00bfCu\u00e1ndo termina esto?","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2022\/02\/22\/138049"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/138049"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=138049"}],"version-history":[{"count":1,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/138049\/revisions"}],"predecessor-version":[{"id":138051,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/138049\/revisions\/138051"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=138049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=138049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=138049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}