{"id":139208,"date":"2025-07-23T08:13:10","date_gmt":"2025-07-23T07:13:10","guid":{"rendered":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=139208"},"modified":"2025-07-23T08:13:10","modified_gmt":"2025-07-23T07:13:10","slug":"la-mente-del-pulpo","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208","title":{"rendered":"La mente del pulpo"},"content":{"rendered":"<p style=\"font-weight: 400\"><strong>c\u00f3mo un brazo falso enga\u00f1\u00f3 a uno de los invertebrados m\u00e1s inteligentes del planeta.<\/strong><\/p>\n<p style=\"font-weight: 400\"><!--more-->\u00bfQu\u00e9 ocurre cuando se enga\u00f1a a un pulpo para que crea que un brazo falso es suyo? La respuesta podr\u00eda cambiar nuestra comprensi\u00f3n sobre la conciencia corporal, no solo en animales como nosotros, sino en todo el \u00e1rbol de la vida.<\/p>\n<p style=\"font-weight: 400\">En un estudio sorprendente, investigadores han demostrado que los pulpos pueden ser v\u00edctimas de la famosa \u201c<a href=\"https:\/\/maldita.es\/malditaciencia\/20211227\/ciencia-ilusion-mano-goma-sentir-estimulos-objetos-ajenos\/\" target=\"_blank\" rel=\"noopener\">ilusi\u00f3n del brazo de goma\u201d<\/a>, un truco psicol\u00f3gico observado por primera vez en humanos. Puede parecer un experimento curioso de laboratorio, pero abre la puerta a preguntas profundas sobre la conciencia, la imagen corporal y c\u00f3mo la evoluci\u00f3n ha dado lugar, de manera independiente, a cerebros complejos que \u201csaben\u201d a qu\u00e9 cuerpo pertenecen.<\/p>\n<p style=\"font-weight: 400\"><strong>Una idea nacida de la psicolog\u00eda<\/strong><\/p>\n<p style=\"font-weight: 400\">La ilusi\u00f3n del brazo de goma es un cl\u00e1sico de la neurociencia y la psicolog\u00eda. En la versi\u00f3n original con humanos, se oculta la mano real del participante y se coloca una mano falsa realista frente a \u00e9l. Si ambas manos (la real y la falsa) se acarician de forma sincronizada, muchas personas empiezan a sentir que la mano falsa es suya. Esta ilusi\u00f3n revela c\u00f3mo el cerebro integra se\u00f1ales visuales, t\u00e1ctiles y proprioceptivas para construir un sentido de pertenencia corporal.<\/p>\n<p style=\"font-weight: 400\">Hasta ahora, este tipo de conciencia corporal solo se hab\u00eda estudiado en vertebrados como humanos, monos e incluso ratones. Pero, \u00bfqu\u00e9 pasa con animales con cuerpos y cerebros radicalmente distintos, como los pulpos?<\/p>\n<p style=\"font-weight: 400\"><strong>El experimento: un brazo falso y algunas caricias suaves<\/strong><\/p>\n<p style=\"font-weight: 400\"><a href=\"https:\/\/www.cell.com\/current-biology\/fulltext\/S0960-9822(25)00592-5\" target=\"_blank\" rel=\"noopener\">Sumire Kawashima y Yuzuru Ikeda<\/a>, del Instituto de Ciencia y Tecnolog\u00eda de Okinawa (OIST), idearon una ingeniosa versi\u00f3n de la ilusi\u00f3n para&nbsp;<em>Callistoctopus aspilosomatis<\/em>, una especie de pulpo nocturno de tama\u00f1o peque\u00f1o. Colocaron una r\u00e9plica de silicona blanda y realista de un brazo de pulpo directamente sobre uno de los brazos reales del animal, fuera de su campo de visi\u00f3n. Luego, con pinzas, acariciaron simult\u00e1neamente ambos brazos durante unos 8 segundos.<\/p>\n<p style=\"font-weight: 400\">Despu\u00e9s de la estimulaci\u00f3n sincronizada, pellizcaron el brazo falso con unas pinzas. Y aqu\u00ed viene la sorpresa: el pulpo reaccion\u00f3 como si le hubieran hecho da\u00f1o de verdad. Retir\u00f3 bruscamente su brazo real, cambi\u00f3 de color (una se\u00f1al conocida de estr\u00e9s) o incluso huy\u00f3.<\/p>\n<p style=\"font-weight: 400\">Estas respuestas defensivas sugieren que el pulpo hab\u00eda integrado las se\u00f1ales visuales y t\u00e1ctiles y \u201ccre\u00eddo\u201d que el brazo falso era parte de su cuerpo.<\/p>\n<p style=\"font-weight: 400\"><strong>Pruebas de control: el tiempo y la postura importan<\/strong><\/p>\n<p style=\"font-weight: 400\">Para asegurarse de que los resultados no eran aleatorios, los investigadores realizaron varios experimentos de control. Cuando las caricias eran asincr\u00f3nicas, o cuando el brazo falso estaba en una postura poco natural (no coincid\u00eda con la del real), o cuando no se realizaban caricias, no se produc\u00eda ninguna reacci\u00f3n ante el pellizco.<\/p>\n<p style=\"font-weight: 400\">Esto refleja exactamente lo que se observa en humanos: la ilusi\u00f3n solo funciona cuando todo est\u00e1 perfectamente coordinado. Esta especificidad sugiere que no se trata de un simple reflejo, sino de un proceso activo de integraci\u00f3n multisensorial, algo que normalmente asociamos con cerebros vertebrados.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfQu\u00e9 nos dice esto sobre la mente del pulpo?<\/strong><\/p>\n<p style=\"font-weight: 400\">Los pulpos son rarezas evolutivas. Son moluscos \u2014parientes de caracoles y almejas\u2014 pero tienen sistemas nerviosos enormes, con m\u00e1s de 500 millones de neuronas (m\u00e1s que algunos mam\u00edferos peque\u00f1os). Y a diferencia de nosotros, la mayor\u00eda de sus neuronas no est\u00e1n concentradas en un cerebro central, sino distribuidas a lo largo de sus brazos.<\/p>\n<p style=\"font-weight: 400\">A pesar de estas diferencias, el estudio revela un caso de evoluci\u00f3n convergente: los pulpos, como los humanos, parecen construir una noci\u00f3n del \u201cyo corporal\u201d a partir de la informaci\u00f3n sensorial. Eso sugiere que no hace falta tener un cerebro como el nuestro para lograr algo tan aparentemente abstracto como identificar las extremidades propias.<\/p>\n<p style=\"font-weight: 400\"><strong>\u00bfUna ventana a la conciencia?<\/strong><\/p>\n<p style=\"font-weight: 400\">Si un pulpo puede ser enga\u00f1ado para creer que un brazo falso es suyo, \u00bfqu\u00e9 nos dice eso sobre c\u00f3mo percibe su cuerpo? Y m\u00e1s all\u00e1: \u00bfqu\u00e9 nos dice sobre los or\u00edgenes evolutivos de la conciencia?<\/p>\n<p style=\"font-weight: 400\">A menudo pensamos que la autoconciencia \u2014especialmente la que implica modelos mentales del cuerpo\u2014 es fruto de una vida social compleja o del lenguaje. Pero los pulpos son solitarios y no tienen nada parecido al habla. Sin embargo, muestran signos de poseer un modelo interno de su cuerpo.<\/p>\n<p style=\"font-weight: 400\">Quiz\u00e1s la conciencia corporal no es tan rara como pens\u00e1bamos. Quiz\u00e1s sea una caracter\u00edstica fundamental para sobrevivir en un mundo f\u00edsico, una que ha evolucionado m\u00faltiples veces en la historia de la vida.<\/p>\n<p style=\"font-weight: 400\"><strong>M\u00e1s all\u00e1 del oc\u00e9ano<\/strong><\/p>\n<p style=\"font-weight: 400\">Los hallazgos podr\u00edan tener implicaciones mucho m\u00e1s all\u00e1 de la biolog\u00eda marina. Comprender c\u00f3mo un sistema nervioso tan diferente logra representar el cuerpo puede inspirar nuevos enfoques en rob\u00f3tica, especialmente en robots blandos y flexibles. Tambi\u00e9n puede ofrecer pistas para tratar trastornos neurol\u00f3gicos humanos en los que se pierde el sentido del cuerpo, como el s\u00edndrome del miembro fantasma o la asomatognosia.<\/p>\n<p style=\"font-weight: 400\">Y, por supuesto, a\u00f1ade una capa m\u00e1s al misterio del pulpo: una criatura sin huesos, con tres corazones, sangre azul y ahora\u2026 una mente que puede ser enga\u00f1ada igual que la nuestra.<\/p>\n<p><iframe loading=\"lazy\" title=\"Rubber arm illusion in octopus \/ Curr. Biol., July 21, 2025 (Vol. 35, Issue 14)\" width=\"1290\" height=\"726\" src=\"https:\/\/www.youtube.com\/embed\/mv5fY-DB6Lg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"font-weight: 400\"><strong>Para saber m\u00e1s<\/strong><\/p>\n<ul style=\"font-weight: 400\">\n<li>Kawashima, S., &amp; Ikeda, Y. (2025).&nbsp;<em>Rubber Arm Illusion in Octopus<\/em>.&nbsp;<em>Current Biology<\/em>.&nbsp;<a href=\"https:\/\/www.cell.com\/current-biology\/fulltext\/S0960-9822(25)00592-5\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cell.com\/current-biology\/fulltext\/S0960-9822(25)00592-5<\/a><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>c\u00f3mo un brazo falso enga\u00f1\u00f3 a uno de los invertebrados m\u00e1s inteligentes del planeta.<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"c\u00f3mo un brazo falso enga\u00f1\u00f3 a uno de los invertebrados m\u00e1s inteligentes del planeta. \u00bfQu\u00e9 ocurre cuando se enga\u00f1a a un pulpo para que crea que un brazo falso es suyo? La respuesta podr\u00eda cambiar nuestra comprensi\u00f3n sobre la conciencia corporal, no solo en animales como nosotros, sino en todo el \u00e1rbol de la vida.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La mente del pulpo - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"c\u00f3mo un brazo falso enga\u00f1\u00f3 a uno de los invertebrados m\u00e1s inteligentes del planeta. \u00bfQu\u00e9 ocurre cuando se enga\u00f1a a un pulpo para que crea que un brazo falso es suyo? La respuesta podr\u00eda cambiar nuestra comprensi\u00f3n sobre la conciencia corporal, no solo en animales como nosotros, sino en todo el \u00e1rbol de la vida.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-07-23T07:13:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-07-23T07:13:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La mente del pulpo - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"c\u00f3mo un brazo falso enga\u00f1\u00f3 a uno de los invertebrados m\u00e1s inteligentes del planeta. \u00bfQu\u00e9 ocurre cuando se enga\u00f1a a un pulpo para que crea que un brazo falso es suyo? La respuesta podr\u00eda cambiar nuestra comprensi\u00f3n sobre la conciencia corporal, no solo en animales como nosotros, sino en todo el \u00e1rbol de la vida.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2025\\\/07\\\/23\\\/139208#blogposting\",\"name\":\"La mente del pulpo - Ciencia Marina y otros asuntos\",\"headline\":\"La mente del pulpo\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2025\\\/07\\\/23\\\/139208\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2025-07-23T08:13:10+01:00\",\"dateModified\":\"2025-07-23T08:13:10+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2025\\\/07\\\/23\\\/139208#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2025\\\/07\\\/23\\\/139208#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2025\\\/07\\\/23\\\/139208#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2025\\\/07\\\/23\\\/139208#listItem\",\"name\":\"La mente del pulpo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2025\\\/07\\\/23\\\/139208#listItem\",\"position\":3,\"name\":\"La mente del pulpo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2025\\\/07\\\/23\\\/139208#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2025\\\/07\\\/23\\\/139208\",\"name\":\"La mente del pulpo - Ciencia Marina y otros asuntos\",\"description\":\"c\\u00f3mo un brazo falso enga\\u00f1\\u00f3 a uno de los invertebrados m\\u00e1s inteligentes del planeta. \\u00bfQu\\u00e9 ocurre cuando se enga\\u00f1a a un pulpo para que crea que un brazo falso es suyo? La respuesta podr\\u00eda cambiar nuestra comprensi\\u00f3n sobre la conciencia corporal, no solo en animales como nosotros, sino en todo el \\u00e1rbol de la vida.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2025\\\/07\\\/23\\\/139208#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2025-07-23T08:13:10+01:00\",\"dateModified\":\"2025-07-23T08:13:10+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La mente del pulpo - Ciencia Marina y otros asuntos","description":"c\u00f3mo un brazo falso enga\u00f1\u00f3 a uno de los invertebrados m\u00e1s inteligentes del planeta. \u00bfQu\u00e9 ocurre cuando se enga\u00f1a a un pulpo para que crea que un brazo falso es suyo? La respuesta podr\u00eda cambiar nuestra comprensi\u00f3n sobre la conciencia corporal, no solo en animales como nosotros, sino en todo el \u00e1rbol de la vida.","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208#blogposting","name":"La mente del pulpo - Ciencia Marina y otros asuntos","headline":"La mente del pulpo","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208\/#articleImage","width":217,"height":72},"datePublished":"2025-07-23T08:13:10+01:00","dateModified":"2025-07-23T08:13:10+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208#listItem","name":"La mente del pulpo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208#listItem","position":3,"name":"La mente del pulpo","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208","name":"La mente del pulpo - Ciencia Marina y otros asuntos","description":"c\u00f3mo un brazo falso enga\u00f1\u00f3 a uno de los invertebrados m\u00e1s inteligentes del planeta. \u00bfQu\u00e9 ocurre cuando se enga\u00f1a a un pulpo para que crea que un brazo falso es suyo? La respuesta podr\u00eda cambiar nuestra comprensi\u00f3n sobre la conciencia corporal, no solo en animales como nosotros, sino en todo el \u00e1rbol de la vida.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2025-07-23T08:13:10+01:00","dateModified":"2025-07-23T08:13:10+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"La mente del pulpo - Ciencia Marina y otros asuntos","og:description":"c\u00f3mo un brazo falso enga\u00f1\u00f3 a uno de los invertebrados m\u00e1s inteligentes del planeta. \u00bfQu\u00e9 ocurre cuando se enga\u00f1a a un pulpo para que crea que un brazo falso es suyo? La respuesta podr\u00eda cambiar nuestra comprensi\u00f3n sobre la conciencia corporal, no solo en animales como nosotros, sino en todo el \u00e1rbol de la vida.","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2025-07-23T07:13:10+00:00","article:modified_time":"2025-07-23T07:13:10+00:00","twitter:card":"summary","twitter:title":"La mente del pulpo - Ciencia Marina y otros asuntos","twitter:description":"c\u00f3mo un brazo falso enga\u00f1\u00f3 a uno de los invertebrados m\u00e1s inteligentes del planeta. \u00bfQu\u00e9 ocurre cuando se enga\u00f1a a un pulpo para que crea que un brazo falso es suyo? La respuesta podr\u00eda cambiar nuestra comprensi\u00f3n sobre la conciencia corporal, no solo en animales como nosotros, sino en todo el \u00e1rbol de la vida.","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"139208","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":0,"frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2025-07-23 07:06:05","updated":"2026-05-26 20:08:38","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa mente del pulpo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"La mente del pulpo","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2025\/07\/23\/139208"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/139208"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=139208"}],"version-history":[{"count":4,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/139208\/revisions"}],"predecessor-version":[{"id":139212,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/139208\/revisions\/139212"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=139208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=139208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=139208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}