{"id":139476,"date":"2026-07-03T11:44:41","date_gmt":"2026-07-03T10:44:41","guid":{"rendered":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/?p=139476"},"modified":"2026-07-03T11:44:41","modified_gmt":"2026-07-03T10:44:41","slug":"que-pescados-son-mas-sanos-para-comer","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476","title":{"rendered":"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer?"},"content":{"rendered":"<p>Hace unos a\u00f1os escrib\u00ed sobre <a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2016\/11\/14\/134485\" target=\"_blank\" rel=\"noopener\">el salm\u00f3n y sus problemas<\/a> y la respuesta de la Embajada de Noruega fue tan expedita que mereci\u00f3 un segundo <em>post<\/em>. No estoy acostumbrado a tanto inter\u00e9s diplom\u00e1tico. Aun as\u00ed, el tema del pescado \u2013qu\u00e9 comer, cu\u00e1nto, de d\u00f3nde viene y si es seguro\u2013 sigue siendo uno de los m\u00e1s confusos para el consumidor medio. Y la confusi\u00f3n no es accidental: conviven intereses industriales, alarmas medi\u00e1ticas mal calibradas y mensajes de salud p\u00fablica que se quedan en el titular sin matizar lo que realmente dice la ciencia.<\/p>\n<h2>La mayor transformaci\u00f3n en la historia de la pesca<\/h2>\n<p>Estamos asistiendo a un cambio sin precedentes en la forma en que obtenemos prote\u00edna marina. <a href=\"https:\/\/www.fao.org\/newsroom\/detail\/fao-report-global-fisheries-and-aquaculture-production-reaches-a-new-record-high\/es\" target=\"_blank\" rel=\"noopener\">La producci\u00f3n mundial de pescado alcanz\u00f3 en 2022 los 223,2 millones de toneladas<\/a> y, por primera vez en la historia, la acuicultura super\u00f3 a la pesca extractiva como principal fuente de animales acu\u00e1ticos.<\/p>\n<p>Que la mitad del pescado que se consume en el mundo haya sido cultivado \u2013y no capturado\u2013 es un dato que merece reflexi\u00f3n. La pesca de captura <a href=\"https:\/\/openknowledge.fao.org\/server\/api\/core\/bitstreams\/ae439370-d5a7-4552-9968-46ab8dd13b58\/content\/sofia\/2022\/capture-fisheries-production.html\" target=\"_blank\" rel=\"noopener\">se ha estabilizado desde finales de los a\u00f1os 1980 en torno a 90 millones de toneladas anuales<\/a>, mientras que la acuicultura no ha dejado de crecer: un 527&nbsp;% entre 1990 y 2018.<\/p>\n<p>Paralelamente, el porcentaje de poblaciones marinas explotadas dentro de niveles biol\u00f3gicamente sostenibles <a href=\"https:\/\/www.pactomundial.org\/ods\/14-vida-submarina\/\" target=\"_blank\" rel=\"noopener\">ha bajado al 62,3&nbsp;% en 2021<\/a>, lo que significa que m\u00e1s de un tercio de las pesquer\u00edas monitorizadas se explotan por encima de su capacidad de recuperaci\u00f3n.<\/p>\n<p>En este contexto, comer pescado es una actividad sustancialmente distinta a la de hace treinta a\u00f1os. Hoy la pregunta sobre la seguridad no puede responderse sin <a href=\"https:\/\/www.seafoodsource.com\/news\/supply-trade\/global-aquaculture-surging-with-production-surpassing-wild-catch-fisheries-2024-un-fao-sofia-report-finds\" target=\"_blank\" rel=\"noopener\">distinguir entre la especie, el origen y el m\u00e9todo de producci\u00f3n<\/a>.<\/p>\n<h2>El problema de la bioacumulaci\u00f3n: no todos los peces son iguales<\/h2>\n<p>El principal contaminante de inter\u00e9s sanitario en el pescado es el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Metilmercurio\" target=\"_blank\" rel=\"noopener\">metilmercurio<\/a>. No porque sea el \u00fanico \u2013los <a href=\"https:\/\/es.wikipedia.org\/wiki\/Bifenilos_policlorados\" target=\"_blank\" rel=\"noopener\">PCBs<\/a>, las <a href=\"https:\/\/www.who.int\/es\/news-room\/fact-sheets\/detail\/dioxins-and-their-effects-on-human-health\" target=\"_blank\" rel=\"noopener\">dioxinas<\/a> y los <a href=\"https:\/\/acsa.gencat.cat\/es\/detall\/article\/Organoclorados-00001\" target=\"_blank\" rel=\"noopener\">plaguicidas organoclorados<\/a> tambi\u00e9n cuentan\u2013, sino porque <a href=\"https:\/\/efsa.onlinelibrary.wiley.com\/doi\/10.2903\/j.efsa.2012.2985\" target=\"_blank\" rel=\"noopener\">su comportamiento en la cadena tr\u00f3fica es sistem\u00e1tico y bien documentado<\/a>. El metilmercurio se acumula en los tejidos grasos y se biomagnifica a medida que se asciende en la red alimentaria.<\/p>\n<p>As\u00ed, <a href=\"https:\/\/www.sabormediterraneo.com\/salud\/pescado_mercurio.htm\" target=\"_blank\" rel=\"noopener\">un at\u00fan o un pez espada puede acumular concentraciones de mercurio cien veces superiores a las del agua que habita<\/a>. La f\u00edsica del problema es implacable: cuanto m\u00e1s larga sea la vida del animal y m\u00e1s alto sea su puesto en la cadena, mayor ser\u00e1 la carga.<\/p>\n<p><a href=\"https:\/\/efsa.onlinelibrary.wiley.com\/doi\/10.2903\/j.efsa.2026.9865\">La Autoridad Europea de Seguridad Alimentaria (EFSA) ha identificado<\/a> al at\u00fan, el pez espada, el bacalao, el abadejo y el lucio como los principales contribuyentes a la exposici\u00f3n al metilmercurio en Europa en todos los grupos de edad, y, en el caso de los ni\u00f1os, la merluza.<\/p>\n<p>La exposici\u00f3n media de la poblaci\u00f3n no suele superar la ingesta semanal tolerable, pero los consumidores habituales de grandes depredadores s\u00ed pueden rebasarla.<\/p>\n<h2>Peligros para la salud en ni\u00f1os y embarazadas<\/h2>\n<p>Aqu\u00ed viene el matiz que casi nunca se explica bien: el riesgo no es el mismo para un adulto sano que para una mujer embarazada o para un ni\u00f1o. En estos grupos, la <a href=\"https:\/\/www.efsa.europa.eu\/en\/press\/news\/121220\" target=\"_blank\" rel=\"noopener\">neurotoxicidad del metilmercurio tiene efectos documentados sobre el desarrollo del sistema nervioso<\/a>. Por eso, las restricciones de consumo no son prudencia burocr\u00e1tica, son medicina preventiva con base s\u00f3lida.<\/p>\n<p><a href=\"https:\/\/www.medscape.com\/viewarticle\/high-mercury-fish-consumption-rising-europe-efsa-reports-2026a100051v\" target=\"_blank\" rel=\"noopener\">Un informe reciente de la EFSA<\/a>, basado en encuestas de 2023 y 2024 en los 27 Estados miembros, revel\u00f3 que aproximadamente uno de cada tres europeos \u2013incluidas mujeres embarazadas\u2013 consume cantidades potencialmente inseguras de especies con alto contenido de mercurio. Hasta el 60&nbsp;% de los encuestados conoc\u00eda los beneficios del pescado, pero solo entre el 10 y el 14&nbsp;% era consciente de los riesgos asociados a los contaminantes.<\/p>\n<p>El desequilibrio informativo es evidente y no es inocente: los beneficios se han comunicado con entusiasmo; los matices, con desgana.<\/p>\n<h2>\u00bfEs seguro el salm\u00f3n de acuicultura?<\/h2>\n<p>Comer salm\u00f3n es seguro, con matices que no justifican el p\u00e1nico medi\u00e1tico. El salm\u00f3n de piscifactor\u00eda noruego \u2013que es el que encontramos en los supermercados espa\u00f1oles\u2013 tiene niveles de contaminantes org\u00e1nicos persistentes (dioxinas, PCBs) que los an\u00e1lisis sistem\u00e1ticos del Instituto de Investigaci\u00f3n Marina noruego <a href=\"https:\/\/www.hi.no\/hi\/nettrapporter\/rapport-fra-havforskningen-en-2025-49\" target=\"_blank\" rel=\"noopener\">sit\u00faan aproximadamente seis veces por debajo de los l\u00edmites m\u00e1ximos europeos<\/a>.<\/p>\n<p>Esos niveles han descendido de forma constante desde 2004 gracias al cambio en la composici\u00f3n de los piensos. Por otro lado, el mercurio no es el problema del salm\u00f3n: es un pez de posici\u00f3n tr\u00f3fica media y con un ciclo de vida relativamente corto en acuicultura.<\/p>\n<p>Eso s\u00ed, la <a href=\"https:\/\/www.aditivos-alimentarios.com\/2016\/01\/E324.html\" target=\"_blank\" rel=\"noopener\">etoxiquina<\/a> \u2013antioxidante a\u00f1adido a los piensos para evitar su oxidaci\u00f3n durante el transporte\u2013 gener\u00f3 alarma hace a\u00f1os porque no es un aditivo deseable. Pero tampoco es la bomba qu\u00edmica que ciertos documentales televisivos pretendieron hacer creer. <a href=\"https:\/\/www.efsa.europa.eu\/es\/news\/efsa-reassesses-safety-feed-additive-ethoxyquin\" target=\"_blank\" rel=\"noopener\">La EFSA la revis\u00f3 y no encontr\u00f3 riesgo para el consumidor a los niveles detectados<\/a> en m\u00fasculo de salm\u00f3n.<\/p>\n<p>Por otro lado, el salm\u00f3n de piscifactor\u00eda tiene una fracci\u00f3n grasa notablemente mayor que el salvaje, porque el pienso y la ausencia de depredadores as\u00ed lo permiten. Esa grasa extra es precisamente donde se acumulan los contaminantes <a href=\"https:\/\/es.wikipedia.org\/w\/index.php?title=Lip%C3%B3filo&amp;oldformat=true\">lip\u00f3filos<\/a>, pero tambi\u00e9n es la fuente de los <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/36103100\/\" target=\"_blank\" rel=\"noopener\">\u00e1cidos grasos omega-3 a los que se atribuyen beneficios cardiovasculares<\/a>.<\/p>\n<h2>La trazabilidad: el eslab\u00f3n m\u00e1s d\u00e9bil<\/h2>\n<p>Seg\u00fan la FAO, <a href=\"https:\/\/www.fao.org\/fishery\/publication\/332256\/en?status=published\" target=\"_blank\" rel=\"noopener\">uno de cada cinco productos pesqueros en el mundo est\u00e1 mal etiquetado<\/a>. El fraude abarca la sustituci\u00f3n de especies por otras m\u00e1s baratas, la falsificaci\u00f3n del m\u00e9todo de captura \u2013salvaje frente a acuicultura\u2013, el origen geogr\u00e1fico incorrecto y la adulteraci\u00f3n con colorantes para simular frescura. En Espa\u00f1a, el impacto econ\u00f3mico de este fraude <a href=\"https:\/\/www.pescafacil.com\/2024\/07\/16\/el-fraude-en-el-etiquetado-del-pescado-tiene-un-impacto-de-mas-de-600-millones-de-euros-al-ano-en-espana\/\" target=\"_blank\" rel=\"noopener\">se estima en m\u00e1s de 600 millones de euros al a\u00f1o<\/a>.<\/p>\n<p>En este contexto, <a href=\"https:\/\/www.uniovi.es\/en\/actualidad\/noticias\/-\/asset_publisher\/Ru0cAJNPrm1m\/content\/id\/1415958\" target=\"_blank\" rel=\"noopener\">un estudio de la Universidad de Oviedo<\/a> que analiz\u00f3 mediante secuenciaci\u00f3n de ADN 401 muestras de pescado congelado encontr\u00f3 que, en el 1,9&nbsp;% de los casos, la especie declarada en la etiqueta no correspond\u00eda al contenido real. Puede parecer un porcentaje peque\u00f1o, pero, aplicado al volumen total del mercado, es una cifra que no deber\u00eda ser tolerable en ning\u00fan sistema de control alimentario serio.<\/p>\n<p><a href=\"https:\/\/eur-lex.europa.eu\/ES\/legal-content\/summary\/common-organisation-of-the-market-in-fishery-products.html\" target=\"_blank\" rel=\"noopener\">La normativa de la UE exige<\/a>, desde finales de 2014, que el etiquetado de productos pesqueros indique la especie, la zona de captura o el pa\u00eds de producci\u00f3n acu\u00edcola, el m\u00e9todo de captura y si el producto ha sido descongelado. El problema es la brecha entre lo que establece el reglamento y lo que llega al consumidor, especialmente en la restauraci\u00f3n, <a href=\"https:\/\/www.fishforward.eu\/es\/project\/traceability\/\" target=\"_blank\" rel=\"noopener\">donde las exigencias son menores y la cadena de intermediaci\u00f3n es m\u00e1s opaca<\/a>.<\/p>\n<h2>Soluciones para frenar el fraude<\/h2>\n<p>Las soluciones t\u00e9cnicas existen, como demuestra <a href=\"https:\/\/www.seatraces.eu\/\">SEATRACES<\/a>, un proyecto liderado por el Instituto de Investigaciones Marinas-CSIC de Vigo, con 19 socios europeos, cuyo objetivo es demostrar que el etiquetado y la trazabilidad son esenciales para proteger y revalorizar la producci\u00f3n pesquera y acu\u00edcola atl\u00e1ntica. Para ello, dise\u00f1an herramientas de autenticaci\u00f3n basadas en la secuenciaci\u00f3n gen\u00e9tica y aplicaciones para tel\u00e9fonos m\u00f3viles. Adem\u00e1s, se ha creado la plataforma europea <a href=\"https:\/\/www.fish-fit.org\/\" target=\"_blank\" rel=\"noopener\">FISH-FIT<\/a>, abierta a laboratorios de control oficial e institutos de investigaci\u00f3n.<\/p>\n<p>Entre sus desarrollos, figura un <a href=\"https:\/\/delegacion.galicia.csic.es\/desarrollan-un-innovador-chip-genetico-para-garantizar-autenticidad-del-mejillon-gallego\/\" target=\"_blank\" rel=\"noopener\">chip gen\u00e9tico para garantizar la autenticidad del mejill\u00f3n gallego<\/a>, dise\u00f1ado en colaboraci\u00f3n con la Universidad de Santiago de Compostela y el Centro de Investigaci\u00f3n Marina y Alimentaria AZTI.<\/p>\n<p>La t\u00e9cnica gen\u00e9tica de <a href=\"https:\/\/www.genome.gov\/es\/genetics-glossary\/Nanopore-DNA-Sequencing\" target=\"_blank\" rel=\"noopener\">secuenciaci\u00f3n de nanoporos<\/a> permite hoy identificar la especie y la procedencia geogr\u00e1fica de cualquier producto marino en cuesti\u00f3n de horas, sin necesidad de un laboratorio especializado. En este sentido, el salto al control rutinario del mercado depende de la voluntad regulatoria, no de limitaciones t\u00e9cnicas.<\/p>\n<h2>Los beneficios reales del consumo de pescado<\/h2>\n<p>Conviene no perder de vista que la evidencia sobre los beneficios del consumo de pescado es s\u00f3lida. <a href=\"https:\/\/www.mayoclinic.org\/es\/diseases-conditions\/heart-disease\/in-depth\/omega-3\/art-20045614\" target=\"_blank\" rel=\"noopener\">La Asociaci\u00f3n Americana del Coraz\u00f3n recomienda al menos una o dos raciones semanales de pescado graso<\/a> \u2013como salm\u00f3n, caballa, sardinas o trucha\u2013 para reducir el riesgo cardiovascular.<\/p>\n<p>Los <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5067287\/\" target=\"_blank\" rel=\"noopener\">\u00e1cidos grasos omega-3 de cadena larga<\/a> (EPA y DHA) tienen efectos bien documentados en la reducci\u00f3n de los <a href=\"https:\/\/fundaciondelcorazon.com\/nutricion\/dieta\/717-dieta-trigliceridos-altos-debo-comer.html\" target=\"_blank\" rel=\"noopener\">triglic\u00e9ridos<\/a>\u2013grasa que aumenta el riesgo cardiovascular\u2013, la presi\u00f3n arterial y la inflamaci\u00f3n sist\u00e9mica. Para quienes no consumen pescado, los suplementos de omega-3 son una alternativa razonable, aunque el pescado sigue siendo la <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S003306202400054\" target=\"_blank\" rel=\"noopener\">fuente preferida porque aporta, adem\u00e1s, otros nutrientes esenciales<\/a>, frecuentemente deficitarios en la dieta occidental.<\/p>\n<p>Lo recomendable es comer con frecuencia especies peque\u00f1as y de ciclo corto \u2013sardinas, anchoas, jurel, caballa, mejill\u00f3n\u2013, que aseguran menor bioacumulaci\u00f3n de mercurio, mayor sostenibilidad, omega-3 y, en general, son m\u00e1s baratas.<\/p>\n<p>Asimismo, <a href=\"https:\/\/www.dsca.gob.es\/es\/node\/361\" target=\"_blank\" rel=\"noopener\">es aconsejable limitar el consumo de pez espada, tibur\u00f3n y at\u00fan rojo<\/a>, especialmente en mujeres embarazadas y ni\u00f1os. Y exigir trazabilidad: preguntar de d\u00f3nde viene el pescado no es excentricidad, sino un derecho reconocido por la normativa europea. Si la etiqueta no indica la especie, la zona de captura y el m\u00e9todo de producci\u00f3n, no cumple con la ley.<\/p>\n<p>El pescado es un alimento excepcional. Aprovecharlo bien requiere un poco m\u00e1s de informaci\u00f3n de la que suele estar disponible en los expositores del supermercado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unos a\u00f1os escrib\u00ed sobre el salm\u00f3n y sus problemas y la respuesta de la Embajada de Noruega fue tan expedita que mereci\u00f3 un segundo post. No estoy acostumbrado a tanto inter\u00e9s diplom\u00e1tico. Aun as\u00ed, el tema del pescado \u2013qu\u00e9 comer, cu\u00e1nto, de d\u00f3nde viene y si es seguro\u2013 sigue siendo uno de los m\u00e1s confusos para el consumidor medio. Y la confusi\u00f3n no es accidental: conviven intereses industriales, alarmas medi\u00e1ticas mal calibradas y mensajes de salud p\u00fablica que se quedan en el titular sin matizar lo que realmente dice la ciencia. La mayor transformaci\u00f3n en la historia de la\u2026<\/p>\n","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"categories":[359,357,1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hace unos a\u00f1os escrib\u00ed sobre el salm\u00f3n y sus problemas y la respuesta de la Embajada de Noruega fue tan expedita que mereci\u00f3 un segundo post. No estoy acostumbrado a tanto inter\u00e9s diplom\u00e1tico. Aun as\u00ed, el tema del pescado \u2013qu\u00e9 comer, cu\u00e1nto, de d\u00f3nde viene y si es seguro\u2013 sigue siendo uno de los m\u00e1s\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Figueras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ciencia Marina y otros asuntos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta property=\"og:description\" content=\"Hace unos a\u00f1os escrib\u00ed sobre el salm\u00f3n y sus problemas y la respuesta de la Embajada de Noruega fue tan expedita que mereci\u00f3 un segundo post. No estoy acostumbrado a tanto inter\u00e9s diplom\u00e1tico. Aun as\u00ed, el tema del pescado \u2013qu\u00e9 comer, cu\u00e1nto, de d\u00f3nde viene y si es seguro\u2013 sigue siendo uno de los m\u00e1s\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-03T10:44:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-03T10:44:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer? - Ciencia Marina y otros asuntos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hace unos a\u00f1os escrib\u00ed sobre el salm\u00f3n y sus problemas y la respuesta de la Embajada de Noruega fue tan expedita que mereci\u00f3 un segundo post. No estoy acostumbrado a tanto inter\u00e9s diplom\u00e1tico. Aun as\u00ed, el tema del pescado \u2013qu\u00e9 comer, cu\u00e1nto, de d\u00f3nde viene y si es seguro\u2013 sigue siendo uno de los m\u00e1s\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2026\\\/07\\\/03\\\/139476#blogposting\",\"name\":\"\\u00bfQu\\u00e9 pescados son m\\u00e1s sanos para comer? - Ciencia Marina y otros asuntos\",\"headline\":\"\\u00bfQu\\u00e9 pescados son m\\u00e1s sanos para comer?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2026\\\/07\\\/03\\\/139476\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2026-07-03T11:44:41+01:00\",\"dateModified\":\"2026-07-03T11:44:41+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2026\\\/07\\\/03\\\/139476#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2026\\\/07\\\/03\\\/139476#webpage\"},\"articleSection\":\"Acuicultura. Cultivos Marinos., Biolog\\u00eda Marina, General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2026\\\/07\\\/03\\\/139476#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2026\\\/07\\\/03\\\/139476#listItem\",\"name\":\"\\u00bfQu\\u00e9 pescados son m\\u00e1s sanos para comer?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2026\\\/07\\\/03\\\/139476#listItem\",\"position\":3,\"name\":\"\\u00bfQu\\u00e9 pescados son m\\u00e1s sanos para comer?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina\",\"name\":\"Antonio Figueras\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2026\\\/07\\\/03\\\/139476#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2026\\\/07\\\/03\\\/139476\",\"name\":\"\\u00bfQu\\u00e9 pescados son m\\u00e1s sanos para comer? - Ciencia Marina y otros asuntos\",\"description\":\"Hace unos a\\u00f1os escrib\\u00ed sobre el salm\\u00f3n y sus problemas y la respuesta de la Embajada de Noruega fue tan expedita que mereci\\u00f3 un segundo post. No estoy acostumbrado a tanto inter\\u00e9s diplom\\u00e1tico. Aun as\\u00ed, el tema del pescado \\u2013qu\\u00e9 comer, cu\\u00e1nto, de d\\u00f3nde viene y si es seguro\\u2013 sigue siendo uno de los m\\u00e1s\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/2026\\\/07\\\/03\\\/139476#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/author\\\/cienciamarina#author\"},\"datePublished\":\"2026-07-03T11:44:41+01:00\",\"dateModified\":\"2026-07-03T11:44:41+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/\",\"name\":\"Ciencia Marina y otros asuntos\",\"alternateName\":\"Ciencia Marina y otros asuntos: divulgaci\\u00f3n sobre biolog\\u00eda marina, cambio global, oceans y energ\\u00edas marinas, investigaciones actuales y la relaci\\u00f3n entre ciencia y sociedad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/ciencia_marina\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer? - Ciencia Marina y otros asuntos","description":"Hace unos a\u00f1os escrib\u00ed sobre el salm\u00f3n y sus problemas y la respuesta de la Embajada de Noruega fue tan expedita que mereci\u00f3 un segundo post. No estoy acostumbrado a tanto inter\u00e9s diplom\u00e1tico. Aun as\u00ed, el tema del pescado \u2013qu\u00e9 comer, cu\u00e1nto, de d\u00f3nde viene y si es seguro\u2013 sigue siendo uno de los m\u00e1s","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476#blogposting","name":"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer? - Ciencia Marina y otros asuntos","headline":"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476\/#articleImage","width":217,"height":72},"datePublished":"2026-07-03T11:44:41+01:00","dateModified":"2026-07-03T11:44:41+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476#webpage"},"articleSection":"Acuicultura. Cultivos Marinos., Biolog\u00eda Marina, General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476#listItem","name":"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476#listItem","position":3,"name":"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general#listItem","name":"General"}}]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina","name":"Antonio Figueras"},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476","name":"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer? - Ciencia Marina y otros asuntos","description":"Hace unos a\u00f1os escrib\u00ed sobre el salm\u00f3n y sus problemas y la respuesta de la Embajada de Noruega fue tan expedita que mereci\u00f3 un segundo post. No estoy acostumbrado a tanto inter\u00e9s diplom\u00e1tico. Aun as\u00ed, el tema del pescado \u2013qu\u00e9 comer, cu\u00e1nto, de d\u00f3nde viene y si es seguro\u2013 sigue siendo uno de los m\u00e1s","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/author\/cienciamarina#author"},"datePublished":"2026-07-03T11:44:41+01:00","dateModified":"2026-07-03T11:44:41+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/","name":"Ciencia Marina y otros asuntos","alternateName":"Ciencia Marina y otros asuntos: divulgaci\u00f3n sobre biolog\u00eda marina, cambio global, oceans y energ\u00edas marinas, investigaciones actuales y la relaci\u00f3n entre ciencia y sociedad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/#person"}}]},"og:locale":"es_ES","og:site_name":"Ciencia Marina y otros asuntos -","og:type":"article","og:title":"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer? - Ciencia Marina y otros asuntos","og:description":"Hace unos a\u00f1os escrib\u00ed sobre el salm\u00f3n y sus problemas y la respuesta de la Embajada de Noruega fue tan expedita que mereci\u00f3 un segundo post. No estoy acostumbrado a tanto inter\u00e9s diplom\u00e1tico. Aun as\u00ed, el tema del pescado \u2013qu\u00e9 comer, cu\u00e1nto, de d\u00f3nde viene y si es seguro\u2013 sigue siendo uno de los m\u00e1s","og:url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476","og:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png","article:published_time":"2026-07-03T10:44:41+00:00","article:modified_time":"2026-07-03T10:44:41+00:00","twitter:card":"summary","twitter:title":"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer? - Ciencia Marina y otros asuntos","twitter:description":"Hace unos a\u00f1os escrib\u00ed sobre el salm\u00f3n y sus problemas y la respuesta de la Embajada de Noruega fue tan expedita que mereci\u00f3 un segundo post. No estoy acostumbrado a tanto inter\u00e9s diplom\u00e1tico. Aun as\u00ed, el tema del pescado \u2013qu\u00e9 comer, cu\u00e1nto, de d\u00f3nde viene y si es seguro\u2013 sigue siendo uno de los m\u00e1s","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"139476","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2026-07-03 10:36:05","updated":"2026-07-03 14:26:41","ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/category\/general"},{"label":"\u00bfQu\u00e9 pescados son m\u00e1s sanos para comer?","link":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/2026\/07\/03\/139476"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/139476"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/comments?post=139476"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/139476\/revisions"}],"predecessor-version":[{"id":139481,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/posts\/139476\/revisions\/139481"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/media?parent=139476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/categories?post=139476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/ciencia_marina\/wp-json\/wp\/v2\/tags?post=139476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}