{"id":108924,"date":"2008-12-08T18:08:00","date_gmt":"2008-12-08T18:08:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/complejidad\/archive\/2008\/12\/08\/108924.aspx"},"modified":"2008-12-08T18:08:00","modified_gmt":"2008-12-08T18:08:00","slug":"mas-sobre-el-memristor","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924","title":{"rendered":"M\u00e1s sobre el memristor"},"content":{"rendered":"<div align=\"justify\">Recientemente, el 21 de noviembre de 2008, ha tenido lugar un simposium en la Universidad de California en Berkeley sobre el <A href=\"http:\/\/weblogs.madrimasd.org\/complejidad\/archive\/2008\/05\/03\/90746.aspx\">memristor<\/a> y otros dispositivos memristivos en el que han participado<span> los verdaderos protagonistas de esta <A href=\"http:\/\/weblogs.madrimasd.org\/complejidad\/archive\/2008\/12\/06\/108807.aspx\">historia<\/a>. Por un lado el Prof. Leon Chua, del Electrical Engineering and Computer Sciences Department, College of Engineering, UC Berkeley que habl\u00f3 sobre el&nbsp; Memristor. Posteriormente<\/span> <span>Stan Williams, HP Senior Fellow y Director of Information &amp; Quantum Systems Lab, Hewlett-Packard, quien encontr\u00f3 el memristor en el laboratorio, habl\u00f3 sobre c\u00f3mo encontr\u00f3 el elemento que faltaba, el memristor.<\/span><span> Ambas ponencias pueden escucharse en <a href=\"http:\/\/es.youtube.com\/watch?v=QFdDPzcZwbs&amp;feature=related\">Memristor and Memristive Systems Symposium<\/a>.<\/p>\n<p>Miguel A. F. Sanju\u00e1n<br \/><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Recientemente, el 21 de noviembre de 2008, ha tenido lugar un simposium en la Universidad de California en Berkeley sobre el memristor y otros dispositivos memristivos en el que han participado los verdaderos protagonistas de esta historia. Por un lado el Prof. Leon Chua, del Electrical Engineering and Computer Sciences Department, College of Engineering, UC Berkeley que habl\u00f3 sobre el&nbsp; Memristor. Posteriormente Stan Williams, HP Senior Fellow y Director of Information &amp; Quantum Systems Lab, Hewlett-Packard, quien encontr\u00f3 el memristor en el laboratorio, habl\u00f3 sobre c\u00f3mo encontr\u00f3 el elemento que faltaba, el memristor. Ambas ponencias pueden escucharse en Memristor and\u2026<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[199,206],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Recientemente, el 21 de noviembre de 2008, ha tenido lugar un simposium en la Universidad de California en Berkeley sobre el memristor y otros dispositivos memristivos en el que han participado los verdaderos protagonistas de esta historia. Por un lado el Prof. Leon Chua, del Electrical Engineering and Computer Sciences Department, College of Engineering, UC\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel A. F. Sanju\u00e1n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"M\u00e1s sobre el memristor - Complejidad\" \/>\n\t\t<meta property=\"og:description\" content=\"Recientemente, el 21 de noviembre de 2008, ha tenido lugar un simposium en la Universidad de California en Berkeley sobre el memristor y otros dispositivos memristivos en el que han participado los verdaderos protagonistas de esta historia. Por un lado el Prof. Leon Chua, del Electrical Engineering and Computer Sciences Department, College of Engineering, UC\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-12-08T18:08:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2008-12-08T18:08:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"M\u00e1s sobre el memristor - Complejidad\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Recientemente, el 21 de noviembre de 2008, ha tenido lugar un simposium en la Universidad de California en Berkeley sobre el memristor y otros dispositivos memristivos en el que han participado los verdaderos protagonistas de esta historia. Por un lado el Prof. Leon Chua, del Electrical Engineering and Computer Sciences Department, College of Engineering, UC\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924#blogposting\",\"name\":\"M\\u00e1s sobre el memristor - Complejidad\",\"headline\":\"M\\u00e1s sobre el memristor\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2008-12-08T18:08:00+01:00\",\"dateModified\":\"2008-12-08T18:08:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924#webpage\"},\"articleSection\":\"Complejidad: aspectos generales, Computaci\\u00f3n y futuro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-aspectos-generales#listItem\",\"name\":\"Complejidad: aspectos generales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-aspectos-generales#listItem\",\"position\":2,\"name\":\"Complejidad: aspectos generales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-aspectos-generales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924#listItem\",\"name\":\"M\\u00e1s sobre el memristor\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924#listItem\",\"position\":3,\"name\":\"M\\u00e1s sobre el memristor\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-aspectos-generales#listItem\",\"name\":\"Complejidad: aspectos generales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad\",\"name\":\"Miguel A. F. Sanju\\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel A. F. Sanju\\u00e1n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924\",\"name\":\"M\\u00e1s sobre el memristor - Complejidad\",\"description\":\"Recientemente, el 21 de noviembre de 2008, ha tenido lugar un simposium en la Universidad de California en Berkeley sobre el memristor y otros dispositivos memristivos en el que han participado los verdaderos protagonistas de esta historia. Por un lado el Prof. Leon Chua, del Electrical Engineering and Computer Sciences Department, College of Engineering, UC\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2008\\\/12\\\/08\\\/108924#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"datePublished\":\"2008-12-08T18:08:00+01:00\",\"dateModified\":\"2008-12-08T18:08:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"M\u00e1s sobre el memristor - Complejidad","description":"Recientemente, el 21 de noviembre de 2008, ha tenido lugar un simposium en la Universidad de California en Berkeley sobre el memristor y otros dispositivos memristivos en el que han participado los verdaderos protagonistas de esta historia. Por un lado el Prof. Leon Chua, del Electrical Engineering and Computer Sciences Department, College of Engineering, UC","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924#blogposting","name":"M\u00e1s sobre el memristor - Complejidad","headline":"M\u00e1s sobre el memristor","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#articleImage","width":217,"height":72},"datePublished":"2008-12-08T18:08:00+01:00","dateModified":"2008-12-08T18:08:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924#webpage"},"articleSection":"Complejidad: aspectos generales, Computaci\u00f3n y futuro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales#listItem","name":"Complejidad: aspectos generales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales#listItem","position":2,"name":"Complejidad: aspectos generales","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924#listItem","name":"M\u00e1s sobre el memristor"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924#listItem","position":3,"name":"M\u00e1s sobre el memristor","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales#listItem","name":"Complejidad: aspectos generales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad","name":"Miguel A. F. Sanju\u00e1n","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel A. F. Sanju\u00e1n"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924","name":"M\u00e1s sobre el memristor - Complejidad","description":"Recientemente, el 21 de noviembre de 2008, ha tenido lugar un simposium en la Universidad de California en Berkeley sobre el memristor y otros dispositivos memristivos en el que han participado los verdaderos protagonistas de esta historia. Por un lado el Prof. Leon Chua, del Electrical Engineering and Computer Sciences Department, College of Engineering, UC","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"datePublished":"2008-12-08T18:08:00+01:00","dateModified":"2008-12-08T18:08:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos","og:type":"article","og:title":"M\u00e1s sobre el memristor - Complejidad","og:description":"Recientemente, el 21 de noviembre de 2008, ha tenido lugar un simposium en la Universidad de California en Berkeley sobre el memristor y otros dispositivos memristivos en el que han participado los verdaderos protagonistas de esta historia. Por un lado el Prof. Leon Chua, del Electrical Engineering and Computer Sciences Department, College of Engineering, UC","og:url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924","og:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","article:published_time":"2008-12-08T18:08:00+00:00","article:modified_time":"2008-12-08T18:08:00+00:00","twitter:card":"summary","twitter:title":"M\u00e1s sobre el memristor - Complejidad","twitter:description":"Recientemente, el 21 de noviembre de 2008, ha tenido lugar un simposium en la Universidad de California en Berkeley sobre el memristor y otros dispositivos memristivos en el que han participado los verdaderos protagonistas de esta historia. Por un lado el Prof. Leon Chua, del Electrical Engineering and Computer Sciences Department, College of Engineering, UC","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"108924","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 20:56:17","updated":"2023-06-19 09:20:11","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales\" title=\"Complejidad: aspectos generales\">Complejidad: aspectos generales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tM\u00e1s sobre el memristor\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad"},{"label":"Complejidad: aspectos generales","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales"},{"label":"M\u00e1s sobre el memristor","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2008\/12\/08\/108924"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/108924"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/comments?post=108924"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/108924\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/media?parent=108924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/categories?post=108924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/tags?post=108924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}