{"id":110899,"date":"2009-01-09T13:52:00","date_gmt":"2009-01-09T13:52:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/complejidad\/archive\/2009\/01\/09\/110899.aspx"},"modified":"2009-01-09T13:52:00","modified_gmt":"2009-01-09T13:52:00","slug":"la-fisica-de-los-cristales-de-nieve","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899","title":{"rendered":"La f\u00edsica de los cristales de nieve"},"content":{"rendered":"<div align=\"justify\">Los cristales de nieve son cristales de hielo que crecen con el vapor de agua formando formas preciosas . Se forman de modo copioso en la atmosfera y forman unos patrones sim\u00e9tricos de una belleza impresionantes. La f\u00edsica de los cristales de nieve es un ejemplo de un problema m\u00e1s general de crecimiento y desarrollo de cristales creando estructuras complejas en muchas escalas de longitudes a lo largo del proceso.<\/div>\n<p><\/p>\n<div align=\"center\"><img decoding=\"async\" src=\"\/blogs\/complejidad\/wp-content\/blogs.dir\/52\/files\/184\/o_snow_crystal09.jpg\"><\/div>\n<p><!--more--><\/p>\n<div align=\"justify\">Posiblemente no haya otra fuente sobre estas bellas estructuras dendr\u00edticas como la que aparece en <a href=\"http:\/\/www.its.caltech.edu\/%7Eatomic\/snowcrystals\/\">Snowcrystals.com<\/a>, que coordina y dirige el <a href=\"http:\/\/www.its.caltech.edu\/%7Eatomic\/\">Prof. Kenneth Libbrecht,<\/a> Catedr\u00e1tico de F\u00edsica y Director del Departamento de F\u00edsica del California Institute of Technology. Para los que quieran saber m\u00e1s y tener conocimientos m\u00e1s profundos acerca de la f\u00edsica de los cristales de nieve pueden saciar su curiosidad en el art\u00edculo <a href=\"http:\/\/www.its.caltech.edu\/%7Eatomic\/publist\/rpp5_4_R03.pdf\">The physics of snow crystals<\/a> publicado por el mismo autor anteriormente citado en la revista Reports on Progress in Physics que edita el Institute of Physics del Reino Unido. Muchos son los fen\u00f3menos complejos de formaci\u00f3n de estructuras que se presentan en este campo de los cristales de nieve.<\/p>\n<p>Miguel AF Sanju\u00e1n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los cristales de nieve son cristales de hielo que crecen con el vapor de agua formando formas preciosas . Se forman de modo copioso en la atmosfera y forman unos patrones sim\u00e9tricos de una belleza impresionantes. La f\u00edsica de los cristales de nieve es un ejemplo de un problema m\u00e1s general de crecimiento y desarrollo de cristales creando estructuras complejas en muchas escalas de longitudes a lo largo del proceso.<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[193,207,199,210],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los cristales de nieve son cristales de hielo que crecen con el vapor de agua formando formas preciosas . Se forman de modo copioso en la atmosfera y forman unos patrones sim\u00e9tricos de una belleza impresionantes. La f\u00edsica de los cristales de nieve es un ejemplo de un problema m\u00e1s general de crecimiento y desarrollo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel A. F. Sanju\u00e1n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La f\u00edsica de los cristales de nieve - Complejidad\" \/>\n\t\t<meta property=\"og:description\" content=\"Los cristales de nieve son cristales de hielo que crecen con el vapor de agua formando formas preciosas . Se forman de modo copioso en la atmosfera y forman unos patrones sim\u00e9tricos de una belleza impresionantes. La f\u00edsica de los cristales de nieve es un ejemplo de un problema m\u00e1s general de crecimiento y desarrollo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2009-01-09T13:52:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2009-01-09T13:52:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La f\u00edsica de los cristales de nieve - Complejidad\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los cristales de nieve son cristales de hielo que crecen con el vapor de agua formando formas preciosas . Se forman de modo copioso en la atmosfera y forman unos patrones sim\u00e9tricos de una belleza impresionantes. La f\u00edsica de los cristales de nieve es un ejemplo de un problema m\u00e1s general de crecimiento y desarrollo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899#blogposting\",\"name\":\"La f\\u00edsica de los cristales de nieve - Complejidad\",\"headline\":\"La f\\u00edsica de los cristales de nieve\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/blogs\\\/complejidad\\\/wp-content\\\/blogs.dir\\\/52\\\/files\\\/184\\\/o_snow_crystal09.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899\\\/#articleImage\"},\"datePublished\":\"2009-01-09T13:52:00+01:00\",\"dateModified\":\"2009-01-09T13:52:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899#webpage\"},\"articleSection\":\"Complejidad e Interdisciplinariedad, Complejidad, Ciencias de la Tierra y Medio Ambiente, Complejidad: aspectos generales, Patrones y Estructuras Complejas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-e-interdisciplinariedad#listItem\",\"name\":\"Complejidad e Interdisciplinariedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-e-interdisciplinariedad#listItem\",\"position\":2,\"name\":\"Complejidad e Interdisciplinariedad\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-e-interdisciplinariedad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899#listItem\",\"name\":\"La f\\u00edsica de los cristales de nieve\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899#listItem\",\"position\":3,\"name\":\"La f\\u00edsica de los cristales de nieve\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-e-interdisciplinariedad#listItem\",\"name\":\"Complejidad e Interdisciplinariedad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad\",\"name\":\"Miguel A. F. Sanju\\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel A. F. Sanju\\u00e1n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899\",\"name\":\"La f\\u00edsica de los cristales de nieve - Complejidad\",\"description\":\"Los cristales de nieve son cristales de hielo que crecen con el vapor de agua formando formas preciosas . Se forman de modo copioso en la atmosfera y forman unos patrones sim\\u00e9tricos de una belleza impresionantes. La f\\u00edsica de los cristales de nieve es un ejemplo de un problema m\\u00e1s general de crecimiento y desarrollo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2009\\\/01\\\/09\\\/110899#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"datePublished\":\"2009-01-09T13:52:00+01:00\",\"dateModified\":\"2009-01-09T13:52:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La f\u00edsica de los cristales de nieve - Complejidad","description":"Los cristales de nieve son cristales de hielo que crecen con el vapor de agua formando formas preciosas . Se forman de modo copioso en la atmosfera y forman unos patrones sim\u00e9tricos de una belleza impresionantes. La f\u00edsica de los cristales de nieve es un ejemplo de un problema m\u00e1s general de crecimiento y desarrollo","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899#blogposting","name":"La f\u00edsica de los cristales de nieve - Complejidad","headline":"La f\u00edsica de los cristales de nieve","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"},"image":{"@type":"ImageObject","url":"\/blogs\/complejidad\/wp-content\/blogs.dir\/52\/files\/184\/o_snow_crystal09.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899\/#articleImage"},"datePublished":"2009-01-09T13:52:00+01:00","dateModified":"2009-01-09T13:52:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899#webpage"},"articleSection":"Complejidad e Interdisciplinariedad, Complejidad, Ciencias de la Tierra y Medio Ambiente, Complejidad: aspectos generales, Patrones y Estructuras Complejas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-e-interdisciplinariedad#listItem","name":"Complejidad e Interdisciplinariedad"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-e-interdisciplinariedad#listItem","position":2,"name":"Complejidad e Interdisciplinariedad","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-e-interdisciplinariedad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899#listItem","name":"La f\u00edsica de los cristales de nieve"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899#listItem","position":3,"name":"La f\u00edsica de los cristales de nieve","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-e-interdisciplinariedad#listItem","name":"Complejidad e Interdisciplinariedad"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad","name":"Miguel A. F. Sanju\u00e1n","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel A. F. Sanju\u00e1n"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899","name":"La f\u00edsica de los cristales de nieve - Complejidad","description":"Los cristales de nieve son cristales de hielo que crecen con el vapor de agua formando formas preciosas . Se forman de modo copioso en la atmosfera y forman unos patrones sim\u00e9tricos de una belleza impresionantes. La f\u00edsica de los cristales de nieve es un ejemplo de un problema m\u00e1s general de crecimiento y desarrollo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"datePublished":"2009-01-09T13:52:00+01:00","dateModified":"2009-01-09T13:52:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos","og:type":"article","og:title":"La f\u00edsica de los cristales de nieve - Complejidad","og:description":"Los cristales de nieve son cristales de hielo que crecen con el vapor de agua formando formas preciosas . Se forman de modo copioso en la atmosfera y forman unos patrones sim\u00e9tricos de una belleza impresionantes. La f\u00edsica de los cristales de nieve es un ejemplo de un problema m\u00e1s general de crecimiento y desarrollo","og:url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899","og:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","article:published_time":"2009-01-09T13:52:00+00:00","article:modified_time":"2009-01-09T13:52:00+00:00","twitter:card":"summary","twitter:title":"La f\u00edsica de los cristales de nieve - Complejidad","twitter:description":"Los cristales de nieve son cristales de hielo que crecen con el vapor de agua formando formas preciosas . Se forman de modo copioso en la atmosfera y forman unos patrones sim\u00e9tricos de una belleza impresionantes. La f\u00edsica de los cristales de nieve es un ejemplo de un problema m\u00e1s general de crecimiento y desarrollo","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"110899","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 20:56:17","updated":"2023-06-19 09:20:11","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-e-interdisciplinariedad\" title=\"Complejidad e Interdisciplinariedad\">Complejidad e Interdisciplinariedad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa f\u00edsica de los cristales de nieve\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad"},{"label":"Complejidad e Interdisciplinariedad","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-e-interdisciplinariedad"},{"label":"La f\u00edsica de los cristales de nieve","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2009\/01\/09\/110899"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/110899"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/comments?post=110899"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/110899\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/media?parent=110899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/categories?post=110899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/tags?post=110899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}