{"id":11465,"date":"2006-01-01T23:12:00","date_gmt":"2006-01-01T23:12:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/complejidad\/archive\/2006\/01\/02\/11465.aspx"},"modified":"2006-01-01T23:12:00","modified_gmt":"2006-01-01T23:12:00","slug":"ciencia-y-complejidad","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465","title":{"rendered":"Ciencia y Complejidad"},"content":{"rendered":"<div align=\"justify\">Para aquellos interesados en los or\u00edgenes de la <i>complejidad<\/i>, resulta de especial inter\u00e9s la figura del cient\u00edfico americano <a href=\"http:\/\/www-history.mcs.st-and.ac.uk\/%7Ehistory\/Mathematicians\/Weaver.html\">Warren Weaver<\/a> (1894-1978), que entre otras cosas fue coautor junto con Claude E. Shannon&nbsp; del libro <i>The Mathematical Theory of Communication<\/i> publicado por The University of Illinois Press en 1949.<\/p>\n<div align=\"center\"><img decoding=\"async\" src=\"\/blogs\/complejidad\/wp-content\/blogs.dir\/52\/files\/184\/o_weaver.jpg\" height=\"219\" width=\"177\" \/><\/p>\n<div align=\"justify\">Pues bien, en 1948 public\u00f3 un interesant\u00edsimo art\u00edculo, considerado fundacional, titulado <i>\u00ab<a href=\"http:\/\/www.ceptualinstitute.com\/genre\/weaver\/weaver-1947b.htm\">Science and Complexity<\/a>\u00bb <\/i>en American Scientist, 36: 536 (1948). De hecho utilizo material que hab\u00eda sido publicado en 1947 y lo m\u00e1s importante es que resulta premonitorio de muchos aspectos de la complejidad de los que se vienen hablando en los \u00faltimos a\u00f1os.&nbsp; <\/p>\n<\/div>\n<\/div>\n<p>Miguel A. F. Sanju\u00e1n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para aquellos interesados en los or\u00edgenes de la complejidad, resulta de especial inter\u00e9s la figura del cient\u00edfico americano Warren Weaver (1894-1978), que entre otras cosas fue coautor junto con Claude E. Shannon&nbsp; del libro The Mathematical Theory of Communication publicado por The University of Illinois Press en 1949. Pues bien, en 1948 public\u00f3 un interesant\u00edsimo art\u00edculo, considerado fundacional, titulado \u00abScience and Complexity\u00bb en American Scientist, 36: 536 (1948). De hecho utilizo material que hab\u00eda sido publicado en 1947 y lo m\u00e1s importante es que resulta premonitorio de muchos aspectos de la complejidad de los que se vienen hablando en los\u2026<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[199],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Para aquellos interesados en los or\u00edgenes de la complejidad, resulta de especial inter\u00e9s la figura del cient\u00edfico americano Warren Weaver (1894-1978), que entre otras cosas fue coautor junto con Claude E. Shannon del libro The Mathematical Theory of Communication publicado por The University of Illinois Press en 1949. Pues bien, en 1948 public\u00f3 un interesant\u00edsimo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel A. F. Sanju\u00e1n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ciencia y Complejidad - Complejidad\" \/>\n\t\t<meta property=\"og:description\" content=\"Para aquellos interesados en los or\u00edgenes de la complejidad, resulta de especial inter\u00e9s la figura del cient\u00edfico americano Warren Weaver (1894-1978), que entre otras cosas fue coautor junto con Claude E. Shannon del libro The Mathematical Theory of Communication publicado por The University of Illinois Press en 1949. Pues bien, en 1948 public\u00f3 un interesant\u00edsimo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-01-01T23:12:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2006-01-01T23:12:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ciencia y Complejidad - Complejidad\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Para aquellos interesados en los or\u00edgenes de la complejidad, resulta de especial inter\u00e9s la figura del cient\u00edfico americano Warren Weaver (1894-1978), que entre otras cosas fue coautor junto con Claude E. Shannon del libro The Mathematical Theory of Communication publicado por The University of Illinois Press en 1949. Pues bien, en 1948 public\u00f3 un interesant\u00edsimo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465#blogposting\",\"name\":\"Ciencia y Complejidad - Complejidad\",\"headline\":\"Ciencia y Complejidad\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/blogs\\\/complejidad\\\/wp-content\\\/blogs.dir\\\/52\\\/files\\\/184\\\/o_weaver.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465\\\/#articleImage\"},\"datePublished\":\"2006-01-01T23:12:00+01:00\",\"dateModified\":\"2006-01-01T23:12:00+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465#webpage\"},\"articleSection\":\"Complejidad: aspectos generales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-aspectos-generales#listItem\",\"name\":\"Complejidad: aspectos generales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-aspectos-generales#listItem\",\"position\":2,\"name\":\"Complejidad: aspectos generales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-aspectos-generales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465#listItem\",\"name\":\"Ciencia y Complejidad\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465#listItem\",\"position\":3,\"name\":\"Ciencia y Complejidad\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/complejidad-aspectos-generales#listItem\",\"name\":\"Complejidad: aspectos generales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad\",\"name\":\"Miguel A. F. Sanju\\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel A. F. Sanju\\u00e1n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465\",\"name\":\"Ciencia y Complejidad - Complejidad\",\"description\":\"Para aquellos interesados en los or\\u00edgenes de la complejidad, resulta de especial inter\\u00e9s la figura del cient\\u00edfico americano Warren Weaver (1894-1978), que entre otras cosas fue coautor junto con Claude E. Shannon del libro The Mathematical Theory of Communication publicado por The University of Illinois Press en 1949. Pues bien, en 1948 public\\u00f3 un interesant\\u00edsimo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/01\\\/01\\\/11465#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"datePublished\":\"2006-01-01T23:12:00+01:00\",\"dateModified\":\"2006-01-01T23:12:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ciencia y Complejidad - Complejidad","description":"Para aquellos interesados en los or\u00edgenes de la complejidad, resulta de especial inter\u00e9s la figura del cient\u00edfico americano Warren Weaver (1894-1978), que entre otras cosas fue coautor junto con Claude E. Shannon del libro The Mathematical Theory of Communication publicado por The University of Illinois Press en 1949. Pues bien, en 1948 public\u00f3 un interesant\u00edsimo","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465#blogposting","name":"Ciencia y Complejidad - Complejidad","headline":"Ciencia y Complejidad","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"},"image":{"@type":"ImageObject","url":"\/blogs\/complejidad\/wp-content\/blogs.dir\/52\/files\/184\/o_weaver.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465\/#articleImage"},"datePublished":"2006-01-01T23:12:00+01:00","dateModified":"2006-01-01T23:12:00+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465#webpage"},"articleSection":"Complejidad: aspectos generales"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales#listItem","name":"Complejidad: aspectos generales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales#listItem","position":2,"name":"Complejidad: aspectos generales","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465#listItem","name":"Ciencia y Complejidad"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465#listItem","position":3,"name":"Ciencia y Complejidad","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales#listItem","name":"Complejidad: aspectos generales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad","name":"Miguel A. F. Sanju\u00e1n","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel A. F. Sanju\u00e1n"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465","name":"Ciencia y Complejidad - Complejidad","description":"Para aquellos interesados en los or\u00edgenes de la complejidad, resulta de especial inter\u00e9s la figura del cient\u00edfico americano Warren Weaver (1894-1978), que entre otras cosas fue coautor junto con Claude E. Shannon del libro The Mathematical Theory of Communication publicado por The University of Illinois Press en 1949. Pues bien, en 1948 public\u00f3 un interesant\u00edsimo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"datePublished":"2006-01-01T23:12:00+01:00","dateModified":"2006-01-01T23:12:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos","og:type":"article","og:title":"Ciencia y Complejidad - Complejidad","og:description":"Para aquellos interesados en los or\u00edgenes de la complejidad, resulta de especial inter\u00e9s la figura del cient\u00edfico americano Warren Weaver (1894-1978), que entre otras cosas fue coautor junto con Claude E. Shannon del libro The Mathematical Theory of Communication publicado por The University of Illinois Press en 1949. Pues bien, en 1948 public\u00f3 un interesant\u00edsimo","og:url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465","og:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","article:published_time":"2006-01-01T23:12:00+00:00","article:modified_time":"2006-01-01T23:12:00+00:00","twitter:card":"summary","twitter:title":"Ciencia y Complejidad - Complejidad","twitter:description":"Para aquellos interesados en los or\u00edgenes de la complejidad, resulta de especial inter\u00e9s la figura del cient\u00edfico americano Warren Weaver (1894-1978), que entre otras cosas fue coautor junto con Claude E. Shannon del libro The Mathematical Theory of Communication publicado por The University of Illinois Press en 1949. Pues bien, en 1948 public\u00f3 un interesant\u00edsimo","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"11465","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 20:56:16","updated":"2023-06-19 08:58:30","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales\" title=\"Complejidad: aspectos generales\">Complejidad: aspectos generales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCiencia y Complejidad\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad"},{"label":"Complejidad: aspectos generales","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/complejidad-aspectos-generales"},{"label":"Ciencia y Complejidad","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/01\/01\/11465"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/11465"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/comments?post=11465"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/11465\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/media?parent=11465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/categories?post=11465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/tags?post=11465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}