{"id":12807,"date":"2006-02-01T01:32:00","date_gmt":"2006-02-01T01:32:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/complejidad\/archive\/2006\/02\/01\/12807.aspx"},"modified":"2006-02-01T01:32:00","modified_gmt":"2006-02-01T01:32:00","slug":"dinamica-no-lineal-y-biologia-de-sistemas","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807","title":{"rendered":"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas"},"content":{"rendered":"<div align=\"justify\">El Centre for Nonlinear Dynamics in Physiology and Medicine de la Universidad McGill de Montreal organiza una <img decoding=\"async\" src=\"\/blogs\/complejidad\/wp-content\/blogs.dir\/52\/files\/184\/o_sysbio.jpg\" align=\"right\" border=\"0\" height=\"133\" hspace=\"10\" vspace=\"5\" width=\"130\" \/> <a href=\"http:\/\/www.cnd.mcgill.ca\/summer\/\">Escuela de Verano sobre Systems Biology Dynamics: from genes to organisms<\/a> durante los dias 23 de Mayo y 2 de Junio de 2006. Entre <a href=\"http:\/\/www.cnd.mcgill.ca\/summer\/program.htm\">los temas que se tratar\u00e1n<\/a> se encuentran la din\u00e1mica no lineal y la teor\u00eda del caos, sistemas estoc\u00e1sticos, ecuaciones diferenciales con retardo, aut\u00f3matas celulares. Entre las aplicaciones: redes de expresi\u00f3n gen\u00e9ticas, propagaci\u00f3n de se\u00f1ales neurales, chips de DNA, din\u00e1mica cardiaca, control neuronal y hematolog\u00eda. <\/p>\n<p>Miguel A. F. Sanju\u00e1n<\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Centre for Nonlinear Dynamics in Physiology and Medicine de la Universidad McGill de Montreal organiza una Escuela de Verano sobre Systems Biology Dynamics: from genes to organisms durante los dias 23 de Mayo y 2 de Junio de 2006. Entre los temas que se tratar\u00e1n se encuentran la din\u00e1mica no lineal y la teor\u00eda del caos, sistemas estoc\u00e1sticos, ecuaciones diferenciales con retardo, aut\u00f3matas celulares. Entre las aplicaciones: redes de expresi\u00f3n gen\u00e9ticas, propagaci\u00f3n de se\u00f1ales neurales, chips de DNA, din\u00e1mica cardiaca, control neuronal y hematolog\u00eda. Miguel A. F. Sanju\u00e1n<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[192,203,197],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Centre for Nonlinear Dynamics in Physiology and Medicine de la Universidad McGill de Montreal organiza una Escuela de Verano sobre Systems Biology Dynamics: from genes to organisms durante los dias 23 de Mayo y 2 de Junio de 2006. Entre los temas que se tratar\u00e1n se encuentran la din\u00e1mica no lineal y la teor\u00eda\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel A. F. Sanju\u00e1n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas - Complejidad\" \/>\n\t\t<meta property=\"og:description\" content=\"El Centre for Nonlinear Dynamics in Physiology and Medicine de la Universidad McGill de Montreal organiza una Escuela de Verano sobre Systems Biology Dynamics: from genes to organisms durante los dias 23 de Mayo y 2 de Junio de 2006. Entre los temas que se tratar\u00e1n se encuentran la din\u00e1mica no lineal y la teor\u00eda\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-02-01T01:32:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2006-02-01T01:32:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas - Complejidad\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Centre for Nonlinear Dynamics in Physiology and Medicine de la Universidad McGill de Montreal organiza una Escuela de Verano sobre Systems Biology Dynamics: from genes to organisms durante los dias 23 de Mayo y 2 de Junio de 2006. Entre los temas que se tratar\u00e1n se encuentran la din\u00e1mica no lineal y la teor\u00eda\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807#blogposting\",\"name\":\"Din\\u00e1mica No Lineal y Biolog\\u00eda de Sistemas - Complejidad\",\"headline\":\"Din\\u00e1mica No Lineal y Biolog\\u00eda de Sistemas\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/blogs\\\/complejidad\\\/wp-content\\\/blogs.dir\\\/52\\\/files\\\/184\\\/o_sysbio.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807\\\/#articleImage\"},\"datePublished\":\"2006-02-01T01:32:00+01:00\",\"dateModified\":\"2006-02-01T01:32:00+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807#webpage\"},\"articleSection\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas, Complejidad y Conferencias, Din\\u00e1mica No Lineal y Caos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas#listItem\",\"name\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas#listItem\",\"position\":2,\"name\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807#listItem\",\"name\":\"Din\\u00e1mica No Lineal y Biolog\\u00eda de Sistemas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807#listItem\",\"position\":3,\"name\":\"Din\\u00e1mica No Lineal y Biolog\\u00eda de Sistemas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas#listItem\",\"name\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad\",\"name\":\"Miguel A. F. Sanju\\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel A. F. Sanju\\u00e1n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807\",\"name\":\"Din\\u00e1mica No Lineal y Biolog\\u00eda de Sistemas - Complejidad\",\"description\":\"El Centre for Nonlinear Dynamics in Physiology and Medicine de la Universidad McGill de Montreal organiza una Escuela de Verano sobre Systems Biology Dynamics: from genes to organisms durante los dias 23 de Mayo y 2 de Junio de 2006. Entre los temas que se tratar\\u00e1n se encuentran la din\\u00e1mica no lineal y la teor\\u00eda\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2006\\\/02\\\/01\\\/12807#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"datePublished\":\"2006-02-01T01:32:00+01:00\",\"dateModified\":\"2006-02-01T01:32:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas - Complejidad","description":"El Centre for Nonlinear Dynamics in Physiology and Medicine de la Universidad McGill de Montreal organiza una Escuela de Verano sobre Systems Biology Dynamics: from genes to organisms durante los dias 23 de Mayo y 2 de Junio de 2006. Entre los temas que se tratar\u00e1n se encuentran la din\u00e1mica no lineal y la teor\u00eda","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807#blogposting","name":"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas - Complejidad","headline":"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"},"image":{"@type":"ImageObject","url":"\/blogs\/complejidad\/wp-content\/blogs.dir\/52\/files\/184\/o_sysbio.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807\/#articleImage"},"datePublished":"2006-02-01T01:32:00+01:00","dateModified":"2006-02-01T01:32:00+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807#webpage"},"articleSection":"Biolog\u00eda Sint\u00e9tica y de Sistemas, Complejidad y Conferencias, Din\u00e1mica No Lineal y Caos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas#listItem","name":"Biolog\u00eda Sint\u00e9tica y de Sistemas"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas#listItem","position":2,"name":"Biolog\u00eda Sint\u00e9tica y de Sistemas","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807#listItem","name":"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807#listItem","position":3,"name":"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas#listItem","name":"Biolog\u00eda Sint\u00e9tica y de Sistemas"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad","name":"Miguel A. F. Sanju\u00e1n","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel A. F. Sanju\u00e1n"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807","name":"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas - Complejidad","description":"El Centre for Nonlinear Dynamics in Physiology and Medicine de la Universidad McGill de Montreal organiza una Escuela de Verano sobre Systems Biology Dynamics: from genes to organisms durante los dias 23 de Mayo y 2 de Junio de 2006. Entre los temas que se tratar\u00e1n se encuentran la din\u00e1mica no lineal y la teor\u00eda","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"datePublished":"2006-02-01T01:32:00+01:00","dateModified":"2006-02-01T01:32:00+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos","og:type":"article","og:title":"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas - Complejidad","og:description":"El Centre for Nonlinear Dynamics in Physiology and Medicine de la Universidad McGill de Montreal organiza una Escuela de Verano sobre Systems Biology Dynamics: from genes to organisms durante los dias 23 de Mayo y 2 de Junio de 2006. Entre los temas que se tratar\u00e1n se encuentran la din\u00e1mica no lineal y la teor\u00eda","og:url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807","og:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","article:published_time":"2006-02-01T01:32:00+00:00","article:modified_time":"2006-02-01T01:32:00+00:00","twitter:card":"summary","twitter:title":"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas - Complejidad","twitter:description":"El Centre for Nonlinear Dynamics in Physiology and Medicine de la Universidad McGill de Montreal organiza una Escuela de Verano sobre Systems Biology Dynamics: from genes to organisms durante los dias 23 de Mayo y 2 de Junio de 2006. Entre los temas que se tratar\u00e1n se encuentran la din\u00e1mica no lineal y la teor\u00eda","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"12807","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 20:56:17","updated":"2023-06-19 08:58:31","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas\" title=\"Biolog\u00eda Sint\u00e9tica y de Sistemas\">Biolog\u00eda Sint\u00e9tica y de Sistemas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDin\u00e1mica No Lineal y Biolog\u00eda de Sistemas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad"},{"label":"Biolog\u00eda Sint\u00e9tica y de Sistemas","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas"},{"label":"Din\u00e1mica No Lineal y Biolog\u00eda de Sistemas","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2006\/02\/01\/12807"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/12807"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/comments?post=12807"}],"version-history":[{"count":0,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/12807\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/media?parent=12807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/categories?post=12807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/tags?post=12807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}