{"id":131585,"date":"2015-06-20T09:14:15","date_gmt":"2015-06-20T08:14:15","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/complejidad\/?p=131585"},"modified":"2015-06-20T11:15:18","modified_gmt":"2015-06-20T10:15:18","slug":"simposio-sobre-fisica-del-cancer-en-valencia","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585","title":{"rendered":"Simposio sobre F\u00edsica del Cancer en Valencia"},"content":{"rendered":"<p>El pasado viernes 19 de junio ha tenido lugar en Valencia un Simposio sobre F\u00edsica del Cancer organizado por el Instituto Valenciano de Oncolog\u00eda. Las perspectivas de la f\u00edsica, matem\u00e1ticas e ingenier\u00eda pueden ayudar a describir la complejidad de la biolog\u00eda del c\u00e1ncer y abrir nuevas avenidas para una posible cura eficaz. El objetivo del simposio ha sido presentar y discutir algunas de las nuevas direcciones que se abren en la investigaci\u00f3n sobre c\u00e1ncer, contando con la presencia de algunos de los l\u00edderes en el campo. La alta participaci\u00f3n con 175 personas registradas y la alta calidad de las presentaciones y discusiones han supuesto un gran hito que es de suponer que fructifique en su momento. En el acto de presentaci\u00f3n participaron el presidente de la Fundaci\u00f3n del Instituto Valenciano de Oncolog\u00eda y actual presidente de la Academia de Medicina de la Comunidad Valenciana Prof. Antonio Llombart Bosch, as\u00ed como la Directora General de Ordenaci\u00f3n, Evaluaci\u00f3n, Investigaci\u00f3n, Calidad y Atenci\u00f3n al Paciente de la Comunidad Valenciana Do\u00f1a Teresa de Rojas Galiana y la Prof. Pilar Campins Falco, Vicerrectora de Investigaci\u00f3n y Pol\u00edtica Cient\u00edfica de la Universidad de Valencia. Asimismo cont\u00f3 con la presencia del presidente de la Real Sociedad Espa\u00f1ola de F\u00edsica.<\/p>\n<p>&nbsp;<\/p>\nngg_shortcode_0_placeholder\n<p>&nbsp;<\/p>\n<p>El programa (<a href=\"https:\/\/indico.cern.ch\/event\/382038\/picture\/20.pdf\">https:\/\/indico.cern.ch\/event\/382038\/picture\/20.pdf<\/a>) cont\u00f3 con especialistas de diversos campos, tanto de la radiof\u00edsica, las aplicaciones de las terapias de particulas a la medicina, la modelizaci\u00f3n matem\u00e1tica de los glioblastomas, las aplicaciones de la f\u00edsica de la complejidad a modelos de interaciones entre celulas tumorales y celulas inmunes, el uso de los aceleradores y la hadronterapia, as\u00ed como otros modelos de la f\u00edsica estad\u00edstica del no equilibrio aplicados a fenomenos biol\u00f3gicos relacionados con la fenomenolog\u00eda del cancer.<\/p>\n<p>En definitiva una estupenda iniciativa que ha llevado a cabo el Dr. Vicente Crisp\u00edn, Jefe de Servicio de Radiof\u00edsica del Instituto Valenciano de Oncolog\u00eda y que esperemos de sus frutos en la necesaria investigaci\u00f3n tanto b\u00e1sica como aplicada en la lucha contra el cancer.<\/p>\n<p>Miguel A. F. Sanju\u00e1n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado viernes 19 de junio ha tenido lugar en Valencia un Simposio sobre F\u00edsica del Cancer organizado por el Instituto Valenciano de Oncolog\u00eda. Las perspectivas de la f\u00edsica, matem\u00e1ticas e ingenier\u00eda pueden ayudar a describir la complejidad de la biolog\u00eda del c\u00e1ncer y abrir nuevas avenidas para una posible cura eficaz. El objetivo del simposio ha sido presentar y discutir algunas de las nuevas direcciones que se abren en la investigaci\u00f3n sobre c\u00e1ncer, contando con la presencia de algunos de los l\u00edderes en el campo. La alta participaci\u00f3n con 175 personas registradas y la alta calidad de las presentaciones\u2026<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[192,193,194,203,201,204,205,202],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El pasado viernes 19 de junio ha tenido lugar en Valencia un Simposio sobre F\u00edsica del Cancer organizado por el Instituto Valenciano de Oncolog\u00eda. Las perspectivas de la f\u00edsica, matem\u00e1ticas e ingenier\u00eda pueden ayudar a describir la complejidad de la biolog\u00eda del c\u00e1ncer y abrir nuevas avenidas para una posible cura eficaz. El objetivo del\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel A. F. Sanju\u00e1n\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Simposio sobre F\u00edsica del Cancer en Valencia - Complejidad\" \/>\n\t\t<meta property=\"og:description\" content=\"El pasado viernes 19 de junio ha tenido lugar en Valencia un Simposio sobre F\u00edsica del Cancer organizado por el Instituto Valenciano de Oncolog\u00eda. Las perspectivas de la f\u00edsica, matem\u00e1ticas e ingenier\u00eda pueden ayudar a describir la complejidad de la biolog\u00eda del c\u00e1ncer y abrir nuevas avenidas para una posible cura eficaz. El objetivo del\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-06-20T08:14:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-06-20T10:15:18+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Simposio sobre F\u00edsica del Cancer en Valencia - Complejidad\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El pasado viernes 19 de junio ha tenido lugar en Valencia un Simposio sobre F\u00edsica del Cancer organizado por el Instituto Valenciano de Oncolog\u00eda. Las perspectivas de la f\u00edsica, matem\u00e1ticas e ingenier\u00eda pueden ayudar a describir la complejidad de la biolog\u00eda del c\u00e1ncer y abrir nuevas avenidas para una posible cura eficaz. El objetivo del\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585#blogposting\",\"name\":\"Simposio sobre F\\u00edsica del Cancer en Valencia - Complejidad\",\"headline\":\"Simposio sobre F\\u00edsica del Cancer en Valencia\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2015-06-20T09:14:15+01:00\",\"dateModified\":\"2015-06-20T11:15:18+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585#webpage\"},\"articleSection\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas, Complejidad e Interdisciplinariedad, Complejidad y Biolog\\u00eda Molecular y Celular, Complejidad y Conferencias, Complejidad y Vida, F\\u00edsica Biol\\u00f3gica, F\\u00edsica, Emergencia y Complejidad, F\\u00edsica, Matem\\u00e1ticas y Biolog\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas#listItem\",\"name\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas#listItem\",\"position\":2,\"name\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585#listItem\",\"name\":\"Simposio sobre F\\u00edsica del Cancer en Valencia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585#listItem\",\"position\":3,\"name\":\"Simposio sobre F\\u00edsica del Cancer en Valencia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/category\\\/biologia-sintetica-y-de-sistemas#listItem\",\"name\":\"Biolog\\u00eda Sint\\u00e9tica y de Sistemas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad\",\"name\":\"Miguel A. F. Sanju\\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel A. F. Sanju\\u00e1n\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585\",\"name\":\"Simposio sobre F\\u00edsica del Cancer en Valencia - Complejidad\",\"description\":\"El pasado viernes 19 de junio ha tenido lugar en Valencia un Simposio sobre F\\u00edsica del Cancer organizado por el Instituto Valenciano de Oncolog\\u00eda. Las perspectivas de la f\\u00edsica, matem\\u00e1ticas e ingenier\\u00eda pueden ayudar a describir la complejidad de la biolog\\u00eda del c\\u00e1ncer y abrir nuevas avenidas para una posible cura eficaz. El objetivo del\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/2015\\\/06\\\/20\\\/131585#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/author\\\/complejidad#author\"},\"datePublished\":\"2015-06-20T09:14:15+01:00\",\"dateModified\":\"2015-06-20T11:15:18+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/\",\"name\":\"Complejidad\",\"description\":\"Exploraciones en la Ciencia de los Sistemas Complejos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/complejidad\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Simposio sobre F\u00edsica del Cancer en Valencia - Complejidad","description":"El pasado viernes 19 de junio ha tenido lugar en Valencia un Simposio sobre F\u00edsica del Cancer organizado por el Instituto Valenciano de Oncolog\u00eda. Las perspectivas de la f\u00edsica, matem\u00e1ticas e ingenier\u00eda pueden ayudar a describir la complejidad de la biolog\u00eda del c\u00e1ncer y abrir nuevas avenidas para una posible cura eficaz. El objetivo del","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585#blogposting","name":"Simposio sobre F\u00edsica del Cancer en Valencia - Complejidad","headline":"Simposio sobre F\u00edsica del Cancer en Valencia","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#articleImage","width":217,"height":72},"datePublished":"2015-06-20T09:14:15+01:00","dateModified":"2015-06-20T11:15:18+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585#webpage"},"articleSection":"Biolog\u00eda Sint\u00e9tica y de Sistemas, Complejidad e Interdisciplinariedad, Complejidad y Biolog\u00eda Molecular y Celular, Complejidad y Conferencias, Complejidad y Vida, F\u00edsica Biol\u00f3gica, F\u00edsica, Emergencia y Complejidad, F\u00edsica, Matem\u00e1ticas y Biolog\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas#listItem","name":"Biolog\u00eda Sint\u00e9tica y de Sistemas"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas#listItem","position":2,"name":"Biolog\u00eda Sint\u00e9tica y de Sistemas","item":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585#listItem","name":"Simposio sobre F\u00edsica del Cancer en Valencia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585#listItem","position":3,"name":"Simposio sobre F\u00edsica del Cancer en Valencia","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas#listItem","name":"Biolog\u00eda Sint\u00e9tica y de Sistemas"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad","name":"Miguel A. F. Sanju\u00e1n","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2d85bfb1b452ac0048171bd1b4698cde?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel A. F. Sanju\u00e1n"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585","name":"Simposio sobre F\u00edsica del Cancer en Valencia - Complejidad","description":"El pasado viernes 19 de junio ha tenido lugar en Valencia un Simposio sobre F\u00edsica del Cancer organizado por el Instituto Valenciano de Oncolog\u00eda. Las perspectivas de la f\u00edsica, matem\u00e1ticas e ingenier\u00eda pueden ayudar a describir la complejidad de la biolog\u00eda del c\u00e1ncer y abrir nuevas avenidas para una posible cura eficaz. El objetivo del","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/author\/complejidad#author"},"datePublished":"2015-06-20T09:14:15+01:00","dateModified":"2015-06-20T11:15:18+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/","name":"Complejidad","description":"Exploraciones en la Ciencia de los Sistemas Complejos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Complejidad - Exploraciones en la Ciencia de los Sistemas Complejos","og:type":"article","og:title":"Simposio sobre F\u00edsica del Cancer en Valencia - Complejidad","og:description":"El pasado viernes 19 de junio ha tenido lugar en Valencia un Simposio sobre F\u00edsica del Cancer organizado por el Instituto Valenciano de Oncolog\u00eda. Las perspectivas de la f\u00edsica, matem\u00e1ticas e ingenier\u00eda pueden ayudar a describir la complejidad de la biolog\u00eda del c\u00e1ncer y abrir nuevas avenidas para una posible cura eficaz. El objetivo del","og:url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585","og:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png","article:published_time":"2015-06-20T08:14:15+00:00","article:modified_time":"2015-06-20T10:15:18+00:00","twitter:card":"summary","twitter:title":"Simposio sobre F\u00edsica del Cancer en Valencia - Complejidad","twitter:description":"El pasado viernes 19 de junio ha tenido lugar en Valencia un Simposio sobre F\u00edsica del Cancer organizado por el Instituto Valenciano de Oncolog\u00eda. Las perspectivas de la f\u00edsica, matem\u00e1ticas e ingenier\u00eda pueden ayudar a describir la complejidad de la biolog\u00eda del c\u00e1ncer y abrir nuevas avenidas para una posible cura eficaz. El objetivo del","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"131585","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-06-03 20:56:18","updated":"2023-06-19 09:30:50","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas\" title=\"Biolog\u00eda Sint\u00e9tica y de Sistemas\">Biolog\u00eda Sint\u00e9tica y de Sistemas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSimposio sobre F\u00edsica del Cancer en Valencia\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad"},{"label":"Biolog\u00eda Sint\u00e9tica y de Sistemas","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/category\/biologia-sintetica-y-de-sistemas"},{"label":"Simposio sobre F\u00edsica del Cancer en Valencia","link":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/2015\/06\/20\/131585"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/131585"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/comments?post=131585"}],"version-history":[{"count":15,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/131585\/revisions"}],"predecessor-version":[{"id":131603,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/posts\/131585\/revisions\/131603"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/media?parent=131585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/categories?post=131585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/complejidad\/wp-json\/wp\/v2\/tags?post=131585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}